{"id":3202,"date":"2009-04-29T09:31:03","date_gmt":"2009-04-29T07:31:03","guid":{"rendered":""},"modified":"2016-02-09T12:38:23","modified_gmt":"2016-02-09T11:38:23","slug":"limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\/","title":{"rendered":"L\u2019improbabile dialogo di Benedetto XVI con i 138 saggi musulmani"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/BenedettoXVI_islam.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-30613 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/BenedettoXVI_islam.jpg\" alt=\"BenedettoXVI_islam\" width=\"215\" height=\"149\" \/><\/a>Asianews,<\/strong> 9 gennaio 2008<\/div>\n<p style=\"text-align: justify;\"><em>Rappresentanti vaticani e dotti musulmani si incontreranno a Roma in marzo prossimo per mettere a punto alcune piste per il dialogo fra cristiani e musulmani. Si rischia il vuoto o la falsit\u00e0 se il dialogo non affronta non solo la teologia, ma i problemi concreti delle due comunit\u00e0.<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Samir Khalil Samir, sj<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Beirut (AsiaNews) &#8211; La lezione magistrale del papa a Regensburg, tanto criticata da molto mondo musulmano (e anche occidentale), sta portando frutti positivi proprio nel dialogo con il mondo islamico. Proprio in seguito al discorso di Regensburg (12 settembre 2006), 38 saggi islamici hanno mandato una prima lettera a commento (13 ottobre 2006) e un anno dopo una seconda lettera (sottoscritta da 138 saggi, diventati intanto 216) per cercare un terreno comune di collaborazione fra cristiani e musulmani.<\/div>\n<p style=\"text-align: justify;\">A sua volta, il 19 novembre scorso, Benedetto XVI\u00a0 ha risposto alla Lettera dei 138 aprendo a una possibile collaborazione su diversi campi. Alcune settimane fa (il 12 dicembre 2007), una lettera al card. Bertone del principe giordano Ghazi bin Muhammad bin Talal, accetta di aprire il campo alla collaborazione: fra febbraio e marzo, personalit\u00e0 della Curia vaticana e del mondo islamico si incontreranno a Roma per stabilire le procedure e i contenuti di tale dialogo.<\/p>\n<p style=\"text-align: justify;\">Ma \u00e8 possibile che il tutto si concluda con un buco nell\u2019acqua. Mi sembra infatti che le personalit\u00e0 musulmane in contatto con il papa, vogliano sfuggire questioni fondamentali e concrete, come i diritti dell\u2019uomo, la reciprocit\u00e0, la violenza ecc. per arroccarsi su un improbabile dialogo teologico \u201csull\u2019anima e Dio\u201d.<\/p>\n<p style=\"text-align: justify;\">Vediamo pi\u00f9 da vicino i problemi emersi.<\/p>\n<p style=\"text-align: justify;\"><strong>I. La Lettera dei 138: \u201cUna parola comune tra noi e voi\u201d<\/strong><\/p>\n<p style=\"text-align: justify;\">Nella Lettera dei 138 \u00e8 piena di buona volont\u00e0: i dottori islamici dicono di voler guardare \u201ca ci\u00f2 che unisce\u201d islam, cristianesimo e altre religioni. Essi hanno perfino fatto lo sforzo di esprimersi in modi \u201ccristiani\u201d, dicendo che il cuore della religione \u00e8 \u201camare Dio e il prossimo\u201d.<\/p>\n<p style=\"text-align: justify;\">L\u2019Islam non si esprime cos\u00ec. Questa \u00e8 un\u2019espressione dell\u2019AT, ripresa da Ges\u00f9 in un senso pi\u00f9 realistico, concreto e universale nella parabola del buon samaritano (Luca 10, 23-37). Ges\u00f9 dice due cose importanti: anzitutto, egli mette il primo comandamento come \u201cuguale\u201d al secondo (e questo non era cos\u00ec chiaro nemmeno nell\u2019AT); in secondo luogo egli precisa chi \u00e8 il prossimo, non il \u201cpi\u00f9 vicino a me\u201d (come espresso dai dotti islamici nella loro lettera in arabo, con la parola j\u00e2r, vicino), ma quello al quale io mi faccio \u201cprossimo\u201d.<\/p>\n<p style=\"text-align: justify;\">Il Vangelo rovescia infatti la domanda dello scriba (\u201cchi \u00e8 il mio prossimo?\u201d) e si chiede chi si \u00e8 comportato come \u201cprossimo\u201d del moribondo. Il prossimo \u00e8 dunque ogni persona umana, anche il nemico, come era il caso del samaritano per gli ebrei.<\/p>\n<p style=\"text-align: justify;\">Nel Vangelo si trovano spesso parabole in cui Ges\u00f9 rovescia i valori comuni: il fariseo e il pubblicano; i pagani rispetto ai giudei; il bambino rispetto all\u2019adulto.<\/p>\n<p style=\"text-align: justify;\">Il pericolo pi\u00f9 grosso della lettera dei 138 \u00e8 nei suoi silenzi, su ci\u00f2 che essa non tratta: non si accenna, ad esempio, ai problemi della comunit\u00e0 internazionale verso la comunit\u00e0 musulmana e ai problemi reali interni alla comunit\u00e0 musulmana.<\/p>\n<p style=\"text-align: justify;\">La Umma si trova in un momento molto delicato, in una fase di estremismo e di radicalismo diffusi in una parte significativa dei musulmani, che \u00e8 una forma di esclusivismo: chi non la pensa come noi \u00e8 nostro nemico. Questo \u00e8 evidente ogni giorno sulla stampa musulmana, e vediamo violenze e attacchi in Iraq, Iran, Pakistan, Afghanistan, fra i musulmani sunniti e sciiti, o contro cristiani o ebrei, o semplicemente contro il musulmano che \u00e8 tollerante &#8230; e ci sono!<\/p>\n<p style=\"text-align: justify;\">Il pericolo per l\u2019Islam non \u00e8 la violenza: questa \u00e8 presente in tutto il mondo e in tutte le religioni e le ideologie. Il pericolo \u00e8 di giustificare tutto questo attraverso la religione. Anche certe violenze contro le donne e i loro diritti sono giustificati con il Corano. Ad esempio, un donna musulmana non pu\u00f2 divorziare, perch\u00e9 il divorzio \u00e8 un diritto del marito, lei pu\u00f2 solo chiedere il favore d\u2019essere ripudiata da lui.<\/p>\n<p style=\"text-align: justify;\">Lui, in base al Corano si pu\u00f2 anche risposare (fino a 4 mogli) e rifarsi una vita, ma la donna, che vive separata, non ha questo diritto. Lei, una giovane sposa, si lamentava con me perch\u00e9 \u201cnon c\u2019\u00e8 giustizia\u201d. Queste situazioni in cui uno si appoggia al Corano o alla sharia per escludere l\u2019altro, sono frequenti.<\/p>\n<p style=\"text-align: justify;\"><strong>II. La risposta del papa: 4 campi di collaborazione<\/strong><\/p>\n<p style=\"text-align: justify;\">Nella risposta del pontefice &#8211; inviata attraverso il card. Tarcisio Bertone, segretario di stato vaticano \u2013 Benedetto XVI esprime \u201cprofondo apprezzamento\u201d per lo spirito positivo che ha ispirato la Lettera dei 138\u00a0 e per l\u2019appello a un impegno comune al fine di promuovere la pace nel mondo.<\/p>\n<p style=\"text-align: justify;\">Detto questo il papa suggerisce di cercare quanto \u00e8 comune. Ma gli elementi non sono identici.<\/p>\n<p style=\"text-align: justify;\">Anzitutto egli fa una annotazione: cerchiamo quanto \u00e8 comune \u201csenza dimenticare le nostre differenze\u201d. Ci\u00f2 significa che per il papa vi sono differenze fra le due comunit\u00e0 che vanno tenute presenti, non nascoste: possiamo essere fratelli e differenti, fratelli e opposti. Questa \u00e8 una regola d\u2019oro, trattandosi di religioni e di dogmi.<\/p>\n<p style=\"text-align: justify;\">Nella Lettera dei 138 si suggerisce che le cose \u201cin comune\u201d sono la fede in un unico Dio. I dotti islamici citano proprio il Corano quando dice \u201cVeniamo a una cosa comune fra noi\u201d, che richiede di non mettere nulla vicino a Dio. Ma questo \u00e8 proprio detto ai cristiani, che vicino a Dio, mettono Ges\u00f9 Cristo.<\/p>\n<p style=\"text-align: justify;\">Per il papa \u201cle cose comuni\u201d esistono, ma esistono anche le differenze e bisogna tenerle presenti.<\/p>\n<p style=\"text-align: justify;\">Le \u201ccose comuni\u201d che il papa elenca sono 3:<\/p>\n<p style=\"text-align: justify;\">&#8211;\u00a0la fede nell&#8217;unico Dio, creatore provvidente;<\/p>\n<p style=\"text-align: justify;\">&#8211;\u00a0Dio, giudice universale, \u201cche alla fine dei tempi considerer\u00e0 ogni persona secondo le sue azioni\u201d (1);<\/p>\n<p style=\"text-align: justify;\">&#8211;\u00a0siamo chiamati \u201cad impegnarci totalmente con lui e ad obbedire alla sua sacra volont\u00e0\u201d (2) .<\/p>\n<p style=\"text-align: justify;\">Il papa allora propone un\u2019applicazione concreta: formare un gruppo di dialogo per cercare un terreno comune. Tale terreno va trovato a diversi livelli:<\/p>\n<p style=\"text-align: justify;\">a)\u00a0Il primo \u00e8 trovare valori che garantiscano \u201cil rispetto reciproco, della solidariet\u00e0 e della pace\u201d.<\/p>\n<p style=\"text-align: justify;\">\u201cRispetto\u201d qui significa anche che vi sono differenze che occorre garantire e accoglierle. Ad esempio, un musulmano pu\u00f2 dire a un cristiano: io non sono d\u2019accordo su quel che tu credi, che cio\u00e8 Ges\u00f9 ha natura umana e divina. Voi cristiani siete politeisti perch\u00e9 mettete affianco al Dio unico, i vostro Ges\u00f9 Cristo e lo Spirito Santo, cio\u00e8 altri d\u00e8i. Io dico: cerchiamo di vivere il rispetto reciproco.<\/p>\n<p style=\"text-align: justify;\">Tu hai pieno diritto nel dire che la concezione islamica esclude la Trinit\u00e0, la divino-umanit\u00e0. Ma lasciami il diritto di poter dire ad esempio che Maometto non \u00e8 un inviato di Dio. Posso riconoscere che egli \u00e8 una grande personalit\u00e0 sul piano umano, politico, un riformatore sociale e spirituale, che ha portato anche rilievi negativi, ma non \u00e8 un profeta. Ho il diritto di dirlo o no? Come tu hai diritto a dire che non credi nella divinit\u00e0 di Cristo \u2013 e sei coerente nella tua fede \u2013, noi anche abbiamo diritto di dire quello che pensiamo su Maometto (3). Insomma, non esistono degli argomenti \u201ctab\u00f9\u201d, ma esistono solo dei modi e dei metodi tab\u00f9, perch\u00e9 violenti e irrispettosi.<\/p>\n<p style=\"text-align: justify;\">b)\u00a0L\u2019altro livello \u00e8 quello della vita umana come \u201csacra\u201d. Questa dimensione etica abbraccia un campo molto largo, che va dal rigetto dell\u2019aborto fino alla fine naturale della vita umana. Ma \u00e8 inserita anche la non violenza, che \u00e8 una delle forme pi\u00f9 nobili del rispetto della vita umana. E significa anche un amore a tutte le opere della cultura e del progresso umano: per l\u2019uguaglianza fra gli uomini, per i diritti umani: un rispetto alla vita e a ci\u00f2 che la fa esprimere e fiorire.<\/p>\n<p style=\"text-align: justify;\">Nel discorso alla Curia romana del 22 dicembre 2006, il papa diceva: \u201c\u00e8 necessario accogliere le vere conquiste dell&#8217;illuminismo, i diritti dell&#8217;uomo e specialmente la libert\u00e0 della fede e del suo esercizio, riconoscendo in essi elementi essenziali anche per l&#8217;autenticit\u00e0 della religione\u201d.<\/p>\n<p style=\"text-align: justify;\">Per Benedetto XVI, \u201cil contenuto del dialogo tra cristiani e musulmani sar\u00e0 in questo momento soprattutto quello di incontrarsi in questo impegno per trovare le soluzioni giuste\u201d. Insieme ai musulmani, impegnarsi \u201ccontro la violenza e per la sinergia tra fede e ragione, tra religione e libert\u00e0\u201d. Il fondamento \u00e8 \u201cla dignit\u00e0 di ogni persona umana\u201d, espressa dai diritti umani.<\/p>\n<p style=\"text-align: justify;\">A questo punto il papa suggerisce ai 138 quattro temi da affrontare:<\/p>\n<p style=\"text-align: justify;\">1)\u00a0diritti umani. Questo \u00e8 il primo punto per fondare il dialogo;<\/p>\n<p style=\"text-align: justify;\">2)\u00a0conoscenza obbiettiva della religione dell\u2019altro. Ossia conoscere l\u2019altro per come l\u2019altro si definisce. Il cristiano deve conoscere l\u2019Islam per come il Corano e i musulmani odierni lo definiscono; il musulmano deve conoscere il cristianesimo attraverso i Vangeli e l\u2019insegnamento della Chiesa (4). Una conoscenza obbiettiva \u00e8 fondamentale per un reale rapporto;<\/p>\n<p style=\"text-align: justify;\">3)\u00a0Condivisione dell\u2019esperienza religiosa. Questo elemento non \u00e8 stato messo in evidenza finora. L\u2019esperienza religiosa \u00e8 pi\u00f9 della conoscenza. Riconosce che anche se il dogma dell\u2019altro, non \u00e8 quello mio, egli pu\u00f2 arricchirmi dal punto di vista umano e spirituale. Alcuni giorni fa, in volo da Beirut a Parigi, ho potuto passare 3 ore a colloquiare con un giovane africano proveniente dalla Mecca, dove aveva compiuto il pellegrinaggio. \u00c8 stato bellissimo e profondo. E questo ci \u00e8 servito ad apprezzare, ma anche rettificare l\u2019immagine che abbiamo l\u2019uno dell\u2019altro (5).<\/p>\n<p style=\"text-align: justify;\">4)\u00a0Impegnarsi per educare i giovani. Se non prepariamo i giovani a vivere gi\u00e0 oggi questo rispetto reciproco, domani ci potremmo trovare ancora in un conflitto fra noi.<\/p>\n<p style=\"text-align: justify;\">Fin qui la lettera del Papa: breve, ma molto densa, segno della sua profonda riflessione.<\/p>\n<p style=\"text-align: justify;\"><strong>III. La risposta al papa di Ghazi Ibn Talal: solo dialogo teologico<\/strong><\/p>\n<p style=\"text-align: justify;\">La risposta dei 138, a firma di Ghazi Ibn Talal, principe di Giordania, data dal 12 dicembre 2007. Dopo alcuni preamboli, la lettera dice che essi accettano l\u2019idea del dialogo e che in marzo invieranno alcuni rappresentanti per precisare i dettagli dell\u2019organizzazione e delle procedure.<\/p>\n<p style=\"text-align: justify;\">Ma poi (al n. 4 del testo) propongono una distinzione tra intrinseco e estrinseco, e spiegano: \u00abPer \u201cintrinseco\u201d intendiamo ci\u00f2 che si riferisce alle nostre anime e alle loro caratteristiche interiori, e per \u201cestrinseco\u201d intendiamo ci\u00f2 che \u00e8 riferito al mondo e quindi alla societ\u00e0\u00bb.<\/p>\n<p style=\"text-align: justify;\">Essi propongono di partire dalla Lettera da loro scritta, \u201cUna parola comune tra noi e voi\u201d, e di concentrarsi \u00abessenzialmente un&#8217;affermazione del Dio Unico, e del duplice comandamento di amare Lui ed il prossimo\u00bb. Tutto il resto appartiene all\u2019estrinseco, di cui fa parte anche l\u2019impegno nella societ\u00e0.<\/p>\n<p style=\"text-align: justify;\">Onestamente, trovo che questa distinzione sia debole e perfino non islamica. Perch\u00e9 se \u201cintrinseco\u201d \u00e8 l\u2019anima ed \u201cestrinseco\u201d \u00e8 il mondo e la societ\u00e0, allora significa che il Corano parla tantissimo delle cose \u201cestrinseche\u201d e pochissimo delle cose \u201cintrinseche\u201d.<\/p>\n<p style=\"text-align: justify;\">Il Corano parla del mondo, del commercio, della vita in societ\u00e0, della guerra, del matrimonio, ecc, ma parla pochissimo dell\u2019anima e del rapporto con Dio. Ma soprattutto il Corano non fa mai questa distinzione. Anzi, il problema dell\u2019Islam \u00e8 proprio quello di non fare alcuna differenza fra questi due livelli. Come mai i 138 vogliono affrontare solo le cose \u201cintrinseche\u201d? Temo che abbiano paura di affrontare tutta la realt\u00e0 delle due religioni.<\/p>\n<p style=\"text-align: justify;\">La risposta di Ghazi continua: \u201c\u00c8 su questa comune base intellettuale e spirituale, quindi, che capiamo che stiamo perseguendo, Dio volendo, un dialogo sui tre temi generali di dialogo che Sua Eminenza ha saggiamente menzionato nella sua lettera:<\/p>\n<p style=\"text-align: justify;\">1) \u201ceffettivo rispetto della dignit\u00e0 di ogni persona umana\u201d;<\/p>\n<p style=\"text-align: justify;\">2) \u201cconoscenza obiettiva della religione dell&#8217;altro\u201d attraverso \u201cla condivisione dell&#8217;esperienza religiosa\u201d; e<\/p>\n<p style=\"text-align: justify;\">3) \u201cun impegno comune alla promozione del rispetto e dell&#8217;accettazione reciproci tra i giovani\u201d(6).<\/p>\n<p style=\"text-align: justify;\">Il principe continua esortando al dialogo, citando un convegno organizzato dalla Comunit\u00e0 di sant\u2019Egidio.<\/p>\n<p style=\"text-align: justify;\">E infine essi si distaccano da \u201calcune recenti dichiarazioni provenienti dal Vaticano e da consiglieri vaticani \u2013 che non possono essere sfuggite all&#8217;attenzione di Sua Eminenza \u2013\u2013 riguardo al principio di fondo del dialogo\u201d.\u00a0 Penso che le persone a cui si riferiscono siano proprio il card. Tauran (e forse p. Christian W. Troll e me stesso), che abbiamo espresso le nostre difficolt\u00e0 sulla possibilit\u00e0 di un dialogo teologico fra cristiani e musulmani.<\/p>\n<p style=\"text-align: justify;\">Lo stesso principe dice di ritenere \u201cinerentemente\u201d impossibile \u201cun accordo teologico completo tra cristiani e musulmani\u201d, ma nonostante ci\u00f2 egli desidera che il dialogo avvenga su questo piano, \u00ab\u201cteologico\u201d o \u201cspirituale\u201d o in qualsivoglia altro modo \u2013 per la ricerca del bene comune e per il bene del mondo intero, Dio volendo\u00bb.<\/p>\n<p style=\"text-align: justify;\">Il principe dunque riafferma il suo impegno di collaborazione sul piano teologico e spirituale. E qui vi \u00e8 un\u2019ambiguit\u00e0: l\u2019Islam, pi\u00f9 che il cristianesimo, mescola il teologico con il politico e perfino con il militare. E loro qui pretendono di parlare solo del teologico.<\/p>\n<p style=\"text-align: justify;\">Con ogni probabilit\u00e0 dietro il pensiero di Ghazi vi \u00e8 qualche teologo. Penso a un\u2019intervista a CNS del 31 ottobre scorso, del prof. Aref Ali Nayed riprodotta su &#8220;Islamica magazine&#8221;, che ripete: \u201cmolti teologi musulmani non sono affatto interessati a un dialogo puramente etico-sociale\u201d; il vero \u201cdialogo deve essere teologicamente e spiritualmente fondato\u201d.<\/p>\n<p style=\"text-align: justify;\">Alcuni mesi fa egli ha anche affermato che la sua concezione del dialogo \u201cesclude tutto ci\u00f2 che non \u00e8 teologico e spirituale\u201d. Ma onestamente non si pu\u00f2 fare questa distinzione: non si possono non affrontare le conseguenze umane e sociali delle posizioni teologiche.<\/p>\n<p style=\"text-align: justify;\"><strong>IV &#8211; Conclusione<\/strong><\/p>\n<p style=\"text-align: justify;\">Per riassumere, perci\u00f2, dobbiamo dire che si comincia a vedere qualche buon frutto importante per il dialogo. E bisogna ricordare che tutto \u00e8 partito da Regensburg, da quella lezione magistrale che sembrava aver distrutto ogni base per il dialogo ed invece lo ha fatto risorgere.<\/p>\n<p style=\"text-align: justify;\">Il discorso di Regensburg era impostato sul regno della ragione come fondamento del dialogo. Il che suppone tutto il movimento delle religione di fronte all\u2019illuminismo, ma senza impoverire la ragione. Insomma, il fondamento di tutto non \u00e8 la religione, ma la ragione umana che \u00e8 ci\u00f2 che \u00e8 comune a tutti gli esseri umani (7).<\/p>\n<p style=\"text-align: justify;\">Il discorso di Regensburg parte proprio da questo problema: come trovare un fondamento comune all\u2019umanit\u00e0 e alle religioni, compreso anche l\u2019Islam?<\/p>\n<p style=\"text-align: justify;\">Nello stato moderno, il fondamento comune si esprime con la dichiarazione universale dei diritti umani, della libert\u00e0 di religione, ecc\u2026 Anche nel dialogo fra cristiani e musulmani, occorre prendere questi come la base del dialogo, altrimenti non arriveremo a nulla. In passato molti teologi musulmani hanno rifiutato la dichiarazione universale dei diritti umani e ne hanno stilato una \u201cislamica\u201d, accusando quella \u201cuniversale\u201d di essere solo \u201coccidentale\u201d. Ma questo nega che vi possa essere universalit\u00e0 e quindi nega che possiamo avere principi comuni. Questo \u00e8 il fondamento del conflitto fra il mondo islamico e l\u2019occidente, o il resto del mondo.<\/p>\n<p style=\"text-align: justify;\">Kofi Annan, invitato una volta dall\u2019Organizzazione dei Paesi islamici aprendo un convegno, ha detto con chiarezza: non pu\u00f2 esistere una dichiarazione \u201cislamica\u201d, \u201cafricana\u201d, \u201ccristiana\u201d \u201cbuddista\u201d dei diritti dell\u2019uomo. La dichiarazione o \u00e8 universale, o non pu\u00f2 esistere.<\/p>\n<p style=\"text-align: justify;\">Invece la lettera del principe al-Ghazi sembra dire che i diritti umani non importano e sono solo una questione politica. Interessa solo il dialogo teologico. Ma a cosa serve parlare del Dio unico, se non riconosco che l\u2019uomo ha una dignit\u00e0 assoluta ad immagine di Dio? Che la libert\u00e0 di coscienza \u00e8 sacra; che il credente non ha pi\u00f9 diritti del miscredente; che l\u2019uomo non ha pi\u00f9 diritti della donna; ecc..?<\/p>\n<p style=\"text-align: justify;\">Bisogna affermare che l\u2019uomo \u00e8 anteriore alla religione: rispettare l\u2019uomo viene prima del rispetto della religione. \u00c9 questo l\u2019approccio cristiano.<\/p>\n<p style=\"text-align: justify;\">Non vorrei che alcuni teologi, trovandosi in difficolt\u00e0 sull\u2019affermazione della dignit\u00e0 di ogni uomo, cercano una via d\u2019uscita nel dialogo teologico. Ma in questo modo si rischia di produrre solo falsit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Ma questo \u00e8 un problema interno anche all\u2019Islam in se stesso. Finch\u00e9 esso non avr\u00e0 basato tutto sulla persona umana e reinterpretato la fede alla luce dei diritti umani, non sar\u00e0 mai moderno.<\/p>\n<p style=\"text-align: justify;\">Nelle due dichiarazione islamiche sui diritti umani, si afferma spesso che l\u2019islam ammette i diritti umani, \u201cpurch\u00e9 siano conformi alla legge\u201d. A un lettore ingenuo che legga la traduzione in inglese, questo potrebbe andare anche bene. Il punto \u00e8 che quanto riportato nelle traduzioni inglesi come \u201clegge\u201d, nelle stesure delle dichiarazioni in lingua araba sono tradotte come \u201cconformi alla sharia\u201d. Ci\u00f2 significa che i diritti umani \u201cislamici\u201d rischiano di riproporre le solite ingiustizie e violenze: apostasia, blasfemia, lapidazione, ingiustizie verso le donne e i figli, ecc&#8230; (8) .<\/p>\n<p style=\"text-align: justify;\">Certo, il dialogo interreligioso non pu\u00f2 essere concentrato solo sui diritti umani, ma non pu\u00f2 nemmeno fare come se non ci fosse un grave problema proprio su questa realt\u00e0.<\/p>\n<p style=\"text-align: justify;\">Mi sia permesso per concludere citando un passo della lettera di san Giacomo (2, 14-26), anche se un po\u2019 lungo. Nel nostro contesto mi pare assai importante, sia per la domanda del versetto 19, sia perch\u00e9 fa l\u2019esempio di \u201cAbraham, l\u2019amico di Dio\u201d (Khalil Allah, come diciamo in arabo), cos\u00ec rispettato dai musulmani:<\/p>\n<p style=\"text-align: justify;\"><em>[14] Che giova, fratelli miei, se uno dice di avere la fede ma non ha le opere? Forse che quella fede pu\u00f2 salvarlo? [15] Se un fratello o una sorella sono senza vestiti e sprovvisti del cibo quotidiano [16] e uno di voi dice loro: &#8220;Andatevene in pace, riscaldatevi e saziatevi&#8221;, ma non date loro il necessario per il corpo, che giova? [17] Cos\u00ec anche la fede: se non ha le opere, \u00e8 morta in se stessa. [18] Al contrario uno potrebbe dire: Tu hai la fede ed io ho le opere; mostrami la tua fede senza le opere, ed io con le mie opere ti mostrer\u00f2 la mia fede. [19] Tu credi che c&#8217;\u00e8 un Dio solo? Fai bene; anche i dem\u00f2ni lo credono e tremano! [20] Ma vuoi sapere, o insensato, come la fede senza le opere \u00e8 senza calore? [21] Abramo, nostro padre, non fu forse giustificato per le opere, quando offr\u00ec Isacco, suo figlio, sull&#8217;altare? [22] Vedi che la fede cooperava con le opere di lui, e che per le opere quella fede divenne perfetta [23] e si comp\u00ec la Scrittura che dice: E Abramo ebbe fede in Dio e gli fu accreditato a giustizia, e fu chiamato amico di Dio. [24] Vedete che l&#8217;uomo viene giustificato in base alle opere e non soltanto in base alla fede. [25] Cos\u00ec anche Raab, la meretrice, non venne forse giustificata in base alle opere per aver dato ospitalit\u00e0 agli esploratori e averli rimandati per altra via? [26] Infatti come il corpo senza lo spirito \u00e8 morto, cos\u00ec anche la fede senza le opere \u00e8 morta.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Note:<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>1)<\/strong> Che saremo giudicati sulle azioni, sui fatti, \u00e8 un pensiero comune a cristiani e musulmani. Il Corano parla di \u00abcoloro che credono in Dio e nell\u2019Ultimo Giorno e compiono il bene\u00bb (2:62 = 5:69). Ma ci\u00f2 significa che c\u2019\u00e8 un\u2019etica \u2013 che pu\u00f2 essere anche comune. Costruire un\u2019etica comune sarebbe una cosa molto importante. Gi\u00e0 in passato si \u00e8 avuto qualcosa di simile. Alla Conferenza Onu del Cairo sulla popolazione e lo sviluppo, nel 1994, il Vaticano ha votato con i paesi islamici. Diversi ambasciatori hanno criticato la Santa Sede perch\u00e9 andava con gli integralisti. In realt\u00e0 su questioni di diritto alla vita, cristiani e musulmani convergono. Lo stupore viene solo dall\u2019occidente secolarizzato, che ha creato un\u2019etica relativista, che lascia decidere all\u2019individuo, in modo soggettivo, ci\u00f2 che \u00e8 bene e ci\u00f2 che \u00e8 male. Questo punto esige un lavoro urgente e grande.<\/p>\n<p style=\"text-align: justify;\"><strong>2)<\/strong> Quando si dice questo, il musulmano si trova perfettamente a suo agio perch\u00e8 l\u2019obbedienza \u00e8 la struttura di vita dell\u2019uomo islamico, \u00e8 l\u2019abbandono alla volont\u00e0 di Dio, l\u2019isl\u00e2m. E anche per il cristiano, la dedizione a Dio (e agli uomini) \u00e8 un ideale grande. Ma su questo punto \u00e8 necessario allargare e precisare il discorso: cosa significa siamo chiamati \u201ca dedicarci totalmente\u201d? Per un estremista islamico, dedicarsi a Dio potrebbe significare anche uccidere, mettere una bomba, farsi saltare in aria. Anche qui risalta una differenza fra cristiani e musulmani, su cui \u00e8 necessario impegnarsi: la non-violenza \u00e8 una scelta spirituale, non politica.<\/p>\n<p style=\"text-align: justify;\"><strong>3)<\/strong> Su questo punto noi cristiani nel mondo arabo soffriamo tanto, perch\u00e8 non ci \u00e8 lecito dire davvero quello che pensiamo. Spesso i musulmani ci chiedono \u201cuno scambio di favori\u201d: noi crediamo che Ges\u00f9 \u00e8 un profeta, voi dovete credere che Maometto \u00e8 un profeta.<\/p>\n<p style=\"text-align: justify;\"><strong>4)<\/strong> in questa conoscenza obbiettiva reciproca, il pericolo maggiore lo corrono i musulmani. Essendo l\u2019islam venuto dopo del cristianesimo, e essendoci nel Corano riferimenti a Ges\u00f9, a Maria, e ai cristiani, molto spesso i musulmani non fanno la fatica di conoscere il cristianesimo per come i cristiani si comprendono, ma si accontentano di quello che dice il Corano. I cristiani, invece, per scoprire l\u2019Islam hanno solo la possibilit\u00e0 di conoscerlo leggendo il Corano.<\/p>\n<p style=\"text-align: justify;\"><strong>5)<\/strong> Questo significa che possiamo condividere la religiosit\u00e0 senza rinunciare ai nostri principi. Si pu\u00f2 anche pensare di pregare insieme. Tante volte in passato si \u00e8 fatta la critica a Ratzinger che era negativo sugli incontri di Assisi, dove dal 1986, personalit\u00e0 religiose si sono incontrati a pregare. La polemica che \u00e8 scaturita tante volte era se persone di diverse religioni potevano pregare insieme. La posizione dell\u2019allora card. Ratzinger era che bisognava evitare tutto ci\u00f2 che poteva suggerire confusione o sincretismo. Ma pregare insieme, come l\u2019ha fatto il papa a Istanbul nella moschea, \u00e8 il massimo del rispetto e del dialogo.<\/p>\n<p style=\"text-align: justify;\"><strong>6)<\/strong> Va notato che essi non si sono accorti che i punti citati dal papa sono 4 e non 3: la condivisione dell\u2019esperienza religiosa, nel testo del papa, \u00e8 un 3\u00b0 punto.<\/p>\n<p style=\"text-align: justify;\"><strong>7)<\/strong> Su questo fatto, la teologia islamica del X secolo aveva le idee molto chiare e rispettava un fondamento comune a tutti gli uomini.\u00a0 Poi il mondo islamico si \u00e8 rinchiuso sempre di pi\u00f9, perfino contro i musulmani razionalisti (come Averro\u00e9).<\/p>\n<p style=\"text-align: justify;\"><strong>8)<\/strong> Vale la pena domandarsi anche quanto peso ha avuto la Lettera dei 138 nel mondo islamico. Nel campo degli esperti vi \u00e8 stata una crescita dell\u2019assenso: da 138 firmatari si \u00e8 passati a 216. Ma nella popolazione non \u00e8 passato nulla. Io ho visto solo pochi articoli in lingua araba, su giornali arabi e islamici. Nessuno di essi faceva un\u2019analisi del contenuto della lettera dei 138. Alcuni davano solo la notizia bruta, altri raccontava solo che cristiani e musulmani volevano incontrarsi sulla fede del Dio unico. Non si pu\u00f2 dire quindi che questa lettera abbia mosso il mondo islamico.<\/p>\n<p style=\"text-align: justify;\">(A.C. Valdera)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Asianews, 9 gennaio 2008 Rappresentanti vaticani e dotti musulmani si incontreranno a Roma in marzo prossimo per mettere a punto alcune piste per il dialogo fra cristiani e musulmani. Si rischia il vuoto o la falsit\u00e0 se il dialogo non affronta non solo la teologia, ma i problemi concreti delle due comunit\u00e0. di Samir Khalil &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":30613,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[110,5,34],"tags":[517],"class_list":["post-3202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-benedetto-xvi","category-chiesa","category-dialogo-con-l-islam","tag-islam-dialogo","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019improbabile dialogo di Benedetto XVI con i 138 saggi musulmani - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019improbabile dialogo di Benedetto XVI con i 138 saggi musulmani - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-29T07:31:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-09T11:38:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/BenedettoXVI_islam.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"215\" \/>\n\t<meta property=\"og:image:height\" content=\"149\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"L\u2019improbabile dialogo di Benedetto XVI con i 138 saggi musulmani\",\"datePublished\":\"2009-04-29T07:31:03+00:00\",\"dateModified\":\"2016-02-09T11:38:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\\\/\"},\"wordCount\":3636,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/BenedettoXVI_islam.jpg\",\"keywords\":[\"Islam dialogo\"],\"articleSection\":[\"Benedetto XVI\",\"Chiesa\",\"Islam dialogo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\\\/\",\"name\":\"L\u2019improbabile dialogo di Benedetto XVI con i 138 saggi musulmani - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/BenedettoXVI_islam.jpg\",\"datePublished\":\"2009-04-29T07:31:03+00:00\",\"dateModified\":\"2016-02-09T11:38:23+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/BenedettoXVI_islam.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/BenedettoXVI_islam.jpg\",\"width\":215,\"height\":149},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019improbabile dialogo di Benedetto XVI con i 138 saggi musulmani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019improbabile dialogo di Benedetto XVI con i 138 saggi musulmani - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019improbabile dialogo di Benedetto XVI con i 138 saggi musulmani - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-04-29T07:31:03+00:00","article_modified_time":"2016-02-09T11:38:23+00:00","og_image":[{"width":215,"height":149,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/BenedettoXVI_islam.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"18 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"L\u2019improbabile dialogo di Benedetto XVI con i 138 saggi musulmani","datePublished":"2009-04-29T07:31:03+00:00","dateModified":"2016-02-09T11:38:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\/"},"wordCount":3636,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/BenedettoXVI_islam.jpg","keywords":["Islam dialogo"],"articleSection":["Benedetto XVI","Chiesa","Islam dialogo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\/","name":"L\u2019improbabile dialogo di Benedetto XVI con i 138 saggi musulmani - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/BenedettoXVI_islam.jpg","datePublished":"2009-04-29T07:31:03+00:00","dateModified":"2016-02-09T11:38:23+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/BenedettoXVI_islam.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/BenedettoXVI_islam.jpg","width":215,"height":149},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/limprobabile-dialogo-di-benedetto-xvi-con-i-138-saggi-musulmani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"L\u2019improbabile dialogo di Benedetto XVI con i 138 saggi musulmani"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3202"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3202\/revisions"}],"predecessor-version":[{"id":30614,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3202\/revisions\/30614"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/30613"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}