{"id":3171,"date":"2009-04-24T13:38:21","date_gmt":"2009-04-24T11:38:21","guid":{"rendered":""},"modified":"2016-07-20T16:49:19","modified_gmt":"2016-07-20T14:49:19","slug":"la-ribellione-delle-masse","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-ribellione-delle-masse\/","title":{"rendered":"La ribellione delle masse"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-36117\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/radical_chic.jpg\" alt=\"radical_chic\" width=\"165\" height=\"200\" \/>Corriere della Sera,<\/strong> 3 maggio 2008<\/div>\n<p style=\"text-align: center;\">di <strong>Ernesto Galli della Loggia<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00abArrogante\u00bb, \u00aboligarchico \u00bb, \u00ablontano dalle masse e vicino ai salotti\u00bb: si sprecano le analisi che rimproverano al Partito democratico di aver perso le elezioni a causa del suo essersi sempre pi\u00f9 rinchiuso nei recinti della \u00abcasta\u00bb, smarrendo il contatto con la realt\u00e0 italiana e alienandosi parti rilevanti del proprio elettorato, specie popolare.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Comunque stiano le cose, di sicuro esse sono apparse cos\u00ec agli occhi di molti e qualche buon motivo, allora, deve pure esserci. Ma va cercato non gi\u00e0 nell&#8217;ultimo paio di anni, nel tratto pi\u00f9 o meno sbrigativo di questo o quel leader, nelle candidature pi\u00f9 o meno paracadutate dall&#8217;alto, nelle mises un po&#8217; troppo sul \u00absemplice ma raffinato\u00bb di Barbara Pollastrini o di Giovanna Melandri, bens\u00ec in quello che \u00e8 successo in Italia almeno negli ultimi due decenni.<\/div>\n<p style=\"text-align: justify;\">A cominciare dall&#8217;epoca di Mani Pulite e subito dopo, allorch\u00e9 parti via via crescenti dell&#8217;establishment italiano, per scampare al naufragio dei suoi tradizionali referenti politici \u2014 la Democrazia Cristiana, il Partito socialista e quello Repubblicano \u2014 corsero a rifugiarsi sotto le ali ospitali dei postcomunisti.<\/p>\n<p style=\"text-align: justify;\">Il furbo dirigente Rai, la giovane industriale in sintonia con i tempi, il navigato notabile meridionale, il pm in carriera, il banchiere di peso, il direttore generale desideroso di non perdere il posto, tutti andarono inevitabilmente \u00aba sinistra\u00bb, per non dire di buona met\u00e0 e forse pi\u00f9 dell&#8217;intero gruppo dirigente democristiano. Tutti sicuri che l\u00ec era il nuovo baricentro del potere: l\u00ec le nuove combinazioni decisive, le assegnazioni di incarichi, i riconoscimenti ambiti.<\/p>\n<p style=\"text-align: justify;\">Fuori dalla \u00absinistra\u00bb (o da quella sua versione allargata che da l\u00ec a poco sarebbe stato l&#8217;Ulivo), della classe dirigente italiana non rimase praticamente che ben poco. E quel poco, per giunta, mantenne quasi sempre il pi\u00f9 assoluto silenzio: accrescendo cos\u00ec ancor di pi\u00f9 la visibilit\u00e0 pubblica dell&#8217;altra parte, quella della grande trasmigrazione a sinistra. Il cui adeguato involucro ideologico fu subito approntato: l&#8217;ideologia della \u00abdifesa della Costituzione\u00bb, opportunamente messa a punto e diffusa proprio allora dall&#8217;ex sinistra democristiana con il potente ausilio strategico del Presidente della Repubblica Oscar Luigi Scalfaro.<\/p>\n<p style=\"text-align: justify;\">A tutto ci\u00f2 il Pds e poi i Diesse aprirono, anzi spalancarono, le braccia. Essi videro probabilmente in questa generale corsa verso di loro delle classi dirigenti italiane l&#8217;annuncio inaspettato di una qualche raggiunta egemonia. Non si accorsero che era invece la premessa del proprio snaturamento. Della propria mutazione da partito popolare a partito di \u00abquelli che contano \u00bb. Ancora peggio: di quelli sicuri che saranno sempre loro a contare.<\/p>\n<p style=\"text-align: justify;\">Ma se le cose hanno potuto svolgersi in questo modo \u00e8 perch\u00e9 gi\u00e0 il Partito comunista \u2014 di cui il Pds e poi i Diesse hanno rappresentato una sorta di aggiornamento, sempre pi\u00f9 aggiornato se si vuole ma sempre legato per mille fili alla matrice originaria \u2014 gi\u00e0 il Partito comunista, dicevo, non era mai stato in realt\u00e0 un partito popolare nel vero senso della parola. Il Pci fu sempre altra cosa, infatti, rispetto ai grandi partiti socialdemocratici europei, per esempio al Labour britannico o alla Spd tedesca.<\/p>\n<p style=\"text-align: justify;\">Partiti dove forte si \u00e8 mantenuto, anche negli usi e nei rituali, un tradizionale sostrato culturale e antropologico schiettamente popolaresco, e perfino plebeo, espresso adeguatamente fino a tempi recenti da figure di capi tratti per l&#8217;appunto dai ceti popolari e dai suoi mestieri, con i gusti e i modelli espressivi relativi. Nel Pci no.<\/p>\n<p style=\"text-align: justify;\">Nel Pci Palmiro Togliatti tradusse l&#8217;antica diffidenza leninista per la spontaneit\u00e0 delle classi subalterne e insieme la lezione egemonica gramsciana in una direzione opposta: cercare di fare largo spazio nel partito, e specie tra i massimi dirigenti, a persone di buona cultura, ancor meglio se di buona famiglia, sostanzialmente a intellettuali borghesi.<\/p>\n<p style=\"text-align: justify;\">Al \u00abMigliore\u00bb non sarebbe mai venuto in mente, tanto per dire, che un capocellula di Mirafiori contasse quanto un professore della Normale. Caratteristica gi\u00e0 del Pci, insomma, fu un forte elitismo sprezzante di tutto ci\u00f2 che sapesse di \u00abpiccolo-borghese\u00bb, pur se innestato su una penetrante attenzione al sentire delle \u00abmasse\u00bb considerate sempre, per\u00f2, alla luce di un pedagogico paternalismo disciplinatore.<\/p>\n<p style=\"text-align: justify;\">Da qui il grande fascino che, anche nei tempi della pi\u00f9 aspra conflittualit\u00e0, i comunisti hanno di continuo esercitato sulla borghesia italiana: precisamente per la loro capacit\u00e0 di presentarsi come un partito fatto apposta per dirigere, per governare, luogo vocazionale del potere, di un potere capace di mettere insieme l&#8217;alto e il basso della societ\u00e0.<\/p>\n<p style=\"text-align: justify;\">Ma la formula di successo del vecchio Pci, la sua miscela singolare di alto e basso in tanto potevano reggere finch\u00e9 il partito era obbligatoriamente lontano dal potere. Quando dopo il &#8217;94 le cose sono cambiate, la formula allora non ha pi\u00f9 tenuto, l&#8217;alto e il basso sono progressivamente andati ognuno per conto suo, e del paternalismo pedagogico le masse, alla fine, non hanno saputo pi\u00f9 che cosa farsene.<\/p>\n<p style=\"text-align: justify;\">(A.C. Valdera)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corriere della Sera, 3 maggio 2008 di Ernesto Galli della Loggia \u00abArrogante\u00bb, \u00aboligarchico \u00bb, \u00ablontano dalle masse e vicino ai salotti\u00bb: si sprecano le analisi che rimproverano al Partito democratico di aver perso le elezioni a causa del suo essersi sempre pi\u00f9 rinchiuso nei recinti della \u00abcasta\u00bb, smarrendo il contatto con la realt\u00e0 italiana e &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-ribellione-delle-masse\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":36117,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[1183,1231],"class_list":["post-3171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica-nazionale","tag-pd","tag-sinistre","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La ribellione delle masse - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-ribellione-delle-masse\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La ribellione delle masse - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-ribellione-delle-masse\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-24T11:38:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-20T14:49:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/radical_chic.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"204\" \/>\n\t<meta property=\"og:image:height\" content=\"247\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-ribellione-delle-masse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-ribellione-delle-masse\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La ribellione delle masse\",\"datePublished\":\"2009-04-24T11:38:21+00:00\",\"dateModified\":\"2016-07-20T14:49:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-ribellione-delle-masse\\\/\"},\"wordCount\":807,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-ribellione-delle-masse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/radical_chic.jpg\",\"keywords\":[\"PD\",\"sinistre\"],\"articleSection\":[\"Politica nazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-ribellione-delle-masse\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-ribellione-delle-masse\\\/\",\"name\":\"La ribellione delle masse - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-ribellione-delle-masse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-ribellione-delle-masse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/radical_chic.jpg\",\"datePublished\":\"2009-04-24T11:38:21+00:00\",\"dateModified\":\"2016-07-20T14:49:19+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-ribellione-delle-masse\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-ribellione-delle-masse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-ribellione-delle-masse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/radical_chic.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/radical_chic.jpg\",\"width\":204,\"height\":247},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-ribellione-delle-masse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La ribellione delle masse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La ribellione delle masse - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-ribellione-delle-masse\/","og_locale":"it_IT","og_type":"article","og_title":"La ribellione delle masse - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-ribellione-delle-masse\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-04-24T11:38:21+00:00","article_modified_time":"2016-07-20T14:49:19+00:00","og_image":[{"width":204,"height":247,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/radical_chic.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-ribellione-delle-masse\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-ribellione-delle-masse\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La ribellione delle masse","datePublished":"2009-04-24T11:38:21+00:00","dateModified":"2016-07-20T14:49:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-ribellione-delle-masse\/"},"wordCount":807,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-ribellione-delle-masse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/radical_chic.jpg","keywords":["PD","sinistre"],"articleSection":["Politica nazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-ribellione-delle-masse\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-ribellione-delle-masse\/","name":"La ribellione delle masse - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-ribellione-delle-masse\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-ribellione-delle-masse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/radical_chic.jpg","datePublished":"2009-04-24T11:38:21+00:00","dateModified":"2016-07-20T14:49:19+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-ribellione-delle-masse\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-ribellione-delle-masse\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-ribellione-delle-masse\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/radical_chic.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/radical_chic.jpg","width":204,"height":247},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-ribellione-delle-masse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La ribellione delle masse"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3171"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3171\/revisions"}],"predecessor-version":[{"id":36118,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3171\/revisions\/36118"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/36117"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}