{"id":3170,"date":"2009-04-24T13:31:24","date_gmt":"2009-04-24T11:31:24","guid":{"rendered":""},"modified":"2016-02-26T13:56:40","modified_gmt":"2016-02-26T12:56:40","slug":"la-pornografia-nel-terzo-millennio","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-pornografia-nel-terzo-millennio\/","title":{"rendered":"La pornografia nel terzo millennio"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/porno.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-31077\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/porno.jpg\" alt=\"porno\" width=\"250\" height=\"166\" \/><\/a>Storia &amp; Identit\u00e0<\/strong>, 14 marzo 2008<\/div>\n<p style=\"text-align: center;\">di <strong>Oscar Sanguinetti<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>1.<\/strong> In un articolo di qualche mese fa \u2014 esattamente il 9 aprile 2007 \u2014 il <em>Corriere della Sera<\/em> informava che, secondo una ricerca condotta in Belgio, nei soli Stati Uniti viene immesso <em>\u00ab<\/em>[\u2026] <em>ogni 39 secondi<\/em> online [un] <em>nuovo video porno\u00bb<\/em>.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Il foglio milanese aggiungeva: <em>\u00abMentre finite di leggere questa frase, 28.258 persone stanno cliccando su una pagina web a contenuto pornografico\u00bb<\/em>. <em>\u00abLa vasta ricerca del quotidiano dei Paesi Bassi<\/em> <em>\u201cHet Laatste Nieuws\u201d (HLN) \u2014 \u201cSesso sul web: le cifre nude e crude\u201d \u2014 ha raccolto, analizzato e sintetizzato per la prima volta i dati, le statistiche e gli approfondimenti provenienti da istituzioni, agenzie stampa, emittenti e giornali a livello internazionale tra le quali ABC, AP, la Cia, BBC, China Daily, Crimes Against Children, Forbes, MSN, Nielsen\/NetRatings, The New York Times, PornStudies, SEC filings, Secure Computing Corp, Yahoo!\u00bb<\/em>.<\/div>\n<p style=\"text-align: justify;\">E ancora: <em>\u00abA met\u00e0 del 2006 sono stati scaricati a livello mondiale 1,5 miliardi tra immagini e video a carattere pornografico \u2014 il 35 percento di tutti i downloads\u00bb<\/em>.<\/p>\n<p style=\"text-align: justify;\">A seconda del volume d\u2019affari prodotto da tali accessi e scaricamenti \u00e8 possibile stilare un classifica dei paesi pi\u00f9 dediti a questa pratica. Con 20,5 miliardi di euro sono in testa i cinesi, seguiti dai sudcoreani (19,25 miliardi), dai giapponesi (15 miliardi) e dagli statunitensi (9,98 miliardi). Agli ultimi posti gli italiani (soli 12 euro a testa per il sesso in rete); fanalino di coda i belgi (9 euro) e i tedeschi (6 euro).<\/p>\n<p style=\"text-align: justify;\"><strong>2.<\/strong> Questo il fatto, ed \u00e8 difficile non rilevarne la gravit\u00e0 oggettiva. E il fatto suggerisce qualche amara riflessione.<\/p>\n<p style=\"text-align: justify;\">Si vede infatti come dai timidi esordi otto-novecenteschi sotto forma di immagini fotografiche <em>os\u00e9e<\/em>, che vedevano per lo pi\u00f9 come fruitori aristocratici annoiati, borghesi secolarizzati, studenti dal sangue ardente, soldati dalle protratte astinenze, siamo arrivati \u2014 anche grazie al Sessantotto americano, soprattutto californiano \u2014 a un autentico e grandioso <em>business<\/em> globale. Questo commercio, se non si auto-limitasse \u2014 per non perdere l\u2019aura di \u00abproibito\u00bb che ne propizia <em>de facto<\/em> il consumo \u2014, invaderebbe il nostro quotidiano come un formaggino o un succo di frutta o una marca di sapone.<\/p>\n<p style=\"text-align: justify;\">Tuttavia dalle botteghe dei barbieri e dal furtivo passamano si \u00e8 ormai passati a forme di canalizzazione e di commercializzazione sempre pi\u00f9 capillarmente invasive, con diversificazioni \u2014 dal pi\u00f9 o meno \u00abpesante\u00bb, o <em>hard<\/em>, fino a forme semi-pornografiche \u2014 a seconda del <em>target <\/em>interessato.<\/p>\n<p style=\"text-align: justify;\">Una diffusione sempre al passo con la tecnologia, che cresce di volume e di penetrazione a ogni evoluzione di quest\u2019ultima, passando da un dato tipo di supporto a uno pi\u00f9 nuovo, cio\u00e8 pi\u00f9 moderno: dai \u00abfilmini\u00bb in bianco e nero destinati ai depravati di inizio secolo \u2014 primo salto di qualit\u00e0: dalle immagini fisse alle immagini in movimento, poi corredate dai \u00abnecessari\u00bb suoni, con tutto l\u2019\u00abarricchimento\u00bb di \u00abeffetti\u00bb che si pu\u00f2 immaginare \u2014, alle riviste patinate degli anni Sessanta-Ottanta \u2014 che per la prima volta si potevano trovare in libera vendita nelle edicole \u2014, pensate per le scuole e per le caserme, alle videocassette, e poi ai canali satellitari \u00abdedicati\u00bb, e ancora ai Cd-Rom e ai Dvd, poi ai telefonini, infine \u2014 ma fino a quando? \u2014 a Internet con la possibilit\u00e0 di <em>hard-core<\/em> \u00abcasalingo\u00bb e le prime esperienze di sesso virtuale, con il passaggio \u2014 l\u2019altro autentico \u00absalto di qualit\u00e0\u00bb \u2014 dalla visione alla possibilit\u00e0 di simulazione.<\/p>\n<p style=\"text-align: justify;\">E dai motori di ricerca al passaparola l\u2019accesso ai siti pornografici di tutte le sfumature oggi non \u00e8 pi\u00f9 un problema.<\/p>\n<p style=\"text-align: justify;\">Ma anche questo non basta: il \u00abmercato\u00bb sta passando infatti da una logica \u00ab<em>pull<\/em>\u00bb a una logica \u00ab<em>push<\/em>\u00bb: in altre parole dall\u2019offerta all\u2019adescamento. Sempre pi\u00f9 spesso capita infatti che si arrivi a contenuti pornografici senza volerlo: o li si trova coperti da innocenti <em>e-mail<\/em> inviateci grazie al commercio di indirizzi di posta elettronica \u2014 che \u00e8 nato partendo dalle liste degli abbonamenti ai vari <em>provider<\/em> \u2014 o si \u00e8 guidati forzatamente su siti pornografici oppure, ancora, ci si imbatte in materiali pornografici coperti da titoli innocenti quando si cerca di scaricare illegalmente software o film dalla rete.<\/p>\n<p style=\"text-align: justify;\">La pornografia costituisce oggi una minaccia di massa, un\u2019alluvione, uno <em>tsunami<\/em> silenzioso ma inarrestabile di fango, un genere di consumo che ha i suoi centri di produzione, i suoi prodotti, i suoi livelli di qualit\u00e0, la sua logistica distributiva, il suo <em>marketing<\/em>, le sue fiere, i suoi \u00absaldi\u00bb, ecc.<\/p>\n<p style=\"text-align: justify;\"><strong>3.<\/strong> Quest\u2019abnorme crescita del \u00abfronte del porno\u00bb \u2014 parodiando il titolo, <em>Fronte del porto<\/em>, di un celebre film di denuncia sociale di Elia Kazan, con Marlon Brando \u2014 \u00e8 stata costantemente accompagnata da una \u00abcopertura\u00bb intellettuale che difendeva in maniera oltranzista il diritto alla libert\u00e0 di pubblicazione, di libero esercizio della sessualit\u00e0 e dei suoi prodromi e introduceva, cos\u00ec come per le droghe, divise in \u00ableggere\u00bb e \u00abpesanti\u00bb, la sottile e devastante distinzione fra <em>hard<\/em> e <em>soft<\/em>, fra erotismo e pornografia, fra informazione sessuale e oscenit\u00e0, fra letteratura e filmografia e prossenetismo di massa.<\/p>\n<p style=\"text-align: justify;\">E, purtroppo, questa alluvione sta avendo effetti devastanti, non solo sui \u00abfruitori\u00bb del prodotto pornografico, ma anche sugli \u00abaddetti\u00bb alla sua fabbricazione e induce una de-moralizzazione diffusa e sempre pi\u00f9 radicale dell\u2019intero corpo sociale.<\/p>\n<p style=\"text-align: justify;\">Nei primi favorisce una visione dei rapporti fra essere umani \u2014 di quelli pi\u00f9 delicati come quelli sessuali e riproduttivi \u2014 sbagliata, deformata in senso peggio che animalesco. E l\u2019abbrutimento generato si traduce nell\u2019aumento dei delitti a sfondo sessuale, nel dilagare sempre pi\u00f9 sfrontato della prostituzione \u2014 di entrambi i sessi, femminile e maschile, adulta e minorile, se non infantile \u2014, nell\u2019abituare le coppie a un tenore di rapporti basato sul piacere e, di conseguenza, fatalmente effimero.<\/p>\n<p style=\"text-align: justify;\">Sempre pi\u00f9 numerose sono soprattutto le ricadute sul piano dei reati che della pornografia produce: sfruttamento della prostituzione, riduzione in schiavit\u00f9, diffusione degli stupefacenti, turismo sessuale, incremento della pedofilia, sempre pi\u00f9 numerose violenze private e familiari \u2014 la cui causa non \u00e8, come alcune incredibili teorie sostengono, la famiglia in quanto organizzazione gerarchica e quindi, di suo, repressiva, ma la famiglia ridotta in condizioni pietose dall\u2019aggressione cui la sottopongono forze che la vogliono dissolvere, in una prospettiva livellatrice. Cresce quindi il disimpegno e il solipsismo non solo materiale ma, soprattutto, psicologico.<\/p>\n<p style=\"text-align: justify;\">Quanto ai protagonisti, si rileva che la crescita del volume di affari moltiplica il numero degli \u00abaddetti\u00bb e crea sempre pi\u00f9 vittime, volontarie ma pi\u00f9 spesso coatte, di organizzazioni, di reti e di circuiti nei quali sono regola la violenza, l\u2019asservimento, l\u2019abbrutimento, la necrofilia, la pedofilia, fino all\u2019autentico sadismo omicida.<\/p>\n<p style=\"text-align: justify;\"><strong>4.<\/strong> Ma si tratta solo di <em>business<\/em>? \u00c8 sempre il profitto a far da criterio ultimo dell\u2019\u00abimpresa\u00bb? Se togliamo il profitto, tutto si spegne? O c\u2019\u00e8 di pi\u00f9?<\/p>\n<p style=\"text-align: justify;\">\u00c8 difficile trarre delle conclusioni \u00abscientifiche\u00bb, perch\u00e9 tutto sommato poco si sa \u2014 ma non nulla del tutto \u2014 delle tenebrose cloache da cui tracima la profluvie di materiale osceno.<\/p>\n<p style=\"text-align: justify;\">Sono per\u00f2 molteplici i sintomi che attestano come sia in atto un\u2019operazione su scala globale e dagl\u2019intenti che vanno al di l\u00e0 del puro guadagno. Come per la droga, la pornografia non sempre \u00e8 a pagamento e comunque ce n\u2019\u00e8 \u00abper tutte le borse\u00bb e ne esistono svariate graduazioni: dal genere \u00abdi iniziazione\u00bb, alla \u00ableggera\u00bb alla \u00abpesante\u00bb.<\/p>\n<p style=\"text-align: justify;\">Abbonda in maniera straordinaria \u2014 per numero di testate, di canali, di siti, di titoli e numero di copie di Dvd e altro materiale \u2014, la si trova ovunque: dalle edicole \u2014 forse le pi\u00f9 spudorate nell\u2019esibizione \u2014 ai <em>sexy shop<\/em>, ai canali locali \u00abpuliti\u00bb \u2014 autentici \u00abdottor Jekyll\u00bb, che trasmettono dibattiti e pubblicit\u00e0 fino alle 23, poi cambiano diabolicamente volto, trasformandosi in \u00abmister Hyde\u00bb e veicolando un\u2019autentica colluvie di oscenit\u00e0 \u2014, alle bancarelle di libri usati, ai mercati popolari\u2026<\/p>\n<p style=\"text-align: justify;\">In questo interesse a che la pornografia divenga un \u00abnormale\u00bb oggetto di \u00abconsumo\u00bb si avverte lo stesso afflato tendenzialmente \u00abdisinteressato\u00bb che si coglie nella propaganda religiosa, nell\u2019apostolato cristiano: qui ti regalano un santino o un opuscolo, l\u00e0 ti offrono il Dvd sottocosto\u2026<\/p>\n<p style=\"text-align: justify;\"><strong>5.<\/strong> Lasciando da parte la voce del sociologo \u2014 non perch\u00e9 sia inutile, ma perch\u00e9 credo che il fondo del problema sia altrove \u2014, che per spiegare il fenomeno pornografico farebbe ricorso a categorie come \u00absociet\u00e0 dei consumi\u00bb, \u00absecolarizzazione\u00bb, liberazione dai costumi patriarcali, \u00ab<em>paradigm shift<\/em>\u00bb della mentalit\u00e0 indotto dal processo di modernizzazione, ecc. (1), occorre puntare lo sguardo su una dimensione pi\u00f9 profonda, utilizzare categorie analitiche che fanno riferimento a un\u2019antropologia senz\u2019altro religiosa, ma appoggiata su una base metafisica, naturale, che la ragione \u2014 purch\u00e9 non si chiuda sul mero dato sperimentale \u2014 pu\u00f2 cogliere e legittimamente delineare.<\/p>\n<p style=\"text-align: justify;\">In effetti che esista un antico legame fra la pornografia e una sorta di contro-religione para-spiritualistica quando non materialistica <em>tout court<\/em>, fra violazione intenzionale del pudore e quella che \u00e8 stata chiamata la \u00abcultura della morte\u00bb \u2014 se non vero e proprio \u00abculto della morte\u00bb \u2014, come punta pi\u00f9 \u00abavanzata\u00bb della filosofia del nichilismo moderno, \u00e8 gi\u00e0 stato messo in luce (2).<\/p>\n<p style=\"text-align: justify;\">La pratica sfrenata e de-ordinata dell\u2019attivit\u00e0 sessuale e il suo sfruttamento \u00e8 gi\u00e0 stata ricondotta a una sorta di iniziazione alla cultura della Rivoluzione per la Rivoluzione, a quell\u2019infrazione di ogni norma morale che teorizza e pratica l\u2019abuso dell\u2019<em>eros<\/em> perch\u00e9 non diventi <em>ag\u00e1pe<\/em> (amor fraterno), ma si converta in odio e in <em>t\u00e1nathos<\/em> (morte), cio\u00e8 in fine prematura dell\u2019essere creato da Dio. E questa cultura di morte, che oggi traspare dalle sempre pi\u00f9 diffuse pratiche abortistiche, eugenetiche, eutanasiche, trova nelle teorie \u2014 e nel modello esistenziale \u2014 di Donatien-Alphonse-Fran\u00e7ois de Sade, meglio conosciuto come Marchese de Sade (1740-1814), il suo esponente pi\u00f9 rappresentativo e genuino.<\/p>\n<p style=\"text-align: justify;\">Non vi \u00e8 dubbio che l\u2019assenso e la fruizione della pornografia siano un elemento di sovversione interiore che s\u2019inquadra perfettamente in quella Rivoluzione in <em>interiore hominis<\/em> che la scuola di pensiero contro-rivoluzionaria chiama \u00abquarta Rivoluzione\u00bb, in quanto si sviluppa logicamente, non solo cronologicamente, dopo quella nelle strutture, nei suoi aspetti di Rivoluzione religiosa, quindi liberale e infine socialista.<\/p>\n<p style=\"text-align: justify;\">Paiono oggi avverarsi le prospettive di quelli che Paul Ricoeur chiama i \u00abmaestri del sospetto\u00bb \u2014 Sigmund Freud (1856-1939) e Friedrich Nietzsche (1844-1900), in particolare \u2014 e degli alfieri della Rivoluzione sessuale \u2014 da Georges Bataille (1897-1962) a Wilhelm Reich (1897-1957), a Georg Groddeck (1866-1934), al popolare Erich Fromm (1900-1980) \u2014, che avevano pronosticato un\u2019esplosione immensa \u2014 se pensiamo alla traduzione in una pratica viziata e viziosa degli stimoli naturali esasperati prodotti dalla \u00abpredicazione\u00bb pornografica \u2014, panica, planetaria, di erotismo \u00abselvaggio\u00bb, de-finalizzato, chiuso, introverso, una eruzione gigantesca di energie \u00aborgoniche\u00bb \u2014 per dirla con Wilhelm Reich (3) \u2014 che vengono cos\u00ec sprecate, sperperate, dissipate, bruciate, attuando cos\u00ec la rottura di ogni gerarchizzazione delle potenze che compongono l\u2019interiorit\u00e0 dell\u2019uomo, segnando, in via di metafora, la morte di Apollo, cio\u00e8 della razionalit\u00e0 perspicace e dell\u2019autocontrollo calmo, e il trionfo di Dioniso, l\u2019istintualit\u00e0 irrazionale (4)<\/p>\n<p style=\"text-align: justify;\">Si realizza cos\u00ec l\u2019annullamento del confine fra spirito e materia, dell\u2019annegamento dell\u2019individualit\u00e0 \u2014 che il neo-gnosticismo, di cui la Rivoluzione sessuale trasuda(5), concepisce come negativit\u00e0 \u2014 in un pleroma indistinto di energie ribollenti e vane.<\/p>\n<p style=\"text-align: justify;\">La pornografia, quindi, si pu\u00f2 combattere, non solo contenendone le manifestazioni estreme come la pedopornografia, ma punendola, anche se ci si pu\u00f2 domandare, viste le cronache, quale efficacia abbiano le misure restrittive quando le norme sono di tenore soggettivistico e <em>de facto<\/em> sono rese inerti da prassi giudiziarie quanto meno omissive, applicate per di pi\u00f9 a una realt\u00e0 che di giorno in giorno sfugge sempre pi\u00f9 agli Stati nazionali e che ha i suoi \u00absantuari\u00bb nelle zone del globo pi\u00f9 destabilizzate e statualmente deboli.<\/p>\n<p style=\"text-align: justify;\">In realt\u00e0 anche questo non \u00e8 sufficiente. La pornografia \u00e8 una malattia morale \u2014 che ha i suoi untori \u2014 e va affrontata in radice come tale, cio\u00e8 attraverso la cura e la \u00abprofilassi\u00bb. Sotto quest\u2019ultimo aspetto \u00e8 necessaria una lotta intelligente e consapevole, di cui \u00e8 essenziale che lo Stato divenga protagonista, anche se non protagonista unico, e non solo con la polizia e con la magistratura, pur benvenute.<\/p>\n<p style=\"text-align: justify;\">Si tratta senz\u2019altro di un lavoro lungo e difficile, che deve combattere la cultura di morte retrostante al fenomeno pornografico \u2014 di ieri e di sempre \u2014 e a incidere su tutto ci\u00f2 che contribuisce a formare le patologie tipiche della condizione umana della nostra epoca: il vuoto esistenziale, l\u2019assenza di mete per cui valga la pena spendersi, il solipsismo, il naturalismo e il materialismo soffocanti che imperano, l\u2019esautorazione e il dissolvimento della famiglia, la martellante e onnipervadente proposta di messaggi e di modelli esistenziali negativi \u2014 una volta si diceva \u00abscandali\u00bb \u2014, non solo perch\u00e9 radicalmente al di fuori da ogni logica religiosa, ma perch\u00e9 patentemente nocivi se praticati nella vita reale.<\/p>\n<p style=\"text-align: justify;\"><strong>Note<\/strong><\/p>\n<p style=\"text-align: justify;\">(1) Sull\u2019influenza \u00abambientale\u00bb dell\u2019industria pornografica sui modelli di comportamento sociale negli Stati Uniti \u00e8 la recente inchiesta di Pamela Paul, <em>Pornopotere. Come l\u2019industria porno sta trasformando la nostra vita<\/em>, trad. it., Orme Editori, Milano 2007; da segnalare sul tema \u00e8 anche lo studio di Pietro Adamo, <em>Il porno di massa. Percorsi dell\u2019hard contemporaneo<\/em>, Cortina, Milano 2004.<\/p>\n<p style=\"text-align: justify;\">(2) Cfr. Massimo Introvigne, <em>Pornografia e Rivoluzione sessuale<\/em>, Editrice Libreria S. Lorenzo, Chiavenna (Sondrio) 1983<\/p>\n<p style=\"text-align: justify;\">(3) Cfr. <em>ibidem<\/em>.<\/p>\n<p style=\"text-align: justify;\">(4) Cfr. Michel Maffesoli, <em>L\u2019ombra di Dioniso. Una sociologia delle passioni<\/em>, trad. it., Garzanti, Milano 1990.<\/p>\n<p style=\"text-align: justify;\">(5) Cfr. Emanuele Samek Lodovici (1942-1981), <em>Metamorfosi della gnosi.<\/em> <em>Quadri della dissoluzione contemporanea<\/em>, Ares, Milano 1991.<\/p>\n<p style=\"text-align: justify;\">(A.C. Valdera)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Storia &amp; Identit\u00e0, 14 marzo 2008 di Oscar Sanguinetti 1. In un articolo di qualche mese fa \u2014 esattamente il 9 aprile 2007 \u2014 il Corriere della Sera informava che, secondo una ricerca condotta in Belgio, nei soli Stati Uniti viene immesso \u00ab[\u2026] ogni 39 secondi online [un] nuovo video porno\u00bb.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-pornografia-nel-terzo-millennio\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":31077,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,25],"tags":[1626],"class_list":["post-3170","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-costume","category-sguardo-sul-nostro-tempo","tag-pornografia","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La pornografia nel terzo millennio - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-pornografia-nel-terzo-millennio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La pornografia nel terzo millennio - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-pornografia-nel-terzo-millennio\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-24T11:31:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-26T12:56:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/porno.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"276\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-pornografia-nel-terzo-millennio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-pornografia-nel-terzo-millennio\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La pornografia nel terzo millennio\",\"datePublished\":\"2009-04-24T11:31:24+00:00\",\"dateModified\":\"2016-02-26T12:56:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-pornografia-nel-terzo-millennio\\\/\"},\"wordCount\":2130,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-pornografia-nel-terzo-millennio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/porno.jpg\",\"keywords\":[\"pornografia\"],\"articleSection\":[\"Costume\",\"Sguardo sul nostro tempo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-pornografia-nel-terzo-millennio\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-pornografia-nel-terzo-millennio\\\/\",\"name\":\"La pornografia nel terzo millennio - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-pornografia-nel-terzo-millennio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-pornografia-nel-terzo-millennio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/porno.jpg\",\"datePublished\":\"2009-04-24T11:31:24+00:00\",\"dateModified\":\"2016-02-26T12:56:40+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-pornografia-nel-terzo-millennio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-pornografia-nel-terzo-millennio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-pornografia-nel-terzo-millennio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/porno.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/porno.jpg\",\"width\":276,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-pornografia-nel-terzo-millennio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La pornografia nel terzo millennio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La pornografia nel terzo millennio - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-pornografia-nel-terzo-millennio\/","og_locale":"it_IT","og_type":"article","og_title":"La pornografia nel terzo millennio - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-pornografia-nel-terzo-millennio\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-04-24T11:31:24+00:00","article_modified_time":"2016-02-26T12:56:40+00:00","og_image":[{"width":276,"height":183,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/porno.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"11 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-pornografia-nel-terzo-millennio\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-pornografia-nel-terzo-millennio\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La pornografia nel terzo millennio","datePublished":"2009-04-24T11:31:24+00:00","dateModified":"2016-02-26T12:56:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-pornografia-nel-terzo-millennio\/"},"wordCount":2130,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-pornografia-nel-terzo-millennio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/porno.jpg","keywords":["pornografia"],"articleSection":["Costume","Sguardo sul nostro tempo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-pornografia-nel-terzo-millennio\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-pornografia-nel-terzo-millennio\/","name":"La pornografia nel terzo millennio - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-pornografia-nel-terzo-millennio\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-pornografia-nel-terzo-millennio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/porno.jpg","datePublished":"2009-04-24T11:31:24+00:00","dateModified":"2016-02-26T12:56:40+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-pornografia-nel-terzo-millennio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-pornografia-nel-terzo-millennio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-pornografia-nel-terzo-millennio\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/porno.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/porno.jpg","width":276,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-pornografia-nel-terzo-millennio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La pornografia nel terzo millennio"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3170"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3170\/revisions"}],"predecessor-version":[{"id":31078,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3170\/revisions\/31078"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/31077"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3170"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3170"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}