{"id":3156,"date":"2009-04-24T11:01:25","date_gmt":"2009-04-24T09:01:25","guid":{"rendered":""},"modified":"2016-04-20T15:19:44","modified_gmt":"2016-04-20T13:19:44","slug":"introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\/","title":{"rendered":"Introvigne lancia l\u2019allarme: \u201cLa Chiesa attaccata dall\u2019interno, i progressisti non amano il Magistero di Giovanni Paolo II e Benedetto XVI"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-33195\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/cardinali_progressisti.jpg\" alt=\"cardinali_progressisti\" width=\"250\" height=\"154\" \/>Petrus,<\/strong> 30 ottobre 2007<\/div>\n<p style=\"text-align: center;\">di <strong>Bruno Volpe<\/strong><\/p>\n<p style=\"text-align: justify;\">CITTA\u2019 DEL VATICANO &#8211; L\u2019attacco sistematico lanciato da pi\u00f9 parti negli ultimi tempi contro la Chiesa \u00e8 il frutto di quella \u2018sporcizia\u2019 che l\u2019allora Cardinale Joseph Ratzinger denunci\u00f2 durante le meditazioni della Via Crucis del 2005.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Giovanni Paolo II stava per tornare alla Casa del Padre e il porporato sarebbe stato chiamato di l\u00ec a poco a succedergli sulla Cattedra di Pietro. Ma sia il Magistero del Papa polacco, sia quello del Papa tedesco, che sono in piena sintonia e continuit\u00e0, non convincono i settori \u2018progressisti\u2019 della Chiesa, gli stessi che avrebbero potuto ispirare, o quantomeno gradire, le continue inchieste giornalistiche mirate a gettare discredito sul Vaticano e sul clero italiano.<\/div>\n<p style=\"text-align: justify;\">E\u2019 la convinzione, espressa in esclusiva a \u2018Petrus\u2019, del Professor Massimo Introvigne, uno dei maggiori esperti di religioni, raggiunto telefonicamente in Uzbekistan, dove sta trascorrendo un breve periodo di riposo.<\/p>\n<p style=\"text-align: justify;\"><strong>Professor Introvigne: domenica, dopo la beatificazione dei 498 martiri spagnoli, alcuni vandali hanno tentato di assaltare la Chiesa di San Eugenio, affidata a sacerdoti della Prelatura dell\u2019Opus Dei\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cIntanto va la mia piena solidariet\u00e0 ai religiosi e ai fedeli, ma la cosa non mi sorprende affatto\u2026\u201c.<\/p>\n<p style=\"text-align: justify;\"><strong>Perch\u00e8?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cE\u2019 la conseguenza di un\u2019estate intera di critiche contro la Chiesa, e di una settimana in cui alcuni organi di stampa, scatenando le fantasie delle menti pi\u00f9 deboli, hanno prima fatto i conti in tasca alla Chiesa e poi hanno dato voce a qualche buon tempone che ha pensato \u2018bene\u2019 addirittura di porre in dubbio la soprannaturalit\u00e0 delle stigmate di Padre Pio. Tutto ci\u00f2 dopo che, sia pure in buona fede, erano state pubblicate le lettere private in cui la Beata Madre Teresa di Calcutta descriveva la sua crisi di fede. E tanto per restare in tema di Opus Dei, non mi meraviglierei se dovesse arrivare anche il turno di San Josemaria Escriv\u00e0\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Si tratta di personaggi beatificati e canonizzati dal Servo di Dio Giovanni Paolo II: solo una coincidenza?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cParliamoci chiaro: oggi c\u2019\u00e8 un attacco da parte di forze laiciste e atee contro la Chiesa e specialmente contro le figure di Giovanni Paolo II e Benedetto XVI. La solidit\u00e0 del loro Magistero, la rettitudine del loro pensiero, d\u00e0 fastidio e, quindi, per vie indirette, si cerca di screditarli, persino attaccando i Santi da loro proclamati\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Professor Introvigne, chi si nasconde dietro questa manovra?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cAlla figura del \u2018grande vecchio\u2019 io non credo, ma non andrei lontano per scovare i veri nemici della Chiesa\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>A chi o cosa allude?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cAgli ambienti libertari e laicisti presenti in molti settori della societ\u00e0 e dei mezzi di informazione. Si alzano polveroni mediatici, come la storia della pedofilia o dei costi della Chiesa. Mi chiedo: ma tra le altre religioni, non esistono casi di pedofilia? Sono per caso tutti gentiluomini? E poi basta con la storiella dei costi della Chiesa! La Chiesa non ha privilegi, e fa del bene gratuitamente, spesso supplendo alle carenze dello Stato!\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>C\u2019 \u00e8 per caso la massoneria dietro questi attacchi?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cIntanto sarebbe corretto distinguere tra le varie branche della massoneria, ma io sono convinto che la massoneria questa volta non abbia nulla a che vedere con queste manovre. Cerchiamo ci\u00f2 che non va dentro casa nostra, sarebbe pi\u00f9 serio ed onesto\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Scusi, Professore: vuole dire che la Chiesa \u00e8 colpita dal proprio interno?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cAllora, chiamiamo le cose con il loro nome. Non \u00e8 certamente un mistero che il Magistero di Giovanni Paolo II e di Benedetto XVI non piacciano ai settori cosiddetti \u2018progressisti\u2019 della Chiesa: certi documenti potrebbero essere stati passati ai giornali per attaccare la Chiesa proprio da suoi esponenti. Come si spiega, ad esempio, l\u2019ostilit\u00e0 di prelati definiti moderni verso il Motu Proprio del Papa Benedetto XVI che, giustamente e con tanta saggezza, ha liberalizzato la Messa tridentina? La fermezza dottrinale e morale di Benedetto XVI oggi \u00e8 la stessa adottata da Giovanni Paolo II ieri. Dunque, confermo che pi\u00f9 che la massoneria, attualmente la Chiesa \u00e8 colpita da suoi stessi settori \u2018progressisti\u2019. Sarebbe dunque opportuno fare luce e pulizia in casa prima di pensare alle congiure esterne\u201d.<\/p>\n<p style=\"text-align: justify;\">(A.C. Valdera)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Petrus, 30 ottobre 2007 di Bruno Volpe CITTA\u2019 DEL VATICANO &#8211; L\u2019attacco sistematico lanciato da pi\u00f9 parti negli ultimi tempi contro la Chiesa \u00e8 il frutto di quella \u2018sporcizia\u2019 che l\u2019allora Cardinale Joseph Ratzinger denunci\u00f2 durante le meditazioni della Via Crucis del 2005.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":33195,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,45],"tags":[789],"class_list":["post-3156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-progressismo-cattolico","tag-progressismo-cattolico-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Introvigne lancia l\u2019allarme: \u201cLa Chiesa attaccata dall\u2019interno, i progressisti non amano il Magistero di Giovanni Paolo II e Benedetto XVI - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Introvigne lancia l\u2019allarme: \u201cLa Chiesa attaccata dall\u2019interno, i progressisti non amano il Magistero di Giovanni Paolo II e Benedetto XVI - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-24T09:01:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-20T13:19:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/cardinali_progressisti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"286\" \/>\n\t<meta property=\"og:image:height\" content=\"176\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Introvigne lancia l\u2019allarme: \u201cLa Chiesa attaccata dall\u2019interno, i progressisti non amano il Magistero di Giovanni Paolo II e Benedetto XVI\",\"datePublished\":\"2009-04-24T09:01:25+00:00\",\"dateModified\":\"2016-04-20T13:19:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\\\/\"},\"wordCount\":695,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/cardinali_progressisti.jpg\",\"keywords\":[\"progressismo cattolico\"],\"articleSection\":[\"Chiesa\",\"Progressismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\\\/\",\"name\":\"Introvigne lancia l\u2019allarme: \u201cLa Chiesa attaccata dall\u2019interno, i progressisti non amano il Magistero di Giovanni Paolo II e Benedetto XVI - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/cardinali_progressisti.jpg\",\"datePublished\":\"2009-04-24T09:01:25+00:00\",\"dateModified\":\"2016-04-20T13:19:44+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/cardinali_progressisti.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/cardinali_progressisti.jpg\",\"width\":286,\"height\":176},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Introvigne lancia l\u2019allarme: \u201cLa Chiesa attaccata dall\u2019interno, i progressisti non amano il Magistero di Giovanni Paolo II e Benedetto XVI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Introvigne lancia l\u2019allarme: \u201cLa Chiesa attaccata dall\u2019interno, i progressisti non amano il Magistero di Giovanni Paolo II e Benedetto XVI - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\/","og_locale":"it_IT","og_type":"article","og_title":"Introvigne lancia l\u2019allarme: \u201cLa Chiesa attaccata dall\u2019interno, i progressisti non amano il Magistero di Giovanni Paolo II e Benedetto XVI - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-04-24T09:01:25+00:00","article_modified_time":"2016-04-20T13:19:44+00:00","og_image":[{"width":286,"height":176,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/cardinali_progressisti.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Introvigne lancia l\u2019allarme: \u201cLa Chiesa attaccata dall\u2019interno, i progressisti non amano il Magistero di Giovanni Paolo II e Benedetto XVI","datePublished":"2009-04-24T09:01:25+00:00","dateModified":"2016-04-20T13:19:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\/"},"wordCount":695,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/cardinali_progressisti.jpg","keywords":["progressismo cattolico"],"articleSection":["Chiesa","Progressismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\/","name":"Introvigne lancia l\u2019allarme: \u201cLa Chiesa attaccata dall\u2019interno, i progressisti non amano il Magistero di Giovanni Paolo II e Benedetto XVI - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/cardinali_progressisti.jpg","datePublished":"2009-04-24T09:01:25+00:00","dateModified":"2016-04-20T13:19:44+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/cardinali_progressisti.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/cardinali_progressisti.jpg","width":286,"height":176},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/introvigne-lancia-lallarme-la-chiesa-attaccata-dallinterno\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Introvigne lancia l\u2019allarme: \u201cLa Chiesa attaccata dall\u2019interno, i progressisti non amano il Magistero di Giovanni Paolo II e Benedetto XVI"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3156"}],"version-history":[{"count":5,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3156\/revisions"}],"predecessor-version":[{"id":33196,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3156\/revisions\/33196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/33195"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}