{"id":3127,"date":"2009-04-22T15:41:05","date_gmt":"2009-04-22T13:41:05","guid":{"rendered":""},"modified":"2016-04-15T14:13:23","modified_gmt":"2016-04-15T12:13:23","slug":"il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\/","title":{"rendered":"Il motu proprio Summorum Pontificum e la fine del postconcilio"},"content":{"rendered":"<div style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-32900\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/summorum_pontificum.jpg\" alt=\"summorum_pontificum\" width=\"185\" height=\"200\" \/>per <strong>Alleanza Cattolica \u2013 Valdera<\/strong> 30 settembre 2007<\/div>\n<p style=\"text-align: center;\"><em>Il senso del documento, tra accoglienza e critiche<br \/>\n<\/em><\/p>\n<p style=\"text-align: center;\"><strong>Stefano Chiappalone<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Trascorsi poco pi\u00f9 di tre anni dalla promulgazione del motuproprio Summorum Pontificum, tracciamo un piccolo bilancio, in attesa dei bilanci pi\u00f9 autorevoli che eventualmente si faranno \u201ccol\u00e0 dove si puote ci\u00f2 che si vuole\u201d. Grazie alla \u201cliberalizzazione\u201d di Papa Benedetto XVI, in questi tre anni \u00e8 aumentato considerevolmente il numero di messe in forma straordinaria (c.d. tridentine) celebrate pi\u00f9 o meno regolarmente. Celebrazioni pre-esistenti si sono stabilizzate, sempre nuovi parroci si avvicinano a questa liturgia che non avevano mai conosciuto (un dato di non poco rilievo \u00e8 la giovane et\u00e0 dei preti e soprattutto dei fedeli \u201ctridentini\u201d).<\/div>\n<p style=\"text-align: justify;\">A dispetto dell\u2019accusa di nostalgismo che sembra invece da attribuire ad un certo clero ormai anziano, sorpreso o perplesso, se non ostile di fronte a giovani non proprio in linea con le idee rivoluzionarie della \u201cgiovent\u00f9\u201d di quarant\u2019anni fa.<\/p>\n<p style=\"text-align: justify;\">Al di l\u00e0 di poche eccezioni lodevoli, la ricezione del motu proprio nel mondo cattolico \u00e8 stata caratterizzata da una immediata <em>damnatio memoriae<\/em> (quanti sacerdoti conoscono questo motuproprio? E in generale, quanti sacerdoti, catechisti, ecc. leggono i documenti del magistero pontificio?) o da un susseguirsi di dichiarazioni o notificazioni i il cui senso (neanche troppo)\u00a0 recondito \u00e8: \u201cusare con cautela\u201d. Il tutto, a loro dire, per scongiurare il pericolo di \u201caffossare\u201d il Concilio Ecumenico Vaticano II (cio\u00e8 l\u2019evento ecclesiale pi\u00f9 citato e meno letto dai progressisti)<\/p>\n<p style=\"text-align: justify;\">Il\u00a0<em>Summorum Pontificum<\/em>\u00a0sicuramente contiene esplosivo, altrimenti le diffuse preoccupazioni non si spiegherebbero. Ma altrettanto sicuramente non sempre \u00e8 chiaro quale sia l\u2019esplosivo in questione, anche per la diffusa tendenza a tenere gli occhi ben fissi sul dettaglio \u2013 o sull\u2019altare, in tal caso \u2013 dimenticandone il quadro generale.<\/p>\n<p style=\"text-align: justify;\">Si teme forse l\u2019innegabile spirito di apertura ai membri della Fraternit\u00e0 Sacerdotale San Pio X, fondata nel 1970 dall\u2019arcivescovo Marcel Lefebvre? Pu\u00f2 anche essere, ma \u00e8 risaputo che i problemi sono dottrinali prima che liturgici. E poi in un contesto ecclesiale fondato sul dialogo con i fratelli separati, che fastidio darebbero dei \u201cfratelli separati\u201d in pi\u00f9 da riammettere nel seno di\u00a0<em>Sancta Romana Ecclesia<\/em>?<\/p>\n<p style=\"text-align: justify;\">Non si \u00e8 scatenato tanto trambusto per la riammissione dell\u2019Amministrazione Apostolica \u201cSan Giovanni Maria Vianney\u201d\u00a0 di Campos, in Brasile, n\u00e9, a maggior ragione, dell\u2019ancor pi\u00f9 piccolo Istituto del Buon Pastore a Bordeaux, in Francia. Del resto questo \u00e8 l\u2019unico aspetto condiviso pienamente persino dal card. Martini, icona del progressismo. Casomai, ridurre la portata del motuproprio alla sola questione lefebvriana costituirebbe per il clero un\u2019ottima scusa per aggirarlo e dimenticarlo: riguarda solo pochi scismatici, a noi non interessa.<\/p>\n<p style=\"text-align: justify;\">N\u00e9 basta a rendere ragione delle corali lamentazioni la nota aspirazione ratzingeriana ad una liturgia pi\u00f9 sacrale: sarebbe ingiusto credere che tutti i critici della \u201cforma straordinaria del rito romano\u201d siano fautori degli abusi liturgici, che del resto non sono previsti nel messale di Paolo VI (come dimostrano ampiamente le celebrazioni officiate dal Papa). Altrimenti lo stesso clamore si sarebbe sollevato gi\u00e0 di fronte ai precedenti richiami di Giovanni Paolo II sulla solennit\u00e0 e la correttezza della celebrazione liturgica, che invece hanno avuto la \u201cnormale\u201d ricezione da parte del clero: cio\u00e8 ascoltati da chi gi\u00e0 non ne aveva bisogno e tranquillamente ignorati dagli altri.<\/p>\n<p style=\"text-align: justify;\">Non sempre gli \u201cavversari\u201d della liturgia romana antica sono anche fautori della sciatteria e qualcuno addirittura\u00a0 improvvisamente ricorda che anche col rito attuale si pu\u00f2 celebrare \u201cin latino\u201d e \u201cdi spalle\u201d (o meglio, \u201crivolti al Signore\u201d come precisava padre Uwe M. Lang nell\u2019omonimo libro, con l\u2019autorevole prefazione dell\u2019allora cardinal Ratzinger). E se anche l\u2019unico risultato pratico del motuproprio fosse una celebrazione della forma ordinaria pi\u00f9 simile alla liturgia celeste che alle paraliturgie televisive, pur di evitare l\u2019aborrita \u201cmessa tridentina\u201d, sarebbe gi\u00e0 un gran risultato.<\/p>\n<p style=\"text-align: justify;\">Si potrebbe continuare, ma i due elementi principali su cui fanno leva pi\u00f9 di frequente le analisi del provvedimento benedettino, cio\u00e8 la fine dello scisma lefebvriano e una liturgia pi\u00f9 aperta al mistero e all\u2019adorazione, sono palesemente insufficienti: potrebbero far esplodere s\u00ec qualcuno s\u00ec e qualcuno no, ma non tutti insieme.<\/p>\n<p style=\"text-align: justify;\">Probabilmente anche qualcuno dei \u201cs\u00ec\u201d, che pur avendo fatto il \u201968 ecclesiale, in fondo si commuoverebbe se per una volta (una sola) tornasse ad iniziare la messa con le antiche parole del salmo 42: \u201cIntroibo ad altare Dei \u2013 Ad Deum qui laetificat iuventutem meam\u201d, \u201cSalir\u00f2 all\u2019altare di Dio \u2013 A Dio che allieta la mia giovinezza\u201d.\u00a0Ma solo come puro amarcord\u00a0 della prima messa, poi basta giocare con un rito che esprime una teologia superata.<\/p>\n<p style=\"text-align: justify;\">E invece no, il papa dice che il rito antico non \u00e8 superato, che tra la messa di Paolo VI e la messa di san Pio V (e di Giovanni XXIII) non c\u2019\u00e8 rottura, entrambe possono coesistere, l\u2019una come forma ordinaria l\u2019altra straordinaria, perch\u00e9 \u201cCi\u00f2 che per le generazioni anteriori era sacro, anche per noi resta sacro e grande, e non pu\u00f2 essere improvvisamente del tutto proibito o, addirittura, giudicato dannoso\u201d.<\/p>\n<p style=\"text-align: justify;\">E oltre a non essere dannoso, \u00e8 persino positivo: \u201cCi fa bene a tutti conservare le ricchezze che sono cresciute nella fede e nella preghiera della Chiesa, e di dar loro il giusto posto\u201d. Il papa dice \u201ca tutti\u201d, non solo a quei pochi (ma meno \u201cpochi\u201d di quanto credono molti vescovi) che ne faranno concretamente uso. E se entrambe le forme possono coesistere, e se questa coesistenza fa bene a tutti, allora anche le diverse spiritualit\u00e0, ecclesiologia, teologia (chiamatele pure come vi pare) che esprimono possono coesistere e fanno bene a tutti.<\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 nella Chiesa non vale il detto \u201cchiodo scaccia chiodo\u201d, n\u00e9 tantomeno \u201cmessale scaccia messale\u201d e \u201cconcilio scaccia concilio\u201d. Il cuore del problema \u00e8 proprio qui: tutti coloro che vedono un\u2019opposizione insanabile tra la messa \u201cvecchia\u201d e quella \u201cnuova\u201d, vedono anche un\u2019opposizione insanabile tra la Chiesa \u201cpre\u201d e \u201cpost\u201d conciliare.<\/p>\n<p style=\"text-align: justify;\">Tanto in alcuni ambienti anticonciliari quanto tra i difensori a spada tratta del Concilio &#8211; con giudizi opposti, gli uni con tristezza, gli altri con gioia \u2013, il Concilio Vaticano II \u00e8 considerato in modo pi\u00f9 o meno velato come il punto di partenza di una nuova religione.\u00a0Benedetto XVI per\u00f2 ci ammonisce che \u201cNon si pu\u00f2 congelare l\u2019autorit\u00e0 magisteriale della Chiesa all\u2019anno 1962 \u2013 ci\u00f2 deve essere ben chiaro alla Fraternit\u00e0. Ma ad alcuni di coloro che si segnalano come grandi difensori del\u00a0<a href=\"http:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/index_it.htm\" target=\"_blank\">Concilio<\/a>\u00a0deve essere pure richiamato alla memoria che\u00a0<a href=\"http:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/index_it.htm\" target=\"_blank\">il Vaticano II<\/a>\u00a0porta in s\u00e9 l\u2019intera storia dottrinale della Chiesa. Chi vuole essere obbediente al\u00a0<a href=\"http:\/\/www.vatican.va\/archive\/hist_councils\/ii_vatican_council\/index_it.htm\" target=\"_blank\">Concilio<\/a>, deve accettare la fede professata nel corso dei secoli e non pu\u00f2 tagliare le radici di cui l\u2019albero vive\u201d (Lettera ai Vescovi del 10 marzo 2009).<\/p>\n<p style=\"text-align: justify;\">Questi fraintendimenti non trovano appiglio nei testi conciliari in s\u00e9, interpretati secondo Pietro e non secondo i media, ma la propaganda grida pi\u00f9 della verit\u00e0 e lo \u201cspirito del Concilio\u201d invece di incarnarsi nella \u201clettera del Concilio\u201d ha preferito incartarsi negli\u00a0<em>slogan<\/em>\u00a0giornalistici.<\/p>\n<p style=\"text-align: justify;\">Paolo VI pass\u00f2 gran parte del suo pontificato a constatare che la \u201cprimavera\u201d tanto attesa era durata poco, presto sostituita dalla corsa all\u2019eresia e all\u2019ideologia spacciate per libert\u00e0; e fu il primo a cercare di rimettere in rotta la barca di Pietro &#8211; pensiamo all\u2019enciclica\u00a0<em>Humanae Vitae<\/em>, alla\u00a0<em>Mysterium Fidei<\/em>, al Credo del Popolo di Dio &#8211; agitata dai ratzingeriani \u201cventi di dottrina\u201d (cfr. l\u2019omelia pre-conclave del 18 aprile 2005).<\/p>\n<p style=\"text-align: justify;\">Giovanni Paolo II ha impiegato 27 anni per somministrare al popolo di Dio, e soprattutto ai suoi pastori, invasive dosi di ortodossia &#8211; il rilancio della Dottrina Sociale e della Nuova Evangelizzazione, di\u00a0 fronte all\u2019illusione di colmare le lacune materiali e spirituali col veleno delle ideologie; il Catechismo della Chiesa Cattolica; il magistero sulla vita e sulla famiglia e quello (spesso frainteso) sulla pace \u2013 che permettessero di applicare il vero Concilio.<\/p>\n<p style=\"text-align: justify;\">Papa Benedetto ha continuato l\u2019opera dei predecessori, condensata nel discorso alla Curia romana del 22 dicembre 2005 in cui ha affermato che \u201cLa Chiesa \u00e8, tanto prima quanto dopo il Concilio, la stessa Chiesa una, santa, cattolica ed apostolica in cammino attraverso i tempi; essa prosegue \u2018il suo pellegrinaggio fra le persecuzioni del mondo e le consolazioni di Dio\u2019, annunziando la morte del Signore fino a che Egli venga\u201d e ha criticato invece l\u2019 \u201cermeneutica della discontinuit\u00e0 e della rottura\u201d, in base alla quale diversi teologi hanno creduto, magari in buona fede, che il Concilio richiedesse di dover predicare una nuova religione, come se l\u2019anticristo \u2013 quello pacifista, ecumenico ed ecologico di Solovev &#8211;\u00a0 fosse tutto sommato pi\u00f9 buono di Cristo.<\/p>\n<p style=\"text-align: justify;\">Qui sta il vero esplosivo del motuproprio\u00a0<em>Summorum Pontificum<\/em>\u00a0&#8211; che non \u00e8 \u201ccontro il Concilio\u201d, semmai \u00e8 un passo avanti nella sua corretta e piena applicazione \u2013 il quale non ponendo in antitesi\u00a0<em>nova et vetera<\/em>, anzi, affermandone la tranquilla possibilit\u00e0 di coesistenza e addirittura di arricchimento reciproco, ha toccato i nervi scoperti di chi invece portava avanti l\u2019ermeneutica della discontinuit\u00e0. Nel discorso del 22 dicembre 2005 c\u2019\u00e8 dunque la pi\u00f9 completa chiave di lettura del motuproprio. E forse anche di tutto questo straordinario pontificato.<\/p>\n<p style=\"text-align: justify;\">(A.C. Valdera)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>per Alleanza Cattolica \u2013 Valdera 30 settembre 2007 Il senso del documento, tra accoglienza e critiche Stefano Chiappalone<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":32900,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,115],"tags":[1094,1474],"class_list":["post-3127","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-liturgia","tag-s-messa","tag-summorum-pontificum","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il motu proprio Summorum Pontificum e la fine del postconcilio - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il motu proprio Summorum Pontificum e la fine del postconcilio - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-22T13:41:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-15T12:13:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/summorum_pontificum.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"195\" \/>\n\t<meta property=\"og:image:height\" content=\"211\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il motu proprio Summorum Pontificum e la fine del postconcilio\",\"datePublished\":\"2009-04-22T13:41:05+00:00\",\"dateModified\":\"2016-04-15T12:13:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\\\/\"},\"wordCount\":1494,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/summorum_pontificum.jpg\",\"keywords\":[\"S Messa\",\"Summorum Pontificum\"],\"articleSection\":[\"Chiesa\",\"Liturgia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\\\/\",\"name\":\"Il motu proprio Summorum Pontificum e la fine del postconcilio - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/summorum_pontificum.jpg\",\"datePublished\":\"2009-04-22T13:41:05+00:00\",\"dateModified\":\"2016-04-15T12:13:23+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/summorum_pontificum.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/summorum_pontificum.jpg\",\"width\":195,\"height\":211},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il motu proprio Summorum Pontificum e la fine del postconcilio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il motu proprio Summorum Pontificum e la fine del postconcilio - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\/","og_locale":"it_IT","og_type":"article","og_title":"Il motu proprio Summorum Pontificum e la fine del postconcilio - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-04-22T13:41:05+00:00","article_modified_time":"2016-04-15T12:13:23+00:00","og_image":[{"width":195,"height":211,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/summorum_pontificum.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il motu proprio Summorum Pontificum e la fine del postconcilio","datePublished":"2009-04-22T13:41:05+00:00","dateModified":"2016-04-15T12:13:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\/"},"wordCount":1494,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/summorum_pontificum.jpg","keywords":["S Messa","Summorum Pontificum"],"articleSection":["Chiesa","Liturgia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\/","name":"Il motu proprio Summorum Pontificum e la fine del postconcilio - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/summorum_pontificum.jpg","datePublished":"2009-04-22T13:41:05+00:00","dateModified":"2016-04-15T12:13:23+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/summorum_pontificum.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/summorum_pontificum.jpg","width":195,"height":211},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-summorum-pontificum-e-la-fine-del-postconcilio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il motu proprio Summorum Pontificum e la fine del postconcilio"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3127"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3127\/revisions"}],"predecessor-version":[{"id":32901,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3127\/revisions\/32901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/32900"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}