{"id":3121,"date":"2009-04-22T14:50:26","date_gmt":"2009-04-22T12:50:26","guid":{"rendered":""},"modified":"2016-06-14T15:13:37","modified_gmt":"2016-06-14T13:13:37","slug":"il-fallimento-del-dossettismo","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fallimento-del-dossettismo\/","title":{"rendered":"Il Fallimento del dossettismo"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-34730\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Prodi_governo.jpg\" alt=\"Prodi_governo\" width=\"240\" height=\"160\" \/>Liberal,<\/strong> 26 gennaio 2008<\/div>\n<p style=\"text-align: center;\">di <strong>Rocco Buttiglione<\/strong><\/p>\n<p style=\"text-align: justify;\">Il governo Prodi \u00e8 caduto in Parlamento. Non \u00e8 caduto perch\u00e9 travolto da una forza maggiore dell\u2019opposizione. \u00c8 caduto per decomposizione della maggioranza.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">In un certo senso il governo inizia a morire nel momento in cui Veltroni e Berlusconi si parlano e cercano di delineare un sistema di regole, scritte e non scritte, che consentano un funzionamento \u201cnormale\u201d della democrazia italiana. Nel momento, per\u00f2, in cui viene meno la pregiudiziale antiberlusconiana, cio\u00e8 l\u2019identificazione surrettizia di berlusconismo e fascismo, viene meno anche il collante della coalizione di governo ed emergono tutte le sue esplosive contraddizioni interne. In altre parole, la coalizione di governo, per resistere, ha bisogno di una sorta di coazione esterna, di un clima di emergenza.<\/div>\n<p style=\"text-align: justify;\">Veltroni pensava, giustamente, che il paese avesse bisogno di uscire da questo clima di bipolarismo barbaro, che usa un linguaggio da guerra civile ed in cui la competizione politica sui programmi e sui valori \u00e8 sostituita dal dileggio dell\u2019avversario e dalla sua demonizzazione. La coalizione di centrosinistra si rivela per\u00f2 incapace di realizzare questa transizione. \u00c8 davanti alla esplosione della coalizione che Veltroni si vede costretto a correre da solo e, di conseguenza, a costruire un sistema elettorale che gli consenta di correre da solo, capovolgendo la posizione tradizionale dei Ds.<\/p>\n<p style=\"text-align: justify;\">Esplode la coalizione di centrosinistra, finisce l\u2019Ulivo. Non ci si faccia ingannare dalle apparenze. Se non fossero stati i centristi a far cadere il governo lo avrebbe fatto di qui a poco la sinistra. La ragione \u00e8 semplice: questo centro e questa sinistra non possono governare insieme, sono reciprocamente incompatibili. Non \u00e8 solo il fallimento di un governo e di una coalizione. \u00c8 il fallimento di una cultura politica, la cultura politica azionista e dossettiana di cui Prodi \u00e8 stato la espressione politica.<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 riuscito l\u2019incontro dei cattolici e dei comunisti. Gli azionisti ed i dossettiani erano convinti che nella Resistenza italiana si fosse realizzato un incontro storico dei cattolici, dei comunisti e dei liberali che generava una forma culturale e politica superiore sia al comunismo che alle democrazie occidentali.<\/p>\n<p style=\"text-align: justify;\">Questa sintesi superiore imponeva una revisione radicale ed anche una abiura parziale del comunismo tradizionale, del liberalismo tradizionale e del cattolicesimo tradizionale. Avrebbero potuto incontrarsi fra loro solo un nuovo comunismo, un nuovo liberalismo ed un nuovo cattolicesimo.<\/p>\n<p style=\"text-align: justify;\">Da questo presupposto discende, fra l\u2019altro, la interpretazione dossettiana del Concilio ecumenico Vaticano II come rottura assoluta con il passato cattolicesimo, bollato in blocco come integrista. La novit\u00e0 politica avrebbe avuto bisogno, per realizzarsi compiutamente, di una riforma religiosa e teologica. \u00c8 in questa luce che si comprendono anche alcune sorprendenti affermazioni degli onorevoli Bindi e Castagnetti secondo i quali i vescovi italiani sarebbero teologicamente in ritardo rispetto alla novit\u00e0 non solo politica ma anche religiosa dell\u2019Ulivo.<\/p>\n<p style=\"text-align: justify;\">Questa idea azionista e dossettiana conquista negli anni post-conciliari quella che Del Noce chiamava la Repubblica della Cultura.<\/p>\n<p style=\"text-align: justify;\">Dopo la caduta del muro di Berlino azionismo e dossettismo (il dossettismo \u00e8 la variante cattolica dell\u2019azionismo) giungono anche alla conquista del potere politico con l\u2019Ulivo e con l\u2019Unione. Il Partito democratico avrebbe dovuto essere il frutto maturo di questa lunga gestazione politica. Era necessario che il dossettismo godesse il suo momento di successo politico perch\u00e9 solo in questo modo era possibile arrivare alla dimostrazione evidente del suo fallimento. Cos\u00ec \u00e8 stato.<\/p>\n<p style=\"text-align: justify;\">Diceva Del Noce che comunismo e cattolicesimo sono essenze irriducibili, non mediabili. E cos\u00ec infatti \u00e8 stato.<\/p>\n<p style=\"text-align: justify;\">I comunisti sono rimasti fuori dal Partito democratico, hanno rifiutato di lasciarsi riassorbire nella sintesi prodiana. Anche la maggioranza dei cattolici \u00e8 rimasta fuori e, comunque, la Chiesa italiana si \u00e8 rifiutata di attribuire ai cattolici dossettiani nel Partito democratico quel ruolo di sua rappresentanza laica che essi si erano attribuiti.<\/p>\n<p style=\"text-align: justify;\">La grande sintesi che avrebbe dovuto abbracciare tutti gli italiani ricostruendo l\u2019unit\u00e0 morale della nazione finisce con l\u2019avere il consenso, nel migliore dei casi, di un po\u2019 meno di un terzo dell\u2019elettorato. In effetti dopo il crollo del comunismo diventa difficile proporre una sintesi di comunismo ed economia di mercato. Si pone, se mai, il problema di come coniugare libert\u00e0 e solidariet\u00e0, ma questa \u00e8 altra cosa, che appartiene, se mai, all\u2019ambito della dottrina sociale cristiana e del pensiero liberale.<\/p>\n<p style=\"text-align: justify;\">Il comunismo, a livello mondiale, si \u00e8 dissolto davanti ad una opposizione intellettuale, religiosa e morale, non \u00e8 stato riassorbito in una sintesi di ordine superiore che ne conservi alcuni elementi.<\/p>\n<p style=\"text-align: justify;\">Dossettismo ed azionismo sono disarmati davanti all\u2019emergere di una globalizzazione che ridimensiona il ruolo dello stato ed il potere della politica ed impone di ripensare in modo del tutto nuovo il rapporto fra stato e societ\u00e0 e fra libert\u00e0 e solidariet\u00e0.<\/p>\n<p style=\"text-align: justify;\">Egualmente disarmato \u00e8 il dossettismo davanti all\u2019emergere delle questioni della bioetica, in una fase storica in cui l\u2019uomo acquisisce capacit\u00e0 inaudite di manipolare se stesso. Qui si delinea per i cattolici un nucleo di valori non negoziabili che resiste al primato assoluto della mediazione politica che \u00e8 invece proprio della ideologia dossettiana.<\/p>\n<p style=\"text-align: justify;\">Per giungere all\u2019incontro cattolici e comunisti devono rinunciare, ciascuno per suo conto, al proprio orizzonte di riferimenti ideali. Si incontrano dunque sul terreno di un pragmatismo assoluto e di un primato della politica che si stacca da ogni riferimento vincolante di valori che la preceda. Cessano, in tal modo, di essere popolari.<\/p>\n<p style=\"text-align: justify;\">Rinunciamo a mostrare (ma il lettore vi arriva facilmente da solo) in che modo le singole tappe del fallimento del governo Prodi si lasciano ricondurre alla insufficienza di questi suoi presupposti ideali. Dalla presa d\u2019atto di questo fallimento ideale bisogna comunque partire per ripensare fuori da schemi consumati il ruolo dei cattolici, dei liberali ed anche della sinistra riformista nel futuro della democrazia italiana.<\/p>\n<p style=\"text-align: justify;\">(A.C. Valdera)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liberal, 26 gennaio 2008 di Rocco Buttiglione Il governo Prodi \u00e8 caduto in Parlamento. Non \u00e8 caduto perch\u00e9 travolto da una forza maggiore dell\u2019opposizione. \u00c8 caduto per decomposizione della maggioranza.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fallimento-del-dossettismo\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":34730,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[1497,1222],"class_list":["post-3121","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica-nazionale","tag-dossettismo","tag-unione","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Fallimento del dossettismo - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fallimento-del-dossettismo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Fallimento del dossettismo - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fallimento-del-dossettismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-22T12:50:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-14T13:13:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Prodi_governo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fallimento-del-dossettismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fallimento-del-dossettismo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il Fallimento del dossettismo\",\"datePublished\":\"2009-04-22T12:50:26+00:00\",\"dateModified\":\"2016-06-14T13:13:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fallimento-del-dossettismo\\\/\"},\"wordCount\":942,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fallimento-del-dossettismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Prodi_governo.jpg\",\"keywords\":[\"dossettismo\",\"Unione\"],\"articleSection\":[\"Politica nazionale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fallimento-del-dossettismo\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fallimento-del-dossettismo\\\/\",\"name\":\"Il Fallimento del dossettismo - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fallimento-del-dossettismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fallimento-del-dossettismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Prodi_governo.jpg\",\"datePublished\":\"2009-04-22T12:50:26+00:00\",\"dateModified\":\"2016-06-14T13:13:37+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fallimento-del-dossettismo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fallimento-del-dossettismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fallimento-del-dossettismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Prodi_governo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Prodi_governo.jpg\",\"width\":275,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-fallimento-del-dossettismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Fallimento del dossettismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Fallimento del dossettismo - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fallimento-del-dossettismo\/","og_locale":"it_IT","og_type":"article","og_title":"Il Fallimento del dossettismo - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fallimento-del-dossettismo\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-04-22T12:50:26+00:00","article_modified_time":"2016-06-14T13:13:37+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Prodi_governo.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fallimento-del-dossettismo\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fallimento-del-dossettismo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il Fallimento del dossettismo","datePublished":"2009-04-22T12:50:26+00:00","dateModified":"2016-06-14T13:13:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fallimento-del-dossettismo\/"},"wordCount":942,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fallimento-del-dossettismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Prodi_governo.jpg","keywords":["dossettismo","Unione"],"articleSection":["Politica nazionale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fallimento-del-dossettismo\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fallimento-del-dossettismo\/","name":"Il Fallimento del dossettismo - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fallimento-del-dossettismo\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fallimento-del-dossettismo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Prodi_governo.jpg","datePublished":"2009-04-22T12:50:26+00:00","dateModified":"2016-06-14T13:13:37+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fallimento-del-dossettismo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fallimento-del-dossettismo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fallimento-del-dossettismo\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Prodi_governo.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Prodi_governo.jpg","width":275,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-fallimento-del-dossettismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il Fallimento del dossettismo"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3121"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3121\/revisions"}],"predecessor-version":[{"id":34731,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3121\/revisions\/34731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/34730"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}