{"id":3120,"date":"2009-04-22T14:43:59","date_gmt":"2009-04-22T12:43:59","guid":{"rendered":""},"modified":"2016-04-13T09:40:31","modified_gmt":"2016-04-13T07:40:31","slug":"il-duomo-diventa-meta-delloltraggio-islamico","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-duomo-diventa-meta-delloltraggio-islamico\/","title":{"rendered":"Il Duomo diventa meta dell&#8217;oltraggio islamico"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-32744\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Islam_Milano.jpg\" alt=\"Islam_Milano\" width=\"250\" height=\"166\" \/>Il Giornale,<\/strong> 4 gennaio 2009<\/div>\n<p style=\"text-align: center;\">di<strong> Salvatore Scarpino<\/strong><\/p>\n<p style=\"text-align: justify;\">Una brutta giornata, quella di ieri per Milano, Italia. Migliaia di palestinesi hanno invaso il centro per manifestare contro l&#8217;attacco israeliano ad Hamas nella striscia di Gaza. Hanno bruciato bandiere con la stella di David, hanno bruciato vessilli con stelle e strisce dell&#8217;Amerika odiata, con la interessata collaborazione dei comunisti di Rifondazione, spazzati dalla volont\u00e0 popolare, ma sostenuti da un odio tenace che li collega all&#8217;esperienza infame di una dittatura condannata dalla storia.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">La storia, quali delitti si compiono contro le sue lezioni. Striscioni e slogan dei manifestanti palestinesi paragonavano lo stato di Israele al Terzo Reich, una similitudine oltraggiosa che spiega a quali aberrazioni pu\u00f2 condurre la predicazione dell&#8217;odio perseguita con la tenacia che le cause ignobili non meritano.<\/div>\n<p style=\"text-align: justify;\">Ma c&#8217;\u00e8 stato anche un altro oltraggio, un atto di prepotenza e di incivilt\u00e0 che ci tocca direttamente, come italiani rispettosi di tutti e per\u00f2 consapevoli, si spera, dei nostri diritti e delle prerogative della nostra civilt\u00e0.<\/p>\n<p style=\"text-align: justify;\">Una strategia precisa ha indotto i manifestanti palestinesi, pi\u00f9 numerosi del previsto, con un rinforzo di militanti, italiani e arabi, entrati in campo all&#8217;ultimo momento, a forzare i limiti preassegnati alla manifestazione e ad irrompere sul sagrato del Duomo per una preghiera non preannunciata e tutto sommato intimidatoria.<\/p>\n<p style=\"text-align: justify;\">\u00c8 comprensibile che le forze dell&#8217;ordine, in un delicato contestato politico-diplomatico, non abbiano contrastato la forzatura. Una preghiera, cosa volete che sia una preghiera? Ma si d\u00e0 il caso che di fronte a quell&#8217;invasione si sono serrate le porte del Duomo. Per comprensibili motivi di sicurezza. Ve l&#8217;immaginate una processione di cristiani nella spianata davanti a una delle pi\u00f9 importanti moschee dell&#8217;Islam?<\/p>\n<p style=\"text-align: justify;\">Noi non siamo fermi alle Crociate, ma certi integralisti islamici s\u00ec. Credono ancora, vogliono credere che l&#8217;Occidente sia guidato da Goffredo di Buglione e cercano la rivincita in una jihad infinita. La preghiera sul sagrato del Duomo \u00e8 un gesto dimostrativo, esemplare che i siti internet dell&#8217;integralismo islamico canteranno fino al pi\u00f9 sperduto villaggio del Pakistan, dell&#8217;Ran, dell&#8217;Irak e dell&#8217;Indonesia, ovunque vigili l&#8217;occhio di Al Qaida.<\/p>\n<p style=\"text-align: justify;\">Non siamo fermi alle Crociate e non esageriamo. Ma non possiamo sorvolare sul fatto che a guidare la preghiera sul sagrato sia stato l&#8217;imam Abu Imad, il predicatore della moschea di viale Jenner, gi\u00e0 noto alla polizia e alla magistratura. Questo religioso, si fa per dire, ha avuto, il 20 dicembre del 2007, la condanna a 3 anni e otto mesi per associazione a delinquere aggravata dalla finalit\u00e0 di terrorismo internazionale. \u00c8 stato ritenuto colpevole di avere collaborato a organizzare attentati in Italia e all&#8217;estero attraverso la costituzione di una cellula legata al \u00abGruppo salafita per la predicazione e il combattimento\u00bb. Condanna confermata in appello nel novembre scorso.<\/p>\n<p style=\"text-align: justify;\">In quale Paese viviamo? A un simile cattivo maestro \u00e8 consentito muoversi, forzare i cordoni delle forze dell&#8217;ordine, predicare nel segno dell&#8217;odio in uno dei luoghi significativi della tradizione cristiana, per negarla e intimidirla. Siamo democratici, ma la scelta convinta di questo sistema non comporta essere imbelli e indifesi.<\/p>\n<p style=\"text-align: justify;\">(A.C. Valdera)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Giornale, 4 gennaio 2009 di Salvatore Scarpino Una brutta giornata, quella di ieri per Milano, Italia. Migliaia di palestinesi hanno invaso il centro per manifestare contro l&#8217;attacco israeliano ad Hamas nella striscia di Gaza. Hanno bruciato bandiere con la stella di David, hanno bruciato vessilli con stelle e strisce dell&#8217;Amerika odiata, con la interessata &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-duomo-diventa-meta-delloltraggio-islamico\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":32744,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[111,35],"tags":[161],"class_list":["post-3120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-islam-in-europa","category-islam-in-italia","tag-islam-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Duomo diventa meta dell&#039;oltraggio islamico - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-duomo-diventa-meta-delloltraggio-islamico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Duomo diventa meta dell&#039;oltraggio islamico - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-duomo-diventa-meta-delloltraggio-islamico\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-22T12:43:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-13T07:40:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Islam_Milano.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-duomo-diventa-meta-delloltraggio-islamico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-duomo-diventa-meta-delloltraggio-islamico\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il Duomo diventa meta dell&#8217;oltraggio islamico\",\"datePublished\":\"2009-04-22T12:43:59+00:00\",\"dateModified\":\"2016-04-13T07:40:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-duomo-diventa-meta-delloltraggio-islamico\\\/\"},\"wordCount\":518,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-duomo-diventa-meta-delloltraggio-islamico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Islam_Milano.jpg\",\"keywords\":[\"islam\"],\"articleSection\":[\"Islam in Europa\",\"Islam in Italia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-duomo-diventa-meta-delloltraggio-islamico\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-duomo-diventa-meta-delloltraggio-islamico\\\/\",\"name\":\"Il Duomo diventa meta dell'oltraggio islamico - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-duomo-diventa-meta-delloltraggio-islamico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-duomo-diventa-meta-delloltraggio-islamico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Islam_Milano.jpg\",\"datePublished\":\"2009-04-22T12:43:59+00:00\",\"dateModified\":\"2016-04-13T07:40:31+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-duomo-diventa-meta-delloltraggio-islamico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-duomo-diventa-meta-delloltraggio-islamico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-duomo-diventa-meta-delloltraggio-islamico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Islam_Milano.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Islam_Milano.jpg\",\"width\":275,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-duomo-diventa-meta-delloltraggio-islamico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Duomo diventa meta dell&#8217;oltraggio islamico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Duomo diventa meta dell'oltraggio islamico - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-duomo-diventa-meta-delloltraggio-islamico\/","og_locale":"it_IT","og_type":"article","og_title":"Il Duomo diventa meta dell'oltraggio islamico - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-duomo-diventa-meta-delloltraggio-islamico\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-04-22T12:43:59+00:00","article_modified_time":"2016-04-13T07:40:31+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Islam_Milano.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-duomo-diventa-meta-delloltraggio-islamico\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-duomo-diventa-meta-delloltraggio-islamico\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il Duomo diventa meta dell&#8217;oltraggio islamico","datePublished":"2009-04-22T12:43:59+00:00","dateModified":"2016-04-13T07:40:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-duomo-diventa-meta-delloltraggio-islamico\/"},"wordCount":518,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-duomo-diventa-meta-delloltraggio-islamico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Islam_Milano.jpg","keywords":["islam"],"articleSection":["Islam in Europa","Islam in Italia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-duomo-diventa-meta-delloltraggio-islamico\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-duomo-diventa-meta-delloltraggio-islamico\/","name":"Il Duomo diventa meta dell'oltraggio islamico - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-duomo-diventa-meta-delloltraggio-islamico\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-duomo-diventa-meta-delloltraggio-islamico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Islam_Milano.jpg","datePublished":"2009-04-22T12:43:59+00:00","dateModified":"2016-04-13T07:40:31+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-duomo-diventa-meta-delloltraggio-islamico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-duomo-diventa-meta-delloltraggio-islamico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-duomo-diventa-meta-delloltraggio-islamico\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Islam_Milano.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Islam_Milano.jpg","width":275,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-duomo-diventa-meta-delloltraggio-islamico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il Duomo diventa meta dell&#8217;oltraggio islamico"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3120"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3120\/revisions"}],"predecessor-version":[{"id":32745,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3120\/revisions\/32745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/32744"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}