{"id":3118,"date":"2009-04-22T14:33:17","date_gmt":"2009-04-22T12:33:17","guid":{"rendered":""},"modified":"2015-11-13T13:46:36","modified_gmt":"2015-11-13T12:46:36","slug":"il-17-congresso-la-societ-armoniosa-tradita-dal-partito","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\/","title":{"rendered":"Il 17&deg; Congresso: la \u201csociet&agrave; armoniosa\u201d tradita dal Partito"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Cina_congresso.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-27748\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Cina_congresso.jpg\" alt=\"Cina_congresso\" width=\"250\" height=\"153\" \/><\/a>AsiaNews,<\/strong> 12 ottobre 2007<\/div>\n<p style=\"text-align: justify;\"><em>Si prevedono pochi cambiamenti sostanziali mentre la corruzione dilaga fra i membri. Gli slogan di Hu Jintao sembrano parole vuote. La repressione di dissidenti, media e personalit\u00e0 religiose, unica strada per creare una situazione \u201cdi gioia e armonia\u201d.<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Bernardo Cervellera<\/strong><\/p>\n<p><!--more--><\/p>\n<div>\n<div style=\"text-align: justify;\">Roma (AsiaNews) \u2013 La Grande Sala del popolo in piazza Tiananmen a Pechino \u00e8 pronta per ricevere gli oltre 2 mila delegati per il 17\u00b0 Congresso del Partito comunista cinese, che si aprir\u00e0 il prossimo 15 ottobre. La sala \u00e8 stata abbellita di nuovi fiori, un nuovo simbolo rotondo del Partito (di 5 metri di diametro!) e una nuova moquette rossa.<\/div>\n<\/div>\n<p style=\"text-align: justify;\">Pochi altri cambiamenti sostanziali sono in vista, anche se si parla di una completa ristrutturazione del Politburo, in cui potrebbe entrare il 52enne Li Keqiang, segretario del Liaoning, da molti visto come il prescelto di Hu Jintao alla propria successione fra 5 anni.<\/p>\n<p style=\"text-align: justify;\">L\u2019imminente Congresso dovrebbe far emergere la vittoria o almeno il consolidamento del potere di Hu Jintao sulla cosiddetta \u201ccricca di Shanghai\u201d, legata all\u2019ex presidente Jiang Zemin. Questa ha subito una sconfitta con l\u2019arresto di Chen Liangyu, segretario della citt\u00e0, accusato per una serie di scandali finanziari. Al Congresso si prevede che Chen Liangyu sia espulso dal Partito e poi processato.<\/p>\n<p style=\"text-align: justify;\">Hu \u00e8 riuscito a piazzare molti suoi uomini come segretari in varie province, ma il Politburo ha ancora alcuni membri della cricca di Shanghai \u2013 come Jia Qinglin e Li Changchun che difficilmente possono essere eliminati. L\u2019ipotesi pi\u00f9 probabile \u00e8 che le due fazioni trovino un modus vivendi, senza danneggiarsi a vicenda.<\/p>\n<p style=\"text-align: justify;\"><strong>Successione e corruzione<\/strong><\/p>\n<p style=\"text-align: justify;\">L\u2019episodio di Chen Liangyu \u2013 uno delle migliaia di casi di corruzione dei membri del Pcc \u2013 e la lotta fra le fazioni sta spingendo il Partito a trovare nuovi modi per nominare i membri del Comitato centrale, aprendo a una specie di \u201cdemocrazia interna\u201d, dove almeno una parte dei membri sia eletta da tutti i delegati del Congresso.<\/p>\n<p style=\"text-align: justify;\">Una struttura formale per l\u2019accesso alle cariche potrebbe scremare gli elementi pi\u00f9 corrotti e risolvere i problemi di successione all\u2019interno del partito. Finora, esso ha assistito sempre a tentativi di successione \u201cereditaria\u201d e veri e propri \u201ccolpi di stato\u201d: Hua Guofeng, erede designato di Mao, scalzato da Deng Xiaoping; Zhao Ziyang scalzato da Li Peng (col benestare di Deng); Jiang Zemin, designato da Deng, come lo stesso Hu Jintao (fin dal 1992).<\/p>\n<p style=\"text-align: justify;\">La democrazia interna non \u00e8 per\u00f2 garanzia per una democrazia popolare. Hu Jintao ha gi\u00e0 espresso con chiarezza molte volte che la democrazia occidentale non \u00e8 adatta alla Cina e che \u201cla supremazia del Pcc\u201d \u00e8 fuori discussione. Eppure \u2013 come proposto tante volte dai think-tank\u00a0 del Partito &#8211;\u00a0 una democrazia alla base permetterebbe denunce e controlli efficaci su quella che \u00e8 la piaga maggiore del Pcc: la corruzione. Il volume di tangenti, furti, manipolazioni, uso illecito di denaro pubblico si aggira sui 70 miliardi di euro (circa il 4% del Prodotto interno lordo o il 10% delle spese governative; dati del 2004) ed \u00e8 un fenomeno in crescita.<\/p>\n<p style=\"text-align: justify;\">Di fronte a questo stigma dell\u2019oligarchia comunista &#8211; con il suo strascico di ingiustizie verso contadini, operai, poveri, pensionati, risparmiatori &#8211;\u00a0 la leadership continua a predicare\u00a0 \u201cservizio e altruismo\u201d, mentre al Congresso si pensa di varare un\u2019ennesima Commissione anti-corruzione.<\/p>\n<p style=\"text-align: justify;\">Ma nessuno crede che il Partito abbia la forza (o la volont\u00e0) di controllare se stesso o punire se stesso. Nel 2006, su 33 mila casi di corruzione ufficialmente denunciati, sono stati arrestati solo 1600 funzionari; pi\u00f9 dell\u201980% dei condannati \u00e8 riuscito ad evitare la pena. Molti giudici hanno confessato che le sentenze \u201cdevono ubbidire alle direttive del Pcc\u201d e non alla giustizia.<\/p>\n<p style=\"text-align: justify;\">Del resto, i motivi per cui crescono le iscrizioni al Partito sono proprio il fatto che ai membri viene dato un pacchetto di benefit da cui \u00e8 escluso il resto della popolazione: un lavoro stabile, pensione, facili possibilit\u00e0 di viaggiare, un appartamento moderno e soprattutto una protezione legale e sociale se per caso hai dei guai con la giustizia.<\/p>\n<p style=\"text-align: justify;\">Un solo esempio: da quasi due anni il governo ha ordinato ai membri del Partito di non investire nelle miniere di carbone, minacciando pene e la chiusura degli impianti in caso di incidenti mortali. La fame di energia del Paese spinge gli imprenditori a far lavorare i minatori per 12-14 ore al giorno, in gallerie spesso senza alcuna sicurezza. Il risultato \u00e8 la morte ogni anno di almeno 20 mila minatori. Ebbene nel 2006, il 95% dei funzionari del Partito implicati nelle propriet\u00e0 di miniere crollate, sono stati prosciolti.<\/p>\n<p style=\"text-align: justify;\"><strong>La societ\u00e0 a servizio del Partito<\/strong><\/p>\n<p style=\"text-align: justify;\">Questi semplici dati mostrano una cruda realt\u00e0: il Pcc, invece di essere l\u2019avanguardia della societ\u00e0, \u00e8 divenuto l\u2019oppressore; i membri del Partito sono divenuti un\u2019oligarchia che usa l\u2019economia per mantenere il potere politico e usa quest\u2019ultimo per accrescere i suoi benefici economici.<\/p>\n<p style=\"text-align: justify;\">Da questo circolo vizioso \u2013 ma economicamente remunerativo &#8211; resta esclusa la maggioranza della popolazione: almeno 600 milioni di contadini hanno salari fino a un decimo di quelli delle citt\u00e0, nessuna pensione o struttura sanitaria; nelle privatizzazioni delle industrie, che hanno arricchito molti membri del Partito, pensionati e disoccupati rimangono senza alcun aiuto; oltre 300 milioni di persone vivono al di sotto della soglia di povert\u00e0.<\/p>\n<p style=\"text-align: justify;\">Un indicatore di quanto governo e Partito siano incuranti della situazione della popolazione viene dai dati sulla sicurezza sociale. Per scuole, sanit\u00e0, pensioni, sussidi il governo cinese spende meno del 12% del Prodotto interno lordo, mentre Paesi sviluppati usano fino al 50% di esso.<\/p>\n<p style=\"text-align: justify;\">Alle piaghe sociali vanno aggiunte quelle ambientali. L\u2019aria della Cina \u00e8 la pi\u00f9 inquinata al mondo e l\u2019acqua potabile manca a met\u00e0 della popolazione cinese; il 75% dei fiumi e laghi sono inquinati; una coltre di smog copre perenne le citt\u00e0, provocando a decine di migliaia di persone malattie e morti per problemi respiratori. Tutto questo \u00e8 dovuto a uno sfruttamento senza limiti del territorio, una mancanza di rispetto per l\u2019ambiente e le leggi, una industrializzazione violenta anche di molte aree rurali.<\/p>\n<p style=\"text-align: justify;\">La risposta della popolazione a questo fiume di ingiustizia continua ad essere quella della rivolta.<\/p>\n<p style=\"text-align: justify;\">Secondo Zhou Yongkang, ministro della Pubblica sicurezza, le proteste di massa sono in aumento nel paese: nel 1994 erano 10 mila; nel 2004 sono state oltre 74 mila. Nel 2005 sono avvenute in Cina oltre 87 mila proteste pubbliche. Ogni giorno il Paese registra fra le 120 e le 230 proteste, in prevalenza nelle zone rurali, dove avvengono espropri di terre a favore di capi villaggi e segretari del Partito che vendono le terre a imprese edilizie o industriali. Nel 2006 le proteste sono diminuite, ma esse hanno assunto un carattere pi\u00f9 violento, con la polizia che ha sparato contro i manifestanti.<\/p>\n<p style=\"text-align: justify;\"><strong>Armonia e repressione<\/strong><\/p>\n<p style=\"text-align: justify;\">Per coprire l\u2019abisso fra il paradiso del Partito e l\u2019inferno della societ\u00e0, Hu Jintao ha coniato alcuni slogan: quello della \u201csociet\u00e0 armoniosa\u201d, a cui tutti devono contribuire e da cui tutti dovrebbero ricavare un equo benessere; dello \u201csviluppo scientifico\u201d con cui si sottolinea che il profitto e l\u2019industrializzazione devono andare di pari passo con la cura per l\u2019ambiente e un rapporto equilibrato fra citt\u00e0 e campagne. Per il prossimo Congresso si pensa addirittura di inserire i due slogan nella costituzione del Partito, accanto ai contributi di Mao, di Deng Xiaoping e di Jiang Zemin. Il problema, messo in luce anche da accademici cinesi, \u00e8 che il governo deve ancora dimostrare che questi non sono puri slogan, una specie di fumo negli occhi per addormentare le masse.<\/p>\n<p style=\"text-align: justify;\">Ad accrescere questa impressione \u00e8 anche la spietata campagna di arresti lanciata dalla leadership contro attivisti per i diritti umani, avvocati difensori di contadini, capi religiosi, gruppi di proteste. Tutto questo risponde proprio al voler creare un \u201cambiente gioioso e armonico\u201d prima del Congresso, eliminando gli elementi di \u201cdisarmonia\u201d. Anche i media devono cancellare tutto ci\u00f2 che stona con questa retorica.<\/p>\n<p style=\"text-align: justify;\">Una nuova legge pubblicata lo scorso anno vieta ai media di pubblicare notizie su &#8220;situazioni di emergenza&#8221; prima delle dichiarazioni dei responsabili locali, con multe da 50 a 100 mila yuan (5-10 mila euro) per i trasgressori. Vi rientrano notizie come esplosioni nelle miniere, disastri ambientali, pericoli per la salute pubblica e persino gli scontri tra contadini e polizia. La nuova normativa riguarda anche la stampa estera, compresa quella di Hong Kong.<\/p>\n<p style=\"text-align: justify;\">A questo va aggiunto il controllo sul web, i blog, le censure preventive sui provider internazionali e gli oscuramenti di molti siti che parlano di democrazia, diritti umani, libert\u00e0 religiosa, Taiwan, ecc.<\/p>\n<p style=\"text-align: justify;\">Da questo punto di vista, si comprende perch\u00e9 i media di Pechino, in occasione di questo Congresso, definito \u201cil pi\u00f9 aperto nella storia del Partito\u201d, non fanno altro che osannare tutti i grandi risultati ottenuti in questi 58 anni di dominio incontrastato del Pcc.<\/p>\n<p style=\"text-align: justify;\">Per evitare possibili sfide a questa \u201crepressione armonica\u201d, Hu Jintao si \u00e8 assicurato l\u2019appoggio dell\u2019esercito. Dal 2004, da quando \u00e8 succeduto a Jiang Zemin come presidente della Commissione militare, egli ha aumentato il budget per le spese militari, potenziato le ricerche spaziali e promosso decine di ufficiali al rango di generale per i posti chiave. Il risultato \u00e8 che l\u2019esercito \u201caderisce alla leadership assoluta del Pcc\u201d e rimane \u201cuno strumento nelle mani del Partito\u201d.<\/p>\n<p style=\"text-align: justify;\">Non vi \u00e8 nemmeno timore che la \u201crepressione armonica\u201d sia scossa da pressioni esterne. Poche settimane prima del Congresso, Hu Jintao ha messo in chiaro che qualunque cambiamento all\u2019interno del Politburo non cambier\u00e0 la politica delle \u201cporte aperte\u201d agli investimenti e agli affari con gli imprenditori internazionali. Egli ha anche promesso una maggiore \u201cintegrazione nella globalizzazione mondiale\u201d. Naturalmente una globalizzazione economica, non dei diritti umani.<\/p>\n<p style=\"text-align: justify;\">(A.C. Valdera)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AsiaNews, 12 ottobre 2007 Si prevedono pochi cambiamenti sostanziali mentre la corruzione dilaga fra i membri. Gli slogan di Hu Jintao sembrano parole vuote. La repressione di dissidenti, media e personalit\u00e0 religiose, unica strada per creare una situazione \u201cdi gioia e armonia\u201d. di Bernardo Cervellera<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":27748,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,108],"tags":[2395],"class_list":["post-3118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cina","category-paesi-e-continenti","tag-cina","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il 17&deg; Congresso: la \u201csociet&agrave; armoniosa\u201d tradita dal Partito - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il 17&deg; Congresso: la \u201csociet&agrave; armoniosa\u201d tradita dal Partito - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-22T12:33:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-13T12:46:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Cina_congresso.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"287\" \/>\n\t<meta property=\"og:image:height\" content=\"176\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il 17&deg; Congresso: la \u201csociet&agrave; armoniosa\u201d tradita dal Partito\",\"datePublished\":\"2009-04-22T12:33:17+00:00\",\"dateModified\":\"2015-11-13T12:46:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\\\/\"},\"wordCount\":1563,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Cina_congresso.jpg\",\"keywords\":[\"Cina\"],\"articleSection\":[\"Cina\",\"Paesi e continenti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\\\/\",\"name\":\"Il 17&deg; Congresso: la \u201csociet&agrave; armoniosa\u201d tradita dal Partito - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Cina_congresso.jpg\",\"datePublished\":\"2009-04-22T12:33:17+00:00\",\"dateModified\":\"2015-11-13T12:46:36+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Cina_congresso.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Cina_congresso.jpg\",\"width\":287,\"height\":176},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il 17&deg; Congresso: la \u201csociet&agrave; armoniosa\u201d tradita dal Partito\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il 17&deg; Congresso: la \u201csociet&agrave; armoniosa\u201d tradita dal Partito - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\/","og_locale":"it_IT","og_type":"article","og_title":"Il 17&deg; Congresso: la \u201csociet&agrave; armoniosa\u201d tradita dal Partito - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-04-22T12:33:17+00:00","article_modified_time":"2015-11-13T12:46:36+00:00","og_image":[{"width":287,"height":176,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Cina_congresso.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il 17&deg; Congresso: la \u201csociet&agrave; armoniosa\u201d tradita dal Partito","datePublished":"2009-04-22T12:33:17+00:00","dateModified":"2015-11-13T12:46:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\/"},"wordCount":1563,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Cina_congresso.jpg","keywords":["Cina"],"articleSection":["Cina","Paesi e continenti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\/","name":"Il 17&deg; Congresso: la \u201csociet&agrave; armoniosa\u201d tradita dal Partito - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Cina_congresso.jpg","datePublished":"2009-04-22T12:33:17+00:00","dateModified":"2015-11-13T12:46:36+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Cina_congresso.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Cina_congresso.jpg","width":287,"height":176},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-17-congresso-la-societ-armoniosa-tradita-dal-partito\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il 17&deg; Congresso: la \u201csociet&agrave; armoniosa\u201d tradita dal Partito"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3118"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3118\/revisions"}],"predecessor-version":[{"id":27749,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3118\/revisions\/27749"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/27748"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}