{"id":31163,"date":"2016-03-10T00:00:07","date_gmt":"2016-03-09T23:00:07","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=31163"},"modified":"2016-03-01T09:48:59","modified_gmt":"2016-03-01T08:48:59","slug":"quella-che-si-estingue-e-la-mia-generazione-tante-scuse","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\/","title":{"rendered":"Quella che si estingue \u00e8 la mia generazione. Tante scuse"},"content":{"rendered":"<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-31164\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/03\/anziani.jpg\" alt=\"anziani\" width=\"250\" height=\"179\" \/>Pubblicato su <strong>Il Covile,<\/strong> anno XVI n.890<\/p>\n<p style=\"text-align: center;\">\u00a027 febbraio 2016<\/p>\n<p style=\"text-align: center;\"><strong>Maurizio Blondet<\/strong><\/p>\n<p style=\"text-align: justify;\">Ida Magli \u00e8 scomparsa. Non avr\u00e0 nemmeno lontanamente gli onori funerari che il Sistema ha tributato ad Umberto Eco. \u00c8 logico: \u00e8 stata la prima a gridare, inascoltata, che l\u2019Europa burocratica era diventata la prigione dei popoli e stava distruggendo la cultura e la civilt\u00e0 europee. Ancor meno \u00e8 stato onorato Piero Buscaroli, grande giornalista, scrittore, musicologo, caratteraccio. Logico: fu sempre <em>un sopravvissuto della Repubblica Sociale in territorio nemico.<\/em> Da giovane praticante, leggevo avidamente i suoi straordinari, originalissimi reportage dalla guerra del Vietnam (per il Borghese); come direttore del <em>Roma <\/em>di Napoli, rivel\u00f2 che l\u2019ex ministro Taviani gli aveva ammesso: gli attentati dei \u00abneri\u00bb erano organizzati dal ministero dell\u2019Interno, democristiano\u00bb.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Indro Montanelli al <em>Giornale<\/em> non si priv\u00f2 della sua penna, nutrita di una cultura magnifica e di una sete offesa di verit\u00e0, ma, vilmente, gli impose di firmare con uno pseudonimo \u2014 Piero Santerno \u2014 perch\u00e9 riteneva compromettente il suo vero nome. Era un discriminato, un impronunciabile nel sistema politico della \u00abLibert\u00e0\u00bb<\/p>\n<p style=\"text-align: justify;\">Da giovane leggevo avidamente \u00abSanterno\u00bb, ho imparato da lui che anch\u2019io ero in territorio nemico, senza ordini<\/p>\n<p style=\"text-align: justify;\"><strong>Buoni e cattivi maestri, se ne vanno tutti<\/strong><\/p>\n<p style=\"text-align: justify;\">I tre erano della generazione precedente alla mia, gli ottanta-novantenni. Quella che \u2014 come ci ha informato l\u2019Istat\u2014 sta morendo in massa: 62 mila nel 2015 pi\u00fa che nel 2014, un\u2019impennata statistica di oltre il 10 per cento, comparabile al 1943, al 1915\u201318, insomma la mortalit\u00e0 dei tempi delle grandi guerre. La differenza \u00e8 che non c\u2019\u00e8 guerra. Vige da decenni quella che chiamano \u00abpace\u00bb: abbondanza, Europa \u00abunita\u00bb, previdenza sociale, societ\u00e0 (residuale) del benessere. E a morire sono i vecchissimi, non i giovani al fronte. Perch\u00e9 i vecchi sono sempre pi\u00fa e i giovani quasi non ci sono. Strana \u00abpace\u00bb, quella dove una societ\u00e0 intera ha cessato di fare figli.<\/p>\n<p style=\"text-align: justify;\">In zoologia, sono i selvatici nello zoo a non generare pi\u00fa: la mia generazione si sta accorgendo troppo tardi che questa \u00abpace\u00bb \u00e8 l\u2019altro nome per lo zoo umano? La mia generazione \u2014 quella dei settantenni, nati nella ripresa della natalit\u00e0 del dopoguerra \u2014 \u00e8 quella che ha creato, voluto, queste gabbie. I miei genitori erano sposini ventenni quando mi diedero vita, nel \u201944; l\u2019appartamento in affitto, tra Sesto e Gorla, era stato bombardato, abitavano in una stanza unica requisita, che il proprietario reclamava; i partigiani compivano le loro vendette ed omicidi mirati per instaurare il bolscevismo. Di notte, passavano SS giovanissime, che gestivano le aziende del triangolo industriale per la produzione bellica. Sul viale Monza tutti gli alberi erano stati tagliati dalla gente per riscaldarsi; vivevano tra le macerie; i miei, nella stanzetta abusiva, riscaldavano il loro neonato versando un po\u2019 di alcol denaturato in un bacile smaltato<\/p>\n<p style=\"text-align: justify;\">Erano, mi raccontava mia madre, felici. Pieni di coraggio e di speranza. Fra l\u2019altro perch\u00e9 lavoravano entrambi in una ditta meccanica militarizzata; e il padrone della ditta, ingegner Peghetti \u2014 che i terroristi rossi della Brigata Garibaldi avrebbero trucidato nel suo letto poco dopo, come primo atto della \u00abliberazione\u00bb \u2014 si congratul\u00f2 della mia nascita con un pacco di viveri, e un biglietto che salutava \u00abMaurizio, pioniere di una nuova Italia rinata nel mondo\u00bb. Mia madre mi raccontava di quell\u2019augurio, considerandolo un mandato.<\/p>\n<p style=\"text-align: justify;\"><strong>Non ce l\u2019ho fatta, mamma. <\/strong><\/p>\n<p style=\"text-align: justify;\">La rinascita dell\u2019Italia l\u2019hai fatta tu e pap\u00e0, l\u2019ha fatta la tua generazione, quelli che erano giovani nel \u201944, che fecero tanti figli, che votarono per non consegnare il paese ai comunisti assassini; che rimisero in piedi le fabbriche bombardate, e in pochissimi anni \u2014 dal \u201959, altri dicono dal \u201953 \u2014 fecero dell\u2019Italia la quinta o sesta potenza industriale, vivacemente competitiva, piena di fabbriche che producevano tutto, acciai e farmaci, idrocarburi, chimica e meccanica, calcolatrici, mobili e navi, ceramiche, carta, auto, seconda in Europa solo alla Germania.<\/p>\n<p style=\"text-align: justify;\">Io \u2014 la mia generazione, i <em>baby-boomers<\/em> \u2014 l\u2019abbiamo ereditata, questa societ\u00e0, e come eredi viziati, non siamo stati capaci di mantenerla. Ci siamo lasciati sedurre dalla \u00abrivoluzione culturale\u00bb; abbiamo creduto alla \u00abliberazione sessuale\u00bb e alle gioie del consumismo e dell\u2019edonismo egoista, l\u2019egoismo standard voluto dalla societ\u00e0 dei consumi. Abbiamo votato con entusiasmo il divorzio, e poi l\u2019aborto legale: 250 mila bambini in meno l\u2019anno, e dopo quarant\u2019anni, abbiamo il coraggio di stupirci perch\u00e9 ci mancano cinque o se milioni di italiani giovani, e dobbiamo importare giovani dal Nordafrica, come lavoratori di una societ\u00e0 in decadenza, che non suscita nei nuovi arrivati nessun orgoglio e nessun desiderio di appartenenza: sfruttati, pagati in nero, certo non ci difenderanno nella guerra prossima ventura. Non sono i \u00abnostri\u00bb figli. Non gli abbiamo consegnato alcun mandato.<\/p>\n<p style=\"text-align: justify;\">Voi avete saputo \u00abintegrare\u00bb i meridionali che venivano dalla gleba, nelle fabbriche di Sesto e di Monza. Noi non abbiamo alcun orgoglio da trasmettere ai maghrebini, fargli desiderare di essere italiani. E come potremmo? Per la \u00abpatria\u00bb, abbiamo solo derisioni, e quindi nessun dovere verso di essa. Le nostre istituzioni, l\u2019apparato pubblico che le manovra, sono corrotte e odiose persino a noi; la nostra cultura, l\u2019abbiamo noi stessi abbandonata per la \u00abcultura-standard\u00bb di massa, pop e dozzinale. Peggio, non facciamo pi\u00fa alcuno sforzo di quelli che faceste voi, per migliorare voi stessi, i vostri salari e le vostre fabbriche.<\/p>\n<p style=\"text-align: justify;\">Da ragazzo ho vissuto in un\u2019Italia del Nord piena di fabbriche che producevano tutto, e davano lavoro a tutti: fabbriche integratrici, adesso sono scomparse e non \u00e8 possibile integrare i nuovi arrivati. Come mai esistevano tante fabbriche e sono scomparse? Il segreto lo sapevate, voi della generazione: perch\u00e9 l\u2019Italia veniva dall\u2019autarchia, da tempi dove non ci si affidava al commercio mondiale per comprare in dollari ci\u00f2 che volevamo, ci si sforzava seriamente \u2014 per politica di governo \u2014 di avere l\u2019autosufficienza nazionale in tutto. Che significava anche: conservare, ed affinare, \u00abcompetenze\u00bb tecniche ed umane. Voi avete sviluppato le tecniche e insegnato competenze.<\/p>\n<p style=\"text-align: justify;\">Noi, la mia generazione, dopo aver aderito alla \u00abrivoluzione sessuale\u00bb e pop, non contenti, abbiamo accettato stupidamente il verbo globalista. Perch\u00e9 produrre grano, quando in Australia e in Canada costa meno? Perch\u00e9 fabbricare computers, quando potere comprarli dalla Cina e da Taiwan? Abbandoniamo l\u2019elettronica in cui non siamo competitivi, e concentriamoci laddove abbiamo il vantaggio competitivo: le giacche di Armani, gli stracci di Dolce e Gabbana. Con i soldi che Armani e i due allegri guadagnano, ci compriamo smartphone e tablets cinesi.<\/p>\n<p style=\"text-align: justify;\">L\u2019effetto non poteva essere pi\u00fa ovvio: l\u2019istupidimento generale della societ\u00e0. Perch\u00e9 una cosa \u00e8 avere lavoratori per fabbricare smartphone e computers, e un\u2019altra per fabbricare pantaloni. Che poi Armani, le sue giacche le fa\u2019 fare in Pakistan, e qui nemmeno facciamo pi\u00fa i pantaloni. Come ho gi\u00e0 detto un\u2019altra volta, qui dove abito adesso, Corsico, Milano, la Richard Ginori aveva 1800 dipendenti. Adesso \u00e8 chiusa. La Cartiera Burgo ne aveva 400: sparita. C\u2019erano miriadi di fabbrichette meccaniche, ossia miriadi di salariati e di specializzati: adesso ci sono dei pensionati e dei supermercati.<\/p>\n<p style=\"text-align: justify;\">Abbiamo anche aderito all\u2019euro; ci liberava della liretta; soprattutto, ci liberava della nostra sovranit\u00e0 nazionale che ci ha sempre pesato per la responsabilit\u00e0 che comportava; l\u2019abbiamo affidata a \u00abl\u2019Europa\u00bb, sicuri che avrebbe provveduto ai nostri interessi meglio di noi. Noi come generazione dei <em>baby-boomers<\/em>, mamma, abbiamo fatto questo. Non io personalmente \u2014 io ho cercato di oppormi, ho fatto persino lo scrutatore nel referendum contro il divorzio e l\u2019aborto, nelle scuole ero nella minoranza che si opponeva a quelle derive, e nel lavoro mi sono fatto bollare ben bene da fascista. Ancor peggio, mi son fatto deridere ed emarginare come cattolico, oscurantista, reazionario antisemita, escludere da tutti i posti rispettabili.<\/p>\n<p style=\"text-align: justify;\">Per\u00f2, sinceramente non posso negare la mia corresponsabilit\u00e0. Come elemento della mia generazione, ne ho condiviso la temperie, mi son lasciato infettare dagli stati d\u2019animo collettivi, sedurre dalle facilit\u00e0 che mi offrivano come liberazione. Alla fin fine, ho divorziato anch\u2019io. E non ho figli.<\/p>\n<p style=\"text-align: justify;\">Adesso questa generazione si appresta ad estinguersi, meritatamente: perch\u00e9 continuare ad esistere, se non ha una vera ragione di vita? Ci siamo liberati di Dio, dai suoi obblighi e della patria, dai suoi doveri. La liberazione sessuale ci d\u00e0 le ultime gioie \u2014 grazie al Viagra, al turismo sessuale, un\u2019indecenza tristissima di vecchi che se lo possono ancora permettere. Se cerco di sunteggiare il bilancio del nostro passaggio nella storia, devo riconoscere: Mai una generazione ha goduto tanto benessere e sicurezza, e mai ha avuto tanta paura di generare, di impegnarsi fino in fondo e per sempre; mai \u00e8 stata pi\u00fa insicura della durata della cosa che chiamiamo \u00abpace\u00bb.<\/p>\n<p style=\"text-align: justify;\">Viviamo fra macerie morali \u2014 quelle che abbiamo creato noi stessi \u2014 aspettando la fine zoologica. L\u2019impennata di mortalit\u00e0 sta per raggiungerci. Ci sta per raggiungere anche la conseguenza del sistema globalizzato, del capitalismo mondiale \u2014 il sistema radicamento sbagliato \u2014 che ci aveva promesso il benessere crescente.<\/p>\n<p style=\"text-align: justify;\">Come ovvio, come sempre, la nuova ondata \u00e8 cominciata negli Stati Uniti. La Federal Reserve di New York ha comunicato pochi giorni fa che gli ultra-sessantacinquenni d\u2019oggi hanno debiti per mutui del 47% <em>superiori <\/em>agli ultrasessantacinquenni del 2003, e il 27% di debiti in pi\u00fa per l\u2019auto a rate. Li riconosco, sono i <em>baby-boomers<\/em>, sono la mia generazione: coi salari in calo da trent\u2019anni, non hanno rinunciato ai \u00ablussi standard\u00bb dell\u2019auto nuova, della villetta. Non potevano permettersela? L\u2019hanno comprata a debito. Mai una generazione di vecchi si \u00e8 indebitata tanto per il superfluo; almeno una volta i vecchi riducevano le spese, la nostra generazione \u2014 la parte americana \u2014 le ha persino aumentate. A credito.<\/p>\n<p style=\"text-align: justify;\">E adesso, sentite la trappola: il pensionato Sal Ruffin, di Weatherby Lake, Missouri, aveva una bella pensione, 3.300 dollari al mese. Adesso, il suo fondo pensionistico gli ha comunicato: da questo mese, la sua pensione \u00e8 1.650 dollari mensili. Sono le gioie del capitalismo terminale: le pensioni in Usa sono private e a capitalizzazione pura, gestite da fondi d\u2019investimento che ricavano i profitti necessari per pagarle impiegando i capitali versati dai soci attivi in Borsa, anzi in tutte le borse mondiali, e in titoli pubblici. Coi titoli pubblici ad interessi zero, le banche centrali che pagano interessi negativi, e le Borse cadenti, i fondi pensione non sono pi\u00fa in grado di pagarle.<\/p>\n<p style=\"text-align: justify;\"><strong>La \u00abriforma\u00bb pensionistica in Usa <\/strong><\/p>\n<p style=\"text-align: justify;\">E detti fondi-pensione hanno ottenuto dal Senato e dal governo una legge \u2014 il <em>Multiemployer Pension Reform Act<\/em> \u2014 che consente loro, dopo comunicazione al Tesoro, di tagliare i pagamenti pensionistici allo scopo di rimanere solventi. Sono gi\u00e0 400 mila americani ad aver subito il taglio; la mia generazione. Quella della liberazione sessuale, del \u201968. La stessa generazione che oltre i 65 s\u2019\u00e8 indebitata per mutui casa, il 47 percento in pi\u00fa di quanto facessero i 65enni di dieci anni prima. Fidando di pagarli con le buone pensioni per cui hanno versato contributi per una vita, e che ora vengono dimezzate.<\/p>\n<p style=\"text-align: justify;\">Pensate che trappola. Il 47% degli americani che pur guadagnano 75 mila dollari annui e pi\u00fa \u2014 quindi classe media, mica poveri \u2014 non \u00e8 in grado di far fronte a una emergenza che costi 500 dollari.<\/p>\n<p style=\"text-align: justify;\">In Europa l\u2019estinzione della mia generazione, che ha aderito volontariamente a tutti gli errori radicali del secolo, \u00e8 a questo punto: che ha lasciato tornare il pericolo turco. <em>Come sempre quando l\u2019Europa abbandona la sua identit\u00e0 cristiana<\/em>. Chi l\u2019avrebbe mai detto? Ci siamo circondati di istituzioni di \u00absicurezza comune\u00bb, NATO, UE, la Turchia nostra alleata, la laicit\u00e0, la secolarizzazione compiuta (mai pi\u00fa intolleranza religiosa) \u2026 e i nostri figli, i nostri nipoti, dovranno forse combattere con le armi l\u2019Islam: e dove sono? Non li abbiamo generati. Combatteranno per noi i maghrebini, i somali, gli eritrei, i siriani che abbiamo accolto \u2014 per pagarli meno di noi, in uno spazio senza identit\u00e0 e senza cultura, dove la civilt\u00e0 \u00e8 stata rimpiazzata dalla cultura pop?<\/p>\n<p style=\"text-align: justify;\">Ve lo dico perch\u00e9 sento alla radio che fra \u00able voci della cultura\u00bb che, dopo aver salutato Umberto Eco, oggi salutano le unioni civili, sento nominare tal Jovanotti. \u00abFinalmente entriamo in Europa\u00bb, ha esultato. Un vero genio, uno che fa molti soldi perch\u00e9 \u00e8 popolare, e molti giovani vanno a quelli che si osa chiamare i suoi concerti. Direte: \u00e8 un giovane. \u00c8 un giovane di 50 anni che abita a New York, spende l\u00ed i milioni che \u00abi giovani\u00bb gli danno tanto volentieri.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ed, cara mamma, non sono stato \u00abIl pioniere di una nuova Italia rinata nel mondo\u00bb. A 72 anni, mi preparo ad estinguermi con la mia generazione sapendo bene che l&#8217;abbiamo meritato: con un lagno, non con un grido. Scusami mamma, non ce l\u2019ho fatta. \u00c8 stata anche colpa mia. Non sono nemmeno sicuro di morire cattolico romano; dei \u00abgiovani\u00bb alla Jovanotti, sono sicuro.<\/p>\n<p style=\"text-align: justify;\">Fonte e \u00a9: Blondet &amp; Friends 22 febbraio 2016.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pubblicato su Il Covile, anno XVI n.890 \u00a027 febbraio 2016 Maurizio Blondet Ida Magli \u00e8 scomparsa. Non avr\u00e0 nemmeno lontanamente gli onori funerari che il Sistema ha tributato ad Umberto Eco. \u00c8 logico: \u00e8 stata la prima a gridare, inascoltata, che l\u2019Europa burocratica era diventata la prigione dei popoli e stava distruggendo la cultura e &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":31164,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,9],"tags":[913],"class_list":["post-31163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-costume","category-demografia","tag-declino-demografico","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quella che si estingue \u00e8 la mia generazione. Tante scuse - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quella che si estingue \u00e8 la mia generazione. Tante scuse - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-09T23:00:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/03\/anziani.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"265\" \/>\n\t<meta property=\"og:image:height\" content=\"190\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Quella che si estingue \u00e8 la mia generazione. Tante scuse\",\"datePublished\":\"2016-03-09T23:00:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\\\/\"},\"wordCount\":2083,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/anziani.jpg\",\"keywords\":[\"declino demografico\"],\"articleSection\":[\"Costume\",\"Demografia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\\\/\",\"name\":\"Quella che si estingue \u00e8 la mia generazione. Tante scuse - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/anziani.jpg\",\"datePublished\":\"2016-03-09T23:00:07+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/anziani.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/03\\\/anziani.jpg\",\"width\":265,\"height\":190},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quella che si estingue \u00e8 la mia generazione. Tante scuse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quella che si estingue \u00e8 la mia generazione. Tante scuse - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\/","og_locale":"it_IT","og_type":"article","og_title":"Quella che si estingue \u00e8 la mia generazione. Tante scuse - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2016-03-09T23:00:07+00:00","og_image":[{"width":265,"height":190,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/03\/anziani.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Quella che si estingue \u00e8 la mia generazione. Tante scuse","datePublished":"2016-03-09T23:00:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\/"},"wordCount":2083,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/03\/anziani.jpg","keywords":["declino demografico"],"articleSection":["Costume","Demografia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\/","name":"Quella che si estingue \u00e8 la mia generazione. Tante scuse - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/03\/anziani.jpg","datePublished":"2016-03-09T23:00:07+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/03\/anziani.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/03\/anziani.jpg","width":265,"height":190},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/quella-che-si-estingue-e-la-mia-generazione-tante-scuse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Quella che si estingue \u00e8 la mia generazione. Tante scuse"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/31163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=31163"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/31163\/revisions"}],"predecessor-version":[{"id":31165,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/31163\/revisions\/31165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/31164"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=31163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=31163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=31163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}