{"id":3103,"date":"2009-04-21T13:09:51","date_gmt":"2009-04-21T11:09:51","guid":{"rendered":""},"modified":"2016-06-15T09:51:10","modified_gmt":"2016-06-15T07:51:10","slug":"gli-altri-oltre-hillary","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-altri-oltre-hillary\/","title":{"rendered":"Gli altri oltre Hillary"},"content":{"rendered":"<div style=\"text-align: center;\">\n<div id=\"attachment_34802\" style=\"width: 240px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-34802\" class=\"wp-image-34802\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Hillary_Clinton.jpg\" alt=\"Hillary_Clinton\" width=\"240\" height=\"160\" \/><p id=\"caption-attachment-34802\" class=\"wp-caption-text\">Hillary Clinton<\/p><\/div>\n<p><strong>Il Domenicale,<\/strong> 19 gennaio 2008<\/div>\n<p style=\"text-align: justify;\"><em>Tutto quello che non vi hanno detto sulle primarie Usa e i loro veri protagonisti. In Italia sembra che non ci sia che lei o al massimo Obama. I nostri giornali progressisti (ma anche no) parteggiano per i Democratici. Poche notizie sui candidati Repubblicani. Speriamo vada a finire come l\u2019altra volta. Tutti a far parapunzip\u00f2 al fighetto Kerry, ma poi rivinse il \u201crozzo\u201d Bush. Spot bipartisan per i candidati di cui nessuno parla mai, ma che alla fine contano e non poco<br \/>\n<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Marco Respinti<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Le primarie sono iniziate, ma, nonostante tutto (lotte, lacrime e il sudore di qualcuno) sono ancora poca cosa. Qualche dato certo si avr\u00e0 a partire dal 6 febbraio, dopo il super-marted\u00ec pieno di voti e di votanti. Epper\u00f2 noi qualche pronostico lo azzardiamo. Se ci saremo sbagliati, mica ci pentiremo: interpreteremo le novit\u00e0 e ricostruiremo il quadro.<\/div>\n<p style=\"text-align: justify;\">Rebus sic stantibus, noi vaticiniamo (e, lo sappiamo, \u00e8 facile) che la lotta delle primarie si ridurr\u00e0 presto, anzi prestissimo al quartetto Hillary Clinton e Barack Obama per il Partito Democratico, pi\u00f9 John Mc Cain e Rudolph Giuliani per il Partito Repubblicano.\u00a0 \u00c8 vero che McCain arranca e che Giuliani non \u00e8 un rubacuori, ma Mitt Romney, il mormone ultramiliardario, chi lo voter\u00e0?<\/p>\n<p style=\"text-align: justify;\">Il discorso vale per le primarie, per\u00f2. Per il dopo, buio pesto. Si parla di un eventuale Michael Bloomberg come terzo incomodo indipendente dopo l\u2019estate. I denari certo li ha: ma quanti lo voterebbero davvero fuori dal suo recinto? Restiamo per\u00f2 all\u2019oggi, poich\u00e9 tempo per tornarci su con dati concreti alla mano ce n\u2019\u00e8 e ce ne sar\u00e0. Oggi siamo sicuri che i big si getteranno sugli Stati elettoralmente decisivi (con la California e lo Stato di New York che avranno la parola forse persino finale, il 5 febbraio, in casa Democratica): chi ha vere chance per farcela concentra infatti sforzi e soldi l\u00e0 dove davvero pu\u00f2 fare la differenza.<\/p>\n<p style=\"text-align: justify;\">Un commentino alla Nostradamus ci sentiamo per\u00f2 a questo punto di farlo.<\/p>\n<p style=\"text-align: justify;\"><strong>Certe forche caudine<\/strong><\/p>\n<p style=\"text-align: justify;\">A sinistra madame Clinton \u00e8 comunque favorita, per una serie di ragioni note a tutti e quindi inutili da ripetere. Obama, per\u00f2, sembra capace d\u2019insidiarle il titolo di reginetta del ballo. Restiamo convinti che sia un bluff, che al momento giusto si sgonfier\u00e0, che la retorica del nero alle primarie (anche se i leader dei neri arrabbiati lo chiamano \u201cbianco\u201d e lui ci sta) sia vuota (si veda il caso Alan Keyes qui accanto). Ma queste sono nostre illazioni.<\/p>\n<p style=\"text-align: justify;\">Il fatto \u00e8 questo: vediamo cosa succede quando voteranno i Democratici degli Stati del Sud profondo. Il razzismo non c\u2019entra nulla, c\u2019entra la storia. Per Democratici che siano, cio\u00e8 oggi pi\u00f9 o meno sempre liberal, quelli del Sud sono sempre del Sud. Se accadesse che i Democratici del Sud premiassero un nero, bisognerebbe riscrivere gran parte di ci\u00f2 che si \u00e8 scritto sugli USA negli ultimi anni. Vorrebbe infatti dire che esiste, come per\u00f2 non \u00e8 mai esistita, una ideologia ufficiale di partito anche negli States e che questa ora riesce, come riesce altrove da tempo, a fare ingollare all\u2019elettorato bocconi amari e nodi storici prima insormontabili.<\/p>\n<p style=\"text-align: justify;\">Dall\u2019altra parte, in casa Repubblicana, i problemi non sono in numero inferiore. Il Grand Old Party non \u00e8 affatto un partito di destra tout court, epper\u00f2 raccoglie storicamente, dalla seconda met\u00e0 del Novecento, pi\u00f9 consensi conservatori che l\u2019antagonista Democratico. L\u2019entit\u00e0 di questi dipende sempre, per\u00f2, da chi \u00e8 il candidato alla Casa Bianca, e qui casca l\u2019asino. Fra McCain e Giuliani, infatti, in grado di contendersi il cuore della Destra non vi \u00e8 davvero nessuno.<\/p>\n<p style=\"text-align: justify;\">Quindi? Quindi, come spesso \u00e8 successo nel passato, la Destra potrebbe scegliere di starsene a casa, stizzita, sdegnosa, scontenta, e decretare cos\u00ec l\u2019elezione di un presidente di minoranza tutto preda della Sinistra, estrema oppure moderata. Un disastro insomma: un disastro per noi che sapete come la pensiamo, un disastro per gli Stati Uniti, un disastro per l\u2019Occidente minato e minacciato all\u2019interno e all\u2019esterno, in guerra, ferito, persino sanguinante. Clinton, Obama, McCain o Giuliani: solo questione di sfumature e d\u2019intensit\u00e0&#8230;<\/p>\n<p style=\"text-align: justify;\">Ma va l\u00e0, direte leggendo. Fidatevi, rispondiamo. Fatevi quattro passi negli USA, appena vi capita.\u00a0 \u201cIt\u2019s the economy, stupid\u201d, certo; ma l\u00ec cose come i gay-rights, l\u2019aborto, le cellule staminali e l\u2019immigrazione sono temi non solo politici, ma politicissimi. E peseranno molto, in un senso o nell\u2019altro, sull\u2019elettorato. Giuliano Ferrara, che gli USA li conosce, sta del resto importando lo stile anche da noi.<\/p>\n<p style=\"text-align: justify;\"><strong>Per capirci un poco di pi\u00f9<\/strong><\/p>\n<p style=\"text-align: justify;\">A questo punto, sconfortati ma non sconsolati, scegliamo di guardare a quelli che non ce la faranno (in blu qui ci sono i Democratici, in rosso i Repubblicani). Manca Mike Huckabee perch\u00e9 di questo homo novus, piuttosto conservatore, si \u00e8 parlato molto.<\/p>\n<p style=\"text-align: justify;\">Premesso che tutta la retorica nostrana sul pericolo insito in campagne elettorali lunghe e lunghissime fa scappare da ridere (gli USA votano ogni due anni,\u00a0 amministrative e poi presidenziali+amministrative, con le primarie che durano un anno, e dunque l\u2019aggiunta di decine di altre elezioni intermedie e locali pure con tanto di primarie, e referendum a iosa), noi sappiamo e quindi vogliamo dire che non \u00e8 che se la tiv\u00f9 non ne parla e i giornali ne tacciono, i candidati alle primarie spariscano.<\/p>\n<p style=\"text-align: justify;\">Di solito, salvo eccezioni, si danno prima e dopo un gran da fare nel mondo delle proprie constituency. Talvolta varano progetti educativi sontuosi o animano iniziative politiche assai rilevanti, destra o sinistra che sia. Qui, insomma, vogliamo ricordare che la vita continua sempre oltre le urne, e pure prospera. E che in un Paese come gli USA molto di ci\u00f2 che \u00e8 decisivo si svolge lontano dalle elezioni, anche se magari grazie a persone che poi un giorno con le elezioni decidono di cimentarsi.<\/p>\n<p style=\"text-align: justify;\">Chi volesse cio\u00e8 capire un poco di pi\u00f9 degli USA, e di come e perch\u00e9 certuni, che sembrano nati solo ieri sotto il cavolo, la spuntino infine magari pure alle elezioni, deve guardare a questi mondi. Mondi reali fatti di gente reale che a volte fa davvero la differenza.<\/p>\n<p style=\"text-align: justify;\"><strong>John edwards, il liberal-tipo<\/strong><\/p>\n<p style=\"text-align: justify;\">Nel 1988 Johnny Reid \u201cJohn\u201d Edwards (South Carolina, 1953) \u00e8 stato eletto al Senato dal North Carolina, nel 2004 ha cercato la nomination nelle primarie fallendo e poi \u00e8 stato scelto come running-mate del senatore John F. Kerry del Massachusetts, cio\u00e8 come eventuale vicepresidente. Alla notizia, la Camera di Commercio USA si \u00e8 gettata nelle braccia di George W. Bush jr., data la contrariet\u00e0 di Edwards a certe riforme intese a ridurre l\u2019impatto dei contenziosi giuridici sull\u2019economia.<\/p>\n<p style=\"text-align: justify;\">Dopo Kerry, Edwards \u00e8 tornato a lavorare per il comitato di azione politica One America Committee che ha creato nel 2001; quindi la Scuola di specializzazione in giurisprudenza dell\u2019Universit\u00e0 del North Carolina di Chapel Hill, sua <em>alma mater<\/em>, lo ha nominato nel febbraio 2005 direttore del Center on Poverty, Work and Opportunity; infine ha trovato impiego come consulente del Fortress Investment Group: $479.512 nel 2006 per il lavoro part-time di un uomo che, secondo The Wall Street Journal del novembre scorso, avrebbe investito $16 milioni di dollari in una a compagnia, appunto la Fortress, che pare avere ben speculato sui guai causati dall\u2019uragano Katrina a New Orleans.<\/p>\n<p style=\"text-align: justify;\">Ai tempi dell\u2019<em>impeachment<\/em> di Bill Clinton, Edwards fu il responsabile delle deposizioni di Monica Lewinsky e del compagno di partito Vernon Jordan. Nel 2000, Al Gore pens\u00f2 a lui (oltre che a John Kerry e a Joseph Lieberman, che poi scelse) per l\u2019eventuale vicepresidenza. A suo tempo Edwards vot\u00f2 per il Patriot Act\u00a0 e si schier\u00f2 pure a favore dell\u2019intervento militare in Irak (giudicava Saddam Hussein una minaccia per Israele e cogente lo spauracchio delle armi di distruzione di massa), ma poi ha cambiato idea.<\/p>\n<p style=\"text-align: justify;\">A favore di aborto, affirmative action (le politiche per le \u201cminoranze discriminate\u201d, donne comprese&#8230;) e pena di morte, l\u2019ex senatore \u00e8 un tipico americano (pochi pure tra i liberal osano parlare contro la pena capitale) cos\u00ec com\u2019\u00e8 un tipico liberal (vedi aborto e affirmative action).<\/p>\n<p style=\"text-align: justify;\">Colpito da pi\u00f9 di una tragedia familiare, si \u00e8 distinto per le battaglie contro i tagli fiscali dell\u2019Amministrazione Bush, per l\u2019indulgenza verso gl\u2019immigrati (\u00e8 favorevole alla regolarizzazione dei clandestini) , per l\u2019ambientalismo, e avversa le leggi contro le unioni civili omosessuali e in difesa del matrimonio. Il politicamente corretto \u00e8 insomma il suo mondo: senza estremismi, ma con pervicacia. Belloccio, giovane, in carriera, amici danarosi , <em>jet-set<\/em>. Si far\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>Mike Gravel: freddo. cinico?<\/strong><\/p>\n<p style=\"text-align: justify;\">L\u2019Alaska lo ha eletto prima presidente della Camera dei Deputati nel proprio parlamento statale (1963-1966), quindi, nel 1968, senatore al Congresso federale. Successe di nuovo nel 1974 e fino al 1980. Lui \u00e8 Maurice Robert \u201cMike\u201d Gravel (Massachusetts, 1930): lass\u00f9 in Alaska ci \u00e8 arrivato negli anni Cinquanta per compravendita di terreni.<\/p>\n<p style=\"text-align: justify;\">Al Congresso di Washington divenne famoso quando cerc\u00f2 di fermare il reclutamento di <em>servicemen<\/em> per la guerra in Vietnam (prima che, nel 1973, la leva obbligatoria venisse abolita) e per aver gettato, nel 1971, in pasto alla curiosit\u00e0 dell\u2019universo mondo (e Noam Chomsky gli fu subito al fianco) i cosiddetti Pentagon Papers, 7mila pagine top-secret commissionate nel 1967 dal ministro della Difesa Robert S. McNamara a proposito delle manovre di politica interna e di pianificazione internazionale prima e durante la guerra occidentale contro il comunismo indocinese.<\/p>\n<p style=\"text-align: justify;\">Che forse non gli spiaceva, come pure non antipatico forse gli stava quello cinese, visto che sei mesi prima del viaggio segreto compiuto dal Segretario di Stato Henry Kissinger a Pechino (sempre 1971) si era prodigato per la normalizzazione dei rapporti fra USA e dragone asiatico, e persino per il \u201cricongiungimento familiare\u201d fra Cina e Taiwan, a spese, ovvio, della seconda.<\/p>\n<p style=\"text-align: justify;\">Forte di questi exploit, nel 1972 cerc\u00f2 con tutte le forze la nomina a potenziale vicepresidente di George MacGovern, il quale per\u00f2 scelse Thomas Eagleton, senatore del Missouri.<\/p>\n<p style=\"text-align: justify;\">Gravel, uomo freddo, professa due fedi: la cattolica e l\u2019ambientalista. Nel 1974, contro il nucleare, se la faceva con Ralph Nader (il leader dei Verdi USA che quest\u2019anno corre da indipendente senz\u2019alcuna chance) e al contempo fu il principale sponsor della Trans-Alaska Pipeline, l\u2019oleodotto: e pensare che c\u2019\u00e8 in giro ancora un sacco di gente che impunemente sostiene che gli antinuclearisti sono solo agenti dei petrolieri&#8230;<\/p>\n<p style=\"text-align: justify;\">Due religioni, si diceva, che Gravel amalgama da sempre con salsa fredda del Grande Nord, come quando, nel 1977, raccolse fondi privati per finanziare la prima Inuit Circumpolar Conference con partecipanti da Alaska, Canada e Groenlandia. Ma dopo un po\u2019 anche gli eschimesi si sono stancati e l\u2019hanno mandato a casa. Alla poltica Gravel \u00e8 tornato nel 1989.<\/p>\n<p style=\"text-align: justify;\">Oggi sogna la Casa Bianca. Appunto: sogna. Favorevole all\u2019aborto, all\u2019introduzione della tassa progressiva, parla di democrazia diretta. Populismo bello e buono. Pochi \u201cdem\u201d lo filano, constituency confusa.<\/p>\n<p style=\"text-align: justify;\"><strong>Dennis Kucinich, Gandhi in d.c.<\/strong><\/p>\n<p style=\"text-align: justify;\">Attualmente Dennis John Kucinich, classe 1946, ascendenza croata e irlandese, \u00e8 deputato al Congresso federale in rappresentanza del 10\u00b0 Distretto dell\u2019Ohio. Ex sindaco di Cleveland (1977-1979), sua citt\u00e0 natale, ci ha provato, in termini di primarie per le presidenziali, quatto anni fa e ci riprova pure quest\u2019anno. Cattolico, divorziato e rimaritato per tre volte, nel 2003 ha ricevuto il Ghandi Peace Award assegnatogli dal Promoting Enduring Peace, una organizzazione quacchera e pacifista come pacifisti sono tutti i quaccheri (i quali hanno espresso due soli presidenti USA, Herbert Hoover e Richard M. Nixon).<\/p>\n<p style=\"text-align: justify;\">Nel 1982, dopo rovesci finanziarie, ha cercato di diventare Segretario di Stato, ma non ce l\u2019ha fatta. Dopo altre vicende politiche di non troppo momento, nel 1994 si \u00e8 ritirato in New Mexico lontano dalle preoccupazioni \u00aballa ricerca\u00bb, ha sempre detto, \u00abdi significato\u00bb. Grande sostenitore dei programmi\u00a0 e delle legislazioni di Sanit\u00e0 pubblica, non ha mancato di mostrare indipendenza di giudizio e di valutazione prendendo le distanze rispetto alla regola del Partito Democratico. Lo ha fatto, e visibilmente, per esempio nel 2001, votando contro il Patriot Act e ancora nel 2006\u00a0 contro la legge\u00a0 che affidava ai tribunali militari il trattamento delle violazioni delle leggi di guerra.<\/p>\n<p style=\"text-align: justify;\">Favorevole alle indagini sul presidente Clinton in vista dell\u2019impeachment, contrario invece alla proposta di emendare la Costituzione federale per far s\u00ec che possa diventare reato grave il bruciare in pubblico le bandiere statunitensi per darsi un tono politico,\u00a0 Kucinich ha dato talvolta segno d\u2019inclinazioni pro-life, anche se mai ha detto s\u00ec alla proposta d\u2019introdurre un emendamento a favore della vita nella legge fondamentale del Paese. Stante quest\u2019ambiguit\u00e0, questo would-be president ha deciso allora un d\u00ec del 2003 di rompere gl\u2019indugi dichiarandosi apertamente e definitivamente pro-choice, cio\u00e8 favorevole all\u2019aborto. Disse che aveva cambiato idea e voleva farlo sapere.<\/p>\n<p style=\"text-align: justify;\">Critico di Bush in politica estera, nel 2004 ha mandato una lettera di solidariet\u00e0 al presidente socialcomunista del Venezuela Hugo Rafael Ch\u00e1vez\u00a0 Frias ed \u00e8 uno dei soli due deputati USA ad aver bocciato l\u2019incriminazione di Mahmud Ahmadinejad a norma di carte ONU per le parole carine che egli usa sugli ebrei. Ah, \u00e8 pure ambientalista.<\/p>\n<p style=\"text-align: justify;\">Domanda: ha scontentato tutti, chi lo vota?<\/p>\n<p style=\"text-align: justify;\"><strong>Alan Keyes, nero di destra<\/strong><\/p>\n<p style=\"text-align: justify;\">Wow, un nero si candida alla Casa Bianca. Barack Obama per tutti? No, Alan Keyes (Maryland, 1950), nero come il carbone, conservatore vero (cio\u00e8 molto, molto pi\u00f9 che solo Repubblicano), cattolico, antiabortista schietto e netto, grande oratore, educatore doc, autore di libri belli ed efficaci ed ex ambasciatore al Consiglio Economico e Sociale delle Nazioni Unite per volere di Ronald W. Reagan; sotto il grande cow-boy della Casa Bianca, ha servito in qualit\u00e0 di assistente Segretario di Stato per gli affari di organizzazione internazionale.<\/p>\n<p style=\"text-align: justify;\">Insomma, \u00e8 in giro da un bel po\u2019, Keyes; ma i nostri media <em>parvenu<\/em> vanno in giro poco a sfrucugliare fra le cose e in mezzo alla gente, anche se Keyes ha pure vissuto per un po\u2019 pure in Italia. Keyes ci ha gi\u00e0 provato senza successo nel 1996 e nel 2000, ma non \u00e8 che, bocciato alle primarie presidenziali, sia sparito. A parte il fatto che appunto oggi ci riprova, fa da sempre un grande lavoro di collegamento e di formazione nel tessuto sociale.<\/p>\n<p style=\"text-align: justify;\">Anche quest\u2019anno non ha <em>chance<\/em>, forse meno di prima; ma correre gli fa un gran bene anche quando perde. Si mostra, infatti, e amplia il mondo dei suoi fan. E cos\u00ec pu\u00f2 fare bene il lavoro che sa fare meglio: scrivere libri, educare alla libert\u00e0 e alla virt\u00f9 (come dicono, e gli piace dirlo, gli americani di destra). Allievo del filosofo straussiano della politica Allan Bloom, pi\u00f9 volte minacciato di morte per aver affrontato in pubblico i dimostranti contro la guerra in Vietnam, ad Harvard divise gli appartamenti con William Kristol, attuale direttore di The Weekly Standard, quintessenza del pensiero neocon di oggi.<\/p>\n<p style=\"text-align: justify;\">Ha tre figli. Nel 2005 \u00e8 saltata fuori la storia che Maya, secondogenita, \u00e8 lesbica. Keyes s\u2019infuria e si rifiuta di continuare a pagarle il college. La stampa monta il caso. E allora Maya dice: ma \u00e8 ovvio, come potrebbe mio padre finanziare qualcuno che opera contro ci\u00f2 in cui lui graniticamente crede da sempre? Logico. In casa Keyes anche la figlia lesbica pensa bene, ordinatamente. Del resto, il buon Alan ha detto in pubblico che alla figlia non ha mai fatto mancare nulla, nemmeno un cent perch\u00e9 sarebbe contrario a ci\u00f2 in cui crede.<\/p>\n<p style=\"text-align: justify;\">Per farsi una idea di quanto sia prezioso e di qualit\u00e0 il lavoro che Keyes svolge quotidianamente da anni, si dia una occhiata alla sua fondazione \u201cRenew America\u201d. Sarebbe un grande presidente. Ma, visto che non ha possibilit\u00e0, Dio lo conservi in salute per il lavoro che fa alacremente nella e per la\u00a0 \u201cRight Nation\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Ron Paul, eroe libertarian<\/strong><\/p>\n<p style=\"text-align: justify;\">Viene dalla Pennsylvania, il senatore Ronald Ernest \u201cRon\u201d Paul, ma si \u00e8 accasato in Texas e, classe 1935, non \u00e8 giovanissimo. Il che significa che \u00e8 un veterano. Di molte battaglie. Tutte tese a limitare il pi\u00f9 possibile la pressione dello Stato su individui, famiglie e loro libere associazioni, pressione che \u00e8 sempre troppa, sanguinosa, insopportabile.<\/p>\n<p style=\"text-align: justify;\">Paul \u00e8 infatti un libertarian tipico, cio\u00e8 un \u201cestremista della libert\u00e0\u201d che in tempi di statalismo comunque trionfante significa essere nel campo dei giusti. Ginecologo, nel 1988 si fece vedere bene come candidato presidenziale del Libertarian Party (LP) pur restando dentro il Grand Old Party, i Repubblicani. Perch\u00e9 i libertarian criticano di brutto i Repubblicani, epper\u00f2 con i Democratici proprio no.<\/p>\n<p style=\"text-align: justify;\">Quest\u2019anno corre da libertarian (ovvio) dentro al GOP, ma l\u2019LP gli ha fatto sapere che, mollata fra qualche tempo la presa Repubblicana, potr\u00e0 correre da terzo incomodo rompiglioni come suo candidato presidenziale. La sua funzione politica pi\u00f9 importante \u00e8 infatti quella di tenere alta una bandiera, pure di \u201cricattare\u201d il GOP da destra e di continuare a morderne il personale ai polpacci fra una presidenziale e l\u2019altra.<\/p>\n<p style=\"text-align: justify;\">Il sogno vero \u00e8 che il GOP diventi infatti tutto di destra, <em>libertarian<\/em> quanto serve, conservatore quanto \u00e8 d\u2019uopo. Un altro sogno, gi\u00e0, ma bello, molto bello. Paul \u00e8 uno di quelli che, con la sua sagace azione dentro il GOP (non fuori) ci permette di coltivarlo: lo permette a noi e a migliaia e migliaia di americani.<\/p>\n<p style=\"text-align: justify;\">Del resto Paul (episcopaliano che un d\u00ec medit\u00f2 se divenire pastore luterano) incarna virt\u00f9 e paradossi, cio\u00e8 pure tic, dei libertarian. Avversa il Patriot Act (ma lui da destra), vuole il gold-standard per il dollaro ed \u00e8 solidamente pro-life anche se si oppone a un legge federale che bandisca l\u2019aborto dappertutto. Lo ritiene infatti statalismo. Al suo posto propone che in materia ogni singolo Stato legiferi da s\u00e9 giacch\u00e9 i singoli Stati sono politicamente sovrani. Parla come un vecchio confederato \u201csudista\u201d, proprio come un buon numero di libertarian tutti d\u2019un pezzo.<\/p>\n<p style=\"text-align: justify;\">Tra una campagna elettorale e l\u2019altra, infatti, Paul lega il proprio nome e la propria firma a cose utili e belle come WorldNetDaily (quotidiano telematico di destra), Ludwig von Mises Institute, e via cos\u00ec.<\/p>\n<p style=\"text-align: justify;\">Insomma, educare, educare, educare: bene se certa gente si butta in politica, provvidenziale quando perde e si butta a capofitto su ci\u00f2 che incide, forma, dura.<\/p>\n<p style=\"text-align: justify;\"><strong>Mitt Romney, un po\u2019 neocon<\/strong><\/p>\n<p style=\"text-align: justify;\">Classe 1947, Willard Mitt Romney \u00e8 figlio di un ex governatore del Michigan: in quello Stato \u00e8 nato, ma poi si \u00e8 spostato nel Massachusetts. L\u00ec ha fatto fortuna come businessman di successo e pure lui, nel 2002 (e fino al 2006), come governatore. Amministratore della Bain &amp; Company (management consulting), fondatore della Bain Capital (investimenti privati), nonch\u00e9 presidente e amministratore del comitato che organizz\u00f2 i giochi olimpici invernali del 2002 a Salt Lake City, nello Utah, \u00e8 un miliardario di quelli veri. E un ex studente di Stanford, un giusperito laureato ad Harvard e un mormone, in giovent\u00f9 missionario in Francia (dove pure soffr\u00ec un grave incidente automobilistico).<\/p>\n<p style=\"text-align: justify;\">Peraltro, la cosa gli ha gi\u00e0 creato non pochi problemi, giacch\u00e9 una parte cospicua degli americani di obbedienza evengelicale lo guardano pi\u00f9 che con sospetto. Ai loro occhi, infatti, il mormonismo \u00e8 solo una setta (non una Chiesa) e quindi deve avere poco spazio pure nella \u201cTerra dei liberi\u201d. Del resto, un\u2019altra parte di evangelicali e molti di coloro che si riconoscono (o che vengono definiti) \u201cconservatori sociali\u201d lo criticano perch\u00e9 poco in sintonia con i loro princ\u00ecpi.<\/p>\n<p style=\"text-align: justify;\">Preparandosi dunque a questo 2008, Romney (che non \u00e8 certo uno sprovveduto) ha accusato il colpo e ha rilanciato. Sostenendo che la realt\u00e0 lo ha cambiato nel corso degli anni, modificando pure le sue prospettive politiche, il miliardario che corre per la Casa Bianca si \u00e8 negli scorsi mesi sempre pi\u00f9 presentato in pubblico utilizzando un linguaggio vicino a quello dei conservatori.<\/p>\n<p style=\"text-align: justify;\">Nel 1994 fu visto farsela con la Planned Parenthood e udito fare commenti filoabortisti, ma dice di essersi sbagliato. Oggi veicola, di genere, un messaggio <em>pro-life<\/em>, e questo, per la Destra in cerca di un vero candidato, con Sam Brownback fuori e Alan Keyes anche, potrebbe (potrebbe) voler dire farsi almeno in parte conquistare. Del resto, fra i \u201cminori\u201d Romney \u00e8 quello che oggi ha maggiori possibilit\u00e0 di tutti: il che non significa moltissimo, ma \u00e8 comunque qualcosa.<\/p>\n<p style=\"text-align: justify;\">La prova del fuoco \u00e8 venuta del resto nel 2003, allorch\u00e9 la Corte Suprema dello Stato del Massachusetts si pronunci\u00f2 a favore delle unioni civili omosessuali: Romney si schier\u00f2 contro e si diede da fare per l\u2019introduzione di un emendamento alla Costituzione del Massachusetts che le vietasse. Nel vasto mondo conservatore, qualcuno \u00e8 disposto a ricordarsene. Piuttosto duro sull\u2019immigrazione clandestina, Romney \u00e8 a favore della pena di morte\u00a0 e della linea Bush sulla guerra al terrorismo. Anche questo a destra piace.<\/p>\n<p style=\"text-align: justify;\"><strong>Fred Thompson, domani forse<\/strong><\/p>\n<p style=\"text-align: justify;\">Il presidente alla Casa Bianca lo ha gi\u00e0 fatto due volte. Fra l\u2019altro pure attore, ha infatti interpretato Ulysess S. Grant in Bury My Heart at Wounded Knee (film per la tiv\u00f9 USA dell\u2019HBO, 2007), tratto peraltro da un noto libro di Dee Brown che certo non \u00e8 un granch\u00e9, e Rachel and Andrew Jackson: A Love Story (HBO, 2001), dove, ovvio, recita la parte di \u201cAndie\u201d. I pi\u00f9 per\u00f2 lo conoscono per la serie Law &amp; Order.<\/p>\n<p style=\"text-align: justify;\">Freddie \u201cFred\u201d Dalton Thompson (Alabama, 1942) ha presieduto l\u2019International Security Advisory Board del Dipartimento di Stato americano, \u00e8 membro della the U.S.-China Economic and Security Review Commission, del Council on Foreign Relations (CFR) ed \u00e8 visiting fellow all\u2019American Enterprise Institute (AEI), il think tank neoconservatore di Washington dove operano tipi come Michael Novak, Joshua Muravchick, David Frum e Michael A. Ledeen.<\/p>\n<p style=\"text-align: justify;\">Insomma, il linguaggio della Destra lo conosce, e anche bene; quando vuole, pure lo parla. Dire per\u00f2 che \u00e8 il candidato del mondo conservatore tout court sarebbe esagerare. Per alcuni, il fatto che venga dall\u2019AEI \u00e8 una garanzia; per altri, il fatto che faccia parte del CFR un anatema. \u00c8 un federalista convinto, sostiene che i singoli Stati dell\u2019Unione debbano avere pi\u00f9 voce in capitolo, non pensa si debba emendare la Costituzione federale introducendo una provvisione contro i \u201cmatrimoni gay\u201d ma vuole che lo facciano i singoli Stati nelle proprie leggi fondamentali, \u00e8 contro l\u2019aborto. Epper\u00f2 il CFR passa per essere una \u201cmassoneria\u201d di poteri oscuri&#8230;<\/p>\n<p style=\"text-align: justify;\">Come conciliare le due cose? \u00c8 questa la domanda a cui Thompson deve rispondere, e presto se vuole costruirsi una constituency consistente. Oggi come oggi, ha pochissime chance. Eppure, con il tempo, come chi ha avuto successo, potrebbe farsi; deve per\u00f2 chiarire la propria offerta. \u00c8 infatti dentro l\u2019establishment quanto serve e potenzialmente in sintonia con il mondo conservatore quanto basta per cercare di lucrarne; epper\u00f2 negli anni futuri.<\/p>\n<p style=\"text-align: justify;\">Deve infatti seminare ancora, e molto, come\u00a0 del resto hanno fatti tutti i nomi grossi e vincenti che lo hanno preceduto.<\/p>\n<p style=\"text-align: justify;\">In campagna elettorale la sua ambivalente ma non ambigua piattaforma basta e avanza. Se una cosa infatti l\u2019era Bush jr. insegna \u00e8 questa. Vinci, e pure bene, e una volta presidente d\u00e0i persino il meglio, trasformando la maior pars che ti ha eletto in una sanior pars dove i numeri non contano ma le cose vere s\u00ec.<\/p>\n<p style=\"text-align: justify;\"><strong>Duncan Hunter, vero<em> pro-lifer<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Duncan Lee Hunter \u00e8 deputato in California (dov\u2019\u00e8 nato nel 1948) dal 1981. Oggi prova il grande balzo. Anche lui, come quelli che gli tengono compagnia in queste due pagine, ha poche possibilit\u00e0 reali, ma di spirito ne ha da vendere.<\/p>\n<p style=\"text-align: justify;\">Veterano del Vietnam fra 1970 e 1971, ha sempre esercitato un forte appeal negli ambienti militari e fra gli ex dei campi di battaglia. I suoi temi forti sono dunque normalmente quelli legati alla difesa nazionale, oggi alla lotta contro il terrorismo internazionale, alla dignit\u00e0 delle forze armate, alla necessit\u00e0 di strategie chiare e nette per i terreni dello scontro militare, e cos\u00ec via.\u00a0 Del resto, suo figlio \u00e8 stato sul fronte irakeno e da l\u00ec l\u2019anno scorso ha pure fatto politica attiva, con la benedizione del padre.<\/p>\n<p style=\"text-align: justify;\">Avvocato, di confessione protestante battista, Hunter ha saputo come fare breccia nel mondo conservatore, specie in quello pro-life (il quale non si sovrappone completamente al primo giacch\u00e9 pi\u00f9 ampio, eppure lo qualifica certamente in modo vasto e profondo). Il 2 febbraio 2005, infatti, Hunter ha proposto una legge, la H.R. 552, ossia The Right to Life Act,\u00a0 la quale garantisce eguale tutela del diritto alla vita di qualsiasi persona umana, nata o non ancora nata.<\/p>\n<p style=\"text-align: justify;\">La provisione riconosce anche la \u201cpersonalit\u00e0\u201d di un essere umano dal momento del suo concepimento e quindi garantisce a essa il pieno godimento dei diritti costituzionali che spetta a ogni cittadino degli Stati Uniti. \u00c8 ancora l\u00ec, non \u00e8 passato, ma pesa, eccome, soprattutto per gli elettori, pro o contro che siano.<\/p>\n<p style=\"text-align: justify;\">Hunter \u00e8 ben noto in patria per la battaglia condotta contro la pornografia e, su altri argomenti, contro l\u2019immigrazione clandestina. Ricordate il muro che deve separare la frontiera sudoccidentale degli Stati Uniti da quella nordorientale del Messico? Hunter ne \u00e8 un grande sponsor pubblico e politico, senza vergogna.<\/p>\n<p style=\"text-align: justify;\">E duro e coerente \u00e8 da sempre anche nella lotta con poco quartiere che conduce da anni contro quelle strutture di organizzazione del commercio internazionale quali NAFTA, CAFTA e WTO percepite mediamente dalla Destra statunitense come spocchiosamente antinazionali e pure d\u2019impronta dirigistica. Non \u00e8 forse la quintessenza del conservatorismo, Hunter, ma alla Destra sa come parlare. I voti oggi li cerca l\u00ec. Dopo le primarie , sar\u00e0 in quel mondo che operer\u00e0, e certamente bene.<\/p>\n<p style=\"text-align: justify;\">(A.C. Valdera)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Domenicale, 19 gennaio 2008 Tutto quello che non vi hanno detto sulle primarie Usa e i loro veri protagonisti. In Italia sembra che non ci sia che lei o al massimo Obama. I nostri giornali progressisti (ma anche no) parteggiano per i Democratici. Poche notizie sui candidati Repubblicani. Speriamo vada a finire come l\u2019altra &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-altri-oltre-hillary\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":34802,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108,76],"tags":[150],"class_list":["post-3103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-paesi-e-continenti","category-stati-uniti","tag-usa","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gli altri oltre Hillary - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-altri-oltre-hillary\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gli altri oltre Hillary - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-altri-oltre-hillary\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-21T11:09:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-15T07:51:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Hillary_Clinton.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"21 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-altri-oltre-hillary\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-altri-oltre-hillary\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Gli altri oltre Hillary\",\"datePublished\":\"2009-04-21T11:09:51+00:00\",\"dateModified\":\"2016-06-15T07:51:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-altri-oltre-hillary\\\/\"},\"wordCount\":4118,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-altri-oltre-hillary\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Hillary_Clinton.jpg\",\"keywords\":[\"Usa\"],\"articleSection\":[\"Paesi e continenti\",\"Stati Uniti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-altri-oltre-hillary\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-altri-oltre-hillary\\\/\",\"name\":\"Gli altri oltre Hillary - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-altri-oltre-hillary\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-altri-oltre-hillary\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Hillary_Clinton.jpg\",\"datePublished\":\"2009-04-21T11:09:51+00:00\",\"dateModified\":\"2016-06-15T07:51:10+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-altri-oltre-hillary\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-altri-oltre-hillary\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-altri-oltre-hillary\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Hillary_Clinton.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Hillary_Clinton.jpg\",\"width\":275,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/gli-altri-oltre-hillary\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gli altri oltre Hillary\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gli altri oltre Hillary - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-altri-oltre-hillary\/","og_locale":"it_IT","og_type":"article","og_title":"Gli altri oltre Hillary - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-altri-oltre-hillary\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-04-21T11:09:51+00:00","article_modified_time":"2016-06-15T07:51:10+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Hillary_Clinton.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"21 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-altri-oltre-hillary\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-altri-oltre-hillary\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Gli altri oltre Hillary","datePublished":"2009-04-21T11:09:51+00:00","dateModified":"2016-06-15T07:51:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-altri-oltre-hillary\/"},"wordCount":4118,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-altri-oltre-hillary\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Hillary_Clinton.jpg","keywords":["Usa"],"articleSection":["Paesi e continenti","Stati Uniti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-altri-oltre-hillary\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-altri-oltre-hillary\/","name":"Gli altri oltre Hillary - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-altri-oltre-hillary\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-altri-oltre-hillary\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Hillary_Clinton.jpg","datePublished":"2009-04-21T11:09:51+00:00","dateModified":"2016-06-15T07:51:10+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-altri-oltre-hillary\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-altri-oltre-hillary\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-altri-oltre-hillary\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Hillary_Clinton.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Hillary_Clinton.jpg","width":275,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/gli-altri-oltre-hillary\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Gli altri oltre Hillary"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3103"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3103\/revisions"}],"predecessor-version":[{"id":34803,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3103\/revisions\/34803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/34802"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}