{"id":3098,"date":"2009-04-21T09:48:00","date_gmt":"2009-04-21T07:48:00","guid":{"rendered":""},"modified":"2015-11-12T11:09:42","modified_gmt":"2015-11-12T10:09:42","slug":"federica-che-viene-uccisa-nel-paradiso-senza-crocifissi","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\/","title":{"rendered":"Federica, che viene uccisa nel &quot;paradiso&quot; senza crocifissi&#8230;"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/laicismo_Spagna.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-27545\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/laicismo_Spagna.jpg\" alt=\"laicismo_Spagna\" width=\"200\" height=\"140\" \/><\/a>Libero,<\/strong> 11 luglio 2008<\/div>\n<p style=\"text-align: center;\"><em>Lloret de Mar come metafora del nostro tempo&#8230;<br \/>\n<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Antonio Socci<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">I socialisti di Zapatero hanno annunciato di voler togliere i crocifissi dagli spazi pubblici. Il caso ha voluto che la notizia uscisse in contemporanea con l\u2019assassinio di Federica, proprio in Spagna, a Llorett de Mar, in un divertimentificio che \u00e8 il nuovo santuario dello sballo giovanile.<\/div>\n<p style=\"text-align: justify;\">Dove la discoteca \u00e8 \u2013 come ha spiegato Vittorino Andreoli \u2013 la cattedrale pagana di \u201cun grande rito di trasformazione collettiva\u201d che fa dimenticare la vita e la realt\u00e0. Gli ingredienti (anche chimici) di questa \u201cnuova religione\u201d sono noti, con il solito comandamento: \u201cvietato vietare\u201d. La felicit\u00e0 si trova davvero l\u00ec? E perch\u00e9 Federica ci ha trovato la morte, macellata come un agnello?<\/p>\n<p style=\"text-align: justify;\">Nessuno ci riflette. Nell\u2019euforica Spagna le autorit\u00e0 sembrano preoccupate soprattutto che il delitto non porti pubblicit\u00e0 negativa alla localit\u00e0 turistica. E vai con la tequila bum bum, dimentichiamo la povera Federica e via i crocifissi. Anche noi da tempo li abbiamo tolti dai cuori, oltrech\u00e9 dalla vita pubblica.<\/p>\n<p style=\"text-align: justify;\">Anzi, l\u2019immagine del crocifisso o quella della Madonna vengono periodicamente dileggiati da sedicenti artisti in nome della libert\u00e0 d\u2019espressione. Del resto il Papa stesso subisce questa sorte nelle manifestazioni di piazza della sedicente \u201cItalia dei migliori\u201d. E la fede cattolica viene azzannata, senza alcuna obiettivit\u00e0, in programmi televisivi che, se fossero realizzati contro qualsiasi altra religione, scatenerebbero subito l\u2019accusa di intolleranza o razzismo. Contro Ges\u00f9 Cristo invece sembra che tutto sia permesso.<\/p>\n<p style=\"text-align: justify;\">Poi, quando ci visita il dolore o si consuma la tragedia o assistiamo all\u2019orrore, gridiamo furenti \u2013 col dito accusatore \u2013 \u201cdov\u2019\u00e8 Dio?\u201d, \u201cPerch\u00e9 non ha impedito tutto questo?\u201d. Dopo l\u2019ecatombe dell\u2019 11 settembre a New York si alz\u00f2 questo stesso grido e una donna, in tutta semplicit\u00e0, parlando in televisione rispose cos\u00ec: \u201cper anni abbiamo detto a Dio di uscire dalle nostre scuole, di uscire dal nostro Governo, e di uscire dalle nostre vite. E da gentiluomo che \u00e8, credo che Lui sia quietamente uscito. Come possiamo aspettarci che Dio ci dia le Sue benedizioni, e la Sua protezione, se prima esigiamo che ci lasci soli?\u201d.<\/p>\n<p style=\"text-align: justify;\">Continuava ricordando quando si lanci\u00f2 la crociata perch\u00e9 non si voleva \u201cche si pregasse nelle scuole americane, e gli americani hanno detto OK. Poi qualcun altro ha detto che sarebbe meglio non leggere la Bibbia nelle scuole americane. Quella stessa Bibbia che dice: \u2018Non uccidere, non rubare, ama il tuo prossimo come te stesso&#8230;\u2019, e gli americani hanno detto OK. Poi, in molti paesi del mondo, qualcuno ha detto: \u2018Lasciamo che le nostre figlie abortiscano, se lo vogliono, senza neanche avvisare i propri genitori\u2019. Ed il mondo ha detto OK\u201d.<\/p>\n<p style=\"text-align: justify;\">Si girano film e show televisivi che sommergono le anime di fango. E si fa musica che celebra violenza, suicidio, droga o ammicca al satanismo. E tutti trovano questo normale e dicono che \u00e8 solo un gioco, com\u2019\u00e8 normale che, secondo le statistiche, un bimbo italiano, prima di aver terminato le elementari, veda in media in tv 8 mila omicidi e 100 mila atti di violenza, ma per carit\u00e0 togliamo la preghiera dalla scuola ch\u00e9 sarebbe un atto di \u201cviolenza psicologica\u201d.<\/p>\n<p style=\"text-align: justify;\">\u201dOra\u201d proseguiva quella donna americana \u201cci chiediamo perch\u00e9 i nostri figli non hanno coscienza, perch\u00e9 non sanno distinguere il bene dal male, e perch\u00e9 uccidono cos\u00ec facilmente estranei, compagni di scuola, e loro stessi. Probabilmente perch\u00e9, com\u2019\u00e8 stato scritto, \u2018l&#8217;uomo miete ci\u00f2 che ha seminato\u2019 (Galati 6:7). Uno studente ha \u2018sinceramente\u2019 chiesto: \u2018Caro Dio, perch\u00e9 non hai salvato quella bambina che \u00e8 stata uccisa in una scuola americana?\u2019. Risposta: \u2018Caro Studente, a Me non \u00e8 permesso entrare nelle scuole americane. Sinceramente, Dio\u2019 \u201d.<\/p>\n<p style=\"text-align: justify;\">Tutto questo non \u00e8 solo americano. Dopo Auschwitz una folla di intellettuali accus\u00f2 Dio: \u201cDov\u2019eri? Come hai potuto permettere tutto questo?\u201d. Nessuno ricordava quale fu la prima battaglia fatta dal nazismo appena arrivato al potere: la guerra dei crocifissi. Il nuovo regime pretese di spazzar via da tutte le scuole l\u2019immagine di Ges\u00f9 crocifisso. Fu uno scontro durissimo e la Chiesa fu praticamente lasciata sola a sostenerlo. Dov\u2019erano gli intellettuali?<\/p>\n<p style=\"text-align: justify;\">Poi il nazismo, fra il 1939 e il 1940, spazz\u00f2 via migliaia di \u201ccrocifissi viventi\u201d, una eutanasia di massa per 70 mila disabili e malati mentali: ritennero le loro delle vite indegne di essere vissute e dettero loro \u201cla morte pietosa\u201d, ma anche in quel caso la Chiesa fu lasciata quasi sola perch\u00e9 nei cuori il crocifisso era stato spazzato via dalla pagana e feroce croce uncinata. E cos\u00ec alla fine Hitler scaten\u00f2 la guerra e la Shoah. Dov\u2019era Dio? Era stato cacciato da tempo. E stava agonizzando nei lager con Massimiliano Kolbe, Edith Stein o Dietrich Bonhoeffer, accanto a una moltitudine di croficissi.<\/p>\n<p style=\"text-align: justify;\">Siamo la generazione che ha visto poi consolidarsi nel mondo il pi\u00f9 immane tentativo di strappare Dio dai cuori, imponendo l\u2019ateismo di Stato: l\u2019impero comunista che si \u00e8 risolto nel pi\u00f9 colossale genocidio planetario di uomini e popoli. Tutto questo c\u2019insegna qualcosa? No. Noi siamo la generazione che non impara dalle tragedie del suo tempo. E per questo forse sar\u00e0 destinata a ripeterle. Non abbiamo forse consegnato la costruzione europea a una tecnocrazia laicista e dispotica che ha voluto strappare le radici cristiane dell\u2019albero europeo? Ed eccoci all\u2019inverno demografico, al declino e all\u2019invasione islamica.<\/p>\n<p style=\"text-align: justify;\">Un grande economista come Giulio Tremonti, nel suo celebre libro, ha affermato che il riscatto \u00e8 possibile solo con una rinascita spirituale. Ma noi siamo \u201cgli uomini impagliati\u201d di Eliot, con la testa piena di vento e il cuore pieno di solitudine. Abbiamo sputato su Ges\u00f9 Cristo e sulla Chiesa credendo che questo fosse \u201clibert\u00e0\u201d, poi ci troviamo soli o disperati e allora puntiamo il dito accusatore sulla presunta \u201cindifferenza\u201d di Dio. Di quel Dio che non cessa un solo giorno di darci il respiro e di farsi incontro a noi.<\/p>\n<p style=\"text-align: justify;\">Siamo la generazione che non sa pi\u00f9 dare senso alla vita, n\u00e9 speranza ai propri figli, che vede addensarsi all\u2019orizzonte nubi cupe di crisi planetarie, di guerre, di carestie, ma non afferra la mano della \u201cRegina della Pace\u201d, presente fra noi per salvarci. Perch\u00e9 si ride del Mistero e del soprannaturale, mentre si va da maghi e astrologi, perch\u00e9 si crede ai giornali e a internet e non al Vangelo, perch\u00e9 si irride chi parla di Satana e dell\u2019Inferno, ma si affollano come non mai sette sataniche o esoteriche, perch\u00e9 si venerano le maschere vuote dei palcoscenici e della tv e si disprezzano i santi, perch\u00e9 si crede che libert\u00e0 sia poter fare qualunque cosa, anzich\u00e9 essere veramente amati.<\/p>\n<p style=\"text-align: justify;\">Questa stagione inizi\u00f2 nel \u201968, quando si cominci\u00f2 a sparare sulla religione come \u201coppio dei popoli\u201d, cos\u00ec oggi l\u2019oppio (o la cocaina) \u00e8 diventata la religione dei popoli, anche di notai, industriali e deputati. Nietsche tuon\u00f2 contro il crocifisso perch\u00e9 \u2013 scrisse \u2013 abol\u00ec i sacrifici umani che erano il motore della storia pagana. E infatti oggi, cancellato il crocifisso dai cuori, sono tornati i sacrifici umani.<\/p>\n<p style=\"text-align: justify;\">Siamo la generazione che ha assistito tranquillamente in 30 anni allo sterminio \u2013 con leggi degli Stati \u2013 di un miliardo di piccole vite umane nascenti, il pi\u00f9 immane sacrificio umano della storia. La generazione che torna a discettare di vite \u201cindegne di essere vissute\u201d, che pretende di trasformare i pi\u00f9 piccoli esseri umani in cavie da laboratorio, che esige \u2013 specialmente \u201cin nome della scienza\u201d &#8211; che tutto sia permesso. In effetti \u201cse Dio non c\u2019\u00e8, tutto \u00e8 permesso\u201d. Ma con quali conseguenze?<\/p>\n<p style=\"text-align: justify;\">L\u2019abbiamo visto nel recente passato. E siccome non ne traiamo le conseguenze lo vediamo nel presente e ancor pi\u00f9 lo vedremo nel futuro. Qualcuno ha osservato: \u201cStrano come sia semplice per le persone cacciare Dio per poi meravigliarsi perch\u00e9 il mondo sta andando all&#8217;inferno\u201d.<\/p>\n<p style=\"text-align: justify;\">(A.C. Valdera)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Libero, 11 luglio 2008 Lloret de Mar come metafora del nostro tempo&#8230; di Antonio Socci<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":27545,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[103,108],"tags":[640],"class_list":["post-3098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-laicismo","category-paesi-e-continenti","tag-spagna","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Federica, che viene uccisa nel &quot;paradiso&quot; senza crocifissi... - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Federica, che viene uccisa nel &quot;paradiso&quot; senza crocifissi... - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-21T07:48:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-12T10:09:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/laicismo_Spagna.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"268\" \/>\n\t<meta property=\"og:image:height\" content=\"188\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Federica, che viene uccisa nel &quot;paradiso&quot; senza crocifissi&#8230;\",\"datePublished\":\"2009-04-21T07:48:00+00:00\",\"dateModified\":\"2015-11-12T10:09:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\\\/\"},\"wordCount\":1282,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/laicismo_Spagna.jpg\",\"keywords\":[\"Spagna\"],\"articleSection\":[\"Laicismo\",\"Paesi e continenti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\\\/\",\"name\":\"Federica, che viene uccisa nel &quot;paradiso&quot; senza crocifissi... - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/laicismo_Spagna.jpg\",\"datePublished\":\"2009-04-21T07:48:00+00:00\",\"dateModified\":\"2015-11-12T10:09:42+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/laicismo_Spagna.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/laicismo_Spagna.jpg\",\"width\":268,\"height\":188},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Federica, che viene uccisa nel &quot;paradiso&quot; senza crocifissi&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Federica, che viene uccisa nel &quot;paradiso&quot; senza crocifissi... - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\/","og_locale":"it_IT","og_type":"article","og_title":"Federica, che viene uccisa nel &quot;paradiso&quot; senza crocifissi... - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-04-21T07:48:00+00:00","article_modified_time":"2015-11-12T10:09:42+00:00","og_image":[{"width":268,"height":188,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/laicismo_Spagna.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Federica, che viene uccisa nel &quot;paradiso&quot; senza crocifissi&#8230;","datePublished":"2009-04-21T07:48:00+00:00","dateModified":"2015-11-12T10:09:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\/"},"wordCount":1282,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/laicismo_Spagna.jpg","keywords":["Spagna"],"articleSection":["Laicismo","Paesi e continenti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\/","name":"Federica, che viene uccisa nel &quot;paradiso&quot; senza crocifissi... - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/laicismo_Spagna.jpg","datePublished":"2009-04-21T07:48:00+00:00","dateModified":"2015-11-12T10:09:42+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/laicismo_Spagna.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/laicismo_Spagna.jpg","width":268,"height":188},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/federica-che-viene-uccisa-nel-paradiso-senza-crocifissi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Federica, che viene uccisa nel &quot;paradiso&quot; senza crocifissi&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3098"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3098\/revisions"}],"predecessor-version":[{"id":27546,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3098\/revisions\/27546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/27545"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}