{"id":3054,"date":"2009-04-16T17:33:32","date_gmt":"2009-04-16T15:33:32","guid":{"rendered":""},"modified":"2016-02-07T19:57:17","modified_gmt":"2016-02-07T18:57:17","slug":"care-signore-la-vera-arte-quella-che-si-fa-in-chiesa","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\/","title":{"rendered":"Care signore la vera arte &egrave; quella che si fa in chiesa"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/messa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-30547\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/messa.jpg\" alt=\"messa\" width=\"250\" height=\"187\" \/><\/a>Il Giornale<\/strong>, 18 novembre 2007<\/div>\n<p style=\"text-align: center;\">di<strong> Camillo Langone<\/strong><\/p>\n<p style=\"text-align: justify;\">Che cos\u2019hai fatto domenica? Ho visto una bella mostra. Questa \u00e8 la risposta che sento sempre pi\u00f9 spesso, specie se faccio la domanda a una donna. A me piace vivere pericolosamente e dichiaro di non andare a vedere mostre da molto tempo, e precisamente da quando ho deciso di andare a messa tutte le domeniche.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Che c\u2019entra, direte voi, le due attivit\u00e0 non sono incompatibili. E invece ho scoperto che lo sono, che la mostra uccide la messa e se non la uccide la danneggia.\u00c8 noto che la moneta cattiva scaccia quella buona, che le imitazioni vendono pi\u00f9 degli originali, che il made in China soffoca il made in ltaly. Bene: le mostre d\u2019arte sono imitazioni, surrogati, sottoprodotti della vera bellezza, che si produce e si venera altrove.<\/div>\n<p style=\"text-align: justify;\">Se n\u2019\u00e8 accorto perfino Mario Botta, l\u2019architetto noto ai milanesi per aver sfigurato la Scala piazzandovi sul tetto una specie di parcheggio multipiano. Lui che di musei ne ha costruiti un mucchio, nel suo ultimo libro, <em>Dove abitano le emozioni<\/em>, sembra essersi pentito: \u00abUna societ\u00e0 forte non avrebbe bisogno di musei per segnalare i propri valori\u00bb.<\/p>\n<p style=\"text-align: justify;\">Siccome siamo una societ\u00e0 debole, ogni capoluogo di provincia sogna il suo mini-Guggenheim la cui funzione \u00e8 inconsapevolmente religiosa. Lo dice sempre lui, il Botta, che i musei \u00absono spazi per la ricerca di spiritualit\u00e0, dove il fruitore va per ricercare valori e significati del suo essere\u00bb.<\/p>\n<p style=\"text-align: justify;\">Gi\u00e0 la parola fruitore dovrebbe mettere sull\u2019avviso. Assomiglia molto a cliente, a consumatore. Come se lo Spirito potesse vendersi al bookstore, fra i cataloghi, le magliette con le riproduzioni dei quadri e i braccialetti artistici della felicit\u00e0 (esistono davvero, sono fra gli oggetti pi\u00f9 venduti alla Tate Gallery di Londra).<\/p>\n<p style=\"text-align: justify;\">Per quanto fra i preti italiani non manchino i soggetti bizzarri, a nessuno di loro \u00e8 mai venuto in mente di chiamare fruitori i partecipanti alla messa. Perch\u00e9 il cattolico praticante non \u00e8 uno spettatore passivo come il mostrista praticante: in chiesa si pu\u00f2 cantare, si pu\u00f2 leggere la Bibbia dal pulpitino a fianco dell\u2019altare, si possono raccogliere le offerte, si possono accendere ceri e candele, si pu\u00f2 anche suonare l\u2019organo.<\/p>\n<p style=\"text-align: justify;\">Alle mostre si pu\u00f2 guardare ma non toccare. Alle messe si pu\u00f2 addirittura mangiare (l\u2019ostia consacrata, previa confessione) e insomma vengono coinvolti tutti i sensi, finanche l\u2019odorato con l\u2019incenso e il tatto col segno di pace.<\/p>\n<p style=\"text-align: justify;\">E che dire dei \u00abvalori e significati\u00bb? Alle mostre i valori sono pi\u00f9 che altro i valori di mercato, e i significati spesso mancano per statuto, basti pensare all\u2019interminabile sfilza di opere denominate <em>Untitled<\/em>. Senza titolo, senza senso. Non ho mai capito come possano gli artisti insegnare qualcosa se non sono nemmeno capaci di dare un nome a ci\u00f2 che fanno.<\/p>\n<p style=\"text-align: justify;\">L\u2019arte contemporanea \u00e8 quasi sempre dissacrante, nichilista, quindi andarla a vedere impoverisce l\u2019anima. Maurizio Cattelan \u00e8 forse il massimo artista italiano vivente e di sicuro \u00e8 un genio, per\u00f2 del male: uno guarda il suo Papa colpito dal meteorite, i suoi fantocci di bambini impiccati agli alberi, e gli viene voglia di suicidarsi.<\/p>\n<p style=\"text-align: justify;\">L\u2019arte antica, al contrario, \u00e8 quasi sempre sacra, e se si trova in un museo significa che \u00e8 stata rubata o comunque estirpata dal suo ambiente naturale. Le colte, delicate fanciulle che vanno per mostre sono in realt\u00e0 complici di infiniti crimini a cominciare da quelli di Napoleone, celebre saccheggiatore di chiese e di conventi.<\/p>\n<p style=\"text-align: justify;\">Piero della Francesca la sua Sacra conversazione non la dipinse per farla fotografare coi telefonini a Brera, ma per essere oggetto di devozione in una chiesa di Urbino. E Raffaello? Che senso ha la sua Madonna Sistina in una pinacoteca di Dresda? Perch\u00e9 limitarsi a guardare il sacro, oltretutto avvilito da un\u2019ambientazione assurda, quando lo si pu\u00f2 vivere nei luoghi originari?<\/p>\n<p style=\"text-align: justify;\">Lo ha spiegato bene Joseph Ratzinger in un libro del 2004: \u00abCi\u00f2 che nei musei pu\u00f2 essere solo testimonianza del passato, ammirata con nostalgia, nella liturgia continua a essere presente vivo\u00bb. La massima esperienza di bellezza della mia vita l\u2019ho fatta a Sant\u2019Antimo, nell\u2019abbazia romanica fra le vigne e gli ulivi di Montalcino, durante l\u2019affollatissima messa domenicale col coro gregoriano dei frati vestiti di bianco, l\u2019incenso che invade la navata, i candelieri vibranti di fiammelle, le devote che si gettano a terra al momento della consacrazione. Non la scambierei con tutto il Louvre.<\/p>\n<p style=\"text-align: justify;\">(A.C. Valdera)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Giornale, 18 novembre 2007 di Camillo Langone Che cos\u2019hai fatto domenica? Ho visto una bella mostra. Questa \u00e8 la risposta che sento sempre pi\u00f9 spesso, specie se faccio la domanda a una donna. A me piace vivere pericolosamente e dichiaro di non andare a vedere mostre da molto tempo, e precisamente da quando ho &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":30547,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[119],"tags":[365],"class_list":["post-3054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte-sacra","tag-arte","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Care signore la vera arte &egrave; quella che si fa in chiesa - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Care signore la vera arte &egrave; quella che si fa in chiesa - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-16T15:33:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-07T18:57:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/messa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Care signore la vera arte &egrave; quella che si fa in chiesa\",\"datePublished\":\"2009-04-16T15:33:32+00:00\",\"dateModified\":\"2016-02-07T18:57:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\\\/\"},\"wordCount\":742,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/messa.jpg\",\"keywords\":[\"arte\"],\"articleSection\":[\"Arte sacra\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\\\/\",\"name\":\"Care signore la vera arte &egrave; quella che si fa in chiesa - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/messa.jpg\",\"datePublished\":\"2009-04-16T15:33:32+00:00\",\"dateModified\":\"2016-02-07T18:57:17+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/messa.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/messa.jpg\",\"width\":259,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Care signore la vera arte &egrave; quella che si fa in chiesa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Care signore la vera arte &egrave; quella che si fa in chiesa - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\/","og_locale":"it_IT","og_type":"article","og_title":"Care signore la vera arte &egrave; quella che si fa in chiesa - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-04-16T15:33:32+00:00","article_modified_time":"2016-02-07T18:57:17+00:00","og_image":[{"width":259,"height":194,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/messa.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Care signore la vera arte &egrave; quella che si fa in chiesa","datePublished":"2009-04-16T15:33:32+00:00","dateModified":"2016-02-07T18:57:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\/"},"wordCount":742,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/messa.jpg","keywords":["arte"],"articleSection":["Arte sacra"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\/","name":"Care signore la vera arte &egrave; quella che si fa in chiesa - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/messa.jpg","datePublished":"2009-04-16T15:33:32+00:00","dateModified":"2016-02-07T18:57:17+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/messa.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/messa.jpg","width":259,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/care-signore-la-vera-arte-quella-che-si-fa-in-chiesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Care signore la vera arte &egrave; quella che si fa in chiesa"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3054"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3054\/revisions"}],"predecessor-version":[{"id":30548,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3054\/revisions\/30548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/30547"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}