{"id":3047,"date":"2009-04-16T17:01:49","date_gmt":"2009-04-16T15:01:49","guid":{"rendered":""},"modified":"2016-01-28T17:32:00","modified_gmt":"2016-01-28T16:32:00","slug":"attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\/","title":{"rendered":"Attenzione ad assolversi, bisogna lasciare la strada di ieri"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Giuliano-Ferrara.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-30033\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Giuliano-Ferrara.jpg\" alt=\"Giuliano Ferrara\" width=\"250\" height=\"131\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Giuliano-Ferrara.jpg 310w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Giuliano-Ferrara-300x157.jpg 300w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a>\u00a0Il Foglio<\/strong>,\u00a010 gennaio 2008<\/div>\n<p style=\"text-align: center;\">di <strong>Giuliano Ferrara<\/strong><\/p>\n<p style=\"text-align: justify;\">La verit\u00e0 sta dentro di noi Cara Ritanna, grazie per la lunga lettera. La molta dei tuoi ragionamenti e sentimenti \u00e8 che io condanno le donne, accuso le donne, giudico le donne che abortiscono.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Io giudico solo me stesso, accuso e condanno solo me stesso, e qualche volta sono come tutti straordinariamente indulgente.<\/p>\n<p style=\"text-align: justify;\">Quando ho risposto a Sofri e alle sue troppo umane provocazioni sulla vita personale, mi sono esposto per complicit\u00e0 in un triplice delitto d`aborto. Leggendo ora i tuoi ragionamenti sulle colpe della societ\u00e0, che condanna le donne ad abortire, mi sono accorto di essermi assolto in poche righe usando uno stile dolcificante che anche tu usi, e per giunta di avere pensato inconsciamente che fosse possibile cavarmela con una dieta liquida e con una buona azione.<\/p>\n<p style=\"text-align: justify;\">E ho fatto pure lo spiritoso e il cinico e il mondano prendendo in giro la mia stessa buona azione, scrivendo che non mi capacitavo di tanta audacia. Ma nella questione che si \u00e8 aperta ironia e pudore sanno di zolfo.<\/p>\n<p style=\"text-align: justify;\">Non essendo mai entrato in un confessionale, fuori dalla comunione con una chiesa che assolva, io mi sono assolto da solo con un espediente sofistico, retorico, della cui miseria mi accorgo solo adesso che tu mi riproponi la storia privata da me raccontata.<\/p>\n<p style=\"text-align: justify;\">Pensavo subliminalmente, aprendomi a me stesso e agli altri, di rendere chiare le responsabilit\u00e0 della cultura, dell`ambiente e dell`ideologia del tempo in cui quei tre delitti sono stati commessi con la mia attonita ma indifferente complicit\u00e0, e che questo servisse a spiegare le ragioni della mia rivolta contro la strage degli innocenti. Subliminalmente, cio\u00e8 con una falsa coscienza della cosa, cio\u00e8 ideologicamente.<\/p>\n<p style=\"text-align: justify;\">In realt\u00e0 io ho personalmente concorso a uccidere tre persone che oggi avrebbero dai venti ai trentacinque anni. La scienza genetica oggi me lo dice a chiare lettere, ma lo sapevo gi\u00e0 senza bisogno del microscopio del genetista, dell`ecografia e dell`amniocentesi. Lo sapevo, e tacqui perch\u00e9 non ero un giusto, e non lo sono tuttora. E ho usato violenza su tre donne, con il loro consenso, lasciando che usassero violenza contro di s\u00e9 e contro il loro e mio amore.<\/p>\n<p style=\"text-align: justify;\">E per lo stesso motivo: perch\u00e9 non ero, e non sono, un giusto. Affetto come sono dal complesso latino di Don Giovanni, dunque incapace di pentimento, mi sono inflitto una piccola punizione a me utile, non esente da orgoglio e narcisismo, nel quadro di una polemica pubblica con tutto il suo effimero trascinato dietro. E mi sono intimamente compiaciuto che molta gente scrivesse al giornale di pregare per me. Un orrore.<\/p>\n<p style=\"text-align: justify;\">Da un certo punto di vista, che \u00e8 quello personale e non quello di una campagna di informazione e cultura sacrosanta, il dramma del mio chiostro senza Dio e senza direttore spirituale \u00e8 poco pi\u00f9 di una farsa. Qualcosa di perfettamente corrispondente al mio uso paradossale della frase irridente sugli atei devoti.<\/p>\n<p style=\"text-align: justify;\">Tutto questo non era nelle mie intenzioni, ma che cosa contano le intenzioni? Il riscatto \u00e8 la grazia, di questo sono certo. La frase giusta, che non si declina n\u00e9 al femminile n\u00e9 al maschile, ma nel caso neutro e universale e pluripersonale della condizione umana e creaturale \u00e8 questa: mea culpa. Ma la grazia fa quello che vuole. E la sincerit\u00e0 di quella frase, che \u00e8 un credo, dalla grazia dipende.<\/p>\n<p style=\"text-align: justify;\">Altro che societ\u00e0. Ogni generazione si fa la societ\u00e0 che sa e che desidera: la nostra si \u00e8 fatta la societ\u00e0 del miliardo di aborti, alcuni per rispetto della privacy individuale, altri per liberare la Donna dall`obbligo procreativo, come si dice.<\/p>\n<p style=\"text-align: justify;\">Infine, ora e domani per migliorare la razza umana e se- lezionare i figli. Io non ci sto pi\u00f9. Punto.<\/p>\n<p style=\"text-align: justify;\">Dunque non condanno le donne e le loro coscienze, le loro decisioni, le loro scelte. N\u00e9 condanno la societ\u00e0 e la sua scala di valori, che \u00e8 importante ma alla fine solo un elemento parziale nella vita di questo mondo. Che la speranza non sia destinata a chiudersi nella riforma delle strutture sociali, nella soluzione politica, nell`utopia d\u00ec un pacifismo che si astrae per comodit\u00e0 morale dalla realt\u00e0 della condizione umana e del suo disordine, credo sia una testimonianza del nostro tempo, del secolo trascorso e di quello che ora avanza, pi\u00f9 ancora e prima che una splendente predicazione di Benedetto XVI.<\/p>\n<p style=\"text-align: justify;\">Giusto battersi per definire meglio la vita, dal concepimento alla morte naturale, nella Dichiarazione universale dei diritti dell`uomo di sessant`anni fa. Giusto correggere; nel senso che anche tu suggerisci, con Ruini e molti altri laici e cattolici e altrimenti credenti, le legislazioni abortiste.<\/p>\n<p style=\"text-align: justify;\">Giusto applicare il compromesso della 194 in modo non indifferente al valore della vita umana, strappando quella legge alla sua condizione totemica di idolo dell`autodeterminazione assoluta di una Donna che, ripeto, non esiste se non nel fumo ideologico che l`ha inventata. Giusto considerare con orrore la pillola Ru486<\/p>\n<p style=\"text-align: justify;\">Giusto non tornare indietro dalla tutela della salute contro l`aborto clandestino. Giusto contemplare casi di legittima difesa nello stroncare una vita nascente. Giusto rafforzare con ogni mezzo i volontari della vita, e tutti coloro che si impegnano nella professione medica e nel grande giro di cura della maternit\u00e0, considerando le donne incinte &#8220;soggetti sociali privilegiati&#8221;.<\/p>\n<p style=\"text-align: justify;\">Giusto mettere le politiche familiari antinataliste e omicide degli stati asiatici di fronte alle loro responsabilit\u00e0 da sostenere davanti al tribunale del valore universale della libert\u00e0 di nascere e del valore della differenza. Ma tutto questo non servirebbe a niente, e sarebbe impossibile da realizzare, se non trovassimo, se non troveremo, un pallido sostituto significativo alla grazia che ci \u00e8 mancata o che non abbiamo riconosciuto, al mea culpa che siamo incapaci di pronunciare con sincerit\u00e0 di testa e di cuore.<\/p>\n<p style=\"text-align: justify;\">Questo sostituto significativo, cosa minima ma indispensabile, \u00e8 la decisione infine razionale, alla quale ti associ nella tua lettera e di cui conosci le conseguenze, di stabilire, ristabilire, in modo certo e consequenziale, dentro le fibre della cultura e della pratica di vita che abbracciamo, che l`aborto \u00e8 un male, che la soppressione del diritto alla nascita \u00e8 da combattere &#8220;in modo intransigente&#8221;, come disse quel vecchiaccio inascoltato e illuminato di Bobbio, e per lo stesso principio, come lui concludeva, che ha indotto l`assemblea generale delle Nazioni Unite a chiedere la moratoria della pena di morte. Senza scantonare, cara Ritanna.<\/p>\n<p style=\"text-align: justify;\">Tu usi una parola che sembrava esclusa, insieme con il professor Buttiglione, dal vocabolario della gente civile che in Europa piace e si piace: la parola peccato. Dici: peccato d`omissione. Ma non si tratta di completare con una sfumatura di nuova ipocrisia un percorso di civilt\u00e0, mettendo insieme una cultura abortista e una nuova cultura della maternit\u00e0, eliminando in tutta fretta il peccato di omissione. Si tratta bens\u00ec di rovesciare la scelta di ieri.<\/p>\n<p style=\"text-align: justify;\">Come diceva Rilke, es war nur die Strasse von Gestern, era solo la strada di ieri. Quella di oggi \u00e8 diversa, \u00e8 un`altra, va nella direzione opposta, ed \u00e8 destinata a tutti noi, maschi e femmine. Non desiderare la vita d`altri, non confondere la tua con la vita di un altro se non sei disponibile alla vita di un altro ancora. Fate l`amore, non l`aborto.<\/p>\n<p style=\"text-align: justify;\">(A.C. Valdera)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Il Foglio,\u00a010 gennaio 2008 di Giuliano Ferrara La verit\u00e0 sta dentro di noi Cara Ritanna, grazie per la lunga lettera. La molta dei tuoi ragionamenti e sentimenti \u00e8 che io condanno le donne, accuso le donne, giudico le donne che abortiscono.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":30033,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2386],"class_list":["post-3047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aborto","tag-aborto","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Attenzione ad assolversi, bisogna lasciare la strada di ieri - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Attenzione ad assolversi, bisogna lasciare la strada di ieri - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-04-16T15:01:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-28T16:32:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Giuliano-Ferrara.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"310\" \/>\n\t<meta property=\"og:image:height\" content=\"163\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Attenzione ad assolversi, bisogna lasciare la strada di ieri\",\"datePublished\":\"2009-04-16T15:01:49+00:00\",\"dateModified\":\"2016-01-28T16:32:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\\\/\"},\"wordCount\":1199,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Giuliano-Ferrara.jpg\",\"keywords\":[\"Aborto\"],\"articleSection\":[\"Aborto\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\\\/\",\"name\":\"Attenzione ad assolversi, bisogna lasciare la strada di ieri - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Giuliano-Ferrara.jpg\",\"datePublished\":\"2009-04-16T15:01:49+00:00\",\"dateModified\":\"2016-01-28T16:32:00+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Giuliano-Ferrara.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/04\\\/Giuliano-Ferrara.jpg\",\"width\":310,\"height\":163},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Attenzione ad assolversi, bisogna lasciare la strada di ieri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Attenzione ad assolversi, bisogna lasciare la strada di ieri - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\/","og_locale":"it_IT","og_type":"article","og_title":"Attenzione ad assolversi, bisogna lasciare la strada di ieri - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-04-16T15:01:49+00:00","article_modified_time":"2016-01-28T16:32:00+00:00","og_image":[{"width":310,"height":163,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Giuliano-Ferrara.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Attenzione ad assolversi, bisogna lasciare la strada di ieri","datePublished":"2009-04-16T15:01:49+00:00","dateModified":"2016-01-28T16:32:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\/"},"wordCount":1199,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Giuliano-Ferrara.jpg","keywords":["Aborto"],"articleSection":["Aborto"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\/","name":"Attenzione ad assolversi, bisogna lasciare la strada di ieri - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Giuliano-Ferrara.jpg","datePublished":"2009-04-16T15:01:49+00:00","dateModified":"2016-01-28T16:32:00+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Giuliano-Ferrara.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/04\/Giuliano-Ferrara.jpg","width":310,"height":163},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/attenzione-ad-assolversi-bisogna-lasciare-la-strada-di-ieri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Attenzione ad assolversi, bisogna lasciare la strada di ieri"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=3047"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3047\/revisions"}],"predecessor-version":[{"id":30034,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/3047\/revisions\/30034"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/30033"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=3047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=3047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=3047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}