{"id":30081,"date":"2016-02-04T00:00:19","date_gmt":"2016-02-03T23:00:19","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=30081"},"modified":"2016-02-01T08:42:15","modified_gmt":"2016-02-01T07:42:15","slug":"unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\/","title":{"rendered":"UNIONI CIVILI. Un progetto nemico dell&#8217;uomo, della famiglia, della societ\u00e0 e di Dio"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/02\/unioni_civili.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-30082\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/02\/unioni_civili.jpg\" alt=\"unioni_civili\" width=\"250\" height=\"155\" \/><\/a>www.ilsussidiario.net <\/strong><\/p>\n<p style=\"text-align: center;\">venerd\u00ec 29 gennaio 2016<\/p>\n<p style=\"text-align: center;\"><strong>Antonio Lopez<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>docente di teologia e decano al Pontificio istituto Giovanni Paolo II per gli studi su matrimonio e famiglia di Washington, DC, legge il ddl Cirinn\u00e0<\/em><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Abbiamo chiesto al professor Antonio L\u00f3pez, docente di teologia e decano al Pontificio istituto Giovanni Paolo II per gli studi su matrimonio e famiglia di Washington, DC, di leggere il ddl Cirinn\u00e0. Ne \u00e8 scaturita la lunga conversazione che proponiamo. Si tratta, per L\u00f3pez, di un vero e proprio attacco al disegno di Dio, di cui lo Stato prende il posto: &#8220;Poich\u00e9 non esiste pi\u00f9 alcun criterio di verit\u00e0 che trascenda l&#8217;opinione e la volont\u00e0 soggettiva dell&#8217;uomo, lo Stato, in quanto soggetto legiferante, acquista un potere quasi divino&#8221;. L\u00f3pez affronta praticamente tutte le parole-chiave al centro dei nuovi diritti: verit\u00e0, coscienza, libert\u00e0, natura, genere, matrimonio, famiglia, unioni civili. La responsabilit\u00e0 del cristiano? &#8220;Annunciare che Dio si \u00e8 fatto uomo per salvare l&#8217;uomo, per rivelare pienamente l&#8217;uomo all&#8217;uomo&#8221;.<\/p>\n<p style=\"text-align: justify;\"><strong>Professor L\u00f3pez, che impressioni ha tratto dalla lettura del ddl Cirinn\u00e0?<\/strong><\/p>\n<p style=\"text-align: justify;\">Il disegno di legge presenta vari problemi. Tra i principali, c&#8217;\u00e8 la totale equiparazione delle unioni civili alla famiglia naturale, come evidente dai rinvii contenuti negli articoli 2 e 3 alla disciplina del matrimonio. Inoltre, estendendo il diritto anche a persone maggiorenni delle stesso genere, il ddl riconosce di fatto anche se non verbalmente il matrimonio omosessuale. Altro punto critico, se pur meno menzionato nel dibattito pubblico, \u00e8 \u2014 articoli 2.2, e 11 \u2014 la \u00abnon discriminazione in qualunque settore della vita pubblica e privata\u00bb. Questo \u00e8 un principio molto radicale, che comprensibilmente potr\u00e0 toccare anche la Chiesa (per esempio quanto ai criteri di assunzione di personale).<\/p>\n<p style=\"text-align: justify;\"><strong>Il nodo pi\u00f9 discusso \u00e8 quello sulle adozioni\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\">L&#8217;istanza \u00e8 comprensibile, perch\u00e9 l&#8217;unione nuziale tra l&#8217;uomo e la donna \u00e8 per natura aperta alla fecondit\u00e0. Quindi, dato che due persone che contraggono un&#8217;unione civile sono equiparate alla famiglia naturale, &#8220;devono&#8221; poter avere dei figli. Se sono dello stesso sesso, li otterranno con adozione garantita dallo Stato o attraverso metodi tecnologici. Ad esempio, se un uomo divorzia da sua moglie sposando un altro uomo, nel caso in cui vinca la causa ed ottenga la tutela del figlio, quest&#8217;ultimo sar\u00e0 costretto ad abitare con due pap\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>Eppure, tutti dicono di mettere davanti a tutto il bene del figlio\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\">In realt\u00e0, a me pare che il figlio sia sempre un retropensiero. Non \u00e8 visto come un dono frutto dell&#8217;amore dell&#8217;uomo e della donna, ma come qualcosa di ottenuto tramite l&#8217;aiuto dello Stato o i mezzi tecnologici.<\/p>\n<p style=\"text-align: justify;\"><strong>E&#8217; il &#8220;diritto&#8221; al figlio che il presidente della Cei, cardinale Bagnasco, ha contestato\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\">Certo. Questo modo di concepire il bambino \u2014 non come dono ma come &#8220;oggetto&#8221; che uno ha il diritto di possedere \u2014 \u00e8 una conseguenza del modo in cui il matrimonio viene concepito: siccome il matrimonio non \u00e8 un dono, ma \u00e8 un rapporto di cui i contraenti sono l&#8217;origine e in un certo senso anche il destino, allora anche il figlio \u00e8 una &#8220;cosa&#8221; che si produce. Non \u00e8 pi\u00f9 una persona, \u00e8 un oggetto. Basterebbe ascoltare la testimonianza di persone che sono state concepite in questi modi per rendersi conto di quanto essi soffrano, per non essere nati come frutto gratuito dell&#8217;amore dei genitori. Un&#8217;altra implicazione delle unioni cos\u00ec disciplinate \u00e8, poi, l&#8217;instabilit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>In che senso?<\/strong><\/p>\n<p style=\"text-align: justify;\">Per contrarre il patto basta iscriversi al registro in presenza di due testimoni. Se la revoca \u00e8 consensuale, lo scioglimento del patto \u00e8 immediato; se non consensuale, \u00e8 sufficiente un anno di tempo. Questa disciplina eliminerebbe di fatto il matrimonio civile, che, se capisco bene, in Italia ha una struttura parallela al sacramento, con impegni rilevanti e stabili, e per il quale peraltro \u00e8 gi\u00e0 previsto il divorzio breve (approvato poco pi\u00f9 di un anno fa, ndr). Con questa nuova legge non credo che il matrimonio civile verrebbe pi\u00f9 scelto da molti. Sembra poi che le unioni civili diano tutti i diritti e non richiedano quasi nessun dovere. Soprattutto, se le unioni civili prendono il posto del matrimonio civile, ne prenderanno anche il nome: vengono recepite a tutti gli effetti come matrimoni.<\/p>\n<p style=\"text-align: justify;\"><strong>Il ddl prevede &#8220;criteri e modalit\u00e0 di estensione alle unioni civili dei diritti spettanti ai nuclei famigliari&#8221;. Che portata ha questa estensione?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00c8 un punto fondamentale. La legge porta sempre dentro di s\u00e9 una concezione dell&#8217;uomo e dei rapporti fra gli uomini. Non \u00e8 mai, per cos\u00ec dire, antropologicamente neutra. Il ddl quindi afferma che il matrimonio naturale, che era una possibilit\u00e0 limitata a persone sessualmente differenti (un uomo e una donna), ora \u00e8 una categoria\/realt\u00e0 che viene estesa a persone dello stesso genere. Ma questa estensione non \u00e8 soltanto un cambiamento quantitativo, bens\u00ec qualitativo. Che persone dello stesso sesso abbiano un&#8217;istituzione comune, con gli stessi diritti di una famiglia, significa che tutte le unioni sono concepite in modo uguale. \u00c8 un cambiamento qualitativo.<\/p>\n<p style=\"text-align: justify;\"><strong>Ci spieghi perch\u00e9\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 la differenza sessuale e la connessa possibilit\u00e0 naturale della fecondit\u00e0 non sono pi\u00f9 parte della definizione essenziale dell&#8217;amore matrimoniale, come accade nell&#8217;unione fra un uomo e una donna. Questa legge stabilir\u00e0 come vero per tutti che il matrimonio \u00e8 fatto da persone il cui amore non c&#8217;entra nulla con la natura (e perci\u00f2 anche con l&#8217;uso) del proprio corpo. Si capisce, cos\u00ec, come una tale equiparazione stravolge il significato del legame tra l&#8217;uomo e la donna, del matrimonio in quanto tale e non si limita affatto ad estendere un &#8220;diritto&#8221;.<\/p>\n<p style=\"text-align: justify;\"><strong>Ci pu\u00f2 spiegare meglio cosa cambia alla radice?<\/strong><\/p>\n<p style=\"text-align: justify;\">Scompare l&#8217;idea di natura creata. La verit\u00e0 \u2014 in questo caso del matrimonio e della famiglia \u2014 coincide con ci\u00f2 che si fa: \u00e8 vero tutto (e solo) ci\u00f2 che \u00e8 possibile fare. Ripeto, questo ddl comunica una concezione dell&#8217;uomo, una nuova antropologia. La presuppone e, rendendola legge, istituzionalizzandola, la promuove. Parlare delle unioni civili \u00e8 parlare di che cos&#8217;\u00e8 l&#8217;uomo. Per questa ragione, \u00e8 ingenuo separare le questioni giuridiche da quelle antropologiche e pensare che mentre lo Stato gestisce neutralmente la vita sociale, altre istituzioni (la chiesa cattolica, le religioni, eccetera) hanno la responsabilit\u00e0 di spiegare il significato (religioso, umanistico) dell&#8217;uomo e della sua vita morale. Un esempio classico \u00e8 la legge sull&#8217;aborto, con la quale non soltanto passa a livello sociale l&#8217;idea che abortire non \u00e8 un male \u2014 o, quanto meno, un male minore e inevitabile \u2014, ma passa anche una nuova idea di ci\u00f2 che io sono, di che cos&#8217;\u00e8 l&#8217;amore, di che cosa sono la fecondit\u00e0 e il lavoro, di cosa posso fare con me stesso.<\/p>\n<p style=\"text-align: justify;\"><strong>Che cambiamento comporta innanzitutto per la persona?<\/strong><\/p>\n<p style=\"text-align: justify;\">L&#8217;uomo non si concepisce pi\u00f9 come dono: bens\u00ec come un essere astratto, avulso da ogni legame, un essere che non risponde di s\u00e9 a nessuno e a nulla. La vita non \u00e8 un dono che ci costituisce, che dobbiamo accogliere e a cui siamo chiamati a gratuitamente rispondere. Il corpo, di conseguenza, \u00e8 concepito come un artefatto, o meglio una &#8220;macchina&#8221; a mia disposizione per poter ottenere mediante il suo uso ci\u00f2 che io decido e voglio: il conclamato diritto di usare della capacit\u00e0 tecnologica di intervenire alla fine e soprattutto all&#8217;inizio della vita umana, mostra nel modo pi\u00f9 evidente questa riduzione del corpo umano a uno strumento che si vuole sempre pi\u00f9 malleabile ai desideri dell&#8217;uomo. Cambia anche il significato dei rapporti costitutivi dell&#8217;uomo \u2014 mi riferisco a figliolanza, maternit\u00e0, paternit\u00e0, nuzialit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>Ci spieghi\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\">Tutti questi rapporti costitutivi diventano rapporti legali. Non sono pi\u00f9 rapporti determinati dalla natura. \u00c8 lo Stato, che, assecondando la libert\u00e0 di ciascuno, definisce che cos&#8217;\u00e8 il matrimonio, chi \u00e8 figlio di chi, qual \u00e8 lo scopo della famiglia e il ruolo che ciascuno ha dentro di essa, eccetera. Tocchiamo in questo modo con mano l&#8217;ironico paradosso cui conduce la concezione liberale dello Stato \u2014 come ha implicitamente ammesso il giudice della Corte suprema americana Thomas, in un interessante passaggio della sua <em>dissenting opinion<\/em> in merito al caso <em>Obergefell vs. Hodges<\/em>, che ha portato alla legalizzazione federale del matrimonio gay negli Stati Uniti: &#8220;Nella tradizione legale americana \u2014 scrive il giudice Thomas \u2014 la libert\u00e0 \u00e8 sempre stata compresa come libert\u00e0 dall&#8217;intrusione del governo e non come diritto di ricevere un qualsivoglia titolo (<em>entitlment<\/em>) da parte del governo stesso&#8221; (\u2026) Tale apparente cambiamento, fa venire a galla in realt\u00e0 una tensione che giace latente all&#8217;origine della concezione liberale dello Stato, concepito come puro garante della libert\u00e0 individuale dei singoli e perci\u00f2 non autorizzato ad imporre alcuna verit\u00e0 che si pretenda &#8216;naturale&#8217;. Quella che sembrava modestia e non ingerenza \u2014 la rinuncia a proporre qualsivoglia &#8216;verit\u00e0&#8217; \u2014 trasforma paradossalmente lo Stato nel creatore stesso della verit\u00e0. Lo Stato non si limita a riconoscere una realt\u00e0 che gi\u00e0 esiste e gli uomini hanno da sempre riconosciuto come tale. Ne diviene il creatore. La soggezione del cittadino allo stato diviene qui assoluta, poich\u00e9 solo la legge dello Stato pu\u00f2 garantire all&#8217;individuo la libert\u00e0 di essere ci\u00f2 che vuole&#8221;.<\/p>\n<p style=\"text-align: justify;\">Se guardiamo alla dichiarazione con cui il giudice Kennedy ha giustificato la decisione della corte suprema di approvare il matrimonio gay, il paradosso diviene ancora pi\u00f9 chiaro. Con un&#8217;interpretazione molto discussa dell&#8217;emendamento 14, Kennedy afferma la natura costituzionale del matrimonio gay in nome del &#8220;diritto di ogni cittadino di definire la propria identit\u00e0&#8221;. Da una parte, dunque, il matrimonio gay appare come il punto di arrivo coerente della antropologia <em>liberal<\/em>: ci\u00f2 che definisce l&#8217;uomo non \u00e8 pi\u00f9 l&#8217;essere creato ad immagine di Dio, ma la sua libert\u00e0 che si autodetermina, senza nessun parametro. Dall&#8217;altra, poich\u00e9 non esiste pi\u00f9 alcun criterio di verit\u00e0 che trascenda l&#8217;opinione e la volont\u00e0 soggettiva dell&#8217;uomo, lo Stato, in quanto soggetto legiferante \u2014 senza entrare nella complessa domanda di chi di fatto rappresenti questo soggetto \u2014 acquista in realt\u00e0 un potere quasi &#8220;divino&#8221;: \u00e8 lo stato infatti che mi permette di essere ci\u00f2 che io non potrei essere senza il suo &#8220;<em>entitlement<\/em>&#8220;. Contro tale visione bisogna tornare a guardare una elementare verit\u00e0: l&#8217;autodeterminazione \u00e8 certamente un aspetto importante della libert\u00e0, ma non l&#8217;unico. La libert\u00e0 esiste ed entra in azione sempre e soltanto in risposta ad un dono, ad un &#8220;dato&#8221; che la precede: gli sposi dicono di s\u00ec ad un amore che \u00e8 stato dato loro. Questa idea di uomo come libert\u00e0 assoluta, cio\u00e8 come libert\u00e0 separata dalla verit\u00e0, \u00e8 un&#8217;astrazione che investe tutti i livelli della vita dell&#8217;uomo di oggi. Ma questa idea \u00e8 semplicemente falsa, astratta appunto.<\/p>\n<p style=\"text-align: justify;\"><strong>Lo stesso che vediamo nella teoria gender?<\/strong><\/p>\n<p style=\"text-align: justify;\">S\u00ec. In essa il genere non \u00e8 pi\u00f9 un sostantivo, cio\u00e8 qualcosa che definisce il tuo essere in modo inalienabile (tu sei donna, per esempio), ma diviene un verbo, qualcosa che tu fai. Il &#8220;genere&#8221; oggi \u00e8 qualcosa che uno fa e la legge riconosce. Sempre pi\u00f9 le leggi negli Stati Uniti definiscono il genere come l&#8217;identit\u00e0 che viene (legalmente) assegnata dai genitori quando il bambino \u00e8 nato, identit\u00e0 che il bambino potr\u00e0 cambiare una volta che decida (o scopra) qual \u00e8 l&#8217;identit\u00e0 sessuale con la quale si trova pi\u00f9 a suo agio. Questo modo di pensare il genere \u00e8 anche frutto della tecnologia: se, per esempio, due omosessuali possono pretendere che la loro unione sia equiparata al matrimonio \u00e8 perch\u00e9 ci sono dei metodi biotecnologici per procurarsi un figlio. Se un maschio pu\u00f2 chiedere di essere riconosciuto come donna \u00e8 perch\u00e9 oggi si possono fare degli interventi chirurgici\/medici che rendono possibile la trasformazione di questa pretesa in realt\u00e0. L&#8217;implicazione che ne segue, ancora una volta, \u00e8 che il corpo sessuato, cosi come il suo ordinamento alla fecondit\u00e0, sono secondari, quindi non necessari, non costitutivi dell&#8217;amore sponsale.<\/p>\n<p style=\"text-align: justify;\"><strong>Lei ha detto: &#8220;I legami costitutivi della persona non sono pi\u00f9 naturali, ma legali&#8221;. Pu\u00f2 spiegare meglio?<\/strong><\/p>\n<p style=\"text-align: justify;\">Se non c&#8217;\u00e8 pi\u00f9 la natura, a prendere il suo posto \u00e8 la legge positiva. Non resta mai un vuoto. Siccome l&#8217;uomo deve vivere &#8220;in societ\u00e0&#8221;, i rapporti umani non rispecchiano o assicurano un bene esistente di per s\u00e9, ma diventano legali, assicurati dallo Stato. Un esempio: se due persone dello stesso sesso possono adottare figli, vuol dire che paternit\u00e0 e maternit\u00e0 sono considerati dei ruoli. Peraltro intercambiabili. Il legame \u00e8 fissato per legge ed \u00e8 ridotto, appunto, a quello che si fa, e che quindi chiunque pu\u00f2 fare al mio posto. Al fondo, ripeto, c&#8217;\u00e8 una precisa concezione di libert\u00e0 sganciata da una verit\u00e0 che riconosco ma non faccio io: la libert\u00e0 come capacit\u00e0 di azione che determina le cose.<\/p>\n<p style=\"text-align: justify;\">Ora, se \u00e8 vero che \u00e8 la legge positiva a permettere alla libert\u00e0 di esercitare il suo potere, allora si capisce il perch\u00e9 della necessit\u00e0 di moltiplicare leggi su leggi tipico della societ\u00e0 liberal. Si veda l&#8217;esempio Usa. Ma questa moltiplicazione di leggi e regolamentazioni non pu\u00f2 sostituire il bisogno di certezza e di stabilit\u00e0 propria dell&#8217;uomo. Che lo Stato garantisca forme cos\u00ec instabili come le unioni civili \u00e8 un male per tutta la societ\u00e0. Come pu\u00f2 sussistere una societ\u00e0 nella quale uno non pu\u00f2 essere certo dei rapporti costitutivi (figliolanza, nuzialit\u00e0, paternit\u00e0, e maternit\u00e0), e quindi dell&#8217;esistenza di legami che non sia dipendenti dall&#8217;emozione sempre transitoria e dalla volont\u00e0 sempre mutevole degli individui?<\/p>\n<p style=\"text-align: justify;\"><strong>Immagino che lei risponda negativamente a questa domanda retorica, per sottolineare la conseguenza logica che scaturisce dalle premesse\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\">Se \u00e8 vero tutto ci\u00f2 che \u00e8 possibile e fattibile, allora la rivoluzione diventa un principio permanente. Per esempio: se in un&#8217;unione le cose non vanno o non si ottiene lo scopo per cui si era insieme, si pu\u00f2 cambiare molto facilmente. Ma l&#8217;amore per natura \u00e8 fedele e fecondo. Nell&#8217;instabilit\u00e0 si fa soffrire e si soffre. Il sentimentalismo, alla base di questa concezione dei legami, \u00e8 inevitabilmente violento, perch\u00e9 mi porta a tentare di ottenere ci\u00f2 che desidero a tutti i costi, imponendo la mia volont\u00e0 sulla realt\u00e0 e sugli altri.<\/p>\n<p style=\"text-align: justify;\"><strong>Negli Usa vedete le conseguenze di quest&#8217;instabilit\u00e0?<\/strong><\/p>\n<p style=\"text-align: justify;\">Qui il matrimonio omosessuale \u00e8 legge, ovvero \u00e8 diventato norma (da giugno scorso). Questo non ha affatto dato avvio ad una corsa degli omosessuali a sposarsi. L&#8217;effetto \u00e8 piuttosto il rafforzarsi di una mentalit\u00e0 che trasforma dal punto di vista concettuale anche il matrimonio naturale. La persona si concepisce come libert\u00e0 che si autodetermina. Il desiderio \u00e8 identificato con l&#8217;inclinazione soggettiva che si prova, e l&#8217;amore e la fecondit\u00e0 sono sottomessi al primato di tale inclinazione. Lo scopo del matrimonio diviene la propria soddisfazione emotiva e cosi il divorzio entra latentemente dentro la forma stessa del matrimonio, in quanto esso non richiede pi\u00f9 la donazione totale (e perci\u00f2 irrevocabile) degli sposi l&#8217;uno all&#8217;altro, ma piuttosto l&#8217;aiutarsi a vicenda a soddisfare l&#8217;uno il desiderio dell&#8217;altro.<\/p>\n<p style=\"text-align: justify;\"><strong>Altre implicazioni?<\/strong><\/p>\n<p style=\"text-align: justify;\">La legge costringe anche a ripensare l&#8217;educazione. Se la legge riconosce un certo tipo di uomo, la scuola e la famiglia devono educare a tale concezione. Quello che si vede sempre di pi\u00f9 \u00e8 che la societ\u00e0 liberale va instaurando un nuovo totalitarismo. Si deve eliminare tutto ci\u00f2 che ostacola l&#8217;esercizio della libert\u00e0 individuale, da una visione del corpo come rivelatore del mistero della persona, alla stabilit\u00e0 matrimoniale, al divieto per l&#8217;uomo di essere signore della vita propria e altrui (si veda l&#8217;approvazione di aborto ed eutanasia). Questo totalitarismo \u00e8 pi\u00f9 sottile dei totalitarismi che abbiamo conosciuto nel passato, \u00e8 in un certo senso invisibile. Esso esercita il suo potere pi\u00f9 attraverso la burocrazia e le leggi &#8220;volute da tutti&#8221; che attraverso un &#8220;dittatore&#8221; o un &#8220;piccolo gruppo&#8221; che ha afferrato il potere.<\/p>\n<p style=\"text-align: justify;\"><strong>Ma allora, cosa sono i &#8220;nuovi diritti&#8221;?<\/strong><\/p>\n<p style=\"text-align: justify;\">E&#8217; importante ponderare bene le parole: il termine &#8220;diritto&#8221; oggi \u00e8 compreso soprattutto come &#8220;protezione della nostra capacit\u00e0 di esercitare il potere che la nostra libert\u00e0 ci conferisce&#8221;. Avere un diritto, la dove non si riconosce pi\u00f9 che la vita \u00e8 data e quindi la libert\u00e0 deve rispondere del dono ricevuto a Colui che l&#8217;ha data, significa essere abilitati a fare ci\u00f2 che si pu\u00f2 e si vuole fare. Molte volte, quando per esempio si parla dei diritti dei bambini, pur volendo proteggere il bene dei pi\u00f9 piccoli, si adotta un linguaggio che ci impone di guardare ai bambini come se fossero adulti, cio\u00e8 come persone indipendenti che devono poter esercitare la loro libert\u00e0. La parola &#8220;diritto&#8221;, invece, ha una storia e un senso assai pi\u00f9 ricco. Purtroppo essa \u00e8 ridotta oggi a significare &#8220;libert\u00e0 da ogni coercizione&#8221;, libert\u00e0 di esercizio delle proprie capacit\u00e0 o desideri. Ci\u00f2 che \u00e8 nuovo, direi quindi, non \u00e8 tanto l&#8217;esistenza di &#8220;diritti&#8221;\u2026<\/p>\n<p style=\"text-align: justify;\"><strong>Ma che questi diritti esprimono un&#8217;antropologia\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\">Certo: un&#8217;antropologia che non \u00e8 amica dell&#8217;uomo. Nonostante le pretese di neutralit\u00e0, quello che c&#8217;\u00e8 in gioco in una tale idea di diritto \u00e8 anche una metafisica della libert\u00e0, cio\u00e8 una definizione di libert\u00e0 come esercizio della propria libert\u00e0 di scelta, indipendentemente da ogni legame col vero e il bene. Secondo la visione classica, non solo cristiana ma, per esempio, anche greco-romana, la libert\u00e0 presuppone un ordine, un contesto cosmico nel quale esiste e si esercita. La libert\u00e0 \u00e8 data per gustare il vero bene, che non \u00e8 alla merce delle mode e della volont\u00e0 dei singoli. Ma ci\u00f2 presuppone che verit\u00e0 e bene siano reali, intrinseci all&#8217;ordine delle cose, e che l&#8217;uomo sia ordinato ad essi per natura. Ogni mia scelta parziale (anche quella della mia vocazione, per esempio) avviene all&#8217;interno del rapporto con il vero bene ed \u00e8 sempre un passo verso o lontano dal mio destino, dal bene. Ora, questa visione viene radicalmente negata nella nostra societ\u00e0 liberal. In essa, ogni individuo fissa sia i propri fini sia il modo in cui raggiungerli. La libert\u00e0 \u00e8 compresa come neutra, cio\u00e8 come non originariamente in moto verso il bene, attratta da esso, ma come indifferente, cio\u00e8 capace di scegliere senza essere attratta da nessuno e da niente. L&#8217;attrattiva stessa diviene nemica. Quindi, in fondo, non c&#8217;\u00e8 pi\u00f9 n\u00e9 bene n\u00e9 male.<\/p>\n<p style=\"text-align: justify;\"><strong>Perch\u00e9 una mentalit\u00e0 che relativizza e colpisce la famiglia chiede unioni simili al matrimonio, con anche la responsabilit\u00e0 dei figli?\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\">Tenendo presente che stiamo giudicando una concezione e non le singole persone, possiamo dire che la situazione \u00e8 assai complessa. In sostanza, tra i sostenitori di queste leggi non ci sono posizioni omogenee. Una giornalista omosessuale del New York Times, Masha Gessen, per esempio dice: &#8220;Lottare per avere il matrimonio gay implica il mentire circa il vero scopo che intendiamo raggiungere, una volta ottenutolo. Noi infatti diciamo che l&#8217;istituzione del matrimonio non cambier\u00e0. E questa \u00e8 una menzogna. L&#8217;istituzione del matrimonio cambier\u00e0, e deve cambiare\u2026 anzi, io penso che non dovrebbe pi\u00f9 esistere&#8221;. A ben guardare, come abbiamo gi\u00e0 rilevato sopra, l&#8217;esigenza del riconoscimento legale sembra che contraddica l&#8217;idea centrale dell&#8217;antropologia liberal: e cio\u00e8 il principio dell&#8217;autodeterminazione assoluta del singolo. Tuttavia, proprio questo \u00e8 il paradosso: quando il posto della natura viene preso dalla legge, si pu\u00f2 essere veramente liberi solo grazie al riconoscimento legale. Se il legame non \u00e8 riconosciuto, il legame non c&#8217;\u00e8: \u00e8 la legge a farlo esistere.<\/p>\n<p style=\"text-align: justify;\"><strong>Qual \u00e8 la responsabilit\u00e0 del cristiano di fronte a tutto questo?<\/strong><\/p>\n<p style=\"text-align: justify;\">E&#8217; una grande responsabilit\u00e0: l&#8217;annuncio della fede. Annunciare che Dio si \u00e8 fatto uomo per salvare l&#8217;uomo, per rivelare pienamente l&#8217;uomo all&#8217;uomo (Gaudium et spes, 22). Ci sono stati tempi, pensiamo per esempio alla crisi dell&#8217;arianesimo, in cui la verit\u00e0 di fede da difendere era che l&#8217;uomo nato da Maria fosse veramente il Figlio di Dio, consustanziale al Padre, veramente Dio. La verit\u00e0 che oggi ha pi\u00f9 bisogno di essere difesa \u00e8 piuttosto la verit\u00e0 dell&#8217;uomo, cos\u00ec come Ges\u00f9 Cristo ne rivela la piena dignit\u00e0 e bellezza. Occorre sempre meglio comprendere ed annunciare la verit\u00e0 dell&#8217;uomo che in Cristo risplende a tutti i livelli: dalle nostre piccole comunit\u00e0 creative alle scuole, dai dibattiti sulle leggi, all&#8217;arena politica\u2026 ciascuno l\u00ec dov&#8217;\u00e8 chiamato e secondo la responsabilit\u00e0 e i talenti che ha. Le unioni civili non sono una questione tangenziale, perch\u00e9 la famiglia \u00e8 questione centrale, \u00e8 il primo luogo dove ciascuno scopre chi \u00e8, cosa vuol dire vivere da e per un altro, cos&#8217;\u00e8 l&#8217;amore\u2026 Non si pu\u00f2 cadere nel tranello di pensare che possa esistere un diritto per cosi dire neutrale, che non prenda posizione rispetto alla definizione della natura dell&#8217;uomo, come se potesse esserci un ordine sociale che prescinda da una precisa visione dell&#8217;uomo. Certo, legge e concezione filosofico-religiosa dell&#8217;uomo non sono mai identificabili, ma non sono mai nemmeno separabili. In questo, la responsabilit\u00e0 del cristiano \u00e8 grande e bella. Anche decisamente drammatica, aggiungerei.<\/p>\n<p style=\"text-align: justify;\"><strong>Dove stiamo andando?<\/strong><\/p>\n<p style=\"text-align: justify;\">Bisogna essere consapevoli che, al di l\u00e0 di tanti beni che ha portato la civilt\u00e0 occidentale, la logica liberal, che separa libert\u00e0 e verit\u00e0 ultima, porta al nichilismo \u2014 come aveva gi\u00e0 acutamente profetizzato Nietzsche \u2014 il che significa all&#8217;autodistruzione dell&#8217;uomo. Ora vediamo pi\u00f9 chiaramente di lui le conseguenze di tale separazione. Il cristiano \u00e8 chiamato a custodire la verit\u00e0 dell&#8217;essere, la verit\u00e0 dell&#8217;amore. Custodire vuole dire non solo proteggere, ma anche proporre a tutti, con umilt\u00e0 e insieme con coraggio e decisione, ci\u00f2 che Cristo ha rivelato dell&#8217;uomo e di Dio.<\/p>\n<p style=\"text-align: justify;\"><strong>Cristo svela anche l&#8217;uomo a se stesso, diceva. Questo cosa comporta verso le leggi?\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\">Cristo, rivelando che Dio vuole l&#8217;uomo come Figlio Suo, ha rivelato &#8220;chi \u00e8&#8221; l&#8217;uomo. Ogni cristiano deve annunciare a tutti i livelli cosa significa questo, cosa significa che la verit\u00e0 dell&#8217;uomo \u00e8 di essere dono \u2014 come scriveva don Giussani nell&#8217;ottavo capitolo di All&#8217;origine della pretesa cristiana. Un nota bene: occorre vivere la testimonianza evitando il rischio di cadere nell&#8217;attivismo, o nella logica del successo. Non ci si pu\u00f2 illudere che il compito del cristiano si esaurisca nell&#8217;organizzare manifestazioni di piazza. Detto questo, per\u00f2, non ci si pu\u00f2 sottrarre al compito: che il popolo cristiano chieda che il matrimonio riconosciuto dallo Stato sia quello naturale non \u00e8 affatto un&#8217;ingerenza mossa da integralismo religioso. Si cerca di difendere il riconoscimento da sempre costante nella storia dell&#8217;umanit\u00e0, non solo cristiana, che il vero bene dell&#8217;amore nuziale \u00e8 quello determinato da Dio sin dall&#8217;inizio e cos\u00ec ben visibile nella differenza sessuale tra l&#8217;uomo e la donna.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>www.ilsussidiario.net venerd\u00ec 29 gennaio 2016 Antonio Lopez docente di teologia e decano al Pontificio istituto Giovanni Paolo II per gli studi su matrimonio e famiglia di Washington, DC, legge il ddl Cirinn\u00e0<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":30082,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[2208,196],"class_list":["post-30081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famiglia","tag-legge-cirinna","tag-unioni-civili","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UNIONI CIVILI. Un progetto nemico dell&#039;uomo, della famiglia, della societ\u00e0 e di Dio - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UNIONI CIVILI. Un progetto nemico dell&#039;uomo, della famiglia, della societ\u00e0 e di Dio - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-03T23:00:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/02\/unioni_civili.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"285\" \/>\n\t<meta property=\"og:image:height\" content=\"177\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"UNIONI CIVILI. Un progetto nemico dell&#8217;uomo, della famiglia, della societ\u00e0 e di Dio\",\"datePublished\":\"2016-02-03T23:00:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\\\/\"},\"wordCount\":3646,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/unioni_civili.jpg\",\"keywords\":[\"legge Cirinn\u00e0\",\"unioni civili\"],\"articleSection\":[\"Famiglia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\\\/\",\"name\":\"UNIONI CIVILI. Un progetto nemico dell'uomo, della famiglia, della societ\u00e0 e di Dio - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/unioni_civili.jpg\",\"datePublished\":\"2016-02-03T23:00:19+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/unioni_civili.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/02\\\/unioni_civili.jpg\",\"width\":285,\"height\":177},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UNIONI CIVILI. Un progetto nemico dell&#8217;uomo, della famiglia, della societ\u00e0 e di Dio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UNIONI CIVILI. Un progetto nemico dell'uomo, della famiglia, della societ\u00e0 e di Dio - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\/","og_locale":"it_IT","og_type":"article","og_title":"UNIONI CIVILI. Un progetto nemico dell'uomo, della famiglia, della societ\u00e0 e di Dio - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2016-02-03T23:00:19+00:00","og_image":[{"width":285,"height":177,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/02\/unioni_civili.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"18 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"UNIONI CIVILI. Un progetto nemico dell&#8217;uomo, della famiglia, della societ\u00e0 e di Dio","datePublished":"2016-02-03T23:00:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\/"},"wordCount":3646,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/02\/unioni_civili.jpg","keywords":["legge Cirinn\u00e0","unioni civili"],"articleSection":["Famiglia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\/","name":"UNIONI CIVILI. Un progetto nemico dell'uomo, della famiglia, della societ\u00e0 e di Dio - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/02\/unioni_civili.jpg","datePublished":"2016-02-03T23:00:19+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/02\/unioni_civili.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/02\/unioni_civili.jpg","width":285,"height":177},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/unioni-civili-un-progetto-nemico-delluomo-della-famiglia-della-societa-e-di-dio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"UNIONI CIVILI. Un progetto nemico dell&#8217;uomo, della famiglia, della societ\u00e0 e di Dio"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/30081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=30081"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/30081\/revisions"}],"predecessor-version":[{"id":30083,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/30081\/revisions\/30083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/30082"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=30081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=30081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=30081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}