{"id":29886,"date":"2016-01-28T00:00:56","date_gmt":"2016-01-27T23:00:56","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=29886"},"modified":"2016-01-26T08:33:31","modified_gmt":"2016-01-26T07:33:31","slug":"la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\/","title":{"rendered":"La verit\u00e0 sulle unioni civili. Domande e risposte per capire meglio il ddl Cirinn\u00e0"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/unioni-civili.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-29887\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/unioni-civili.jpg\" alt=\"unioni civili\" width=\"250\" height=\"143\" \/><\/a>Tempi <\/strong>23 gennaio 2016<\/p>\n<p style=\"text-align: justify;\"><em>Cosa sono e come si differenziano dal matrimonio? Davvero \u201cce le chiedono Bruxelles e la Corte costituzionale\u201d? La<\/em> stepchild adoption <em>apre all\u2019utero in affitto?<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Giancarlo Cerrelli<\/strong><\/p>\n<p style=\"text-align: center;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">A pochi giorni dall\u2019inizio della discussione, presso l\u2019aula del Senato, del disegno di legge sulle unioni civili, \u00e8 opportuno fare chiarezza su molti luoghi comuni, che, purtroppo, sono accettati come veri da molti italiani.<\/p>\n<p style=\"text-align: justify;\"><strong>Che cosa sono le<\/strong> <strong>unioni civili tra persone dello stesso sesso cos\u00ec come previste dal disegno di legge che sar\u00e0 discusso dalla fine di gennaio presso il Senato?<\/strong><\/p>\n<p style=\"text-align: justify;\">Le unioni civili tra persone dello stesso sesso sono una costruzione giuridica di dubbia costituzionalit\u00e0 e connotata da una forte valenza ideologica, con la quale s\u2019intenderebbe dare rilevanza giuridica al rapporto affettivo tra due partner dello stesso sesso, con una disciplina simile a quella prevista per il matrimonio.<\/p>\n<p style=\"text-align: justify;\"><strong>Quali sono i punti salienti del disegno di legge sulle unioni civili?<\/strong><\/p>\n<p style=\"text-align: justify;\">Per la costituzione di un\u2019unione civile sar\u00e0 necessaria la celebrazione di un rito davanti all\u2019ufficiale di Stato civile, alla presenza di due testimoni e si render\u00e0 una promessa di impegno, cos\u00ec come nel matrimonio. Si dar\u00e0, dunque, lettura degli articoli del codice civile da cui deriver\u00e0 l\u2019obbligo reciproco alla fedelt\u00e0, all\u2019assistenza morale e materiale e alla coabitazione, come nel matrimonio. I \u201cciviluniti\u201d, altres\u00ec, potranno stabilire di assumere un cognome comune scegliendolo tra i loro cognomi; avranno il diritto alla pensione di reversibilit\u00e0 del partner, godranno del medesimo regime patrimoniale e successorio che il codice civile riconosce ai coniugi e come se ci\u00f2 non bastasse il disegno di legge stabilisce che tutte le disposizioni che si riferiscono al matrimonio e le disposizioni contenenti le parole \u00abconiuge\u00bb, \u00abconiugi\u00bb, in qualsiasi disposizione legislativa ricorrano, si applicheranno anche a ognuna delle parti dell\u2019unione civile tra persone dello stesso sesso.<\/p>\n<p style=\"text-align: justify;\">L\u2019equiparazione, per\u00f2, tra unioni civili e matrimonio non solo \u00e8 inopportuna e ingiusta, ma \u00e8 anche dannosa, poich\u00e9 la creazione giuridica di nuovi modelli \u201cfamiliari\u201d apre la strada a una ridefinizione del concetto di famiglia che depotenzia la vera famiglia: tante famiglie, nessuna famiglia. La norma, tuttavia, pi\u00f9 controversa e inaccettabile del disegno di legge \u00e8 quella che prevede la cosiddetta stepchild adoption, cio\u00e8 l\u2019adozione del figlio naturale o adottivo del partner omosessuale.<\/p>\n<p style=\"text-align: justify;\"><strong>Quali sono le differenze tra le unioni civili e il matrimonio?<\/strong><\/p>\n<p style=\"text-align: justify;\">Sostanzialmente nessuna. Il disegno di legge, di fatto, fa continui rimandi alla disciplina che il nostro ordinamento prevede per il matrimonio. Nel disegno di legge, l\u2019unione civile \u2013 con il pretesto di differenziarla dal matrimonio \u2013 \u00e8 definita come \u201cspecifica formazione sociale\u201d; tale definizione, per\u00f2, \u00e8 soltanto un elemento di facciata, perch\u00e9 nella sostanza la disciplina che il disegno di legge prevede per le unioni civili \u00e8 identica a quella del matrimonio. Il testo che sar\u00e0 all\u2019esame del Senato, pur non prevedendo formalmente l\u2019adozione piena, prevede come detto l\u2019adozione del figlio naturale o adottivo del partner omosessuale. Tale istituto \u00e8 inaccettabile non solo perch\u00e9 rafforza il business della fecondazione eterologa e apre la strada alla vergognosa pratica dell\u2019utero in affitto, che in alcuni paesi \u00e8, purtroppo, ammessa. Ma soprattutto perch\u00e9 non tiene conto di quei bambini che non potranno godere della ricchezza che si \u00e8 soliti ricevere dal crescere in un rapporto di complementariet\u00e0 e differenza di ruoli che la natura ha voluto indicare in una famiglia costituita da un padre e una madre.<\/p>\n<p style=\"text-align: justify;\"><strong>Quale scopo ha questo disegno di legge?<\/strong><\/p>\n<p style=\"text-align: justify;\">I promotori del disegno di legge sulle unioni civili affermano che il loro scopo \u00e8 di far riconoscere alle coppie omosessuali gli stessi diritti di cui godono le coppie eterosessuali coniugate, cos\u00ec da rimuovere un\u2019inaccettabile disparit\u00e0 di trattamento. Tale rivendicazione pu\u00f2 apparire a molti, anche ad alcuni cattolici, innocua e persino giusta; invero tale pretesa, che non \u00e8 una priorit\u00e0, \u00e8 profondamente iniqua e nasconde, altres\u00ec, un fine ideologico e simbolico. Infatti, essa tutela esclusivamente i desideri degli adulti, senza tener conto dei diritti dei bambini, cui \u00e8 negato il diritto pi\u00f9 naturale di questo mondo: quello di avere per genitori un padre e una madre. \u00c8 triste costatare la chiara visione adultocentrica del progetto di legge. Alle coppie omosessuali si vuole dare l\u2019agio, per via legislativa, di procurarsi un figlio. \u00c8 qui chiara ed evidente la pretesa simbolica e ideologica di tali unioni. D\u2019altra parte, chi promuove le unioni civili rifiuta categoricamente un\u2019attribuzione ai conviventi omosessuali di meri diritti individuali \u2013 diritto all\u2019assistenza del convivente in ospedale, in carcere e cos\u00ec via, gi\u00e0 ampiamente riconosciuti dall\u2019ordinamento giuridico \u2013 mentre esige che siano riconosciuti i medesimi diritti propri del matrimonio alle coppie omosessuali, in quanto coppie.<\/p>\n<p style=\"text-align: justify;\"><strong>Che cosa cela tale pretesa simbolica e ideologica di uguaglianza?<\/strong><\/p>\n<p style=\"text-align: justify;\">Dietro a tale richiesta di uguaglianza si cela l\u2019intento di voler decostruire le basi antropologiche, finora fondamento della societ\u00e0, per ricostruirle su basi che intendono un diritto non pi\u00f9 orientato alla lettura del reale, ma come strumento per trasformare la realt\u00e0; che giunge a considerare diritti dei meri desideri. Il disegno di legge sulle unioni civili omosessuali risponde a un desiderio emulativo nei confronti delle coppie eterosessuali. I rapporti omosessuali ed eterosessuali, per\u00f2, sono antropologicamente diversi e il diritto dovrebbe tenerne conto. Il diritto, infatti, tutela interessi sociali, non rapporti affettivi, altrimenti tutti i legami di amicizia dovrebbero essere legittimamente tutelati dall\u2019ordinamento giuridico. Il vincolo matrimoniale \u00e8 storicamente tutelato perch\u00e9 funzionale all\u2019ordine delle generazioni.<\/p>\n<p style=\"text-align: justify;\">La vera ragione per cui il nostro ordinamento giuridico d\u00e0 rilevanza al matrimonio, non \u00e8 per il fatto che due persone provino affetto l\u2019una per l\u2019altra, ma perch\u00e9 un\u2019unione matrimoniale \u00e8 potenzialmente feconda e crea un sistema di educazione e inserimento sociale delle nuove generazioni. La tutela giuridica di cui godono le coppie coniugate a differenza delle unioni omosessuali non pu\u00f2 essere considerata una discriminazione, in quanto le due fattispecie rispondono a due situazioni differenti, che non possono essere trattate in egual modo, pena il commettere una profonda ingiustizia nei confronti dell\u2019unica famiglia riconosciuta dal nostro ordinamento giuridico.<\/p>\n<p style=\"text-align: justify;\"><strong>Un\u2019approvazione del disegno di legge sulle unioni civili senza l\u2019art. 5 che prevede la stepchild adoption sarebbe accettabile?<\/strong><\/p>\n<p style=\"text-align: justify;\">Un\u2019approvazione del disegno di legge con lo stralcio della stepchild adoption o con la previsione dell\u2019affido rafforzato non sarebbe accettabile, perch\u00e9 non muterebbe il carattere ideologico del provvedimento, che, peraltro, manterrebbe la struttura di un simil-matrimonio. Infatti: a) Saremmo di fronte a una vera e propria ingiustizia di dubbia costituzionalit\u00e0, perch\u00e9 due fattispecie strutturalmente differenti come unioni civili e matrimonio, sarebbero disciplinate in egual modo pur essendo ontologicamente diverse. b) L\u2019adozione, anche nel caso in cui non dovesse essere inserita in prima battuta nel disegno di legge, tuttavia non tarderebbe a essere riconosciuta legittima dalle corti di giustizia, com\u2019\u00e8 avvenuto anche in altri Stati. Due fattispecie analoghe, aventi la medesima disciplina, come il matrimonio e il disegno di legge sulle unioni civili, non potrebbero, a giudizio delle corti, essere trattate in modo differente e dunque in poco tempo le unioni omosessuali verrebbero in tutto a essere equiparate al matrimonio, anche riguardo all\u2019adozione piena. Differente sarebbe il caso in cui il Parlamento approvasse un testo unico ricognitivo di tutti i diritti che il nostro ordinamento gi\u00e0 riconosce ai conviventi, compresi quelli omosessuali.<\/p>\n<p style=\"text-align: justify;\"><strong>Perch\u00e9 si teme che la <em>stepchild adoption<\/em> possa aprire la strada all\u2019abominevole pratica dell\u2019utero in affitto?<\/strong><\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 ne \u00e8 un\u2019immediata conseguenza. In Italia l\u2019utero in affitto \u00e8 vietato dalla legge 40, ma non lo \u00e8 in altri paesi. Com\u2019\u00e8 accaduto pi\u00f9 di una volta in Italia, sono stati proprio i giudici a non punire chi \u00e8 tornato dall\u2019estero con il bimbo in braccio, frutto di un utero in affitto. Nel momento in cui ci si trova di fronte a casi di utero in affitto, il reato contestato dalle procure \u00e8 solitamente l\u2019alterazione di stato civile del minore, cio\u00e8 l\u2019aver dichiarato falsamente di essere genitori del piccolo; tuttavia i giudici prevalentemente hanno pi\u00f9 volte ritenuto che non fosse configurabile il reato di alterazione di stato civile quando i coniugi avessero sottoscritto l\u2019atto di nascita ottenuto nel paese estero, in qualit\u00e0 di genitori.<\/p>\n<p style=\"text-align: justify;\">Come ho detto sopra, infatti, saranno proprio le corti di giustizia ad ammettere ci\u00f2 che il legislatore non avr\u00e0 ritenuto di prevedere. Basti pensare ad alcuni orientamenti giudiziari di apertura verso la pratica dell\u2019utero in affitto, che auspicano \u2013 vedi Tribunale di Napoli del 17 luglio 2015 \u2013 che siano ammessi in Italia \u00abprogetti di genitorialit\u00e0 privi di legami biologici con il nato\u00bb diversi dall\u2019adozione; ovvero la sentenza del tribunale di Varese del 7 novembre 2014 che sostiene che \u00e8 divenuto irrilevante il metodo di concepimento e che dunque le false dichiarazioni rese dai falsi genitori a un pubblico ufficiale siano da ritenersi un danno innocuo e quindi non punibile.<\/p>\n<p style=\"text-align: justify;\">Tutto ci\u00f2 consentir\u00e0 a due partner omosessuali di \u201cprocurarsi\u201d facilmente un figlio. Vediamo come: uno dei partner omosessuali di un\u2019unione civile si \u201cprocurer\u00e0\u201d un figlio all\u2019estero, comprando l\u2019utero di una donna, poi una volta giunto in Italia con il bimbo, tramite la <em>stepchild adoption<\/em>, consentir\u00e0 al proprio partner di diventare genitore adottivo. Certamente interverr\u00e0 il controllo dei giudici, ma tale controllo invece di tranquillizzare preoccupa, perch\u00e9 se gi\u00e0 ora che non vi \u00e8 una legge che prevede la <em>stepchild adoption<\/em> alcuni tribunali (vedi ad esempio quello dei minori di Roma e Corte d\u2019Appello di Roma) hanno ammesso l\u2019adozione del figlio del partner omosessuale, figuriamoci cosa accadr\u00e0 nel momento in cui vi sar\u00e0 una base normativa di riferimento, che ammetter\u00e0 la <em>stepchild adoption<\/em>. Il criterio ermeneutico \u201cthe best interest of the child\u201d, ossia il superiore interesse del minore, che \u00e8 alla base dell\u2019istituto dell\u2019adozione, sar\u00e0 gravemente disatteso. La <em>stepchild adoption<\/em> sar\u00e0 una scorciatoia legislativa per far giungere velocemente all\u2019adozione i \u201cciviluniti\u201d aggirando la disciplina prevista dalla legge 184\/1983.<\/p>\n<p style=\"text-align: justify;\"><strong>Che peso hanno le corti di giustizia in tutto questo?<\/strong><\/p>\n<p style=\"text-align: justify;\">Hanno un peso notevole. Molte sentenze stanno riscrivendo il diritto di famiglia con lo scopo di privatizzare e rendere sempre pi\u00f9 fluidi i rapporti familiari, cos\u00ec da favorire l\u2019avvento di una \u201cfamiglia on demand\u201d in cui si potr\u00e0 scegliere di entrare e uscire a piacimento quante volte si vorr\u00e0 da un tipo di famiglia che si potr\u00e0 scegliere tra una variet\u00e0 di modelli, in base ai propri desideri e ai propri gusti sessuali. Alcuni giudici si sentono artefici del cambiamento sociale facendo un uso tecnocratico e ideologico del diritto, cio\u00e8 usandolo come strumento, non per leggere il reale ma per cambiare la realt\u00e0 e il corso della natura; il diritto diventa, pertanto, il mezzo per propiziare una societ\u00e0 finta e artificiale. Un elemento di viva preoccupazione desta constatare la posizione di molti giudici schierati a favore della vergognosa pratica della <em>stepchild adoption<\/em>.<\/p>\n<p style=\"text-align: justify;\"><strong>Una regolamentazione delle unioni omosessuali ce la chiede l\u2019Europa?<\/strong><\/p>\n<p style=\"text-align: justify;\">No. Non \u00e8 per niente vero. Non esistono, infatti, disposizioni che trasferiscano all\u2019Unione Europea le competenze in materia di diritto di famiglia nazionale. Il diritto di famiglia sostanziale \u00e8 di competenza esclusiva degli Stati membri. Tuttavia, l\u2019Unione Europea ha una competenza concorrente con quella degli Stati membri nello spazio di libert\u00e0, sicurezza e giustizia, dove Bruxelles ha ricevuto dai trattati l\u2019incarico di sviluppare la cooperazione giudiziaria in materia civile (compresa la famiglia) con implicazioni transfrontaliere. Ci\u00f2, per\u00f2, non significa assolutamente che l\u2019Europa ci imponga le unioni gay.<\/p>\n<p style=\"text-align: justify;\">Non esiste un consenso tra i vari Stati nazionali sul tema delle unioni omosessuali, la Corte europea dei diritti umani di Strasburgo \u2013 sul presupposto del margine di apprezzamento conseguentemente loro riconosciuto \u2013 afferma che sono riservate alla discrezionalit\u00e0 del legislatore nazionale le eventuali forme di tutela per le coppie di soggetti appartenenti al medesimo sesso. La stessa sentenza Schalk and Kopf contro Austria, infatti, pur ritenendo possibile un\u2019interpretazione estensiva dell\u2019art. 12 della Corte europea dei diritti umani, che prevede il diritto di contrarre matrimonio anche alle coppie omosessuali, chiarisce come non derivi da una siffatta interpretazione una norma impositiva per gli Stati membri.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c8 vero che l\u2019Italia \u00e8 stata condannata dalla Corte europea dei diritti umani perch\u00e9 non ha nel suo ordinamento una disciplina che regolamenti le unioni omosessuali?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00c8 vero. La Corte europea dei diritti umani, con decisione del 21 luglio 2015 Oliari e altri contro Italia, ha condannato l\u2019Italia, ma \u00e8 anche vero che il governo italiano non ha presentato appello contro la sentenza che condanna l\u2019Italia per il mancato riconoscimento delle convivenze omosessuali. Il termine per l\u2019appello \u00e8 scaduto il 21 ottobre 2015 e la sentenza \u00e8 ora diventata definitiva. Non aver appellato la sentenza \u00e8 stata una decisione incomprensibile, che tra l\u2019altro ha come conseguenza l\u2019obbligo per l\u2019Italia di pagare immediatamente la multa inflitta dalla Corte, a danno dei contribuenti. Gli Stati appellano quasi sempre le sentenze della Corte europea dei diritti dell\u2019uomo e quella del governo Renzi \u00e8 una scelta ideologica che mostra chiaramente da che parte sta. Peraltro, a fronte di interpretazioni aberranti della sentenza Oliari, occorre sempre ricordare che questa Corte non ha affatto ingiunto all\u2019Italia di approvare leggi come la Cirinn\u00e0, che parificano le unioni omosessuali ai matrimoni. La Corte afferma che gli Stati europei sono tenuti a riconoscere i \u201cdiritti fondamentali\u201d dei conviventi omosessuali, ma sulle forme di questo riconoscimento lascia piena libert\u00e0 a ciascuno Stato. E la sentenza afferma esplicitamente che non c\u2019\u00e8 alcun obbligo d\u2019includere in questo riconoscimento l\u2019adozione.<\/p>\n<p style=\"text-align: justify;\">\u00c8 utile rilevare, inoltre, che nell\u2019attuazione del loro obbligo positivo ai sensi dell\u2019articolo 8 della Convenzione, gli Stati godono di un certo margine di discrezionalit\u00e0. Qualora non vi sia accordo tra gli Stati membri del Consiglio d\u2019Europa, com\u2019\u00e8 il caso del matrimonio tra coppie omosessuali, in particolare quando la causa solleva delicate questioni morali o etiche, il margine sar\u00e0 pi\u00f9 ampio (si vedano X, Y e Z contro Regno Unito, 22 aprile 1997, \u00a7 44, Reports 1997-II; Frett\u00e9 c. Francia, n. 36515\/97, \u00a7 41, CEDU 2002-I; e Christine Goodwin, sopra citata, \u00a7 85). Il margine sar\u00e0 usualmente ampio anche quando si richiede allo Stato di garantire l\u2019equilibrio tra opposti interessi privati e pubblici o tra diritti della Convenzione (si vedano Frett\u00e9, sopra citata, \u00a7 42; Odi\u00e8vre c. Francia [GC], n. 42326\/98, \u00a7\u00a7 44 49, CEDU 2003 III; Evans c. Regno Unito [GC], n. 6339\/05, \u00a7 77,CEDU 2007 I; Dickson c. Regno Unito [GC], n. 44362\/04, \u00a7 78, CEDU 2007 V; e S.H.e altri, sopra citata, \u00a7 94). Concludendo, si pu\u00f2 pertanto ribadire che l\u2019Italia \u00e8 sovrana nel decidere come regolamentare le coppie di conviventi omosessuali.<\/p>\n<p style=\"text-align: justify;\"><strong>La Corte costituzionale italiana con le sentenze numero 138\/2010 e 170\/2014 ha obbligato il Parlamento a dare regolamentazione giuridica alle unioni di persone dello stesso sesso<\/strong><\/p>\n<p style=\"text-align: justify;\">No. La Corte costituzionale non pone alcun obbligo al Parlamento a disciplinare le unioni di persone dello stesso sesso. Come afferma la stessa Corte \u00abspetta al Parlamento, nell\u2019esercizio della sua piena discrezionalit\u00e0, nei tempi, nei modi e nei limiti stabiliti dalla legge, individuare le forme di garanzia e di riconoscimento per le unioni suddette\u00bb. Il Parlamento \u00e8 libero, pertanto, di regolamentare o meno tali unioni, senza alcun limite di tempo. La sentenza della Corte costituzionale n. 138\/2010 ha, peraltro, ritenuto infondata la questione di legittimit\u00e0 costituzionale degli articoli 93, 96, 98, 107, 108, 143, 143-bis, 156-bis del codice civile in riferimento agli articoli 2, 3, 29 e 117 primo comma della Costituzione, nella \u00abparte in cui, sistematicamente interpretati, tali articoli non consentono che le persone di orientamento omosessuale possano contrarre matrimonio con persone dello stesso sesso\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>La nozione di matrimonio.<\/strong><\/p>\n<p style=\"text-align: justify;\">Con buona pace di alcuni giuristi, che vorrebbero reinterpretare il dettato costituzionale sulla famiglia, \u00e8 bene precisare che durante i lavori preparatori della Carta costituzionale la questione delle unioni omosessuali rimase del tutto estranea al dibattito, bench\u00e9 la condizione omosessuale non fosse certo sconosciuta. I costituenti, elaborando l\u2019articolo 29 della Costituzione, tennero conto di un istituto che aveva una precisa conformazione e un\u2019articolata disciplina nell\u2019ordinamento civile. Essi ebbero presente, infatti, la nozione di matrimonio definita dal codice civile entrato in vigore nel 1942, che stabiliva (e tuttora stabilisce) che i coniugi dovessero essere persone di sesso diverso.<\/p>\n<p style=\"text-align: justify;\">Ci\u00f2 \u00e8 stato ribadito sia dalle sentenze della Corte costituzionale numeri 138\/2010 e 170\/2014 e anche dalla recente sentenza del Consiglio di Stato del 26 ottobre 2015 n. 4.897, in cui si afferma che il matrimonio omosessuale deve intendersi incapace, nel vigente sistema di regole, di costituire tra le parti lo status giuridico proprio delle persone coniugate (con i diritti e gli obblighi connessi) proprio in quanto privo dell\u2019indefettibile condizione della diversit\u00e0 di sesso dei nubendi, che il nostro ordinamento configura quale connotazione ontologica essenziale dell\u2019atto di matrimonio.<\/p>\n<p style=\"text-align: justify;\">Prova di ci\u00f2 \u00e8 che anche il secondo comma dell\u2019articolo 29 della Costituzione, che afferma il principio dell\u2019eguaglianza morale e giuridica dei coniugi, ebbe riguardo proprio alla posizione della donna cui intendeva attribuire pari dignit\u00e0 e diritti nel rapporto coniugale. Si deve ribadire, dunque, che la norma non prese in considerazione le unioni omosessuali, bens\u00ec intese riferirsi al matrimonio nel significato tradizionale di detto istituto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tempi 23 gennaio 2016 Cosa sono e come si differenziano dal matrimonio? Davvero \u201cce le chiedono Bruxelles e la Corte costituzionale\u201d? La stepchild adoption apre all\u2019utero in affitto? di Giancarlo Cerrelli<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":29887,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,15],"tags":[602,2208,196],"class_list":["post-29886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-costume","category-famiglia","tag-adozioni-gay","tag-legge-cirinna","tag-unioni-civili","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La verit\u00e0 sulle unioni civili. Domande e risposte per capire meglio il ddl Cirinn\u00e0 - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La verit\u00e0 sulle unioni civili. Domande e risposte per capire meglio il ddl Cirinn\u00e0 - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-27T23:00:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/unioni-civili.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La verit\u00e0 sulle unioni civili. Domande e risposte per capire meglio il ddl Cirinn\u00e0\",\"datePublished\":\"2016-01-27T23:00:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\\\/\"},\"wordCount\":2768,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/unioni-civili.jpg\",\"keywords\":[\"adozioni gay\",\"legge Cirinn\u00e0\",\"unioni civili\"],\"articleSection\":[\"Costume\",\"Famiglia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\\\/\",\"name\":\"La verit\u00e0 sulle unioni civili. Domande e risposte per capire meglio il ddl Cirinn\u00e0 - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/unioni-civili.jpg\",\"datePublished\":\"2016-01-27T23:00:56+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/unioni-civili.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/unioni-civili.jpg\",\"width\":280,\"height\":160},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La verit\u00e0 sulle unioni civili. Domande e risposte per capire meglio il ddl Cirinn\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La verit\u00e0 sulle unioni civili. Domande e risposte per capire meglio il ddl Cirinn\u00e0 - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\/","og_locale":"it_IT","og_type":"article","og_title":"La verit\u00e0 sulle unioni civili. Domande e risposte per capire meglio il ddl Cirinn\u00e0 - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2016-01-27T23:00:56+00:00","og_image":[{"width":280,"height":160,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/unioni-civili.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"14 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La verit\u00e0 sulle unioni civili. Domande e risposte per capire meglio il ddl Cirinn\u00e0","datePublished":"2016-01-27T23:00:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\/"},"wordCount":2768,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/unioni-civili.jpg","keywords":["adozioni gay","legge Cirinn\u00e0","unioni civili"],"articleSection":["Costume","Famiglia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\/","name":"La verit\u00e0 sulle unioni civili. Domande e risposte per capire meglio il ddl Cirinn\u00e0 - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/unioni-civili.jpg","datePublished":"2016-01-27T23:00:56+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/unioni-civili.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/unioni-civili.jpg","width":280,"height":160},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-verita-sulle-unioni-civili-domande-e-risposte-per-capire-meglio-il-ddl-cirinna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La verit\u00e0 sulle unioni civili. Domande e risposte per capire meglio il ddl Cirinn\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/29886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=29886"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/29886\/revisions"}],"predecessor-version":[{"id":29888,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/29886\/revisions\/29888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/29887"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=29886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=29886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=29886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}