{"id":29846,"date":"2015-08-25T00:00:24","date_gmt":"2015-08-24T22:00:24","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=29846"},"modified":"2016-01-25T12:50:32","modified_gmt":"2016-01-25T11:50:32","slug":"considerazioni-sullislam-4-rubrica-vivaio","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/considerazioni-sullislam-4-rubrica-vivaio\/","title":{"rendered":"Considerazioni sull\u2019islam \/ 4 &#8211; rubrica Vivaio"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/islam_orda.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-29847\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/01\/islam_orda.jpg\" alt=\"islam_orda\" width=\"250\" height=\"154\" \/><\/a>Avvenire<\/strong> \u2013 rubrica Vivaio &#8211; Domenica<\/p>\n<p style=\"text-align: center;\">25 novembre 1990<\/p>\n<p style=\"text-align: center;\">\u00a0<strong>Vittorio Messori<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Saltata<\/strong> una settimana per qualche imprevisto problema di salute, eccoci qui di nuovo a continuare le nostre &#8220;ipotesi su Maometto&#8221;. E vorremmo continuare scendendo dai puri e semplici dati delia storia (molti ne abbiamo elencati nelle tre precedenti &#8220;puntate&#8221;) alla riflessione di fede su quei dati medesimi. Ponendoci dal punto di vista cristiano, perch\u00e9 l&#8217;Islam? Se davvero la storia \u00e8 guidata dal Dio cristiano, \u00e8 possibile intuire almeno un poco, anche qui, del Suo misterioso disegno? Pur \u00abtra le ombre e gli enigmi, vedendo come in uno specchio\u00bb, per dirla con san Paolo, che riflessione trarre dallo scandalo della straordinaria fortuna di una fede che proclama Ges\u00f9 un semplice profeta, per giunta sorpassato?<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Innanzitutto, va notato che l&#8217;erompere subitaneo dal vuoto del deserto delle orde di cavalleria dietro i verdi stendardi di Muhammad, &#8220;l&#8217;ultimo dei rivelatori&#8221;, d\u00e0 inizio a una costante che sar\u00e0 sempre &#8211; ed enigmaticamente \u2014 realizzata in tutta la storia della Chiesa. Quella costante, cio\u00e8, che vuole che la chiusura di una regione sia accompagnata dall&#8217;apertura contemporanea di altre regioni dove si rivela possibile un nuovo, abbondante raccolto.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec, in quello stesso VII secolo in cui il cristianesimo perde la parte meridionale del Mediterraneo, la Chiesa realizza una spettacolare espansione nel Nord e nell&#8217;Est dell&#8217;Europa. I territori conquistati dai musulmani in Asia Minore e nel Nordafrica sono amplissimamente compensati dai territori evangelizzati nell&#8217;oriente europeo dai missionari partiti da Costantinopoli e nel nord da quelli inviati da Roma (e la cristianit\u00e0, allora, era ancora unita).<\/p>\n<p style=\"text-align: justify;\">In Europa la Chiesa non copriva che la penisola greca e la Tracia e quella striscia, poco pi\u00f9 che un corridoio, che andava dall&#8217;Italia all&#8217;Inghilterra passando per i paesi franchi. A causa dei primi successi musulmani mai nella storia la presenza cristiana fu ridotta in uno spazio cos\u00ec esiguo. Eppure, mentre il sipario cala sul Sud, il sipario si alza sul Nord e l&#8217;Est, tanto che la cristianizzazione della restante Europa \u00e8 altrettanto rapida delle conquiste asiatiche e africane dell&#8217;Islam.<\/p>\n<p style=\"text-align: justify;\">Il giovanile ardore dei cavalieri di Allah lanciati nella guerra santa \u00e8 parallelo all&#8217;altrettanto impetuoso sforzo di evangelizzazione \u2014 coronato da immensi successi, storicamente quasi inspiegabili, \u2014 dei missionari di Ges\u00f9 il Cristo. Dalla Siria alla Mauretania cadono sotto il dominio musulmano antiche Chiese lacerate da grovigli ereticali; ma, al contempo, ecco sorgere altre Chiese tutte nuove, fedeli, piene di vita e cariche di futuro. Per fare un solo esempio: quasi nell&#8217;anno stesso dello sbarco islamico in Spagna, quel monaco inglese che prender\u00e0 il nome latinizzato di Bonifacio comincia l&#8217;evangelizzazione della Germania, creando una solidissima Chiesa esemplare per fedelt\u00e0 a Roma.<\/p>\n<p style=\"text-align: justify;\"><strong>Ebbene:<\/strong> come dicevamo, la dialettica, inaugurata allora, di &#8220;chiusura di una porta \u2014 apertura di un&#8217;altra&#8221;, diverr\u00e0 una costante della storia delia Chiesa. Si verificher\u00e0, per fare uno degli esempi pi\u00f9 noti, anche nel XVI secolo, quando la Riforma protestante ridurr\u00e0 la Chiesa cattolica in uno spazio quasi altrettanto esiguo di quello dopo le prime invasioni dei maomettani. Ma anche qui, con una contemporaneit\u00e0 perfetta che fa riflettere, ci\u00f2 che fu perduto in Europa fu compensato dallo spalancarsi del Nuovo Mondo.<\/p>\n<p style=\"text-align: justify;\">La presenza cattolica fu di nuovo ridotta ai minimi termini agli inizi del XIX secolo, a causa della bufera giacobina prima e napoleonica poi che avevano devastato quasi tutto ci\u00f2 che si era costruito in secoli di lavoro. L&#8217;Europa, per giunta, cominciava quel processo di allontanamento del cristianesimo che avrebbe condotto a una secolarizzazione radicale. Eppure, \u00e8 proprio a partire da quel povero &#8220;resto&#8221; che la Chiesa \u2014 per la prima volta nella sua storia \u2014 diventa davvero &#8220;cattolica&#8221;, cio\u00e8 universale, con l&#8217;espansione negli ancora vergini territori dell&#8217;Africa Nera e dell&#8217;Estremo Oriente asiatico.<\/p>\n<p style=\"text-align: justify;\">Il massimo del successo missionario si ha nei decenni in cui il Papa, prigioniero in Vaticano, medita addirittura di fuggire da Roma e la casta di increduli borghesi che ovunque ha in mano il potere guarda con sarcastica compassione a una Chiesa che considera un relitto del passato, in via di fatale estinzione. E, invece, proprio quei tempi sono quelli dell&#8217;espansione inaudita delle frontiere cattoliche. E mentre nell&#8217;Occidente europeo i &#8220;papisti&#8221; sono disprezzati quando non perseguitati, in quell&#8217;Estremo Occidente che \u00e8 l&#8217;America del Nord la Chiesa, da pochissime migliaia di fedeli, giunge impetuosamente a comprendere oltre un quarto della popolazione.<\/p>\n<p style=\"text-align: justify;\">Per fare qualche altro esempio tratto dai nostri tempi: la chiusura, a causa della rivoluzione comunista, della promettente missione in Cina si accompagner\u00e0 alla contemporanea, straordinaria (e imprevista) recettivit\u00e0 al Vangelo della contigua Corea.<\/p>\n<p style=\"text-align: justify;\">C&#8217;\u00e8, dunque, nella storia delia Chiesa, una dialettica di &#8220;perdita-conquista&#8221;, di &#8220;chiusura-apertura&#8221; che costituisce una misteriosa costante che inizia proprio con l&#8217;invasione islamica.<\/p>\n<p style=\"text-align: justify;\"><strong>La conquista<\/strong> musulmana di tutto il litorale dall&#8217;Anatolia allo Stretto di Gibilterra spezza per la prima volta l&#8217;unit\u00e0 del Mediterraneo: il Mare Nostrum, il bacino cio\u00e8 di libera circolazione per uomini, idee, merci. L&#8217;Europa non ha pi\u00f9 collegamento con l&#8217;Africa e con l&#8217;Asia, chiuse dal muro islamico. Bloccata cos\u00ec verso il Mezzogiorno e l&#8217;Oriente, la missione \u00e8 costretta a proiettarsi verso il Nord e il Nord Est. Effetto dell&#8217;islamismo \u00e8 dunque la creazione di una compatta cristianit\u00e0 nell&#8217;Europa: e questa parte del mondo (lo vedemmo proprio qui, tempo fa) sembra essere oggetto d&#8217;attenzione privilegiata e non casuale nei misteriosi piani della Provvidenza. Sar\u00e0 forse questo &#8220;prima l&#8217;Europa e poi il resto del mondo&#8221; uno dei motivi &#8220;segreti&#8221; che spiegano l&#8217;imprevisto blocco che la mezzaluna impone all&#8217;espansione missionaria cristiana?<\/p>\n<p style=\"text-align: justify;\">A far riflettere ulteriormente, sta il fatto che, mentre le Chiese d&#8217;Africa e d&#8217;Asia caddero in quel modo facile che abbiamo visto, la Chiesa d&#8217;Europa fu salvata da due autentici &#8220;miracoli&#8221;. David Knowels: \u00abProprio nel preciso momento in cui la tenaglia stava per chiudersi da Ovest e da Est. la flotta e l&#8217;esercito musulmani furono battuti davanti a Costantinopoli (anno 717) e Carlo Martello sbaragliava i saraceni a Poitiers (anno 732). L&#8217;Europa fu salva. A Ovest i Pirenei segnarono il limite dei territori musulmani. A Est l&#8217;impero bizantino pot\u00e9 sopravvivere ancora 7 secoli. Il che, tra l&#8217;altro, permise la cristianizzazione dell&#8217;Europa orientale. Russia compresa. Se Costantinopoli fosse caduta allora, la fede non avrebbe mai potuto essere divulgata tra il Danubio e gli Urali\u00bb.<\/p>\n<p style=\"text-align: justify;\">Ma non \u00e8 che un assaggio dell&#8217;enigma posto dall&#8217;Islam. Marted\u00ec e gioved\u00ec occorrer\u00e0 continuare. ( 391)<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=29850\" target=\"_blank\">CONTINUA<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avvenire \u2013 rubrica Vivaio &#8211; Domenica 25 novembre 1990 \u00a0Vittorio Messori Saltata una settimana per qualche imprevisto problema di salute, eccoci qui di nuovo a continuare le nostre &#8220;ipotesi su Maometto&#8221;. E vorremmo continuare scendendo dai puri e semplici dati delia storia (molti ne abbiamo elencati nelle tre precedenti &#8220;puntate&#8221;) alla riflessione di fede su &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/considerazioni-sullislam-4-rubrica-vivaio\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":29864,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,24],"tags":[161],"class_list":["post-29846","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-islam","category-storia","tag-islam-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Considerazioni sull\u2019islam \/ 4 - rubrica Vivaio - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/considerazioni-sullislam-4-rubrica-vivaio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Considerazioni sull\u2019islam \/ 4 - rubrica Vivaio - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/considerazioni-sullislam-4-rubrica-vivaio\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2015-08-24T22:00:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-25T11:50:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/08\/avvenire-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"241\" \/>\n\t<meta property=\"og:image:height\" content=\"209\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/considerazioni-sullislam-4-rubrica-vivaio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/considerazioni-sullislam-4-rubrica-vivaio\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Considerazioni sull\u2019islam \\\/ 4 &#8211; rubrica Vivaio\",\"datePublished\":\"2015-08-24T22:00:24+00:00\",\"dateModified\":\"2016-01-25T11:50:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/considerazioni-sullislam-4-rubrica-vivaio\\\/\"},\"wordCount\":1067,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/considerazioni-sullislam-4-rubrica-vivaio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/avvenire-logo.png\",\"keywords\":[\"islam\"],\"articleSection\":[\"Islam\",\"Storia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/considerazioni-sullislam-4-rubrica-vivaio\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/considerazioni-sullislam-4-rubrica-vivaio\\\/\",\"name\":\"Considerazioni sull\u2019islam \\\/ 4 - rubrica Vivaio - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/considerazioni-sullislam-4-rubrica-vivaio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/considerazioni-sullislam-4-rubrica-vivaio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/avvenire-logo.png\",\"datePublished\":\"2015-08-24T22:00:24+00:00\",\"dateModified\":\"2016-01-25T11:50:32+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/considerazioni-sullislam-4-rubrica-vivaio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/considerazioni-sullislam-4-rubrica-vivaio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/considerazioni-sullislam-4-rubrica-vivaio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/avvenire-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/08\\\/avvenire-logo.png\",\"width\":241,\"height\":209},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/considerazioni-sullislam-4-rubrica-vivaio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Considerazioni sull\u2019islam \\\/ 4 &#8211; rubrica Vivaio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Considerazioni sull\u2019islam \/ 4 - rubrica Vivaio - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/considerazioni-sullislam-4-rubrica-vivaio\/","og_locale":"it_IT","og_type":"article","og_title":"Considerazioni sull\u2019islam \/ 4 - rubrica Vivaio - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/considerazioni-sullislam-4-rubrica-vivaio\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2015-08-24T22:00:24+00:00","article_modified_time":"2016-01-25T11:50:32+00:00","og_image":[{"width":241,"height":209,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/08\/avvenire-logo.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/considerazioni-sullislam-4-rubrica-vivaio\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/considerazioni-sullislam-4-rubrica-vivaio\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Considerazioni sull\u2019islam \/ 4 &#8211; rubrica Vivaio","datePublished":"2015-08-24T22:00:24+00:00","dateModified":"2016-01-25T11:50:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/considerazioni-sullislam-4-rubrica-vivaio\/"},"wordCount":1067,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/considerazioni-sullislam-4-rubrica-vivaio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/08\/avvenire-logo.png","keywords":["islam"],"articleSection":["Islam","Storia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/considerazioni-sullislam-4-rubrica-vivaio\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/considerazioni-sullislam-4-rubrica-vivaio\/","name":"Considerazioni sull\u2019islam \/ 4 - rubrica Vivaio - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/considerazioni-sullislam-4-rubrica-vivaio\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/considerazioni-sullislam-4-rubrica-vivaio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/08\/avvenire-logo.png","datePublished":"2015-08-24T22:00:24+00:00","dateModified":"2016-01-25T11:50:32+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/considerazioni-sullislam-4-rubrica-vivaio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/considerazioni-sullislam-4-rubrica-vivaio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/considerazioni-sullislam-4-rubrica-vivaio\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/08\/avvenire-logo.png","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/08\/avvenire-logo.png","width":241,"height":209},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/considerazioni-sullislam-4-rubrica-vivaio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Considerazioni sull\u2019islam \/ 4 &#8211; rubrica Vivaio"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/29846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=29846"}],"version-history":[{"count":2,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/29846\/revisions"}],"predecessor-version":[{"id":29853,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/29846\/revisions\/29853"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/29864"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=29846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=29846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=29846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}