{"id":2912,"date":"2009-03-24T16:16:29","date_gmt":"2009-03-24T15:16:29","guid":{"rendered":""},"modified":"2016-04-18T10:00:00","modified_gmt":"2016-04-18T08:00:00","slug":"il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\/","title":{"rendered":"Il Motu Proprio di Benedetto XVI e l&#8217;ermeneutica della continuit&agrave;"},"content":{"rendered":"<div style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-32914\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/missale_romanum.jpg\" alt=\"missale_romanum\" width=\"136\" height=\"200\" \/>\u00a0<strong>\u00a0Sacerdos,<\/strong> novembre 2000<\/div>\n<p style=\"text-align: center;\">don <strong>Pietro Cantoni<br \/>\n<\/strong><\/p>\n<p style=\"text-align: justify;\">Il 7 luglio 2007 \u00e8 stata pubblicato il <em>Motu Proprio <\/em>che estende la facolt\u00e0 di celebrare nella forma precedente la riforma liturgica del 1970. Le reazioni al documento papale possono apparire sproporzionate se ci si ostina a ridurlo alle modestissime proporzioni di un documento di dialogo ecumenico nei confronti di una esigua minoranza. Se cos\u00ec fosse non si capirebbe davvero l&#8217;ostilit\u00e0 con cui \u00e8 stato accolto in molti ambienti ed anche \u2013 purtroppo \u2013 da parte di qualche vescovo.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">In realt\u00e0 il documento va ben oltre il fatto specifico della celebrazione della Messa secondo il <em>Missale Romanum <\/em>del 1962. Per comprendere l&#8217;effettiva portata di questo documento, conviene partire da che cosa esso non \u00e8.<\/div>\n<p style=\"text-align: justify;\">Non \u00e8 la sconfessione del concilio ecumenico Vaticano II e neppure della riforma liturgica che ne \u00e8 conseguita. \u00c8 cosa talmente ovvia che pu\u00f2 apparire persino inutilmente ridondante il ripeterlo, se non fosse per l&#8217;insistenza con cui il pericolo viene denunciato. Come sempre, davanti a reazioni cos\u00ec insistenti e ad affermazioni cos\u00ec frequentemente ripetute, dobbiamo aver la saggezza di riconoscere un nucleo di verit\u00e0. Quando c&#8217;\u00e8 tanto fumo, ci deve pur essere un po&#8217; di arrosto&#8230;<\/p>\n<p style=\"text-align: justify;\">Una sconfessione infatti c&#8217;\u00e8: non per\u00f2 del Concilio, ma dell&#8217;interpretazione del Concilio all&#8217;insegna della rottura.<\/p>\n<p style=\"text-align: justify;\">Nell&#8217;ormai famoso e difficilmente sopravvalutabile discorso di Benedetto XVI alla curia romana del 22 dicembre 2005, il papa poneva alla radice della situazione di crisi in cui versa il mondo cattolico, lo scontro tra due interpretazioni dell&#8217;ultimo concilio ecumenico: \u00ab<em>due ermeneutiche contrarie si sono trovate a confronto e hanno litigato tra loro<\/em>\u00bb. Due e non tre&#8230; Con quel discorso siamo finalmente usciti dal modello ternario conservatori-progressisti- moderati che rifletteva di fatto una lettura ideologica della vita della Chiesa. Il modello binario di Benedetto XVI \u00e8 \u2013 come deve essere \u2013 puramente teologico.<\/p>\n<p style=\"text-align: justify;\">\u00ab<em>Da una parte esiste un&#8217;interpretazione che vorrei chiamare &#8220;ermeneutica della discontinuit\u00e0 e della rottura&#8221;; essa non di rado si \u00e8 potuta avvalere della simpatia dei mass-media, e anche di una parte della teologia moderna. Dall&#8217;altra parte c&#8217;\u00e8 l'&#8221;ermeneutica della riforma&#8221;, del rinnovamento nella continuit\u00e0 dell&#8217;unico soggetto-Chiesa, che il Signore ci ha donato; \u00e8 un soggetto che cresce nel tempo e si sviluppa, rimanendo per\u00f2 sempre lo stesso, unico soggetto del Popolo di Dio in cammino. L&#8217;ermeneutica della discontinuit\u00e0 rischia di finire in una rottura tra Chiesa preconciliare e Chiesa postconciliare<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Trattandosi di uno schema binario e non ternario, l'&#8221;ermeneutica della rottura&#8221; \u00e8 <em>double face<\/em>: una volta ammessa una insanabile spaccatura tra la Chiesa pre-conciliare e la Chiesa postconciliare (terminologia che ha solo un valore cronologico e non teologico), si apre la strada ad una scelta. C&#8217;\u00e8 chi sceglie il postconcilio ed \u00e8 infastidito da tutto quello che succedeva &#8220;prima&#8221; e c&#8217;\u00e8 chi sceglie il preconcilio e &#8220;sopporta&#8221; \u2013 spesso applicando con larghezza la restrizione mentale \u2013 tutto quello che \u00e8 successo dopo.<\/p>\n<p style=\"text-align: justify;\">Entrambe queste posizioni si ritrovano unite in un atteggiamento sostanzialmente soggettivista e in una conseguente ricezione del Magistero \u2013 conciliare e non \u2013 puramente formale. In conformit\u00e0 con questo approccio esso \u00e8 accettabile <em>solo <\/em>se se si muove in conformit\u00e0 con &#8220;lo spirito del Concilio&#8221; oppure <em>solo <\/em>nella misura in cui riafferma cose gi\u00e0 dette prima del Concilio.<\/p>\n<p style=\"text-align: justify;\">Non credo sia inutile ricordare che il termine greco <em>hairesis <\/em>\u2013 da cui l&#8217;italiano &#8220;eresia&#8221; \u2013 significa &#8220;scelta&#8221;, &#8220;preferenza&#8221;, &#8220;elezione&#8221;, &#8220;partito&#8221;, implicando sempre una fondamentale affermazione della soggettivit\u00e0. Entrambi questi atteggiamenti, nella esteriore differenza delle forme, esprimono un comune sentire postmoderno e relativista.<\/p>\n<p style=\"text-align: justify;\">L'&#8221;ermeneutica della riforma&#8221;, del &#8220;rinnovamento nella continuit\u00e0&#8221; \u00e8 invece espressione della fede tradizionale della Chiesa cattolica.<\/p>\n<p style=\"text-align: justify;\">Noi cattolici infatti siamo stati spesso accusati dai nostri fratelli protestanti e\u2013 prima ancora \u2013 dagli ortodossi, di avere &#8220;aggiunto&#8221; qualcosa al deposito della fede affidato agli apostoli. \u00c8 nota la polemica riguardo al <em>Fr\u00fchkatholizismus <\/em>per cui alcuni esegeti protestanti hanno ravvisato gi\u00e0 nel canone delle Sacre Scritture elementi di quel cattolicesimo che doveva poi essere rifiutato da Lutero in nome di un radicale &#8220;ritorno alle origini&#8221;.<\/p>\n<p style=\"text-align: justify;\">La scoperta della categoria dello sviluppo, come indispensabile strumento per comprendere la tradizione patristica e quindi la fede stessa, fu proprio ci\u00f2 che determin\u00f2 il passaggio di John Henri Newman dall&#8217;anglicanesimo alla Chiesa cattolica. Nella logica dello sviluppo forme anteriori della fede, quando sono accolte e trasmesse per secoli nella Chiesa non possono essere abolite, ma possono e devono essere interpretate per cui, in una fondamentale identit\u00e0 di senso, vengono colte in modo pi\u00f9 pieno e profondo.<\/p>\n<p style=\"text-align: justify;\">Nel <em>Motu Proprio<\/em> infatti e nella lettera di accompagnamento, il papa insiste nell&#8217;affermare che il rito romano precedente la riforma (ma lo stesso \u2013 per le stesse ragioni \u2013 pu\u00f2 essere affermato anche del rito ambrosiano) non \u00e8 mai stato abrogato. \u00ab<em>Quanto all\u2019uso del Messale del 1962, come forma extraordinaria della Liturgia della Messa, vorrei attirare l\u2019attenzione sul fatto che questo Messale non fu mai giuridicamente abrogato e, di conseguenza, in linea di principio, rest\u00f2 sempre permesso<\/em>\u00bb (Lettera di accompagnamento).<\/p>\n<p style=\"text-align: justify;\">Infatti: \u00ab<em>Ci\u00f2 che per le generazioni anteriori era sacro, anche per noi resta sacro e grande, e non pu\u00f2 essere improvvisamente del tutto proibito o, addirittura, giudicato dannoso<\/em>\u00bb (<em>Ibidem<\/em>).<\/p>\n<p style=\"text-align: justify;\">Quando fu fatta la riforma liturgica non si pens\u00f2 di dover abrogare la liturgia precedente. Si era infatti convinti che la cosa sarebbe andata da s\u00e9: la nuova liturgia avrebbe insensibilmente ed inesorabilmente sostituito l&#8217;antica, come era successo spesso nella lunga storia della Chiesa. Gli eventi presero invece decisamente un&#8217;altra direzione.<\/p>\n<p style=\"text-align: justify;\">Non si era tenuto conto del fatto che la riforma era avvenuta \u2013 o, perlomeno, era stata percepita \u2013 come qualcosa di &#8220;fatto a tavolino&#8221; da un gruppo di esperti e non come il frutto maturo di una impercettibile evoluzione storica. Inoltre si era sottovalutato che si trattava della pi\u00f9 imponente riforma liturgica di tutta quanta la storia del cristianesimo. Verso la met\u00e0 del seicento il patriarca di Mosca <em>Nikita Minic Nikon<\/em> (1605-1681) attu\u00f2 una riforma del rito bizantino slavo celebrato dalla chiesa russa. La riforma consistette sostanzialmente nel conformare i libri liturgici russi ai libri liturgici greci utilizzati allora a Costantinopoli.<\/p>\n<p style=\"text-align: justify;\">In concreto la portata dei cambiamenti era veramente minima: il pi\u00f9 significativo \u00e8 il segno di croce e le benedizioni con tre dita anzich\u00e9 con due. Il risultato fu uno scisma di terribili proporzioni (frantumatosi ben presto in diverse branche) che conta ancora ai nostri giorni milioni di aderenti. Toccare la liturgia \u00e8 sempre molto rischioso! Cos\u00ec la riforma liturgica non si afferm\u00f2 affatto in modo &#8220;indolore&#8221;.<\/p>\n<p style=\"text-align: justify;\">Da una parte essa forn\u00ec l&#8217;occasione ad una serie di scandalosi abusi, dove l&#8217;abuso principale \u2013 quello strisciante \u2013 era l&#8217;idea che la liturgia fosse qualcosa di continuamente da inventare, da &#8220;fare&#8221; e non piuttosto l&#8217;accoglienza e la celebrazione del dono e dell&#8217;azione di Dio in mezzo agli uomini: \u00abTutte le volte che celebriamo questi santi misteri si compie l&#8217;opera della nostra redenzione\u00bb (Preghiera sulle offerte della II Domenica durante l&#8217;anno).<\/p>\n<p style=\"text-align: justify;\">Dall&#8217;altra suscit\u00f2 una reazione a volte violenta e a volte nascosta, ma comunque reale e fastidiosa, tale da generare un clima di disagio che fin\u00ec per rendere problematici i suoi innegabili effetti positivi l\u00e0 dove essa era applicata e vissuta in ossequio alle norme e \u2013 soprattutto \u2013 in conformit\u00e0 con la teologia liturgica che la costituzione conciliare <em>Sacrosanctum Concilium <\/em>aveva cos\u00ec profondamente delineato.<\/p>\n<p style=\"text-align: justify;\">Questa reazione critica era arrivata \u2013 in qualche caso \u2013 addirittura a mettere in discussione l&#8217;ortodossia della riforma. Cosa assurda e teologicamente inconsistente, soprattutto se esaminata dal punto di vista di una corretta ecclesiologia, ma che era resa molto credibile dai tanti abusi liturgici che finivano per addolorare e spazientire i fedeli. Ad un certo punto, vista l&#8217;inattesa reazione alla riforma, il presidente del Pontificio Consiglio per l&#8217;esecuzione della riforma liturgica Mons. Annibale Bugnini si adoper\u00f2 per ottenere l&#8217;abrogazione dell&#8217;antico rito, ma senza successo.<\/p>\n<p style=\"text-align: justify;\">Ci si rese infatti subito conto che si trattava di un atto assai problematico. I canonisti avevano ipotizzato la possibilit\u00e0 di una <em>abrogatio<\/em>, cio\u00e8 di una eliminazione di fatto dovuta al totale riordino della materia: si sarebbe comunque trattato di qualcosa di inaudito, cio\u00e8 dell&#8217;abolizione mediante un atto giuridico di un rito liturgico ortodosso e immemoriale. Ci si doveva allora obbligatoriamente riferire al can 21 del Codice di Diritto Canonico: \u00ab<em>Nel dubbio la revoca della legge preesistente non si presume, ma le leggi posteriori devono essere ricondotte alle precedenti e con queste conciliate, per quanto \u00e8 possibile<\/em> \u00bb.<\/p>\n<p style=\"text-align: justify;\">Il <em>Motu Proprio <\/em>non fa dunque che sanzionare questa situazione di fatto: la Chiesa, davanti al rito antico, si trova a riconoscere, come in altri casi analoghi (per es. l&#8217;ordinazione delle donne al ministero presbiterale, cfr. Giovanni Paolo II, Lettera apostolica <em>Ordinatio sacerdotalis <\/em>del 22 maggio 1994, nn. 2 e 4), di non avere la facolt\u00e0 di procedere. Questo non significa affatto una limitazione indebita del potere della Chiesa, ma solo il riconoscimento che la consuetudine liturgica, ortodossa ed immemoriale, costituisce una delle espressioni della sua stessa <em>sacra potestas<\/em>.<\/p>\n<p style=\"text-align: justify;\">Due forme rituali che \u2013 all&#8217;interno di uno stesso rito, il Rito Romano \u2013 coesistono pacificamente come forma ordinaria (il rito romano frutto della riforma liturgica del 1970) e straordinaria (il rito precedente la riforma) appaiono cos\u00ec come l&#8217;icona vivente del modo corretto di interpretare qualunque riforma nella Chiesa e quindi anche l&#8217;ultimo concilio ecumenico.<\/p>\n<p style=\"text-align: justify;\">Ecco perch\u00e9, anche se apparentemente circoscritto quanto alla sua materia propria, questo <em>Motu Proprio <\/em>\u00e8 cos\u00ec importante e suscita tanto clamore. Qualcuno lo ha visto polemicamente come una specie di Apocalisse (la fine del &#8220;fermento&#8221; innovativo del Concilio&#8230;).<\/p>\n<p style=\"text-align: justify;\">In un certo senso lo \u00e8. Apocalisse vuol dire infatti &#8220;<em>rivelazione<\/em>&#8221; e questo documento sta rivelando il pensiero nascosto di molti cuori (cfr. Lc 2,34).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0Sacerdos, novembre 2000 don Pietro Cantoni Il 7 luglio 2007 \u00e8 stata pubblicato il Motu Proprio che estende la facolt\u00e0 di celebrare nella forma precedente la riforma liturgica del 1970. Le reazioni al documento papale possono apparire sproporzionate se ci si ostina a ridurlo alle modestissime proporzioni di un documento di dialogo ecumenico nei confronti &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":32914,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,115],"tags":[344,1094],"class_list":["post-2912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-liturgia","tag-concilio-vaticano-ii","tag-s-messa","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il Motu Proprio di Benedetto XVI e l&#039;ermeneutica della continuit&agrave; - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il Motu Proprio di Benedetto XVI e l&#039;ermeneutica della continuit&agrave; - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-03-24T15:16:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-18T08:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/missale_romanum.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"174\" \/>\n\t<meta property=\"og:image:height\" content=\"256\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il Motu Proprio di Benedetto XVI e l&#8217;ermeneutica della continuit&agrave;\",\"datePublished\":\"2009-03-24T15:16:29+00:00\",\"dateModified\":\"2016-04-18T08:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\\\/\"},\"wordCount\":1581,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/missale_romanum.jpg\",\"keywords\":[\"Concilio Vaticano II\",\"S Messa\"],\"articleSection\":[\"Chiesa\",\"Liturgia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\\\/\",\"name\":\"Il Motu Proprio di Benedetto XVI e l'ermeneutica della continuit&agrave; - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/missale_romanum.jpg\",\"datePublished\":\"2009-03-24T15:16:29+00:00\",\"dateModified\":\"2016-04-18T08:00:00+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/missale_romanum.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/missale_romanum.jpg\",\"width\":174,\"height\":256},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il Motu Proprio di Benedetto XVI e l&#8217;ermeneutica della continuit&agrave;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il Motu Proprio di Benedetto XVI e l'ermeneutica della continuit&agrave; - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\/","og_locale":"it_IT","og_type":"article","og_title":"Il Motu Proprio di Benedetto XVI e l'ermeneutica della continuit&agrave; - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-03-24T15:16:29+00:00","article_modified_time":"2016-04-18T08:00:00+00:00","og_image":[{"width":174,"height":256,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/missale_romanum.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il Motu Proprio di Benedetto XVI e l&#8217;ermeneutica della continuit&agrave;","datePublished":"2009-03-24T15:16:29+00:00","dateModified":"2016-04-18T08:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\/"},"wordCount":1581,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/missale_romanum.jpg","keywords":["Concilio Vaticano II","S Messa"],"articleSection":["Chiesa","Liturgia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\/","name":"Il Motu Proprio di Benedetto XVI e l'ermeneutica della continuit&agrave; - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/missale_romanum.jpg","datePublished":"2009-03-24T15:16:29+00:00","dateModified":"2016-04-18T08:00:00+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/missale_romanum.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/missale_romanum.jpg","width":174,"height":256},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-motu-proprio-di-benedetto-xvi-e-lermeneutica-della-continuit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il Motu Proprio di Benedetto XVI e l&#8217;ermeneutica della continuit&agrave;"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2912"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2912\/revisions"}],"predecessor-version":[{"id":32915,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2912\/revisions\/32915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/32914"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}