{"id":2899,"date":"2009-03-18T13:34:28","date_gmt":"2009-03-18T12:34:28","guid":{"rendered":""},"modified":"2016-03-16T10:29:19","modified_gmt":"2016-03-16T09:29:19","slug":"la-buona-diagnosi-contro-leugenetica","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-diagnosi-contro-leugenetica\/","title":{"rendered":"La buona diagnosi contro l\u2019eugenetica"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-31834\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/neonato.jpg\" alt=\"neonato\" width=\"250\" height=\"153\" \/>Il Foglio, <\/strong>22 maggio 2008<\/div>\n<p style=\"text-align: justify;\"><em>Un gruppo di neonatologi e psichiatri lancia un appello per liberare la \u201cscelta della donna\u201d dall\u2019incubo della perfezione. Sicard denunci\u00f2 la pratica della selezione che \u201ctende alla soppressione e non alla cura\u201d<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Nicoletta Tiliacos <\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Roma. \u201cLa pratica della diagnosi prenatale tende alla soppressione e non alla cura\u201d, cos\u00ec facendo cromosomi e geni, che custodiscono il segreto e l\u2019unicit\u00e0 della persona umana, sono sempre pi\u00f9 considerati \u201cagenti patogeni infettivi che la medicina deve sradicare\u201d.<\/div>\n<p style=\"text-align: justify;\">Questa non \u00e8 buona medicina, ma \u201cuna ideologia resa possibile dalla tecnica\u201d e \u201cuna politica sanitaria che flirta ogni giorno di pi\u00f9 con l\u2019eugenetica\u201d.<\/p>\n<p style=\"text-align: justify;\">A lanciare la denuncia fu nel 2007 Didier Sicard, presidente del Comitato di bioetica francese, autore del pi\u00f9 importante manifesto contro la strisciante eugenetica praticata per mezzo della selezione prenatale.<\/p>\n<p style=\"text-align: justify;\">In Spagna dal 1992 si esegue sistematicamente l\u2019eliminazione degli embrioni portatori di emofilia nei trattamenti di fecondazione artificiale in vitro.<\/p>\n<p style=\"text-align: justify;\">In Inghilterra \u00e8 possibile con la diagnosi preimpianto eliminare embrioni che hanno la predisposizione ad ammalarsi di cancro al seno o alle ovaie, da adulti. Dal tema della diagnosi prenatale, che da strumento di cura diventa alibi per l\u2019estinzione del non nato, passa l\u2019intera battaglia contro l\u2019eugenetica e l\u2019aborto selettivo al centro della moratoria. Nel 2006 anche la rivista Nature analizz\u00f2 a lungo lo spettro di questa \u201cneo-eugenetica\u201d.<\/p>\n<p style=\"text-align: justify;\">Ora Carlo Bellieni, uno dei pi\u00f9 importanti neonatologi italiani, chiede di salvare la buona diagnostica e combattere la selezione della specie. Un appello per un \u201caccesso consapevole alla diagnosi genetica prenatale\u201d \u00e8 stato promosso da Bellieni e da un gruppo di neonatologi, ginecologi, psichiatri, bioeticisti e rappresentanti di associazioni di disabili, \u201cpreoccupati per le conseguenze che l\u2019impiego diffuso ed indiscriminato di questa pratica pu\u00f2 avere sia a breve che a lungo termine nella popolazione\u201d.<\/p>\n<p style=\"text-align: justify;\">I destinatari dell\u2019appello, spiega al Foglio Bellieni, \u201csono operatori e comitati etici. Troppo spesso, infatti, la diagnosi genetica prenatale viene proposta\/imposta in modo routinario, e troppo spesso la donna viene lasciata sola a decidere, con una diagnosi di malattia del figlio in arrivo, che cosa fare di lui. Ma negli Stati Uniti, dove la pratica prevede la piena informazione, il colloquio con lo specialista della malattia diagnosticata, l\u2019analisi delle prospettive terapeutiche, si \u00e8 visto che crolla il ricorso all\u2019aborto\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>\u201cBambini persi in seguito alla procedura\u201d<\/strong><\/p>\n<p style=\"text-align: justify;\">Un appello non contro la diagnosi genetica prenatale, dunque, ma per il suo buon uso, dal quale escludere ogni ombra eugenetica. Le procedure diagnostiche genetiche prenatali (amniocentesi e villocentesi) non sono affatto esenti da rischi.<\/p>\n<p style=\"text-align: justify;\">I ginecologi canadesi parlano di un aborto non voluto ogni duecento procedure, il Royal College of Obstetrics and Gynecology di uno ogni cento: in ogni caso, \u201cconsiderando che in Italia si eseguono circa centomila amniocentesi ogni anno e che la maggior parte dei feti sottoposti a indagine prenatale risulta sana, appare sconcertante l\u2019elevato numero di bambini (probabilmente sani) persi in seguito alla procedura\u201d.<\/p>\n<p style=\"text-align: justify;\">Vari studi, inoltre \u201cdimostrano che le donne che si sottopongono a diagnosi genetica prenatale (sia nella forma invasiva che in quella di screening con ecografie mirate o integrate con analisi del sangue materno) raramente hanno piena consapevolezza dei limiti, dei rischi, delle modalit\u00e0 di esecuzione e degli scopi degli screening\u201d.<\/p>\n<p style=\"text-align: justify;\">L\u2019appello chiede allora di valutare i diversi screening prenatali \u201calla luce dei possibili rischi e benefici per entrambi i soggetti (madre e bambino\/a)\u201d, e di farli precedere \u201cda una dettagliata informazione su limiti, rischi, implicazioni e possibilit\u00e0 terapeutiche nell\u2019ambito di una adeguata consulenza pre diagnostica, affinch\u00e9 la donna possa compiere una scelta informata e autenticamente consapevole, conservando la piena libert\u00e0 di accettare o rifiutare lo screening o il test.<\/p>\n<p style=\"text-align: justify;\">Mai devono essere usati termini generici (\u2018piccolo\u2019, \u2018trascurabile\u2019, \u2018grande\u2019) quando si spiega il tasso di rischio, ma vanno forniti dati numerici, nonch\u00e9 il significato di tali dati\u201d.<\/p>\n<p style=\"text-align: justify;\">Fra i firmatari troviamo i bioeticisti Gabriella Gambino e Claudia Navarini, Paolo Arosio, neonatologo e presidente dell\u2019associazione \u201cAmici di Giovanni\u201d, Luigi Vittorio Berliri, presidente dell\u2019associazione \u201cSpes contra Spem\u201d, Loris Brunetta, presidente dell\u2019associazione ligure talassemici, Sabrina Paluzzi, presidente dell\u2019associazione \u201cLa Quercia Millenaria\u201d e Claudia Ravaldi, psichiatra e presidente dell\u2019associazione \u201cCiao Lapo\u201d.<\/p>\n<p style=\"text-align: justify;\">I promotori dell\u2019appello spiegano che la richiesta di integrare sistematicamente la diagnostica prenatale con una \u201cfase pre diagnostica e una post diagnostica si basa sulla constatazione che la diagnosi genetica prenatale non \u00e8 eticamente neutra\u201d, perch\u00e9 comporta una scelta, \u201ce le scelte richiedono una reale conoscenza dei dati e implicano una responsabilit\u00e0\u201d.<\/p>\n<p style=\"text-align: justify;\">I firmatari del documento chiedono inoltre che in caso di riscontro di una patologia, la diagnosi prenatale non sia da considerarsi terminata (salvo esplicito diniego da parte della donna) senza il coinvolgimento di uno specialista della patologia riscontrata, la consulenza post diagnostica suggerita anche dal <em>Journal of the American Medical Association<\/em>.<\/p>\n<p style=\"text-align: justify;\">Una specialista in grado di fornire informazioni sulla patologia, sulla possibilit\u00e0 di un percorso terapeutico e su \u201cpossibili agevolazioni socio-economiche in grado di assistere la famiglia, e senza informare sulla possibilit\u00e0 di partorire in anonimato e dare il figlio in adozione\u201d.<\/p>\n<p style=\"text-align: justify;\">L\u2019autonomia delle donne nelle decisioni sulla loro gravidanza pu\u00f2 essere seriamente compromessa da un uso routinario della diagnosi, che i firmatari chiamano \u201cnon scelta\u201d, della diagnosi genetica prenatale, che spesso proviene da una pressione sociale per non far mettere al mondo figli con anomalie genetiche. \u201cOccorre garantire nei fatti la libert\u00e0 nella scelta\u201d.<\/p>\n<p style=\"text-align: justify;\">\u201cUna diagnosi medica non dovrebbe mai diventare una sentenza di morte\u201d ha detto Fernando Pascual, docente di filosofia presso l\u2019Ateneo pontificio Regina Apostolorum di Roma. Stiamo assistendo alla giustificazione della selezione sulla base addirittura di anomalie dentarie del concepito.Lo stesso Bellieni a un convegno della Pontificia accademia Pro vita ha detto che la diagnostica pone un altro problema: \u201cQual \u00e8 il sentire dei bambini nati nell\u2019attuale stato di possibilit\u00e0 selettiva prenatale?\u201d. C\u2019\u00e8 chi parla dell\u2019attuale come una \u201cgenerazione di sopravvissuti\u201d.<\/p>\n<p style=\"text-align: justify;\">___________________________<\/p>\n<p style=\"text-align: justify;\"><strong>Leggi anche:<\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=2778\" target=\"_blank\">Nascite &#8220;indegne&#8221;, eugenetica e mito della perfezione nella diagnosi prenatale<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Foglio, 22 maggio 2008 Un gruppo di neonatologi e psichiatri lancia un appello per liberare la \u201cscelta della donna\u201d dall\u2019incubo della perfezione. Sicard denunci\u00f2 la pratica della selezione che \u201ctende alla soppressione e non alla cura\u201d di Nicoletta Tiliacos<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-diagnosi-contro-leugenetica\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":31834,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,117],"tags":[1578],"class_list":["post-2899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bioetica","category-eugenetica","tag-diagnosi-prenatale","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La buona diagnosi contro l\u2019eugenetica - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-diagnosi-contro-leugenetica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La buona diagnosi contro l\u2019eugenetica - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-diagnosi-contro-leugenetica\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-03-18T12:34:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-16T09:29:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/neonato.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"287\" \/>\n\t<meta property=\"og:image:height\" content=\"176\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-diagnosi-contro-leugenetica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-diagnosi-contro-leugenetica\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La buona diagnosi contro l\u2019eugenetica\",\"datePublished\":\"2009-03-18T12:34:28+00:00\",\"dateModified\":\"2016-03-16T09:29:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-diagnosi-contro-leugenetica\\\/\"},\"wordCount\":986,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-diagnosi-contro-leugenetica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/neonato.jpg\",\"keywords\":[\"diagnosi prenatale\"],\"articleSection\":[\"Bioetica\",\"Eugenetica\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-diagnosi-contro-leugenetica\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-diagnosi-contro-leugenetica\\\/\",\"name\":\"La buona diagnosi contro l\u2019eugenetica - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-diagnosi-contro-leugenetica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-diagnosi-contro-leugenetica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/neonato.jpg\",\"datePublished\":\"2009-03-18T12:34:28+00:00\",\"dateModified\":\"2016-03-16T09:29:19+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-diagnosi-contro-leugenetica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-diagnosi-contro-leugenetica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-diagnosi-contro-leugenetica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/neonato.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/neonato.jpg\",\"width\":287,\"height\":176},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-buona-diagnosi-contro-leugenetica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La buona diagnosi contro l\u2019eugenetica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La buona diagnosi contro l\u2019eugenetica - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-diagnosi-contro-leugenetica\/","og_locale":"it_IT","og_type":"article","og_title":"La buona diagnosi contro l\u2019eugenetica - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-diagnosi-contro-leugenetica\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-03-18T12:34:28+00:00","article_modified_time":"2016-03-16T09:29:19+00:00","og_image":[{"width":287,"height":176,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/neonato.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-diagnosi-contro-leugenetica\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-diagnosi-contro-leugenetica\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La buona diagnosi contro l\u2019eugenetica","datePublished":"2009-03-18T12:34:28+00:00","dateModified":"2016-03-16T09:29:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-diagnosi-contro-leugenetica\/"},"wordCount":986,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-diagnosi-contro-leugenetica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/neonato.jpg","keywords":["diagnosi prenatale"],"articleSection":["Bioetica","Eugenetica"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-diagnosi-contro-leugenetica\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-diagnosi-contro-leugenetica\/","name":"La buona diagnosi contro l\u2019eugenetica - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-diagnosi-contro-leugenetica\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-diagnosi-contro-leugenetica\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/neonato.jpg","datePublished":"2009-03-18T12:34:28+00:00","dateModified":"2016-03-16T09:29:19+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-diagnosi-contro-leugenetica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-diagnosi-contro-leugenetica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-diagnosi-contro-leugenetica\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/neonato.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/neonato.jpg","width":287,"height":176},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-buona-diagnosi-contro-leugenetica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La buona diagnosi contro l\u2019eugenetica"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2899"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2899\/revisions"}],"predecessor-version":[{"id":31835,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2899\/revisions\/31835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/31834"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}