{"id":2882,"date":"2009-03-18T09:21:57","date_gmt":"2009-03-18T08:21:57","guid":{"rendered":""},"modified":"2016-01-24T13:43:21","modified_gmt":"2016-01-24T12:43:21","slug":"i-segni-della-morte","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-segni-della-morte\/","title":{"rendered":"I segni della morte"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/morte.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-29788\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/morte.jpg\" alt=\"morte\" width=\"250\" height=\"188\" \/><\/a>L&#8217;Osservatore Romano<\/strong><\/div>\n<div style=\"text-align: center;\">3 settembre 2008<\/div>\n<p style=\"text-align: justify;\"><em><em>A quarant&#8217;anni dal rapporto di Harvard. Seguono alcune considerazioni di <strong>Chiara Mantovani<\/strong> e <strong>Roberto De Mattei<\/strong> sulla morte cerebrale<\/em><\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Lucetta Scaraffia<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Quarant&#8217;anni fa, verso la fine dell&#8217;estate del 1968, il cosiddetto rapporto di Harvard cambiava la definizione di morte basandosi non pi\u00f9 sull&#8217;arresto cardiocircolatorio, ma sull&#8217;encefalogramma piatto: da allora l&#8217;organo indicatore della morte non \u00e8 pi\u00f9 soltanto il cuore, ma il cervello.Si tratta di un mutamento radicale della concezione di morte &#8211; che ha risolto il problema del distacco dalla respirazione artificiale, ma che soprattutto ha reso possibili i trapianti di organo &#8211; accettato da quasi tutti i Paesi avanzati (dove \u00e8 possibile realizzare questi trapianti), con l&#8217;eccezione del Giappone.<\/div>\n<p style=\"text-align: justify;\">Anche la Chiesa cattolica, consentendo il trapianto degli organi, accetta implicitamente questa definizione di morte, ma con molte riserve: per esempio, nello Stato della Citt\u00e0 del Vaticano non \u00e8 utilizzata la certificazione di morte cerebrale. A ricordare questo fatto \u00e8 ora il filosofo del diritto Paolo Becchi in un libro (<em>Morte cerebrale e trapianto di organi<\/em>, Morcelliana) che &#8211; oltre a rifare la storia della definizione e dei dibattiti seguiti negli anni Settanta, tra i quali il pi\u00f9 importante \u00e8 senza dubbio quello di cui fu protagonista Hans Jonas &#8211; affronta con chiarezza la situazione attuale, molto pi\u00f9 complessa e controversa.<\/p>\n<p style=\"text-align: justify;\">Il motivo per cui questa nuova definizione \u00e8 stata accettata cos\u00ec rapidamente sta nel fatto che essa non \u00e8 stata letta come un radicale cambiamento del concetto di morte, ma soltanto &#8211; scrive Becchi &#8211; come &#8220;una conseguenza del processo tecnologico che aveva reso disponibili alla medicina pi\u00f9 affidabili strumenti per rilevare la perdita delle funzioni cerebrali&#8221;. La giustificazione scientifica di questa scelta risiede in una peculiare definizione del sistema nervoso, oggi rimessa in discussione da nuove ricerche, che mettono in dubbio proprio il fatto che la morte del cervello provochi la disintegrazione del corpo.<\/p>\n<p style=\"text-align: justify;\">Come dimostr\u00f2 nel 1992 il caso clamoroso di una donna entrata in coma irreversibile e dichiarata cerebralmente morta prima di accorgersi che era incinta; si decise allora di farle continuare la gravidanza, e questa prosegu\u00ec regolarmente fino a un aborto spontaneo. Questo caso e poi altri analoghi conclusi con la nascita del bambino hanno messo in questione l&#8217;idea che in questa condizione si tratti di corpi gi\u00e0 morti, cadaveri da cui espiantare organi. Sembra, quindi, avere avuto ragione Jonas quando sospettava che la nuova definizione di morte, pi\u00f9 che da un reale avanzamento scientifico, fosse stata motivata dall&#8217;interesse, cio\u00e8 dalla necessit\u00e0 di organi da trapiantare.<\/p>\n<p style=\"text-align: justify;\">Naturalmente, in proposito si \u00e8 aperta nel mondo scientifico una discussione, in parte raccolta nel volume, curato da Roberto de Mattei, <em>Finis vitae. <\/em><em>Is brain death still life?<\/em> (Rubbettino), i cui contributi &#8211; di neurologi, giuristi e filosofi statunitensi ed europei &#8211; sono concordi nel dichiarare che la morte cerebrale non \u00e8 la morte dell&#8217;essere umano. Il rischio di confondere il coma (morte corticale) con la morte cerebrale \u00e8 sempre possibile.<\/p>\n<p style=\"text-align: justify;\">E questa preoccupazione venne espressa al concistoro straordinario del 1991 dal cardinale Ratzinger nella sua relazione sul problema delle minacce alla vita umana: &#8220;Pi\u00f9 tardi, quelli che la malattia o un incidente faranno cadere in un coma &#8220;irreversibile&#8221;, saranno spesso messi a morte per rispondere alle domande di trapianti d&#8217;organo o serviranno, anch&#8217;essi, alla sperimentazione medica (&#8220;cadaveri caldi&#8221;)&#8221;.<\/p>\n<p style=\"text-align: justify;\">Queste considerazioni aprono ovviamente nuovi problemi per la Chiesa cattolica, la cui accettazione del prelievo degli organi da pazienti cerebralmente morti, nel quadro di una difesa integrale e assoluta della vita umana, si regge soltanto sulla presunta certezza scientifica che essi siano effettivamente cadaveri.<\/p>\n<p style=\"text-align: justify;\">Ma la messa in dubbio dei criteri di Harvard apre altri problemi bioetici per i cattolici: l&#8217;idea che la persona umana cessi di esistere quando il cervello non funziona pi\u00f9, mentre il suo organismo &#8211; grazie alla respirazione artificiale &#8211; \u00e8 mantenuto in vita, comporta una identificazione della persona con le sole attivit\u00e0 cerebrali, e questo entra in contraddizione con il concetto di persona secondo la dottrina cattolica, e quindi con le direttive della Chiesa nei confronti dei casi di coma persistente. Come ha fatto notare Peter Singer, che si muove su posizioni opposte a quelle cattoliche: &#8220;Se i teologi cattolici possono accettare questa posizione in caso di morte cerebrale, dovrebbero essere in grado di accettarla anche in caso di anencefalie&#8221;.<\/p>\n<p style=\"text-align: justify;\">Facendo il punto sulla questione, Becchi scrive che &#8220;l&#8217;errore, sempre pi\u00f9 evidente, \u00e8 stato quello di aver voluto risolvere un problema etico-giuridico con una presunta definizione scientifica&#8221;, mentre il nodo dei trapianti &#8220;non si risolve con una definizione medico-scientifica della morte&#8221;, ma attraverso l&#8217;elaborazione di &#8220;criteri eticamente e giuridicamente sostenibili e condivisibili&#8221;.<\/p>\n<p style=\"text-align: justify;\">La Pontificia Accademia delle Scienze &#8211; che negli anni Ottanta si era espressa a favore del rapporto di Harvard \u2013 nel 2005 \u00e8 tornata sul tema con un convegno su &#8220;I segni della morte&#8221;. Il quarantesimo anniversario della nuova definizione di morte cerebrale sembra quindi riaprire la discussione, sia dal punto di vista scientifico generale, sia in ambito cattolico, al cui interno l&#8217;accettazione dei criteri di Harvard viene a costituire un tassello decisivo per molte altre questioni bioetiche oggi sul tappeto, e per il quale al tempo stesso costa rimettere in discussione uno dei pochi punti concordati tra laici e cattolici negli ultimi decenni.<\/p>\n<p style=\"text-align: center;\"><strong>* * *<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Agenzia Zenit <\/strong>luned\u00ec, 8 settembre 2008<\/p>\n<p style=\"text-align: center;\"><strong>MORTE QUANDO?<\/strong><\/p>\n<p><em>ROMA &#8211; Pubblichiamo di seguito per la rubrica di Bioetica l&#8217;intervento della dottoressa <strong>Chiara Mantovani<\/strong>, Presidente dell&#8217;Associazione Medici Cattolici Italiani (AMCI) di Ferrara e Presidente di Scienza &amp; Vita di Ferrara.<\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>* * *<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Lucetta Scaraffia, dalle pagine dell\u2019Osservatore Romano, riapre una questione che periodicamente solleva discussioni e perplessit\u00e0: la dichiarazione di morte di una persona umana.<\/p>\n<p style=\"text-align: justify;\">L\u2019argomento \u00e8 terribile ed affascinante: conosco persone che, tanti anni fa, si iscrissero ad una associazione di donatori d\u2019organo spinte dal solo terrore di essere sepolti vivi. Meglio star certi di finire nella cassa senza rischi di svegliarsi. Il che non \u00e8 propriamente una dimostrazione di fiducia nella perizia medica, ma ha una sua giustificazione emotiva.<\/p>\n<p style=\"text-align: justify;\">Non sar\u00e0 forse inutile ripetere alcune piccole considerazioni, tenendo presente sia gli aspetti tecnico-scientifici che quelli etici; non affrontando quelli medico-legali, per il solo motivo che essi sono regolati dalla legislazione, sulla quale attualmente non c\u2019\u00e8 modo di agire: questo \u00e8 dunque un aspetto ininfluente non sulla prassi, ma certamente sulla comprensione del problema.<\/p>\n<p style=\"text-align: justify;\">Per\u00f2 resta vero, e anzi assolutamente notabile, che la legislazione si avvale, per esprimersi, di basi di competenza che le sono estranee: ecco il ruolo della scienza medica supportata dal corredo tecnico sufficiente a fornire basi oggettive. Cos\u00ec come \u00e8 doveroso rimarcare che la nostra legislazione prevede i protocolli pi\u00f9 aderenti alle notizie scientifiche certe di cui disponiamo, diversamente da quanto accade in altri Stati europei o nordamericani<\/p>\n<p style=\"text-align: justify;\">E diciamo subito una verit\u00e0 tanto sgradevole quanto evidente: prima o poi bisogna consegnare il corpo morto ad un seppellitore. Oggi anche ad un inceneritore, a causa del poco spazio disponibile per i cimiteri nelle aree urbane e ancor pi\u00f9 il disagio psicologico del pensiero della decomposizione. Non si tratta di cinismo, ma solo di realismo.<\/p>\n<p style=\"text-align: justify;\">Per cominciare \u00e8 indispensabile fare chiarezza sui termini usati: leggo affermazioni tanto inesatte al punto da fraintendere la realt\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>Morte cerebrale<\/strong>: \u00e8 una espressione errata, dannosa, fuorviante. Troppo usata, purtroppo, come sinonimo di <strong>\u201cmorte encefalica<\/strong>\u201d, che invece \u00e8 tutta un\u2019altra questione. Per dare un\u2019idea, anche se grossolana: come se affermassimo che dormire profondamente \u00e8 come essere morto.<\/p>\n<p style=\"text-align: justify;\">Invece, con \u201cmorte encefalica\u201d si intende il silenzio elettrico (l\u2019assenza totale, ripetutamente registrata, di ogni attivit\u00e0 nella corteccia cerebrale, nel ponte e nel bulbo: tutto l\u2019encefalo!) di ogni struttura deputata a generare e coordinare qualsiasi altra attivit\u00e0 del corpo.<\/p>\n<p style=\"text-align: justify;\">Anche solo da questa generica definizione chiunque pu\u00f2 capire che se uno che sembra morto, perch\u00e9 magari non risponde alle parole e ai suoni intorno a lui, ma invece respira da solo e il suo cuore batte autonomamente, evidentemente non \u00e8 davvero morto! Succede che una parte dell\u2019encefalo sia rovinata, ma non tutto: ci\u00f2 che regola cuore e polmoni funziona! Non entriamo qui nel delicato argomento di come si voglia considerare la vita di questa ipotetica (ma poi mica tanto!) persona: sofferente, non dignitosa, inutile, insopportabile (per gli altri). Queste sono valutazioni diverse dalla semplice constatazione che la vita non ha abbandonato quel corpo.<\/p>\n<p style=\"text-align: justify;\"><strong>Come stabiliamo la morte? Rilevando la cessazione delle funzioni che conosciamo necessarie alla vita: respirazione e circolazione.<\/strong> Chiaramente deve essere una cessazione, non una temporanea e breve interruzione; ma sappiamo anche che un quarto d\u2019ora nell\u2019adulto, mezzoretta nel bambino, senza respirare e\/o battere del cuore (e le due cose sono strettamente collegate) causano la morte.<\/p>\n<p style=\"text-align: justify;\">In pratica: senza ossigeno (procurato nei polmoni) distribuito in tutto il corpo dalla pompa-cuore, il cervello (tutto il cervello!!!) si danneggia e non funziona pi\u00f9, ovvero non \u00e8 in grado di assolvere alla sua funzione di struttura di coordinamento e di input per tutte le funzioni vitali.<\/p>\n<p style=\"text-align: justify;\">E\u2019 un meraviglioso meccanismo autoregolamentato: l\u2019encefalo fa da centralina elettrica, la circolazione porta l\u2019ossigeno dai polmoni alla periferia, anche alla centralina stessa. Interrompere a qualsiasi livello queste funzioni integrate \u00e8 mettere la macchina corporea fuori uso. Se vediamo qualcuno gravemente traumatizzato, trapassato da pallottole, esanime, senza respirazione, intuiamo la sua morte; ma il motivo vero, in ultima analisi, \u00e8 sempre riconducibile all\u2019impossibilit\u00e0 di assicurare ossigeno e acqua ai tessuti!<\/p>\n<p style=\"text-align: justify;\">Non sembri, questa elementare descrizione dei meccanismi fisici, dettata da indifferenza verso i sempre presenti significati metafisici: ma \u00e8 troppa la confusione attualmente presente per tralasciare il lato pi\u00f9 concreto.<\/p>\n<p style=\"text-align: justify;\"><strong>Coma (depass\u00e9, profondo: aggettivi ancora usati ma inesatti) stato vegetativo (permanente o persistente che dir si voglia: in ogni modo si dice impropriamente), non sono equivalenti della morte encefalica: ovvero dello stato in cui, per quel che ne sappiamo finora, la capacit\u00e0 di provvedere ai processi vitali (appunto quelli che consentono la vita) \u00e8 venuta meno<\/strong>.<\/p>\n<p style=\"text-align: justify;\">E con chiarezza si pu\u00f2 affermare che <strong>oggi in Italia la legge consente l\u2019espianto di organi solo in caso di morte accertata con criteri neurologici che definiscano un quadro di morte encefalica e non cerebrale<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Per dirla bene<strong>: l\u2019elettroencefalogramma piatto NON \u00e8 ancora morte encefalica, non si espiantano organi se i centri profondi bulbari danno ancora segno di attivit\u00e0 elettrica.<\/strong><\/p>\n<p style=\"text-align: justify;\">In altri luoghi del mondo pu\u00f2 succedere: ci giungono notizie che un metodo per giustiziare i condannati in Cina sia l\u2019espianto in vivo, ma fortunatamente non siamo in Cina (almeno finora).<\/p>\n<p style=\"text-align: justify;\">Qualcuno pu\u00f2 riferire di una certa \u201cfretta\u201d nel cercare di ottenere il permesso dei parenti (in Italia ancora vincolante): e qui si apre la voragine di un corretto rapporto e comunicazione dei medici nei confronti dei pazienti e delle loro famiglie.<\/p>\n<p style=\"text-align: justify;\">C\u2019\u00e8 poi il grande dramma psicologico di vedere qualcuno che amiamo sottoposto a ci\u00f2 che sembra una cura medica (circolazione e ventilazione forzate per mantenere quel necessario apporto di ossigeno): bisognerebbe spiegare bene che sono solo i tempi richiesti proprio per quell\u2019accertamento rigoroso dei criteri di morte encefalica; bisognerebbe riuscire a far intendere che \u00e8 proprio un meccanismo di sicurezza per accorgersi se ci si \u00e8 sbagliati, se una registrazione si \u00e8 interrotta dando risultati falsati. E\u2019 durissimo vedere e sentir parlare di \u201ccadavere a cuore battente\u201d, perch\u00e9 siamo tradizionalmente legati all\u2019immagine del cuore come centro della vita, ma \u00e8 indispensabile fare uno sforzo chiarificatore per togliere, per quanto \u00e8 possibile, l\u2019illusione di vita.<\/p>\n<p style=\"text-align: justify;\">Certamente nessuna legge riesce ad impedire l\u2019abuso: e la consapevolezza di questo dovrebbe sempre accompagnare il legislatore, inducendolo ad una prudenza e ad una umilt\u00e0 che consentano sempre l\u2019aggiornamento sulla base di eventuali nuove scoperte tecnico-scientifiche.<\/p>\n<p style=\"text-align: justify;\">Leggo nell\u2019articolo di Lucetta Scaraffia cui facevo riferimento all\u2019inizio: Come ha fatto notare Peter Singer, che si muove su posizioni opposte a quelle cattoliche: &#8220;Se i teologi cattolici possono accettare questa posizione in caso di morte cerebrale, dovrebbero essere in grado di accettarla anche in caso di anencefalie&#8221;.<\/p>\n<p style=\"text-align: justify;\">Mi sia consentito replicare sommessamente a Singer che il problema non \u00e8 \u201ccattolico\u201d: i teologi cattolici esprimono posizioni coerenti con la teologia partendo dai dati di ragione forniti da altre discipline. E ci\u00f2 che stride \u00e8 proprio che in realt\u00e0 il comportamento consigliato dai teologi morali di fede cattolica \u00e8 coerente con le coordinate espresse finora: il paziente anencefalico dovrebbe essere (e in Italia lo \u00e8!) monitorato per tutta quella parte di encefalo che ha e solo al raggiungimento del silenzio elettrico \u00e8 dichiarato morto!<\/p>\n<p style=\"text-align: justify;\">Si applica proprio in questo caso-limite tutta la prudenza invocata prima: se bastasse solo un EEG, visto che non c\u2019\u00e8 niente da controllare (il bimbo anencefalico ha solo piccole parti di cervello, spesso non la corteccia) sarebbe dichiarato morto subito. Invece si va oltre, si aspetta che ogni pi\u00f9 piccolo segnale sia cessato, e si aspetta che sia cessato per un tempo doppio rispetto all\u2019adulto perch\u00e9 conosciamo la maggiore resistenza del tessuto nervoso del neonato all\u2019anossia.<\/p>\n<p style=\"text-align: justify;\">Se si ragionasse nei termini di \u201cassenza di coscienza\u201d (senza corteccia cerebrale non c\u2019\u00e8 coscienza) si darebbe ragione al signor Singer, il quale, dal canto suo, non ha neppure bisogno dell\u2019EEG per dichiarare un essere umano una non-persona: per lui fino a quando non si hanno capacit\u00e0 di parola e relazione, non si ha dignit\u00e0 umana! Se si ragionasse nei termini di vita degna-non degna, si potrebbero accelerare i tempi di morte di pazienti senza corteccia funzionante (senza capacit\u00e0 di relazione), ma con il cuore che batte da solo e con i polmoni che scambiano anidride carbonica con ossigeno.<\/p>\n<p style=\"text-align: justify;\">Invece la testardaggine tutta cristiana di appoggiarsi al dato reale ci protegge fino in fondo. Quando sussiste segno di vita, \u00e8 vita. Bella, brutta, gradevole o puzzolente, \u00e8 vita.<\/p>\n<p style=\"text-align: justify;\">Ma nell\u2019articolo uscito il 3 settembre, si riportava anche un\u2019altra affermazione francamente sorprendente: Facendo il punto sulla questione, Becchi scrive che \u201cl\u2019errore, sempre pi\u00f9 evidente, \u00e8 stato quello di aver voluto risolvere un problema etico-giuridico con una presunta definizione scientifica\u201d, mentre il nodo dei trapianti \u201cnon si risolve con una definizione medico-scientifica della morte\u201d, ma attraverso l\u2019elaborazione di \u201ccriteri eticamente e giuridicamente sostenibili e condivisibili\u201d.<\/p>\n<p style=\"text-align: justify;\">Forse fraintendo, me lo auguro, ma qui c\u2019\u00e8 un invito a prescindere dai fatti. Che cosa pu\u00f2 appoggiare legittimamente il giudizio se non la conoscenza del fatto, nella misura che \u00e8 possibile alla ragione e all\u2019esperienza? Quando la morte si accertava con lo specchietto (se si appannava, si era vivi; se no, si era sepolti. E per giunta senza aspettare troppo tempo, per via della puzza) si commettevano delitti contro l\u2019etica o contro la buona pratica clinica? E poi la verit\u00e0 su cui appoggiare il giudizio dovrebbe scaturire dall\u2019accordo su ci\u00f2 che \u00e8 giusto? Mettiamo ai voti i criteri di accertamento della morte?<\/p>\n<p style=\"text-align: justify;\">Il problema etico \u00e8 di (apparente) semplice soluzione: si dispone con rispetto del cadavere, si tratta con rispetto il vivente. Mi pare superfluo soffermarmi sulla differenza tra \u201cdisporre\u201d e \u201ctrattare\u201d.<\/p>\n<p style=\"text-align: justify;\">La natura di cosa, ancorch\u00e9 nobile, del corpo morto attiene alla sostanza cadaverica; la natura di persona del corpo vivente attiene alla sostanza di essere. L\u2019una e l\u2019altra vedono nei loro confronti applicata l\u2019etica quando ricevono un trattamento adeguato alla rispettiva natura.<\/p>\n<p style=\"text-align: justify;\">Il problema giuridico \u00e8 pi\u00f9 complesso perch\u00e9 si tratta di tradurre in pratica norme valide per ogni situazione. E in un panorama etico e sociale diviso, anzi, frammentato, come il moderno, questa \u00e8 operazione sempre pi\u00f9 complessa. Ma se anche la legislazione si allontana dalla concretezza del dato conosciuto e onestamente riconosciuto, e se cade nel tranello della concertazione, allora non so immaginare quale possibilit\u00e0 possa avere l\u2019etica di trovare un fondamento comune.<\/p>\n<p style=\"text-align: center;\"><em><strong>* * *<\/strong> <\/em><\/p>\n<p style=\"text-align: center;\"><strong>Considerazioni sulla \u201cmorte cerebrale\u201d dopo l\u2019articolo dell\u2019\u201cOsservatore Romano\u201d<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>L\u2019intolleranza mediatica contro l\u2019editoriale di Lucetta Scaraffia, I segni della morte, sull\u2019\u201cOsservatore Romano\u201d del 3 settembre 2008, suggerisce alcune considerazioni sul tema delicato e cruciale della morte cerebrale.<\/em><\/p>\n<p style=\"text-align: center;\"><strong>Roberto De Mattei<\/strong><\/p>\n<p style=\"text-align: justify;\">Tutti possono consentire sulla definizione, in negativo, della morte come \u201cfine della vita\u201d. Ma che cos\u2019\u00e8 la vita? La biologia attribuisce la qualifica di vivente ad un organismo che ha in s\u00e9 stesso un principio unitario e integratore che ne coordina le parti e ne dirige l\u2019attivit\u00e0. Gli organismi viventi sono tradizionalmente distinti in vegetali, animali ed umani.<\/p>\n<p style=\"text-align: justify;\">La vita della pianta, dell\u2019animale e dell\u2019uomo, pur di natura diversa, presuppone, in ogni caso un sistema integrato animato da un\u00a0 principio attivo e unificatore. La morte dell\u2019individuo vivente, sul piano biologico, \u00e8 il momento in cui il principio vitale che gli \u00e8 proprio cessa le sue funzioni. Lasciamo da parte il fatto che, per l\u2019essere umano, questo principio vitale, definito anima, sia di natura spirituale e incorruttibile. Fermiamoci al concetto, unanimamente ammesso, che l\u2019uomo pu\u00f2 dirsi clinicamente morto quando il principio che lo vivifica si \u00e8 spento e l\u2019organismo, privato del suo centro ordinatore, inizia un processo di dissoluzione che porter\u00e0 alla progressiva decomposizione del corpo.<\/p>\n<p style=\"text-align: justify;\">Ebbene, la scienza non ha finora potuto dimostrare che il principio vitale dell\u2019organismo umano risieda in alcun organo del corpo. Il sistema integratore del corpo, considerato come un \u201ctutto\u201d, non \u00e8 infatti localizzabile in un singolo organo, sia pure importante, come il cuore o l\u2019encefalo. Le attivit\u00e0 cerebrali e cardiache presuppongono la vita, ma non \u00e8 propriamente in esse la causa della vita.<\/p>\n<p style=\"text-align: justify;\">Non bisogna confondere le attivit\u00e0 con il loro principio. La vita \u00e8 qualcosa di inafferrabile che trascende i singoli organi materiali, dell\u2019essere animato, e che non pu\u00f2 essere misurata materialmente, e tanto meno creata: \u00e8 un mistero della natura, su cui \u00e8 giusto che la scienza indaghi, ma di cui la scienza non \u00e8 padrona. Quando la scienza pretende di creare o manipolare la vita, si fa essa stessa filosofia e religione, scivolando nello \u201cscientismo\u201d.<\/p>\n<p style=\"text-align: justify;\">Il volume Finis Vitae. La morte cerebrale \u00e8 ancora vita?, pubblicato in coedizione dal Consiglio Nazionale delle Ricerche e da Rubbettino (Soveria Mannelli 2008), con il contributo di diciotto studiosi internazionali, dimostra questi concetti in quasi cinquecento pagine.<\/p>\n<p style=\"text-align: justify;\">Non solo non pu\u00f2 essere accettato il criterio neurologico che fa riferimento alla &#8220;morte corticale&#8221;, perch\u00e9 in essa rimane integro parte dell\u2019encefalo e permane attiva la capacit\u00e0 di regolazione centrale delle funzioni omeostatiche e vegetative; non solo non pu\u00f2 essere accettato il criterio che fa riferimento alla morte del tronco-encefalo, perch\u00e9 non \u00e8 dimostrato che le strutture al di sopra del tronco abbiano perso la possibilit\u00e0 di funzionare se stimolate in altro modo; ma neppure pu\u00f2 essere accettato il criterio della cosiddetta &#8220;morte cerebrale&#8221;, intesa come cessazione permanente di tutte le funzioni dell\u2019encefalo (cervello, cervelletto e tronco cerebrale) con la conseguenza di uno stato di coma irreversibile.<\/p>\n<p style=\"text-align: justify;\">Lo stesso prof. Carlo Alberto De Fanti, il neurologo che vuole staccare la spina a Liliana Englaro, autore di un libro dedicato a questo argomento (Soglie, Bollati Boringhieri, Torino 2007), ha ammesso che \u00a0la morte cerebrale pu\u00f2 essere forse definita un \u201cpunto di non ritorno\u201d, ma \u201cnon coincide con la morte dell\u2019organismo come un tutto (che si verifica solo dopo l\u2019arresto cardiocircolatorio)\u201d (\u201cL\u2019Unit\u00e0\u201d, 3 settembre 2008). E\u2019 evidente come il \u201cpunto di non ritorno\u201d, posto che sia realmente tale, \u00e8 una situazione di gravissima menomazione, ma non \u00e8 la morte dell\u2019individuo.<\/p>\n<p style=\"text-align: justify;\">L\u2019irreversibilit\u00e0 della perdita delle funzioni cerebrali, accertata dall\u2019\u201cencefalogramma piatto\u201d, non dimostra la morte dell\u2019individuo. La perdita totale dell\u2019unitariet\u00e0 dell\u2019organismo, intesa come la capacit\u00e0 di integrare e coordinare l\u2019insieme delle sue funzioni, non dipende infatti dall\u2019encefalo, e neppure dal cuore.<\/p>\n<p style=\"text-align: justify;\">L\u2019accertamento della cessazione del respiro e del battito del cuore non significa che nel cuore o nei polmoni stia la fonte della vita. Se la tradizione giuridica e medica, non solo occidentale, ha da sempre ritenuto che la morte dovesse essere accertata attraverso la cessazione delle attivit\u00e0 cardiocircolatorie \u00e8 perch\u00e9 l\u2019esperienza dimostra che all\u2019arresto di tali attivit\u00e0 fa seguito, dopo alcune ore, il rigor mortis e quindi l\u2019inizio della disgregazione del corpo.<\/p>\n<p style=\"text-align: justify;\">Ci\u00f2 non accade in alcun modo dopo la cessazione delle attivit\u00e0 cerebrali. Oggi la scienza fa s\u00ec che donne con encefalogramma piatto possano portare a termine la gravidanza, mettendo al mondo bambini sani. Un individuo in stato di \u201ccoma irreversibile\u201d pu\u00f2 essere tenuto in vita, con il supporto di mezzi artificiali; un cadavere non potr\u00e0 mai essere rianimato, neppure collegandolo a sofisticati apparecchi.<\/p>\n<p style=\"text-align: justify;\">Restano da aggiungere alcune considerazioni. Il direttore del Centro Nazionale Trapianti, \u00a0Alessandro Nanni Costa, ha dichiarato i criteri di Harvard \u201cnon sono mai stati messi in discussione dalla comunit\u00e0 scientifica\u201d (\u201cLa Repubblica\u201d, 3 settembre 2008). Se anche ci\u00f2 fosse vero, e non lo \u00e8, \u00e8 facile rispondere che ci\u00f2 che caratterizza la scienza \u00e8 proprio la sua capacit\u00e0 di porre sempre in discussione i risultati acquisiti.<\/p>\n<p style=\"text-align: justify;\">Qualsiasi epistemologo sa che la finalit\u00e0 della scienza non \u00e8 produrre certezze, bens\u00ec ridurre le incertezze. Altri, come il prof. Francesco D\u2019Agostino, presidente onorario del Comitato Nazionale di Bioetica, sostengono che, sul piano scientifico, la tesi contraria alla morte cerebrale \u201c\u00e8 ampiamente minoritaria\u201d (\u201cIl Giornale\u201d, 3 settembre 2008).<\/p>\n<p style=\"text-align: justify;\">Il prof. D\u2019Agostino ha scritto belle pagine in difesa del diritto naturale e non pu\u00f2 ignorare che il criterio della maggioranza pu\u00f2 avere rilievo sotto l\u2019aspetto politico e sociale, non certo quando si tratta di verit\u00e0 filosofiche o scientifiche. Intervenendo nel dibattito, una studiosa \u201claica\u201d come Luisella Battaglia osserva che \u201cil valore degli argomenti non si misura dal numero delle persone che vi aderiscono\u201d e \u201cil fatto che i dubbi siano avanzati da frange minoritarie non ha alcuna rilevanza dal punto di vista della validit\u00e0 delle tesi sostenute\u201d (\u201cIl Secolo XIX\u201d, 4 settembre 2008).<\/p>\n<p style=\"text-align: justify;\">Sul piano morale poi l\u2019esistenza stessa di una possibilit\u00e0 di vita esige l\u2019astensione dall\u2019atto potenzialmente omicida. Se esiste anche solo il dieci per cento che dietro un cespuglio vi sia un uomo, nessuno \u00e8 autorizzato ad aprire il fuoco. In campo bioetico, il principio in dubio pro vita resta centrale.<\/p>\n<p style=\"text-align: justify;\">La verit\u00e0 \u00e8 che la definizione della morte cerebrale fu proposta dalla Harvard Medical School, nell\u2019estate del 1968, pochi mesi dopo il primo trapianto di cuore di Chris Barnard (dicembre 1967), per giustificare eticamente i trapianti di cuore, che prevedevano che il cuore dell\u2019espiantato battesse ancora, ovvero che, secondo i canoni della medicina tradizionale, egli fosse ancora vivo.<\/p>\n<p style=\"text-align: justify;\">L\u2019espianto, in questo caso equivaleva ad un omicidio, sia pure compiuto \u201ca fin di bene\u201d. La scienza poneva la morale di fronte a un drammatico quesito: \u00e8 lecito sopprimere un malato, sia pure condannato a morte, o irreversibilmente leso, per salvare un\u2019altra vita umana, di \u201cqualit\u00e0\u201d superiore?<\/p>\n<p style=\"text-align: justify;\">Di fronte a questo bivio, che avrebbe dovuto imporre un serrato confronto tra opposte teorie morali, l\u2019Universit\u00e0 di Harvard si assunse la responsabilit\u00e0 di una \u201cridefinizione\u201d del concetto di morte che permettesse di aprire la strada ai trapianti, aggirando le secche del dibattito etico.<\/p>\n<p style=\"text-align: justify;\">Non c\u2019era bisogno di dichiarare lecita l\u2019uccisione del paziente vivo; era sufficiente dichiararlo clinicamente morto. In seguito al rapporto scientifico di Harvard, la definizione di morte venne cambiata in quasi tutti gli Stati americani e, in seguito, anche nella maggior parte dei Paesi cosiddetti sviluppati (in Italia, la \u201csvolta\u201d fu segnata dalla legge 29 dicembre 1993 n. 578 che all\u2019art. 1 recita: \u201cLa morte si identifica con la cessazione irreversibile di tutte le funzioni del cervello\u201d).<\/p>\n<p style=\"text-align: justify;\">La natura del dibattito non \u00e8 dunque scientifica, ma etica. Che questa sia la verit\u00e0 lo conferma il senatore del PD Ignazio Marino che in un articolo su \u201cRepubblica\u201d del 3 settembre definisce l\u2019articolo dell\u2019\u201cOsservatore Romano\u201d \u201cun atto irresponsabile che rischia di mettere in pericolo la possibilit\u00e0 di salvare centinaia di migliaia di vite grazie alla donazione degli organi\u201d.<\/p>\n<p style=\"text-align: justify;\">Queste parole insinuano innanzitutto una menzogna: quella che il rifiuto della morte cerebrale porti alla cessazione di ogni tipo di donazione, laddove il problema etico non riguarda la maggior parte dei trapianti, ma si pone solo per il \u00a0prelievo di organi vitali che comporti la morte del donatore, come \u00e8 il caso dell\u2019espianto del cuore. Ci\u00f2 spiega come Benedetto XVI, che ha sempre nutrito riserve verso il concetto di morte cerebrale, si sia a suo tempo detto favorevole alla donazione di organi (cfr. Sandro Magister, Trapianti e morte cerebrale, l\u2019\u201cOsservatore Romano\u201d ha rotto il tab\u00f9, <span style=\"text-decoration: underline;\">www.chiesa<\/span>).<\/p>\n<p style=\"text-align: justify;\">Il vero problema \u00e8 che il prezzo da pagare per salvare queste vite \u00e8 quello tragico di sopprimerne altre. Si vuole sostituire il principio utilitaristico secondo cui si pu\u00f2 fare il male per ottenere un bene, alla massima occidentale e cristiana secondo cui non \u00e8 lecito fare il male, neppure per ottenere un bene superiore.<\/p>\n<p style=\"text-align: justify;\">Se un tempo i \u201csegni\u201d tradizionali della morte dovevano accertare che una persona viva non fosse considerata morta, oggi il nuovo criterio harvardiano pretende di trattare il vivente come un cadavere per poterlo espiantare. A monte di tutto questo sta quel medesimo disprezzo per la vita umana che dopo avere imposto la legislazione sull\u2019aborto vuole spalancare la strada a quella sull\u2019eutanasia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;Osservatore Romano 3 settembre 2008 A quarant&#8217;anni dal rapporto di Harvard. Seguono alcune considerazioni di Chiara Mantovani e Roberto De Mattei sulla morte cerebrale di Lucetta Scaraffia<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-segni-della-morte\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":29788,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,55],"tags":[1550],"class_list":["post-2882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bioetica","category-eutanasia","tag-morte-cerebrale","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I segni della morte - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-segni-della-morte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I segni della morte - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-segni-della-morte\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-03-18T08:21:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-24T12:43:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/morte.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"256\" \/>\n\t<meta property=\"og:image:height\" content=\"192\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-segni-della-morte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-segni-della-morte\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"I segni della morte\",\"datePublished\":\"2009-03-18T08:21:57+00:00\",\"dateModified\":\"2016-01-24T12:43:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-segni-della-morte\\\/\"},\"wordCount\":4071,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-segni-della-morte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/morte.jpg\",\"keywords\":[\"morte cerebrale\"],\"articleSection\":[\"Bioetica\",\"Eutanasia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-segni-della-morte\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-segni-della-morte\\\/\",\"name\":\"I segni della morte - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-segni-della-morte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-segni-della-morte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/morte.jpg\",\"datePublished\":\"2009-03-18T08:21:57+00:00\",\"dateModified\":\"2016-01-24T12:43:21+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-segni-della-morte\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-segni-della-morte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-segni-della-morte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/morte.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/morte.jpg\",\"width\":256,\"height\":192},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-segni-della-morte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I segni della morte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I segni della morte - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-segni-della-morte\/","og_locale":"it_IT","og_type":"article","og_title":"I segni della morte - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-segni-della-morte\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-03-18T08:21:57+00:00","article_modified_time":"2016-01-24T12:43:21+00:00","og_image":[{"width":256,"height":192,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/morte.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"20 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-segni-della-morte\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-segni-della-morte\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"I segni della morte","datePublished":"2009-03-18T08:21:57+00:00","dateModified":"2016-01-24T12:43:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-segni-della-morte\/"},"wordCount":4071,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-segni-della-morte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/morte.jpg","keywords":["morte cerebrale"],"articleSection":["Bioetica","Eutanasia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-segni-della-morte\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-segni-della-morte\/","name":"I segni della morte - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-segni-della-morte\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-segni-della-morte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/morte.jpg","datePublished":"2009-03-18T08:21:57+00:00","dateModified":"2016-01-24T12:43:21+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-segni-della-morte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-segni-della-morte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-segni-della-morte\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/morte.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/morte.jpg","width":256,"height":192},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-segni-della-morte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"I segni della morte"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2882"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2882\/revisions"}],"predecessor-version":[{"id":29789,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2882\/revisions\/29789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/29788"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}