{"id":2880,"date":"2009-03-17T17:29:19","date_gmt":"2009-03-17T16:29:19","guid":{"rendered":""},"modified":"2015-02-12T20:19:48","modified_gmt":"2015-02-12T19:19:48","slug":"levoluzione-condanna-darwin","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/levoluzione-condanna-darwin\/","title":{"rendered":"L\u2019evoluzione condanna Darwin"},"content":{"rendered":"<div style=\"text-align: center;\"><strong>\u00a0Le Figaro Magazine<\/strong>, 26 ottobre 1991<\/div>\n<p style=\"text-align: justify;\"><em>Dal 13 al 19 ottobre, duecento scienziati, di cui quattro premi Nobel, si sono riuniti nel quadro degli \u201cIncontri di Blois\u201d. Tema: l\u2019origine della vita. Colloquio appassionante. Anche in questo campo le vecchie teorie crollano. Prospettive rivoluzionarie si aprono.<\/em><\/p>\n<p style=\"text-align: center;\"><strong>* * * <\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Per fare il punto su questa \u00abevoluzione degli evoluzionisti\u00bb, il Figaro-Magazine, da la parola a cinque scienziati di fama internazionale, in rappresentanza di cinque diverse discipline.<\/div>\n<p style=\"text-align: justify;\">Che cosa dicono? Che la teoria darwinista pu\u00f2 spiegare un certo numero di cose secondarie, ma non le fasi essenziali dell\u2019evoluzione (l\u2019apparizione dei nuovi organi, dei nuovi tipi di organizzazione, come gli uccelli, i vertebrati\u2026) mentre proprio a questo scopo era stata formulata.<\/p>\n<p style=\"text-align: justify;\">Ecco infine, esposto chiaramente, ci\u00f2 che alcuni cercano ancora di mantenere segreto: non abbiamo pi\u00f9, attualmente, una spiegazione globale dell\u2019evoluzione della vita sulla terra.<\/p>\n<p style=\"text-align: justify;\">Questa questione non ha solo un interesse scientifico o filosofico. In effetti come dice il biologo Michael Denton: \u00abLa filosofia, l\u2019etica dell\u2019uomo occidentale sono fondate in larga misura sulla sua rivendicazione centrale, ossia che l\u2019umanit\u00e0 sia nata da un processo completamente cieco di selezione di molecole.<\/p>\n<p style=\"text-align: justify;\">Il nostro secolo sarebbe incomprensibile senza la rivoluzione darwiniana. Le correnti sociali e politiche che hanno spazzato il mondo nel corso degli ultimi ottanta anni sarebbero state impossibili senza la sua sanzione intellettuale<em>.<\/em>\u00bb (<em>Evolution, a theory\u00a0 in crisis<\/em>, 1986).<\/p>\n<p style=\"text-align: justify;\">Esempio terribile: la testimonianza di Monsignor Cuthbert O\u2019Gara, che vide, nella sua diocesi in Cina, instaurarsi l\u2019Armata Rossa uscita dai corsi di \u2026 darwinismo.<\/p>\n<p style=\"text-align: justify;\">Il marxismo venne solo dopo: una volta che le mentalit\u00e0 si erano abituate all\u2019idea che la \u00ablotta selvaggia per la vita\u00bb era \u00abla caratteristica essenziale della Natura\u00bb. Alcuni mesi dopo la caduta della statua di Lenin, quella di Darwin vacilla a sua volta. Coincidenza inquietante.<\/p>\n<p style=\"text-align: center;\">* * *<\/p>\n<p style=\"text-align: center;\">Prof. <strong>ROBERTO FONDI<br \/>\n<\/strong><\/p>\n<p style=\"text-align: center;\"><em>Paleontologo, professore all\u2019Universit\u00e0 di Siena.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Nella natura, non a caso, esiste un programma! Influenze non materiali hanno dovuto agire nel corso dell\u2019evoluzione.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>In quanto paleontologo, pu\u00f2 dire se le scoperte effettuate in questo campo rispondono alle attese della teoria darwinista?<\/strong><\/p>\n<p style=\"text-align: justify;\">Pr. Fondi \u2013 La teoria darwinista, ma anche il pensiero evoluzionista iniziato da Lamarck, riposa su tre postulati:<\/p>\n<p style=\"text-align: justify;\">1. La vita \u00e8 stata generata in modo spontaneo, con l\u2019assemblaggio di diverse molecole;<\/p>\n<p style=\"text-align: justify;\">2. la vita ha subito un processo di trasformazione graduale che ha permesso di passare da forme semplici a organismi sempre pi\u00f9 complessi;<\/p>\n<p style=\"text-align: justify;\">3. la generazione della vita e la sua trasformazione sono state realizzate grazie all\u2019azione di forze naturali (elettromagnetiche, chimiche, gravitazionali, ecc.), e non metafisiche o spirituali.<\/p>\n<p style=\"text-align: justify;\">Per mostrare la falsit\u00e0 dei primi due postulati di questa mitologia moderna, la paleontologia \u00e8 sufficiente: le rocce pi\u00f9 antiche sono vecchie di 4 miliardi di anni. Ora i primi esseri viventi (alghe blu o batteri) appaiono 3,5 miliardi di anni fa. Non c\u2019\u00e8 dunque che un lasso di tempo di 500 milioni di anni per \u00abprodurre\u00bb il primo essere vivente, e questo \u00e8 troppo corto perch\u00e9 la vita abbia potuto essere prodotta per caso.<\/p>\n<p style=\"text-align: justify;\"><strong>Troppo corto?<\/strong><\/p>\n<p style=\"text-align: justify;\">Si: la cellula pi\u00f9 semplice che si possa immaginare \u00e8 gi\u00e0 un oggetto di una complessit\u00e0 inimmaginabile, con la sua famosa doppia elica di DNA che gli permette di duplicarsi. Quanto al secondo postulato, \u00e8 rifiutato dalla paleontologia del XX\u00b0 secolo: essa mostra che la storia della vita \u00e8 piena di discontinuit\u00e0, che non rientra negli schemi darwiniani.<\/p>\n<p style=\"text-align: justify;\"><strong>Quali sono queste discontinuit\u00e0?<\/strong><\/p>\n<p style=\"text-align: justify;\">La prima, come ho appena detto, \u00e8 l\u2019apparizione della vita stessa. Le rocce antiche non portano alcuna traccia del brodo di molecole &#8211; \u00abil brodo primordiale\u00bb &#8211; da dove sarebbe sorta la vita.<\/p>\n<p style=\"text-align: justify;\">Inoltre, le pi\u00f9 antiche forme di vita sono durate 3 miliardi e 200 milioni di anni e non portano alcuna novit\u00e0 di rilievo ad eccezione dell\u2019\u00abinvenzione\u00bb del nucleo cellulare. Poi, tre faune composte da organismi pluricellulari sono apparse all\u2019improvviso: queste faune sono cos\u00ec differenti le une dalle altre e cos\u00ec ravvicinate nel tempo che non permettono di concepire qualsiasi legame plausibile di \u00abdiscendenza con modifica\u00bb tra di loro.<\/p>\n<p style=\"text-align: justify;\">Lungo la storia della vita, assisteremo a delle apparizioni improvvise di forme nuove spesso radicalmente diverse tra loro che resteranno sostanzialmente immutate per milioni di anni, e che finiranno con estinzioni altrettanto improvvise e seguite, immediatamente, da nuove apparizioni. Cos\u00ec, se si immagina un albero genealogico dell\u2019evoluzione, non esistono che delle foglie e qualche ramo, ma niente nodi n\u00e9 tronco: \u00e8 un albero che non sta in piedi! Per questo, quando un paleontologo prende pubblicamente partito per le idee di Darwin, non \u00e8, secondo me, in pace con la sua coscienza.<\/p>\n<p style=\"text-align: justify;\"><strong>Che cosa si pu\u00f2 dedurre da tutto ci\u00f2 per quanto concerne il terzo postulato?<\/strong><\/p>\n<p style=\"text-align: justify;\">Pu\u00f2 essere messo in discussione. In effetti, secondo il punto di vista darwinista (anche quello di Gould, che ammette la discontinuit\u00e0 ma non vuole ricorrere ad altre spiegazioni che non siano mutazioni dovute al caso e alle leggi strettamente meccanicistiche), \u00e8 impossibile mostrare come queste discontinuit\u00e0, questi \u00absalti\u00bb possono essere superati.<\/p>\n<p style=\"text-align: justify;\">Possiamo dunque pensare che la materia vivente non sia solo quella che noi chiamiamo materia, ma sia una \u00abmateria informata\u00bb. Vale a dire che lo sviluppo degli organismi non \u00e8 solo determinato dal caso, dalla necessit\u00e0 o dalle leggi meccaniche, ma anche da un\u2019informazione, un programma inscritto nella materia vivente.<\/p>\n<p style=\"text-align: justify;\">Qui si tratta di un punto fondamentale. Se ammettiamo la necessit\u00e0 di modalit\u00e0 di informazione diverse da quelle strettamente materiali conosciute fino ad ora, per spiegare lo sviluppo della vita quale ci rivela la paleontologia, noi possiamo ammettere l\u2019esistenza di \u00abforme\u00bb o di archetipi. E allora tutto pu\u00f2 essere spiegato risalendo da un fenomeno agli archetipi che lo regolano.<\/p>\n<p style=\"text-align: justify;\">Per riassumere potrei dire che credo a una \u00abevoluzione per archetipi\u00bb. Le specie non appaiono a partire da niente, esse esistono gi\u00e0 nella realt\u00e0 sotto forme potenziali, sono la manifestazione di archetipi. Ogni archetipo pu\u00f2 esprimersi in numerose maniere \u2013 da cui le variazioni che costatiamo all\u2019interno di un tipo \u2013 ma non c\u2019\u00e8 intermediario possibile tra gli archetipi, da qui le discontinuit\u00e0 che costatiamo nell\u2019evoluzione.<\/p>\n<p style=\"text-align: justify;\"><strong>La maggioranza dei biologi senza dubbio non condivider\u00e0 questa visione.<\/strong><\/p>\n<p style=\"text-align: justify;\">Per me \u00e8 solo una questione di tempo. Gli evoluzionisti evolvono\u2026 E credo che non sia escluso che a partire dalla biologia si possa domani, cos\u00ec come partendo oggi dalla fisica, arrivare alla conclusione che la realt\u00e0 fisica non \u00e8 la realt\u00e0 completa.<\/p>\n<p style=\"text-align: center;\">* * *<\/p>\n<p style=\"text-align: center;\">Prof. <strong>JEAN DORST<\/strong> (1924-2001)<\/p>\n<p style=\"text-align: center;\">\u00a0<em>Zoologo, ex-direttore del Museo di Storia Naturale, Membro dell\u2019Accademia delle Scienze.<\/em><\/p>\n<p style=\"text-align: justify;\"><em><em>Una concezione materialista del mondo? Incoerente! Le \u00abmutazioni dovute al caso\u00bb (credo dei darwinisti) non spiegano l\u2019evoluzione\u2026<\/em><\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Sembrerebbe che ci fossero due tipi di evoluzione?<\/strong>Prof. Dorst. Si. C\u2019\u00e8 innanzitutto la micro-evoluzione: cio\u00e8 il passaggio progressivo da una specie ad un\u2019altra vicina alla prima. \u00c8 un fenomeno molto ben conosciuto, la si verifica nei laboratori dove migliaia di esperienze sono state effettuate. Ma c\u2019\u00e8 anche la macro-evoluzione, cio\u00e8 il passaggio da un tipo di organizzazione ad un altro, dai batraci ai rettili o dai rettili agli uccelli per esempio.<\/p>\n<p style=\"text-align: justify;\"><strong>Le teorie darwiniste attuali possono spiegarlo?<\/strong><\/p>\n<p style=\"text-align: justify;\">Georges Teissier, che fu uno dei miei professori diceva: \u00abUna piccola mutazione\u2026una piccola mutazione, ecc.\u00bb e si passerebbe cos\u00ec da una specie ad un\u2019altra, da un ordine ad un altro ordine \u2013 unicamente per l\u2019azione di piccole mutazioni \u00abdovute al caso\u00bb &#8211; e della selezione naturale deputata ad eliminare gli individui meno competitivi. Ecco il \u00abdarwinismo\u00bb, ma non \u00e8 vero. Vi \u00e8 qui una estrapolazione abusiva. I meccanismi che permettono di comprendere come una piccola \u00abdistanza\u00bb evolutiva (tra il lupo e il cane per esempio) possa essere oltrepassata non sono gli stessi di quelli che possono spiegare il superamento di una grande \u201cdistanza\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Su quali fatti si basa per dire questo?<\/strong><\/p>\n<p style=\"text-align: justify;\">Il mio maestro Pierre-P. Grass\u00e9 diceva: \u201cSpiegatemi l\u2019occhio e vi conceder\u00f2 tutto il resto\u201d. Non si vede (\u00e8 il caso di dirlo) come una successione di piccole mutazioni a caso potrebbe produrre un tale risultato. Ma la stessa cosa per l\u2019uscita dall\u2019acqua o per il passaggio da batraci a rettili, cos\u00ec come per gli uccelli. Ci vogliono tanti adattamenti complessi per permettere il volo che non si pu\u00f2, malgrado l\u2019esistenza di fossili come l\u2019archeopterix, spiegare la genesi degli uccelli con una \u00abmicro-evoluzione\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Tuttavia le teorie darwiniste pretendono di fornire una spiegazione globale dell\u2019evoluzione.<\/strong><\/p>\n<p style=\"text-align: justify;\">Uno dei miei amici, che \u00e8 marxista, ha l\u2019abitudine di dire che la filosofia \u00e8 come una stanza immersa nell\u2019oscurit\u00e0 pi\u00f9 totale dove c\u2019\u00e8 un gatto nero che si cerca di prendere, e che il marxismo \u00e8 anch\u2019esso una stanza buia nella quale non ci sono gatti neri, ma si grida ben forte che si \u00e8 preso il gatto!<\/p>\n<p style=\"text-align: justify;\">Ebbene, \u00e8 lo stesso per il darwinismo. Si grida che si \u00e8 \u201cafferrata\u201d la soluzione per spiegare l\u2019evoluzione, mentre questa soluzione non si trova nella stanza dove la si cerca! Non si pu\u00f2 spiegare il passaggio dall\u2019ameba all\u2019uomo in alcune centinaia di milioni di anni con i soli meccanismi postulati dai darwinisti.<\/p>\n<p style=\"text-align: justify;\">Una tale evoluzione tuttavia \u00e8 esistita, ma i fatti ci mostrano che un certo numero di \u00absalti\u00bb evolutivi, dei salti qualitativi e quantitativi insieme, hanno dovuto prodursi nel corso del suo svolgimento per rendere conto di tali salti bisogna che esistano altri meccanismi diversi da quelli che noi vediamo attualmente in azione nella natura. Bisogna dunque avere il coraggio di riconoscere che non abbiamo una spiegazione totale dell\u2019evoluzione.<\/p>\n<p style=\"text-align: justify;\"><strong>Lei \u00e8 dunque d\u2019accordo con la conclusione dell\u2019opera di Michael Denton che diceva: \u00abIl mistero dei misteri, l\u2019origine degli esseri viventi sulla terra \u00e8 sempre ugualmente enigmatico come all\u2019epoca in cui Darwin si imbarcava sul \u201cBeagle\u201d<\/strong> (1)<strong>\u00bb<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Si, nella maniera pi\u00f9 completa. Quest\u2019opera che \u00e8 stata molto criticata, e anche tacciata di opera \u201ccreazionista\u201d \u2013 cosa totalmente assurda \u2013 contiene degli errori e qualche estrapolazione, ma la sua conclusione generale \u00e8 assolutamente corretta: vediamo nascere delle nuove specie, ma sono sempre dei rettili, dei mammiferi, in breve trattasi di \u201cdej\u00e0 vu\u201d e non dei nuovi tipi di organizzazione. E noi non sappiamo come i tipi attuali si sono formati.<\/p>\n<p style=\"text-align: justify;\"><strong>Ci viene offerta comunque qualche pista?<\/strong><\/p>\n<p style=\"text-align: justify;\">A partire dal momento in cui, come credo, il caso non pu\u00f2 spiegare l\u2019evoluzione, si pone la questione della finalit\u00e0. Il finalismo \u00e8 la bestia nera degli scienziati\u2026 Allora, io sono finalista? In quanto scienziato mi proibisco di esserlo. Ma in fondo c\u2019\u00e8 quanto meno un disegno e questo disegno \u00e8 scritto nella natura che noi osserviamo, nell\u2019equilibrio tra le specie, che io constato in quanto ecologista, in certi adattamenti straordinari che si osservano (tra le piante e gli insetti, come \u00e8 noto) e che vanno ben aldil\u00e0 di quanto la teoria darwinista possa spiegare.<\/p>\n<p style=\"text-align: justify;\">Il caso esiste a livello della micro-evoluzione ma non esiste a livello fondamentale: a un tale livello esistono leggi che non abbiamo ancora identificato che permettono la realizzazione del programma.<\/p>\n<p style=\"text-align: justify;\"><strong>Si pu\u00f2 dire in questo caso che l\u2019uomo o i mammiferi sarebbero apparsi in ogni caso nell\u2019evoluzione, anche se questa fosse stata diversa?<\/strong><\/p>\n<p style=\"text-align: justify;\">Per l\u2019uomo non posso esserne certo ma per i mammiferi penso di si. Ho scritto nella prefazione a un opera collettiva che ho diretto: \u201csupponiamo che la vita sia apparsa altrove nell\u2019Universo, quale sarebbe la sua forma? \u00c8, naturalmente, una mia speculazione, ma io penso che sarebbe apparsa nello stesso modo, che si sarebbero ritrovati gli stessi tipi di organizzazione\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Tuttavia nella visione darwinista, \u00e8 escluso che lo stesso fenomeno si produca due volte in modo identico?<\/strong><\/p>\n<p style=\"text-align: justify;\">Questo perch\u00e9 la nozione di programma non \u00e8 presa in considerazione. Se tutto fosse dovuto al caso, la formazione di ogni specie risulterebbe da un accumulo di casi talmente improbabili da escludere che ci\u00f2 si produca pi\u00f9 di una volta.<\/p>\n<p style=\"text-align: justify;\"><strong>Abbiamo prove dell\u2019esistenza di simili programmi?<\/strong><\/p>\n<p style=\"text-align: justify;\">Si, quando un insetto imita un serpente, per esempio, si tratta di un puro caso, ma esistono delle farfalle che imitano altre farfalle e questo in maniera cos\u00ec perfetta che le si confondono, mentre si tratta di specie molto diverse (sul piano fisiologico). Ci\u00f2 \u00e8 tanto pi\u00f9 significativo in quanto \u00abl\u2019imitatore\u00bb non ha nessun interesse a farlo, essendo \u00abl\u2019imitato\u00bb tanto commestibile quanto lui\u2026 Come spieghereste questo senza dire che la vita obbedisce a un programma di sviluppo, a leggi che generano tali somiglianze?<\/p>\n<p style=\"text-align: justify;\"><strong>Per quanto riguarda l\u2019uomo, uno zoologo quale lei \u00e8 come spiega la differenza tra lui e lo scimpanz\u00e8?<br \/>\n<\/strong><br \/>\nLa differenza fra l\u2019uomo e lo scimpanz\u00e8 consiste in una differenza di un solo cromosoma, uno solo! Certo il nostro cervello \u00e8 pi\u00f9 grosso, ma quando si vedono delle differenze cos\u00ec deboli, la cosa ci spinge a pensare che ci\u00f2 che separa l\u2019uomo dalla scimmia non si situa soltanto nel piano neurologico o genetico. Il pensiero e l\u2019intelligenza non possono spiegarsi solo in termini neurologici. Ci sono innumerevoli lavori sull\u2019uomo e lo scimpanz\u00e8, ma non si \u00e8 mai trovato niente che spieghi come l\u2019uomo sia diventato quello che \u00e8, mentre lo scimpanz\u00e8 \u00e8 restato sugli alberi!<\/p>\n<p style=\"text-align: justify;\"><strong>Insomma, ascoltandola, si vede che l\u2019approccio materialista non pu\u00f2 arrivare a nulla, tanto a livello dello studio dell\u2019insieme dell\u2019evoluzione quanto a livello dello studio del pensiero dell\u2019uomo?<\/strong><\/p>\n<p style=\"text-align: justify;\">Si, assolutamente. Infatti, dire che una delle acquisizioni della scienza attuale \u00e8 che essa si oppone alla visione riduzionista della natura. Infatti, allo stato delle nostre conoscenze attuali, non \u00e8 possibile mettere in piedi una concezione materialista del mondo che sia coerente.<\/p>\n<p style=\"text-align: justify;\">Quanto a sapere se, dietro questo fenomeno che noi studiamo, c\u2019\u00e8, in azione nell\u2019evoluzione, questo pensiero universale, coerente e che ci supera, che noi chiamiamo Dio, \u00e8 una questione che non concerne lo scienziato in quanto tale. Ma che l\u2019uomo, senz\u2019altro, deve porsi.<\/p>\n<p style=\"text-align: center;\"><strong>* * *<\/strong><\/p>\n<p style=\"text-align: center;\">Prof. <strong>GIUSEPPE SERMONTI<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>Genetista, docente all\u2019Universit\u00e0 di Perugia, direttore della<\/em> Rivista di Biologia \u2013 Biology Forum.<\/p>\n<p style=\"text-align: justify;\"><em>Il darwinismo non \u00e8 solo falso, \u00e8 disonesto! I progressi della genetica non verificano le idee darwiniste: vi si oppongono.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Lei ha affermato a pi\u00f9 riprese di essere in opposizione all\u2019evoluzione?<\/strong><\/p>\n<p style=\"text-align: justify;\">Prof. Sermonti. No, \u00e8 un problema di termine: \u00abevoluzione\u00bb significa per lo pi\u00f9 \u00abtrasformazione con progresso dovuta al caso e alla selezione maturale\u00bb, vale a dire che c\u2019\u00e8 confusione tra il processo (la trasformazione) e la teoria che pretende di spiegare questo processo, la teoria darwinista; per questo non voglio usare questa parola.<\/p>\n<p style=\"text-align: justify;\"><strong>Qual \u00e8 dunque la sua visione dello sviluppo della vita?<\/strong><\/p>\n<p style=\"text-align: justify;\">Per me, l\u2019origine di una specie risiede in una trasformazione brusca da una specie all\u2019altra, un po\u2019 come una farfalla che \u00e8 generata da un bruco. Si tratta dunque di una visione non graduale di ci\u00f2 che si chiama \u00abevoluzione\u00bb. Abbiamo numerose ragioni per pensare che queste trasformazioni non possono essere state prodotte da dei meccanismi darwiniani.<\/p>\n<p style=\"text-align: justify;\"><strong>Quali sono i fatti che dimostrerebbero l\u2019inesattezza delle teorie darwiniste?<\/strong><\/p>\n<p style=\"text-align: justify;\">Contrariamente a ci\u00f2 che si crede, la genetica non si accorda assolutamente con la teoria darwinista. Cos\u00ec le mutazioni che si producono sulla famosa doppia elica di DNA, che costituisce la base delle nostre genesi, non sono mai costruttive. Le mutazioni possono essere vantaggiose, ma non possono essere positive perch\u00e9 costituiscono sempre la perdita di qualche cosa, la perdita di una funzione. Per esempio per la talpa \u00e8 vantaggioso essere cieca, ma non si pu\u00f2 dire che si tratti di un progresso, di una evoluzione positiva! Ebbene! Tutte le mutazioni conosciute sono come questa: non forniscono le basi per creare qualcosa di realmente nuovo.<\/p>\n<p style=\"text-align: justify;\"><strong>Anche quando nuovi tipi di drosofile sono ottenuti cos\u00ec?<\/strong><\/p>\n<p style=\"text-align: justify;\">Non c\u2019\u00e8 affatto apparizione di \u00abnovit\u00e0\u00bb: si tratta di modifiche del colore degli occhi, delle forme delle ali, dell\u2019atrofia di un organo. Non si tratta di evoluzione. Non c\u2019\u00e8 passaggio da un tipo di organizzazione ad un altro. Non c\u2019\u00e8 sviluppo di nuove funzioni!<\/p>\n<p style=\"text-align: justify;\">Per riassumere, la genetica ci mostra che c\u2019\u00e8 un\u2019unit\u00e0 del vivente poich\u00e9 il DNA \u00e8 lo stesso ovunque e che, quindi, una specie deriva da un\u2019altra specie. Ma essa ci mostra anche che questa derivazione non pu\u00f2 effettuarsi secondo i meccanismi e ai ritmi postulati dai darwinisti: questa trasformazione non \u00e8 graduale, non riposa su delle mutazioni e non \u00e8 nemmeno adattativi.<\/p>\n<p style=\"text-align: justify;\"><strong>Capita spesso di leggere che il funzionamento dell\u2019evoluzione \u00e8 stato capito\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\">Giustamente! Autori come Dawkins ci dicono che prima c\u2019erano dei misteri, ma che ora tutto \u00e8 chiaro: dire questo \u00e8 una vera falsificazione scientifica! Ci sono enormi problemi da risolvere! Veda, mi sono dedicato a combattere il darwinismo, non perch\u00e9 si tratta di una teoria falsa \u2013 ci sono tante teorie false al mondo! \u2013 ma perch\u00e9 \u00e8 disonesta. Inoltre mi ha colpito il fatto che gli stessi difensori del darwinismo non ci credono.<\/p>\n<p style=\"text-align: justify;\"><strong>Ernst Mayr ci crede \u2026<\/strong><\/p>\n<p style=\"text-align: justify;\">Ma \u00e8 un \u00abvescovo\u00bb, un grande prelato della teoria, deve far vedere che ci crede! Io non penso che una volta rientrato in camera sua, solo con se stesso, creda veramente che delle piccole mutazioni casuali e la selezione naturale possano bastare a produrre un dinosauro a partire da un\u2019ameba \u2013 non \u00e8 possibile che lo creda!<\/p>\n<p style=\"text-align: justify;\"><strong>Quali sono state le conseguenze dello sviluppo delle idee darwiniane sulla nostra societ\u00e0?<\/strong><\/p>\n<p style=\"text-align: justify;\">Sono state molto importanti e sono di 3 ordini:<\/p>\n<p style=\"text-align: justify;\">1. Innanzitutto l\u2019idea che nell\u2019Universo nulla pu\u00f2 avere senso. Leggete Monod e Rostand. \u00c8 il darwinismo che ha fornito un quadro per il successo dell\u2019esistenzialismo\u2026<\/p>\n<p style=\"text-align: justify;\">2. In seguito l\u2019idea che il pi\u00f9 forte ha sempre ragione, che il solo criterio per decidere del diritto, della giustizia, \u00e8 di battersi e di vincere con qualsiasi mezzo. Per principio, non c\u2019\u00e8 pi\u00f9 morale, n\u00e9 valori, n\u00e9 altra giustificazione ai nostri atti se non lo \u201cstruggle for life\u201d, la lotta per la vita.<\/p>\n<p style=\"text-align: justify;\">3. Il razzismo, per finire. Darwin era chiaramente razzista. Ai nostri giorni i suoi difensori cercano di \u00ablavarlo\u00bb da questa tara ma egli, tra l\u2019altro, diceva: \u00abTra tutti gli uomini, ci deve essere lotta aperta, e non si deve, con leggi o consuetudini, impedire ai migliori di avere successo e di allevare il maggior numero di figli. In un tempo a venire, non molto lontano, se lo si misura in secoli, \u00e8 quasi certo che le razze umane pi\u00f9 civilizzate stermineranno e sostituiranno le razze selvagge in tutto il mondo\u00bb.<\/p>\n<p style=\"text-align: justify;\">In effetti, il darwinismo \u00e8 duro da combattere, non perch\u00e9 sia scientificamente solido, ma perch\u00e9 esso \u00e8 in sintonia con certe idee che hanno dominato la societ\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>E nel suo caso quali sono le sue concezioni filosofiche?<\/strong><\/p>\n<p style=\"text-align: justify;\">Penso che dobbiamo scoprire noi stessi, capire il nostro mondo, il suo senso, la sua bellezza, il nostro dovere. Se crediamo che l\u2019uomo non sia altro che una scimmia mancata, questo senso sparisce. Solo se pensiamo che c\u2019\u00e8 una logica, una finalit\u00e0 (diciamolo!) nel mondo, noi possiamo guardarci in faccia e trovare regole per la nostra vita. Mi sembra che quello che sappiamo della natura e della vita \u00e8 molto pi\u00f9 in accordo con una simile visione che non con la visione darwinista<\/p>\n<p style=\"text-align: center;\"><strong>* * *<\/strong><\/p>\n<p style=\"text-align: center;\">Prof. <strong>ETIENNE WOLFF<\/strong> <em>E<\/em><\/p>\n<p style=\"text-align: center;\"><em>mbriologo, professore al Coll\u00e9ge de France, Membro dell\u2019Accademia delle scienze, Membro dell\u2019Acad\u00e9mie fran\u00e7aise.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Nell\u2019evoluzione la cosa straordinaria \u00e8 che essa sembra orientata\u00bb. Un orientamento, si: in azione nella natura. Qualche cosa che cerca di realizzarsi \u2026<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Qual \u00e8 la visione che un embriologo ha dell\u2019evoluzione?<\/strong><\/p>\n<p style=\"text-align: justify;\">Prof. Wolff. Poich\u00e9, al momento, non conosciamo altri fattori materiali d\u2019evoluzione che non siano le mutazioni, \u00e8 certo che il ruolo di questi fattori darwiniani non pu\u00f2 essere eliminato. Ma nell\u2019evoluzione, ci sono le piccole evoluzioni e la grande evoluzione. Si \u00e8 realizzato, in modo sperimentale delle piccole evoluzioni, ma queste non vanno mai molto lontano.<\/p>\n<p style=\"text-align: justify;\"><strong>Allora la grande evoluzione si svolge nello stesso modo?<\/strong><\/p>\n<p style=\"text-align: justify;\">Abbiamo diverse ragioni di dubitarne. Esempi come quello dell\u2019occhio dove non si conosce alcun intermediario tra la macchia pigmentata di alcuni vertebrati e l\u2019occhio assolutamente indifferenziato come quello dei cefalopodi e dei vertebrati lasciano pensare che la grande evoluzione si sia realizzata non solo grazie a dei piccoli salti della natura.<\/p>\n<p style=\"text-align: justify;\">\u00c8 chiaro che i fattori meccanici hanno giocato un ruolo, ma ci\u00f2 che permette di immaginare che ha potuto esserci qualche cosa d\u2019altro, \u00e8 il vedere che l\u2019evoluzione \u00e8 in qualche modo orientata. \u00c8 importante costatare che ci sono tendenze dell\u2019evoluzione a fare qualche cosa di nuovo, di meglio adattato, di pi\u00f9 complesso, e questo a tutti i livelli della gerarchia animale.<\/p>\n<p style=\"text-align: justify;\">Per esempio il tipo mammifero \u00e8 stato una specie di direzione dell\u2019evoluzione durante tutto il periodo della fine dell\u2019era primaria e dell\u2019inizio dell\u2019era secondaria. Si conoscono una decina di precursori dei mammiferi di cui uno solo, non si sa quale, \u00e8 \u201carrivato a buon fine\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Vuol dire che il tipo \u00abmammifero\u00bb ha cercato di realizzarsi attraverso diversi tentativi indipendenti gli uni dagli altri?<\/strong><\/p>\n<p style=\"text-align: justify;\">Si, e ci sono molti altri esempi, cos\u00ec il tipo \u00abuccello\u00bb, o piuttosto il tipo \u00abanimale volante\u00bb. Molti gruppi differenti hanno cercato di realizzarlo: i dinosauri, gli pterosauri, e poi c\u2019\u00e8 stato l\u2019archeopterix.<\/p>\n<p style=\"text-align: justify;\"><strong>E se l\u2019evoluzione fosse da rifare, si pu\u00f2 pensare che esisterebbero le stesse tendenze?<\/strong><\/p>\n<p style=\"text-align: justify;\">Se l\u2019evoluzione fosse lasciata solo al caso, \u00e8 evidente che sarebbe del tutto diversa. Ma, fermo restando gli esempi che abbiamo citato, ci viene detto \u2013 \u00e8 un\u2019intuizione, non una certezza \u2013 ci sarebbero state quanto meno delle tendenze analoghe che si sarebbero manifestate, si sente bene la presenza di qualcosa che cerca di realizzarsi nella natura.<\/p>\n<p style=\"text-align: justify;\"><strong>Possiamo trarre delle conclusioni filosofiche<\/strong><\/p>\n<p style=\"text-align: justify;\">Non posso pronunciarmi. Ma in ogni caso \u00e8 qualcosa di straordinario che l\u2019evoluzione sembri cos\u00ec orientata secondo una certa direzione\u2026<\/p>\n<p style=\"text-align: center;\">* * *<\/p>\n<p style=\"text-align: center;\">Prof. <strong>M. P. SCHUTZENBERGER<\/strong> (1920-1996)<\/p>\n<p style=\"text-align: center;\"><em>Matematico e medico, gi\u00e0 professore di biologia matematica a Harward, Professore all\u2019Universit\u00e0 di Parigi VII, Membro dell\u2019Accademia delle Scienze. <\/em><\/p>\n<p style=\"text-align: justify;\"><em>L\u2019evoluzione non pu\u00f2 essere dovuta al caso!\u00bb. L\u2019ordine perfezionato degli esseri viventi non \u00e8 potuto uscire dal caos\u2026<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Vediamo diffondersi sempre pi\u00f9 l\u2019idea che l\u2019ordine pu\u00f2 nascere dal caos. Che ne dice un matematico come lei?<\/strong><\/p>\n<p style=\"text-align: justify;\">Prof. Schutzenberger. Tutti quelli che hanno conosciuto von Forster, prima che avesse sviluppato questa idea, sanno che si tratta di una battuta\u2026 che alcuni in seguito hanno preso sul serio. Ma in effetti gli ordini che appaiono cos\u00ec sono ordini molto semplici, senza alcun rapporto con le strutturazioni che si osservano presso gli esseri viventi. Tanto pi\u00f9 che verso questi ultimi non si tratta solo di un ordine geometrico, ma anche di un ordine funzionale. Agitando gli ingranaggi di un orologio, non potete sperare che vadano a mettersi nel solo ordine che non solo permetta alle rotelle di ingranarsi le une nelle altre, ma, in pi\u00f9, possa permettere all\u2019orologio di dare l\u2019ora esatta!<\/p>\n<p style=\"text-align: justify;\"><strong>I procedimenti del caso e della selezione naturale non possono dunque spiegare l\u2019evoluzione?<\/strong><\/p>\n<p style=\"text-align: justify;\">Supponiamo anche che delle mutazioni abbiano fatto apparire delle piume. Ci vuole la fede (darwinista) del carbonaio per credere che solo grazie al caso siano apparse nella stirpe degli uccelli tutte le altre modificazioni ereditarie che ne fanno delle macchine da volo cos\u00ec strutturate.<\/p>\n<p style=\"text-align: justify;\"><strong>Cosa possiamo concludere?<\/strong><\/p>\n<p style=\"text-align: justify;\">Tutto ci\u00f2 sembra contraddire categoricamente la tesi di Gould (2) secondo la quale l\u2019aspetto importante dell\u2019evoluzione sarebbe l\u2019intervento del caso. Nella sua visione, che \u00e8 un rimaneggiamento di quella di Monod, la cosa importante, sono catastrofi, prosciugamento di mari, inondazioni delle pianure, cadute di meteoriti. Secondo Gould, questi fenomeni completamente esterni allo sviluppo della vita avrebbero fatto sparire le specie dominanti permettendo a nuove specie di invadere gli spazi liberi cos\u00ec creati. Cos\u00ec la sparizione dei dinosauri avrebbe favorito i mammiferi.<\/p>\n<p style=\"text-align: justify;\"><strong>Ma perch\u00e9 proprio i mammiferi che rappresentano, rispetto a loro, un progresso lungo lo stesso asse che va dai pesci ai rettili<\/strong><\/p>\n<p style=\"text-align: justify;\">Dopo i dinosauri, la Terra sarebbe forse dovuta appartenere agli scorpioni. Ora non \u00e8 ci\u00f2 che \u00e8 successo. In ogni caso \u00e8 curioso che questi cataclismi coincidano con un progresso della vita verso la complessit\u00e0. Cos\u00ec dunque i fenomeni evocati per spiegare l\u2019evoluzione hanno avuto un ruolo, ma non il ruolo essenziale.<\/p>\n<p style=\"text-align: justify;\">Se c\u2019\u00e8 una legge, un campo di forze (uso delle parole vaghe e non vorrei assolutamente che vi si mettessero dietro delle immagini) ad implicare che la vita diventi sempre pi\u00f9 complessa e pi\u00f9 funzionale, se esiste un tale principio, si pu\u00f2 pensare che la selezione naturale sia del tutto sussidiaria!<\/p>\n<p style=\"text-align: justify;\">Tuttavia, la maggioranza dei ricercatori dice che conosciamo nelle loro grandi linee le cause dell\u2019evoluzione..<\/p>\n<p style=\"text-align: justify;\">Tutti si dicono darwinisti, ma nessuno dice la stessa cosa. In effetti ci sono due modelli contraddittori: quello dei paleontologi, che contano in milioni di anni, e quello dei biologi, che lavorano in maggioranza su dei batteri per i quali sei mesi gi\u00e0 equivalgono all\u2019eternit\u00e0. L\u2019incompatibilit\u00e0 di questi due modi di affrontare il problema diventer\u00e0 sempre pi\u00f9 visibile con i progressi della scienza. Per questo bisogner\u00e0 al pi\u00f9 presto dichiarare aperta la successione al darwinismo.<\/p>\n<p style=\"text-align: justify;\"><strong>Note<\/strong><\/p>\n<p style=\"text-align: justify;\">1) Beagle: la nave sulla quale Darwin effettu\u00f2 nel 1831 il giro del mondo da cui trasse i primi elementi della sua teoria.<\/p>\n<p style=\"text-align: justify;\">2) S. J.Gould, La vie est belle, 1998<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Le Figaro Magazine, 26 ottobre 1991 Dal 13 al 19 ottobre, duecento scienziati, di cui quattro premi Nobel, si sono riuniti nel quadro degli \u201cIncontri di Blois\u201d. Tema: l\u2019origine della vita. Colloquio appassionante. Anche in questo campo le vecchie teorie crollano. Prospettive rivoluzionarie si aprono. * * *<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/levoluzione-condanna-darwin\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":32245,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51],"tags":[275],"class_list":["post-2880","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evoluzionismo","tag-evoluzionismo-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u2019evoluzione condanna Darwin - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/levoluzione-condanna-darwin\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019evoluzione condanna Darwin - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/levoluzione-condanna-darwin\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-03-17T16:29:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-02-12T19:19:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/origine_vita.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/levoluzione-condanna-darwin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/levoluzione-condanna-darwin\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"L\u2019evoluzione condanna Darwin\",\"datePublished\":\"2009-03-17T16:29:19+00:00\",\"dateModified\":\"2015-02-12T19:19:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/levoluzione-condanna-darwin\\\/\"},\"wordCount\":4072,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/levoluzione-condanna-darwin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/origine_vita.jpg\",\"keywords\":[\"evoluzionismo\"],\"articleSection\":[\"Evoluzionismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/levoluzione-condanna-darwin\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/levoluzione-condanna-darwin\\\/\",\"name\":\"L\u2019evoluzione condanna Darwin - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/levoluzione-condanna-darwin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/levoluzione-condanna-darwin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/origine_vita.jpg\",\"datePublished\":\"2009-03-17T16:29:19+00:00\",\"dateModified\":\"2015-02-12T19:19:48+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/levoluzione-condanna-darwin\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/levoluzione-condanna-darwin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/levoluzione-condanna-darwin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/origine_vita.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/origine_vita.jpg\",\"width\":259,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/levoluzione-condanna-darwin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019evoluzione condanna Darwin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019evoluzione condanna Darwin - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/levoluzione-condanna-darwin\/","og_locale":"it_IT","og_type":"article","og_title":"L\u2019evoluzione condanna Darwin - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/levoluzione-condanna-darwin\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-03-17T16:29:19+00:00","article_modified_time":"2015-02-12T19:19:48+00:00","og_image":[{"width":259,"height":194,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/origine_vita.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"20 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/levoluzione-condanna-darwin\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/levoluzione-condanna-darwin\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"L\u2019evoluzione condanna Darwin","datePublished":"2009-03-17T16:29:19+00:00","dateModified":"2015-02-12T19:19:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/levoluzione-condanna-darwin\/"},"wordCount":4072,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/levoluzione-condanna-darwin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/origine_vita.jpg","keywords":["evoluzionismo"],"articleSection":["Evoluzionismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/levoluzione-condanna-darwin\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/levoluzione-condanna-darwin\/","name":"L\u2019evoluzione condanna Darwin - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/levoluzione-condanna-darwin\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/levoluzione-condanna-darwin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/origine_vita.jpg","datePublished":"2009-03-17T16:29:19+00:00","dateModified":"2015-02-12T19:19:48+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/levoluzione-condanna-darwin\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/levoluzione-condanna-darwin\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/levoluzione-condanna-darwin\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/origine_vita.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/origine_vita.jpg","width":259,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/levoluzione-condanna-darwin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"L\u2019evoluzione condanna Darwin"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2880"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2880\/revisions"}],"predecessor-version":[{"id":18532,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2880\/revisions\/18532"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/32245"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}