{"id":28688,"date":"2015-12-10T00:00:42","date_gmt":"2015-12-09T23:00:42","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=28688"},"modified":"2015-12-09T18:14:39","modified_gmt":"2015-12-09T17:14:39","slug":"altro-che-crisi-quella-del-matrimonio-e-una-disfatta","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\/","title":{"rendered":"Altro che crisi. Quella del matrimonio \u00e8 una disfatta"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/12\/divorzio.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-28689\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/12\/divorzio.jpg\" alt=\"divorzio\" width=\"250\" height=\"196\" \/><\/a>Da <strong>Settimo cielo<\/strong>, blog di Sandro Magister, 3 dicembre 2015<\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong>&#8220;Dum Romae consulitur Saguntum expugnatur&#8221;. Non risulta che qualche padre sinodale abbia citato Tito Livio, nelle tre settimane di discussione sulla famiglia. Ma quella celebre frase sarebbe stata pi\u00f9 che mai appropriata. Perch\u00e9 mentre si attende con ansia il pronunciamento di papa Francesco sulla comunione ai divorziati risposati, il matrimonio sta correndo verso l&#8217;estinzione. E non solo dove la secolarizzazione ha fatto il deserto, ma anche in un paese universalmente definito familista e cattolico come l&#8217;Italia.<\/p>\n<p style=\"text-align: justify;\">A richiamare la cruda realt\u00e0 dei fatti \u00e8 il fulminante articolo che segue. \u00c8 uscito pochi giorni fa su &#8220;L&#8217;Osservatore Romano&#8221; e ne \u00e8 autore un demografo italiano di prima grandezza, non cattolico. Assolutamente da leggere.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: center;\"><strong>Non \u00e8 una semplice crisi<\/strong><\/p>\n<p style=\"text-align: center;\">di<\/p>\n<p style=\"text-align: justify;\">Anno 2009, in Italia: matrimoni celebrati 230.613. Anno 2014: matrimoni celebrati 189.765. Stavamo messi male nel 2009, stiamo messi peggio, inutile girarci attorno, cinque anni dopo. Negli ultimi cinque anni si sono persi quarantamila matrimoni, pari al diciotto per cento degli stessi.<\/p>\n<p style=\"text-align: justify;\">Sbagliano quanti vedono negli ultimi dati ISTAT su matrimoni e divorzi la certificazione della crisi del matrimonio. Quella del matrimonio \u00e8 stata in Italia una vera e propria rotta, un rompete le righe, un liberi tutti, non una semplice crisi. E viene da lontano. Il matrimonio in Italia non ha retto al divorzio. O, se vogliamo essere pi\u00f9 precisi, ha retto al divorzio in una misura estremamente pi\u00f9 debole che in pressoch\u00e9 tutti gli altri Paesi dell\u2019Europa occidentale: questa \u00e8 la semplice verit\u00e0 da cui partire.<\/p>\n<p style=\"text-align: justify;\">Dalla seconda met\u00e0 degli anni Settanta dello scorso secolo \u00e8 un continuo precipitare. Ancora nel 1973, anno precedente il referendum sul divorzio, i matrimoni, in una popolazione di alcuni milioni inferiore all\u2019attuale, erano stati oltre 418.000, dei quali 386.000 celebrati con rito religioso, scesi oggi a 108.000, cosicch\u00e9 se negli ultimi quarant\u2019anni i matrimoni hanno perso il cinquantacinque per cento la perdita di quelli religiosi ha toccato l\u2019ottantadue per cento, oltre i quattro quinti della loro consistenza. Perdita ch\u2019\u00e8 stata ancora maggiore nelle regioni del nord dove, oggi, c\u2019\u00e8 poco pi\u00f9 di un matrimonio religioso l\u2019anno ogni mille abitanti.<\/p>\n<p style=\"text-align: justify;\">Il matrimonio religioso nelle regioni pi\u00f9 ricche, moderne, avanzate anche culturalmente d\u2019Italia \u00e8 gi\u00e0 oggi ridotto al lumicino. A Milano siamo a 0,8 matrimoni l\u2019anno celebrati in chiesa ogni mille abitanti, senza meno il valore pi\u00f9 basso di tutto il mondo cattolico. Questo \u00e8 il quadro. Che mette ulteriormente in rilievo due sue caratteristiche: lo scivolamento a grandi passi verso l\u2019inconsistenza del matrimonio religioso ma anche, e al tempo stesso, l\u2019incapacit\u00e0 del matrimonio civile, in contrazione a sua volta, di attrarre nella sua orbita anche soltanto una modesta quota dei mancati matrimoni religiosi.<\/p>\n<p style=\"text-align: justify;\">In altre parole: \u00e8 l\u2019istituzione del matrimonio in se stessa a essere sprofondata in Italia in una crisi che appare senza ritorno, e di questo sprofondare fa le spese in modo soverchiante il matrimonio religioso, destinato a questi ritmi a scomparire letteralmente nel giro dei prossimi due-tre decenni.<\/p>\n<p style=\"text-align: justify;\">Se vuole fare una riflessione sulla famiglia, la Chiesa cattolica non pu\u00f2 non partire da qui. La forma famiglia passa sempre meno attraverso il matrimonio per la sua costituzione. Si fa famiglia a prescindere dal matrimonio, senza matrimonio, non soltanto senza il matrimonio religioso ma anche senza quello civile. Un fenomeno assai pi\u00f9 massiccio di quanto non sia mediamente in Europa, dove pure non si scherza in fatto di crisi del matrimonio.<\/p>\n<p style=\"text-align: justify;\">Questo \u00e8 il primo elemento che caratterizza la situazione in Italia. Il secondo \u00e8 invece assai poco ricordato. Il crollo del matrimonio non ha lasciato le cose invariate in fatto di famiglie, neppure dal punto di vista strettamente quantitativo. C\u2019\u00e8 molta meno famiglia, oggi in Italia.<\/p>\n<p style=\"text-align: justify;\">Non c\u2019\u00e8 stata affatto una compensazione dei matrimoni grazie a convivenze e coppie di fatto, n\u00e9 compensazione dei figli, come si lascia credere. Negli ultimi due-tre decenni a vincere, aumentando in misura quasi esponenziale, sono state soltanto le famiglie unipersonali, ovvero quelle composte da una sola persona, ovvero ancora le non famiglie, arrivate alla cifra di 7,7 milioni due anni fa, oggi probabilmente attorno agli otto milioni (attenzione, cinque milioni di queste sono di veri celibi\/nubili, persone mai sposate n\u00e9 divorziate). E questo mentre le coppie, comprensive di quelle non unite in matrimonio, sono appena 13,7 milioni in una popolazione di sessantuno milioni, delle quali ben cinque milioni senza figli.<\/p>\n<p style=\"text-align: justify;\">Al precipitare del matrimonio ha dunque corrisposto, in Italia, l\u2019affievolirsi della densit\u00e0 di famiglia e la riduzione della famiglia a forme sempre pi\u00f9 vistosamente nucleari.<\/p>\n<p style=\"text-align: justify;\">Terzo elemento, forse il pi\u00f9 sconcertante e ignorato. L\u2019et\u00e0 media della donna al matrimonio \u00e8 arrivata a sfiorare i 33 anni (32,6). L\u2019et\u00e0 media della donna al parto (non solo del primo figlio, dei figli di qualsiasi ordine) \u00e8 pari a 31 anni e mezzo. Tra la nascita del figlio e il matrimonio c\u2019\u00e8 dunque oltre un anno di differenza: ma a venire prima di oltre un anno \u00e8 il figlio, non il matrimonio.<\/p>\n<p style=\"text-align: justify;\">\u00a0Insomma, eccoci al punto, il paradossale divario tra la pi\u00f9 alta et\u00e0 media al matrimonio e la pi\u00f9 bassa et\u00e0 media della donna alla nascita dei figli certifica l\u2019ormai avvenuta separazione tra la nascita dei figli e il matrimonio: i figli non si fanno pi\u00f9 in costanza di matrimonio, come si suol dire tecnicamente, e com\u2019era fenomenologicamente fino a tre-quattro decenni fa. E in questo rovesciamento del paradigma che vuole il figlio successivo al matrimonio c\u2019\u00e8 anche, se non soprattutto, il riflesso dell\u2019estrema separazione, ormai avvenuta, tra i rapporti sessuali da un lato e la riproduzione sessuale, ovvero i figli, dall\u2019altro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da Settimo cielo, blog di Sandro Magister, 3 dicembre 2015 \u00a0&#8220;Dum Romae consulitur Saguntum expugnatur&#8221;. Non risulta che qualche padre sinodale abbia citato Tito Livio, nelle tre settimane di discussione sulla famiglia. Ma quella celebre frase sarebbe stata pi\u00f9 che mai appropriata. Perch\u00e9 mentre si attende con ansia il pronunciamento di papa Francesco sulla comunione &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":28689,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[15],"tags":[315,314],"class_list":["post-28688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famiglia","tag-divorzio","tag-matrimonio","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Altro che crisi. Quella del matrimonio \u00e8 una disfatta - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Altro che crisi. Quella del matrimonio \u00e8 una disfatta - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-09T23:00:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/12\/divorzio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"254\" \/>\n\t<meta property=\"og:image:height\" content=\"199\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Altro che crisi. Quella del matrimonio \u00e8 una disfatta\",\"datePublished\":\"2015-12-09T23:00:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\\\/\"},\"wordCount\":921,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/divorzio.jpg\",\"keywords\":[\"divorzio\",\"matrimonio\"],\"articleSection\":[\"Famiglia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\\\/\",\"name\":\"Altro che crisi. Quella del matrimonio \u00e8 una disfatta - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/divorzio.jpg\",\"datePublished\":\"2015-12-09T23:00:42+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/divorzio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/12\\\/divorzio.jpg\",\"width\":254,\"height\":199},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Altro che crisi. Quella del matrimonio \u00e8 una disfatta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Altro che crisi. Quella del matrimonio \u00e8 una disfatta - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\/","og_locale":"it_IT","og_type":"article","og_title":"Altro che crisi. Quella del matrimonio \u00e8 una disfatta - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2015-12-09T23:00:42+00:00","og_image":[{"width":254,"height":199,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/12\/divorzio.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Altro che crisi. Quella del matrimonio \u00e8 una disfatta","datePublished":"2015-12-09T23:00:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\/"},"wordCount":921,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/12\/divorzio.jpg","keywords":["divorzio","matrimonio"],"articleSection":["Famiglia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\/","name":"Altro che crisi. Quella del matrimonio \u00e8 una disfatta - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/12\/divorzio.jpg","datePublished":"2015-12-09T23:00:42+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/12\/divorzio.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/12\/divorzio.jpg","width":254,"height":199},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/altro-che-crisi-quella-del-matrimonio-e-una-disfatta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Altro che crisi. Quella del matrimonio \u00e8 una disfatta"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/28688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=28688"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/28688\/revisions"}],"predecessor-version":[{"id":28692,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/28688\/revisions\/28692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/28689"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=28688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=28688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=28688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}