{"id":2851,"date":"2009-03-13T13:24:08","date_gmt":"2009-03-13T12:24:08","guid":{"rendered":""},"modified":"2024-05-20T16:29:22","modified_gmt":"2024-05-20T14:29:22","slug":"il-jihad-nel-pensiero-islamico-contemporaneo","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-jihad-nel-pensiero-islamico-contemporaneo\/","title":{"rendered":"Il &laquo;Jihad&raquo; nel pensiero islamico contemporaneo"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/Jihad.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-36216 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/08\/Jihad-300x168.jpg\" alt=\"\" width=\"300\" height=\"168\" \/><\/a><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/www.laciviltacattolica.it\/\" target=\"_blank\" rel=\"noopener\">La Civilt\u00e0 Cattolica<\/a><\/span><\/strong> n.3791<\/p>\n<p style=\"text-align: center;\">7 giugno 2008<\/p>\n<p style=\"text-align: center;\">\u00a0di <strong>Giovanni Sale<\/strong> s.j.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">In questi ultimi anni, soprattutto dopo l&#8217;attacco terroristico dell&#8217;11 settembre 2001 alle Torri Gemelle di New York, il termine<em>. jihad, <\/em>attraverso l&#8217;uso martellante fattone dai <em>media, <\/em>\u00e8 entrato a far parte del linguaggio quotidiano e dell&#8217;universo immaginario. Per gli occidentali esso \u00e8 sinonimo di guerra totale, illimitata, senza regole nei pi\u00f9 genera paure ancestrali, ricordi di un passato segnato dalla contrapposizione e dalla violenza. J<em>ihad, <\/em>al pari di altri termini che provengono da un contesto religioso, ha un significato poliedrico, fluttuante, legato alle vicende politico-religiose che ne hanno accompagnato la diffusione.<\/span><\/p>\n<p style=\"text-align: justify;\"><!--more--><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-43022 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/jihad_Europa-300x169.jpg\" alt=\"\" width=\"350\" height=\"197\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/jihad_Europa-300x169.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/jihad_Europa-768x432.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/jihad_Europa-1024x576.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/05\/jihad_Europa.jpg 1608w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/>Letteralmente, in arabo, significa \u00absforzo\u00bb; nel contesto del Corano, invece, assume il significato di \u00abdarsi da fare\u00bb, \u00abimpegnarsi\u00bb per la religione, per la causa di Dio. La complessit\u00e0 del termine non sorprende se si considera la centralit\u00e0 che esso ha sempre avuto nel pensiero religioso musulmano e il lungo arco di tempo durante il quale \u00e8 stato usato.<\/span><\/p>\n<p style=\"text-align: justify;\">I<span style=\"color: #000000;\">n ogni caso non \u00e8 facile determinare in modo univoco il significato d\u00ec <em>jihad; <\/em>in generale possiamo dire che esso \u00e8 stato sempre oggetto di interpretazioni diverse e spesso divergenti da parte di scuole religiose o di differenti orientamenti confessionali. Il profeta Maometto non dichiar\u00f2 mai esplicitamente <em>un jihad; <\/em>tuttavia le numerose battaglie che intraprese contro gli infedeli rappresentarono il prototipo del <em>jihad <\/em>perfetto.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La lunga storia delle conquiste islamiche non ci aiuta a capire che cosa sia propriamente il <em>jihad: <\/em>infatti quelle pi\u00f9 importanti (VII e VIII secolo) soltanto successivamente furono reinterpretate secondo tale concetto; di fatto non sappiamo come fossero percepite dai musulmani di quei tempi. Lo stesso discorso vale per le guerre successive, combattute per lo pi\u00f9 contro altri musulmani.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Possiamo dire che esistono due modi differenti di intendere il <em>ji<\/em><em>had: <\/em>uno pi\u00f9 rigorista, ricalcato sulle fonti antiche e, in particolare, sui testi coranici; l&#8217;altro pi\u00f9 liberale e \u00abmodernista\u00bb, che interpreta tale concetto sulla base di categorie moderne. Secondo questa seconda tendenza (definita anche irenica), il<em> jihad <\/em>\u00e8 totalmente pacifico e indica il combattimento spirituale del fedele per adeguare la propria vita ai precetti religiosi. Tale definizione vanta precedenti importanti tra le fonti classiche, in particolare quelle di tendenza mistica; oggi \u00e8 fatta propria da gran parte degli intellettuali islamici che vivono in Occidente o che insegnano nelle universit\u00e0 occidentali.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Gli islamici che invece interpretano il<em> jihad <\/em>alla luce della tradizione classica, associandolo quindi all&#8217;idea della guerra, ne mettono in evidenza l&#8217;elemento sia difensivo sia offensivo, ambedue orientati alla proclamazione della verit\u00e0 dell&#8217;isl\u00e0m e alla purificazione dell<em>&#8216;umma <\/em>musulmana.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-34285 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/jihad.jpg\" alt=\"\" width=\"295\" height=\"171\" \/>Va sottolineato, per\u00f2, che per la maggior parte dei teorici del<em> jihad <\/em>esso dev&#8217;essere dichiarato in modo legittimo dall&#8217;autorit\u00e0 competente: vale a dire dal capo supremo della comunit\u00e0 religiosa e in relazione a una questione ritenuta di importanza vitale per l&#8217;intera comunit\u00e0 musulmana. Quando esistono tali condizioni, il<em> jihad <\/em>per i fedeli musulmani ha valore quasi assoluto e rientra nella categoria di \u00abguerra giusta\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tale posizione non \u00e8, per\u00f2, oggi accolta dai fondamentalisti radicali. In ogni caso, per comprendere il significato di<em> jihad \u00e8 <\/em>necessario analizzare i testi islamici. In questo articolo faremo riferimento soltanto alle opere e al pensiero dei maggiori pensatori e ideologi islamici del XX secolo e di quelli contemporanei, rimandando per il periodo classico ad altri interventi pubblicati sulla nostra rivista (1)<em>.<\/em><\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>Il \u00ab<em>jihad<\/em>\u00bb spirituale o irenico<\/strong><\/span><\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-34289 aligncenter\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/jihad-1.jpg\" alt=\"\" width=\"287\" height=\"164\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Gi\u00e0 nei primi decenni del Novecento nei maggiori centri del pensiero musulmano in Egitto, India, Pakistan, alcuni intellettuali o giuristi \u00abmodernisti\u00bb cercarono di reinterpretare secondo categorie moderne, comprensibili anche a persone non di fede islamica, la tradizionale nozione di<em> jihad. <\/em>In particolare, in Egitto Muhammad Abduh e il suo discepolo Rashid Rida gi\u00e0 nei primi anni del Novecento elaborarono, facendo anche riferimento alla tradizione, nuovi approcci interpretativi al concetto di<em> jihad, <\/em>come risulta chiaramente dalle loro <em>fatwa.<\/em><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Essi conferirono un carattere prettamente spirituale a tale nozione, anche se la loro dottrina non va confusa con quella elaborata nei secoli precedenti dai mistici sufi, conosciuta come <em>\u00abgrande jihad\u00bb. <\/em>Per Abduh e Rida il<em> jihad va <\/em>inteso soprattutto come proclamazione della verit\u00e0, come diritto inalienabile dei musulmani ad annunciare la dottrina del Profeta. L&#8217;unica forma di guerra consentita, secondo loro, \u00e8 quella difensiva, nel caso, cio\u00e8, che i \u00abveri credenti\u00bb vengano attaccati dagli infedeli.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tale definizione di<em> jihad <\/em>si allontanava da quelle classiche che privilegiavano il momento bellico. In realt\u00e0, essa rispondeva, in quel periodo, anche a scopi apertamente apologetici: definire il <em>jihad <\/em>in senso unicamente spirituale-difensivo era un modo di replicare ai missionari cristiani, i quali accusavano l&#8217;isl\u00e0m di essere una \u00abreligione della spada\u00bb: invece, secondo loro, la religione islamica aveva come obiettivo principale la convivenza pacifica con le altre credenze e intendeva lavorare per la pace tra i popoli.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tale impostazione irenica del<em> jihad, <\/em>come ricordato, gi\u00e0 nei primi decenni del Novecento non era condivisa da una buona parte degli ambienti islamici tradizionalisti. Le critiche mosse da pi\u00f9 parti alle tesi di Rida erano radicali e a volte andavano al fondo del problema: se il <em>jihad <\/em>si pu\u00f2 combattere soltanto in forma difensiva, come andrebbero interpretate le prime conquiste musulmane a partire da quelle effettuate da Maometto?<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">In modo ancora pi\u00f9 ardito, da parte di altri si obiettava: esiste una qualche analogia tra il modo con cui gli imperialisti europei trattano i loro sudditi islamici e il modo in cui si comportarono nel tempo passato i musulmani invasori? Va ricordato che tali interrogativi sono abbastanza rari nella letteratura islamica sia classica sia moderna, in quanto le prime conquiste, in particolare quelle operate dal Profeta, sono considerate alla stregua di miracoli o atti prodigiosi, aventi come fine di confermare la verit\u00e0 dell&#8217;isl\u00e0m e del Corano. Perci\u00f2 raramente tali questioni furono sottoposte al vaglio critico.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Rida per\u00f2 nei suoi scritti risponde puntualmente a tali domande, anche se con un ragionamento un poco tortuoso, facendo riferimento alle fonti coraniche e alla storia dell&#8217;isl\u00e0m. Da un lato egli afferma che le prime battaglie combattute dal Profeta erano prevalentemente difensive, poste in essere cio\u00e8 per difendere contro i pagani la verit\u00e0 dell&#8217;isl\u00e0m; dall&#8217;altro lato, invece, egli affermava, per spiegare gli attacchi offensivi condotti contro alcune popolazioni, che a quell&#8217;epoca la guerra era un comportamento piuttosto usuale tra i popoli; sicch\u00e9 non \u00e8 possibile parlare a tale riguardo di \u00abaggressione\u00bb, nel senso moderno della parola.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Secondo Rida, perfino le guerre combattute successivamente dagli islamici contro i bizantini furono semplicemente difensive, poich\u00e9 questi, a suo avviso, intendevano cacciare gli arabi dai loro territori spingendoli verso zone desertiche.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Insomma, manipolando la verit\u00e0 storica e interpretandola secondo le proprie esigenze dottrinali, l&#8217;intellettuale egiziano riteneva che nella maggior parte dei casi i musulmani fossero stati obbligati a combattere i popoli confinanti, perch\u00e9 questi impedivano ai musulmani di proclamare la verit\u00e0: \u00abI musulmani \u2014 egli scrive \u2014 usarono la forza soltanto quando si trovarono in difficolt\u00e0 o quando era assolutamente necessario, poich\u00e9 volevano offrire l&#8217;isl\u00e0m ai popoli, e se questi avessero accettato sarebbero stati assimilati, e se rifiutavano allora prelevavano una piccola <em>jizya <\/em>[&#8230;] e lasciavano loro la libert\u00e0 personale, le propriet\u00e0 e la loro religione\u00bb (2).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tale interpretazione irenica del <em>jihad, <\/em>sebbene non fosse seguita dalla maggior parte dei giuristi islamici, i quali su tale materia si orientavano secondo gli insegnamenti della tradizione, ebbe un grande influsso sui nuovi movimenti di rinascita islamica, come, ad esempio, i Fratelli Musulmani e successivamente per il gruppo indo-pakistano che si ispirava al grande ideologo islamico A. al-Mawdudi.<\/span><\/p>\n<p style=\"text-align: justify;\">L<span style=\"color: #000000;\">&#8216;organizzazione dei Fratelli Musulmani fu fondata alla fine degli anni Venti da H. al-Banna, giovane insegnante di orientamento tradizionalista e fin dall&#8217;infanzia attratto dalla spiritualit\u00e0 e dalla mistica sufi. L&#8217;organizzazione sin dagli inizi si impegn\u00f2 in modo militante a favorire la rinascita nel mondo arabo dell&#8217;isl\u00e0m delle origini e ad incoraggiare la ripresa degli studi dei suoi testi fondamentali. Esso certamente fu uno dei movimenti che maggiormente negli anni successivi contribu\u00ec allo sviluppo dell&#8217;isl\u00e0m radicale e movimentista in diversi Paesi arabi.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Nel suo libretto di propaganda al-Banna, a proposito del <em>jihad, <\/em>afferma perentoriamente che esso ha carattere strettamente difensivo e correda tale affermazione con diverse <em>citazioni <\/em>tratte dal Corano e dagli <em>hadith <\/em>(detti) tradizionali. Verso la fine del suo opuscolo, l&#8217;autore si pone la seguente domanda: \u00abPer che cosa combattono i musulmani?\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">E risponde: \u00abDio non ha obbligato i musulmani <em>aljibad <\/em>n\u00e9 come strumento di aggressione, n\u00e9 come veicolo dei loro desideri personali, bens\u00ec per proteggere la proclamazione dell&#8217;isl\u00e0m, come garanzia di pace, e come strumento per realizzare la grande missione del cui fardello si sono fatti carico i musulmani; ossia la missione di gui\u00addare il popolo nella verit\u00e0 e nella pace\u00bb (3).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Allo stesso tempo, per\u00f2, egli mette in guardia i musulmani dal lasciarsi fuorviare dalle false dottrine (come quelle propagate dagli occidentali) e di essere sempre pronti a combattere per l&#8217;isl\u00e0m, ma avverte, citando il Corano: \u00abSe [i nemici di Dio] preferiscono la pace, anche tu preferiscila. E confida in Dio\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Il maggior rappresentante di questa tendenza fu per\u00f2 il pensatore indo-pakistano al-Mawdudi, a cui si deve l&#8217;elaborazione di gran parte del quadro teorico della reviviscenza musulmana della seconda met\u00e0 del XX secolo. Il suo libro sul <em>jihad, <\/em>intitolato <em>Al-Jt-<\/em><em>hadfi al-islam, <\/em>contribu\u00ec in quegli anni a propagare all&#8217;interno del mondo islamico una concezione irenica della \u00abguerra santa\u00bb; su questo trattato inoltre si form\u00f2 un&#8217;intera generazione di islamisti radicali.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Al-Mawdudi nel suo scritto innanzitutto critica con pungente ironia le pi\u00f9 comuni raffigurazioni occidentali del <em>jihad <\/em>(considerato come guerra aggressiva e brutale) poste in circolazione da missionari cristiani allo scopo \u2014 scrive l&#8217;autore \u2014 di creare divisione all&#8217;interno della comunit\u00e0 islamica e rendere pi\u00f9 dura l&#8217;occupazione delle grandi potenze coloniali.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Per l&#8217;ideologo indopakistano il <em>jihad <\/em>\u00e8 insieme annuncio della vera religione di Allah e impegno civile per creare un mondo pi\u00f9 giusto e vivibile. \u00abChe cosa abbiamo a che fare, signori, con il combattimento? \u2014 egli scrive \u2014 Siamo semplici missionari che proclamano, e invitiamo il popolo alla religione di Allah, la religione della sicurezza e della pace. [&#8230;] che cosa abbiamo a che fare con il combattimento con la spada? Dio proibisce qualsiasi rapporto con la spada! Salvo quello di proteggerci quando qualcuno ci attacca\u00bb (4).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Secondo la prospettiva di al-Mawdudi, insomma, combattere il <em>jihad <\/em>significa farsi carico della causa di Dio, opporsi alla tirannia dell&#8217;uomo sull&#8217;uomo, liberandolo da ogni ingiustizia e ridandogli il posto che gli compete nella creazione. Insomma il<em> jihad <\/em>\u00e8 soprattutto lotta di liberazione, lotta per la giustizia, lotta per la pace universale. Da questo punto di vista \u00e8 diritto e insieme responsabilit\u00e0 dei musulmani denunciare e combattere la corruzione e le storture dell&#8217;attuale sistema sociale, segnato dalla violenza, dall&#8217;egoismo e dalla disuguaglianza.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Al-Mawdudi invita tutti i musulmani a impegnarsi in questa lotta per cambiare e migliorare il mondo: per far questo \u00e8 per\u00f2 necessario instaurare innanzitutto lo Stato islamico e applicare interamente la legge coranica, voluta da Dio per il bene di tutti gli uomini.<\/span><\/p>\n<p style=\"text-align: justify;\">T<span style=\"color: #000000;\">ale concezione del<em> jihad, <\/em>come detto, si discosta profondamente dalla dottrina classica e da ci\u00f2 che generalmente era insegnato nelle scuole coraniche. Di fatto, \u00e8 stato notato, nel testo di al-Mawdudi non sono mai presi in considerazione i versetti coranici normalmente associati dalla letteratura classica al <em>ji<\/em><em>had <\/em>e soltanto vagamente si fa riferimento alle vicende della storia politica e militare musulmana: egli preferisce portare avanti il suo discorso su un piano eminentemente teorico, partendo da alcuni presupposti di carattere ideologico, ispirati per lo pi\u00f9 alle dottrine socialiste, o pseudomarxiste, molto in voga in quegli anni anche tra gli intellettuali islamici, per poi arrivare alle conseguenze di cui si \u00e8 detto: l&#8217;instaurazione cio\u00e8 dello Stato islamico.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Nel suo scritto anche al-Mawdudi si occupa della questione disputata sulla natura delle conquiste islamiche dei primi secoli. Se il <em>jihad, <\/em>egli si chiede, \u00e8 essenzialmente difensivo come si spiegano le grandi conquiste musulmane dei primi secoli? Esse avevano lo scopo di soggiogare altri popoli al dominio dei capi islamici? A tale proposito l&#8217;autore imposta il suo discorso sulla base di due criteri: la percezione che della guerra avevano i non musulmani e, al contrario, gli obiettivi che i musulmani attraverso questa intendevano raggiungere.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Egli ammette che i non musulmani considerarono all&#8217;inizio i nuovi conquistatori come \u00abimperialisti\u00bb, poich\u00e9 subivano il dominio dei nuovi padroni, ma, quando questi cessarono di combatterli e di molestarli, \u00abfu loro chiaro l&#8217;intento dei musulmani e la ragione per cui erano usciti dalla loro patria.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Dopo di che si resero conto del carattere totalmente rivoluzionario della visione che essi desiderano diffondere propagandando il loro sistema di credenza ai quattro angoli del mondo\u00bb (5). Per cui, aggiunge al-Mawdudi, i primi conquistatori musulmani non possono essere tacciati di colonialismo o di imperialismo, come lo sono invece le potenze coloniali del XX secolo, in quanto loro scopo primario era annunciare le credenze dell&#8217;isl\u00e0m e la libert\u00e0.<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>\u00ab<em>Jibad<\/em>\u00bb difensivo e \u00ab<em>jihad<\/em>\u00bb combattente<\/strong><\/span><\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-48816 size-medium\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Islam_fondamentalismo-300x214.jpg\" alt=\"\" width=\"300\" height=\"214\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Islam_fondamentalismo-300x214.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Islam_fondamentalismo-768x548.jpg 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Islam_fondamentalismo-1024x731.jpg 1024w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2020\/10\/Islam_fondamentalismo.jpg 2037w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Con il successivo sviluppo dell&#8217;isl\u00e0m radicale in diversi Paesi arabi, e in particolare in Egitto, compaiono, a partire dagli anni Sessanta, nuove interprelazioni del <em>jihad <\/em>orientate non pi\u00f9 su posizioni \u00ecreniche, ma piuttosto militanti e tendenzialmente combattive. La personalit\u00e0 pi\u00f9 significativa da questo punto di vista \u00e8 l&#8217;egiziano Sayyid Qutb, che, a pieno titolo, pu\u00f2 essere considerato il fondatore del movimento islamico radicale.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Egli proveniva da un ambiente laico e da giovane studente aveva lavorato come critico letterario. Nel 1949 si rec\u00f2 negli Stati Uniti, dove visse alcuni anni: tale esperienza modific\u00f2 completamente il suo modo di pensare, facendogli riscoprire le proprie radici islamiche. Ritornato in patria prese contatto con i Fratelli Musulmani e nel giro di pochi anni divenne il principale teorico del movimento.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Come gran parte degli islamisti radicali, sotto il regime di Nasser fu pi\u00f9 volte condannato a lunghe pene detentive. Si \u00e8 detto, infatti, che l&#8217;esperienza del carcere fu l&#8217;incudine dove si forgi\u00f2 l&#8217;isl\u00e0m radicale in Egitto (6).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Qutb scrisse buona parte dei suoi testi e commentali durante gli anni di prigionia. Nel 1965 fu scarcerato e nuovamente arrestato quando diede alle stampe la sua opera pi\u00f9 importante, <em>Pietre miliari sulla via, <\/em>considerata dall&#8217;autorit\u00e0 governativa sovversiva e antistatale. Incolpato ingiustamente di aver attentato alla vita del presidente Nasser, fu condannato a morte nel 1966 e giustiziato. Per la maggior parte dei Fratelli musulmani divenne un martire della verit\u00e0, e le sue opere ebbero grande diffusione tra gli islamici radicali.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Nel suo testo fondamentale egli afferma che, a eccezione dell&#8217;isl\u00e0m, tutte le grandi ideologie del XX secolo hanno fallito i loro obiettivi. Denuncia per\u00f2 che il vero isl\u00e0m \u00e8 stato tradito dai responsabili degli Stati e dalle <em>\u00e9lites <\/em>attualmente al potere, ma ritiene che esso viva ancora nel cuore dei credenti. \u00c8 dunque necessario, afferma, che i musulmani facciano rinascere l&#8217;isl\u00e0m e combattano \u00abla barbarie\u00bb attuale, come a suo tempo fece il profeta Maometto.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Egli invita i musulmani a ritornare all&#8217;isl\u00e0m delle origini, epurandolo da tutte le escrescenze e le contaminazioni moderne, volute per lo pi\u00f9 da interessi di parte. La sua dottrina sul<em> jihad <\/em>si fonda sui versetti coranici di carattere bellico e sulla storia musulmana delle origini. Secondo Qutb, il<em> jihad <\/em>\u00e8 un \u00abprogramma progressivo\u00bb che passa da uno stadio a un altro in modo razionale.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Con questo egli intende dire che sulla base delle prescrizioni coraniche c&#8217;\u00e8 un divenire, uno sviluppo logico, che accompagna la progressione del.<em> jihad, <\/em>per cui si va dalla proclamazione pacifica della verit\u00e0 alla guerra su scala limitata, per difendere i musulmani minacciali o per vendicare i torti subiti, fino alla stadio finale della guerra illimitata. Insomma, per Qutb, il<em> jihad <\/em>ha due facce simmetriche: una difensiva e l&#8217;altra aggressiva.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Egli, circa quest&#8217;ultimo aspetto, aggiunge che, sebbene il<em> jihad <\/em>possa essere offensivo, non \u00e8 per\u00f2 mai coercitivo negli obiettivi che intende perseguire. In sostanza esso <em>\u00e8 <\/em>lo strumento mediante il quale i musulmani garantiscono che la proclamazione del messaggio dell&#8217;isl\u00e0m sia ascoltato, sbarazzando il mondo da strutture e poteri che ostacolano la proclamazione pacifica della verit\u00e0, \u00abil<em> Jihad\u2014 <\/em>egli scrive \u2014 \u00e8 necessario per la proclamazione, poich\u00e9 i suoi obiettivi sono annunciare la liberazione dell&#8217;uomo in modo che affronti la realt\u00e0 presente con strumenti equipollenti in ogni aspetto, e non basta una proclamazione di carattere ipotetico o teorico, siano le terre islamiche sicure o minacciate dai popoli limitrofi\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Egli, inoltre, ritiene il<em> jihad <\/em>parte integrante della struttura dell&#8217;isl\u00e0m stesso, anche se \u00e8 molto attento a non confondere il <em>jihad <\/em>offensivo con la guerra ordinaria: \u00abI1<em> jihad <\/em>islamico \u00e8 una realt\u00e0 in s\u00e9 e non ha alcuna relazione con la guerra moderna: n\u00e9 per le sue motivazioni, n\u00e9 per la conduzione. Le motivazioni del <em>jihad <\/em>affondano le radici nell&#8217;essenza stessa dell&#8217;isl\u00e0m, nel suo vero ruolo nel mondo e negli altissimi princ\u00ecpi che Dio ha dettato\u00bb \u00a0(7)<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Per alcuni aspetti Qutb si avvicina al pensiero di al-Mawdudi, soprattutto quando parla di<em> jihad <\/em>nel senso di proclamazione della verit\u00e0 di Dio e di liberazione integrale dell&#8217;uomo: temi questi molto presenti nella letteratura politica di quegli anni. Altri aspetti invece connessi tradizionalmente al pensiero jihadista, come, ad esempio, l&#8217;ampliamento del territorio dell&#8217;isl\u00e0m e la difesa dei suoi confini, non sembrano interessare molto il nostro autore.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Forse, \u00e8 stato detto, poich\u00e9 risultava difficile o impossibile definire con certezza i confini reali della <em>umma <\/em>musulmana, considerato anche il fatto che alcuni Governi musulmani, secondo il pensatore egiziano erano da considerarsi apostati e quindi fuori della comunione islamica. In quegli anni per i musulmani radicali, la questione pi\u00f9 urgente non era la difesa dei confini dell&#8217;isl\u00e0m, quanto la proclamazione dell&#8217;isl\u00e0m puro, non contaminato da costumi e da mentalit\u00e0 occidentali. Questo spiega perch\u00e9 fino agli anni Settanta il problema di Israele non fosse ritenuto dagli islamisti radicali un problema grave e urgente, come avvenne invece nei decenni successivi.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Gli anni Ottanta e Novanta furono gli anni dell&#8217;affermazione a livello transnazionale dell&#8217;islamismo radicale, non pi\u00f9 circoscritto a piccoli gruppi di intellettuali o combattenti per la fede, ma divenuto ormai movimento di opinione capace di mobilitare parte delle masse popolari arabe, orientandole verso la causa islamista. Il primo Paese a scegliere la soluzione rivoluzionaria per l&#8217;instaurazione di uno Stato integralmente islamico fu l&#8217;Iran, che fungeva in quegli anni da punto di riferimento del movimento islamico internazionale, in ambito sia sciita sia sunnita.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tale mutamento fu dovuto, almeno in parte, al fallimento della cosiddetta politica di modernizzazione, ispirata a modelli occidentali, portata avanti, a partire dagli anni Cinquanta, da leader che in modo autoritario avevano imposto una sorta di laicismo di Stato e in buona parte disatteso le promesse di riscatto sociale degli strati pi\u00f9 deboli della popolazione, sulle quali si era fondata per diversi anni la propaganda di regime.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">L&#8217;intrinseca debolezza di questi sistemi si manifest\u00f2 con evidenza nella guerra dei 6 giorni combattuta nel giugno del 1967 tra Israele e gli Stati arabi limitrofi \u2014 Egitto, Giordania e Siria \u2014 e conclusasi con la sconfitta degli eserciti arabi e con l&#8217;occupazione da parte del piccolo Stato di Israele di varie porzioni di territorio arabo. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tale guerra fu la causa della cosiddetta \u00abinfelicit\u00e0 araba\u00bb (8); essa di fatto mostr\u00f2 l&#8217;intrinseca inconsistenza di tali regimi autoritari e la loro incapacit\u00e0 di rispondere alle aspettative di chi fino ad allora li aveva appoggiati.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Secondo molti musulmani, era chiaro che bisognava cambiare rotta e ridare nuova forza e nuove idealit\u00e0 alla causa nazionale araba; per gli islamici radicali, al contrario, bisognava abbattere tali regimi atei e corrotti e rifondare lo Stato sulla <em>sharia. <\/em>Quando poi il presidente egiziano Sadat negli anni 1977-79 intavol\u00f2 negoziati di pace con Israele per recuperare i territori occupati, egli fu accusato dai fondamentalisti di tradire la causa araba e divenne l&#8217;obiettivo principale della loro propaganda politica. Sadat, come \u00e8 noto, fu assassinato da un gruppo di Fratelli Musulmani il 6 ottobre 1981.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Subito dopo l&#8217;assassinio, la polizia, durante una perquisizione effettuata nelle sedi e nelle abitazioni di alcuni capi islamici, trov\u00f2 un importante documento di propaganda politica intitolato \u00abII dovere trascurato\u00bb, scritto da M. al-Salam Farag, pubblicato successivamente. Il contenuto di questo documento \u00e8 di somma importanza per constatare i cambiamenti verificatisi all&#8217;interno del movimento fondamentalista islamico a 15 anni dalla morte del loro primo ideologo, Sayyid Qutb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">In questo testo il tema <em>d\u00e9ljthad <\/em>occupa un posto preminente. Mentre per Qutb il <em>jihad <\/em>era un proclama di liberazione di carattere palingenetico, diretto al mondo intero, per Farag, invece, \u00e8 lo strumento che nel prossimo futuro permetter\u00e0 ai musulmani di dominare il mondo e di ristabilire il califfato, abolito da M. Kemal Atat\u00f9rk nel 1924. Farag nel suo scritto affronta direttamente le questioni cruciali concernenti l&#8217;islamismo radicale; nel far questo, a differenza dei suoi predecessori, egli non \u00e8 minimamente condizionato da suggestioni ideologiche di matrice occidentale, quali il marxismo e il socialismo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Per lui, \u00ecl<em> jihad <\/em>\u00e8 un imperativo di carattere globale indirizzato alla conversione del mondo intero alla dottrina del Corano. Su questa materia, Farag, a differenza di Qutb, non ammette l&#8217;idea di una libera scelta da parte delle persone tra isl\u00e0m e miscredenza; anzi egli intende combattere direttamente la miscredenza, considerata un&#8217;offesa al comandamento di Dio. Dopo la conquista di tutti i popoli all&#8217;isl\u00e0m, questa sar\u00e0 la sola religione praticata dall&#8217;umanit\u00e0.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Per Farag, il trionfo definitivo dell&#8217;isl\u00e0m \u00e8 oggetto di profezia, e ai musulmani non resta altro che realizzarla. Il suo giudizio sul presente \u00e8 tagliente e incisivo: \u00abOggi \u2014 egli scrive \u2014 i musulmani vivono in Stati governati da apostati in base a leggi che non si fondano sulla <em>sharia. <\/em>L&#8217;imperativo dei musulmani \u00e8 creare uno Stato musulmano; nessun altro obiettivo pu\u00f2 distrarre i credenti da questa missione\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Neppure il problema di Israele deve distrarre i veri musulmani dal loro obiettivo primario: \u00e8 pi\u00f9 importante, egli dice, combattere il nemico vicino (il regime degli apostati) che il nemico lontano (Israele e Stati Uniti). Infatti, \u00absi verserebbe sangue musulmano per ottenere tale vittoria. Occorre domandarsi se questa vittoria risponderebbe agli interessi di uno Stato islamico o, piuttosto, a quelli di un governo miscredente [&#8230;].<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tali governi sfrutterebbero a proprio vantaggio la concezione nazionalistica dei veri musulmani [&#8230;]. Il combattimento deve avvenire sotto la bandiera dell&#8217;isi\u00e0m e al comando di una dirigenza islamica\u00bb (9). Soltanto la ripresa del<em> jihad <\/em>su scala globale secondo lo stile antico, sostiene Farag, \u00e8 capace di ridare prestigio e forza al mondo islamico, oggi asservito per colpa dei suoi governanti miscredenti agli interessi dell&#8217;Occidente.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Infatti la ragione principale \u00abdel degrado, dell&#8217;umiliazione, della divisione e della frammentazione che affliggono oggi il mondo islamico\u00bb \u00e8 dovuta soprattutto all&#8217;abbandono del<em> jihad <\/em>come mezzo di liberazione e di propagazione \u00abdella vera fede\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Da questo punto di vista Farag si appropria dell&#8217;intero versante bellico della storia e della dottrina religiosa islamica, ignorando volutamente qualsiasi elemento della tradizione che non si muova in tale direzione, come, ad esempio, la concezione del<em> jihad <\/em>in senso mistico-spirituale (o \u00abgrande <em>jihad<\/em>\u00bb), che egli definisce come un semplice diversivo rispetto all&#8217;impegno tassativo per ogni credente di combattere fattivamente per la fede (10).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Da quanto detto risulta evidente che Farag \u00e8 certamente l&#8217;autore pi\u00f9 radicale in tema di<em> jihad<\/em>; anzi con lui nasce un diverso tipo di consapevolezza sulla funzione politico-religiosa della \u00abguerra santa\u00bb, che avr\u00e0 una grande influenza sul radicalismo islamico degli anni successivi.<\/span><\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #000000;\"><strong>La dottrina contemporanea sul \u00ab<em>jihad<\/em>\u00bb<\/strong><\/span><\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-32685 aligncenter\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2004\/11\/fondamentalismo_islam.jpg\" alt=\"\" width=\"306\" height=\"214\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La dottrina sul<em> jihad ha <\/em>avuto un nuovo e imprevisto sviluppo negli ultimi tempi caratterizzandosi in alcuni casi in senso antigovernativo e in altri, come nel caso di <em>al-Qaeda, <\/em>come attacco globale rivolto ai presunti nemici dell&#8217;isl\u00e0m, in particolare agli Stati arabi filo-occidentali, considerati traditori della causa islamica, a Israele e agli Stati Uniti. Ma di questo qui non ci occupiamo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Negli ultimi decenni sono stati scritti in materia di <em>jihad <\/em>numerosi libri, i quali fondamentalmente si muovono nel solco dei due filoni di pensiero precedentemente analizzati: quello del <em>jihad <\/em>irenico (o difensivo), teso soprattutto alla proclamazione delle verit\u00e0 religiose, e quello del<em> jihad <\/em>combattente o aggressivo, avente come fine la restaurazione del vero isl\u00e0m e l&#8217;acquisizione di nuovi territori alla <em>umma <\/em>musulmana.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Uno dei maggiori esponenti contemporanei della prima tendenza \u00e8 il siriano M. Sa&#8217;id al-Buti. Per questi il<em> jihad \u00e8 <\/em>soprattutto uno strumento di proclamazione del vero isl\u00e0m; inoltre, pur non escludendo del tutto l&#8217;elemento bellico, gli assegna una funzione prevalentemente difensiva: \u00ab\u00c8 divenuto assiomatico che la responsabilit\u00e0 di sorvegliare e difendere questi due patrimoni [il territorio e la societ\u00e0] non pu\u00f2 essere assolta dal <em>jihad <\/em>pacifico [&#8230;]. \u00c8 un compito che pu\u00f2 essere svolto unicamente ricacciando gli aggressori, respingendoli e impedendo qualsiasi danno possano arrecare\u00bb (11).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Pur non accettando il <em>jihad <\/em>puramente aggressivo, secondo lo stile di diversi gruppi fondamentalisti, egli non \u00e8 invece contrario al cosiddetto \u00ab<em>jihad <\/em>preventivo\u00bb, quando si \u00e8 praticamente certi che uno o pi\u00f9 Stati stranieri siano intenzionali a colpire la \u00abnazione\u00bb islamica. Egli giustifica tale tipo di intervento facendo riferimento alle vicende del Profeta, il quale nei suoi ultimi anni di vita combatt\u00e8 contro gli ebrei e contro altre trib\u00f9 arabe politeiste per prevenire un loro attacco contro la vera religione.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">In ogni caso, tale interpretazione relativamente tollerante del<em> jihad <\/em>fu duramente contrastata dai fondamentalisti islamici, perch\u00e9 considerata eccessivamente irenica e contraria agli interessi dell&#8217;isl\u00e0m; essi, fra l&#8217;altro, contestavano ad al-Buti il modo con cui egli nella sua opera <em>Al-Jihadfi al-Isl<\/em><em>am <\/em>aveva delimitato il \u00abterritorio dell&#8217;isl\u00e0m\u00bb, escludendone la Spagna: \u00abNon \u00e8 dunque necessario \u2014 gli veniva obiettato \u2014 per tutti i musulmani purificarla dai suoi rapaci aggressori e ritornare allo Stato islamico?\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">In una successiva edizione della sua opera sul <em>ji<\/em><em>had <\/em>egli su questo punto fa marcia indietro e afferma: \u00abAl-Andalus [la Spagnai rimane parte del territorio dell&#8217;isl\u00e0m giuridicamente, e i musulmani hanno la responsabilit\u00e0, secondo i giureconsulti, di riportarla all&#8217;ovile dell&#8217;isl\u00e0m. Il fatto che i musulmani abbiano trascurato questa loro responsabilit\u00e0 nel corso di tanti secoli non cambia di una virgola quest&#8217;obbligo\u00bb (12).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tale considerazione, che risponde a esigenze interne di propaganda, contraddice di fatto l&#8217;idea di fondo espressa dall&#8217;autore in tema di <em>jihad; <\/em>va anche detto per\u00f2 che incongruenze di questo tipo non sono rare nei testi che trattano di tale delicata materia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Le tesi di al-Buti sul <em>jihad <\/em>difensivo sono state confutate da altri autori che si muovono invece nel solco della tradizione del \u00ab<em>ji<\/em><em>had<\/em> combattente\u00bb. Tra questi ricordiamo il saudita A. al-Qadiri, esponente di spicco del gruppo degli ideologi dell&#8217;islamismo radicale. Egli ha una concezione piuttosto trionfalistica del <em>jihad<\/em>, il cui fine principale \u00e8 glorificare i credenti in Allah e umiliare i miscredenti.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Secondo la sua concezione, il <em>jihad<\/em> \u00e8 la lotta di Dio, per cui non c&#8217;\u00e8 dubbio che, una volta proclamata, essa risulter\u00e0 vittoriosa e produrr\u00e0 i suoi effetti, nel senso che tutti gli infedeli, una volta vinti e sottomessi, si convertiranno in massa alla vera religione.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">C&#8217;\u00e8 un aspetto nel pensiero di questo ideologo radicale che \u00e8 assolutamente nuovo nel panorama degli scritti sul <em>jihad<\/em>. Al-Qadiri \u00e8 l&#8217;unico autore che cerchi di conciliare il <em>jihad <\/em>combattente (\u00abpiccolo <em>jihad<\/em>\u00bb) con lo <em>jihad<\/em> spirituale e interiore (\u00abgrande <em>jihad<\/em>\u00bb). Sappiamo che quest&#8217;ultima forma di <em>jihad <\/em>fu guardata con grande sospetto dalla tradizione ortodossa (poich\u00e9 essa si svilupp\u00f2 in ambienti legati alla mistica sufi), anzi da molti autorevoli giuristi essa fu apertamente rigettata e la sua trattazione, anche in sede teorica, considerata fuorviante.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Secondo al-Qadiri, invece, il combattimento spirituale \u00e8 parte integrante di quello militare; egli ritiene che i ripetuti insuccessi degli eserciti arabi contro Israele e contro gli invasori occidentali siano dovuti al fatto che non ci si prepara spiritualmente alla battaglia. Mentre sarebbe necessario prepararsi al <em>jihad<\/em> contro gli infedeli e gli occupanti sia sotto il profilo militare e strategico, sia soprattutto sotto il profilo spirituale.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Secondo D. Cook, uno dei maggiori studiosi della materia, l&#8217;opera pi\u00f9 importante scritta negli ultimi tempi in materia di <em>jihad <\/em>sarebbero i tre volumi pubblicati nel 1993 dal siriano M. Khayr Haykal, intitolata, \u00ab<em>Jihad <\/em>e combattimento secondo la politica della legge rivelata\u00bb (13). L&#8217;opera tocca tutti i punti concernenti il <em>jihad,<\/em> anche quelli considerati pi\u00f9 spinosi e dibattuti.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Haykal \u00e8 l&#8217;unico tra i teorici contemporanei che affronti il delicato problema della liceit\u00e0 dell&#8217;uso delle armi di distruzione di massa nel <em>jihad.<\/em> Egli ne ammette l&#8217;uso, ricorrendo all&#8217;autorit\u00e0 delle parole del Profeta, il quale approvava il ricorso alla balestra in battaglia, nonostante l&#8217;inconsueta potenza distruttiva di tale arma: \u00abLe due cose infatti \u2014 egli scrive \u2014 sono connesse tra loro, al di l\u00e0 delle notevoli differenze per quanto riguarda la dimensione del pericolo [&#8230;] e ci\u00f2 perch\u00e9 l&#8217;armamento moderno rientra nella definizione dei testi giuridici che autorizzano l&#8217;utilizzo di qualsiasi tattica o arma militare contro il nemico durante la battaglia [&#8230;]. Sicch\u00e9, su questa base fondamentale, \u00e8 consentito l&#8217;impiego di armi contemporanee quali la bomba atomica\u00bb (14).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A tale considerazione aggiunge poi che sarebbe auspicabile che nel territorio interessato non risiedessero musulmani, condizione questa, nel nostro mondo globalizzato, difficile da realizzare. Insomma per Haykal il <em>jihad<\/em> non \u00e8 una lotta incontrollata e senza limiti, anzi, facendo riferimento all&#8217;autorit\u00e0 dei testi antichi che egli conosce molto bene, ritiene che essa sia una forma di \u00abguerra regolata\u00bb e che la sua regolamentazione dipenda di volta in volta dalle reali esigenze della comunit\u00e0 musulmana. In sostanza, la sua idea di <em>jihad <\/em>\u00e8 tanto lontana da quella degli autori irenisti della prima met\u00e0 del Novecento quanto vicina al pensiero degli islamisti radicali, persino a quelli di matrice al-qaedica.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A tutt&#8217;oggi \u00e8 difficile prevedere se nel futuro tale orientamento radicale in tema di <em>jihad <\/em>continuer\u00e0 ad essere prevalente tra i giuristi e gli intellettuali islamici. Intanto molti musulmani respingono la pretesa dei cosiddetti fondamentalisti globali di condurre un <em>jihad <\/em>contro i nemici crociati, sionisti o capitalisti, in difesa dell&#8217;isl\u00e0m e per liberare il territorio dalla presenza degli infedeli. Essi ritengono che tale movimento non abbia nessuna autorit\u00e0 per lanciare un <em>jihad<\/em> combattente, poich\u00e9 tale potere, sostengono, \u00e8 prerogativa esclusiva di un capo musulmano, quale un imam o un califfo legittimo.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Al di l\u00e0 dell&#8217;uso attuale della nozione di <em>jihad,<\/em> non \u00e8 impossibile che in un prossimo futuro essa venga interpretata in termini spirituali o escludendone la componente violenta. Del resto in alcuni settori, anche se minoritari, del mondo islamico il <em>jihad<\/em> \u00e8 inteso come lotta o combattimento per il perfezionamento spirituale.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Inoltre una conseguenza dell&#8217;odierno ricorso al <em>jihad<\/em> e del modo violento e indiscriminato con cui \u00e8 praticato da alcuni gruppi di fondamentalisti, in particolare da al-Qaeda, potrebbe generare un netto rifiuto di tale forma di lotta da parte della maggioranza musulmana silenziosa. Il che non sarebbe impossibile a lungo termine, anche se allo stato dei fatti non ci sono seri indizi che facciano sperare in uri cambiamento di rotta.<\/span><\/p>\n<h4 style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>Note<\/strong><\/span><\/h4>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>1)<\/strong> Cfr G. DE ROSA, <em>Isl\u00e0m e Occidente. Un dialogo difficile ma necessario, <\/em>Leumann (To) &#8211; Roma, Elledici &#8211; La Civilt\u00e0 Cattolica, 2004.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>2)<\/strong> R. RIDA, <em>Fatwa, <\/em>vol. IH, Beirut, 1970, 1.155.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>3)<\/strong> H. al BANNA, <em>Majmu&#8217; at rasa&#8217; il ai-Imam al-Shahib Hasan al-Banna&#8217;, <\/em>Beirut, Dar Al Andalus, 1965,297.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>4)<\/strong> A. AL-MAWDUDI, <em>Al-]ihad fi ai-Isiam, <\/em>Damasco, 1984, 9.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>5)<\/strong> Ivi, 50.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>6)<\/strong> Cfr D. COOK, <em>Storia delj\u00echad. Da Maometto ai nostri giorni, <\/em>Torino, Einaudi,2007, 153.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>7)<\/strong> Sul fondamentalismo islamico si vedano: R. GUOLO, <em>II fondamentalismo islamico, <\/em>Roma &#8211; Bari, Laterza, 2002, 13 s; E KHOSROKHAVAR, <em>I nuovi martiri di Allab. <\/em>Milano, Bruno Mondadori, 2002, 3 s; M. INTROVIGNE. <em>Fondamentalismi. I diversi volli dell&#8217;in-<\/em><em>transigenia religiosa, <\/em>Casale Monferrato (Al), Flemme, 2004; G. KEPEL, <em>jibatl. Ascesa e <\/em><em>declino, <\/em>Milano, Carocci, 2002; B. LEWIS, <em>La crisi dell&#8217;isiam, <\/em>Milano, Mondadori, 2005; P. BRANCA, <em>Vo\u00e0 dell&#8217;isi\u00e0m moderno. Il pensiero arabo-musulmano fra rinnovamento e tradizione, <\/em>Genova, Marietti, 1991.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>8)<\/strong> Cfr S. KASSFFI, <em>L\u2019infelicit\u00e0 araba, <\/em>Torino, Einaudi, 2006, 52; B. LEWIS, <em>Semiti e an<\/em><em>tisemiti. <\/em>Milano, Rizzoli, 2003, 228.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>9)<\/strong> M. PAGAR, <em>The NeglectedDuty, <\/em>New York, Macmillan, 1986, 192<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>10)<\/strong> Cfr D. CdOK, <em>Storia del jihad. Da Maometto ai nostri giorni, <\/em>cit., 164.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>11)<\/strong> M. AL-BUTI, <em>Al-]ihad fi al-Islam, <\/em>Beirut, Dar al-Fikr al-Mu&#8217;asir, 1997, 93.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>12)<\/strong> Ivi, 271.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>13) <\/strong>Cfr. D. COOK, <em>Suicide attacks or \u00abMartyrdom operations\u00bb in Contemporary jihad literature<\/em>, in www.ozlanka.com\/commentary\/jihad.htm<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"><strong>14) <\/strong>M. K. HAYKAL, <em>Al-Jihad wa-l-qital fi al-siyasa al-shara&#8217;iyya<\/em>, vol. II, Beirut, Dar al-Barayiq, 1993, 1.352.<\/span><\/p>\n<p style=\"text-align: justify;\">__________________________________________________<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #000000;\">Leggi anche:<\/span> <\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=129\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Jihad: cosa significa?<\/span><\/a><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=277\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\">Jihad, solo una questione di spirito?<\/span><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Civilt\u00e0 Cattolica n.3791 7 giugno 2008 \u00a0di Giovanni Sale s.j. In questi ultimi anni, soprattutto dopo l&#8217;attacco terroristico dell&#8217;11 settembre 2001 alle Torri Gemelle di New York, il termine. jihad, attraverso l&#8217;uso martellante fattone dai media, \u00e8 entrato a far parte del linguaggio quotidiano e dell&#8217;universo immaginario. Per gli occidentali esso \u00e8 sinonimo di &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-jihad-nel-pensiero-islamico-contemporaneo\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":36216,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16,36],"tags":[1109,527],"class_list":["post-2851","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-islam","category-fondamentalismo-islamico","tag-islam-cose","tag-jihad","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il &laquo;Jihad&raquo; nel pensiero islamico contemporaneo - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Il \u00abJihad\u00bb nel pensiero islamico contemporaneo dove ha prevalso il signifcato di combattimento militare e violento su quello spirituale\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-jihad-nel-pensiero-islamico-contemporaneo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il &laquo;Jihad&raquo; nel pensiero islamico contemporaneo - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Il \u00abJihad\u00bb nel pensiero islamico contemporaneo dove ha prevalso il signifcato di combattimento militare e violento su quello spirituale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-jihad-nel-pensiero-islamico-contemporaneo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-03-13T12:24:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-20T14:29:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/08\/Jihad.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"168\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"29 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-jihad-nel-pensiero-islamico-contemporaneo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-jihad-nel-pensiero-islamico-contemporaneo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Il &laquo;Jihad&raquo; nel pensiero islamico contemporaneo\",\"datePublished\":\"2009-03-13T12:24:08+00:00\",\"dateModified\":\"2024-05-20T14:29:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-jihad-nel-pensiero-islamico-contemporaneo\\\/\"},\"wordCount\":5324,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-jihad-nel-pensiero-islamico-contemporaneo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Jihad.jpg\",\"keywords\":[\"islam cos'\u00e8\",\"Jihad\"],\"articleSection\":[\"Islam\",\"Islam fondamentalismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-jihad-nel-pensiero-islamico-contemporaneo\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-jihad-nel-pensiero-islamico-contemporaneo\\\/\",\"name\":\"Il &laquo;Jihad&raquo; nel pensiero islamico contemporaneo - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-jihad-nel-pensiero-islamico-contemporaneo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-jihad-nel-pensiero-islamico-contemporaneo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Jihad.jpg\",\"datePublished\":\"2009-03-13T12:24:08+00:00\",\"dateModified\":\"2024-05-20T14:29:22+00:00\",\"description\":\"Il \u00abJihad\u00bb nel pensiero islamico contemporaneo dove ha prevalso il signifcato di combattimento militare e violento su quello spirituale\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-jihad-nel-pensiero-islamico-contemporaneo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-jihad-nel-pensiero-islamico-contemporaneo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-jihad-nel-pensiero-islamico-contemporaneo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Jihad.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2016\\\/08\\\/Jihad.jpg\",\"width\":300,\"height\":168},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/il-jihad-nel-pensiero-islamico-contemporaneo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il &laquo;Jihad&raquo; nel pensiero islamico contemporaneo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il &laquo;Jihad&raquo; nel pensiero islamico contemporaneo - Rassegna Stampa Cattolica","description":"Il \u00abJihad\u00bb nel pensiero islamico contemporaneo dove ha prevalso il signifcato di combattimento militare e violento su quello spirituale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-jihad-nel-pensiero-islamico-contemporaneo\/","og_locale":"it_IT","og_type":"article","og_title":"Il &laquo;Jihad&raquo; nel pensiero islamico contemporaneo - Rassegna Stampa Cattolica","og_description":"Il \u00abJihad\u00bb nel pensiero islamico contemporaneo dove ha prevalso il signifcato di combattimento militare e violento su quello spirituale","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-jihad-nel-pensiero-islamico-contemporaneo\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-03-13T12:24:08+00:00","article_modified_time":"2024-05-20T14:29:22+00:00","og_image":[{"width":300,"height":168,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/08\/Jihad.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"29 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-jihad-nel-pensiero-islamico-contemporaneo\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-jihad-nel-pensiero-islamico-contemporaneo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Il &laquo;Jihad&raquo; nel pensiero islamico contemporaneo","datePublished":"2009-03-13T12:24:08+00:00","dateModified":"2024-05-20T14:29:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-jihad-nel-pensiero-islamico-contemporaneo\/"},"wordCount":5324,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-jihad-nel-pensiero-islamico-contemporaneo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/08\/Jihad.jpg","keywords":["islam cos'\u00e8","Jihad"],"articleSection":["Islam","Islam fondamentalismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-jihad-nel-pensiero-islamico-contemporaneo\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-jihad-nel-pensiero-islamico-contemporaneo\/","name":"Il &laquo;Jihad&raquo; nel pensiero islamico contemporaneo - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-jihad-nel-pensiero-islamico-contemporaneo\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-jihad-nel-pensiero-islamico-contemporaneo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/08\/Jihad.jpg","datePublished":"2009-03-13T12:24:08+00:00","dateModified":"2024-05-20T14:29:22+00:00","description":"Il \u00abJihad\u00bb nel pensiero islamico contemporaneo dove ha prevalso il signifcato di combattimento militare e violento su quello spirituale","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-jihad-nel-pensiero-islamico-contemporaneo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-jihad-nel-pensiero-islamico-contemporaneo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-jihad-nel-pensiero-islamico-contemporaneo\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/08\/Jihad.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2016\/08\/Jihad.jpg","width":300,"height":168},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/il-jihad-nel-pensiero-islamico-contemporaneo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Il &laquo;Jihad&raquo; nel pensiero islamico contemporaneo"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2851"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2851\/revisions"}],"predecessor-version":[{"id":60555,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2851\/revisions\/60555"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/36216"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2851"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2851"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}