{"id":2850,"date":"2009-03-13T11:57:40","date_gmt":"2009-03-13T10:57:40","guid":{"rendered":""},"modified":"2016-03-11T13:26:03","modified_gmt":"2016-03-11T12:26:03","slug":"samuelson-adesso-la-politica-deve-tornare-al-centro","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/samuelson-adesso-la-politica-deve-tornare-al-centro\/","title":{"rendered":"Samuelson: &laquo;Adesso la politica deve tornare al centro&raquo;"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-31739\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/Paul-Samuelson.jpg\" alt=\"Paul Samuelson\" width=\"240\" height=\"171\" \/>Il Sole 24 Ore,<\/strong> 5 Novembre 2008<\/div>\n<p style=\"text-align: justify;\"><em>La crisi economica\u00a0si era annunciata dieci anni fa ma\u00a0\u00a0si \u00e8 preferito continuare a fare soldi. Adesso il pericolo \u00e8 lo spostamento a &#8220;sinistra&#8221; dell&#8217;economia\u00a0americana, con effetti ancor piu&#8217; dannosi. Parla Paul Samuelson, decano degli economisti Usa<br \/>\n<\/em><\/p>\n<p style=\"text-align: center;\">dal nostro inviato <strong>Mario Platero<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">CHICAGO &#8211; Paul Samuelson non abita pi\u00f9 qui. Ma ricorda con nostalgia, quando, 73 anni fa, viveva da studente alla Chicago university. Ha un&#8217;immagine chiara degli anni della Depressione, quando \u00abdalle finestre dell&#8217;universit\u00e0 vedevo un mondo molto diverso da quello che descrivevano i libri di testo, un mondo di povera gente e disperazione\u00bb.Samuelson, decano degli economisti americani, premio Nobel e autore di testi di importanza storica, ricorda anche i lunghi pomeriggi d&#8217;estate passati sulle spiagge del lago Michigan, su cui si affaccia Chicago: \u00abNon perch\u00e9 fossi un fannullone o figlio di ricchi. Ma perch\u00e9 vedevo la delusione sul volto dei miei compagni che sprecavano il tempo a cercare un lavoro per l&#8217;estate, senza alcuna possibilit\u00e0 di successo\u00bb.<\/div>\n<p style=\"text-align: justify;\">\u00c8 qui, a Chicago, da dove \u00e8 partita l&#8217;avventura di Barack Obama, che Samuelson ha studiato fra i neoclassici e i conservatori, per poi trovare una sua strada pi\u00f9 interventista e keynesiana, davanti all&#8217;evidenza del disastro che si era consumato in quegli anni: prima con il crollo di Borsa del 1929 e poi con la Depressione.<\/p>\n<p style=\"text-align: justify;\">Abbandon\u00f2 il conservatorismo che dominava la sua scuola di Chicago per cominciare un percorso molto diverso, che lui stesso definisce centrista. I ricordi si affollano, ma su tutto prevalgono due fatti che oggi, a 93 anni, gli danno forza e stupore allo stesso tempo: la catastrofe finanziaria degli ultimi mesi, molto simile per dinamica a quella degli anni Trenta; la candidatura di un afro-americano alla Casa Bianca: \u00abNon mi sarei aspettato di vedere nella mia vita n\u00e9 l&#8217;uno n\u00e9 l&#8217;altro. Figuriamci tutti e due. A 93 anni c&#8217;\u00e8 ancora qualcosa che riesce a sorprendermi, un privilegio non da poco per uno della mia et\u00e0\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Cos&#8217;altro la sorprende professore?<\/strong><\/p>\n<p style=\"text-align: justify;\">L&#8217;ottusit\u00e0 del genere umano. Questa era una crisi annunciata. Bear Stearns era l&#8217;intermediario della Long Term Capital, il primo campanello d&#8217;allarme che squill\u00f2 dieci anni fa per dirci di fare attenzione. Ma fare soldi a breve era pi\u00f9 importante della certezza di stabilit\u00e0 a lungo termine. E su un punto non ci sono dubbi: la colpa \u00e8 nostra. \u00c8 Wall Street ad aver aperto la strada al disastro su cui si \u00e8 poi messo il resto del mondo. Sono stati i nostri professori, alcuni miei allievi al Mit, ad aver sviluppato teorie per la distribuzione del rischio, che sarebbero poi risultate fatali per un semplice errore: non hanno tenuto conto dell&#8217;insaziabilit\u00e0 del genere umano.<\/p>\n<p style=\"text-align: justify;\"><strong>Vale a dire?<\/strong><\/p>\n<p style=\"text-align: justify;\">Immagini di avere una mazza da baseball, se ci prova, riuscir\u00e0 a mettere in equilibrio su un dito. Ma se il bastone diventa grande quanto l&#8217;Empire State Building, allora sar\u00e0 impossibile metterlo in equilibrio. Il gigantismo incontrollato \u00e8 stato il nostro peccato. Ci vorranno regole nuove. Ma attenzione non regole che strangolino il malato.<\/p>\n<p style=\"text-align: justify;\"><strong>Se guarda al futuro immediato, cosa la preoccupa?<\/strong><\/p>\n<p style=\"text-align: justify;\">Che il pendolo dell&#8217;ideologia si sposti troppo a sinistra. Mi spaventa l&#8217;idea che al Senato potrebbe essere una maggioranza di 60 voti a favore dei democratici, che impedir\u00e0 l&#8217;ostruzionismo. Questo significa che si potranno fare in libert\u00e0 cose che potrebbero essere altrettanto dannose per il Paese, ad esempio aumentare spese inutili, per accontentare certe basi politiche. Rafforzando i sindacati, che hanno portato non pochi danni al Paese con rigidit\u00e0 distruttive per l&#8217;industria dell&#8217;auto.<\/p>\n<p style=\"text-align: justify;\"><strong>Lei crede comunque che si torner\u00e0 indietro a politiche simili al New Deal?<\/strong><\/p>\n<p style=\"text-align: justify;\">Non si torna mai indietro. Il mondo \u00e8 diverso. Ci sono nuove sfide. Quelle ambientali, ad esempio, che diventano centrali per lo sviluppo. Il mondo cambia. E dunque il mio consiglio \u00e8 di guardare avanti, non indietro. Il mio appello \u00e8 semplice: non si abbandoni il centro. Sono un centrista perch\u00e9 so dalla storia economica quali pericoli possono derivare dai movimenti estremi, sia quelli verso un eccessivo liberismo, come quello che abbiamo testimoniato prima della crisi, sia quelli verso gli estremi della centralizzazione e della rigidit\u00e0. Mi ascolti: Mao e Marx erano pagliacci, non avevano alcuna idea di come si deve gestire un&#8217;economia. Il nuovo Presidente dovr\u00e0 collocarsi al centro. E guidare l&#8217;America lungo nuovi percorsi che ancora non conosciamo.<\/p>\n<p style=\"text-align: justify;\"><strong>Parliamo di una sfida concreta: \u00e8 favorevole a salvare l&#8217;industria dell&#8217;auto, come sono state salvate le banche?<\/strong><\/p>\n<p style=\"text-align: justify;\">No. Ma se si dovr\u00e0 fare un pacchetto di aiuti, prima le aziende dovranno fallire. Si dovr\u00e0 avere il coraggio di riconoscere che il management ha sbagliato, ma che hanno sbagliato anche i sindacati a rivendicare diritti fuori dai modelli competitivi internazionali<\/p>\n<p style=\"text-align: justify;\"><strong>Altro argomento molto concreto, la spesa pubblica. Ci vorranno importanti pacchetti di stimolo per l&#8217;economia. \u00c8 preoccupato dal disavanzo che ne seguir\u00e0?<\/strong><\/p>\n<p style=\"text-align: justify;\">Gli stimoli sono importanti. Purch\u00e9 siano intelligenti. Da sempre si \u00e8 stampato danaro per rimettere in carreggiata un&#8217;economia in difficolt\u00e0. Lo hanno fatto anche i tedeschi fra le due guerre. Sappiamo quali saranno i pericoli: iperinflazione. Anche nel caso americano il processo porter\u00e0 inflazione. Ma non credo che avremo iperinflazione. Non credo che gli aumenti possano essere superiori al 10 per cento.<\/p>\n<p style=\"text-align: justify;\"><strong>E l&#8217;Europa? Ci sono vincoli per la Bce perch\u00e9 si occupi solo di inflazione e sulla spesa pubblica per il patto di stabilit\u00e0.<\/strong><\/p>\n<p style=\"text-align: justify;\">Se li dimentichi quei vincoli. Non si pu\u00f2 ragionare come se questo fosse un normale aggiustamento ciclico che pu\u00f2 essere accomodato con piccoli spostamenti. La svolta \u00e8 epocale e la Banca centrale europea \u00e8 in ritardo. Dovr\u00e0 cambiare filosofia, dovr\u00e0 mettere la recessione davanti al pericolo di inflazione. \u00c8 questione di intelligenza non di regole. Allo stesso modo sono certo che i Governi nazionali ignoreranno Bruxelles. Mi fanno sorridere le rivendicazioni dei burocrati che sventolano i manuali. Ragazzi: la casa brucia, altro che manuali. Anche perch\u00e9, ci pensi: non ci sar\u00e0 un Paese che sgarra a danno degli altri. Lo faranno tutti insieme e dunque saranno &#8211; saremo &#8211; tutti sulla stessa barca.<\/p>\n<p style=\"text-align: justify;\"><strong>L&#8217;America \u00e8 in declino?<\/strong><\/p>\n<p style=\"text-align: justify;\">La forza economica americana ha sofferto molto. No so se riusciremo a ritrovare il predominio del passato. Ma sono convinto di una cosa: il nostro indebolimento relativo si sarebbe verificato lo stesso, con o senza crisi, non foss&#8217;altro perch\u00e9 la Cina e l&#8217;India avanzano. E dunque parliamo di globalizzazione: \u00e8 con noi per restare. Ma un piccolo rallentamento non far\u00e0 male: oggi abbiamo bisogno di ecletticit\u00e0, non di lacciuoli legalistici.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Sole 24 Ore, 5 Novembre 2008 La crisi economica\u00a0si era annunciata dieci anni fa ma\u00a0\u00a0si \u00e8 preferito continuare a fare soldi. Adesso il pericolo \u00e8 lo spostamento a &#8220;sinistra&#8221; dell&#8217;economia\u00a0americana, con effetti ancor piu&#8217; dannosi. Parla Paul Samuelson, decano degli economisti Usa dal nostro inviato Mario Platero<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/samuelson-adesso-la-politica-deve-tornare-al-centro\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":31739,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,108,76],"tags":[2389,150],"class_list":["post-2850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-paesi-e-continenti","category-stati-uniti","tag-economia","tag-usa","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Samuelson: &laquo;Adesso la politica deve tornare al centro&raquo; - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/samuelson-adesso-la-politica-deve-tornare-al-centro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Samuelson: &laquo;Adesso la politica deve tornare al centro&raquo; - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/samuelson-adesso-la-politica-deve-tornare-al-centro\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-03-13T10:57:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-11T12:26:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/Paul-Samuelson.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"266\" \/>\n\t<meta property=\"og:image:height\" content=\"190\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/samuelson-adesso-la-politica-deve-tornare-al-centro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/samuelson-adesso-la-politica-deve-tornare-al-centro\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Samuelson: &laquo;Adesso la politica deve tornare al centro&raquo;\",\"datePublished\":\"2009-03-13T10:57:40+00:00\",\"dateModified\":\"2016-03-11T12:26:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/samuelson-adesso-la-politica-deve-tornare-al-centro\\\/\"},\"wordCount\":1083,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/samuelson-adesso-la-politica-deve-tornare-al-centro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/Paul-Samuelson.jpg\",\"keywords\":[\"Economia\",\"Usa\"],\"articleSection\":[\"Economia\",\"Paesi e continenti\",\"Stati Uniti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/samuelson-adesso-la-politica-deve-tornare-al-centro\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/samuelson-adesso-la-politica-deve-tornare-al-centro\\\/\",\"name\":\"Samuelson: &laquo;Adesso la politica deve tornare al centro&raquo; - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/samuelson-adesso-la-politica-deve-tornare-al-centro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/samuelson-adesso-la-politica-deve-tornare-al-centro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/Paul-Samuelson.jpg\",\"datePublished\":\"2009-03-13T10:57:40+00:00\",\"dateModified\":\"2016-03-11T12:26:03+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/samuelson-adesso-la-politica-deve-tornare-al-centro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/samuelson-adesso-la-politica-deve-tornare-al-centro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/samuelson-adesso-la-politica-deve-tornare-al-centro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/Paul-Samuelson.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/Paul-Samuelson.jpg\",\"width\":266,\"height\":190},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/samuelson-adesso-la-politica-deve-tornare-al-centro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Samuelson: &laquo;Adesso la politica deve tornare al centro&raquo;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Samuelson: &laquo;Adesso la politica deve tornare al centro&raquo; - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/samuelson-adesso-la-politica-deve-tornare-al-centro\/","og_locale":"it_IT","og_type":"article","og_title":"Samuelson: &laquo;Adesso la politica deve tornare al centro&raquo; - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/samuelson-adesso-la-politica-deve-tornare-al-centro\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-03-13T10:57:40+00:00","article_modified_time":"2016-03-11T12:26:03+00:00","og_image":[{"width":266,"height":190,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/Paul-Samuelson.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/samuelson-adesso-la-politica-deve-tornare-al-centro\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/samuelson-adesso-la-politica-deve-tornare-al-centro\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Samuelson: &laquo;Adesso la politica deve tornare al centro&raquo;","datePublished":"2009-03-13T10:57:40+00:00","dateModified":"2016-03-11T12:26:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/samuelson-adesso-la-politica-deve-tornare-al-centro\/"},"wordCount":1083,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/samuelson-adesso-la-politica-deve-tornare-al-centro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/Paul-Samuelson.jpg","keywords":["Economia","Usa"],"articleSection":["Economia","Paesi e continenti","Stati Uniti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/samuelson-adesso-la-politica-deve-tornare-al-centro\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/samuelson-adesso-la-politica-deve-tornare-al-centro\/","name":"Samuelson: &laquo;Adesso la politica deve tornare al centro&raquo; - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/samuelson-adesso-la-politica-deve-tornare-al-centro\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/samuelson-adesso-la-politica-deve-tornare-al-centro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/Paul-Samuelson.jpg","datePublished":"2009-03-13T10:57:40+00:00","dateModified":"2016-03-11T12:26:03+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/samuelson-adesso-la-politica-deve-tornare-al-centro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/samuelson-adesso-la-politica-deve-tornare-al-centro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/samuelson-adesso-la-politica-deve-tornare-al-centro\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/Paul-Samuelson.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/Paul-Samuelson.jpg","width":266,"height":190},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/samuelson-adesso-la-politica-deve-tornare-al-centro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Samuelson: &laquo;Adesso la politica deve tornare al centro&raquo;"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2850"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2850\/revisions"}],"predecessor-version":[{"id":31740,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2850\/revisions\/31740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/31739"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}