{"id":2838,"date":"2009-03-13T09:12:26","date_gmt":"2009-03-13T08:12:26","guid":{"rendered":""},"modified":"2015-12-21T16:08:48","modified_gmt":"2015-12-21T15:08:48","slug":"pochi-bambini-down-arrivano-alla-nascita","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pochi-bambini-down-arrivano-alla-nascita\/","title":{"rendered":"Pochi bambini down arrivano alla nascita"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/bimbo_down.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-29014\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/bimbo_down.jpg\" alt=\"bimbo_down\" width=\"250\" height=\"166\" \/><\/a>Corrispondenza Romana <\/strong>n.1061\/04<\/div>\n<div style=\"text-align: center;\">del 4 ottobre 2008<\/div>\n<p style=\"text-align: justify;\"><em>In seguito alla candidatura repubblicana del governatore Sarah Palin alla vicepresidenza degli Stati Uniti \u00e8 riemerso l\u2019interesse per la sindrome di Down. <\/em><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Il 18 aprile, Palin ha dato alla luce Trig Paxon Van Palin, pur avendo saputo dai medici, nel dicembre scorso, che il bimbo era affetto dalla sindrome di Down, come riferito dall\u2019\u201cAssociated Press\u201d il 3 maggio. Secondo un articolo dell\u2019opinionista Michael Gerson, pubblicato sul \u201cWashington Post\u201d del 10 settembre, quando le analisi prenatali rivelano la presenza della sindrome di Down, il 90% delle volte si decide per l\u2019aborto.<\/div>\n<p style=\"text-align: justify;\">Il numero degli aborti di bambini affetti dalla sindrome potrebbe ulteriormente aumentare se la raccomandazione emanata lo scorso anno dalla American College of Obstetricians and Gynecologists venisse applicata, ha aggiunto. Il College ha infatti invitato a sottoporre precocemente all\u2019analisi per la sindrome di Down tutte le donne in gravidanza e non solo quelle al di sopra di una certa et\u00e0, i cui bambini hanno quindi maggiori probabilit\u00e0 di esserne affetti. Gerson ha tuttavia sostenuto che i figli nati con sindrome di Down \u00abgeneralmente non vengono considerati dai loro genitori come una maledizione ma come una complessa benedizione\u00bb.<\/p>\n<p style=\"text-align: justify;\">Molti medici e consiglieri, tuttavia, invitano le madri ad abortire. Questa tendenza a voler porre fine a vite \u00abimperfette\u00bb, ha proseguito Gerson, non pu\u00f2 essere tenuta distinta rispetto al nostro generale atteggiamento nei confronti dei disabili. \u00abQuesta tendenza alimenta un darwinismo sociale in cui il pi\u00f9 forte \u00e8 considerato migliore, la persona dipendente come avente un valore inferiore e in cui i deboli debbono talvolta essere oggetto di selezione\u00bb, ha concluso. Nonostante le difficolt\u00e0 di chi si trova con un figlio down, molti quotidiani hanno raccontato casi in cui i genitori che si sono trovati in queste situazioni hanno vissuto esperienze positive.<\/p>\n<p style=\"text-align: justify;\">Crescere un figlio down pu\u00f2 portare alla luce molte verit\u00e0 profonde per i genitori e i loro figli, secondo il \u201cWashington Post\u201d del 14 settembre. Nell\u2019articolo si descrive il caso di Adrianne Pedlikin, madre di tre figli, tra cui un bambino di 10 anni affetto dalla sindrome di Down. Pur riconoscendo le difficolt\u00e0 e le sfide legate al dover crescere un figlio down, l\u2019articolo sottolinea che, allo stesso tempo, sia Adrianne che suo marito Philip non nascondono il loro amore per questo figlio e affermano che la sua nascita ha cambiato la loro visione del mondo in senso positivo.<\/p>\n<p style=\"text-align: justify;\">Un\u2019altra testimonianza positiva di chi \u00e8 genitore di un bimbo down \u00e8 stata pubblicata il 2 giugno sul quotidiano britannico \u201cGuardian\u201d. Annie Rey racconta della repulsione che provava, quando era giovane, nei confronti dei disabili. Poi, arrivata ai 40 anni, ha scoperto di essere incinta di un bambino con la sindrome di Down. \u00abDurante la gravidanza passavo dall\u2019ottimismo alla disperazione: ottimismo nella speranza che il bambino, che all\u2019et\u00e0 di 20 settimane abbiamo appreso essere maschio, non avesse veramente la sindrome di Down, e disperazione al pensiero che invece l\u2019avesse\u00bb, ha scritto.<\/p>\n<p style=\"text-align: justify;\">Suo figlio Paddi ha ora 2 anni e lei ha accettato l\u2019idea di avere un bambino down. Ha detto di aver scoperto che suo figlio non \u00e8 \u00abuna diagnosi\u00bb, ma un bambino con molte qualit\u00e0. \u00abSono fermamente convinta che se il mio prezioso bambino non esistesse, il nostro mondo, e forse il mondo intero, sarebbe un posto pi\u00f9 povero\u00bb, ha concluso.<\/p>\n<p style=\"text-align: justify;\">Dal Canada, la famiglia Shaw ha raccontato la propria esperienza con un figlio down, in un articolo pubblicato il 2 marzo sull\u2019\u201cOttawa Citizen\u201d. Michael e Lesley Shaw avrebbero abortito se avessero saputo che la loro figlia Sydney era affetta dalla sindrome di Down, secondo quanto hanno riferito al quotidiano. Il padre ha dichiarato che, ora che Sydney ha 9 anni, hanno cambiato opinione e considerano la loro figlia come \u00abuna bimba meravigliosa e gioiosa\u00bb.<\/p>\n<p style=\"text-align: justify;\">\u00abSydney ha arricchito la mia vita ad un punto tale che non credevo possibile\u00bb, ha detto Michael Shaw. \u00abHa cambiato l\u2019intera visione che avevo sulla vita, su ci\u00f2 che ha valore e cosa non ne ha, e su ci\u00f2 che consideriamo apprezzabile\u00bb. Michael Shaw fa anche parte della Canadian Down Syndrome Society, un\u2019organizzazione preoccupata per il rischio di una generalizzazione della diagnosi prenatale in Canada e le ripercussioni sui bambini sindromici.<\/p>\n<p style=\"text-align: justify;\">Nel febbraio 2007, la Society of Obstetricians and Gynecologists of Canada ha emanato nuove linee guida in cui si raccomanda che ad ogni donna incinta, di qualunque et\u00e0, venga offerto uno screening genetico prenatale non invasivo. Secondo l\u2019\u201cOttawa Citizen\u201d circa l\u201980%-90% delle donne canadesi a cui \u00e8 diagnosticata la sindrome di Down decidono di abortire (\u201cZenit\u201d, 28 settembre 2008).<\/p>\n<p style=\"text-align: justify;\">Lo sviluppo di nuove tecniche diagnostiche potrebbe facilitare ulteriormente la decisione dei genitori di ricorrere all\u2019aborto dei feti non perfetti. Il 21 giugno, il quotidiano \u201cTimes\u201d di Londra ha riferito di un esame sperimentale, sviluppato da un\u2019equipe dell\u2019Universit\u00e0 cinese di Hong Kong, che prometterebbe di diagnosticare la sindrome di Down attraverso l\u2019esame del sangue della madre.<\/p>\n<p style=\"text-align: justify;\">Attualmente si ricorre ad esami pi\u00f9 invasivi quali l\u2019amniocentesi o la villocentesi. Questi test comportano l\u2019introduzione di un ago nel ventre materno per asportare del liquido amniotico in cui \u00e8 immerso il feto, oppure una particella della placenta.<\/p>\n<p style=\"text-align: justify;\">Secondo il \u201cTimes\u201d queste tecniche hanno una percentuale di aborto spontaneo di uno su cento, tanto che ogni anno, in Gran Bretagna, 320 gravidanze sane vengono interrotte a causa delle diagnosi invasive. Il nuovo esame \u00e8 ancora in fase sperimentale, ma potrebbe essere pronto per un uso corrente tra qualche anno.<\/p>\n<p style=\"text-align: justify;\">Secondo un articolo pubblicato il 14 settembre dal quotidiano britannico \u201cObserver\u201d, i rischi connessi con le diagnosi prenatali per la sindrome di Down sarebbero molto pi\u00f9 alti. Una nuova ricerca rivela infatti che per ogni tre bambini abortiti, affetti dalla sindrome, due bambini sani muoiono per aborto spontaneo dovuto alle tecniche invasive. Questa nuova ricerca, pubblicata da poco sulla rivista \u201cDown Syndrome Research and Practice\u201d, sostiene che per diagnosticare e prevenire la nascita di 660 bambini down, 400 feti sani vengono perduti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Corrispondenza Romana n.1061\/04 del 4 ottobre 2008 In seguito alla candidatura repubblicana del governatore Sarah Palin alla vicepresidenza degli Stati Uniti \u00e8 riemerso l\u2019interesse per la sindrome di Down.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pochi-bambini-down-arrivano-alla-nascita\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":29014,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,117],"tags":[382],"class_list":["post-2838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aborto","category-eugenetica","tag-eugenetica-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pochi bambini down arrivano alla nascita - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pochi-bambini-down-arrivano-alla-nascita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pochi bambini down arrivano alla nascita - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pochi-bambini-down-arrivano-alla-nascita\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-03-13T08:12:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-12-21T15:08:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/bimbo_down.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pochi-bambini-down-arrivano-alla-nascita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pochi-bambini-down-arrivano-alla-nascita\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Pochi bambini down arrivano alla nascita\",\"datePublished\":\"2009-03-13T08:12:26+00:00\",\"dateModified\":\"2015-12-21T15:08:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pochi-bambini-down-arrivano-alla-nascita\\\/\"},\"wordCount\":977,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pochi-bambini-down-arrivano-alla-nascita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/bimbo_down.jpg\",\"keywords\":[\"eugenetica\"],\"articleSection\":[\"Aborto\",\"Eugenetica\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pochi-bambini-down-arrivano-alla-nascita\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pochi-bambini-down-arrivano-alla-nascita\\\/\",\"name\":\"Pochi bambini down arrivano alla nascita - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pochi-bambini-down-arrivano-alla-nascita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pochi-bambini-down-arrivano-alla-nascita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/bimbo_down.jpg\",\"datePublished\":\"2009-03-13T08:12:26+00:00\",\"dateModified\":\"2015-12-21T15:08:48+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pochi-bambini-down-arrivano-alla-nascita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pochi-bambini-down-arrivano-alla-nascita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pochi-bambini-down-arrivano-alla-nascita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/bimbo_down.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/bimbo_down.jpg\",\"width\":275,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/pochi-bambini-down-arrivano-alla-nascita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pochi bambini down arrivano alla nascita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pochi bambini down arrivano alla nascita - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pochi-bambini-down-arrivano-alla-nascita\/","og_locale":"it_IT","og_type":"article","og_title":"Pochi bambini down arrivano alla nascita - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pochi-bambini-down-arrivano-alla-nascita\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-03-13T08:12:26+00:00","article_modified_time":"2015-12-21T15:08:48+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/bimbo_down.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pochi-bambini-down-arrivano-alla-nascita\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pochi-bambini-down-arrivano-alla-nascita\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Pochi bambini down arrivano alla nascita","datePublished":"2009-03-13T08:12:26+00:00","dateModified":"2015-12-21T15:08:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pochi-bambini-down-arrivano-alla-nascita\/"},"wordCount":977,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pochi-bambini-down-arrivano-alla-nascita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/bimbo_down.jpg","keywords":["eugenetica"],"articleSection":["Aborto","Eugenetica"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pochi-bambini-down-arrivano-alla-nascita\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pochi-bambini-down-arrivano-alla-nascita\/","name":"Pochi bambini down arrivano alla nascita - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pochi-bambini-down-arrivano-alla-nascita\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pochi-bambini-down-arrivano-alla-nascita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/bimbo_down.jpg","datePublished":"2009-03-13T08:12:26+00:00","dateModified":"2015-12-21T15:08:48+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pochi-bambini-down-arrivano-alla-nascita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pochi-bambini-down-arrivano-alla-nascita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pochi-bambini-down-arrivano-alla-nascita\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/bimbo_down.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/bimbo_down.jpg","width":275,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/pochi-bambini-down-arrivano-alla-nascita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Pochi bambini down arrivano alla nascita"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2838"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2838\/revisions"}],"predecessor-version":[{"id":29015,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2838\/revisions\/29015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/29014"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}