{"id":2770,"date":"2009-03-09T09:57:16","date_gmt":"2009-03-09T08:57:16","guid":{"rendered":""},"modified":"2016-06-14T14:12:55","modified_gmt":"2016-06-14T12:12:55","slug":"neonati-poche-settimane-tanto-diritto-di-vivere","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/neonati-poche-settimane-tanto-diritto-di-vivere\/","title":{"rendered":"Neonati: poche settimane, tanto diritto di vivere"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-34700\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/prematuro.jpg\" alt=\"prematuro\" width=\"250\" height=\"166\" \/>Avvenire<\/strong> inserto <em>E\u2019 Vita, <\/em>14 giugno 2007<\/div>\n<p style=\"text-align: justify;\">Nel 1960 il 90% dei bambini di peso inferiore al chilo moriva. Fortuna che nessuno ha pensato di etichettare la cura di questi piccolissimi come &#8220;accanimento terapeutico&#8221;, altrimenti non saremmo arrivati al risultato di oggi: il 90% dei bambini sotto il chilo di peso sopravvive.<\/p>\n<p style=\"text-align: center;\">di <strong>Carlo Bellieni<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">\u00c8 stato dunque un eccesso curare questi bambini, pur sapendo che, all\u2019epoca, quasi tutti sarebbero morti? Basterebbe chiederlo ai loro pap\u00e0 e mamme, per capire che ne \u00e8 valsa la pena. Oggi si assiste a qualcosa di simile: i bambini nati a 23 settimane hanno il 25% circa di possibilit\u00e0 di vivere e quelli di 22 settimane circa il 5-10%. Vale la pena di provare a curarli alla nascita? Se lo stanno chiedendo in molti, colpiti dal fatto che di quelli sopravvissuti molti risulteranno variamente disabili.<\/div>\n<p style=\"text-align: justify;\">Ma proviamo a capire meglio: se vediamo un vicino di casa che cade dal quinto piano di un caseggiato c\u2019\u00e8 un\u2019alta possibilit\u00e0 che muoia o che resti gravemente ferito, ma non per questo non ci affanniamo per chiamare un\u2019ambulanza. Se \u00e8 fortunatissimo se la caver\u00e0 con qualche graffio, ma potrebbe anche poter restare costretto a muoversi su una sedia a rotelle. Non lo sappiamo, ma un vicino \u00e8 in pericolo, e chiamiamo l\u2019ambulanza.<\/p>\n<p style=\"text-align: justify;\">Per il neonato la situazione \u00e8 analoga: tranne pochissimi casi, se nasce piccolissimo non abbiamo nessuno strumento per sapere se sopravviver\u00e0, se avr\u00e0 danni gravi o lievi. Sappiamo che i rischi che muoia sono altissimi, e i rischi che resti con qualche forma di disabilit\u00e0 lo sono altrettanto: cosa facciamo? Lo lasciamo morire?<\/p>\n<p style=\"text-align: justify;\">Nel febbraio 2006 <em>Repubblica<\/em> titolava \u00abFermiamo le cure intensive per i neonati troppo prematuri\u00bb, commentando un documento presentato da un gruppo di medici in quei giorni a Firenze. \u00abNiente cure intensive per il neonato di 22-23 settimane, ma solo un accompagnamento dolce alla morte \u2013 si leggeva nella sintesi giornalistica \u2013; trattamento intensivo per quello di 24 solo se la rianimazione produce \u00absforzi respiratori spontanei, frequenza cardiaca, ripresa del colorito; rianimazione e cure intensive obbligatorie, invece, per i nati dalle 25 settimane in poi\u00bb.<\/p>\n<p style=\"text-align: justify;\">Ma cos\u2019ha di diverso un neonato da un adulto, che invece cureremmo senza alcuna esitazione? Forse due cose: la possibilit\u00e0 di esprimersi e farsi valere e il fatto che ancora non ha avuto il tempo di farsi amare.<\/p>\n<p style=\"text-align: justify;\">Riguardo la scelta se curarlo sulla base della sua impossibilit\u00e0 di esprimersi, crediamo che in uno Stato civile questo non possa essere mai un criterio per prendere una decisione: chi \u00e8 debole, proprio per questo dev\u2019essere pi\u00f9 tutelato. Riguardo la seconda ipotesi \u2013 cio\u00e8 curare solo chi \u00e8 chiaramente voluto e amato \u2013 solo un pregiudizio porta a credere che la scomparsa di un bambino dia meno dolore di quella di un adulto. Ma se anche cos\u00ec non fosse, dovremmo curare \u2013 o astenerci dal farlo \u2013 solo nell\u2019interesse del paziente (il bambino) e non di altri (i tutori).<\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 allora \u2013 come si chiedeva Fabio Mosca, direttore della Clinica Mangiagalli di Milano al recente Congresso nazionale di neonatologia di Rimini \u2013 non concedere una chance a chi nasce, seppur a rischio di morte o di danni? Si potr\u00e0 rispondere: \u00abPerch\u00e9 \u00e8 interesse del bambino gravemente disabile non vivere\u00bb.<\/p>\n<p style=\"text-align: justify;\">Siamo sicuri? \u00c8 stato forse chiesto a lui cosa preferisce? L\u2019abbiamo semmai chiesto ai genitori, che sono impegnati col trauma di una nascita prematura, destinatari della comunicazione frettolosa dell\u2019unica verit\u00e0 che un medico pu\u00f2 dire in quel momento, che cio\u00e8 non sappiamo quali saranno le conseguenze.<\/p>\n<p style=\"text-align: justify;\">Pu\u00f2 nascere da questo una decisione cosciente e ben informata? Si sente dire anche che si deve far prevalere la &#8220;qualit\u00e0&#8221; della vita prevedibile per il bambino: ma come si pu\u00f2 decidere della qualit\u00e0 della vita se alla nascita non abbiamo strumenti per conoscerla e se, oltretutto, il diretto interessato non pu\u00f2 darci il suo parere? Giuseppe Buonocore, ex presidente della European Society of Pediatric Research, sostiene che invece di pensare a scegliere chi deve vivere, la societ\u00e0 dovrebbe impegnarsi per una distribuzione solidale, seria, utile di fondi, di cultura, di integrazione a chi \u00e8 pi\u00f9 malato.<\/p>\n<p style=\"text-align: justify;\">Certo, attenti a non cadere nell\u2019accanimento terapeutico; se un bambino dopo aver iniziato le manovre curative non risponde entro un ragionevole periodo di tempo non abbiamo motivi per insistere; cos\u00ec come non si devono usare mezzi straordinari per rianimare bambini con patologie mortali.<\/p>\n<p style=\"text-align: justify;\">E, infine, attenti a tenere i genitori sempre al centro del programma curativo che pu\u00f2 comprendere le cure intensive come le cure palliative di fin di vita: i genitori sono i primi alleati del bambino, bisogna fare in modo che mai nessuno possa dire che il dolore di un bambino \u00e8 insopportabile, in un\u2019epoca che ha gli strumenti per vincerlo. Ma non \u00e8 accanimento terapeutico trattare il neonato come tratteremmo l\u2019adulto che avesse un grave incidente stradale: prima di dire che le cure sono inutili in un adulto verificheremmo diagnosi e prognosi, mentre qui\u2026 abbiamo solo il breve tempo di uno sguardo sul lettino in sala parto.<\/p>\n<p style=\"text-align: justify;\">Dunque perch\u00e9 non agire con questi piccoli come si agisce con gli altri? Perch\u00e9, sostiene il presidente dei neonatologi toscani, Franco Bagnoli, non usare il solito tubo per l\u2019ossigeno, vedere se risponde ed eventualmente sospendere le cure se la risposta non arriva? Attenti: sospendendo le cure sotto una certa et\u00e0, anche dei bambini che sarebbero sopravvissuti e avrebbero avuto pochi danni saranno lasciati senza cure.<\/p>\n<p style=\"text-align: justify;\">Ma forse l\u2019handicap ci fa cos\u00ec paura che preferiamo dare un taglio alle zone grigie dove non \u00e8 tanto incerto il sopravvivere, ma \u00e8 quasi certo l\u2019handicap. Oltre 300 operatori della sanit\u00e0 neonatale scrissero nel 2006 una lettera aperta ai giornali prendendo le distanze da una mentalit\u00e0 che vede la vita umana come qualcosa che si pu\u00f2 sezionare con barriere e confini, e un congresso di oltre 500 medici e infermieri neonatologi tenutosi a Bologna nel dicembre dello stesso anno ribadiva lo stesso concetto, pur concordando che c\u2019\u00e8 un limite all\u2019intervento medico, ma che questo va visto caso per caso e verificato con attenzione prima di dire che non \u00e8 il caso di intervenire.<\/p>\n<p style=\"text-align: justify;\">In questi giorni il Ministro Turco e il Comitato Nazionale di Bioetica prendono visione del problema e si domanderanno se \u00e8 giusto rianimare chi \u00e8 a rischio di morte, pretendendo, speriamo, che si abbia una sicura diagnosi \u2013 quasi sempre impossibile alla nascita \u2013 prima di sospendere le cure.<\/p>\n<p style=\"text-align: justify;\">Si domanderanno anche se vale la pena di rianimare un piccolissimo a rischio di disabilit\u00e0\u2026 e su questo speriamo che si facciano consigliare anche da coloro che vivono concretamente la disabilit\u00e0, troppo spesso lasciati nel silenzio e che, contrariamente alle visioni fobiche della malattia che ci attorniano, raramente, davvero raramente chiedono di morire. La disabilit\u00e0 fa paura; ma che mai pi\u00f9 facciano paura i disabili: loro si aspettano non un\u2019etichetta di indesiderati ma un maggior impegno dalla societ\u00e0 dei &#8220;sani&#8221;.<\/p>\n<p style=\"text-align: justify;\">(A.C. Valdera)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avvenire inserto E\u2019 Vita, 14 giugno 2007 Nel 1960 il 90% dei bambini di peso inferiore al chilo moriva. Fortuna che nessuno ha pensato di etichettare la cura di questi piccolissimi come &#8220;accanimento terapeutico&#8221;, altrimenti non saremmo arrivati al risultato di oggi: il 90% dei bambini sotto il chilo di peso sopravvive. di Carlo Bellieni<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/neonati-poche-settimane-tanto-diritto-di-vivere\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":34700,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[1246],"class_list":["post-2770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bioetica","tag-cure-neonatali","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neonati: poche settimane, tanto diritto di vivere - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/neonati-poche-settimane-tanto-diritto-di-vivere\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neonati: poche settimane, tanto diritto di vivere - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/neonati-poche-settimane-tanto-diritto-di-vivere\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-03-09T08:57:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-14T12:12:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/prematuro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/neonati-poche-settimane-tanto-diritto-di-vivere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/neonati-poche-settimane-tanto-diritto-di-vivere\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Neonati: poche settimane, tanto diritto di vivere\",\"datePublished\":\"2009-03-09T08:57:16+00:00\",\"dateModified\":\"2016-06-14T12:12:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/neonati-poche-settimane-tanto-diritto-di-vivere\\\/\"},\"wordCount\":1125,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/neonati-poche-settimane-tanto-diritto-di-vivere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/prematuro.jpg\",\"keywords\":[\"cure neonatali\"],\"articleSection\":[\"Bioetica\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/neonati-poche-settimane-tanto-diritto-di-vivere\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/neonati-poche-settimane-tanto-diritto-di-vivere\\\/\",\"name\":\"Neonati: poche settimane, tanto diritto di vivere - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/neonati-poche-settimane-tanto-diritto-di-vivere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/neonati-poche-settimane-tanto-diritto-di-vivere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/prematuro.jpg\",\"datePublished\":\"2009-03-09T08:57:16+00:00\",\"dateModified\":\"2016-06-14T12:12:55+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/neonati-poche-settimane-tanto-diritto-di-vivere\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/neonati-poche-settimane-tanto-diritto-di-vivere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/neonati-poche-settimane-tanto-diritto-di-vivere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/prematuro.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/prematuro.jpg\",\"width\":275,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/neonati-poche-settimane-tanto-diritto-di-vivere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neonati: poche settimane, tanto diritto di vivere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neonati: poche settimane, tanto diritto di vivere - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/neonati-poche-settimane-tanto-diritto-di-vivere\/","og_locale":"it_IT","og_type":"article","og_title":"Neonati: poche settimane, tanto diritto di vivere - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/neonati-poche-settimane-tanto-diritto-di-vivere\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-03-09T08:57:16+00:00","article_modified_time":"2016-06-14T12:12:55+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/prematuro.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/neonati-poche-settimane-tanto-diritto-di-vivere\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/neonati-poche-settimane-tanto-diritto-di-vivere\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Neonati: poche settimane, tanto diritto di vivere","datePublished":"2009-03-09T08:57:16+00:00","dateModified":"2016-06-14T12:12:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/neonati-poche-settimane-tanto-diritto-di-vivere\/"},"wordCount":1125,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/neonati-poche-settimane-tanto-diritto-di-vivere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/prematuro.jpg","keywords":["cure neonatali"],"articleSection":["Bioetica"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/neonati-poche-settimane-tanto-diritto-di-vivere\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/neonati-poche-settimane-tanto-diritto-di-vivere\/","name":"Neonati: poche settimane, tanto diritto di vivere - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/neonati-poche-settimane-tanto-diritto-di-vivere\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/neonati-poche-settimane-tanto-diritto-di-vivere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/prematuro.jpg","datePublished":"2009-03-09T08:57:16+00:00","dateModified":"2016-06-14T12:12:55+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/neonati-poche-settimane-tanto-diritto-di-vivere\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/neonati-poche-settimane-tanto-diritto-di-vivere\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/neonati-poche-settimane-tanto-diritto-di-vivere\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/prematuro.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/prematuro.jpg","width":275,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/neonati-poche-settimane-tanto-diritto-di-vivere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Neonati: poche settimane, tanto diritto di vivere"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2770"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2770\/revisions"}],"predecessor-version":[{"id":34701,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2770\/revisions\/34701"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/34700"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}