{"id":2736,"date":"2009-03-05T16:03:22","date_gmt":"2009-03-05T15:03:22","guid":{"rendered":""},"modified":"2015-01-29T12:13:58","modified_gmt":"2015-01-29T11:13:58","slug":"stanno-spezzando-lanima-del-tibet","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/stanno-spezzando-lanima-del-tibet\/","title":{"rendered":"Stanno spezzando l&#8217;anima del Tibet"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/oppression_Tibet.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-18013\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/oppression_Tibet.jpg\" alt=\"oppression_Tibet\" width=\"250\" height=\"163\" \/><\/a>Mondo e Missione<\/strong>, n.5 maggio 2008<\/div>\n<p style=\"text-align: justify;\"><em>Parla Pietro Verni, presidente dell\u2019Associazione Italia-Tibet: \u00abLa tradizione tibetana \u00e8 a rischio estinzione. Un genocidio culturale pianificato da Pechino e che parte da lontano\u00bb. Parola di un esperto<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Paolo M. Alfieri<\/strong><\/p>\n<p style=\"text-align: center;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">\u00abSe per genocidio culturale intendiamo un preciso tentativo continuato nel tempo di proibire a una cultura di esprimersi liberamente nel suo complesso, allora sicuramente in Tibet siamo di fronte a un fenomeno di questo tipo per mano della Cina\u00bb.<\/p>\n<p style=\"text-align: justify;\">A parlare \u00e8 Pietro Verni, tra i pi\u00f9 profondi conoscitori della realt\u00e0 tibetana. Presidente dell\u2019associazione Italia-Tibet, da oltre vent\u2019anni compie viaggi di studio e ricerca in India, Tibet e nella regione himalayana ed \u00e8 l\u2019unico autore italiano ad aver scritto una biografia autorizzata del Dalai Lama.<\/p>\n<p style=\"text-align: justify;\">Proprio il Dalai Lama ha parlato di \u00abgenocidio culturale\u00bb ai danni del Tibet, alimentando un acceso dibattito. \u00abA usare per primi tale definizione &#8211; spiega Verni &#8211; furono due documenti di una Commissione internazionale di giuristi editi tra il 1960 e il 1961, subito dopo la definitiva conquista del Tibet da parte della Repubblica popolare cinese.<\/p>\n<p style=\"text-align: justify;\">In tutti questi decenni c\u2019\u00e8 stato un tentativo, ahim\u00e8 riuscito, di un annichilimento della cultura tibetana, sia religiosa che laica. Anche negli ultimi anni, quando la situazione apparentemente sembrerebbe cambiata, con l\u2019apertura a una possibilit\u00e0 di espressione religiosa popolare, in realt\u00e0 ci troviamo davanti soltanto a specchietti per le allodole confezionati per i turisti. Purtroppo la vera tradizione culturale tibetana \u00e8 tuttora inibita\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Come si attua nel concreto questo genocidio?<\/strong><\/p>\n<p style=\"text-align: justify;\">Prendiamo il teatro tibetano, di tradizione completamente diversa dall\u2019opera cinese; ebbene, vi sono stati immessi tutta una serie di caratteri assolutamente sinocentrici. Quanto alla religione, basti pensare che anche le regole interne dei monasteri sono nelle mani dei dirigenti politici cinesi. Lo stesso numero dei monaci \u00e8 condizionato all\u2019approvazione del Partito e i monaci devono subire delle sessioni di indottrinamento patriottico nelle quali si chiede loro di denunciare pubblicamente le attivit\u00e0 \u00abcriminali\u00bb del Dalai Lama. L\u2019evolversi del buddhismo, cos\u00ec come \u00e8 stato nell\u2019ultimo millennio, \u00e8 assolutamente contestato. Sopravvivono solo frammenti dell\u2019antica cultura.<\/p>\n<p style=\"text-align: justify;\"><strong>Anche la lingua tibetana rischia di sparire\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\">Il tibetano \u00e8 ormai quasi solo un dialetto. Tutto avviene in cinese. Ricordo che le due lingue, cos\u00ec come le rispettive grafie, sono assolutamente inconciliabili. Basti pensare che il cinese \u00e8 una scrittura ideogrammatica mentre quella tibetana \u00e8 alfabetica, di derivazione sanscrita, e le lingue parlate sono reciprocamente incomprensibili, come lo svedese e l\u2019arabo. Il tibetano \u00e8 stato introdotto a scuola come seconda lingua solo di recente; fino alla met\u00e0 degli anni Ottanta era assolutamente proibito parlarlo e scriverlo nell\u2019ambito scolastico.<\/p>\n<p style=\"text-align: justify;\"><strong>Perch\u00e9 Pechino ha questa necessit\u00e0 di annientare la cultura oltre ad attuare la repressione politica?<\/strong><\/p>\n<p style=\"text-align: justify;\">I due elementi vanno di pari passo. I cinesi capiscono che per avere un controllo totale sulla popolazione tibetana non ci si pu\u00f2 affidare soltanto alla repressione politica. Si deve spezzare l\u2019anima, oltre che le gambe, di un popolo. Nel periodo rampante della rivoluzione culturale, i cinesi erano convinti di aver risolto tutti i loro problemi affidandosi alle violenze. Si risvegliarono invece negli anni Ottanta con un popolo tibetano compatto nel non riconoscere l\u2019occupazione e ancora legato alle proprie tradizioni. I cinesi capirono come la repressione da sola non sarebbe bastata. Hanno poi s\u00ec aperto il Tibet al turismo, ma cercando di snaturare la cultura locale lasciando visibili solo gli aspetti pi\u00f9 folcloristici. Un po\u2019 come se in Italia fosse consentito lo svolgimento di qualche processione religiosa, ma al clero non fosse consentita una vera preparazione al mistero cristiano.<\/p>\n<p style=\"text-align: justify;\"><strong>Gli incentivi di Pechino al trasferimento dei cittadini cinesi in Tibet rispondono a questa esigenza di annientamento?<\/strong><\/p>\n<p style=\"text-align: justify;\">Esistono facilitazioni per i \u00abcoloni\u00bb, sia riguardo\u00a0 alle deroghe sulla politica del figlio unico che ad incentivi economici. Di solito i coloni cinesi non si trasferiscono in Tibet per mettere radici: la loro permanenza media \u00e8 di sette anni. A nessun cinese piace vivere a quattromila metri e il Tibet \u00e8 considerato solo una periferia dell\u2019impero: vorrebbero tutti emigrare a Shangai, a Canton, a Pechino. Se vanno in Tibet \u00e8 solo perch\u00e9 sperano di arricchirsi. Un po\u2019 come succedeva al colonialismo europeo pi\u00f9 straccione, tipo quello italiano.<\/p>\n<p style=\"text-align: justify;\"><strong>Molti coloni sono stati recentemente oggetto di intimidazioni da parte di gruppi tibetani. Perch\u00e9?<\/strong><\/p>\n<p style=\"text-align: justify;\">I cinesi a cui sono stati bruciati i negozi non sono poveracci, ma persone, spesso razziste, che si recano in Tibet con il compito di sfruttare ed emarginare i tibetani, assumendo tutti i posti di responsabilit\u00e0 nella societ\u00e0. Cos\u00ec vengono visti dai tibetani come diretti responsabili della loro marginalizzazione. Anche gli oggetti venduti ai turisti sono tutti di fabbricazione cinese e venduti su bancarelle cinesi.<\/p>\n<p style=\"text-align: justify;\"><strong>La Cina tende anche a modificare la storia, sostenendo di aver \u00abliberato\u00bb il Tibet&#8230;<\/strong><\/p>\n<p style=\"text-align: justify;\">I cinesi sono entrati in Tibet il 6 ottobre 1950 sfondando sette punti di frontiera e vincendo contro un esercito che rispondeva a un governo. Non esiste alcuna \u00abpacifica liberazione del Tibet\u00bb. \u00c8 un po\u2019 difficile liberare qualcuno che non voleva essere \u00abliberato\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Quali sono le caratteristiche principali della cultura tibetana?<\/strong><\/p>\n<p style=\"text-align: justify;\">Sicuramente l\u2019esperienza del sacro. Il Tibet \u00e8 stato il cuore pi\u00f9 compiutamente e sentitamente spirituale dell\u2019Asia. La koin\u00e8 culturale tibetana \u00e8 imperniata sull\u2019esperienza del sacro e della religiosit\u00e0, che si declinava peraltro in modi molto differenti, dalla superstizione della religiosit\u00e0 popolare alle vette del pensiero metafisico dei grandi pensatori buddhisti. Da questo punto di vista il Tibet tradizionale ha delle analogie con l\u2019Italia pre-moderna.<\/p>\n<p style=\"text-align: justify;\"><strong>\u00c8 un sacro che si riflette anche nell\u2019arte?<\/strong><\/p>\n<p style=\"text-align: justify;\">Assolutamente s\u00ec; non esiste un\u2019arte laica tibetana, tutta l\u2019arte \u00e8 di matrice religiosa. L\u2019espressione artistica laica si \u00e8 manifestata in Tibet esclusivamente nel teatro, mentre pittura, architettura, scultura sono tutte arti che prevedevano la raffigurazione dell\u2019elemento religioso.<\/p>\n<p style=\"text-align: justify;\"><strong>I turisti cosa vedono realmente della cultura tibetana?<\/strong><\/p>\n<p style=\"text-align: justify;\">Molto poco. Intanto vedono un Tibet sfregiato dal modernismo architettonico. Lhasa \u00e8 una citt\u00e0 devastata: tutte le tracce dell\u2019architettura tibetana, anche povera, sono state spazzate via da una serie di volgari palazzoni, edifici senza anima. Tutta la zona di Shol, che era l\u2019antico quartiere tibetano ai piedi del Potala (l\u2019enorme meraviglia dell\u2019Asia, residenza storica dei Dalai Lama), non c\u2019\u00e8 pi\u00f9. Povert\u00e0 architettonica e arroganza edilizia si mescolano per dare vita a risultati dall\u2019incubo. Ai piedi del Potala i cinesi hanno anche piazzato un Mig russo; proviamo a pensare se fosse accaduta una cosa simile davanti a san Pietro\u2026<\/p>\n<p style=\"text-align: justify;\"><strong>Perch\u00e9 il Dalai Lama parla di \u00abgenocidio culturale\u00bb, ma non chiede il boicottaggio olimpico?<\/strong><\/p>\n<p style=\"text-align: justify;\">Temo che il Dalai Lama, persona dal punto di vista personale e morale di grandissima levatura, sia incappato in un grosso errore di prospettiva politica da cui ha difficolt\u00e0 a uscire. Ha sperato che una politica di incredibili concessioni unilaterali da parte sua, come la rinuncia a chiedere l\u2019indipendenza, potesse smuovere la \u00abpietas\u00bb di Pechino. Questa politica, inaugurata il 17 giugno del 1988 con la \u00abproposta di Strasburgo\u00bb, non ha portato risultati.<\/p>\n<p style=\"text-align: justify;\">C\u2019\u00e8 stata una breve stagione, tra il 2002 e il 2007, in cui due inviati del Dalai Lama avevano colloqui con esponenti della gerarchia cinese, ma Pechino ha poi troncato l\u2019iniziativa, sostenendo che \u00abnon esiste un problema tibetano di cui discutere\u00bb. Forse le recenti violenze hanno mandato il messaggio a Pechino che un problema tibetano esiste. Pechino rischia che il percorso della Torcia olimpica si riveli, perdonatemi il paragone, una sorta di Via Crucis. Temo, per\u00f2, che la Cina non abbia intenzione di cambiare la sua politica di chiusura.<\/p>\n<p style=\"text-align: justify;\"><strong>Si pu\u00f2 parlare anche di genocidio vero e proprio?<\/strong><\/p>\n<p style=\"text-align: justify;\">Direi di s\u00ec, visto che le ong internazionali sostengono che per effetto, diretto e indiretto, dell\u2019occupazione cinese dal 1950 a oggi sono morti pi\u00f9 di un milione di tibetani. Una cifra impressionante, che per\u00f2 \u00abdisturba\u00bb coloro che fanno affari con Pechino. Cos\u00ec come disturbano altre realt\u00e0 \u00abscomode\u00bb, dalla repressione degli uiguri nello Xinjiang a quella dei cattolici e dei praticanti del Falun Gong.<\/p>\n<p style=\"text-align: justify;\"><strong>Sua moglie \u00e8 tibetana; che cosa pensa di quello che accade?<\/strong><\/p>\n<p style=\"text-align: justify;\">Mia moglie \u00e8 una \u00abtibetana in collera\u00bb, come direbbero i cinesi. Si ritiene vittima di una terrificante ingiustizia. Ancora oggi ha gli occhi che le si riempiono di lacrime quando pensa alla \u00abvergogna\u00bb di non aver potuto celebrare le cerimonie religiose funerarie di sua madre in Tibet. Probabilmente anche il padre subir\u00e0 l\u2019\u00abonta\u00bb di non poter morire nella sua terra di origine. Mia moglie ritiene che i tibetani abbiano il diritto di vivere da uomini e donne libere nel loro Paese. I tibetani non rinunceranno mai, Dalai Lama o meno, a ritenere fondamentale la richiesta di indipendenza per il Tibet. Fosse anche solo un sogno, \u00e8 quello che i tibetani continuano a trasmettere alle nuove generazioni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mondo e Missione, n.5 maggio 2008 Parla Pietro Verni, presidente dell\u2019Associazione Italia-Tibet: \u00abLa tradizione tibetana \u00e8 a rischio estinzione. Un genocidio culturale pianificato da Pechino e che parte da lontano\u00bb. Parola di un esperto di Paolo M. Alfieri<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/stanno-spezzando-lanima-del-tibet\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":18013,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,32,108],"tags":[1534],"class_list":["post-2736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cina","category-filosofia-del-comunismo","category-paesi-e-continenti","tag-tibet","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stanno spezzando l&#039;anima del Tibet - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/stanno-spezzando-lanima-del-tibet\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stanno spezzando l&#039;anima del Tibet - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/stanno-spezzando-lanima-del-tibet\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-03-05T15:03:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-01-29T11:13:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/oppression_Tibet.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"278\" \/>\n\t<meta property=\"og:image:height\" content=\"181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/stanno-spezzando-lanima-del-tibet\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/stanno-spezzando-lanima-del-tibet\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Stanno spezzando l&#8217;anima del Tibet\",\"datePublished\":\"2009-03-05T15:03:22+00:00\",\"dateModified\":\"2015-01-29T11:13:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/stanno-spezzando-lanima-del-tibet\\\/\"},\"wordCount\":1425,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/stanno-spezzando-lanima-del-tibet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/oppression_Tibet.jpg\",\"keywords\":[\"Tibet\"],\"articleSection\":[\"Cina\",\"Comunismo\",\"Paesi e continenti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/stanno-spezzando-lanima-del-tibet\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/stanno-spezzando-lanima-del-tibet\\\/\",\"name\":\"Stanno spezzando l'anima del Tibet - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/stanno-spezzando-lanima-del-tibet\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/stanno-spezzando-lanima-del-tibet\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/oppression_Tibet.jpg\",\"datePublished\":\"2009-03-05T15:03:22+00:00\",\"dateModified\":\"2015-01-29T11:13:58+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/stanno-spezzando-lanima-del-tibet\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/stanno-spezzando-lanima-del-tibet\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/stanno-spezzando-lanima-del-tibet\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/oppression_Tibet.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/oppression_Tibet.jpg\",\"width\":278,\"height\":181},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/stanno-spezzando-lanima-del-tibet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stanno spezzando l&#8217;anima del Tibet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stanno spezzando l'anima del Tibet - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/stanno-spezzando-lanima-del-tibet\/","og_locale":"it_IT","og_type":"article","og_title":"Stanno spezzando l'anima del Tibet - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/stanno-spezzando-lanima-del-tibet\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-03-05T15:03:22+00:00","article_modified_time":"2015-01-29T11:13:58+00:00","og_image":[{"width":278,"height":181,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/oppression_Tibet.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/stanno-spezzando-lanima-del-tibet\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/stanno-spezzando-lanima-del-tibet\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Stanno spezzando l&#8217;anima del Tibet","datePublished":"2009-03-05T15:03:22+00:00","dateModified":"2015-01-29T11:13:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/stanno-spezzando-lanima-del-tibet\/"},"wordCount":1425,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/stanno-spezzando-lanima-del-tibet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/oppression_Tibet.jpg","keywords":["Tibet"],"articleSection":["Cina","Comunismo","Paesi e continenti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/stanno-spezzando-lanima-del-tibet\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/stanno-spezzando-lanima-del-tibet\/","name":"Stanno spezzando l'anima del Tibet - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/stanno-spezzando-lanima-del-tibet\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/stanno-spezzando-lanima-del-tibet\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/oppression_Tibet.jpg","datePublished":"2009-03-05T15:03:22+00:00","dateModified":"2015-01-29T11:13:58+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/stanno-spezzando-lanima-del-tibet\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/stanno-spezzando-lanima-del-tibet\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/stanno-spezzando-lanima-del-tibet\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/oppression_Tibet.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/oppression_Tibet.jpg","width":278,"height":181},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/stanno-spezzando-lanima-del-tibet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Stanno spezzando l&#8217;anima del Tibet"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2736"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2736\/revisions"}],"predecessor-version":[{"id":18014,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2736\/revisions\/18014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/18013"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}