{"id":2727,"date":"2009-03-04T13:12:39","date_gmt":"2009-03-04T12:12:39","guid":{"rendered":""},"modified":"2016-02-04T10:02:40","modified_gmt":"2016-02-04T09:02:40","slug":"la-nuova-cristianit-perduta-di-pietro-scoppola","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nuova-cristianit-perduta-di-pietro-scoppola\/","title":{"rendered":"La nuova cristianit&agrave; perduta di Pietro Scoppola"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/Scoppola-_cover.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-30216\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/Scoppola-_cover.jpg\" alt=\"Scoppola _cover\" width=\"151\" height=\"200\" \/><\/a>Il Tempo,<\/strong> 23 luglio 1985<\/div>\n<p style=\"text-align: center;\"><em>&#8220;Religione civile&#8221; e secolarizzazione.<br \/>\n<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Augusto Del Noce<\/strong><\/p>\n<p style=\"text-align: justify;\">Il recente libro di Pietro Scoppola <em>La &#8220;nuova cristianit\u00e0&#8221; perduta<\/em> (Ed Studium, Roma) ha il merito di affrontare senza reticenze quello che \u00e8 il paradosso pi\u00f9 singolare e pi\u00f9 visibile dei decenni del dopoguerra italiano: un partito &#8220;cristiano&#8221; sorto non soltanto nell\u2019esigenza di tutelare i legittimi diritti dei cattolici, ma nella speranza (o, almeno, accompagnato nelle sue origini dalla speranza) di fondare una &#8220;nuova cristianit\u00e0&#8221;, detiene da quarant\u2019anni la funzione di guida prevalente nella politica italiana: pure, in questo periodo \u00e8 avvenuto il massimo processo di cristianizzazione che mai si era dato nella storia del nostro paese.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">E, notiamo, di cristianizzazione non violenta, in nessun modo imposta: si \u00e8 diffuso, per cos\u00ec dire spontaneamente, il giudizio secondo cui il cattolicesimo, come dogmi e come morale,appartenga a un passato che deve essere studiato senza remore e senza odio ma che perci\u00f2 stesso non possa essere riconosciuto, per ragione della mutata situazione storica, come guida nelle scelte effettive; e, questa \u00e8 una mia aggiunta, non manca chi, laico, considera positivamente la DC come garante di un passaggio indolore da una societ\u00e0 ancora religiosa a una societ\u00e0 secolarizzata. Altro merito di questo libro \u00e8 di svolgere un discorso coerente e rigoroso, senza alcun infingimento, cos\u00ec da servire da stimolo anche a chi, come chi scrive, abbia idee alquanto differenti.<\/p>\n<p style=\"text-align: justify;\"><strong>Due frasi<\/strong><\/p>\n<p style=\"text-align: justify;\">Porter\u00f2 l\u2019attenzione su due passi che mi sembra rendano appieno il significato del libro. (Quale si \u00e8 svolta in Italia) \u00abla secolarizzazione \u00e8 certo una sconfitta per la Chiesa, o almeno una durissima prova; ma non \u00e8, in nessun modo, una vittoria della cultura laica: in realt\u00e0 nessuna cultura ha vinto; tutte si sono disgregate nell\u2019impatto con la societ\u00e0 di massa di tipo consumistico\u00bb (p. 145), (ai cristiani spetta ora il compito di promuovere) \u00abuna relativa deconfessionalizzazione della presenza cristiana, la capacit\u00e0 di offrire tipi di comportamento universalmente validi, una &#8220;religione civile&#8221; della responsabilit\u00e0 e della solidariet\u00e0, quei valori appunto di cui la democrazia si alimenta e senza i quali \u00e8 destinata a scadere in puro compromesso di interessi\u00bb (p. 194).<\/p>\n<p style=\"text-align: justify;\">Sembrerebbe dalla prima che la presente situazione morale italiana, caratterizzata dalla secolarizzazione che si \u00e8 detta, non sia spiegabile attraverso fattori<em> ideali.<\/em> L\u2019attacco alle tradizioni e ai valori cattolici \u00e8 giunto alle spalle, del tutto imprevisto, legato al processo tecnico, economico e sociale.<\/p>\n<p style=\"text-align: justify;\">L\u2019avversario nuovo \u00e8 stato ed \u00e8 il &#8220;consumismo&#8221;, mentre i cattolici continuavano e continuano a combattere gli avversari di ieri, il comunismo \u00abintrinsecamente perverso\u00bb della <em>Divini Redemptoris<\/em> e il laicismo. Continuano, nella maggioranza, e altres\u00ec in formazioni che si presentano come nuove, a non accorgersi che questo anniversario nuovo e affatto imprevisto, colpiva, insieme, la Chiesa e i tradizionali avversari: fermava il comunismo, cos\u00ec da costringerlo a metter da parte i suoi aspetti messianici, e mediava il passaggio a una borghesia di tipo nuovo, che pi\u00f9 nulla conserva di quei valori morali che avevano presieduto al nascere dello spirito borghese laico e ne avevano accompagnato lo sviluppo.<\/p>\n<p style=\"text-align: justify;\">Dalla seconda, la rinuncia al miraggio di una &#8220;nuova cristianit\u00e0&#8221; veruna religione civile che, certamente, non esclude la &#8220;religione ecclesiastica&#8221; ma che pu\u00f2 venire condivisa da tutti i democratici.<\/p>\n<p style=\"text-align: justify;\">Non sono affatto d\u2019accordo: per me la priorit\u00e0 deve esser data alla causalit\u00e0 ideale, e anzi se c\u2019\u00e8 un periodo storico in cui tale priorit\u00e0 si manifesta, \u00e8 proprio questo. Comincer\u00f2 con una tesi che penso trovi Scoppola consenziente: la cristianizzazione presente non \u00e8 che una aspetto di un fenomeno pi\u00f9 generale: la caduta, particolarmente sensibili negli anni dal \u201960 a oggi, e particolarmente accentuata dolo il \u201870 e dopo la completamente fallita contestazione, della <em>religiosit\u00e0 della vita politica<\/em>.<\/p>\n<p style=\"text-align: justify;\">Per i comunisti del passato, secondo la frase del giovane Gramsci &#8211; che su questo punto non faceva che esprimere una tesi corrente nel socialismo rivoluzionario &#8211; \u00abil socialismo \u00e8 la religione che deve ammazzare il cristianesimo\u00bb, costretto dalla storia a &#8220;suicidarsi&#8221; davanti al suo avversario; ossia come gli dei pagani erano scomparsi senza lasciar traccia davanti al Dio unico del cristianesimo, cos\u00ec tale Dio sarebbe scomparso davanti all\u2019Uomo Nuovo comunista.<\/p>\n<p style=\"text-align: justify;\">I laici degli anni Trenta parlavano con Croce della \u00abreligione della libert\u00e0\u00bb che si era affievolita nella stessa et\u00e0 liberale e che ora era da riprendere e da restaurare. Per i cattolici di quel tempo si trattava di &#8220;restaurare&#8221; (nel significato che d\u00e0 oggi a questo termine il cardinale Ratzinger) la cristianit\u00e0; \u00e8 certo che i progetti erano diversi, e padre Gemelli e Maritain non pensavano allo stesso modo: entrambi per\u00f2, e menziono quelli che forse sono i due estremi, perseguivano questo ideale, e non erano davvero isolati.<\/p>\n<p style=\"text-align: justify;\">Religioni diverse, immanentistiche le une, trascendente la cattolica. Tuttavia, sempre religioni. Lo stadio presente della secolarizzazione \u00e8 caratterizzato dal venir meno di questa inscindibilit\u00e0 di religione e di politica; molti anni fa avevo parlato di due periodi dell\u2019<em>epoca della secolarizzazione<\/em>, quello sacrale che si era manifestato nel ventennio tra le due guerre attraverso le religioni secolari del comunismo, del fascismo e del nazismo e delle loro antitesi sull\u2019ideale della &#8220;nuova cristianit\u00e0&#8221;, e quello profano che trovava espressione in quella che allora si era soliti chiamare la &#8220;societ\u00e0 opulenta&#8221;.<\/p>\n<p style=\"text-align: justify;\">Ora, questo, pi\u00f9 che passaggio, rovesciamento non \u00e8 avvenuto in nome di una nuova idea. I &#8220;valori forti&#8221; della tradizione sono tramontati, o almeno hanno subito una eclissi, ma non sono stati sostituiti. Di qui lo strano nichilismo di oggi, che in realt\u00e0 \u00e8 accettazione della realt\u00e0 esistente: secolarizzazione e nichilismo sono le due facce della stessa medaglia.<\/p>\n<p style=\"text-align: justify;\">Certo, il fatto che tale rovesciamento non sia avvenuto in nome di un nuovo &#8220;valore forte&#8221; pi\u00f9 inclinare a spiegarlo con un impatto della societ\u00e0 dei consumi che mette in crisi tutte le culture. A ben riflettere ci si accorge per\u00f2 che non \u00e8 cos\u00ec. primo fattore di questa crisi di valori \u00e8 stata la crisi della cultura marxista, che si \u00e8 arrestata &#8211; e non poteva non arrestarsi &#8211; a una &#8220;rivoluzione a met\u00e0&#8221;. Possiamo certo dire che non \u00e8 riuscita a sostituire i suoi valori agli antichi; ma a produrre &#8220;il vuoto dei valori&#8221; si.<\/p>\n<p style=\"text-align: justify;\">Consideriamo infatti la sua polemica contro i valori &#8220;assoluti ed eterni&#8221; visti come strumenti di conservazione e, conseguentemente, contro il pensiero &#8220;metafisico&#8221;; contro quanto di metafisico restava nel laicismo (per l\u2019Italia, nell\u2019idealismo e particolarmente nella filosofia di Croce); contro la morale kantiana. La <em>pars destruens<\/em> del marxismo \u00e8 riuscita, scissa dalla <em>costruens.<\/em> Ma in questa scissione ha assunto un carattere diverso da quello che presentava nel marxismo, e appunto ha dato origine al nichilismo.<\/p>\n<p style=\"text-align: justify;\">Accogliere la <em>pars destruens<\/em> non si poteva se non &#8220;combinandola&#8221; come \u00e8 avvenuto, con elementi nietzcheani e freudiani; dando luogo a quella che pomposamente viene della &#8220;scuola del sospetto&#8221; e che si risolve nell\u2019esercizio di smascherare la volont\u00e0 di potere che sottenderebbe ogni affermazione di carattere assoluto, sancendo il relativismo, e che in realt\u00e0 \u00e8 un\u2019amalgama-intruglio in cui va perduta quella parte di verit\u00e0 che pure si pu\u00f2 trovare in Marx, in Nietzche e in Freud.<\/p>\n<p style=\"text-align: justify;\">Passiamo a vedere quale contraccolpo le negazioni marxiste abbiano avuto nel laicismo. Si direbbe che esso ha ripercorso a rovescio la sua storia. dalla sua versione romantica all\u2019illuministica e poi alla libertina. Cio\u00e8 a quella &#8220;permissivistica&#8221;. tutto \u00e8 permesso, salvo l\u2019osservanza di certe regole necessarie alla coesistenza, accettate in ragione della loro utilit\u00e0. Se si guarda almeno alla cultura diffusa si \u00e8 portati alla conclusione solo apparentemente paradossale che l\u2019egemonia culturale tenuta una volta dal crocianesimo, poi dal gramscismo, \u00e8 oggi passata nelle mani d\u2019un pi\u00f9 o meno dissimulato libertinismo.<\/p>\n<p style=\"text-align: justify;\">La letteratura storico-filosofica sul pensiero libertino si \u00e8 notevolmente accresciuta negli ultimi anni, e basta una lettura cursoria, p. es. del libro dello Schneiber <em>Il libertino. Per una storia sociale della cultura borghese nel XVI e XVII secolo<\/em> (Ed. Il Mulino) per accorgersi di quanto le valutazioni di tipo libertino permeino i giudizi correnti; sostanzialmente immutate perch\u00e8il tipo di pensiero libertino \u00e8 una costante che si riproduce identica nei periodi di crisi: sua insegna \u00e8 quel \u00abtutto \u00e8 permesso\u00bb di cui ho gia detto. E basta entrare in una libreria per vedere quanta parte sia fatta agli autori della letteratura libertina, una volta pressoch\u00e9 proibita.<\/p>\n<p style=\"text-align: justify;\">Il contraccolpo \u00e8 stato forte &#8211; e gi\u00e0 lo si \u00e8 spesso avvertito &#8211; anche nel mondo cattolico, sotto la forma pi\u00f9 o meno larvata della sostituzione della morale della &#8220;legge&#8221; con una morale della &#8220;situazione&#8221;. Anche qui il pensiero &#8220;metafisico&#8221; \u00e8 stato considerato come &#8220;retrivo&#8221; e ci si \u00e8 troppo spesso orientati verso un fideismo: c\u2019\u00e8 la scienza che basta per organizzare la vita in questo mondo; e c\u2019\u00e8 la fede, che pu\u00f2 &#8220;vitalizzare&#8221; in quest\u2019azione di miglioramento del mondo. La mediazione metafisica viene meno. E qui mi si permetta di dire quel che evidentemente non posso ora dimostrare: senza mediazione metafisica la fede \u00e8 destinata ad estinguersi.<\/p>\n<p style=\"text-align: justify;\">Quel che comunque non si pu\u00f2 dire certo \u00e8 che le nuove e irrequiete teologie postconciliari hanno avuto a radice della loro novit\u00e0 la recezione della pars destruens del marxismo; e che l\u2019estensione della scristianizzazione si spiega soprattutto non per ragioni esterne ma interne allo stesso mondo cattolico.<\/p>\n<p style=\"text-align: justify;\"><strong>Conseguenze<\/strong><\/p>\n<p style=\"text-align: justify;\">Queste constatazioni portano a due conseguenze. la prima \u00e8 l\u2019equivoco che si annida nel termine &#8220;consumismo&#8221;. Vuol significare relativa abbondanza di beni materiali (del resto molto relativa per la gran parte degli italiani)? Si dovrebbe allora arrivare alla conclusione che la religione pu\u00f2 prosperare soltanto dove c\u2019\u00e8 miseria, e dove la Chiesa pu\u00f2 cercare di alleviarla con le sue opere di carit\u00e0. A una strana conclusione fuerbachiana sulla correlazione fra miseria temporale e religione! Meglio usare il termine &#8220;permissivismo&#8221; che designa una disposizione morale piuttosto che un fatto economico.<\/p>\n<p style=\"text-align: justify;\">La seconda, assai pi\u00f9 importante, \u00e8 la seguente: non \u00e8 stato il consumismo a corrodere le culture, cos\u00ec che oggi piuttosto che proseguire nelle vecchie polemiche, esse dovrebbero pensare a promuovere una &#8220;religione civile&#8221;; al contrario \u00e8 stata <em>la caduta della religione civile a rendere possibile l\u2019invasione permissivistica.<\/em><\/p>\n<p style=\"text-align: justify;\">Qual \u00e8 infatti il presupposto di questa religione civile, se non l\u2019esistenza di un &#8220;comune mondo morale&#8221; rispetto al quale sia universale il consenso, al di l\u00e0 delle diversit\u00e0 di confessioni religiose? Si pu\u00f2 dire che questa idea abbia percorso in varie forme i secoli dell\u2019et\u00e0 moderna e abbia trovato una certa realt\u00e0 nella seconda met\u00e0 dell\u2019Ottocento e nei primi decenni del nostro secolo. Si pu\u00f2 aggiungere forse che ha trovato la sua epigrafe nel celebre scritto di Croce <em>Perch\u00e9 non possiamo non dirci cristiani<\/em>. Ma oggi \u00e8 irrimediabilmente caduta. Il fatto che pi\u00f9 colpisce \u00e8 la presenza di una pluralit\u00e0 di morali del tutto inconciliabili: segno che le morali sono inscindibili dalle concezioni metafisiche e religiose.<\/p>\n<p style=\"text-align: justify;\">Di pi\u00f9, oltre all\u2019irrealizzabilit\u00e0, mi sembra pericolosa anche come proposta. Si tratterebbe infatti di un fondamento della democrazia come orizzonte entro cui si muoverebbero i vari partiti, concordi nell\u2019accettarla, parzialmente divisi rispetto ai mezzi e alle tecniche attraverso cui pu\u00f2 venir realizzata. Ma \u00e8 lontano il passo da questa concordia su certi valori comuni a quello di una &#8220;democrazia consociativa&#8221;?<\/p>\n<p style=\"text-align: justify;\">E\u2019 da osservare come questa idea sia del tutto diversa dall\u2019 &#8220;inculturazione&#8221; di cui parla Giovanni Paolo II; per la quale \u00e8 la religione cattolica, nel suo senso pieno, che deve permeare la politica dei cattolici. Certo la formazione politica a cui l\u2019inculturazione pu\u00f2 dar luogo deve venire, di fatto, a compromessi e concessioni; ma nel fatto stesso dell\u2019affermazione di principi e di ideali che vanno oltre i programmi, si presenta come inizio di una societ\u00e0 cristiana: se si vuol dire cos\u00ec, di una &#8220;nuova cristianit\u00e0&#8221;.<\/p>\n<p style=\"text-align: justify;\">Il fatto che progetti di &#8220;nuova cristianit\u00e0&#8221; siano andati falliti non toglie che altri non possano presentarsi; o che l\u2019idea della &#8220;nuova cristianit\u00e0&#8221; non debba restare principio ispirativo. La &#8220;desacralizzazione&#8221; della politica a cui abbiamo assistito e che sarebbe la condizione dell\u2019abbandono da questo ideale, non \u00e8 un fatto neutro e non \u00e8 un progresso, suppone un processo ideale, di cui si sono delineati i tratti essenziali, e portato a una consapevolezza filosofica, deve riconoscersi nel nuovo nichilismo: non tollera di venir limitato da una &#8220;religione civile&#8221;; \u00e8 l\u2019aspetto profano dell\u2019epoca della secolarizzazione.<\/p>\n<p style=\"text-align: center;\"><strong>* * *<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>Un\u2019intervista radiofonica \u201cinedita\u201d allo storico Pietro Scoppola. La \u201cnuova cristianit\u00e0 perduta&#8221;. Con questo titolo nel 1985 veniva pubblicato dalle Edizioni Studium&#8230;<\/em><\/p>\n<p style=\"text-align: center;\"><strong>La \u201cnuova cristianit\u00e0\u201d perduta<\/strong><\/p>\n<p style=\"text-align: center;\"><strong><em>Pier Silverio Pozzi<\/em><\/strong><em><em>, Radio Rai, 15 aprile 1985<\/em><\/em><\/p>\n<p style=\"text-align: justify;\">La<em> \u201cnuova cristianit\u00e0\u201d perduta. <\/em>Con questo titolo nel 1985 veniva pubblicato dalle <em>Edizioni Studium <\/em>\u00e8 un piccolo volume di riflessioni di Pietro Scoppola <em>\u201ctese a mostrare come e quando la coscienza del passato spinga a guardare alla realt\u00e0 del nostro tempo con occhi nuovi, a cogliere con sensibilit\u00e0 accresciuta i nessi che esistono fra le diverse forme di vita associata, che uniscono la vita religiosa alla politica, non meno che all\u2019economia, per assumere responsabilit\u00e0 conseguenti. Ad un anno dalla morte di Pietro Scoppola, uno storico che ha lasciato il segno nella cultura italiana e di un maestro che ha formato le coscienze di pi\u00f9 di una generazione, pubblichiamo un\u2019intervista radiofonica all\u2019autore fatta allora da Pier Silverio Pozzi, \u00e8 andata in onda il 15 aprile 1985 nell\u2019ambito dei programmi della Rai per il Lazio.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Un libro, una provocazione<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Professor Scoppola, lei ha scritto nella premessa che questo suo libro vuole essere una provocazione. Credo che il titolo stesso La \u201cnuova cristianit\u00e0 perduta\u201d sia una provocazione. Lo vuole spiegare?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cLa provocazione \u00e8 in quella contrapposizione tra il \u00abnuova\u00bb e il \u00abperduta\u00bb, se \u00e8 nuova come mai \u00e8 gi\u00e0 perduta? L\u2019espressione \u00abnuova cristianit\u00e0\u201d era stata usata negli anni Trenta in uno scritto famoso <em>Umanesimo integrale<\/em> del filosofo francese Jacques Maritain e in questa espressione Maritain riassumeva il progetto di una nuova societ\u00e0, di un modello nuovo di societ\u00e0 distinto sia dal modello capitalistico, che allora appariva in crisi, e sia dal modello comunista che si presentava con il volto dello stalinismo, il volto disumano possiamo dire dello stalinismo.<\/p>\n<p style=\"text-align: justify;\">Questo modello di nuova cristianit\u00e0 ha mobilitato nel dopoguerra, dopo la caduta del fascismo, molte energie nell\u2019Europa e in particolare nell\u2019Italia che ha visto in questo un punto di riferimento importante, soprattutto per le nuove generazioni. Ebbene si sono mosse queste energie, si sono impegnate nell\u2019azione, hanno dato vita a un grande movimento sociale e politico che ha avuto grande successo, non dimentichiamo il 18 aprile del \u201948, ma da tutto questo che cosa \u00e8 nato? Non \u00e8 nata una nuova cristianit\u00e0, \u00e8 nata la societ\u00e0 secolarizzata del nostro tempo, la societ\u00e0 consumistica che \u00e8 altra cosa dalla nuova cristianit\u00e0 che Maritain aveva progettato. In questo senso \u00e8 perduta\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Analizzando i difficili rapporto tra vita religiosa, politica, sociale ed economica dei cristiani nel nostro paese, dal dopoguerra ad oggi lei sostiene che i cattolici impegnati nel politico hanno s\u00ec il merito di aver reso possibile lo sviluppo industriale, ma sono altres\u00ec corresponsabili dell\u2019affermarsi di questa societ\u00e0 consumistica causa prima del particolare processo di secolarizzazione in atto nel nostro paese.<\/strong><\/p>\n<p style=\"text-align: justify;\">&#8220;No, io per la verit\u00e0 non dico che sono corresponsabili, io dico che c\u2019\u00e8 una coincidenza tra periodo in cui i cattolici hanno avuto la massima responsabilit\u00e0 di governo e processo di sviluppo della societ\u00e0 consumistica con tutti gli effetti collaterali che sono, tra l\u2019altro, quello della secolarizzazione, della perdita di certi valori della tradizione cristiana. C\u2019\u00e8 una coincidenza ma non c\u2019\u00e8 un nesso di causalit\u00e0. Mi spiego meglio.<\/p>\n<p style=\"text-align: justify;\">La mobilitazione cattolica ha creato un consenso democratico cos\u00ec ampio, cos\u00ec diffuso nel nostro paese che ha reso possibile una fase di grande sviluppo industriale. Questo sviluppo, non lo dimentichiamo, \u00e8 quello cui dobbiamo la liberazione della miseria secolare nel nostro paese. Non possiamo dimenticarci che ancora nel dopoguerra nel nostro paese c\u2019erano sacche di miseria gravissime nel sud, in alcune zone del mondo contadino, di cui oggi si \u00e8 perso quasi il ricordo, ma che sono pure molto importanti per capire l\u2019opera, il ruolo che ha svolto questa mobilitazione dell\u2019energia del mondo cattolico.<\/p>\n<p style=\"text-align: justify;\">Ma insieme a questo sviluppo economico, a questa industrializzazione che ha prodotto questi effetti positivi e benefici nella vita sociale del paese, abbiamo avuto che cosa? La nascita della societ\u00e0 industriale con tutti i suoi meccanismi, per giunta c\u2019\u00e8 stata la coincidenza che io sottolineo tra sviluppo dell\u2019industria e diffusione dei mezzi di comunicazione di massa.<\/p>\n<p style=\"text-align: justify;\">Nel 1954 entra in funzione, all\u2019inizio dell\u2019anno, la televisione e questo fa da effetto moltiplicatore, accentua gli effetti dell\u2019industrializzazione, si crea una mentalit\u00e0 nuova, la mentalit\u00e0 della societ\u00e0 dei consumi, e come effetto di queste trasformazioni, di questo mutamento di mentalit\u00e0 abbiamo anche quei processi di secolarizzazione che incidono sulla cultura tradizionale del mondo contadino e mettono in crisi la vecchia tradizionale cristianit\u00e0 presente nel nostro paese, la societ\u00e0 cristiana del passato viene travolta da questi processi di sviluppo\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Perch\u00e9 siamo secolarizzati?<\/strong><\/p>\n<p style=\"text-align: justify;\">All\u2019origine di questa societ\u00e0 secolarizzata non c\u2019\u00e8 solo il consumismo, c\u2019\u00e8 il responsabile disimpegno degli uomini di cultura, di tutti, sia laici che cristiani. \u201cNon so se si possa parlare di disimpegno degli uomini di cultura, perch\u00e9 nella storia di questi 40 anni in realt\u00e0 gli uomini di cultura sono stati spesso protagonisti. Semmai gli uomini di cultura sono stati troppo incollati alle posizioni dei rispettivi gruppi politici, dei rispettivi partiti, non ci sono state le condizioni di un dialogo aperto nella cultura, tra le diverse culture, che rendesse possibile una presa di coscienza comune di quelli che erano gli elementi nuovi che si venivano manifestando nella realt\u00e0 italiana.<\/p>\n<p style=\"text-align: justify;\">Ciascuno si \u00e8 preoccupato di posizioni di parte pi\u00f9 che guardare con occhio critico, con attenzione vigile a quello che il paese stava diventando. Il compito della cultura avrebbe dovuto e dovrebbe essere questo: di muoversi, vorrei dire, un passo pi\u00f9 avanti rispetto agli uomini di azione che sono impegnati nella quotidianit\u00e0 della politica, un passo pi\u00f9 avanti quindi con una attenzione pi\u00f9 attenta a quello che sta accadendo nel profondo.<\/p>\n<p style=\"text-align: justify;\">Direi che nel complesso questa funzione critica, e diciamo pure un po\u2019 profetica, la cultura italiana non lo ha svolto, \u00e8 stata un cultura molto legata alle singole posizioni oppure talvolta &#8211; e questo \u00e8 vero, non posso non darle ragione &#8211; su posizioni di fuga, una cultura chiusa in se stessa che coltivava i suoi spazi senza una grande attenzione a questi fenomeni e alla responsabilit\u00e0 che questi fenomeni comportava\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>Ritorniamo a parlare della secolarizzazione. Lei professor Scoppola, parlando della societ\u00e0 secolarizzata, scrive che la cristianit\u00e0 \u00e8 davvero perduta come realt\u00e0 sociale, come mondo dei valori vissuto, come modo di vita di una comunit\u00e0 nel suo insieme. Ma allora \u00e8 valida l\u2019equazione secolarizzazione uguale cristianizzazione.\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cNon credo che si debba identificare secolarizzazione con scristianizzazione. Il concetto di secolarizzazione ha anche aspetti positivi che vanno sottolineati, e io ne faccio cenno nelle pagine del mio volume. Se intendiamo la secolarizzazione nel senso tradizionale, classico, come processo cio\u00e8 di differenziazione, di conquista di autonomia del sapere scientifico, di conquista di autonomia della politica, dell\u2019economia rispetto ad una visione di tipo sacrale quale \u00e8 quella che veniva dalla tradizione medievale, dalla tradizione dei secoli passati.<\/p>\n<p style=\"text-align: justify;\">Se intendiamo secolarizzazione come processo di distinzione, di conquista di autonomia all\u2019interno di un mondo di valori che rimane saldo e che rimane valido, tutto questo \u00e8 positivo, ma la secolarizzazione, io sostengo in questo mio volumetto, ha avuto in Italia un altro significato, un altro volto, non \u00e8 stata crescita e processo di differenziazione all\u2019interno di un mondo di valori, \u00e8 stata, per certi aspetti, uscita da questo mondo di valori, \u00e8 un salto, io dico, in un vuoto etico. In questo senso questo tipo di secolarizzazione ha portato a una scristianizzazione, ad una caduta dei valori tradizionali senza che siano nati in Italia forme di comportamenti etici alternativi\u201d.<\/p>\n<p style=\"text-align: justify;\"><strong>La cultura di fronte al vuoto<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Professore un\u2019ultima domanda. Di fronte a questo vuoto etico che cosa possono e debbono fare gli uomini di cultura?<\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cGli uomini di cultura devono uscire da questa logica delle appartenenze politiche, partitiche, devono essere i primi a sentire la responsabilit\u00e0 di un impegno comune, di un dialogo, per rifondare nel nostro paese questa base, questo tessuto etico che \u00e8 la condizione della stessa vita democratica.<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 possibile la democrazia come semplice compromesso di interessi, se la democrazia non \u00e8 sostenuta, animata da un tessuto di valori morali, da uno spirito religioso, nel senso pi\u00f9 ampio del termine. Nel nostro paese tutta la cultura deve collaborare a questa rinascita, a questo rinnovamento culturale. La sensazione un po\u2019 amara \u00e8 che oggi ci si continua a dividere e a combattere nelle vecchie trincee, sulle vecchie posizioni. Si continua a polemizzare sullo stato laico, come se ci fosse ancora lo stato laico degli anni di Gentile: quando lo stato esprimeva questi valori, aveva un suo disegno educativo. Ma oggi lo stato italiano \u00e8 il primo ad essere coinvolto nella crisi della quale stiamo discutendo.<\/p>\n<p style=\"text-align: justify;\">Non ha senso che noi ci contrapponiamo sul concetto dello stato laico, e viceversa avrebbe molto pi\u00f9 senso se si facesse uno sforzo comune per ridare forza, valore, credibilit\u00e0, ai valori della nostra costituzione, al dettato, ai grandi valori che sono scritti nella costituzione e che rischiano altrimenti di restare lettera morta e di non essere pi\u00f9 qualcosa di vivo che deve sostenere la vita associata in questo paese\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Tempo, 23 luglio 1985 &#8220;Religione civile&#8221; e secolarizzazione. di Augusto Del Noce Il recente libro di Pietro Scoppola La &#8220;nuova cristianit\u00e0&#8221; perduta (Ed Studium, Roma) ha il merito di affrontare senza reticenze quello che \u00e8 il paradosso pi\u00f9 singolare e pi\u00f9 visibile dei decenni del dopoguerra italiano: un partito &#8220;cristiano&#8221; sorto non soltanto nell\u2019esigenza &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nuova-cristianit-perduta-di-pietro-scoppola\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":30216,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66,106],"tags":[1539,568],"class_list":["post-2727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-adel-noce-scritti","category-cattolicesimo-democratico","tag-pietro-scoppola","tag-secolarizzazione","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La nuova cristianit&agrave; perduta di Pietro Scoppola - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nuova-cristianit-perduta-di-pietro-scoppola\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La nuova cristianit&agrave; perduta di Pietro Scoppola - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nuova-cristianit-perduta-di-pietro-scoppola\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-03-04T12:12:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-02-04T09:02:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/Scoppola-_cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"195\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nuova-cristianit-perduta-di-pietro-scoppola\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nuova-cristianit-perduta-di-pietro-scoppola\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La nuova cristianit&agrave; perduta di Pietro Scoppola\",\"datePublished\":\"2009-03-04T12:12:39+00:00\",\"dateModified\":\"2016-02-04T09:02:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nuova-cristianit-perduta-di-pietro-scoppola\\\/\"},\"wordCount\":3478,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nuova-cristianit-perduta-di-pietro-scoppola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/Scoppola-_cover.jpg\",\"keywords\":[\"Pietro Scoppola\",\"secolarizzazione\"],\"articleSection\":[\"A.Del Noce - scritti\",\"Cattolicesimo dem.\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nuova-cristianit-perduta-di-pietro-scoppola\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nuova-cristianit-perduta-di-pietro-scoppola\\\/\",\"name\":\"La nuova cristianit&agrave; perduta di Pietro Scoppola - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nuova-cristianit-perduta-di-pietro-scoppola\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nuova-cristianit-perduta-di-pietro-scoppola\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/Scoppola-_cover.jpg\",\"datePublished\":\"2009-03-04T12:12:39+00:00\",\"dateModified\":\"2016-02-04T09:02:40+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nuova-cristianit-perduta-di-pietro-scoppola\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nuova-cristianit-perduta-di-pietro-scoppola\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nuova-cristianit-perduta-di-pietro-scoppola\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/Scoppola-_cover.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/03\\\/Scoppola-_cover.jpg\",\"width\":195,\"height\":259},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-nuova-cristianit-perduta-di-pietro-scoppola\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La nuova cristianit&agrave; perduta di Pietro Scoppola\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La nuova cristianit&agrave; perduta di Pietro Scoppola - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nuova-cristianit-perduta-di-pietro-scoppola\/","og_locale":"it_IT","og_type":"article","og_title":"La nuova cristianit&agrave; perduta di Pietro Scoppola - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nuova-cristianit-perduta-di-pietro-scoppola\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-03-04T12:12:39+00:00","article_modified_time":"2016-02-04T09:02:40+00:00","og_image":[{"width":195,"height":259,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/Scoppola-_cover.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"17 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nuova-cristianit-perduta-di-pietro-scoppola\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nuova-cristianit-perduta-di-pietro-scoppola\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La nuova cristianit&agrave; perduta di Pietro Scoppola","datePublished":"2009-03-04T12:12:39+00:00","dateModified":"2016-02-04T09:02:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nuova-cristianit-perduta-di-pietro-scoppola\/"},"wordCount":3478,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nuova-cristianit-perduta-di-pietro-scoppola\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/Scoppola-_cover.jpg","keywords":["Pietro Scoppola","secolarizzazione"],"articleSection":["A.Del Noce - scritti","Cattolicesimo dem."],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nuova-cristianit-perduta-di-pietro-scoppola\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nuova-cristianit-perduta-di-pietro-scoppola\/","name":"La nuova cristianit&agrave; perduta di Pietro Scoppola - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nuova-cristianit-perduta-di-pietro-scoppola\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nuova-cristianit-perduta-di-pietro-scoppola\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/Scoppola-_cover.jpg","datePublished":"2009-03-04T12:12:39+00:00","dateModified":"2016-02-04T09:02:40+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nuova-cristianit-perduta-di-pietro-scoppola\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nuova-cristianit-perduta-di-pietro-scoppola\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nuova-cristianit-perduta-di-pietro-scoppola\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/Scoppola-_cover.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/03\/Scoppola-_cover.jpg","width":195,"height":259},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-nuova-cristianit-perduta-di-pietro-scoppola\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La nuova cristianit&agrave; perduta di Pietro Scoppola"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2727"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2727\/revisions"}],"predecessor-version":[{"id":30217,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2727\/revisions\/30217"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/30216"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}