{"id":26993,"date":"2015-10-15T00:00:55","date_gmt":"2015-10-14T22:00:55","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=26993"},"modified":"2019-04-09T10:21:19","modified_gmt":"2019-04-09T08:21:19","slug":"redemptionis-sacramentum","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/redemptionis-sacramentum\/","title":{"rendered":"Redemptionis sacramentum"},"content":{"rendered":"<p style=\"text-align: center;\">CONGREGAZIONE PER IL CULTO DIVINO E LA DISCIPLINA DEI SACRAMENTI<strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>ISTRUZIONE<\/strong><\/p>\n<p style=\"text-align: center;\"><strong><em>Redemptionis sacramentum<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><strong>su alcune cose che si devono osservare ed evitare <\/strong><\/p>\n<p style=\"text-align: center;\"><strong>circa la Santissima Eucaristia<\/strong><\/p>\n<p style=\"text-align: center;\">INDICE<\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/10\/S.Messa_.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-26994 size-full alignnone\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/10\/S.Messa_.jpg\" alt=\"S.Messa\" width=\"280\" height=\"180\" \/><\/a><\/p>\n<p style=\"text-align: center;\">_______________________<\/p>\n<p style=\"text-align: center;\"><!--more--><\/p>\n<p style=\"text-align: center;\"><strong>Proemio<\/strong> [1-13]<\/p>\n<p style=\"text-align: center;\"><strong>Capitolo I<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>La regolamentazione della sacra Liturgia <\/strong>[14-18]<\/p>\n<p style=\"text-align: center;\">1. Il Vescovo diocesano, grande Sacerdote del suo gregge [19-25]<\/p>\n<p style=\"text-align: center;\">2. Le Conferenze dei Vescovi [26-28]<\/p>\n<p style=\"text-align: center;\">3. I Sacerdoti [29-33]<\/p>\n<p style=\"text-align: center;\">4. I Diaconi [34-35]<\/p>\n<p style=\"text-align: center;\"><strong>Capitolo II<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>La partecipazione dei fedeli laici alla celebrazione dell\u2019Eucaristia<\/strong><\/p>\n<p style=\"text-align: center;\">1. Una partecipazione attiva e consapevole [36-42]<\/p>\n<p style=\"text-align: center;\">2. I compiti dei fedeli laici nella celebrazione della Messa [43-47]<\/p>\n<p style=\"text-align: center;\"><strong>Capitolo III<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>La retta celebrazione della santa Messa<\/strong><\/p>\n<p style=\"text-align: center;\">1. La materia della Santissima Eucaristia [48-50]<\/p>\n<p style=\"text-align: center;\">2. La Preghiera eucaristica [51-56]<\/p>\n<p style=\"text-align: center;\">3. Le altri parti della Messa [57-74]<\/p>\n<p style=\"text-align: center;\">4. L\u2019unione dei vari riti con la celebrazione della Messa [75-79]<\/p>\n<p style=\"text-align: center;\"><strong>Capitolo IV<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>La santa Comunione<\/strong><\/p>\n<p style=\"text-align: center;\">\u00a01. Disposizioni per ricevere la santa Comunione [80-87]<\/p>\n<p style=\"text-align: center;\">2. La distribuzione della santa Comunione [88-96]<\/p>\n<p style=\"text-align: center;\">3.La Comunione dei Sacerdoti [97-99]<\/p>\n<p style=\"text-align: center;\">4.La Comunione sotto le due specie [100-107]<\/p>\n<p style=\"text-align: center;\"><strong>Capitolo V<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Altri aspetti riguardanti l\u2019Eucaristia<\/strong><\/p>\n<p style=\"text-align: center;\">1. Il luogo della celebrazione della santa Messa [108-109]<\/p>\n<p style=\"text-align: center;\">2. Circostanze varie relative alla santa Messa [110-116]<\/p>\n<p style=\"text-align: center;\">3. I vasi sacri [117-120]<\/p>\n<p style=\"text-align: center;\">4. Le vesti liturgiche [121-128]<\/p>\n<p style=\"text-align: center;\"><strong>Capitolo VI<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>La conservazione della Santissima Eucaristia e il suo culto fuori della Messa<\/strong><\/p>\n<p style=\"text-align: center;\">1. La conservazione della Santissima Eucaristia [129-133]<\/p>\n<p style=\"text-align: center;\">2. Altre forme di culto della Santissima Eucaristia fuori della Messa [134-141]<\/p>\n<p style=\"text-align: center;\">3. Le processioni e i Congressi eucaristici [142-145]<\/p>\n<p style=\"text-align: center;\"><strong>Capitolo VII<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>I compiti straordinari dei fedeli laici <\/strong>[146-153]<\/p>\n<p style=\"text-align: center;\">1. Il ministro straordinario della santa Comunione [154-160]<\/p>\n<p style=\"text-align: center;\">2. La predicazione [161]<\/p>\n<p style=\"text-align: center;\">3. Le celebrazioni particolari che si svolgono in assenza del Sacerdote [162-167]<\/p>\n<p style=\"text-align: center;\">4. Coloro che sono stati dimessi dallo stato clericale [168]<\/p>\n<p style=\"text-align: center;\"><strong>Capitolo VIII<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>I rimedi<\/strong> [169-171]<\/p>\n<p style=\"text-align: center;\">1.\u00a0<em>Graviora delicta<\/em> [172]<\/p>\n<p style=\"text-align: center;\">2. Atti gravi [173]<\/p>\n<p style=\"text-align: center;\">3. Altri abusi [174-175]<\/p>\n<p style=\"text-align: center;\">4. Il Vescovo diocesano [176-180]<\/p>\n<p style=\"text-align: center;\">5. La Sede Apostolica [181-182]<\/p>\n<p style=\"text-align: center;\">6. Segnalazioni di abusi in materia liturgica [183-184]<strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Conclusione<\/strong>\u00a0 [185-186]<\/p>\n<p style=\"text-align: center;\">____________________________<strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>PROEMIO<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[1.]<\/strong> Nella Santissima Eucaristia la Madre Chiesa riconosce con ferma fede, accoglie con gioia, celebra e venera con atteggiamento adorante il sacramento della Redenzione, [1] annunciando la morte di Cristo Ges\u00f9, proclamando la sua resurrezione, nell\u2019attesa della sua venuta nella gloria, [2] come Signore e Dominatore invincibile, Sacerdote eterno e Re dell\u2019universo, per offrire alla maest\u00e0 infinita del Padre onnipotente il regno di verit\u00e0 e di vita\u00a0[3]<\/p>\n<p style=\"text-align: justify;\"><strong>[2.]<\/strong> La dottrina della Chiesa sulla Santissima Eucaristia, in cui \u00e8 contenuto l\u2019intero bene spirituale della Chiesa, ovvero Cristo stesso, nostra Pasqua,\u00a0[4] fonte e culmine [5] di tutta la vita cristiana, il cui influsso causale \u00e8 alle origini stesse della Chiesa,\u00a0[6] \u00e8 stata esposta con premurosa sollecitudine e grande autorevolezza nel corso dei secoli negli scritti dei Concili e dei Sommi Pontefici. Recentemente, inoltre, nella Lettera Enciclica \u00ab<em><a href=\"http:\/\/www.vatican.va\/holy_father\/special_features\/encyclicals\/documents\/hf_jp-ii_enc_20030417_ecclesia_eucharistia_it.html\" target=\"_blank\" rel=\"noopener noreferrer\">Ecclesia de Eucharistia<\/a><\/em>\u00bb il Sommo Pontefice Giovanni Paolo II ha nuovamente esposto sul medesimo argomento alcuni aspetti di grande importanza per il contesto ecclesiale della nostra epoca.\u00a0[7]<\/p>\n<p style=\"text-align: justify;\">In particolare, il Sommo Pontefice, affinch\u00e9 la Chiesa tuteli debitamente anche al giorno d\u2019oggi un cos\u00ec grande mistero nella celebrazione della sacra Liturgia, ha dato disposizione a questa Congregazione per il Culto Divino e la Disciplina dei Sacramenti\u00a0[8] di preparare, d\u2019intesa con la Congregazione per la Dottrina della Fede, la presente Istruzione, in cui fossero trattate alcune questioni concernenti la disciplina del sacramento dell\u2019Eucaristia. Quanto appare in questa Istruzione va, pertanto, letto in continuit\u00e0 con la citata Lettera Enciclica \u00ab<em><a href=\"http:\/\/www.vatican.va\/holy_father\/special_features\/encyclicals\/documents\/hf_jp-ii_enc_20030417_ecclesia_eucharistia_it.html\" target=\"_blank\" rel=\"noopener noreferrer\">Ecclesia de Eucharistia<\/a><\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Tuttavia, non si ha l\u2019intenzione di offrire in essa l\u2019insieme delle norme relative alla Santissima Eucaristia, quanto piuttosto di riprendere con tale Istruzione alcuni elementi, che risultano tuttora validi nella normativa gi\u00e0 esposta e stabilita, per rafforzare il senso profondo delle norme liturgiche,[9] e indicarne altri che spieghino e completino i precedenti, illustrandoli ai Vescovi, ma anche ai Sacerdoti, ai Diaconi e a tutti i fedeli laici, affinch\u00e9 ciascuno li metta in pratica secondo il proprio ufficio e le proprie possibilit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>[3.]<\/strong> Le norme contenute in questa Istruzione si considerino inerenti alla materia liturgica nell\u2019ambito del Rito romano e, con le opportune varianti, degli altri Riti della Chiesa latina giuridicamente riconosciuti.<\/p>\n<p style=\"text-align: justify;\"><strong>[4.] <\/strong>\u00abNon c\u2019\u00e9 dubbio che la riforma liturgica del Concilio abbia portato grandi vantaggi per una pi\u00f9 consapevole, attiva e fruttuosa partecipazione dei fedeli al santo Sacrificio dell\u2019altare\u00bb.\u00a0[10] Tuttavia, \u00abnon mancano delle ombre\u00bb.\u00a0[11] Non si possono, pertanto, passare sotto silenzio gli abusi, anche della massima gravit\u00e0, contro la natura della Liturgia e dei sacramenti, nonch\u00e9 contro la tradizione e l\u2019autorit\u00e0 della Chiesa, che non di rado ai nostri giorni in diversi ambiti ecclesiali compromettono le celebrazioni liturgiche. In alcuni luoghi gli abusi commessi in materia liturgica sono all\u2019ordine del giorno, il che ovviamente non pu\u00f2 essere ammesso e deve cessare.<\/p>\n<p style=\"text-align: justify;\"><strong>[5.]<\/strong> L\u2019osservanza delle norme emanate dall\u2019autorit\u00e0 della Chiesa esige conformit\u00e0 di pensiero e parola, degli atti esterni e della disposizione d\u2019animo. Una osservanza puramente esteriore delle norme, come \u00e8 evidente, contrasterebbe con l\u2019essenza della sacra Liturgia, nella quale Cristo Signore vuole radunare la sua Chiesa perch\u00e9 sia con lui \u00abun solo corpo e un solo spirito\u00bb.[12] L\u2019atto esterno deve essere, pertanto, illuminato dalla fede e dalla carit\u00e0 che ci uniscono a Cristo e gli uni agli altri e generano l\u2019amore per i poveri e gli afflitti. Le parole e i riti della Liturgia sono, inoltre, espressione fedele maturata nei secoli dei sentimenti di Cristo e ci insegnano a sentire come lui:\u00a0[13] conformando a quelle parole la nostra mente, eleviamo al Signore i nostri cuori. Quanto detto nella presente Istruzione intende condurre a tale conformit\u00e0 dei sentimenti nostri con quelli di Cristo, espressi nelle parole e nei riti della Liturgia.<\/p>\n<p style=\"text-align: justify;\"><strong>[6.]<\/strong> Tali abusi, infatti, \u00abcontribuiscono ad oscurare la retta fede e la dottrina cattolica su questo mirabile Sacramento\u00bb.[14] In questo modo si impedisce pure \u00abai fedeli di rivivere in un certo senso l\u2019esperienza dei due discepoli di Emmaus: \u201cE i loro occhi si aprirono e lo riconobbero\u201d\u00bb.[15] Davanti alla potenza e alla divinit\u00e0[16] di Dio e allo splendore della sua bont\u00e0, particolarmente visibile nel sacramento dell\u2019Eucaristia, si addice, infatti, che tutti i fedeli nutrano e manifestino quel senso dell\u2019adorabile maest\u00e0 di Dio, che hanno ricevuto attraverso la passione salvifica del Figlio Unigenito.[17]<\/p>\n<p style=\"text-align: justify;\"><strong>[7.]<\/strong> Gli abusi non di rado si radicano in un falso concetto di libert\u00e0. Dio, per\u00f2, ci concede in Cristo non quella illusoria libert\u00e0 in base alla quale facciamo tutto ci\u00f2 che vogliamo, ma la libert\u00e0, per mezzo della quale possiamo fare ci\u00f2 che \u00e8 degno e giusto.[18] Ci\u00f2 vale invero non soltanto per quei precetti derivati direttamente da Dio, ma anche, considerando convenientemente l\u2019indole di ciascuna norma, per le leggi promulgate dalla Chiesa. Da ci\u00f2 la necessit\u00e0 che tutti si conformino agli ordinamenti stabiliti dalla legittima autorit\u00e0 ecclesiastica.<\/p>\n<p style=\"text-align: justify;\"><strong>[8.]<\/strong> Si deve, inoltre, notare con grande amarezza la presenza di \u00abiniziative ecumeniche che, pur generose nelle intenzioni, indulgono qua e l\u00e0 a prassi eucaristiche contrarie alla disciplina nella quale la Chiesa esprime la sua fede\u00bb. Il dono dell\u2019Eucaristia, tuttavia, \u00ab\u00e8 troppo grande per sopportare ambiguit\u00e0 e diminuzioni\u00bb. \u00c8, pertanto, opportuno correggere e definire con maggiore accuratezza alcuni elementi, di modo che anche in questo ambito \u00abl\u2019Eucaristia continui a risplendere in tutto il fulgore del suo mistero\u00bb.[19]<\/p>\n<p style=\"text-align: justify;\"><strong>[9.]<\/strong> Gli abusi trovano, infine, molto spesso fondamento nell\u2019ignoranza, giacch\u00e9 per lo pi\u00f9 si rigetta ci\u00f2 di cui non si coglie il senso pi\u00f9 profondo, n\u00e9 si conosce l\u2019antichit\u00e0. Infatti, \u00abdell\u2019afflato e dello spirito\u00bb della stessa sacra Scrittura \u00absono permeate\u00bb appieno \u00able preghiere, le orazioni e gli inni e da essa derivano il loro significato le azioni e i segni sacri\u00bb.[20] Quanto ai segni visibili, \u00abdi cui la sacra Liturgia si serve per significare le realt\u00e0 divine invisibili, essi sono stati scelti da Cristo o dalla Chiesa\u00bb.[21] Infine, le strutture e le forme delle sacre celebrazioni, secondo la tradizione di ciascun rito sia d\u2019Oriente sia d\u2019Occidente, sono in sintonia con la Chiesa universale anche per quanto riguarda usi universalmente accolti dalla ininterrotta tradizione apostolica<span style=\"color: #074d7c;\"><span style=\"background-color: #d5d5d5;\">\u00a0<\/span><\/span>[22] che \u00e8 compito proprio della Chiesa trasmettere fedelmente e con cura alle future generazioni. Tutto ci\u00f2 viene sapientemente custodito e salvaguardato dalle norme liturgiche.<\/p>\n<p style=\"text-align: justify;\"><strong>[10.]<\/strong> La stessa Chiesa non ha alcuna potest\u00e0 rispetto a ci\u00f2 che \u00e8 stato stabilito da Cristo e che costituisce parte immutabile della Liturgia.\u00a0[23] Se fosse, infatti, spezzato il legame che i sacramenti hanno con Cristo stesso, che li ha istituiti, e con gli eventi su cui la Chiesa \u00e8 fondata,[24] ci\u00f2 non sarebbe di nessun giovamento per i fedeli, ma nuocerebbe a loro gravemente. La sacra Liturgia, infatti, \u00e8 intimamente collegata con i principi della dottrina\u00a0[25] e l\u2019uso di testi e riti non approvati comporta, di conseguenza, che si affievolisca o si perda il nesso necessario tra la <em>lex orandi<\/em> e la <em>lex credendi\u00a0<\/em>26]<\/p>\n<p style=\"text-align: justify;\"><strong>[11.]<\/strong> Troppo grande \u00e8 il Mistero dell\u2019Eucaristia \u00abperch\u00e9 qualcuno possa permettersi di trattarlo con arbitrio personale, che non ne rispetterebbe il carattere sacro e la dimensione universale\u00bb.[27] Chi al contrario, anche se Sacerdote, agisce cos\u00ec, assecondando proprie inclinazioni, lede la sostanziale unit\u00e0 del rito romano, che va tenacemente salvaguardata,[28] e compie azioni in nessun modo consone con la fame e sete del Dio vivente provate oggi dal popolo, n\u00e9 svolge autentica attivit\u00e0 pastorale o corretto rinnovamento liturgico, ma priva piuttosto i fedeli del loro patrimonio e della loro eredit\u00e0. Atti arbitrari, infatti, non giovano a un effettivo rinnovamento,[29] ma ledono il giusto diritto dei fedeli all\u2019azione liturgica che \u00e8 espressione della vita della Chiesa secondo la sua tradizione e la sua disciplina. Inoltre, introducono elementi di deformazione e discordia nella stessa celebrazione eucaristica che, in modo eminente e per sua natura, mira a significare e realizzare mirabilmente la comunione della vita divina e l\u2019unit\u00e0 del popolo di Dio\u00a0[30] Da essi derivano insicurezza dottrinale, perplessit\u00e0 e scandalo del popolo di Dio e, quasi inevitabilmente, reazioni aspre: tutti elementi che nel nostro tempo, in cui la vita cristiana risulta spesso particolarmente difficile in ragione del clima di \u00absecolarizzazione\u00bb, confondono e rattristano notevolmente molti fedeli.[31]<\/p>\n<p style=\"text-align: justify;\"><strong>[12.]<\/strong> Tutti i fedeli, invece, godono del diritto di avere una liturgia vera e in particolar modo una celebrazione della santa Messa che sia cos\u00ec come la Chiesa ha voluto e stabilito, come prescritto nei libri liturgici e dalle altre leggi e norme. Allo stesso modo, il popolo cattolico ha il diritto che si celebri per esso in modo integro il sacrificio della santa Messa, in piena conformit\u00e0 con la dottrina del Magistero della Chiesa. \u00c8, infine, diritto della comunit\u00e0 cattolica che per essa si compia la celebrazione della Santissima Eucaristia in modo tale che appaia come vero sacramento di unit\u00e0, escludendo completamente ogni genere di difetti e gesti che possano generare divisioni e fazioni nella Chiesa [32]<\/p>\n<p style=\"text-align: justify;\"><strong>[13.]<\/strong> Tutte le norme e i richiami esposti in questa Istruzione si connettono, sia pure in vario modo, con il compito della Chiesa, a cui spetta di vigilare sulla retta e degna celebrazione di questo grande mistero. Dei vari gradi con cui le singole norme si raccordano con la legge suprema di tutto il diritto ecclesiastico, che \u00e8 la cura per la salvezza delle anime, tratta l\u2019ultimo capitolo della presente Istruzione.[33]<\/p>\n<p style=\"text-align: center;\"><strong>Capitolo I<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>LA REGOLAMENTAZIONE DELLA SACRA LITURGIA<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[14.]<\/strong> \u00abRegolamentare la sacra Liturgia compete unicamente all\u2019autorit\u00e0 della Chiesa, la quale risiede nella Sede Apostolica e, a norma del diritto, nel Vescovo Sacrae\u00bb.<span style=\"color: #1772af;\"><span style=\"background-color: #d5d5d5;\">\u00a0<\/span><\/span>[34]<\/p>\n<p style=\"text-align: justify;\"><strong>[15.]<\/strong> Il Romano Pontefice, \u00abVicario di Cristo e Pastore qui in terra della Chiesa universale, in forza del suo ufficio ha potest\u00e0 ordinaria, suprema, piena, immediata e universale sulla Chiesa, che pu\u00f2 sempre esercitare liberamente\u00bb,\u00a0[35] anche comunicando con i pastori e i fedeli.<\/p>\n<p style=\"text-align: justify;\"><strong>[16.]<\/strong> \u00c8 di competenza della Sede Apostolica ordinare la sacra Liturgia della Chiesa universale, pubblicare i libri liturgici e autorizzarne le versioni nelle lingue correnti, nonch\u00e9 vigilare perch\u00e9 gli ordinamenti liturgici, specialmente quelli attraverso i quali \u00e8 regolata la celebrazione del Santissimo Sacrificio della Messa, siano osservati fedelmente ovunque.\u00a0[36]<\/p>\n<p style=\"text-align: justify;\"><strong>[17.]<\/strong> La Congregazione per il Culto Divino e la Disciplina dei Sacramenti \u00absi occupa di tutto ci\u00f2 che, salva la competenza della Congregazione per la Dottrina della Fede, spetta alla Sede Apostolica circa la regolamentazione e la promozione della sacra Liturgia, in primo luogo dei Sacramenti. Essa favorisce e tutela la disciplina dei sacramenti, specialmente per quanto attiene alla loro valida e lecita celebrazione\u00bb. Infine, \u00abesercita attenta vigilanza perch\u00e9 siano osservate esattamente le disposizioni liturgiche, se ne prevengano gli abusi e, laddove essi siano scoperti, vengano eliminati\u00bb.\u00a0[37] In questa materia, secondo la tradizione di tutta la Chiesa, \u00e8 predominante la sollecitudine per la celebrazione della santa Messa e per il culto che si tributa alla Santissima Eucaristia anche fuori della Messa.<\/p>\n<p style=\"text-align: justify;\"><strong>[18.]<\/strong> I fedeli hanno il diritto che l\u2019autorit\u00e0 ecclesiastica regoli pienamente ed efficacemente la sacra Liturgia, in modo tale che essa non sembri mai \u00abpropriet\u00e0 privata di qualcuno, n\u00e9 del celebrante n\u00e9 della comunit\u00e0 nella quale si celebrano i Misteri\u00bb. [38]<\/p>\n<p style=\"text-align: center;\"><strong>1. Il Vescovo diocesano, grande Sacerdote del suo gregge<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[19.] <\/strong>Il Vescovo diocesano, primo dispensatore dei misteri di Dio, \u00e8 moderatore, promotore e custode di tutta la vita liturgica nella Chiesa particolare a lui affidata.[39] Infatti, \u00abil Vescovo, insignito della pienezza del sacramento dell\u2019Ordine, \u00e8 l\u2019\u201ceconomo della grazia del supremo sacerdozio\u201d[40] specialmente nell\u2019Eucaristia, che offre egli stesso o fa offrire,[41] e della quale la Chiesa continuamente vive e cresce\u00bb.[42]<\/p>\n<p style=\"text-align: justify;\"><strong>[20.] <\/strong>Si ha, infatti, una precipua manifestazione della Chiesa ogni volta che si celebra la Messa, specialmente nella chiesa cattedrale, \u00abnella partecipazione piena e attiva di tutto il popolo santo di Dio, [\u2026] all\u2019unica preghiera, all\u2019unico altare, cui presiede il Vescovo\u00bb,circondato dai suoi Sacerdoti, Diaconi e ministri.[43] Inoltre, ogni\u00ablegittima celebrazione dell\u2019Eucaristia \u00e8 diretta dal Vescovo, al quale \u00e8 affidato l\u2019ufficio di prestare e regolare il culto della religione cristiana alla Divina Maest\u00e0 secondo i precetti del Signore e le leggi della Chiesa, dal suo particolare giudizio ulteriormente determinate per la sua diocesi\u00bb.\u00a0[44]<\/p>\n<p style=\"text-align: justify;\"><strong>[21.]<\/strong> Infatti, al Vescovo \u00abdiocesano spetta, entro i limiti della sua competenza, dare norme in materia liturgica nella Chiesa a lui affidata, alle quali tutti sono tenuti\u00bb.\u00a0[45] Tuttavia, il Vescovo vigili sempre che non venga meno quella libert\u00e0, che \u00e8 prevista dalle norme dei libri liturgici, di adattare, in modo intelligente, la celebrazione sia all\u2019edificio sacro sia al gruppo dei fedeli sia alle circostanze pastorali, cosicch\u00e9 l\u2019intero rito sacro sia effettivamente rispondente alla sensibilit\u00e0 delle persone.[46]<\/p>\n<p style=\"text-align: justify;\"><strong>[22.]<\/strong> Il Vescovo regge la Chiesa particolare a lui affidata<span style=\"color: #1772af;\"><span style=\"background-color: #d5d5d5;\">\u00a0<\/span><\/span>[47] ed \u00e8 suo compito regolamentare, dirigere, spronare, talvolta anche riprendere,\u00a0[48] adempiendo il sacro ufficio che egli ha ricevuto mediante l\u2019ordinazione episcopale\u00a0[49] per l\u2019edificazione del suo gregge nella verit\u00e0 e nella santit\u00e0.\u00a0[50] Illustri il genuino senso dei riti e dei testi liturgici e alimenti nei Sacerdoti, nei Diaconi e nei fedeli lo spirito della sacra Liturgia,[51] perch\u00e9 tutti siano condotti ad un\u2019attiva e fruttuosa celebrazione dell\u2019Eucaristia,\u00a0[52] e assicuri parimenti che tutto il corpo ecclesiale proceda unanime, nell\u2019unit\u00e0 della carit\u00e0, sul piano diocesano, nazionale, universale<span style=\"color: #1772af;\"><span style=\"background-color: #d5d5d5;\">.<\/span><\/span>\u00a0[53]<\/p>\n<p style=\"text-align: justify;\"><strong>[23.]<\/strong> I fedeli \u00abdevono aderire al Vescovo come la Chiesa a Ges\u00f9 Cristo e come Ges\u00f9 Cristo al Padre, affinch\u00e9 tutte le cose siano concordi nell\u2019unit\u00e0 e crescano per la gloria di Dio\u00bb.\u00a0[54]Tutti, anche i membri degli Istituti di vita consacrata e delle Societ\u00e0 di vita apostolica, e di tutte quante le associazioni o movimenti ecclesiali di qualsiasi genere, sono soggetti all\u2019autorit\u00e0 del Vescovo diocesano in tutto ci\u00f2 che riguarda la materia liturgica,\u00a0[55] salvo i diritti legittimamente concessi. Compete, dunque, al Vescovo diocesano il diritto e il dovere di vigilare e verificare, riguardo alla materia liturgica, le chiese e gli oratori situati nel suo territorio, come anche quelle fondate o dirette dai membri dei sopra menzionati istituti, se ad esse abitualmente accedono i fedeli.[56]<\/p>\n<p style=\"text-align: justify;\"><strong>[24.]<\/strong> Da parte sua, il popolo cristiano ha il diritto che il Vescovo diocesano vigili affinch\u00e9 non si insinuino abusi nella disciplina ecclesiastica, specialmente riguardo al ministero della parola, alla celebrazione dei sacramenti e dei sacramentali, al culto di Dio e dei santi.\u00a0[57]<\/p>\n<p style=\"text-align: justify;\"><strong>[25.]<\/strong> Le commissioni, i consiglio comitati costituiti dal Vescovo, perch\u00e9 contribuiscano \u00aba promuovere la Liturgia, la musica e l\u2019arte sacra nella sua diocesi\u00bb, agiranno secondo il pensiero e le direttive del Vescovo e dovranno poter contare sulla sua autorit\u00e0 e sulla sua ratifica per svolgere convenientemente il proprio compito\u00a0[58] e perch\u00e9 sia mantenuto l\u2019effettivo governo del Vescovo nella sua diocesi. Riguardo a tutti questi gruppi, agli altri istituti e a qualsiasi iniziativa in materia liturgica, i Vescovi si chiedano, come gi\u00e0 da tempo risulta urgente, se sia stata finora fruttuosa\u00a0[59] la loro attivit\u00e0 e valutino attentamente quali correttivi o miglioramenti vadano inseriti nella loro struttura e nella loro attivit\u00e0,\u00a0[60] affinch\u00e9 trovino nuovo vigore. Si tenga sempre presente che gli esperti vanno scelti tra coloro, la cui solidit\u00e0 nella fede cattolica e la cui preparazione in materia teologica e culturale siano riconosciute.<\/p>\n<p style=\"text-align: center;\"><strong>2. Le Conferenze dei Vescovi<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[26.]<\/strong> Ci\u00f2 vale anche per quelle commissioni attinenti alla medesima materia che, su sollecitazione del Concilio,\u00a0[61] sono istituite dalla Conferenza dei Vescovi e i cui membri \u00e8 necessario che siano Vescovi e siano ben distinti dagli esperti coadiutori. Qualora il numero di membri di una Conferenza dei Vescovi non risulti sufficiente perch\u00e9 si possa senza difficolt\u00e0 trarre da loro e istituire una commissione liturgica, si nomini un consiglio o gruppo di esperti che, sempre sotto la presidenza di un Vescovo, adempia per quanto possibile a tale compito, evitando per\u00f2 il nome di \u00abCommissione liturgica\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>[27.]<\/strong> La Sede Apostolica ha notificato fin dal 1970\u00a0[62] la cessazione di tutti gli esperimenti relativi alla celebrazione della santa Messa ed ha ribadito tale cessazione nel 1988.\u00a0[63] Pertanto, i singoli Vescovi e le loro Conferenze non hanno alcuna facolt\u00e0 di permettere gli esperimenti riguardo ai testi e ad altro che non sia prescritto nei libri liturgici. Per poter praticare in avvenire tali esperimenti \u00e8 necessario il permesso della Congregazione per il Culto Divino e la Disciplina dei Sacramenti, dato per iscritto e richiesto dalle Conferenze dei Vescovi. Esso, tuttavia, non verr\u00e0 concesso se non per grave causa. Quanto alle iniziative di inculturazione in materia liturgica, si osservino rigorosamente e integralmente le norme specificamente stabilite.[64]<\/p>\n<p style=\"text-align: justify;\"><strong>[28.]<\/strong> Tutte le norme attinenti alla materia liturgica, stabilite a norma del diritto da una Conferenza dei Vescovi per il proprio territorio, vanno sottoposte alla\u00a0<em>recognitio<\/em>\u00a0della Congregazione per il Culto Divino e la Disciplina dei Sacramenti, senza la quale non posseggono alcuna forza obbligante.\u00a0[65]<\/p>\n<p style=\"text-align: center;\"><strong>3. I Sacerdoti<\/strong>\u00ec<\/p>\n<p style=\"text-align: justify;\"><strong>[29.] <\/strong>I Sacerdoti, validi, provvidi e necessari collaboratori dell\u2019ordine episcopale,\u00a0[66] chiamati a servire il popolo di Dio, costituiscono con il loro Vescovo un unico presbiterio,[67] sebbene destinato a uffici diversi. \u00abNelle singole comunit\u00e0 locali di fedeli rendono, per cos\u00ec dire, presente il Vescovo, cui sono uniti con animo fiducioso e grande, ne condividono, secondo il loro grado, gli uffici e la sollecitudine e li esercitano con dedizione quotidiana\u00bb. E \u00abper questa loro partecipazione nel sacerdozio e nella missione, i Sacerdoti riconoscano nel Vescovo il loro padre e gli obbediscano con rispettoso amore\u00bb.[68] Inoltre, \u00absempre intenti al bene dei figli di Dio, cerchino di portare il loro contributo al lavoro pastorale di tutta la diocesi, anzi, di tutta la Chiesa\u00bb.[69]<\/p>\n<p style=\"text-align: justify;\"><strong>[30.]<\/strong> Grande \u00e8 la responsabilit\u00e0 \u00abche hanno nella celebrazione eucaristica soprattutto i Sacerdoti, ai quali compete di presiederla\u00a0<em>in persona Christi<\/em>, assicurando una testimonianza e un servizio di comunione non solo alla comunit\u00e0 che direttamente partecipa alla celebrazione, ma anche alla Chiesa universale, che \u00e8 sempre chiamata in causa dall\u2019Eucaristia. Occorre purtroppo lamentare che, soprattutto a partire dagli anni della riforma liturgica dopo il Concilio Vaticano II, per un malinteso senso di creativit\u00e0 e di adattamento, non sono mancati abusi, che sono stati motivo di sofferenza per molti\u00bb.\u00a0[70]<\/p>\n<p style=\"text-align: justify;\"><strong>[31.]<\/strong> In coerenza con quanto da loro promesso nel rito della sacra ordinazione e rinnovato di anno in anno nel corso della Messa crismale, i Sacerdoti celebrino \u00abdevotamente e con fede i misteri di Cristo a lode di Dio e santificazione del popolo cristiano, secondo la tradizione della Chiesa, specialmente nel sacrificio dell\u2019Eucaristia e nel sacramento della riconciliazione\u00bb.\u00a0[71] Non svuotino il significato profondo del proprio ministero, deformando la celebrazione liturgica con cambiamenti, riduzioni o aggiunte arbitrarie.\u00a0[72] Come disse, infatti, S. Ambrogio: \u00abLa Chiesa non \u00e8 ferita in se stessa, [\u2026] ma in noi. Guardiamoci, dunque, dal far divenire i nostri sbagli una ferita per la Chiesa\u00bb.\u00a0[73] Si badi, quindi, che la Chiesa di Dio non riceva offesa da parte dei Sacerdoti, i quali hanno offerto se stessi al ministero con tanta solennit\u00e0. Vigilino, anzi, fedelmente sotto l\u2019autorit\u00e0 del Vescovo, affinch\u00e9 simili deformazioni non siano commesse da altri.<\/p>\n<p style=\"text-align: justify;\"><strong>[32.]<\/strong> \u00abIl parroco faccia in modo che la Santissima Eucaristia sia il centro dell\u2019assemblea parrocchiale dei fedeli, si adoperi perch\u00e9 i fedeli si nutrano mediante la celebrazione devota dei sacramenti e in special modo perch\u00e9 si accostino frequentemente al sacramento della Santissima Eucaristia e della penitenza; si impegni inoltre a fare in modo che i fedeli siano formati alla preghiera, da praticare anche nella famiglia, e partecipino consapevolmente e attivamente alla sacra Liturgia, di cui il parroco deve essere il moderatore nella sua parrocchia, sotto l\u2019autorit\u00e0 del Vescovo diocesano, e sulla quale \u00e8 tenuto a vigilare perch\u00e9 non si insinuino abusi\u00bb.\u00a0[74] Sebbene sia opportuno che nella preparazione efficace delle celebrazioni liturgiche, specialmente della santa Messa, egli sia coadiuvato da vari fedeli, non deve tuttavia in nessun modo cedere loro quelle prerogative in materia che sono proprie del loro ufficio.<\/p>\n<p style=\"text-align: justify;\"><strong>[33.]<\/strong> Infine, tutti \u00abi Sacerdoti abbiano cura di coltivare adeguatamente la scienza e l\u2019arte liturgica, affinch\u00e9, per mezzo del loro ministero liturgico, le comunit\u00e0 cristiane ad essi affidate, elevino una lode sempre pi\u00f9 perfetta a Dio, Padre, Figlio e Spirito Santo\u00bb.\u00a0[75] Soprattutto, siano pervasi di quella meraviglia e di quello stupore che la celebrazione del mistero pasquale nell\u2019Eucaristia procura nel cuore dei fedeli.\u00a0[76]<\/p>\n<p style=\"text-align: center;\"><strong>4. I Diaconi<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[34.]<\/strong> I Diaconi, \u00abai quali sono imposte le mani non per il sacerdozio, ma per il servizio\u00bb,[77] uomini di buona reputazione,\u00a0[78] devono agire, con l\u2019aiuto di Dio, in modo tale da essere riconosciuti come veri discepoli di colui,\u00a0[79] \u00abche non venne per farsi servire, ma per servire\u00bb<span style=\"color: #1772af;\"><span style=\"background-color: #d5d5d5;\">\u00a0<\/span><\/span>[80] e fu in mezzo ai suoi discepoli \u00abcome colui che serve\u00bb.\u00a0[81] E fortificati dal dono dello Spirito Santo ricevuto mediante l\u2019imposizione delle mani, servano il popolo di Dio in comunione con il Vescovo e il suo presbiterio\u00a0[82] Considerino perci\u00f2 il Vescovo come padre e siano di aiuto a lui e al suo Presbiterio \u00abnel ministero della parola, dell\u2019altare e della carit\u00e0\u00bb.[83]<\/p>\n<p style=\"text-align: justify;\"><strong>[35.]<\/strong> Non trascurino mai \u00abdi custodire il mistero della fede, come dice l\u2019Apostolo, in una coscienza pura\u00a0[84] per annunziare tale fede con le parole e le opere, secondo il Vangelo e la tradizione della Chiesa\u00bb,\u00a0[85] servendo con tutto il cuore fedelmente e con umilt\u00e0 la sacra Liturgia come fonte e culmine della vita della Chiesa, \u00abaffinch\u00e9 tutti, diventati figli di Dio mediante la fede e il Battesimo, si riuniscano insieme, lodino Dio nella Chiesa, prendano parte al Sacrificio e alla mensa del Signore\u00bb.\u00a0[86] Pertanto, tutti i Diaconi, per quanto li riguarda, si impegnino a far s\u00ec che la sacra Liturgia sia celebrata a norma dei libri liturgici debitamente approvati.<\/p>\n<p style=\"text-align: center;\"><strong>Capitolo II<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>LA PARTECIPAZIONE DEI FEDELI LAICI ALLA CELEBRAZIONE DELL\u2019EUCARISTIA<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>1. Una partecipazione attiva e consapevole<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[36.]<\/strong> La celebrazione della Messa, in quanto azione di Cristo e della Chiesa, costituisce il centro di tutta la vita cristiana per la Chiesa sia universale sia particolare, e per i singoli fedeli,<span style=\"color: #074d7c;\"><span style=\"background-color: #d5d5d5;\">\u00a0<\/span><\/span>[87] che \u00absono interessati in diverso modo, secondo la diversit\u00e0 di ordini, di compiti, e di partecipazione attiva [88]. In questo modo il popolo cristiano, \u201cstirpe eletta, sacerdozio regale, nazione santa, popolo che Dio si \u00e8 acquistato\u201d,\u00a0[89] manifesta il proprio coerente e gerarchico ordine\u00bb.[90] \u00abIl sacerdozio comune dei fedeli e il sacerdozio ministeriale o gerarchico, quantunque differiscano essenzialmente e non solo di grado, sono tuttavia ordinati l\u2019uno all\u2019altro, poich\u00e9 l\u2019uno e l\u2019altro, ognuno a suo modo, partecipano dell\u2019unico sacerdozio di Cristo\u00bb.[91]<\/p>\n<p style=\"text-align: justify;\"><strong>[37.] <\/strong>Tutti i fedeli, liberati dai propri peccati e incorporati nella Chiesa con il Battesimo, dal carattere loro impresso sono abilitati al culto della religione cristiana,\u00a0[92] affinch\u00e9 in virt\u00f9 del loro regale sacerdozio,\u00a0[93] perseverando nella preghiera e lodando Dio,[94] si manifestino come vittima viva, santa, gradita a Dio e provata in tutte le loro azioni,\u00a0[95] diano dovunque testimonianza di Cristo e a chi la richieda rendano ragione della loro speranza di vita eterna.[96] Pertanto, anche la partecipazione dei fedeli laici alla celebrazione dell\u2019Eucaristia e degli altri riti della Chiesa non pu\u00f2 essere ridotta ad una mera presenza, per di pi\u00f9 passiva, ma va ritenuta un vero esercizio della fede e della dignit\u00e0 battesimale.<\/p>\n<p style=\"text-align: justify;\"><strong>[38.]<\/strong> L\u2019ininterrotta dottrina della Chiesa sulla natura non soltanto conviviale, ma anche e soprattutto sacrificale dell\u2019Eucaristia va giustamente considerata tra i principali criteri per una piena partecipazione di tutti i fedeli a un cos\u00ec grande sacramento.[97] \u00abSpogliato del suo valore sacrificale, il mistero viene vissuto come se non oltrepassasse il senso e il valore di un qualsiasi incontro conviviale e fraterno\u00bb\u00a0[98]<\/p>\n<p style=\"text-align: justify;\"><strong>[39.]<\/strong> Per promuovere ed evidenziare la partecipazione attiva, la recente riforma dei libri liturgici ha favorito, secondo le intenzioni del Concilio, le acclamazioni del popolo, le risposte, la salmodia, le antifone, i canti, nonch\u00e9 le azioni o i gesti e l\u2019atteggiamento del corpo e ha provveduto a far osservare a tempo debito il sacro silenzio, prevedendo nelle rubriche anche le parti spettanti ai fedeli.\u00a0[99]\u00a0Ampio spazio si d\u00e0, inoltre, ad una appropriata libert\u00e0 di adattamento fondata sul principio che ogni celebrazione risponda alle necessit\u00e0, alla capacit\u00e0, alla preparazione dell\u2019animo e all\u2019indole dei partecipanti, secondo le facolt\u00e0 stabilite dalle norme liturgiche. Nella scelta dei canti, delle melodie, delle orazioni e delle letture bibliche, nel pronunciare l\u2019omelia, nel comporre la preghiera dei fedeli, nel rivolgere talora le monizioni e nell\u2019ornare secondo i vari tempi la chiesa esiste ampia possibilit\u00e0 di introdurre in ogni celebrazione una certa variet\u00e0 che contribuisca a rendere maggiormente evidente la ricchezza della tradizione liturgica e a conferire accuratamente una connotazione particolare alla celebrazione, tenendo conto delle esigenze pastorali, cos\u00ec da favorire la partecipazione interiore. Va, tuttavia, ricordato che l\u2019efficacia delle azioni liturgiche non sta nella continua modifica dei riti, ma nell\u2019approfondimento della parola di Dio e del mistero celebrato.\u00a0[100]<\/p>\n<p style=\"text-align: justify;\"><strong>[40.]<\/strong> Tuttavia, bench\u00e9 la celebrazione della Liturgia possieda indubbiamente tale connotazione di partecipazione attiva di tutti i fedeli, non ne consegue, come per logica deduzione, che tutti debbano materialmente compiere qualcosa oltre ai previsti gesti ed atteggiamenti del corpo, come se ognuno debba necessariamente assolvere ad uno specifico compito liturgico. La formazione catechetica provveda, piuttosto, con cura a correggere nozioni e usi superficiali in merito diffusi in alcuni luoghi negli ultimi anni e a risvegliare sempre nei fedeli un rinnovato senso di grande ammirazione davanti alla profondit\u00e0 di quel mistero di fede che \u00e8 l\u2019Eucaristia, nella cui celebrazione la Chiesa passa \u00abdal vecchio al nuovo\u00bb ininterrottamente.\u00a0[101] Nella celebrazione dell\u2019Eucaristia, infatti, come pure in tutta la vita cristiana, che da essa trae forza e ad essa tende, la Chiesa, come san Tommaso Apostolo, si prostra in adorazione davanti al Signore crocifisso, morto, sepolto e risorto \u00abnella grandezza del suo divino splendore e esclama in eterno: \u201cSignore mio e Dio mio!\u201d\u00bb.[102]<\/p>\n<p style=\"text-align: justify;\"><strong>[41.]<\/strong> Per suscitare, promuovere e alimentare il senso interiore della partecipazione liturgica risultano particolarmente utili la celebrazione assidua ed estesa della Liturgia delle Ore, l\u2019uso dei sacramentali e gli esercizi della piet\u00e0 popolare cristiana. Tali esercizi, \u00abche, sebbene non riguardino a rigore di diritto la sacra Liturgia, sono invero provvisti di particolare importanza e dignit\u00e0\u00bb, vanno ritenuti, soprattutto quando risultano elogiati e approvati dallo stesso Magistero<span style=\"color: #1772af;\"><span style=\"background-color: #d5d5d5;\">\u00a0<\/span><\/span>[103]\u00a0dotati di un qualche legame con il contesto liturgico, come \u00e8 specialmente per la preghiera del Rosario.\u00a0[104]\u00a0Poich\u00e9, inoltre, queste opere di piet\u00e0 guidano il popolo cristiano alla partecipazione ai sacramenti, e in particolar modo all\u2019Eucaristia, \u00abnonch\u00e9 alla meditazione dei misteri della nostra redenzione e all\u2019imitazione degli insigni esempi dei santi in cielo, esse allora ci rendono partecipi del culto liturgico non senza giovamento di salvezza\u00bb.\u00a0[105]<\/p>\n<p style=\"text-align: justify;\"><strong>[42.]<\/strong> \u00c8 necessario comprendere che la Chiesa non si riunisce per umana volont\u00e0, ma \u00e8 convocata da Dio nello Spirito Santo, e risponde per mezzo della fede alla sua vocazione gratuita: il termine <em>ekkles\u00eda<\/em> rimanda, infatti, a <em>klesis<\/em>, che significa \u201cchiamata\u201d.[106] Il sacrificio eucaristico non va poi ritenuto come \u00abconcelebrazione\u00bb in senso univoco del Sacerdote insieme con il popolo presente\u00a0[107]. Al contrario, l\u2019Eucaristia celebrata dai Sacerdoti \u00e8 un dono \u00abche supera radicalmente il potere dell\u2019assemblea [\u2026]. La comunit\u00e0 che si riunisce per la celebrazione dell\u2019Eucaristia necessita assolutamente di un Sacerdote ordinato che la presieda per poter essere veramente assemblea eucaristica. D\u2019altra parte, la comunit\u00e0 non \u00e8 in grado di darsi da sola il ministro ordinato\u00bb\u00a0[108]. \u00c8 assolutamente necessaria la volont\u00e0 comune di evitare ogni ambiguit\u00e0 in materia e portare rimedio alle difficolt\u00e0 insorte negli ultimi anni. Pertanto, si usino soltanto con cautela locuzioni quali \u00abcomunit\u00e0 celebrante\u00bb o \u00abassemblea celebrante\u00bb, o in altre lingue moderne \u00abcelebrating assembly\u00bb, \u00abasamblea celebrante\u00bb, \u00abassembl\u00e9e c\u00e9l\u00e9brante\u00bb, e simili.<\/p>\n<p style=\"text-align: center;\"><strong>2. I compiti dei fedeli laici nella celebrazione della Messa<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[43.]<\/strong> \u00c8 giusto e lodevole che per il bene della comunit\u00e0 e di tutta la Chiesa di Dio alcuni fedeli laici svolgano secondo la tradizione alcuni compiti attinenti alla celebrazione della sacra Liturgia.<a name=\"_ftnref109\"><\/a> [109] Conviene che siano pi\u00f9 persone a distribuirsi tra loro o a svolgere i vari uffici o le varie parti dello stesso ufficio.\u00a0[110]<\/p>\n<p style=\"text-align: justify;\"><strong>[44.]<\/strong> Oltre ai ministeri istituiti dell\u2019accolito e del lettore,\u00a0[111] tra i suddetti uffici particolari vi sono quelli dell\u2019accolito\u00a0\u00a0[112] e del lettore [113] per incarico temporaneo, ai quali sono congiunti gli altri uffici descritti nel Messale Romano,\u00a0[114] nonch\u00e9 i compiti di preparare le ostie, di pulire i lini e simili. Tutti \u00absia ministri ordinati sia fedeli laici, esercitando il loro ministero o ufficio, compiano solo e tutto ci\u00f2 che \u00e8 di loro competenza\u00bb\u00a0[115] e tanto nella stessa celebrazione liturgica quanto nella sua preparazione facciano s\u00ec che la Liturgia della Chiesa si svolga con dignit\u00e0 e decoro.<\/p>\n<p style=\"text-align: justify;\"><strong>[45.]<\/strong> Si deve evitare il rischio di oscurare la complementariet\u00e0 tra l\u2019azione dei chierici e quella dei laici, cos\u00ec da sottoporre il ruolo dei laici a una sorta, come si suol dire, di \u00abclericalizzazione\u00bb, mentre i ministri sacri assumono indebitamente compiti che sono propri della vita e dell\u2019azione dei fedeli laici. [116]<\/p>\n<p style=\"text-align: justify;\"><strong>[46.] <\/strong>Il fedele laico chiamato a prestare il suo aiuto nelle celebrazioni liturgiche occorre che sia debitamente preparato e che si distingua per vita cristiana, fede, condotta e fedelt\u00e0 al Magistero della Chiesa. \u00c8 bene che costui abbia ricevuto una congrua formazione liturgica, secondo la sua et\u00e0, condizione, genere di vita e cultura religiosa.\u00a0[117] Non si scelga nessuno, la cui designazione possa destare meraviglia tra i fedeli.\u00a0[118]<\/p>\n<p style=\"text-align: justify;\"><strong>[47.]<\/strong> \u00c8 veramente ammirevole che persista la nota consuetudine che siano presenti dei fanciulli o dei giovani, chiamati di solito \u00abministranti\u00bb, che prestino servizio all\u2019altare alla maniera dell\u2019accolito, e abbiano ricevuto, secondo le loro capacit\u00e0, una opportuna catechesi riguardo al loro compito\u00a0[119] Non si deve dimenticare che dal novero di questi fanciulli \u00e8 scaturito nel corso dei secoli un cospicuo numero di ministri sacri. [120] Si istituiscano o promuovano per essi delle associazioni, anche con la partecipazione e l\u2019aiuto dei genitori, con le quali si provveda pi\u00f9 efficacemente alla cura pastorale dei ministranti. Quando tali associazioni assumono carattere internazionale, spetta alla Congregazione per il Culto Divino e la Disciplina dei Sacramenti erigerle o esaminare e approvare i loro statuti [121] A tale servizio dell\u2019altare si possono ammettere fanciulle o donne a giudizio del Vescovo diocesano e nel rispetto delle norme stabilite\u00a0[122]<\/p>\n<p style=\"text-align: center;\"><strong>Capitolo III<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>LA RETTA CELEBRAZIONE DELLA SANTA MESSA<\/strong><\/p>\n<p style=\"text-align: center;\"><strong style=\"text-align: justify;\">1. La materia della Santissima Eucaristia<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[48.]<\/strong> Il pane utilizzato nella celebrazione del santo Sacrificio eucaristico deve essere azimo, esclusivamente di frumento e preparato di recente, in modo che non ci sia alcun rischio di decomposizione.[123] Ne consegue, dunque, che quello preparato con altra materia, anche se cereale, o quello a cui sia stata mescolata materia diversa dal frumento, in quantit\u00e0 tale da non potersi dire, secondo la comune estimazione, pane di frumento, non costituisce materia valida per la celebrazione del sacrificio e del sacramento eucaristico\u00a0[124] \u00c8 un grave abuso introdurre nella confezione del pane dell\u2019Eucaristia altre sostanze, come frutta, zucchero o miele. Va da s\u00e9 che le ostie devono essere confezionate da persone che non soltanto si distinguano per onest\u00e0, ma siano anche esperte nel prepararle e fornite di strumenti adeguati.\u00a0[125]<\/p>\n<p style=\"text-align: justify;\"><strong>[49.]<\/strong> In ragione del segno espresso, conviene che qualche parte del pane eucaristico ottenuto dalla frazione sia distribuito almeno a qualche fedele al momento della Comunione. \u00abLe ostie piccole non sono comunque affatto escluse, quando il numero dei comunicandi, o altre ragioni pastorali lo esigano\u00bb;\u00a0[126] si usino, anzi, di solito particole per lo pi\u00f9 piccole, che non richiedano ulteriore frazione.<\/p>\n<p style=\"text-align: justify;\"><strong>[50.] <\/strong>Il vino utilizzato nella celebrazione del santo sacrificio eucaristico deve essere naturale, del frutto della vite, genuino, non alterato, n\u00e9 commisto a sostanze estranee [127] Nella stessa celebrazione della Messa va mescolata ad esso una modica quantit\u00e0 di acqua. Con la massima cura si badi che il vino destinato all\u2019Eucaristia sia conservato in perfetto stato e non diventi aceto.\u00a0[128] \u00c8 assolutamente vietato usare del vino, sulla cui genuinit\u00e0 e provenienza ci sia dubbio: la Chiesa esige, infatti, certezza rispetto alle condizioni necessarie per la validit\u00e0 dei sacramenti. Non si ammetta, poi, nessun pretesto a favore di altre bevande di qualsiasi genere, che non costituiscono materia valida.<\/p>\n<p style=\"text-align: center;\"><strong>2. La Preghiera eucaristica<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[51.]<\/strong> Si usino soltanto le Preghiere eucaristiche che si trovano nel Messale Romano o legittimamente approvate dalla Sede Apostolica secondo i modi e i termini da essa definiti. \u00abNon si pu\u00f2 tollerare che alcuni Sacerdoti si arroghino il diritto di comporre preghiere eucaristiche\u00bb [129] o modificare il testo di quelle approvate dalla Chiesa, n\u00e9 adottarne altre composte da privati [130].<\/p>\n<p style=\"text-align: justify;\"><strong>[52.]<\/strong> La recita della Preghiera eucaristica, che per sua stessa natura \u00e8 come il culmine dell\u2019intera celebrazione, \u00e8 propria del Sacerdote, in forza della sua ordinazione. \u00c8, pertanto, un abuso far s\u00ec che alcune parti della Preghiera eucaristica siano recitate da un Diacono, da un ministro laico oppure da uno solo o da tutti i fedeli insieme. La Preghiera eucaristica deve, dunque, essere interamente recitata dal solo Sacerdote.\u00a0[131]<\/p>\n<p style=\"text-align: justify;\"><strong>[53.]<\/strong> Mentre il Sacerdote celebrante recita la Preghiera eucaristica, \u00abnon si sovrappongano altre orazioni o canti, e l\u2019organo o altri strumenti musicali tacciano\u00bb,\u00a0[132] salvo che per le acclamazioni del popolo debitamente approvate, di cui si veda pi\u00f9 avanti.<\/p>\n<p style=\"text-align: justify;\"><strong>[54.]<\/strong> Il popolo, tuttavia, prende parte sempre attivamente e mai in modo meramente passivo:al Sacerdote\u00absi associ con fede e in silenzio, ed anche con gli interventi stabiliti nel corso della Preghiera eucaristica, quali sono le risposte nel dialogo del Prefazio, il Santo, l\u2019acclamazione dopo la consacrazione e l\u2019Amen dopo la dossologia finale, ed altre acclamazioni approvate dalla Conferenza dei Vescovi e confermate dalla Santa Sede\u00bb.\u00a0[133]<\/p>\n<p style=\"text-align: justify;\"><strong>[55.]<\/strong> In alcuni luoghi \u00e8 invalso l\u2019abuso per cui il Sacerdote spezza l\u2019ostia al momento della consacrazione durante la celebrazione della santa Messa. Tale abuso si compie, per\u00f2, contro la tradizione della Chiesa e va riprovato e molto urgentemente corretto.<\/p>\n<p style=\"text-align: justify;\"><strong>[56.]<\/strong> Non si ometta nella Preghiera eucaristica il ricordo del nome del Sommo Pontefice e del Vescovo diocesano, per conservare un\u2019antichissima tradizione e manifestare la comunione ecclesiale. Infatti, \u00ablo stesso radunarsi insieme della comunit\u00e0 eucaristica \u00e8 anche comunione con il proprio Vescovo e con il Romano Pontefice\u00bb.\u00a0[134]<\/p>\n<p style=\"text-align: center;\"><strong>3. Le altre parti della Messa<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[57.]<\/strong> \u00c8 diritto della comunit\u00e0 dei fedeli che ci siano regolarmente, soprattutto nella celebrazione domenicale, una adeguata e idonea musica sacra e, sempre, un altare, dei paramenti e sacri lini che splendano, secondo le norme, per dignit\u00e0, decoro e pulizia.<\/p>\n<p style=\"text-align: justify;\"><strong>[58.]<\/strong> Parimenti, tutti i fedeli hanno il diritto che la celebrazione dell\u2019Eucaristia sia diligentemente preparata in tutte le sue parti, in modo tale che in essa sia degnamente ed efficacemente proclamata e illustrata la parola di Dio, sia esercitata con cura, secondo le norme, la facolt\u00e0 di scelta dei testi liturgici e dei riti, e nella celebrazione della Liturgia sia debitamente custodita e alimentata la loro fede nelle parole dei canti.<\/p>\n<p style=\"text-align: justify;\"><strong>[59.]<\/strong> Si ponga fine al riprovevole uso con il quale i Sacerdoti, i Diaconi o anche i fedeli mutano e alterano a proprio arbitrio qua e l\u00e0 i testi della sacra Liturgia da essi pronunciati. Cos\u00ec facendo, infatti, rendono instabile la celebrazione della sacra Liturgia e non di rado ne alterano il senso autentico.<\/p>\n<p style=\"text-align: justify;\"><strong>[60.]<\/strong> Nella celebrazione della Messa la Liturgia della Parola e la Liturgia eucaristica sono strettamente congiunte tra loro e formano un solo atto di culto. Pertanto, non \u00e8 lecito separare una parte dall\u2019altra, celebrandole in tempi e luoghi differenti [135] Inoltre, non \u00e8 lecito eseguire singole sezioni della santa Messa in vari momenti anche di uno stesso giorno.<\/p>\n<p style=\"text-align: justify;\"><strong>[61.]<\/strong> Nello scegliere le letture bibliche da proclamare nella celebrazione della Messa, si seguano le norme che si trovano nei libri liturgici,\u00a0[136] affinch\u00e9 realmente\u00abla mensa della Parola di Dio sia imbandita ai fedeli con maggiore abbondanza e vengano ad essi aperti pi\u00f9 largamente i tesori della Bibbia\u00bb.\u00a0[137]<\/p>\n<p style=\"text-align: justify;\"><strong>[62.]<\/strong> Non \u00e8 permesso omettere o sostituire di propria iniziativa le letture bibliche prescritte n\u00e9 sostituire specialmente \u00able letture e il salmo responsoriale, che contengono la parola di Dio, con altri testi non biblici\u00bb.[138]<\/p>\n<p style=\"text-align: justify;\"><strong>[63.]<\/strong> La lettura del Vangelo, che \u00abcostituisce il culmine della Liturgia della Parola\u00bb,[139] \u00e8 riservata, secondo la tradizione della Chiesa, nella celebrazione della sacra Liturgia al ministro ordinato. [140]\u00a0Non \u00e8 pertanto consentito a un laico, anche religioso, proclamare il Vangelo durante la celebrazione della santa Messa e neppure negli altri casi in cui le norme non lo permettano esplicitamente\u00a0[141].<\/p>\n<p style=\"text-align: justify;\"><strong>[64.]<\/strong> L\u2019omelia, che si tiene nel corso della celebrazione della santa Messa ed \u00e8 parte della stessa Liturgia,\u00a0[142] \u00abdi solito \u00e8 tenuta dallo stesso Sacerdote celebrante o da lui affidata a un Sacerdote concelebrante, o talvolta, secondo l\u2019opportunit\u00e0, anche al Diacono, mai per\u00f2 a un laico\u00a0[143]. In casi particolari e per un giusto motivo l\u2019omelia pu\u00f2 essere tenuta anche da un Vescovo o da un Presbitero che partecipa alla celebrazione anche se non pu\u00f2 concelebrare\u00bb.[144]<\/p>\n<p style=\"text-align: justify;\"><strong>[65.]<\/strong> Va ricordato che, in base a quanto prescritto dal canone 767, \u00a7 1, si ritiene abrogata ogni precedente norma che abbia consentito a fedeli non ordinati di tenere l\u2019omelia durante la celebrazione eucaristica. [145] Tale prassi \u00e8, di fatto, riprovata e non pu\u00f2, pertanto, essere accordata in virt\u00f9 di alcuna consuetudine.<\/p>\n<p style=\"text-align: justify;\"><strong>[66.]<\/strong> Il divieto di ammissione dei laici alla predicazione durante la celebrazione della Messa vale anche per i seminaristi, per gli studenti di discipline teologiche, per quanti abbiano ricevuto l\u2019incarico di \u00abassistenti pastorali\u00bb, e per qualsiasi altro genere, gruppo, comunit\u00e0 o associazione di laici.\u00a0[146]<\/p>\n<p style=\"text-align: justify;\"><strong>[67.]<\/strong> Soprattutto, si deve prestare piena attenzione affinch\u00e9 l\u2019omelia si incentri strettamente sul mistero della salvezza, esponendo nel corso dell\u2019anno liturgico sulla base delle letture bibliche e dei testi liturgici i misteri della fede e le regole della vita cristiana e offrendo un commento ai testi dell\u2019Ordinario o del Proprio della Messa o di qualche altro rito della Chiesa.[147] Va da s\u00e9 che tutte le interpretazioni della sacra Scrittura debbano essere ricondotte a Cristo come supremo cardine dell\u2019economia della salvezza, ma ci\u00f2 avvenga tenendo anche conto dello specifico contesto della celebrazione liturgica. Nel tenere l\u2019omelia si abbia cura di irradiare la luce di Cristo sugli eventi della vita. Ci\u00f2 per\u00f2 avvenga in modo da non svuotare il senso autentico e genuino della parola di Dio, trattando, per esempio, solo di politica o di argomenti profani o attingendo come da fonte a nozioni provenienti da movimenti pseudo-religiosi diffusi nella nostra epoca.[148]<\/p>\n<p style=\"text-align: justify;\"><strong>[68.]<\/strong> Il Vescovo diocesano vigili con attenzione sull\u2019omelia,\u00a0[149] facendo anche circolare tra i ministri sacri norme, lineamenti e sussidi e promovendo incontri e altre iniziative apposite, affinch\u00e9 essi abbiano spesso occasione di riflettere con maggiore accuratezza sulla natura dell\u2019omelia e trovino un aiuto per quanto concerne la sua preparazione.<\/p>\n<p style=\"text-align: justify;\"><strong>[69.]<\/strong> Non si ammetta nella santa Messa, come nelle altre celebrazioni liturgiche, un Credo o Professione di fede, che non sia inserito nei libri liturgici debitamente approvati.<\/p>\n<p style=\"text-align: justify;\"><strong>[70.] <\/strong>Le offerte che i fedeli sono soliti presentare durante la santa Messa per la Liturgia eucaristica non si riducono necessariamente al pane e al vino per la celebrazione dell\u2019Eucaristia, ma possono comprendere anche altri doni che vengono portati dai fedeli sotto forma di denaro o altri beni utili per la carit\u00e0 verso i poveri. I doni esteriori devono, tuttavia, essere sempre espressione visibile di quel vero dono che il Signore aspetta da noi: un cuore contrito e l\u2019amore di Dio e del prossimo, per mezzo del quale siamo conformati al sacrificio di Cristo che offr\u00ec se stesso per noi. Nell\u2019Eucaristia, infatti, risplende in sommo grado il mistero di quella carit\u00e0 che Ges\u00f9 Cristo ha rivelato nell\u2019Ultima Cena lavando i piedi dei discepoli. Tuttavia, a salvaguardia della dignit\u00e0 della sacra Liturgia occorre che le offerte esteriori siano presentate in modo adeguato. Pertanto, il denaro, come pure le altre offerte per i poveri, siano collocati in un luogo adatto, ma fuori della mensa eucaristica.\u00a0[150] Ad eccezione del denaro e, nel caso, in ragione del segno, di una minima parte degli altri doni, \u00e8 preferibile che tali offerte vengano presentate al di fuori della celebrazione della Messa.<\/p>\n<p style=\"text-align: justify;\"><strong>[71.]<\/strong> Si mantenga l\u2019uso del Rito romano di scambiare la pace prima della santa Comunione, come stabilito nel Rito della Messa. Secondo la tradizione del Rito romano, infatti, questo uso non ha connotazione n\u00e9 di riconciliazione n\u00e9 di remissione dei peccati, ma piuttosto la funzione di manifestare pace, comunione e carit\u00e0 prima di ricevere la Santissima Eucaristia. [151] \u00c8, invece, l\u2019atto penitenziale da eseguire all\u2019inizio della Messa, in particolare secondo la sua prima forma, ad avere carattere di riconciliazione tra i fratelli.<\/p>\n<p style=\"text-align: justify;\"><strong>[72.] <\/strong>Conviene \u00abche ciascuno dia la pace soltanto a coloro che gli stanno pi\u00f9 vicino, in modo sobrio\u00bb. \u00abIl Sacerdote pu\u00f2 dare la pace ai ministri, rimanendo tuttavia sempre nel presbiterio, per non disturbare la celebrazione. Cos\u00ec ugualmente faccia se, per qualche motivo ragionevole, vuol dare la pace ad alcuni fedeli\u00bb. Nec fiat cantus quidam ad pacem comitandam sed sine mora procedatur ad \u00abAgnus Dei\u00bb. \u00abPer ci\u00f2 che riguarda il modo di compiere lo stesso gesto di pace, esso \u00e8 stabilito dalle Conferenze dei Vescovi [\u2026] secondo l\u2019indole e le usanze dei popoli\u00bb e confermato da parte della Sede Apostolica.\u00a0[152]<\/p>\n<p style=\"text-align: justify;\"><strong>[73.]<\/strong> Nella celebrazione della santa Messa la frazione del pane eucaristico, che va fatta soltanto ad opera del Sacerdote celebrante, con l\u2019aiuto, se \u00e8 il caso, di un Diacono o del concelebrante, ma non di un laico, inizia dopo lo scambio della pace, mentre si recita l\u2019\u00abAgnello di Dio\u00bb. Il gesto della frazione del pane, infatti,\u00abcompiuto da Cristo nell\u2019ultima Cena, che sin dal tempo apostolico ha dato il nome a tutta l\u2019azione eucaristica, significa che i molti fedeli, nella Comunione derivante dall\u2019unico pane di vita, che \u00e8 il Cristo morto e risorto per la salvezza del mondo, costituiscono un solo corpo (<em>1 Cor<\/em> 10, 17)\u00bb. [153] Il rito, pertanto, deve essere eseguito con grande rispetto.[154] Sia per\u00f2 breve. Si corregga molto urgentemente l\u2019abuso invalso in alcuni luoghi di prolungare senza necessit\u00e0 tale rito, anche con l\u2019aiuto di laici contrariamente alle norme, e di attribuirgli una esagerata importanza\u00a0[155].<\/p>\n<p style=\"text-align: justify;\"><strong>[74.]<\/strong> Se vi fosse l\u2019esigenza di fornire informazioni o testimonianze di vita cristiana ai fedeli radunati in Chiesa, \u00e8 generalmente preferibile che ci\u00f2 avvenga al di fuori della Messa. Tuttavia, per una grave causa, si possono offrire tali informazioni o testimonianze quando il Sacerdote abbia pronunciato la preghiera dopo la Comunione. Questo uso, tuttavia, non diventi consueto. Tali informazioni e testimonianze, inoltre, non abbiano un senso tale da poter essere confuse con l\u2019omelia, [156] n\u00e9 si pu\u00f2 a causa loro totalmente sopprimere l\u2019omelia stessa.<\/p>\n<p style=\"text-align: center;\"><strong>4. L\u2019unione dei vari riti con la celebrazione della Messa<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[75.]<\/strong> Per una ragione teologica inerente alla celebrazione eucaristica o ad un rito particolare, i libri liturgici talora prescrivono o permettono la celebrazione della santa Messa unitamente a un altro rito, specialmente dei sacramenti.\u00a0[157] Negli altri casi, tuttavia, la Chiesa non ammette tale collegamento, soprattutto quando si tratta di circostanze aventi indole superficiale e vana.<\/p>\n<p style=\"text-align: justify;\"><strong>[76.]<\/strong> Inoltre, secondo l\u2019antichissima tradizione della Chiesa romana, non \u00e8 lecito unire il sacramento della Penitenza con la santa Messa in modo tale che diventi un\u2019unica azione liturgica. Ci\u00f2 non impedisce, tuttavia, che dei Sacerdoti, salvo coloro che celebrano o concelebrano la santa Messa, ascoltino le confessioni dei fedeli che lo desiderino, anche mentre si celebra la Messa nello stesso luogo, per venire incontro alle necessit\u00e0 dei fedeli.\u00a0[158] Ci\u00f2 tuttavia si svolga nella maniera opportuna.<\/p>\n<p style=\"text-align: justify;\"><strong>[77.]<\/strong> In nessun modo si combini la celebrazione della santa Messa con il contesto di una comune cena, n\u00e9 la si metta in rapporto con analogo tipo di convivio. Salvo che in casi di grave necessit\u00e0, non si celebri la Messa su di un tavolo da pranzo [159] o in un refettorio o luogo utilizzato per tale finalit\u00e0 conviviale, n\u00e9 in qualunque aula in cui sia presente del cibo, n\u00e9 coloro che partecipano alla Messa siedano a mensa nel corso stesso della celebrazione. Se per grave necessit\u00e0 si dovesse celebrare la Messa nello stesso luogo in cui dopo si deve cenare, si interponga un chiaro spazio di tempo tra la conclusione della Messa e l\u2019inizio della cena e non si esibisca ai fedeli nel corso della Messa del cibo ordinario.<\/p>\n<p style=\"text-align: justify;\"><strong>[78.]<\/strong> Non \u00e8 lecito collegare la celebrazione della Messa con eventi politici o mondani o con circostanze che non rispondano pienamente al Magistero della Chiesa cattolica. Si deve, inoltre, evitare del tutto di celebrare la Messa per puro desiderio di ostentazione o di celebrarla secondo lo stile di altre cerimonie, tanto pi\u00f9 se profane, per non svuotare il significato autentico dell\u2019Eucaristia.<\/p>\n<p style=\"text-align: justify;\"><strong>[79.]<\/strong> Infine, va considerato nel modo pi\u00f9 severo l\u2019abuso di introdurre nella celebrazione della santa Messa elementi contrastanti con le prescrizioni dei libri liturgici, desumendoli dai riti di altre religioni.<\/p>\n<p style=\"text-align: center;\"><strong>Capitolo IV<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>LA SANTA COMUNIONE<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>1. Disposizioni per ricevere la santa Comunione<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[80.]<\/strong> L\u2019Eucaristia sia proposta ai fedeli anche \u00abcome antidoto, che ci libera dalle colpe quotidiane e ci preserva dai peccati mortali\u00bb,[160] come \u00e8 posto in luce nelle diverse parti della Messa. Quanto all\u2019atto penitenziale collocato all\u2019inizio della Messa, esso ha lo scopo di disporre i partecipanti perch\u00e9 siano in grado di celebrare degnamente i santi misteri;\u00a0[161] tuttavia, \u00ab\u00e8 privo dell\u2019efficacia del sacramento della Penitenza\u00bb\u00a0<a href=\"http:\/\/www.vatican.va\/roman_curia\/congregations\/ccdds\/documents\/rc_con_ccdds_doc_20040423_redemptionis-sacramentum_it.html#_ftn162\">[<\/a>162] e, per quanto concerne la remissione dei peccati gravi, non si pu\u00f2 ritenere un sostituto del sacramento della Penitenza. I pastori di anime curino con diligenza l\u2019istruzione catechetica, in modo che ai fedeli sia trasmesso l\u2019insegnamento cristiano a questo riguardo.<\/p>\n<p style=\"text-align: justify;\"><strong>[81.]<\/strong> La consuetudine della Chiesa afferma, inoltre, la necessit\u00e0 che ognuno esamini molto a fondo se stesso, [163] affinch\u00e9 chi sia conscio di essere in peccato grave non celebri la Messa n\u00e9 comunichi al Corpo del Signore senza avere premesso la confessione sacramentale, a meno che non vi sia una ragione grave e manchi l\u2019opportunit\u00e0 di confessarsi; nel qual caso si ricordi che \u00e8 tenuto a porre un atto di contrizione perfetta, che include il proposito di confessarsi quanto prima\u00a0[164].<\/p>\n<p style=\"text-align: justify;\"><strong>[82.] <\/strong>Inoltre, \u00abla Chiesa ha dato delle norme che mirano insieme a favorire l\u2019accesso frequente e fruttuoso dei fedeli alla mensa eucaristica e a determinare le condizioni oggettive in cui ci si deve astenere del tutto dal distribuire la Comunione\u00bb.\u00a0[165]<\/p>\n<p style=\"text-align: justify;\"><strong>[83.]<\/strong> \u00c8 certamente la cosa migliore che tutti coloro che partecipano ad una celebrazione della santa Messa e sono forniti delle dovute condizioni ricevano in essa la santa Comunione. Talora, tuttavia, avviene che i fedeli si accostino alla sacra mensa in massa e senza il necessario discernimento. \u00c8 compito dei pastori correggere con prudenza e fermezza tale abuso.<\/p>\n<p style=\"text-align: justify;\"><strong>[84.]<\/strong> Inoltre, se si celebra la santa Messa per una grande folla o, per esempio, nelle grandi citt\u00e0, occorre che si faccia attenzione affinch\u00e9 per mancanza di consapevolezza non accedano alla santa Comunione anche i non cattolici o perfino i non cristiani, senza tener conto del Magistero della Chiesa in ambito dottrinale e disciplinare. Spetta ai pastori avvertire al momento opportuno i presenti sulla verit\u00e0 e sulla disciplina da osservare rigorosamente.<\/p>\n<p style=\"text-align: justify;\"><strong>[85.]<\/strong> I ministri cattolici amministrano lecitamente i sacramenti ai soli fedeli cattolici, i quali parimenti li ricevono lecitamente dai soli ministri cattolici, salvo le disposizioni del can. 844 \u00a7\u00a7 2, 3 e 4, e del can. 861 \u00a7 2.\u00a0[166] Inoltre, le condizioni stabilite dal can. 844 \u00a7 4, alle quali non pu\u00f2 essere derogato in alcun modo,\u00a0[167] non possono essere separate tra loro; \u00e8, pertanto, necessario che tutte siano sempre richieste simultaneamente.<\/p>\n<p style=\"text-align: justify;\"><strong>[86.]<\/strong> I fedeli siano accortamente guidati alla pratica di accedere al sacramento della Penitenza al di fuori della celebrazione della Messa, soprattutto negli orari stabiliti, di modo che la sua amministrazione si svolga con tranquillit\u00e0 e a loro effettivo giovamento, senza che siano impediti da una attiva partecipazione alla Messa. Coloro che sono soliti comunicarsi ogni giorno o molto spesso siano istruiti in modo da accedere al sacramento della Penitenza nei tempi opportuni, secondo le possibilit\u00e0 di ciascuno.\u00a0[168]<\/p>\n<p style=\"text-align: justify;\"><strong>[87.]<\/strong> Si premetta sempre alla Prima Comunione dei bambini la confessione sacramentale e l\u2019assoluzione.\u00a0[169] La Prima Comunione, inoltre, sia sempre amministrata da un Sacerdote e mai al di fuori della celebrazione della Messa. Salvo casi eccezionali, \u00e8 poco appropriato amministrarla il Gioved\u00ec Santo \u00abin Cena Domini\u00bb. Si scelga piuttosto un altro giorno, come le domeniche II-VI di Pasqua o la solennit\u00e0 del Santissimo Corpo e Sangue di Cristo o le domeniche \u00abper annum\u00bb, in quanto la domenica \u00e8 giustamente considerata il giorno dell\u2019Eucaristia.[170] A ricevere l\u2019Eucaristia non \u00abaccedano i bambini che non abbiano raggiunto l\u2019et\u00e0 della ragione o che\u00bb il parroco \u00ababbia giudicato non sufficientemente pronti\u00bb.\u00a0[171] Tuttavia, qualora avvenga che un bambino, in via del tutto eccezionale rispetto all\u2019et\u00e0, sia ritenuto maturo per ricevere il sacramento, non gli si rifiuti la Prima Comunione, a condizione che sia stato sufficientemente preparato.<\/p>\n<p style=\"text-align: center;\"><strong>2. La distribuzione della santa Comunione<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[88.]<\/strong> I fedeli di solito ricevano la Comunione sacramentale dell\u2019Eucaristia nella stessa Messa e al momento prescritto dal rito stesso della celebrazione, vale a dire immediatamente dopo la Comunione del Sacerdote celebrante\u00a0[172]. Spetta al Sacerdote celebrante, eventualmente coadiuvato da altri Sacerdoti o dai Diaconi, distribuire la Comunione e la Messa non deve proseguire, se non una volta ultimata la Comunione dei fedeli. Soltanto laddove la necessit\u00e0 lo richieda, i ministri straordinari possono, a norma del diritto, aiutare il Sacerdote celebrante\u00a0[173].<\/p>\n<p style=\"text-align: justify;\"><strong>[89.]<\/strong> Affinch\u00e9, anche \u00abper mezzo dei segni, la Comunione appaia meglio come partecipazione al Sacrificio che si celebra\u00bb,\u00a0[174] \u00e8 da preferirsi che i fedeli possano riceverla con ostie consacrate nella stessa Messa.\u00a0[175]<\/p>\n<p style=\"text-align: justify;\"><strong>[90.]<\/strong> \u00abI fedeli si comunicano in ginocchio o in piedi, come stabilito dalla Conferenza dei Vescovi\u00bb, e confermato da parte della Sede Apostolica. \u00abQuando per\u00f2 si comunicano stando in piedi, si raccomanda che, prima di ricevere il Sacramento, facciano la debita riverenza, da stabilire dalle stesse norme\u00bb.\u00a0[176]<\/p>\n<p style=\"text-align: justify;\"><strong>[91.]<\/strong> Nella distribuzione della santa Comunione \u00e8 da ricordare che \u00abi ministri sacri non possono negare i sacramenti a coloro che li chiedano opportunamente, siano disposti nel debito modo e non abbiano dal diritto la proibizione di riceverli\u00bb.\u00a0[177] Pertanto, ogni cattolico battezzato, che non sia impedito dal diritto, deve essere ammesso alla sacra comunione. Non \u00e8 lecito, quindi, negare a un fedele la santa Comunione, per la semplice ragione, ad esempio, che egli vuole ricevere l\u2019Eucaristia in ginocchio oppure in piedi.<\/p>\n<p style=\"text-align: justify;\"><strong>[92.]<\/strong> Bench\u00e9 ogni fedele abbia sempre il diritto di ricevere, a sua scelta, la santa Comunione in bocca,\u00a0[178] se un comunicando, nelle regioni in cui la Conferenza dei Vescovi, con la conferma da parte della Sede Apostolica, lo abbia permesso, vuole ricevere il Sacramento sulla mano, gli sia distribuita la sacra ostia. Si badi, tuttavia, con particolare attenzione che il comunicando assuma subito l\u2019ostia davanti al ministro, di modo che nessuno si allontani portando in mano le specie eucaristiche. Se c\u2019\u00e8 pericolo di profanazione, non sia distribuita la santa Comunione sulla mano dei fedeli.\u00a0[179]<\/p>\n<p style=\"text-align: justify;\"><strong>[93.]<\/strong> \u00c8 necessario che si mantenga l\u2019uso del piattino per la Comunione dei fedeli, per evitare che la sacra ostia o qualche suo frammento cada.\u00a0[180]<\/p>\n<p style=\"text-align: justify;\"><strong>[94.]<\/strong> Non \u00e8 consentito ai fedeli di \u00abprendere da s\u00e9 e tanto meno passarsi tra loro di mano in mano\u00bb\u00a0[181] la sacra ostia o il sacro calice. In merito, inoltre, va rimosso l\u2019abuso che gli sposi durante la Messa nuziale si distribuiscano in modo reciproco la santa Comunione.<\/p>\n<p style=\"text-align: justify;\"><strong>[95.]<\/strong> Il fedele laico \u00abche ha gi\u00e0 ricevuto la Santissima Eucaristia, pu\u00f2 riceverla una seconda volta nello stesso giorno, soltanto entro la celebrazione eucaristica alla quale partecipa, salvo il disposto del can. 921 \u00a7 2\u00bb.[182]<\/p>\n<p style=\"text-align: justify;\"><strong>[96.]<\/strong> Va disapprovato l\u2019uso di distribuire, contrariamente alle prescrizioni dei libri liturgici, a mo\u2019 di Comunione durante la celebrazione della santa Messa o prima di essa ostie non consacrate o altro materiale commestibile o meno. Tale uso, infatti, non si concilia con la tradizione del Rito romano e reca in s\u00e9 il rischio di ingenerare confusione tra i fedeli riguardo alla dottrina eucaristica della Chiesa. Se in alcuni luoghi vige, per concessione, la consuetudine particolare di benedire il pane e distribuirlo dopo la Messa, si fornisca con grande cura una corretta catechesi di questo gesto. Non si introducano, invece, altre usanze similari, n\u00e9 si utilizzino mai a tale scopo ostie non consacrate.<\/p>\n<p style=\"text-align: center;\"><strong>3. La Comunione dei Sacerdoti<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[97.]<\/strong> Ogni volta che celebra la santa Messa, il Sacerdote deve comunicarsi all\u2019altare al momento stabilito dal Messale; i concelebranti, invece, prima di procedere alla distribuzione della Comunione. Il Sacerdote celebrante o concelebrante non attenda mai per comunicarsi il termine della Comunione del popolo\u00a0[183]<\/p>\n<p style=\"text-align: justify;\"><strong>[98.]<\/strong> La Comunione dei Sacerdoti concelebranti si svolga secondo le norme prescritte nei libri liturgici, facendo sempre uso di ostie consacrate durante la stessa Messa,\u00a0[184] e ricevendo tutti i concelebranti la Comunione sotto le due specie. Si noti che, quando il Sacerdote o il Diacono amministra ai concelebranti la sacra ostia o il calice, non dice nulla, vale a dire non pronuncia le parole \u00abIl Corpo di Cristo\u00bb o \u00abIl Sangue di Cristo\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>[99.]<\/strong> La Comunione sotto le due specie \u00e8 sempre permessa \u00abai Sacerdoti, che non possono celebrare o concelebrare\u00bb [185].<\/p>\n<p style=\"text-align: center;\"><strong>4. La Comunione sotto le due specie<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[100.]<\/strong> Al fine di manifestare ai fedeli con maggior chiarezza la pienezza del segno nel convivio eucaristico, sono ammessi alla Comunione sotto le due specie nei casi citati nei libri liturgici anche i fedeli laici, con il presupposto e l\u2019incessante accompagnamento di una debita catechesi circa i principi dogmatici fissati in materia dal Concilio Ecumenico Tridentino\u00a0[186].<\/p>\n<p style=\"text-align: justify;\"><strong>[101.]<\/strong> Per amministrare la santa Comunione ai fedeli laici sotto le due specie si dovr\u00e0 tenere appropriatamente conto delle circostanze, sulle quali spetta anzitutto ai Vescovi diocesani dare una valutazione. Ci\u00f2 si escluda assolutamente quando esista rischio, anche minimo, di profanazione delle sacre specie\u00a0[187]. Per un pi\u00f9 ampio coordinamento, occorre che le Conferenze dei Vescovi pubblichino, con la conferma da parte della Sede Apostolica, mediante la Congregazione per il Culto Divino e la Disciplina dei Sacramenti, le norme relative soprattutto al \u00abmodo di distribuire ai fedeli la santa Comunione sotto le due specie e all\u2019estensione della facolt\u00e0\u00bb\u00a0[188].<\/p>\n<p style=\"text-align: justify;\"><strong>[102.]<\/strong> Non si amministri ai fedeli laici il calice, laddove sia presente un numero di comunicandi tanto grande\u00a0[189] che risulterebbe difficile stimare la quantit\u00e0 di vino necessario per l\u2019Eucaristia e esisterebbe il rischio che \u00abrimanga una quantit\u00e0 di Sangue di Cristo superiore al giusto da assumere al termine della celebrazione\u00bb,\u00a0[190] n\u00e9 parimenti laddove l\u2019accesso al calice pu\u00f2 essere regolato con difficolt\u00e0 o fosse richiesta una quantit\u00e0 sufficiente di vino, della quale solo difficilmente si pu\u00f2 avere garanzia di provenienza e qualit\u00e0, o laddove non sia disponibile un congruo numero di ministri sacri n\u00e9 di ministri straordinari della sacra Comunione provvisti di appropriata preparazione, o laddove una parte notevole del popolo perseveri, per varie ragioni, nel rifiutarsi di accedere al calice, facendo cos\u00ec venir meno in un certo qual modo il segno dell\u2019unit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>[103.]<\/strong> Le norme del Messale Romano ammettono il principio che, nei casi in cui la Comunione \u00e8 distribuita sotto le due specie, \u00abil Sangue di Cristo pu\u00f2 essere bevuto direttamente al calice, per intinzione, con la cannuccia o con il cucchiaino\u00bb.\u00a0[191] Quanto all\u2019amministrazione della Comunione ai fedeli laici, i Vescovi possono escludere la modalit\u00e0 della Comunione con la cannuccia o il cucchiaino, laddove non sia uso locale, rimanendo comunque sempre vigente la possibilit\u00e0 di amministrare la Comunione per intinzione. Se per\u00f2 si usa questa modalit\u00e0, si ricorra ad ostie che non siano n\u00e9 troppo sottili, n\u00e9 troppo piccole e il comunicando riceva dal Sacerdote il Sacramento soltanto in bocca.\u00a0[192]<\/p>\n<p style=\"text-align: justify;\"><strong>[104.]<\/strong> Non si permetta al comunicando di intingere da s\u00e9 l\u2019ostia nel calice, n\u00e9 di ricevere in mano l\u2019ostia intinta. Quanto all\u2019ostia da intingere, essa sia fatta di materia valida e sia consacrata, escludendo del tutto l\u2019uso di pane non consacrato o di altra materia.<\/p>\n<p style=\"text-align: justify;\"><strong>[105.]<\/strong> Se non fosse sufficiente un solo calice per distribuire la Comunione sotto le due specie ai Sacerdoti concelebranti o ai fedeli, nulla osta che il Sacerdote celebrante usi pi\u00f9 calici.\u00a0[193] Va, infatti, ricordato che tutti i Sacerdoti che celebrano la santa Messa sono tenuti a comunicarsi sotto le due specie. In ragione del segno, \u00e8 lodevole servirsi di un calice principale pi\u00f9 grande insieme ad altri calici di minori dimensioni.<\/p>\n<p style=\"text-align: justify;\"><strong>[106.]<\/strong> Ci si astenga, tuttavia, dal riversare dopo la consacrazione il Sangue di Cristo da un vaso in un altro, per evitare qualunque cosa che possa risultare irrispettosa di cos\u00ec grande mistero. Per ricevere il Sangue del Signore non si utilizzino in nessun caso brocche, crateri o altri vasi non integralmente rispondenti alle norme stabilite.<\/p>\n<p style=\"text-align: justify;\"><strong>[107.]<\/strong> Secondo la normativa stabilita dai canoni, \u00abchi getta via le specie consacrate, oppure le asporta o le conserva a scopo sacrilego, incorre nella scomunica <em>latae sententiae<\/em> riservata alla Sede Apostolica; il chierico inoltre pu\u00f2 essere punito con altra pena, non esclusa la dimissione dallo stato clericale\u00bb.\u00a0[194] All\u2019interno di questo caso si deve considerare annoverabile qualunque azione volontariamente e gravemente volta a dispregio delle sacre specie. Se, pertanto, qualcuno agisce contro le suddette norme, gettando ad esempio le sacre specie nel sacrario o in luogo indegno o a terra, incorre nelle pene stabilite\u00a0[195]. Tengano, inoltre, tutti presente che, al termine della distribuzione della santa Comunione durante la celebrazione della Messa, vanno osservate le prescrizioni del Messale Romano, e soprattutto che quanto eventualmente resta del Sangue di Cristo deve essere subito interamente consumato dal Sacerdote o, secondo le norme, da un altro ministro, mentre le ostie consacrate avanzate vengano o immediatamente consumate all\u2019altare dal Sacerdote o portate in un luogo appositamente destinato a conservare l\u2019Eucaristia\u00a0[196].<\/p>\n<p style=\"text-align: center;\"><strong>Capitolo V<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>ALTRI ASPETTI RIGUARDANTI L\u2019EUCARISTIA<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>\u00a01.\u00a0<\/strong><strong>Il luogo della celebrazione della santa Messa<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[108.]<\/strong> \u00abLa celebrazione eucaristica venga compiuta nel luogo sacro, a meno che in un caso particolare la necessit\u00e0 non richieda altro; nel qual caso, la celebrazione deve essere compiuta in un luogo decoroso\u00bb. [197] Su tale necessit\u00e0 sar\u00e0, di norma, il Vescovo diocesano a valutare secondo il caso per la propria diocesi.<\/p>\n<p style=\"text-align: justify;\"><strong>[109.]<\/strong> Non \u00e8 mai consentito a un Sacerdote celebrare nel tempio o luogo sacro di una religione non cristiana.<\/p>\n<p style=\"text-align: center;\"><strong>2. Circostanze varie relative alla santa Messa<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[110.]<\/strong> \u00abSempre memori che nel mistero del Sacrificio eucaristico viene esercitata ininterrottamente l\u2019opera della redenzione, i Sacerdoti celebrino frequentemente; anzi se ne raccomanda caldamente la celebrazione quotidiana, la quale, anche quando non si possa avere la presenza dei fedeli, \u00e8 un atto di Cristo e della Chiesa, nella cui celebrazione i Sacerdoti adempiono il loro principale compito\u00bb.\u00a0[198]<\/p>\n<p style=\"text-align: justify;\"><strong>[111.]<\/strong> Un Sacerdote sia ammesso a celebrare o concelebrare l\u2019Eucaristia \u00abanche se sconosciuto al rettore della chiesa, purch\u00e9 esibisca la lettera commendatizia\u00bb della Sede Apostolica o del suo Ordinario o del suo Superiore, data almeno entro l\u2019anno, \u00aboppure si possa prudentemente ritenere che non sia impedito di celebrare\u00bb\u00a0[199]. I Vescovi provvedano che abitudini contrarie siano eliminate.<\/p>\n<p style=\"text-align: justify;\"><strong>[112.]<\/strong> La Messa si celebra o in lingua latina o in altra lingua, purch\u00e9 si faccia ricorso a testi liturgici approvati a norma del diritto. Salvo le celebrazioni della Messa che devono essere svolte nella lingua del popolo secondo gli orari e i tempi stabiliti dall\u2019autorit\u00e0 ecclesiastica, \u00e8 consentito sempre e ovunque ai Sacerdoti celebrare in latino\u00a0[200].<\/p>\n<p style=\"text-align: justify;\"><strong>[113.]<\/strong> Quando la Messa \u00e8 concelebrata da pi\u00f9 Sacerdoti, nel pronunciare la Preghiera eucaristica si usi la lingua conosciuta sia da tutti i Sacerdoti concelebranti sia dal popolo riunito. Qualora avvenga che vi siano tra i Sacerdoti alcuni che non conoscono la lingua della celebrazione, cosicch\u00e9 non possono debitamente pronunciare le parti della Preghiera eucaristica che sono loro proprie, essi non concelebrino, ma preferibilmente assistano secondo le norme alla celebrazione indossando l\u2019abito corale\u00a0[201].<\/p>\n<p style=\"text-align: justify;\"><strong>[114.]<\/strong> \u00abNelle Messe domenicali della parrocchia, in quanto \u2018comunit\u00e0 eucaristica\u2019, \u00e8 normale poi che si ritrovino i vari gruppi, movimenti, associazioni, le stesse piccole comunit\u00e0 religiose in essa presenti\u00bb [202]. Bench\u00e9 sia possibile, a norma del diritto, celebrare la Messa per gruppi particolari, ciononostante tali gruppi non sono dispensati dalla fedele osservanza delle norme liturgiche\u00a0[203].<\/p>\n<p style=\"text-align: justify;\"><strong>[115.]<\/strong> Va riprovato l\u2019abuso di sospendere in modo arbitrario la celebrazione della santa Messa per il popolo, contro le norme del Messale Romano e la sana tradizione del Rito romano, con il pretesto di promuovere \u00abil digiuno eucaristico\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>[116.]<\/strong> Non si moltiplichino le Messe, contro la norma del diritto, e, quanto alle offerte per l\u2019intenzione della Messa, si osservino tutte le regole comunque vigenti in forza del diritto.\u00a0[204]<\/p>\n<p style=\"text-align: center;\"><strong>3. I vasi sacri<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[117.]<\/strong> I vasi sacri destinati ad accogliere il Corpo e il Sangue del Signore, siano rigorosamente foggiati a norma di tradizione e dei libri liturgici.\u00a0[205] \u00c8 data facolt\u00e0 alle Conferenze dei Vescovi di stabilire, con la conferma della Santa Sede, se sia opportuno che i vasi sacri siano fabbricati anche con altri materiali solidi. Tuttavia, si richiede strettamente che tali materiali siano davvero nobili secondo il comune giudizio di ciascuna regione,\u00a0[206] di modo che con il loro uso si renda onore al Signore e si eviti completamente il rischio di sminuire agli occhi dei fedeli la dottrina della presenza reale di Cristo nelle specie eucaristiche. \u00c8 pertanto riprovevole qualunque uso, per il quale ci si serva nella celebrazione della Messa di vasi comuni o piuttosto scadenti quanto alla qualit\u00e0 o privi di qualsiasi valore artistico, ovvero di semplici cestini o altri vasi in vetro, argilla, creta o altro materiale facilmente frangibile. Ci\u00f2 vale anche per i metalli e altri materiali facili ad alterarsi\u00a0[207].<\/p>\n<p style=\"text-align: justify;\"><strong>[118.]<\/strong> I vasi sacri, prima di essere usati, devono essere benedetti dal Sacerdote secondo i riti prescritti nei libri liturgici\u00a0[208]. \u00c8 lodevole che la benedizione sia impartita dal Vescovo diocesano, che valuter\u00e0 se i vasi siano adatti all\u2019uso a cui sono destinati.<\/p>\n<p style=\"text-align: justify;\"><strong>[119.]<\/strong> Il Sacerdote, ritornato all\u2019altare dopo la distribuzione della Comunione, stando in piedi all\u2019altare o a un tavolo purifica la patena o la pisside al di sopra del calice, secondo le prescrizioni del Messale, e asciuga il calice con il purificatoio. Se \u00e8 presente il Diacono, questi torna all\u2019altare insieme al Sacerdote e purifica lui i vasi. \u00c8 tuttavia consentito, specialmente se sono numerosi, lasciare i vasi sacri da purificare opportunamente coperti sull\u2019altare o sulla credenza sul corporale e che il Sacerdote o il Diacono li purificano subito dopo la Messa, una volta congedato il popolo. Parimenti, l\u2019accolito istituito aiuta il Sacerdote o il Diacono a purificare e sistemare i vasi sacri sia all\u2019altare sia alla credenza. In assenza del Diacono l\u2019accolito istituito porta alla credenza i vasi sacri e li purifica, li asciuga e li sistema come al solito\u00a0[209].<\/p>\n<p style=\"text-align: justify;\"><strong>[120.]<\/strong> I pastori abbiano cura di mantenere costantemente puliti i lini della mensa sacra, e in particolare quelli destinati ad accogliere le sacre specie, e di lavarli piuttosto di frequente secondo la prassi tradizionale. \u00c8 lodevole che l\u2019acqua del primo lavaggio, che va eseguito a mano, si versi nel sacrario della chiesa o a terra in un luogo appropriato. Successivamente, si pu\u00f2 effettuare un nuovo lavaggio nel modo consueto.<\/p>\n<p style=\"text-align: center;\"><strong>4. Le vesti liturgiche<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[121.]<\/strong> \u00abLa variet\u00e0 dei colori nelle vesti sacre ha lo scopo di esprimere, anche con mezzi esterni, da un lato la caratteristica particolare dei misteri della fede che vengono celebrati, e dall\u2019altro il senso della vita cristiana in cammino lungo il corso dell\u2019anno liturgico\u00bb\u00a0[210]. In realt\u00e0, la differenza \u00abdi compiti nella celebrazione della sacra Liturgia, si manifesta esteriormente con la diversit\u00e0 delle vesti sacre. Conviene che tali vesti sacre contribuiscano anche al decoro della stessa azione sacra\u00bb\u00a0[211].<\/p>\n<p style=\"text-align: justify;\"><strong>[122.]<\/strong> \u00abIl camice \u00e8 stretto ai fianchi dal cingolo, a meno che non sia fatto in modo da aderire al corpo anche senza cingolo. Prima di indossare il camice, se questo non copre l\u2019abito comune attorno al collo, si usi l\u2019amitto\u00bb.\u00a0[212]<\/p>\n<p style=\"text-align: justify;\"><strong>[123.]<\/strong> \u00abNella Messa e nelle altre azioni sacre direttamente collegate con essa, veste propria del Sacerdote celebrante \u00e8 la casula o pianeta, se non viene indicato diversamente, da indossarsi sopra il camice e la stola\u00bb.\u00a0[213] Parimenti, il Sacerdote che porta la casula secondo le rubriche non tralasci di indossare la stola. Tutti gli Ordinari provvedano che ogni uso contrario sia eliminato.<\/p>\n<p style=\"text-align: justify;\"><strong>[124.]<\/strong> Nel Messale Romano si d\u00e0 facolt\u00e0 ai Sacerdoti che concelebrano la Messa accanto al celebrante principale, il quale indossi sempre la casula del colore prescritto, di poter omettere, in presenza di una giusta causa, come ad esempio il numero piuttosto elevato di concelebranti e la mancanza di paramenti, \u00abla casula o la pianeta, facendo uso della stola sopra il camice\u00bb.\u00a0[214] Qualora tuttavia fosse possibile prevedere tale situazione, si provveda in merito per quanto possibile. Coloro che concelebrano possono anch\u2019essi, oltre al celebrante principale, vestire per necessit\u00e0 la casula di colore bianco. Per il resto, si osservino le norme dei libri liturgici.<\/p>\n<p style=\"text-align: justify;\"><strong>[125.]<\/strong> Veste propria del Diacono \u00e8 la dalmatica, da indossarsi sopra il camice e la stola. Al fine di preservare una insigne tradizione della Chiesa, \u00e8 lodevole non valersi della facolt\u00e0 di omettere la dalmatica\u00a0[215].<\/p>\n<p style=\"text-align: justify;\"><strong>[126.]<\/strong> \u00c8 riprovevole l\u2019abuso per cui i ministri sacri, anche quando partecipa un solo ministro, celebrano la santa Messa, contrariamente alle prescrizioni dei libri liturgici, senza vesti sacre o indossando la sola stola sopra la cocolla monastica o il normale abito religioso o un vestito ordinario\u00a0[216]. Gli Ordinari provvedano a correggere quanto prima tali abusi e a far s\u00ec che in tutte le chiese e gli oratori sotto la propria giurisdizione sia presente un congruo numero di vesti liturgiche realizzate secondo le norme.<\/p>\n<p style=\"text-align: justify;\"><strong>[127.]<\/strong> Nei libri liturgici si d\u00e0 speciale facolt\u00e0 di utilizzare nei giorni pi\u00f9 solenni le sacre vesti festive, ovvero di maggiore dignit\u00e0, anche se non siano del colore del giorno\u00a0[217]. Tale facolt\u00e0, tuttavia, riguardando propriamente vesti tessute molti anni or sono al fine di preservare il patrimonio della Chiesa, viene estesa impropriamente a innovazioni in modo tale che, lasciando da parte gli usi tramandati, si assumono forme e colori secondo gusti soggettivi e si menoma il senso di tale norma a detrimento della tradizione. In occasione di un giorno festivo, vesti sacre di color oro o argento possono sostituire, secondo opportunit\u00e0, quelle di altro colore, ma non le vesti violacee e nere.<\/p>\n<p style=\"text-align: justify;\"><strong>[128.]<\/strong> La Santa Messa e le altre celebrazioni liturgiche, che sono azioni di Cristo e del popolo di Dio gerarchicamente costituito, siano ordinate in modo tale che i sacri ministri e i fedeli laici vi possano chiaramente partecipare secondo la propria condizione. \u00c8 preferibile dunque \u00abche i presbiteri presenti alla celebrazione eucaristica, se non sono scusati da una giusta causa, esercitino di solito il ministero del proprio Ordine e quindi partecipino come concelebranti, indossando le sacre vesti. Diversamente indossano il proprio abito corale o la cotta sopra la veste talare\u00bb [218] Non \u00e8 decoroso, salvo motivate eccezioni, che essi partecipino alla Messa, quanto all\u2019aspetto esterno, alla maniera di fedeli laici.<\/p>\n<p style=\"text-align: center;\"><strong>Capitolo VI<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>LA CONSERVAZIONE DELLA SANTISSIMA EUCARISTIA<br \/>\nE IL SUO CULTO FUORI DELLA MESSA<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>1. La conservazione della Santissima Eucaristia<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[129.]<\/strong> \u00abLa celebrazione dell\u2019Eucaristia nel Sacrificio della Messa \u00e8 veramente l\u2019origine e il fine del culto eucaristico fuori della Messa. Dopo la Messa si conservano le sacre specie soprattutto perch\u00e9 i fedeli, e in modo particolare i malati e gli anziani che non possono essere presenti alla Messa, si uniscano, per mezzo della Comunione sacramentale, a Cristo e al suo sacrificio, immolato e offerto nella Messa\u00bb [219] Questa conservazione, inoltre, permette anche la pratica di adorare questo grande Sacramento e di prestare ad esso il culto di latria, che si deve a Dio. \u00c8 necessario, pertanto, che si promuovano certe forme cultuali di adorazione non solo privata ma anche pubblica e comunitaria istituite o approvate validamente dalla stessa Chiesa\u00a0[220].<\/p>\n<p style=\"text-align: justify;\"><strong>[130.]<\/strong> \u00abSecondo la struttura di ciascuna chiesa e le legittime consuetudini locali, il Santissimo Sacramento sia conservato nel tabernacolo in una parte della chiesa di particolare dignit\u00e0, elevata, ben visibile e decorosamente ornata\u00bb, nonch\u00e9, in virt\u00f9 della tranquillit\u00e0 del luogo, dello spazio davanti al tabernacolo e della presenza di panche o sedie e inginocchiatoi, \u00abadatta alla preghiera\u00bb\u00a0[221]. Si attenda, inoltre, con cura a tutte le prescrizioni dei libri liturgici e alla norma del diritto,\u00a0[222] specialmente al fine di evitare il pericolo di profanazione\u00a0[223].<\/p>\n<p style=\"text-align: justify;\"><strong>[131.]<\/strong> Oltre a quanto prescritto dal can. 934 \u00a7 1, \u00e8 vietato conservare il Santissimo Sacramento in un luogo non soggetto alla sicura autorit\u00e0 del Vescovo diocesano o dove esista pericolo di profanazione. In questo caso, il Vescovo diocesano revochi immediatamente la facolt\u00e0 di conservazione dell\u2019Eucaristia precedentemente concessa\u00a0[224].<\/p>\n<p style=\"text-align: justify;\"><strong>[132.]<\/strong> Nessuno porti a casa o in altro luogo la Santissima Eucaristia, contrariamente alla norma del diritto. Si tenga, inoltre, presente che il sottrarre o ritenere a fine sacrilego o il gettar via le specie consacrate sono atti che rientrano in quei <em>graviora delicta<\/em>, la cui assoluzione \u00e8 riservata alla Congregazione per la Dottrina della Fede. [225]<\/p>\n<p style=\"text-align: justify;\"><strong>[133.]<\/strong> Il Sacerdote o il Diacono o il ministro straordinario che, in assenza o sotto impedimento del ministro ordinario, trasporta la Santissima Eucaristia per amministrare la Comunione a un malato, si rechi dal luogo in cui il Sacramento \u00e8 conservato fino al domicilio del malato lungo un tragitto possibilmente diretto e tralasciando ogni altra occupazione, in modo da evitare qualsiasi rischio di profanazione e riservare la massima riverenza al Corpo di Cristo. Si osservi sempre il rito dell\u2019amministrazione della Comunione ai malati come\u00a0prescritto nel Rituale Romano. [226]<\/p>\n<p style=\"text-align: center;\"><strong>2. Alcune forme di culto della Santissima Eucaristia fuori della Messa<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[134.]<\/strong> \u00abIl culto all\u2019Eucaristia fuori della Messa \u00e8 di valore inestimabile nella vita della Chiesa. Tale culto \u00e8 strettamente congiunto con la celebrazione del Sacrificio eucaristico\u00bb\u00a0[227]. Pertanto, si promuova con impegno la piet\u00e0 sia pubblica sia privata verso la Santissima Eucaristia anche al di fuori della Messa, affinch\u00e9 dai fedeli sia reso culto di adorazione a Cristo veramente e realmente presente [228] il quale \u00e8 \u00abSommo Sacerdote dei beni futuri\u00bb\u00a0[229] e Redentore dell\u2019universo. \u00abSpetta ai Pastori incoraggiare, anche con la testimonianza personale, il culto eucaristico, particolarmente le esposizioni del Santissimo Sacramento, nonch\u00e9 la sosta adorante davanti a Cristo presente sotto le specie eucaristiche\u00bb\u00a0[230].<\/p>\n<p style=\"text-align: justify;\"><strong>[135.]<\/strong> I fedeli \u00abdurante il giorno non omettano di fare la visita al Santissimo Sacramento, in quanto prova di gratitudine, segno d\u2019amore e debito di riconoscenza a Cristo Signore l\u00e0 presente\u00bb.\u00a0[231] L\u2019adorazione di Ges\u00f9 presente nel Santissimo Sacramento, infatti, in quanto Comunione di desiderio, unisce fortemente il fedele a Cristo, come risplende dall\u2019esempio di numerosi santi\u00a0[232]. \u00abSe non vi si oppone una grave ragione, la chiesa nella quale viene conservata la Santissima Eucaristia, resti aperta ai fedeli almeno per qualche ora al giorno, affinch\u00e9 possano trattenersi in preghiera dinanzi al\u00a0Santissimo Sacramento\u00bb. [233]<\/p>\n<p style=\"text-align: justify;\"><strong>[136.]<\/strong> L\u2019Ordinario incoraggi molto vivamente l\u2019adorazione eucaristica, sia breve sia prolungata o quasi continua, con il concorso del popolo. Negli ultimi anni, infatti, in molti \u00abluoghi l\u2019adorazione quotidiana del Santissimo Sacramento ha guadagnato ampio spazio e diviene fonte inesauribile di santit\u00e0\u00bb, bench\u00e9 vi siano anche luoghi \u00abdove va registrata una quasi totale noncuranza del culto dell\u2019adorazione eucaristica\u00bb\u00a0[234].<\/p>\n<p style=\"text-align: justify;\"><strong>[137.]<\/strong> L\u2019esposizione della Santissima Eucaristia sia compiuta sempre secondo le prescrizioni dei libri liturgici.\u00a0[235] Non si escluda anche la recita del Rosario, mirabile \u00abnella sua semplicit\u00e0 ed elevatezza\u00bb, [236] dinanzi al Santissimo Sacramento conservato o esposto. Tuttavia, soprattutto quando si fa l\u2019esposizione, si ponga in luce l\u2019indole di questa preghiera come contemplazione dei misteri della vita di Cristo Redentore e del disegno di salvezza del Padre onnipotente, utilizzando in particolare letture desunte dalla sacra Scrittura.\u00a0[237]<\/p>\n<p style=\"text-align: justify;\"><strong>[138.]<\/strong> Comunque, il Santissimo Sacramento non deve mai rimanere esposto, anche per brevissimo tempo, senza sufficiente custodia. Si faccia, dunque, in modo che, in tempi stabiliti, alcuni fedeli siano sempre presenti almeno a turno.<\/p>\n<p style=\"text-align: justify;\"><strong>[139.]<\/strong> Se il Vescovo diocesano ha ministri sacri o altri destinabili a tale funzione, \u00e8 diritto dei fedeli fare spesso visita al Santissimo Sacramento per l\u2019adorazione e prendere parte almeno qualche volta nel corso dell\u2019anno all\u2019adorazione della Santissima Eucaristia esposta.<\/p>\n<p style=\"text-align: justify;\"><strong>[140.]<\/strong> \u00c8 particolarmente raccomandabile che nelle citt\u00e0 o almeno nei comuni di maggiori dimensioni il Vescovo diocesano designi una chiesa per l\u2019adorazione perpetua, in cui per\u00f2 si celebri frequentemente, e per quanto possibile anche quotidianamente, la santa Messa, interrompendo rigorosamente l\u2019esposizione nel momento in cui si svolge la funzione [238]. \u00c8 opportuno che l\u2019ostia da esporre durante l\u2019adorazione sia consacrata nella Messa che precede immediatamente il tempo dell\u2019adorazione e sia posta nell\u2019ostensorio sopra l\u2019altare dopo la Comunione [239].<\/p>\n<p style=\"text-align: justify;\"><strong>[141.]<\/strong> Il Vescovo diocesano riconosca e, secondo le possibilit\u00e0, incoraggi i fedeli nel loro diritto di costituire confraternite ed associazioni per la pratica dell\u2019adorazione anche perpetua. Nei casi in cui tali associazioni assumono indole internazionale, spetta alla Congregazione per il Culto Divino e la Disciplina dei Sacramenti erigerle o approvare i loro statuti [240].<\/p>\n<p style=\"text-align: center;\"><strong>3. Le processioni e i Congressi eucaristici<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[142.]<\/strong> \u00abSpetta al Vescovo diocesano stabilire delle direttive circa le processioni, con cui provvedere alla loro partecipazione e dignit\u00e0\u00bb, [241] e promuovere l\u2019adorazione dei fedeli.<\/p>\n<p style=\"text-align: justify;\"><strong>[143.]<\/strong> \u00abOve, a giudizio del Vescovo diocesano, \u00e8 possibile, si svolga, quale pubblica testimonianza di venerazione verso la Santissima Eucaristia e specialmente nella solennit\u00e0 del Corpo e Sangue di Cristo, la processione condotta attraverso le pubbliche vie\u00bb, [242] perch\u00e9 la devota \u00abpartecipazione dei fedeli alla processione eucaristica nella solennit\u00e0 del Corpo e Sangue di Cristo \u00e8 una grazia del Signore che ogni anno riempie di gioia chi vi partecipa\u00bb\u00a0[243].<\/p>\n<p style=\"text-align: justify;\"><strong>[144.]<\/strong> Bench\u00e9 in alcuni luoghi ci\u00f2 non risulti possibile, occorre tuttavia che non vada perduta la tradizione di svolgere le processioni eucaristiche. Si cerchino, piuttosto, nuove maniere di praticarle nelle circostanze attuali, come ad esempio presso i santuari, all\u2019interno di propriet\u00e0 ecclesiastiche o, con il permesso dell\u2019autorit\u00e0 civile, nei giardini pubblici.<\/p>\n<p style=\"text-align: justify;\"><strong>[145.]<\/strong> Va considerata di grande valore l\u2019utilit\u00e0 pastorale dei Congressi eucaristici, i quali \u00aboccorre siano segno vero di fede e carit\u00e0\u00bb\u00a0[244]. Siano essi preparati con diligenza e svolti secondo quanto stabilito,\u00a0[245] affinch\u00e9 sia dato ai fedeli di venerare i sacri misteri del Corpo e del Sangue del Figlio di Dio in modo da sentire incessantemente in se stessi il frutto della redenzione\u00a0[246].<\/p>\n<p style=\"text-align: center;\"><strong>Capitolo VII<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>I COMPITI STRAORDINARI DEI FEDELI LAICI<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[146.]<\/strong> Il sacerdozio ministeriale non pu\u00f2 essere in nessun modo sostituito. Se, infatti, in una comunit\u00e0 manca il Sacerdote, essa \u00e8 priva dell\u2019esercizio della funzione sacramentale di Cristo, Capo e Pastore, che appartiene all\u2019essenza stessa della vita della comunit\u00e0\u00a0[247]. Infatti, \u00abil ministro, che pu\u00f2 celebrare <em>in persona Christi<\/em> il sacramento dell\u2019Eucaristia, \u00e8 solo il Sacerdote validamente ordinato\u00bb\u00a0[248].<\/p>\n<p style=\"text-align: justify;\"><strong>[147.]<\/strong> Se tuttavia il bisogno della Chiesa lo richiede, in mancanza dei ministri sacri, i fedeli laici possono, a norma del diritto, supplirlo in alcune mansioni liturgiche.\u00a0[249] Questi fedeli sono chiamati e delegati a svolgere determinati compiti, di maggiore e di minore importanza, sostenuti dalla grazia del Signore. Molti fedeli laici si sono gi\u00e0 dedicati e si dedicano tuttora sollecitamente a tale servizio, soprattutto nelle terre di missione, dove la Chiesa ha ancora poca diffusione o si trova in condizioni di persecuzione,\u00a0[250] ma anche in altre regioni colpite dalla scarsit\u00e0 di Sacerdoti e Diaconi.<\/p>\n<p style=\"text-align: justify;\"><strong>[148.]<\/strong> In particolar modo, di grande importanza va considerata l\u2019istituzione dei catechisti, che hanno fornito e forniscono con grande impegno un aiuto unico e assolutamente necessario alla diffusione della fede e della Chiesa\u00a0[251].<\/p>\n<p style=\"text-align: justify;\"><strong>[149.]<\/strong> In alcune diocesi di pi\u00f9 antica evangelizzazione molto di recente sono stati incaricati come \u00abassistenti pastorali\u00bb dei fedeli laici, moltissimi dei quali hanno senza dubbio giovato al bene della Chiesa, sostenendo l\u2019azione pastorale propria del Vescovo, dei Sacerdoti e dei Diaconi. Si badi, tuttavia, che il profilo di tale compito non sia troppo assimilato alla forma del ministero pastorale dei chierici. Si deve, cio\u00e8, curare che gli \u00abassistenti pastorali\u00bb non si assumano funzioni che spettano propriamente al ministero dei sacri ministri.<\/p>\n<p style=\"text-align: justify;\"><strong>[150.]<\/strong> L\u2019attivit\u00e0 dell\u2019assistente pastorale sia volta ad agevolare il ministero dei Sacerdoti e dei Diaconi, suscitare vocazioni al sacerdozio e al diaconato e preparare con zelo, a norma del diritto, i fedeli laici in ciascuna comunit\u00e0 a svolgere i vari compiti liturgici secondo la molteplicit\u00e0 dei carismi.<\/p>\n<p style=\"text-align: justify;\"><strong>[151.]<\/strong> Soltanto in caso di vera necessit\u00e0 si dovr\u00e0 ricorrere all\u2019aiuto dei ministri straordinari nella celebrazione della Liturgia. Ci\u00f2, infatti, non \u00e8 previsto per assicurare una pi\u00f9 piena partecipazione dei laici, ma \u00e8 per sua natura suppletivo e provvisorio\u00a0[252]. Se, inoltre, per necessit\u00e0 si ricorre agli uffici dei ministri straordinari, si moltiplichino le preghiere speciali e continue al Signore, perch\u00e9 mandi presto un Sacerdote al servizio della comunit\u00e0 e susciti con abbondanza le vocazioni agli Ordini sacri\u00a0[253].<\/p>\n<p style=\"text-align: justify;\"><strong>[152.]<\/strong> Tali funzioni meramente sostitutive non risultino, poi, pretesto di alterazione dello stesso ministero dei Sacerdoti, di modo che costoro trascurino la celebrazione della santa Messa per il popolo loro affidato, la personale sollecitudine verso i malati e la premura di battezzare i bambini, assistere ai matrimoni e celebrare le esequie cristiane, le quali spettano anzitutto ai Sacerdoti con l\u2019aiuto dei Diaconi. Non avvenga, pertanto, che i Sacerdoti nelle parrocchie scambino indifferentemente le funzioni di servizio pastorale con i Diaconi o i laici, confondendo in tal modo la specificit\u00e0 di ognuno.<\/p>\n<p style=\"text-align: justify;\"><strong>[153.]<\/strong> Inoltre, non \u00e8 consentito ai laici assumere le funzioni o i paramenti del Diacono o del Sacerdote, n\u00e9 altre vesti simili ad essi.<\/p>\n<p style=\"text-align: center;\"><strong>1. Il ministro straordinario della sacra Comunione<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[154.]<\/strong> Come \u00e8 stato gi\u00e0 ricordato, \u00abministro, in grado di celebrare <em>in persona Christi <\/em>il sacramento dell\u2019Eucaristia, \u00e8 il solo Sacerdote validamente ordinato\u00bb.[254] Perci\u00f2 il nome di \u00abministro dell\u2019Eucaristia\u00bb spetta propriamente al solo Sacerdote. Anche a motivo della sacra Ordinazione, i ministri ordinari della santa Comunione sono i Vescovi, i Sacerdoti e i Diaconi,[255] ai quali, dunque, spetta distribuire la santa Comunione ai fedeli laici nella celebrazione della santa Messa. Si manifesti, cos\u00ec, correttamente e con pienezza il loro compito ministeriale nella Chiesa e si adempia il segno sacramentale.<\/p>\n<p style=\"text-align: justify;\"><strong>[155.]<\/strong> Oltre ai ministri ordinari c\u2019\u00e8 l\u2019accolito istituito, che \u00e8 per istituzione ministro straordinario della santa Comunione anche al di fuori della celebrazione della Messa. Se inoltre ragioni di autentica necessit\u00e0 lo richiedano, il Vescovo diocesano pu\u00f2 delegare, a norma del diritto,\u00a0[256] allo scopo anche un altro fedele laico come ministro straordinario, <em>ad actum<\/em> o <em>ad tempus<\/em>, servendosi nella circostanza della appropriata formula di benedizione. Questo atto di deputazione, tuttavia, non ha necessariamente forma liturgica, n\u00e9 in alcun modo, se la avesse, pu\u00f2 essere assimilato a una sacra Ordinazione. Soltanto in casi particolari e imprevisti, pu\u00f2 essere dato un permesso <em>ad actum<\/em> da parte del Sacerdote che presiede la celebrazione eucaristica\u00a0[257].<\/p>\n<p style=\"text-align: justify;\"><strong>[156.]<\/strong> Questo ufficio venga inteso in senso stretto secondo la sua denominazione di ministro straordinario della santa Comunione, e non \u00abministro speciale della santa Comunione\u00bb o \u00abministro straordinario dell\u2019Eucaristia\u00bb o \u00abministro speciale dell\u2019Eucaristia\u00bb, definizioni che ne amplificano indebitamente e impropriamente la portata.<\/p>\n<p style=\"text-align: justify;\"><strong>[157.]<\/strong> Se \u00e8 di solito presente un numero di ministri sacri sufficiente anche alla distribuzione della santa Comunione, non si possono deputare a questo compito i ministri straordinari della santa Comunione. In simili circostanze, coloro che fossero deputati a tale ministero, non lo esercitino. \u00c8 riprovevole la prassi di quei Sacerdoti che, bench\u00e9 presenti alla celebrazione, si astengono comunque dal distribuire la Comunione, incaricando di tale compito i laici.\u00a0[258]<\/p>\n<p style=\"text-align: justify;\"><strong>[158.]<\/strong> Il ministro straordinario della santa Comunione, infatti, potr\u00e0 amministrare la Comunione soltanto quando mancano il Sacerdote o il Diacono, quando il Sacerdote \u00e8 impedito da malattia, vecchiaia o altro serio motivo o quando il numero dei fedeli che accedono alla Comunione \u00e8 tanto grande che la celebrazione stessa della Messa si protrarrebbe troppo a lungo\u00a0[259] .Tuttavia, ci\u00f2 si ritenga nel senso che andr\u00e0 considerata motivazione del tutto insufficiente un breve prolungamento, secondo le abitudini e la cultura del luogo.<\/p>\n<p style=\"text-align: justify;\"><strong>[159.]<\/strong> Non \u00e8 in nessun modo consentito al ministro straordinario della santa Comunione delegare all\u2019amministrazione dell\u2019Eucaristia qualcun altro, come ad esempio un genitore, il marito o il figlio del malato che si deve comunicare.<\/p>\n<p style=\"text-align: justify;\"><strong>[160.]<\/strong> Il Vescovo diocesano riesamini la prassi degli ultimi anni in materia e la corregga secondo opportunit\u00e0 o la determini con maggior chiarezza. Se per effettiva necessit\u00e0 tali ministri straordinari vengono deputati in maniera estesa, occorre che il Vescovo diocesano pubblichi delle norme particolari, con cui, tenendo presente la tradizione della Chiesa, stabilisca delle direttive a norma del diritto in merito all\u2019esercizio di questo compito.<\/p>\n<p style=\"text-align: center;\"><strong>2. La predicazione<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[161.]<\/strong> Come \u00e8 stato gi\u00e0 detto, l\u2019omelia \u00e8 per la sua importanza e natura riservata al Sacerdote o al Diacono durante la Messa.\u00a0[260] Per quanto attiene ad altre forme di predicazione, se in particolari circostanze la necessit\u00e0 lo richiede o in specifici casi l\u2019utilit\u00e0 lo esige, si possono a norma del diritto ammettere a predicare in chiesa o in un oratorio al di fuori della Messa, i fedeli laici\u00a0[261]. Ci\u00f2 pu\u00f2 avvenire soltanto per l\u2019esiguit\u00e0 del numero di ministri sacri in alcuni luoghi al fine di supplire ad essi e non lo si pu\u00f2 mutare da caso di assoluta eccezionalit\u00e0 a fatto ordinario, n\u00e9 deve essere inteso come autentica promozione del laicato\u00a0[262]. Va, inoltre, ricordato che la facolt\u00e0 di permettere ci\u00f2, sempre <em>ad actum<\/em>, spetta agli Ordinari del luogo e non ad altri, neppure Sacerdoti o Diaconi.<\/p>\n<p style=\"text-align: center;\"><strong>3. Celebrazioni particolari che si svolgono in assenza del Sacerdote<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[162.]<\/strong> La Chiesa, nel giorno che prende il nome di \u00abdomenica\u00bb, si raduna insieme fedelmente per commemorare, specialmente con la celebrazione della Messa, la resurrezione del Signore e tutto il mistero pasquale\u00a0[263]. Infatti, \u00abnessuna comunit\u00e0 cristiana si edifica, se non si radica ed incardina nella celebrazione della Santissima Eucaristia\u00bb\u00a0[264] Il popolo cristiano ha, dunque, il diritto che sia celebrata l\u2019Eucaristia in proprio favore la domenica, nelle feste di precetto, negli altri giorni principali di festa e, per quanto possibile, anche quotidianamente. Se, pertanto, di domenica in una parrocchia o altra comunit\u00e0 di fedeli \u00e8 difficile avere la celebrazione della Messa, il Vescovo diocesano valuti insieme con il presbiterio gli opportuni rimedi [265].\u00a0Tra queste soluzioni, le principali saranno quelle di chiamare altri Sacerdoti allo scopo o che i fedeli vadano nella chiesa di un luogo vicino per prendervi parte al mistero eucaristico\u00a0[266].<\/p>\n<p style=\"text-align: justify;\"><strong>[163.]<\/strong> Tutti i Sacerdoti, ai quali sono stati affidati il sacerdozio e l\u2019Eucaristia \u00abper il bene\u00bb degli altri,\u00a0[267] abbiano a mente che \u00e8 loro dovere offrire a tutti i fedeli l\u2019opportunit\u00e0 di poter soddisfare il precetto di prendere parte alla Messa di domenica [268]. Per parte loro, i fedeli laici hanno il diritto che nessun Sacerdote, se non in presenza di effettiva impossibilit\u00e0, si rifiuti mai di celebrare la Messa per il popolo o rifiuti che essa sia celebrata da un altro, se non si pu\u00f2 soddisfare in altro modo il precetto di prendere parte alla Messa di domenica e negli altri giorni stabiliti.<\/p>\n<p style=\"text-align: justify;\"><strong>[164.]<\/strong> \u00abSe per la mancanza del ministro sacro o per altra grave causa diventa impossibile la partecipazione alla celebrazione eucaristica\u00bb,\u00a0[269] il popolo cristiano ha il diritto che il Vescovo diocesano provveda, secondo le possibilit\u00e0, che sia compiuta una celebrazione per la comunit\u00e0 stessa la domenica sotto la propria autorit\u00e0 e secondo le norme stabilite dalla Chiesa. Tali celebrazioni domenicali, tuttavia, vanno sempre considerate del tutto straordinarie. Pertanto, sar\u00e0 cura di tutti, sia Diaconi sia fedeli laici, ai quali \u00e8 assegnato un compito da parte del Vescovo diocesano all\u2019interno di tali celebrazioni, \u00abmantenere viva nella comunit\u00e0 una vera \u201cfame\u201d dell\u2019Eucaristia, che conduca a non perdere nessuna occasione di avere la celebrazione della Messa, anche approfittando della presenza occasionale di un Sacerdote non impedito a celebrarla dal diritto della Chiesa\u00bb.\u00a0[270]<\/p>\n<p style=\"text-align: justify;\"><strong>[165.]<\/strong> Occorre evitare con cura ogni forma di confusione tra questo tipo di riunioni e la celebrazione eucaristica.\u00a0[271] I Vescovi diocesani, pertanto, valutino con prudenza se in tali riunioni si debba distribuire la santa Comunione. Per un pi\u00f9 ampio coordinamento, la questione sia opportunamente determinata nell\u2019ambito della Conferenza dei Vescovi, in modo da pervenire a una risoluzione, con la conferma da parte della Sede Apostolica, mediante la Congregazione per il Culto Divino e la Disciplina dei Sacramenti. Sar\u00e0 preferibile, inoltre, in assenza del Sacerdote e del Diacono, che le varie parti siano distribuite tra pi\u00f9 fedeli anzich\u00e9 sia un solo fedele laico a guidare l\u2019intera celebrazione. In nessun caso \u00e8 appropriato dire che un fedele laico \u00abpresiede\u00bb la celebrazione.<\/p>\n<p style=\"text-align: justify;\"><strong>[166.]<\/strong> Parimenti, il Vescovo diocesano, al quale soltanto spetta la questione, non conceda con facilit\u00e0 che tali celebrazioni, soprattutto se in esse si distribuisce anche la santa Comunione, avvengano nei giorni feriali e soprattutto in luoghi in cui si \u00e8 potuto o si potr\u00e0 celebrare la Messa la domenica precedente o successiva. I Sacerdoti sono fermamente pregati di celebrare, secondo le possibilit\u00e0, quotidianamente la santa Messa per il popolo in una delle chiese a loro affidate.<\/p>\n<p style=\"text-align: justify;\"><strong>[167.]<\/strong> \u00abSimilmente, non si pu\u00f2 pensare di sostituire la santa Messa domenicale con celebrazioni ecumeniche della Parola o con incontri di preghiera in comune con cristiani appartenenti alle [\u2026] Comunit\u00e0 ecclesiali, oppure con la partecipazione ai loro riti liturgici\u00bb [272]. Se poi il Vescovo diocesano, spinto da necessit\u00e0, ha permesso <em>ad actum<\/em> la partecipazione dei cattolici, i pastori badino che tra i fedeli cattolici non si ingeneri confusione quanto alla necessit\u00e0 di prendere parte anche in queste occasioni alla Messa di precetto, in un\u2019altra ora della giornata\u00a0[273].<\/p>\n<p style=\"text-align: center;\"><strong style=\"text-align: justify;\">4. Coloro che sono stati dimessi dallo stato clericale<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[168.]<\/strong> Al \u00abchierico che a norma del diritto perde lo stato clericale [\u2026] \u00e8 proibito esercitare la potest\u00e0 di ordine\u00bb.\u00a0[274] A costui, pertanto, non \u00e8 consentito celebrare sotto alcun pretesto i sacramenti, salvo esclusivamente il caso di eccezionalit\u00e0 previsto dal diritto\u00a0[275], n\u00e9 \u00e8 consentito ai fedeli ricorrere a lui per la celebrazione, quando non vi \u00e8 giusta causa che permetta ci\u00f2 a norma del can. 1335\u00a0[276]. Tali persone, inoltre, non tengano l\u2019omelia,\u00a0[277] n\u00e9 assumano mai alcun incarico o compito nella celebrazione della sacra Liturgia, di modo che non si ingeneri confusione tra i fedeli e non ne risulti offuscata la verit\u00e0.<\/p>\n<p style=\"text-align: center;\"><strong>Capitolo VIII<\/strong><\/p>\n<p style=\"text-align: center;\"><strong>I RIMEDI<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[169.]<\/strong> Quando si compie un abuso nella celebrazione della sacra Liturgia, si opera un\u2019autentica contraffazione della Liturgia cattolica. Ha scritto san Tommaso: \u00abincorre nel vizio di falsificazione chi per conto della Chiesa manifesta a Dio un culto contro la modalit\u00e0 istituita per autorit\u00e0 divina dalla Chiesa e consueta in essa\u00bb.[278]<\/p>\n<p style=\"text-align: justify;\"><strong>[170.]<\/strong> Al fine di porre rimedio a tali abusi, ci\u00f2 \u00abche in sommo grado urge \u00e8 la formazione biblica e liturgica del popolo di Dio, dei pastori e dei fedeli\u00bb,\u00a0[279] di modo che la fede e la disciplina della Chiesa in merito alla sacra Liturgia siano correttamente presentate e comprese. Se tuttavia gli abusi persistono, occorrer\u00e0 procedere, a norma del diritto, a tutela del patrimonio spirituale e dei diritti della Chiesa, facendo ricorso a tutti i mezzi legittimi.<\/p>\n<p style=\"text-align: justify;\"><strong>[171.]<\/strong> Tra i vari abusi vi sono quelli che costituiscono obiettivamente <em>graviora delicta<\/em>, gli atti gravi e altri che vanno nondimeno evitati e attentamente corretti. Tenendo conto di tutto ci\u00f2 che \u00e8 stato in particolar modo trattato nel Capitolo I di questa Istruzione, occorrer\u00e0 prestare ora attenzione a quanto segue.<\/p>\n<p style=\"text-align: center;\"><strong><em>1. Graviora delicta<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[172.]<\/strong> I <em>graviora delicta<\/em> contro la santit\u00e0 del Santissimo Sacrificio e sacramento dell\u2019Eucaristia vanno trattati seguendo le \u00abNorme relative ai <em>graviora delicta<\/em> riservati alla Congregazione per la Dottrina della Fede\u00bb,<span style=\"color: #1772af;\"><span style=\"background-color: #d5d5d5;\">\u00a0<\/span><\/span>[280] vale a dire:<\/p>\n<p style=\"text-align: justify;\">a) sottrazione o ritenzione a fine sacrilego o il gettar via le specie consacrate;\u00a0[281]<\/p>\n<p style=\"text-align: justify;\">b) tentata azione liturgica del Sacrificio eucaristico o sua simulazione; [282]<\/p>\n<p style=\"text-align: justify;\">c) concelebrazione proibita del Sacrificio eucaristico insieme a ministri di Comunit\u00e0 ecclesiali i quali non hanno la successione apostolica, n\u00e9 riconoscono la dignit\u00e0 sacramentale dell\u2019ordinazione sacerdotale;\u00a0[283]<\/p>\n<p style=\"text-align: justify;\">d) consacrazione a fine sacrilego di una materia senza l\u2019altra nella celebrazione eucaristica o anche di entrambe al di fuori della celebrazione eucaristica.\u00a0[284]<\/p>\n<p style=\"text-align: center;\"><strong>2. Atti gravi<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[173.]<\/strong> Sebbene il giudizio sulla gravit\u00e0 della questione vada formulato secondo la dottrina comune della Chiesa e le norme da essa stabilite, come atti gravi vanno sempre obiettivamente considerati quelli che mettono a rischio la validit\u00e0 e dignit\u00e0 della Santissima Eucaristia, ovvero quelli che contrastano con i casi precedentemente illustrati ai nn. 48-52, 56, 76-77, 79, 91-92, 94, 96, 101-102, 104, 106, 109, 111, 115, 117, 126, 131-133, 138, 153 e 168. Si deve, inoltre, fare attenzione alle prescrizioni del Codice di Diritto Canonico e in particolare a quanto stabilito dai cann. 1364, 1369, 1373, 1376, 1380, 1384, 1385, 1386 e 1398.<\/p>\n<p style=\"text-align: center;\"><strong>3. Altri abusi<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[174.]<\/strong> Inoltre, le azioni commesse contro quelle norme, di cui si tratta altrove in questa Istruzione e nelle norme stabilite dal diritto, non vanno considerate con leggerezza, ma le si annoveri tra gli altri abusi da evitare e correggere con sollecitudine.<\/p>\n<p style=\"text-align: justify;\"><strong>[175.]<\/strong> Quanto esposto nella presente Istruzione, come risulta chiaro, non riporta tutte le violazioni contro la Chiesa e la sua disciplina, quali sono definite nei canoni, nelle leggi liturgiche e nelle altre norme della Chiesa secondo la dottrina del Magistero o la sana tradizione. Se qualche errore viene commesso, andr\u00e0 corretto a norma del diritto.<\/p>\n<p style=\"text-align: center;\"><strong>4. Il Vescovo diocesano<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[176.]<\/strong> Il Vescovo diocesano, \u00abessendo il principale dispensatore dei misteri di Dio, si adoperi di continuo perch\u00e9 i fedeli affidati alle sue cure crescano in grazia mediante la celebrazione dei sacramenti e perch\u00e9 conoscano e vivano il mistero pasquale\u00bb.\u00a0[285] A lui spetta, \u00abentro i limiti della sua competenza, dare norme in materia liturgica, alle quali tutti sono tenuti\u00bb.\u00a0[286]<\/p>\n<p style=\"text-align: justify;\"><strong>[177.]<\/strong> \u00abPoich\u00e9 deve difendere l\u2019unit\u00e0 della Chiesa universale, il Vescovo \u00e8 tenuto a promuovere la disciplina comune a tutta la Chiesa e perci\u00f2 a urgere l\u2019osservanza di tutte le leggi ecclesiastiche. Vigili che non si insinuino abusi nella disciplina ecclesiastica, soprattutto nel ministero della parola, nella celebrazione dei sacramenti e dei sacramentali, nel culto di Dio e dei Santi\u00bb\u00a0[287]<\/p>\n<p style=\"text-align: justify;\"><strong>[178.]<\/strong> Pertanto, ogni qualvolta l\u2019Ordinario del luogo o di un Istituto religioso oppure di una Societ\u00e0 di vita apostolica abbia notizia, quanto meno verosimile, a proposito di un delitto o di un abuso riguardante la Santissima Eucaristia, indaghi con cautela, in prima persona o mediante altro chierico idoneo, sui fatti, le circostanze e l\u2019imputabilit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>[179.]<\/strong> I delitti contro la fede e i <em>graviora delicta<\/em> commessi durante la celebrazione dell\u2019Eucaristia e degli altri sacramenti siano segnalati senza indugio alla Congregazione per la Dottrina della Fede, che li esamina \u00abe, all\u2019occorrenza, procede a dichiarare o ad infliggere le sanzioni canoniche a norma del diritto, sia comune che proprio\u00bb.\u00a0[288]<\/p>\n<p style=\"text-align: justify;\"><strong>[180.]<\/strong> Diversamente, l\u2019Ordinario proceda a norma dei sacri canoni, applicando, ove fosse il caso, le pene canoniche e tenendo presente in modo particolare quanto stabilito dal can. 1326. Qualora si tratti di azioni gravi, informi la Congregazione per il Culto Divino e la Disciplina dei Sacramenti.<\/p>\n<p style=\"text-align: center;\"><strong>5. La Sede Apostolica<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[181.]<\/strong> Ogni qualvolta la Congregazione per il Culto Divino e la Disciplina dei Sacramenti ha notizia, quanto meno verosimile, di un delitto o abuso relativo alla Santissima Eucaristia, ne informa l\u2019Ordinario, affinch\u00e9 indaghi sul fatto. Qualora esso risulti grave, l\u2019Ordinario invii al pi\u00f9 presto allo stesso Dicastero un esemplare degli atti relativi all\u2019indagine eseguita e, eventualmente, sulla pena inflitta.<\/p>\n<p style=\"text-align: justify;\"><strong>[182.]<\/strong> Nei casi di maggiore difficolt\u00e0 l\u2019Ordinario non trascuri per il bene della Chiesa universale, della cui sollecitudine anche egli partecipa in virt\u00f9 della sacra Ordinazione, di trattare la questione dopo avere consultato il parere della Congregazione per il Culto Divino e la Disciplina dei Sacramenti. Da parte sua, questa Congregazione, in virt\u00f9 delle facolt\u00e0 ad essa concesse dal Romano Pontefice, sosterr\u00e0 l\u2019Ordinario secondo il caso, accordandogli le necessarie dispense\u00a0[289] o comunicandogli istruzioni e prescrizioni, alle quali egli ottemperi con diligenza.<\/p>\n<p style=\"text-align: center;\"><strong>6. Segnalazioni di abusi in materia liturgica<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[183.]<\/strong> In modo assolutamente particolare tutti, secondo le possibilit\u00e0, facciano s\u00ec che il Santissimo Sacramento dell\u2019Eucaristia sia custodito da ogni forma di irriverenza e aberrazione e tutti gli abusi vengano completamente corretti. Questo \u00e8 compito della massima importanza per tutti e per ciascuno, e tutti sono tenuti a compiere tale opera, senza alcun favoritismo.<\/p>\n<p style=\"text-align: justify;\"><strong>[184.]<\/strong> Ogni cattolico, sia Sacerdote sia Diacono sia fedele laico, ha il diritto di sporgere querela su un abuso liturgico presso il Vescovo diocesano o l\u2019Ordinario competente a quegli equiparato dal diritto o alla Sede Apostolica in virt\u00f9 del primato del Romano Pontefice.\u00a0[290] \u00c8 bene, tuttavia, che la segnalazione o la querela sia, per quanto possibile, presentata dapprima al Vescovo diocesano. Ci\u00f2 avvenga sempre con spirito di verit\u00e0 e carit\u00e0.<\/p>\n<p style=\"text-align: center;\"><strong>Conclusione<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[185.]<\/strong> \u00abAi germi di disgregazione tra gli uomini, che l\u2019esperienza quotidiana mostra tanto radicati nell\u2019umanit\u00e0 a causa del peccato, si contrappone la forza generatrice di unit\u00e0 del corpo di Cristo. L\u2019Eucaristia, costruendo la Chiesa, proprio per questo crea comunit\u00e0 fra gli uomini\u00bb.[291] Pertanto, questa Congregazione per il Culto Divino e la Disciplina dei Sacramenti si augura che, anche mediante l\u2019attenta applicazione di quanto richiamato alla mente nella presente Istruzione, l\u2019umana fragilit\u00e0 intralci in misura minore l\u2019azione del Santissimo Sacramento dell\u2019Eucaristia e, rimossa ogni irregolarit\u00e0, bandito ogni uso riprovato, per intercessione della Beata Vergine Maria, \u00abdonna eucaristica\u00bb,\u00a0[292] la presenza salvifica di Cristo nel Sacramento del suo Corpo e del suo Sangue risplenda su tutti gli uomini.<\/p>\n<p style=\"text-align: justify;\"><strong>[186.]<\/strong> Tutti i fedeli partecipino, secondo le possibilit\u00e0, pienamente, consapevolmente e attivamente alla Santissima Eucaristia,\u00a0[293] la venerino con tutto il cuore nella devozione e nella vita. I Vescovi, i Sacerdoti e i Diaconi, nell\u2019esercizio del sacro ministero, si interroghino in coscienza sulla autenticit\u00e0 e sulla fedelt\u00e0 delle azioni da loro compiute a nome di Cristo e della Chiesa nella celebrazione della sacra Liturgia. Ogni ministro sacro si interroghi, anche con severit\u00e0, se ha rispettato i diritti dei fedeli laici, che affidano a lui con fiducia se stessi e i loro figli, nella convinzione che tutti svolgono correttamente per i fedeli quei compiti che la Chiesa, per mandato di Cristo, intende adempiere nel celebrare la sacra Liturgia\u00a0[294]. Ciascuno ricordi sempre, infatti, di essere servitore della sacra Liturgia\u00a0[295].<\/p>\n<p style=\"text-align: justify;\">Nonostante qualunque cosa in contrario.<\/p>\n<p style=\"text-align: justify;\"><em>Questa Istruzione, redatta, per disposizione del Sommo Pontefice Giovanni Paolo II, dalla Congregazione per il Culto Divino e la Disciplina dei Sacramenti d\u2019intesa con la Congregazione per la Dottrina della Fede, \u00e8 stata approvata dallo stesso Pontefice il 19 marzo 2004, nella solennit\u00e0 di san Giuseppe, il quale ne ha disposto la pubblicazione e l\u2019immediata osservanza da parte di tutti coloro a cui spetta.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Roma, dalla Congregazione per il Culto Divino e la Disciplina dei Sacramenti, il 25 marzo 2004, nella solennit\u00e0 dell\u2019Annunciazione del Signore.<\/em><\/p>\n<p style=\"text-align: right;\"><strong>Francis Card. Arinze<\/strong><\/p>\n<p style=\"text-align: right;\"><em>Prefetto<\/em><\/p>\n<p style=\"text-align: right;\"><strong>Domenico Sorrentino<\/strong><\/p>\n<p style=\"text-align: right;\"><em>Arcivescovo Segretario<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>NOTE<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>[1]<\/strong> Cf. Missale Romanum,\u00a0<em>ex decreto sacrosancti Oecumenici Concilii Vaticani II instauratum, auctoritate Pauli Pp. VI promulgatum, Ioannis Pauli Pp. II cura recognitum<\/em>, editio typica tertia, diei 20 aprilis 2000, Typis Vaticanis, 2002, Missa votiva de Dei misericordia, oratio super oblata, p. 1159.<\/p>\n<p style=\"text-align: justify;\"><strong>[2]<\/strong> Cf. <em>1 Cor<\/em> 11, 26; Missale Romanum, Prex Eucharistica, acclamatio post consecrationem, p. 576; Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, 17 aprile 2003, nn. 5, 11, 14, 18: AAS 95 (2003) pp. 436, 440-441, 442, 445.<\/p>\n<p style=\"text-align: justify;\"><strong>[3]<\/strong> Cf. <em>Is <\/em>10, 33; 51, 22; Missale Romanum, In sollemnitate Domini nostri Iesu Christi, universorum Regis, Praefatio, p. 499.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.vatican.va\/roman_curia\/congregations\/ccdds\/documents\/rc_con_ccdds_doc_20040423_redemptionis-sacramentum_it.html#_ftnref4\"><strong>[4]<\/strong><\/a> Cf.<em>1 Cor<\/em> 5, 7; Conc. Ecum. Vat. II, Decr. sul ministero e la vita dei sacerdoti, <em>Presbyterorum ordinis<\/em>, 7 dicembre 1965, n. 5; Giovanni Paolo II, Esort. Apost., <em>Ecclesia in Europa<\/em>, 28 giugno 2003, n. 75: AAS 95 (2003) pp. 649-719, qui p. 693.<\/p>\n<p style=\"text-align: justify;\"><strong>[5]<\/strong> Cf. Conc. Ecum. Vat. II, Cost. dogm. sulla Chiesa, <em>Lumen gentium<\/em>, 21 novembre 1964, n. 11.<\/p>\n<p style=\"text-align: justify;\"><strong>[6]<\/strong> Cf. Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, 17 aprile 2003, n. 21: AAS 95 (2003) p. 447.<\/p>\n<p style=\"text-align: justify;\"><strong>[7]<\/strong> Cf. <em>Ibidem<\/em>: AAS 95 (2003) pp. 433-475.<\/p>\n<p style=\"text-align: justify;\"><strong>[8]<\/strong> Cf. <em>Ibidem<\/em>, n. 52: AAS 95 (2003) p. 468.<\/p>\n<p style=\"text-align: justify;\"><strong>[9]<\/strong> Cf. <em>Ibidem<\/em>.<\/p>\n<p style=\"text-align: justify;\"><strong>[10]<\/strong><em> Ibidem<\/em>, n. 10: AAS 95 (2003) p. 439.<\/p>\n<p style=\"text-align: justify;\"><strong>[11]<\/strong><em> Ibidem<\/em>;cf. Giovanni Paolo II,Lett. Apost., <em>Vicesimus quintus annus<\/em>, 4 dicembre 1988, nn. 12-13: AAS 81 (1989) pp. 909-910; cf. anche Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, 4 dicembre 1963, n. 48.<\/p>\n<p style=\"text-align: justify;\"><strong>[12]<\/strong> Missale Romanum, Prex Eucharistica III, p. 588; cf. <em>1 Cor<\/em> 12, 12-13; <em>Ef<\/em> 4, 4.<\/p>\n<p style=\"text-align: justify;\"><strong>[13]<\/strong> Cf. <em>Fil<\/em> 2, 5.<\/p>\n<p style=\"text-align: justify;\"><strong>[14]<\/strong> Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 10: AAS 95 (2003) p. 439.<\/p>\n<p style=\"text-align: justify;\"><strong>[15]<\/strong><em> Ibidem<\/em>, n. 6: AAS 95 (2003) p. 437; cf.\u00a0<em>Lc<\/em>\u00a024, 31.<\/p>\n<p style=\"text-align: justify;\"><strong>[16]<\/strong> Cf. <em>Rm<\/em> 1, 20.<\/p>\n<p style=\"text-align: justify;\"><strong>[17]<\/strong> Cf. Missale Romanum, Praefatio I de Passione Domini, p. 528.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #1772af;\"><span style=\"background-color: #d5d5d5;\">[<\/span><\/span><strong>18]<\/strong> Cf. Giovanni Paolo II, Lett. Enc., <em>Veritatis splendor<\/em>, 6 agosto 1993, n. 35: AAS 85 (1993) pp. 1161-1162; Giovanni Paolo II, Omelia tenuta presso Camden Yards, 9 ottobre 1995, n. 7: <em>Insegnamenti di Giovanni Paolo II<\/em>, XVII, 2 (1995), Libreria Editrice Vaticana, 1998, p. 788.<\/p>\n<p style=\"text-align: justify;\"><strong>[19]<\/strong> Cf. Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 10: AAS 95 (2003) p. 439.<\/p>\n<p style=\"text-align: justify;\"><strong>[20]<\/strong> Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 24; cf. Congr. per il Culto Div. e la Disc. dei Sacram., Istr., <em>Varietates legitimae<\/em>, 25 gennaio 1994, nn. 19 e 23: AAS 87 (1995) pp. 295-296, 297.<\/p>\n<p style=\"text-align: justify;\"><strong>[21]<\/strong> Cf. Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 33.<\/p>\n<p style=\"text-align: justify;\"><strong>[22]<\/strong> Cf. S. Ireneo, <em>Adversus Haereses<\/em>, III, 2: SCh., 211, 24-31; S. Agostino, <em>Epistula ad Ianuarium<\/em>, 54, I: PL 33, 200: \u00abIlla autem quae non scripta, sed tradita custodimus, quae quidem toto terrarum orbe servantur, datur intellegi vel ab ipsis Apostolis, vel plenariis conciliis, quorum est in Ecclesia saluberrima auctoritas, commendata atque statuta retineri\u00bb; Giovanni Paolo II, Lett. Enc., <em>Redemptoris missio<\/em>, 7 dicembre 1990, nn. 53-54: AAS 83 (1991) pp. 300-302; Congr. per la Dottr. della Fede, Lett. ai Vescovi della Chiesa Cattolica su alcuni aspetti della Chiesa intesa come comunione, <em>Communionis notio<\/em>, 28 maggio 1992, nn. 7-10: AAS 85 (1993) pp. 842-844; Congr. per il Culto Div. e la Disc. dei Sacram., Istr.,<em>Varietates legitimae<\/em>, n. 26: AAS 87 (1995) pp. 298-299.<\/p>\n<p style=\"text-align: justify;\"><strong>[23]<\/strong> Cf. Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 21.<\/p>\n<p style=\"text-align: justify;\"><strong>[24]<\/strong> Cf. Pio XII, Cost. Ap., <em>Sacramentum Ordinis<\/em>, 30 novembre 1947: AAS 40 (1948) p. 5; Congr. per la Dottr. della Fede, Dichiar., <em>Inter insigniores<\/em>, 15 ottobre 1976, parte IV: AAS 69 (1977) pp. 107-108; Congr. per il Culto Div. e la Disc. dei Sacram., Istr., <em>Varietates legitimae<\/em>, n. 25: AAS 87 (1995) p. 298.<\/p>\n<p style=\"text-align: justify;\"><strong>[25]<\/strong> Cf. Pio XII, Lett. Enc., <em>Mediator Dei<\/em>, 20 novembre 1947: AAS 39 (1947) p. 540.<\/p>\n<p style=\"text-align: justify;\"><strong>[26]<\/strong> Cf. S. Congr. per i Sacram. e per il Culto Div., Istr., <em>Inaestimabile donum<\/em>, 3aprilis 1980: AAS 72 (1980) p. 333.<\/p>\n<p style=\"text-align: justify;\"><strong>[27]<\/strong> Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>,<em>\u00a0<\/em>n. 52: AAS 95 (2003) p. 468<\/p>\n<p style=\"text-align: justify;\"><strong>[28]<\/strong> Cf. Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia,<em> Sacrosanctum Concilium<\/em>, nn. 4, 38; Decr. sulle Chiese Orientali Cattoliche, <em>Orientalium Ecclesiarum<\/em>, 21 novembre 1964, nn. 1, 2, 6; Paolo VI, Cost. Ap., <em>Missale Romanum<\/em>: AAS 61 (1969) pp. 217-222; Missale Romanum, Institutio Generalis, n. 399; Congr. per il Culto Div. e la Disc. dei Sacram., Istr., <em>Liturgiam authenticam<\/em>, 28 marzo 2001, n. 4: AAS 93 (2001) pp. 685-726, qui p. 686.<\/p>\n<p style=\"text-align: justify;\"><strong>[29 ]<\/strong>Cf. Giovanni Paolo II, Esort. Ap., <em>Ecclesia in Europa<\/em>, n. 72: AAS 95 (2003) p. 692.<\/p>\n<p style=\"text-align: justify;\"><strong>[30]<\/strong> Cf. Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, 25 maggio 1967, n. 23: AAS 95 (2003) pp. 448-449; S. Congr. dei Riti, Istr., <em>Eucharisticum mysterium<\/em>, 25 maggio 1967, n. 6: AAS 59 (1967) p. 545.<\/p>\n<p style=\"text-align: justify;\"><strong>[31]<\/strong> Cf. S. Congr. per i Sacram. e per il Culto Div., Istr., <em>Inaestimabile donum<\/em>: AAS 72 (1980) pp. 332-333.<\/p>\n<p style=\"text-align: justify;\"><strong>[32]<\/strong> Cf. <em>1 Cor<\/em> 11, 17-34; Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 52: AAS 95 (2003) pp. 467-468.<\/p>\n<p style=\"text-align: justify;\"><strong>[33]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>, 25 gennaio 1983, can. 1752.<\/p>\n<p style=\"text-align: justify;\"><strong>[34]<\/strong> Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia,<em> Sacrosanctum Concilium<\/em>, n. 22 \u00a7 1. Cf.<em>Codice di Diritto Canonico<\/em>, can. 838 \u00a7 1.<\/p>\n<p style=\"text-align: justify;\"><strong>[35]<\/strong><em> Codice di Diritto Canonico<\/em>,can. 331; cf. Conc. Ecum. Vat. II, Cost. dogm. sulla Chiesa, <em>Lumen gentium<\/em>, n. 22.<\/p>\n<p style=\"text-align: justify;\"><strong>[36]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>, can. 838 \u00a7 2.<\/p>\n<p style=\"text-align: justify;\"><strong>[37]<\/strong> Giovanni Paolo II, Cost. Ap., <em>Pastor bonus<\/em>, 28 giugno 1988: AAS 80 (1988) pp. 841-924; qui artt. 62, 63, e 66, pp. 876-877.<\/p>\n<p style=\"text-align: justify;\"><strong>[38]<\/strong> Cf. Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 52: AAS 95 (2003) p. 468.<\/p>\n<p style=\"text-align: justify;\"><strong>[39]<\/strong> Cf. Conc. Ecum. Vat. II, Decr. sull\u2019ufficio pastorale dei Vescovi nella Chiesa, <em>Christus Dominus<\/em>, 28 ottobre 1965, n. 15; cf. anche Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 41; <em>Codice di Diritto Canonico<\/em>,can. 387.<\/p>\n<p style=\"text-align: justify;\"><strong>[40]<\/strong> Orazione per la consacrazione episcopale nel rito bizantino:\u00a0<em>Euchologion to mega<\/em>, Roma, 1873, p. 139.<\/p>\n<p style=\"text-align: justify;\"><strong>[41]<\/strong> Cf. S. Ignazio di Antiochia, <em>Ad Smyrn.<\/em>8, 1: ed. F.X. Funk, I, p. 282.<\/p>\n<p style=\"text-align: justify;\"><strong>[42]<\/strong> Conc. Ecum. Vat. II, Cost. dogm. sulla Chiesa, <em>Lumen gentium<\/em>, n. 26; cf. S. Congr. dei Riti, Istr., <em>Eucharisticum mysterium<\/em>, n. 7: AAS 59 (1967) p. 545; cf. anche Giovanni Paolo II, Esort. Ap., <em>Pastores gregis<\/em>, 16 ottobre 2003, nn. 32-41: <em>L\u2019 Osservatore romano<\/em>, 17 ottobre 2003, pp. 6-8.<\/p>\n<p style=\"text-align: justify;\"><strong>[43]<\/strong> Cf. Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 41; cf. S. Ignazio di Antiochia, <em>Ad Magn.<\/em> 7; <em>Ad Philad.<\/em> 4; <em>Ad Smyrn.<\/em> 8: ed. F.X. Funk, I, pp. 236, 266, 281; Missale Romanum, Institutio Generalis, n. 22; cf. anche<em> Codice di Diritto Canonico<\/em>,can. 389.<\/p>\n<p style=\"text-align: justify;\"><strong>[44]<\/strong> Conc. Ecum. Vat. II, Cost. dogm. sulla Chiesa, <em>Lumen gentium<\/em>, n. 26.<\/p>\n<p style=\"text-align: justify;\"><strong>[45]<\/strong><em> Codice di Diritto Canonico<\/em>, can. 838 \u00a7 4.<\/p>\n<p style=\"text-align: justify;\"><strong>[46]<\/strong> Cf. Cons. ad exsequ. Const. Lit., Dubium: <em>Notitiae<\/em> 1 (1965) p. 254.<\/p>\n<p style=\"text-align: justify;\"><strong>[47]<\/strong> Cf. <em>At<\/em> 20, 28; Conc. Ecum. Vat. II, Cost. dogm.sulla Chiesa, <em>Lumen<\/em> <em>gentium<\/em>, nn. 21 e 27; Decr. sull\u2019ufficio pastorale dei Vescovi nella Chiesa, <em>Christus<\/em> <em>Dominus<\/em>, n. 3.<\/p>\n<p style=\"text-align: justify;\"><strong>[48]<\/strong> Cf. S. Congr. per il Culto Div., Istr., <em>Liturgicae instaurationes<\/em>, 5 settembre 1970: AAS 62 (1970) p. 694.<\/p>\n<p style=\"text-align: justify;\"><strong>[49]<\/strong> Cf. Conc. Ecum. Vat. II, Cost. dogm.sulla Chiesa, <em>Lumen<\/em> <em>gentium<\/em>, n. 21; Decr. sull\u2019ufficio pastorale dei Vescovi nella Chiesa, <em>Christus<\/em> <em>Dominus<\/em>, n. 3.<\/p>\n<p style=\"text-align: justify;\"><strong>[50]<\/strong> Cf. Caeremoniale Episcoporum <em>ex decreto sacrosancti Oecumenici Concilii Vaticani II instauratum, auctoritate Ioannis Pauli Pp. II promulgatum<\/em>,<em> e<\/em>ditio typica, diei 14 septembris 1984, Typis Polyglottis Vaticanis, 1985, n. 10.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #1772af;\"><span style=\"background-color: #d5d5d5;\">[<\/span><\/span><strong>51]<\/strong> Cf. Missale Romanum, Institutio Generalis, n. 387.<\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #1772af;\"><span style=\"background-color: #d5d5d5;\">[<\/span><\/span><strong>52]<\/strong> Cf. <em>ibidem<\/em>, n. 22.<\/p>\n<p style=\"text-align: justify;\"><strong>[53]<\/strong> Cf. S. Congr. per il Culto Div., Istr., <em>Liturgicae instaurationes<\/em>: AAS 62 (1970) p. 694.<\/p>\n<p style=\"text-align: justify;\"><strong>[54]<\/strong> Conc. Ecum. Vat. II, Cost. dogm. sulla Chiesa, <em>Lumen gentium<\/em>, n. 27; cf. <em>2 Cor <\/em>4, 15.<\/p>\n<p style=\"text-align: justify;\"><strong>[55]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>, cann. 397 \u00a7 1; 678 \u00a7 1.<\/p>\n<p style=\"text-align: justify;\"><strong>[56]<\/strong> Cf. <em>ibidem<\/em>, can. 683 \u00a7 1.<\/p>\n<p style=\"text-align: justify;\"><strong>[57]<\/strong> Cf. <em>ibidem<\/em>, can. 392.<\/p>\n<p style=\"text-align: justify;\"><strong>[58]<\/strong> Cf. Giovanni Paolo II, Lett. Ap., <em>Vicesimus quintus annus<\/em>, n. 21: AAS 81 (1989) p. 917; Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, nn. 45-46; Pio XII, Lett. Enc., <em>Mediator Dei<\/em>: AAS 39 (1947) p. 562.<\/p>\n<p style=\"text-align: justify;\"><strong>[59]<\/strong> Cf. Giovanni Paolo II, Lett. Apost., <em>Vicesimus quintus annus<\/em>, n. 20: AAS 81 (1989) p. 916.<\/p>\n<p style=\"text-align: justify;\"><strong>[60]<\/strong> Cf. <em>ibidem<\/em>.<\/p>\n<p style=\"text-align: justify;\"><strong>[61]<\/strong> Cf. Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 44; Congr. per i Vescovi, Lett. ai Presidenti delle Conferenze dei Vescovi inviata anche a nome della Congr. per l\u2019Evangelizzazione dei Popoli, 21 giugno 1999, n. 9: AAS 91 (1999) p. 999.<\/p>\n<p style=\"text-align: justify;\"><strong>[62]<\/strong> Cf. Congr. per il Culto Div., Istr., <em>Liturgicae instaurationes<\/em>, n. 12: AAS 62 (1970) pp. 692-704, qui p. 703.<\/p>\n<p style=\"text-align: justify;\"><strong>[63]<\/strong> Cf. Congr. per il CultoDiv., <em>Dichiarazione circa le Preghiere eucaristiche e gli esperimenti liturgici<\/em>, 21 marzo 1988: <em>Notitiae<\/em> 24 (1988) pp. 234-236.<\/p>\n<p style=\"text-align: justify;\"><strong>[64]<\/strong> Cf. Congr. per il Culto Div. e la Disc. dei Sacram., Istr., <em>Varietates legitimae<\/em>: AAS 87 (1995) pp. 288-314.<\/p>\n<p style=\"text-align: justify;\"><strong>[65]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>,can. 838 \u00a7 3; S. Congr. dei Riti, Istr. <em>Inter Oecumenici<\/em>, 26 settembre 1964, n. 31: AAS 56 (1964) p. 883; Congr. per il Culto Div. e la Disc. dei Sacram., Istr., <em>Liturgiam authenticam<\/em>, nn. 79-80: AAS 93 (2001) pp. 711-713.<\/p>\n<p style=\"text-align: justify;\"><strong>[66]<\/strong> Cf. Conc. Ecum. Vat. II, Decr. sul ministero e la vita dei sacerdoti, <em>Presbyterorum ordinis<\/em>, 7 dicembre 1965, n. 7; Pontificale Romanum, ed. 1962: Ordo consecrationis sacerdotalis, in Praefatione; Pontificale Romanum\u00a0<em>ex decreto sacrosancti Oecumenici Concilii Vaticani II renovatum, auctoritate Pauli Pp. VI editum, Ioannis Pauli Pp. II cura recognitum<\/em>: De Ordinatione Episcopi, presbyterorum et diaconorum, editio typica altera, diei 29 iunii 1989, Typis Polyglottis Vaticanis, 1990, cap. II, De Ordin. presbyterorum, Praenotanda, n. 101.<\/p>\n<p style=\"text-align: justify;\"><strong>[67]<\/strong> Cf. S. Ignatio di Antiochia, <em>Ad Philad.<\/em> 4: ed. F.X. Funk, I, p. 266; S. Cornelio I citato in S. Cipriano, <em>Epist.<\/em> 48, 2: ed. G. Hartel, III, 2, p. 610.<\/p>\n<p style=\"text-align: justify;\"><strong>[68]<\/strong> Conc. Ecum. Vat. II, Cost. dogm. sulla Chiesa, <em>Lumen gentium<\/em>, n. 28.<\/p>\n<p style=\"text-align: justify;\"><strong>[69]<\/strong> Cf. <em>ibidem<\/em>.<\/p>\n<p style=\"text-align: justify;\"><strong>[70]<\/strong> Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 52; cf. n. 29: AAS 95 (2003) pp. 467-468; 452-453.<\/p>\n<p style=\"text-align: justify;\"><strong>[71]<\/strong> Pontificale Romanum, De Ordinatione Episcopi, presbyterorum et diaconorum, editio typica altera: <em>De Ordinatione presbyterorum<\/em>, n. 124; cf. Missale Romanum, Feria V in Hebdomada Sancta: Ad Missam chrismatis, Renovatio promissionum sacerdotalium, p. 292<\/p>\n<p style=\"text-align: justify;\"><strong>[72]<\/strong> Cf. Conc. Ecum. Trid., Sessione VII, 3 marzo 1547, Decr. sui Sacramenti, can. 13: DS 1613; Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 22; Pio XII, Lett. Enc., <em>Mediator Dei<\/em>: AAS 39 (1947) pp. 544, 546-547, 562; <em>Codice di Diritto Canonico<\/em>, can. 846, \u00a7 1; Missale Romanum, Institutio Generalis, n. 24.<\/p>\n<p style=\"text-align: justify;\"><strong>[73]<\/strong> S. Ambrogio, <em>De Virginitate<\/em>, n. 48: PL 16, 278.<\/p>\n<p style=\"text-align: justify;\"><strong>[74]<\/strong><em> Codice di Diritto Canonico<\/em>, can. 528 \u00a7 2.<\/p>\n<p style=\"text-align: justify;\"><strong>[75]<\/strong> Conc. Ecum. Vat. II, Decr. sul ministero e la vita dei sacerdoti, <em>Presbyterorum ordinis<\/em>, n. 5.<\/p>\n<p style=\"text-align: justify;\"><strong>[76]<\/strong> Cf. Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 5: AAS 95 (2003) p. 436.<\/p>\n<p style=\"text-align: justify;\"><strong>[77]<\/strong> Conc. Ecum. Vat. II, Cost. dogm. sulla Chiesa, <em>Lumen gentium<\/em>, n. 29; cf. <em>Constitutiones Ecclesiae Aegypticae<\/em>, III, 2: ed. F.X. Funk, <em>Didascalia<\/em>, II, p. 103; <em>Statuta Ecclesiae Ant.<\/em>, 37-41: ed. D. Mansi 3, 954.<\/p>\n<p style=\"text-align: justify;\"><strong>[78]<\/strong> Cf. <em>At<\/em> 6, 3.<\/p>\n<p style=\"text-align: justify;\"><strong>[79]<\/strong> Cf. <em>Gv<\/em> 13, 35.<\/p>\n<p style=\"text-align: justify;\"><strong>[80]<\/strong> <em>Mt<\/em> 20, 28.<\/p>\n<p style=\"text-align: justify;\"><strong>[81]<\/strong> Cf. <em>Lc<\/em> 22, 27.<\/p>\n<p style=\"text-align: justify;\"><strong>[82]<\/strong> Cf. Caeremoniale Episcoporum, nn. 9, 23. Cf. Conc. Ecum. Vat. II, Cost. dogm. sulla Chiesa, <em>Lumen gentium<\/em>, n. 29.<\/p>\n<p style=\"text-align: justify;\"><strong>[83]<\/strong> Cf. Pontificale Romanum, De Ordinatione Episcopi, presbyterorum et diaconorum, editio typica altera, cap. III, <em>De Ordin. diaconorum<\/em>, n. 199.<\/p>\n<p style=\"text-align: justify;\"><strong>[84]<\/strong> Cf. <em>1 Tm<\/em> 3, 9.<\/p>\n<p style=\"text-align: justify;\"><strong>[85]<\/strong> Cf. Pontificale Romanum, De Ordinatione Episcopi, presbyterorum et diaconorum, editio typica altera, cap. III, <em>De Ordin. diaconorum<\/em>, n. 200.<\/p>\n<p style=\"text-align: justify;\"><strong>[86]<\/strong> Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 10.<a name=\"_ftn87\"><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>[87]<\/strong> Cf. <em>ibidem<\/em>, n. 41; Conc. Ecum. Vat. II, Cost. dogm. sulla Chiesa, <em>Lumen gentium<\/em>, n. 11; Decr. sul ministero e la vita dei sacerdoti, <em>Presbyterorum ordinis<\/em>, nn. 2, 5, 6; Decr. sull\u2019ufficio pastorale dei Vescovi, <em>Christus Dominus<\/em>, n. 30; Decr. sull\u2019ecumenismo, <em>Unitatis redintegratio<\/em>, 21 novembre 1964, n. 15; S. Congr. dei Riti, Istr., <em>Eucharisticum mysterium<\/em>, nn. 3 e, 6: AAS 59 (1967) pp. 542, 544-545; Missale Romanum, Institutio Generalis, n. 16.<\/p>\n<p style=\"text-align: justify;\"><strong>[88]<\/strong> Cf. Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 26; Missale Romanum, Institutio Generalis, n. 91.<\/p>\n<p style=\"text-align: justify;\"><strong>[89]<\/strong><em> 1 Pt<\/em> 2, 9; cf. 2, 4-5.<\/p>\n<p style=\"text-align: justify;\"><strong>[90]<\/strong> Missale Romanum, Institutio Generalis, n. 91; cf. Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 14.<\/p>\n<p style=\"text-align: justify;\"><strong>[91]<\/strong> Conc. Ecum. Vat. II, Cost. dogm. sulla Chiesa, <em>Lumen gentium<\/em>, n. 10.<\/p>\n<p style=\"text-align: justify;\"><strong>[92]<\/strong> Cf. S. Tommasod\u2019Aquino, <em>Summa Theol.<\/em>, III, q. 63, a. 2.<\/p>\n<p style=\"text-align: justify;\"><strong>[93]<\/strong> Cf. Conc. Ecum. Vat. II, Cost. dogm. sulla Chiesa, <em>Lumen gentium<\/em>, n. 10; cf. Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 28: AAS 95 (2003) p. 452.<\/p>\n<p style=\"text-align: justify;\"><strong>[94]<\/strong> Cf. <em>At<\/em> 2, 42-47.<\/p>\n<p style=\"text-align: justify;\"><strong>[95]<\/strong> Cf. <em>Rm<\/em> 12, 1.<\/p>\n<p style=\"text-align: justify;\"><strong>[96]<\/strong> Cf. <em>1 Pt<\/em> 3, 15; 2, 4-10.<\/p>\n<p style=\"text-align: justify;\"><strong>[97]<\/strong> Cf. Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, nn. 12-18: AAS 95 (2003) pp. 441-445; Id.,Lett., <em>Dominicae Cenae<\/em>, 24 febbraio 1980, n. 9: AAS 72 (1980) pp. 129-133.<\/p>\n<p style=\"text-align: justify;\"><strong>[98]<\/strong> Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 10: AAS 95 (2003) p. 439.<\/p>\n<p style=\"text-align: justify;\"><strong>[99]<\/strong> Cf. Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, nn. 30-31.<\/p>\n<p style=\"text-align: justify;\"><strong>[100]<\/strong> Cf. S. Congr. per il Culto Divino, Istr., <em>Liturgicae instaurationes<\/em>, n. 1: AAS 62 (1970) p. 695.<\/p>\n<p style=\"text-align: justify;\"><strong>[101]<\/strong> Cf. Missale Romanum, Feria secunda post Dominica V in Quadragesima, Collecta, p. 258.<\/p>\n<p style=\"text-align: justify;\"><strong>[102]<\/strong> Giovanni Paolo II,Lett. Ap., <em>Novo Millennio ineunte<\/em>, 6 gennaio 2001, n. 21: AAS 93 (2001) p. 280; cf. <em>Gv<\/em> 20, 28.<\/p>\n<p style=\"text-align: justify;\"><strong>[103]<\/strong> Cf. Pio XII, Lett. Enc., <em>Mediator Dei<\/em>: AAS 39 (1947) p. 586; cf. anche Conc. Ecum. Vat. II, Cost. dogm. sulla Chiesa, <em>Lumen gentium<\/em>, n. 67; Paolo VI, Esort. Ap., <em>Marialis cultus<\/em>, 11 febbraio 1974, n. 24: AAS 66 (1974) pp. 113-168, qui p. 134; Congr. per il Culto Div. e la Disc. dei Sacram., <em>Direttorio su piet\u00e0 popolare e Liturgia<\/em>, 17 dicembre 2001.<\/p>\n<p style=\"text-align: justify;\"><strong>[104]<\/strong> Cf. Giovanni Paolo II, Ep. Ap., <em>Rosarium Virginis Mariae<\/em>, 16 ottobre 2002: AAS 95 (2003) pp. 5-36.<\/p>\n<p style=\"text-align: justify;\"><strong>[105]<\/strong> Pio XII, Lett. Enc., <em>Mediator Dei<\/em>: AAS 39 (1947) pp. 586-587.<\/p>\n<p style=\"text-align: justify;\"><strong>[106]<\/strong> Cf. Congr. per il Culto Div. e la Disc. dei Sacram., Istr., <em>Varietates legitimae<\/em>, n. 22: AAS 87 (1995) p. 297.<\/p>\n<p style=\"text-align: justify;\"><strong>[107]<\/strong> Cf. Pio XII, Lett. Enc., <em>Mediator Dei<\/em>: AAS 39 (1947) p. 553.<\/p>\n<p style=\"text-align: justify;\"><strong>[108]<\/strong> Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 29: AAS 95 (2003) p. 453; cf. Conc. Ecum. Lateran. IV., 11-30 novembre 1215, cap. 1: DS802; Conc. Ecum. Trid., Sess. XXIII, 15 luglio 1563, Dottrina e canonisulla sacr. ordin., cap. 4: DS 1767-1770; Pio XII, Lett. Enc., <em>Mediator Dei<\/em>: AAS 39 (1947) p. 553.<\/p>\n<p style=\"text-align: justify;\"><strong>[109]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>,can. 230 \u00a7 2; cf. anche Missale Romanum, Institutio Generalis, n. 97.<\/p>\n<p style=\"text-align: justify;\"><strong>[110]<\/strong> Cf. anche Missale Romanum, Institutio Generalis, n. 109.<\/p>\n<p style=\"text-align: justify;\"><strong>[111]<\/strong> Cf. Paolo VI, Motu proprio, <em>Ministeria quaedam<\/em>, 15 agosto 1972, nn. VI-XII: Pontificale Romanum<em> ex decreto sacrosancti Oecumenici Concilii Vaticani II instauratum, auctoritate Pauli Pp. VI promulgatum<\/em>, De institutione lectorum et acolythorum, de admissione inter candidatos ad diaconatum et presbyteratum, de sacro caelibatu amplectendo, editio typica, diei 3 decembris 1972, Typis Polyglottis Vaticanis, 1973, p. 10: AAS 64 (1972) pp. 529-534, qui pp. 532-533;<em> Codice di Diritto Canonico<\/em>, can. 230 \u00a7 1; Missale Romanum, Institutio Generalis, nn. 98-99, 187-193.<\/p>\n<p style=\"text-align: justify;\"><strong>[112]<\/strong> Cf. Missale Romanum, Institutio Generalis, nn. 187-190, 193;<em> Codice di Diritto Canonico<\/em>, can. 230 \u00a7\u00a7 2-3.<\/p>\n<p style=\"text-align: justify;\"><strong>[113]<\/strong> Cf. Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 24; S. Congr. per i Sacr. e per il Culto Div., Istr., <em>Inaestimabile donum<\/em>, nn. 2 e 18: AAS 72 (1980) pp. 334, 338; Missale Romanum, Institutio Generalis, nn. 101, 194-198; <em>Codice di Diritto Canonico<\/em>, can. 230 \u00a7 2-3.<\/p>\n<p style=\"text-align: justify;\"><strong>[114]<\/strong> Cf. Missale Romanum, Institutio Generalis, nn. 100-107.<\/p>\n<p style=\"text-align: justify;\"><strong>[115]<\/strong><em> Ibidem<\/em>, n. 91; cf. Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 28.<\/p>\n<p style=\"text-align: justify;\"><strong>[116]<\/strong> Cf. Giovanni Paolo II, Discorso alla Conferenza dei Vescovi delle Antille, 7 maggio 2002, n. 2: AAS 94 (2002) pp. 575-577; Esort. Ap. post-sinodale, <em>Christifideles laici<\/em>, 30 dicembre 1988, n. 23: AAS 81 (1989) pp. 393-521, qui pp. 429-431; Congr. per il Clero ed altre, Istr., <em>Ecclesiae de mysterio<\/em>, 15 agosto 1997, Principi teologici, n. 4: AAS 89 (1997) pp. 860-861.<\/p>\n<p style=\"text-align: justify;\"><strong>[117]<\/strong> Cf. Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 19.<\/p>\n<p style=\"text-align: justify;\"><strong>[118]<\/strong> Cf. S. Congr. per il Culto Divino, Istr., <em>Immensae caritatis<\/em>, 29 gennaio 1973: AAS 65 (1973) p. 266.<\/p>\n<p style=\"text-align: justify;\"><strong>[119]<\/strong> Cf. S. Congr. dei Riti, Istr., <em>De Musica sacra<\/em>, 3 settembre 1958, n. 93c: AAS 50 (1958) p. 656.<\/p>\n<p style=\"text-align: justify;\"><strong>[120]<\/strong> Cf. Pont. Cons. per l\u2019Interpr. dei Testi Legisl., Responsio ad propositum dubium, 11 luglio 1992: AAS 86 (1994) pp. 541-542; Congr. per il Culto Div. e la Disc. dei Sacram., Lett. ai Presidenti delle Conf. dei Vescovi sul servizio liturgico dei laici, 15 marzo 1994:<em>Notitiae<\/em> 30 (1994) 333-335, 347-348.<\/p>\n<p style=\"text-align: justify;\"><strong>[121]<\/strong> Cf. Giovanni Paolo II, Cost. Ap., <em>Pastor bonus<\/em>, art. 65: AAS 80 (1988) p. 877.<\/p>\n<p style=\"text-align: justify;\"><strong>[122]<\/strong> Cf. Pont. Cons. per l\u2019Interpr. dei Testi Legisl., Responsio ad propositum dubium, 11 luglio 1992: AAS 86 (1994) pp. 541-542; Congr. per il Culto Div. e la Disc. dei Sacram., Lett. ai Presidenti delle Conf. dei Vescovi sul servizio liturgico dei laici, 15 marzo 1994: <em>Notitiae<\/em> 30 (1994) 333-335, 347-348; Lett. a qualche Vescovo, 27 luglio 2001: <em>Notitiae<\/em> 38 (2002) 46-54.<\/p>\n<p style=\"text-align: justify;\"><strong>[123]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>, can. 924 \u00a7 2: Missale Romanum, Institutio Generalis, n. 320.<\/p>\n<p style=\"text-align: justify;\"><strong>[124]<\/strong> Cf. S. Congr. per la Disc. dei Sacram., Istr., <em>Dominus Salvator noster<\/em>,<em> 2<\/em>6 marzo 1929, n. 1: AAS 21 (1929) pp. 631-642, qui p. 632.<\/p>\n<p style=\"text-align: justify;\"><strong>[125]<\/strong> Cf. <em>ibidem<\/em>, n. II: AAS 21 (1929) p. 635.<\/p>\n<p style=\"text-align: justify;\"><strong>[126]<\/strong> Cf. Missale Romanum, Institutio Generalis, n. 321.<\/p>\n<p style=\"text-align: justify;\"><strong>[127]<\/strong> Cf. <em>Lc<\/em> 22, 18; <em>Codice di Diritto Canonico<\/em>,can. 924 \u00a7\u00a7 1, 3; Missale Romanum, Institutio Generalis, n. 322.<\/p>\n<p style=\"text-align: justify;\"><strong>[128]<\/strong> Cf. Missale Romanum, Institutio Generalis, n. 323.<\/p>\n<p style=\"text-align: justify;\"><strong>[129]<\/strong> Giovanni Paolo II, Lett. Ap., <em>Vicesimus quintus annus<\/em>, n. 13: AAS 81 (1989) p. 910.<\/p>\n<p style=\"text-align: justify;\"><strong>[130]<\/strong> S. Congr. per i Sacram. e per il Culto Div., Istr., <em>Inaestimabile donum<\/em>, n. 5: AAS 72 (1980) p. 335.<\/p>\n<p style=\"text-align: justify;\"><strong>[131]<\/strong> Cf. Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 28: AAS 95 (2003) p. 452; Missale Romanum, Institutio Generalis, n. 147; S. Congr. per il CultoDiv., Istr.,<em>Liturgicae instaurationes<\/em>, n. 4: AAS 62 (1970) p. 698; S. Congr. per i Sacram. e per il Culto Div., Istr., <em>Inaestimabile donum<\/em>, n. 4: AAS 72 (1980) p. 334.<\/p>\n<p style=\"text-align: justify;\"><strong>[132]<\/strong> Missale Romanum, Institutio Generalis, n. 32.<\/p>\n<p style=\"text-align: justify;\"><strong>[133]<\/strong><em> Ibidem<\/em>, n. 147; cf. Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 28: AAS 95 (2003) p. 452; cf. anche Congr. per i Sacram. e per il Culto Div., Istr., <em>Inaestimabile donum<\/em>, n. 4: AAS 72 (1980) pp. 334-335.<\/p>\n<p style=\"text-align: justify;\"><strong>[134]<\/strong> Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 39: AAS 95 (2003) p. 459.<\/p>\n<p style=\"text-align: justify;\"><strong>[135]<\/strong> Cf. S. Congr. per il Culto Div., Istr., <em>Liturgicae instaurationes<\/em>, n. 2b: AAS 62 (1970) p. 696.<\/p>\n<p style=\"text-align: justify;\"><strong>[136]<\/strong> Cf. Missale Romanum, Institutio Generalis, nn. 356-362.<\/p>\n<p style=\"text-align: justify;\"><strong>[137]<\/strong> Cf. Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 51.<\/p>\n<p style=\"text-align: justify;\"><strong>[138]<\/strong> Missale Romanum, Institutio Generalis, n. 57; cf. Giovanni Paolo II, Lett. Ap.,<em>Vicesimus quintus annus<\/em>, n. 13: AAS 81 (1989) p. 910; Congr. per la Dottr. della Fede, Dichiarazione sulla unicit\u00e0 e universalit\u00e0 salvifica di Cristo e della Chiesa, <em>Dominus Iesus<\/em>, 6 agosto 2000: AAS 92 (2000) pp. 742-765.<\/p>\n<p style=\"text-align: justify;\"><strong>[139]<\/strong> Missale Romanum, Institutio Generalis, n. 60.<\/p>\n<p style=\"text-align: justify;\"><strong>[140]<\/strong> Cf. <em>ibidem<\/em>, nn. 59-60.<\/p>\n<p style=\"text-align: justify;\"><strong>[141]<\/strong> Cf. per es. Rituale Romanum, <em>ex decreto sacrosancti Oecumenici Concilii Vaticani II renovatum, auctoritate Pauli Pp. VI editum Ioannis Pauli Pp. II cura recognitum<\/em>: Ordo celebrandi Matrimonium, editio typica altera, diei 19 martii 1990, Typis Polyglottis Vaticanis, 1991, n. 125; Rituale Romanum, <em>ex decreto sacrosancti Oecumenici Concilii Vaticani II instauratum, auctoritate Pauli Pp. VI promulgatum<\/em>, Ordo Unctionis infirmorum eorumque pastoralis curae, editio typica, diei 7 decembris 1972, Typis Polyglottis Vaticanis, 1972, n. 72.<\/p>\n<p style=\"text-align: justify;\"><strong>[142]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>, can. 767 \u00a7 1.<\/p>\n<p style=\"text-align: justify;\"><strong>[143]<\/strong> Cf. Missale Romanum, Institutio Generalis, n. 66; cf. anche<em> Codice di Diritto Canonico<\/em>, can. 6, \u00a7\u00a7 1, 2; e can. 767 \u00a7 1, in merito a ci\u00f2 si tengano presenti anche le prescrizioni della Congr. per il Clero ed altre, Istr., <em>Ecclesiae de mysterio<\/em>, Disposizioni pratiche, art. 3 \u00a7 1: AAS 89 (1997) p. 865.<\/p>\n<p style=\"text-align: justify;\"><strong>[144]<\/strong> Missale Romanum, Institutio Generalis, n. 66; cf. anche<em>\u00a0Codice di Diritto Canonico<\/em>, can. 767 \u00a7 1.<\/p>\n<p style=\"text-align: justify;\"><strong>[145]<\/strong> Cf. Congr. per il Clero ed altre, Istr., <em>Ecclesiae de mysterio<\/em>, Disposizioni pratiche, art. 3 \u00a7 1: AAS 89 (1997) p. 865; cf. anche <em>Codice di Diritto Canonico<\/em>, can. 6, \u00a7\u00a7 1, 2; Pont. Comm. per l\u2019Interpr. autent. del Codice di Diritto Canonico, Responsio ad propositum dubium, 20 giugno 1987: AAS 79 (1987) p. 1249.<\/p>\n<p style=\"text-align: justify;\"><strong>[146]<\/strong> Cf. Congr. per il Clero ed altre, Istr., <em>Ecclesiae de mysterio<\/em>, Disposizioni pratiche, art. 3 \u00a7 1: AAS 89 (1997) pp. 864-865.<\/p>\n<p style=\"text-align: justify;\"><strong>[147]<\/strong> Cf. Conc. Ecum. Trid., Sess. XXII, 17 settembre 1562, Il Ss.mo Sacrificio della Messa, cap. 8: DS1749; Missale Romanum, Institutio Generalis, n. 65.<\/p>\n<p style=\"text-align: justify;\"><strong>[148]<\/strong> Cf. Giovanni Paolo II, Discorso ad alcuni Vescovi degli Stati Uniti d\u2019America in occasione della visita \u00abad limina Apostolorum\u00bb, 28 maggio 1993, n. 2: AAS 86 (1994) p. 330.<\/p>\n<p style=\"text-align: justify;\"><strong>[149]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>,can. 386 \u00a7 1.<\/p>\n<p style=\"text-align: justify;\"><strong>[150]<\/strong> Cf. Missale Romanum, Institutio Generalis, n. 73.<\/p>\n<p style=\"text-align: justify;\"><strong>[151]<\/strong> Cf. <em>ibidem<\/em>, n. 154.<\/p>\n<p style=\"text-align: justify;\"><strong>[152]<\/strong> Cf. <em>ibidem<\/em>, nn. 82, 154.<\/p>\n<p style=\"text-align: justify;\"><strong>[153]<\/strong> Cf.Missale Romanum, Institutio Generalis, n. 83.<\/p>\n<p style=\"text-align: justify;\"><strong>[154]<\/strong> Cf. S. Congr. per il Culto Divino, Istr., <em>Liturgicae instaurationes<\/em>, n. 5: AAS 62 (1970) p. 699.<\/p>\n<p style=\"text-align: justify;\"><strong>[155]<\/strong> Cf. Missale Romanum, Institutio Generalis, nn. 83, 240, 321.<\/p>\n<p style=\"text-align: justify;\"><strong>[156]<\/strong> Cf. Congr. per il Clero ed altre, Istr., <em>Ecclesiae de mysterio<\/em>, Disposizioni pratiche, art. 3 \u00a7 2: AAS 89 (1997) p. 865.<\/p>\n<p style=\"text-align: justify;\"><strong>[157]<\/strong> Cf. specialmente <em>Institutio generalis de Liturgia Horarum<\/em>, nn. 93-98; Rituale Romanum, <em>ex decreto sacrosancti Oecumenici Concilii Vaticani II instauratum, auctoritate Ioannis Pauli Pp. II promulgatum<\/em>: De Benedictionibus, editio typica, diei 31 maii 1984, Typis Polyglottis Vaticanis, 1984, Praenotanda, n. 28; Ordo coronandi imaginem beatae Mariae Virginis, editio typica, diei 25martii 1981, Typis Polyglottis Vaticanis, 1981, nn. 10 e 14, pp. 10-11; S. Congr. per il Culto Divino, Istr., sulle Messe nei gruppi particolari, <em>Actio pastoralis<\/em>, 15 maggio 1969: AAS 61 (1969) pp. 806-811; Direttorio per le Messe dei fanciulli,<em> Pueros baptizatos<\/em>, 1 novembre 1973: AAS 66 (1974) pp. 30-46; Missale Romanum, Institutio Generalis, n. 21.<\/p>\n<p style=\"text-align: justify;\"><strong>[158]<\/strong> Cf. Giovanni Paolo II, Motu proprio, <em>Misericordia Dei<\/em>, 7 aprile 2002, n. 2: AAS 94 (2002) p. 455; Cf. Congr. per il Culto Div. e la Disc. dei Sacram., Responsa ad dubia proposita: <em>Notitiae<\/em> 37 (2001) pp. 259-260.<\/p>\n<p style=\"text-align: justify;\"><strong>[159]<\/strong> Cf. S. Congr. per il CultoDiv., Istr., <em>Liturgicae instaurationes<\/em>, n. 9: AAS 62 (1970) p. 702.<\/p>\n<p style=\"text-align: justify;\"><strong>[160]<\/strong> Conc. Ecum. Trid., Sess. XIII, 11 ottobre 1551, Decr. sulla Ss. Eucaristia, cap. 2: DS 1638; cf. Sess. XXII, 17 settembre 1562, Il Ss. Sacrificio della Messa, cap. 1-2: DS 1740, 1743; S. Congr. dei Riti, Istr.,\u00a0<em>Eucharisticum mysterium<\/em>, n. 35: AAS 59 (1967) p. 560.<\/p>\n<p style=\"text-align: justify;\"><strong>[161]<\/strong> Cf. Missale Romanum, Ordo Missae, n. 4, p. 505.<\/p>\n<p style=\"text-align: justify;\"><strong>[162]<\/strong> Missale Romanu<a name=\"_ftn163\"><\/a>m, Institutio Generalis, n. 51.<\/p>\n<p style=\"text-align: justify;\"><strong>[163]<\/strong> Cf. <em>1 Cor<\/em> 11, 28.<\/p>\n<p style=\"text-align: justify;\"><strong>[164]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>, can. 916; Conc. Ecum. Trid., Sess. XIII, 11 ottobre 1551, Decr. sulla Ss. Eucaristia, cap. 7: DS 1646-1647; Giovanni Paolo II, Lett. Enc.,<em>Ecclesia de Eucharistia<\/em>, n. 36: AAS 95 (2003) pp. 457-458; S. Congr. dei Riti, Istr.,<em>Eucharisticum mysterium<\/em>, n. 35: AAS 59 (1967) p. 561.<\/p>\n<p style=\"text-align: justify;\"><strong>[165]<\/strong> Cf. Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 42: AAS 95 (2003) p. 461.<\/p>\n<p style=\"text-align: justify;\"><strong>[166]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>, can. 844 \u00a7 1; Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, nn. 45-46: AAS 95 (2003) pp. 463-464; cf. anche Pont. Cons. per la Promoz. dell\u2019Unit\u00e0 dei Cristiani, Direttorio per l\u2019applicazione dei principi e norme sull\u2019ecumenismo, <em>La recherche de l\u2019unit\u00e9<\/em>, 25 marzo 1993, nn. 130-131: AAS 85 (1993) pp. 1039-1119, qui p. 1089.<\/p>\n<p style=\"text-align: justify;\"><strong>[167]<\/strong> Cf. Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 46: AAS 95 (2003) pp. 463-464.<\/p>\n<p style=\"text-align: justify;\"><strong>[168]<\/strong> Cf. S. Congr. dei Riti, Istr., <em>Eucharisticum mysterium<\/em>, n. 35: AAS 59 (1967) p. 561.<\/p>\n<p style=\"text-align: justify;\"><strong>[169]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>,can. 914; S. Congr. per la Disc. dei Sacram., Dichiaraz., <em>Sanctus Pontifex<\/em>, 24 maggio 1973: AAS 65 (1973) p. 410; S. Congr. per i Sacram. e per il Culto Div. e S. Congr. per il Clero, Lett. ai Presidenti delle Conf. dei Vescovi, <em>In quibusdam<\/em>, 31 marzo 1977:<em> Enchiridion Documentorum Instaurationis Liturgicae<\/em>, II, Roma 1988, pp. 142-144; S. Congr. per i Sacram. e per il Culto Div. e S. Congr. per il Clero, Responsum ad propositum dubium, 20 maggio 1977:AAS 69 (1977) p. 427.<\/p>\n<p style=\"text-align: justify;\"><strong>[170]<\/strong> Cf. Giovanni Paolo II, Lett. Ap., <em>Dies Domini<\/em>, 31 maggio 1998, nn. 31-34: AAS 90 (1998) pp. 713-766, qui pp. 731-734.<\/p>\n<p style=\"text-align: justify;\"><strong>[171]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>,can. 914.<\/p>\n<p style=\"text-align: justify;\"><strong>[172]<\/strong> Cf. Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 55.<\/p>\n<p style=\"text-align: justify;\"><strong>[173]<\/strong>Cf. S. Congr. dei Riti, Istr., <em>Eucharisticum mysterium<\/em>, n. 31: AAS 59 (1967) p. 558; Pont. Cons. per l\u2019Interpr. dei Testi Legislativi, Responsio ad propositum dubium, 1 giugno 1988: AAS 80 (1988) p. 1373.<\/p>\n<p style=\"text-align: justify;\"><strong>[174]<\/strong> Missale Romanum, Institutio Generalis, n. 85.<\/p>\n<p style=\"text-align: justify;\"><strong>[175]<\/strong> Cf. Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 55; S. Congr. dei Riti, Istr., <em>Eucharisticum mysterium<\/em>, n. 31: AAS 59 (1967) p. 558; Missale Romanum, Institutio Generalis, nn. 85, 157, 243.<\/p>\n<p style=\"text-align: justify;\"><strong>[176]<\/strong> Cf. Missale Romanum, Institutio Generalis, n. 160.<\/p>\n<p style=\"text-align: justify;\"><strong>[177]<\/strong><em> Codice di Diritto Canonico<\/em>,can. 843 \u00a7 1; cf. can. 915.<\/p>\n<p style=\"text-align: justify;\"><strong>[178]<\/strong> Cf. Missale Romanum, Institutio Generalis, n. 161.<\/p>\n<p style=\"text-align: justify;\"><strong>[179]<\/strong> Congr. per il Culto Div. e la Disc. dei Sacram., Dubium: <em>Notitiae<\/em> 35 (1999) pp. 160-161.<\/p>\n<p style=\"text-align: justify;\"><strong>[180]<\/strong> Cf. Missale Romanum, Institutio Generalis, n. 118.<\/p>\n<p style=\"text-align: justify;\"><strong>[181]<\/strong><em> Ibidem<\/em>, n. 160.<\/p>\n<p style=\"text-align: justify;\"><strong>[182]<\/strong><em> Codice di Diritto Canonico<\/em>, can. 917; cf. Pont. Comm. per l\u2019Interpretazione Autentica del Codice di Diritto Canonico, Responsio ad propositum dubium, 11 luglio 1984: AAS 76 (1984) p. 746.<\/p>\n<p style=\"text-align: justify;\"><strong>[183]<\/strong> Cf. Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 55; Missale Romanum, Institutio Generalis, nn. 158-160, 243-244, 246.<\/p>\n<p style=\"text-align: justify;\"><strong>[184]<\/strong> Cf. Missale Romanum, Institutio Generalis, nn. 237-249; cf. anche nn. 85, 157.<\/p>\n<p style=\"text-align: justify;\"><strong>[185]<\/strong> Cf. <em>ibidem<\/em>, n. 283a.<\/p>\n<p style=\"text-align: justify;\"><strong>[186]<\/strong> Cf. Conc. Ecum. Trid., Sessio XXI, 16 luglio 1562, Decr. sulla comunione eucaristica, capp. 1-3: DS 1725-1729; Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 55; Missale Romanum, Institutio Generalis, nn. 282-283.<\/p>\n<p style=\"text-align: justify;\"><strong>[187]<\/strong> Cf. Missale Romanum, Institutio Generalis, n. 283.<\/p>\n<p style=\"text-align: justify;\"><strong>[188]<\/strong> Cf. <em>ibidem<\/em>.<\/p>\n<p style=\"text-align: justify;\"><strong>[189]<\/strong> Cf. S. Congr. per il CultoDiv., Istr., <em>Sacramentali Communione<\/em>, 29 giugno 1970: AAS 62 (1970) p. 665; Istr., <em>Liturgicae instaurationes<\/em>, n. 6a: AAS 62 (1970) p. 699.<\/p>\n<p style=\"text-align: justify;\"><strong>[190]<\/strong> Missale Romanum, Institutio Generalis, n. 285a.<\/p>\n<p style=\"text-align: justify;\"><strong>[191]<\/strong><em> Ibidem<\/em>, n. 245.<\/p>\n<p style=\"text-align: justify;\"><strong>[192]<\/strong> Cf. <em>ibidem<\/em>, nn. 285b et 287.<\/p>\n<p style=\"text-align: justify;\"><strong>[193]<\/strong> Cf. <em>ibidem<\/em>, nn. 207 et 285a.<\/p>\n<p style=\"text-align: justify;\"><strong>[194]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>, can. 1367.<\/p>\n<p style=\"text-align: justify;\"><strong>[195]<\/strong> Cf. Pont. Cons. per l\u2019Interpr. dei Testi Legisl., Responsio ad propositum dubium, 3 luglio 1999: AAS 91 (1999) p. 918.<\/p>\n<p style=\"text-align: justify;\"><strong>[196]<\/strong> Cf. Missale Romanum, Institutio Generalis, nn. 163, 284.<\/p>\n<p style=\"text-align: justify;\"><strong>[197]<\/strong><em> Codice di Diritto Canonico<\/em>,can. 932 \u00a7 1; cf. S. Congr. per il Culto Div., Istr., <em>Liturgicae instaurationes<\/em>, n. 9: AAS 62 (1970) p. 701.<\/p>\n<p style=\"text-align: justify;\"><strong>[198]<\/strong><em> Codice di Diritto Canonico<\/em>, can. 904; cf. Conc. Ecum. Vat. II, Cost. dogm. sulla Chiesa, <em>Lumen gentium<\/em>, n. 3; Decr. sul ministero e la vita dei sacerdoti, <em>Presbyterorum ordinis<\/em>, n. 13; cf. anche Conc. Ecum. Trid., Sess. XXII, 17 settembre 1562, Il Ss. Sacrificio della Messa, cap. 6: DS 1747; Paolo VI, Lett. Enc., <em>Mysterium fidei<\/em>, 3 settembre 1965: AAS 57 (1965) pp. 753-774, qui pp. 761-762; cf. Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 11: AAS 95 (2003) pp. 440-441; S. Congr. dei Riti, Istr., <em>Eucharisticum mysterium<\/em>, n. 44: AAS 59 (1967) p. 564; Missale Romanum, Institutio Generalis, n. 19.<\/p>\n<p style=\"text-align: justify;\"><strong>[199]<\/strong> Cf.<em>Codice di Diritto Canonico<\/em>, can. 903; Missale Romanum, Institutio Generalis, n. 200.<\/p>\n<p style=\"text-align: justify;\"><strong>[200]<\/strong> Cf. Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 36 \u00a7 1; <em>Codice di Diritto Canonico<\/em>, can. 928.<\/p>\n<p style=\"text-align: justify;\"><strong>[201]<\/strong> Cf. Missale Romanum, Institutio Generalis, n. 114.<\/p>\n<p style=\"text-align: justify;\"><strong>[202]<\/strong> Giovanni Paolo II, Lett. Ap., <em>Dies Domini<\/em>, n. 36: AAS 90 (1998) pp. 713-766, qui p. 735; cf. anche S. Congr. dei Riti, Istr.,\u00a0<em>Eucharisticum mysterium<\/em>, n. 27: AAS 59 (1967) p. 556.<\/p>\n<p style=\"text-align: justify;\"><strong>[203]<\/strong> Giovanni Paolo II, Lett. Ap., <em>Dies Domini<\/em>, soprattutto n. 36: AAS 90 (1998) pp. 735-736; S. Congr. per il Culto Divino, Istr., <em>Actio pastoralis<\/em>, 15 maggio 1969: AAS 61 (1969) pp. 806-811.<\/p>\n<p style=\"text-align: justify;\"><strong>[204]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>, cann. 905, 945-958; cf. Congr. per il Clero, Decr., <em>Mos iugiter<\/em>, 22 febbraio 1991: AAS 83 (1991) pp. 443-446.<\/p>\n<p style=\"text-align: justify;\"><strong>[205]<\/strong> Cf. Missale Romanum, Institutio Generalis, nn. 327-333.<\/p>\n<p style=\"text-align: justify;\"><strong>[206]<\/strong> Cf. <em>ibidem<\/em>, n. 332.<\/p>\n<p style=\"text-align: justify;\"><strong>[207]<\/strong> Cf. Missale Romanum, Institutio Generalis, n. 332; S. Congr. per i Sacram. e per il Culto Div., Istr., <em>Inaestimabile donum<\/em>, n. 16: AAS 72 (1980) p. 338.<\/p>\n<p style=\"text-align: justify;\"><strong>[208]<\/strong> Cf. Missale Romanum, Institutio Generalis, n. 333; Appendix IV. <em>Ordo benedictionis calicis et patenae intra Missam adhibendus<\/em>, pp. 1255-1257; Pontificale Romanum <em>ex decreto sacrosancti Oecumenici Concilii Vaticani II instauratum, auctoritate Pauli Pp. VI promulgatum<\/em>, Ordo Dedicationis ecclesiae et altaris, editio typica, diei 29 maii 1977, Typis Polyglottis Vaticanis, 1977, cap. VII, pp. 125-132.<\/p>\n<p style=\"text-align: justify;\"><strong>[209]<\/strong> Cf. Missale Romanum, Institutio Generalis, nn. 163, 183, 192.<\/p>\n<p style=\"text-align: justify;\"><strong>[210]<\/strong><em> Ibidem<\/em>, n. 345.<\/p>\n<p style=\"text-align: justify;\"><strong>[211]<\/strong><em> Ibidem<\/em>, n. 335.<\/p>\n<p style=\"text-align: justify;\"><strong>[212]<\/strong> Cf. <em>ibidem<\/em>, n. 336.<\/p>\n<p style=\"text-align: justify;\"><strong>[213]<\/strong> Cf. <em>ibidem<\/em>, n. 337.<\/p>\n<p style=\"text-align: justify;\"><strong>[214]<\/strong> Cf. <em>ibidem<\/em>, n. 209.<\/p>\n<p style=\"text-align: justify;\"><strong>[215]<\/strong> Cf. <em>ibidem<\/em>, n. 338.<\/p>\n<p style=\"text-align: justify;\"><strong>[216]<\/strong> Cf. S. Congr. per il Culto Div., Istr., <em>Liturgicae instaurationes<\/em>, n. 8c: AAS 62 (1970) p. 701.<\/p>\n<p style=\"text-align: justify;\"><strong>[217]<\/strong> Cf. Missale Romanum, Institutio Generalis, n. 346g.<\/p>\n<p style=\"text-align: justify;\"><strong>[218]<\/strong><em> Ibidem<\/em>, n. 114; cf. nn. 16-17.<\/p>\n<p style=\"text-align: justify;\"><strong>[219]<\/strong> S. Congr. per il Culto Div., Decr., <em>Eucharistiae sacramentum<\/em>, 21 giugno 1973: AAS 65 (1973) 610.<\/p>\n<p style=\"text-align: justify;\"><strong>[220]<\/strong> Cf. <em>ibidem.<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>[221]<\/strong> Cf. S. Congr. dei Riti, Istr., <em>Eucharisticum mysterium<\/em>, n. 54: AAS 59 (1967) p. 568; Istr., <em>Inter Oecumenici<\/em>, 26 settembre 1964, n. 95: AAS 56 (1964) p. 898; Missale Romanum, Institutio Generalis, n. 314.<\/p>\n<p style=\"text-align: justify;\"><strong>[222]<\/strong> Cf. Giovanni Paolo II, Lett., <em>Dominicae Cenae<\/em>, n. 3: AAS 72 (1980) pp. 117-119; S. Congr. dei Riti, Istr., <em>Eucharisticum mysterium<\/em>, n. 53: AAS 59 (1967) p. 568; <em>Codice di Diritto Canonico<\/em>, can. 938 \u00a7 2; Rituale Romanum, De sacra Communione et de cultu Mysterii eucharistici extra Missam, Praenotanda, n. 9; Missale Romanum, Institutio Generalis, nn. 314-317.<\/p>\n<p style=\"text-align: justify;\"><strong>[223]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>, can. 938 \u00a7\u00a7 3-5.<\/p>\n<p style=\"text-align: justify;\"><strong>[224]<\/strong> S. Congr. per la Disc. dei Sacram., Istr., <em>Nullo unquam<\/em>, 26 maggio 1938, n. 10d: AAS 30 (1938) p. 206.<\/p>\n<p style=\"text-align: justify;\"><strong>[225]<\/strong> Cf. Giovanni Paolo II, Motu proprio, <em>Sacramentorum sanctitatis tutela<\/em>, 30 aprile 2001: AAS 93 (2001) pp. 737-739; Congr. per la Dottrina della Fede, Lett. ai Vescovi della Chiesa Cattolica e agli altri Ordinari e Gerarchi interessati: sui delitti pi\u00f9 gravi riservati alla stessa Congregazione per la Dottrina della Fede: AAS 93 (2001) p. 786.<\/p>\n<p><strong>[226]<\/strong> Cf. Rituale Romanum, De sacra Communione et de cultu Mysterii eucharistici extra Missam, nn. 26-78.<\/p>\n<p><strong>[227]<\/strong> Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>,<em>\u00a0<\/em>n. 25: AAS 95 (2003) pp. 449-450.<\/p>\n<p style=\"text-align: justify;\"><strong>[228]<\/strong> Cf. Conc. Ecum. Trid., Sess. XIII, 11 ottobre 1551, Decr. sulla Ss. Eucharistia, cap. 5: DS 1643; Pio XII, Lett. Enc., <em>Mediator Dei<\/em>: AAS 39 (1947) p. 569; Paolo VI, Lett. Enc.,<em>Mysterium Fidei<\/em>: AAS 57 (1965) pp. 769-770; S. Congr. dei Riti, Istr., <em>Eucharisticum mysterium<\/em>, n. 3f: AAS 59 (1967) p. 543; S. Congr. per i Sacram. e per il Culto Div., Istr.,<em>Inaestimabile donum<\/em>, n. 20: AAS 72 (1980) p. 339; Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>,<em>\u00a0<\/em>n. 25: AAS 95 (2003) pp. 449-450.<\/p>\n<p style=\"text-align: justify;\"><strong>[229]<\/strong> Cf. <em>Ebr<\/em> 9, 11; Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 3: AAS 95 (2003) p. 435.<\/p>\n<p style=\"text-align: justify;\"><strong>[230]<\/strong> Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 25: AAS 95 (2003) p. 450.<\/p>\n<p style=\"text-align: justify;\"><strong>[231]<\/strong> Paolo VI, Lett. Enc., <em>Mysterium fidei<\/em>, 3 settembre 1965: AAS 57 (1965) p. 771.<\/p>\n<p style=\"text-align: justify;\"><strong>[232]<\/strong> Cf. Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 25: AAS 95 (2003) pp. 449-450.<\/p>\n<p style=\"text-align: justify;\"><strong>[233]<\/strong><em> Codice di Diritto Canonico<\/em>,can. 937.<\/p>\n<p style=\"text-align: justify;\"><strong>[234]<\/strong> Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 10: AAS 95 (2003) p. 439.<\/p>\n<p style=\"text-align: justify;\"><strong>[235]<\/strong> Cf. Rituale Romanum, De sacra Communione et de cultu Mysterii eucharistici extra Missam, nn. 82-100; Missale Romanum, Institutio Generalis, n. 317; <em>Codice di Diritto Canonico<\/em>,can. 941 \u00a7 2.<\/p>\n<p style=\"text-align: justify;\"><strong>[236]<\/strong> Giovanni Paolo II, Lett.. Ap., <em>Rosarium Virginis Mariae<\/em>, 16 ottobre 2002: AAS 95 (2003) pp. 5-36; qui n. 2, p. 6.<\/p>\n<p style=\"text-align: justify;\"><strong>[237]<\/strong> Cf. Congr. per il Culto Div. e la Disc. dei Sacram., Lettera della Congregazione, 15 gennaio 1997: <em>Notitiae<\/em> 34 (1998) pp. 506-510; Penit. Apost., Lett. a qualche sacerdote, 8 marzo 1996: Notitiae 34 (1998) 511.<\/p>\n<p style=\"text-align: justify;\"><strong>[238]<\/strong> Cf. S. Congr. dei Riti, Istr., <em>Eucharisticum mysterium<\/em>, n. 61: AAS 59 (1967) p. 571; Rituale Romanum, De sacra Communione et de cultu Mysterii eucharistici extra Missam, n. 83; Missale Romanum, Institutio Generalis, n. 317; <em>Codice di Diritto Canonico<\/em>,can. 941 \u00a7 2.<\/p>\n<p style=\"text-align: justify;\"><strong>[239]<\/strong> Cf. Rituale Romanum, De sacra Communione et de cultu Mysterii eucharistici extra Missam, n. 94.<\/p>\n<p style=\"text-align: justify;\"><strong>[240]<\/strong> Cf. Giovanni Paolo II, Cost. Ap., <em>Pastor bonus<\/em>, art. 65: AAS 80 (1988) p. 877.<\/p>\n<p style=\"text-align: justify;\"><strong>[241]<\/strong><em> Codice di Diritto Canonico<\/em>, can. 944 \u00a7 2; cf. Rituale Romanum, De sacra Communione et de cultu Mysterii eucharistici extra Missam, Praenotanda, n. 102; Missale Romanum, Institutio Generalis, n. 317.<\/p>\n<p style=\"text-align: justify;\"><strong>[242]<\/strong><em> Codice di Diritto Canonico<\/em>, can. 944 \u00a7 1; cf. Rituale Romanum, De sacra Communione et de cultu Mysterii eucharistici extra Missam, Praenotanda, nn. 101-102; Missale Romanum, Institutio Generalis, n. 317.<\/p>\n<p style=\"text-align: justify;\"><strong>[243]<\/strong> Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 10: AAS 95 (2003) p. 439.<\/p>\n<p style=\"text-align: justify;\"><strong>[244]<\/strong> Cf. Rituale Romanum, De sacra Communione et de cultu Mysterii eucharistici extra Missam, Praenotanda, n. 109.<\/p>\n<p style=\"text-align: justify;\"><strong>[245]<\/strong> Cf. <em>ibidem<\/em>, nn. 109-112.<\/p>\n<p style=\"text-align: justify;\"><strong>[246]<\/strong> Cf. Missale Romanum, In sollemnitate sanctissimi Corporis et Sanguinis Christi, Collecta, p. 489.<\/p>\n<p style=\"text-align: justify;\"><strong>[247]<\/strong> Cf. Congr. per il Clero ed altre, Istr., <em>Ecclesiae de mysterio<\/em>, Principi teologici, n. 3: AAS 89 (1997) p. 859.<\/p>\n<p style=\"text-align: justify;\"><strong>[248]<\/strong><em> Codice di Diritto Canonico<\/em>, can. 900 \u00a7 1; cf. Conc. Ecum. Lateran. IV., 11-30 novembre 1215, cap. 1: DS 802; Clemente VI, Lett. ad Mekhitar, Catholicon Armeniorum,<em>Super quibusdam<\/em>, 29 settembre 1351: DS 1084; Conc. Ecum. Trid., Sess. XXIII, 15 luglio 1563, Dottrina e canoni sulla sacr. ordin., cap. 4: DS 1767-1770; Pio XII, Lett. Enc.,<em>Mediator Dei<\/em>: AAS 39 (1947) p. 553.<\/p>\n<p style=\"text-align: justify;\"><strong>[249]<\/strong> Cf.<em>Codice di Diritto Canonico<\/em>, can. 230 \u00a7 3; Giovanni Paolo II, Discorso al Simposio sulla \u00abpartecipazione dei fedeli laici al ministero pastorale dei sacerdoti\u00bb, 22 aprile 1994, n. 2: <em>L\u2019Osservatore Romano<\/em>, 23 aprile 1994; Congr. per il Clero ed altre, Istr., <em>Ecclesiae de mysterio<\/em>, Proemio: AAS 89 (1997) pp. 852-856.<\/p>\n<p style=\"text-align: justify;\"><strong>[250]<\/strong> Cf. Giovanni Paolo II, Lett. Enc., <em>Redemptoris missio<\/em>, nn. 53-54: <em>AAS <\/em>83 (1991) pp. 300-302; Congr. per il Clero ed altre, Istr., <em>Ecclesiae de mysterio<\/em>, Proemio: AAS 89 (1997) pp. 852-856.<\/p>\n<p style=\"text-align: justify;\"><strong>[251]<\/strong> Cf. Conc. Ecum. Vat. II, Decreto sull\u2019attivit\u00e0 missionaria della Chiesa, <em>Ad gentes<\/em>, 7 dicembre 1965, n. 17; Giovanni Paolo II, Lett. Enc., <em>Redemptoris missio<\/em>, n. 73: AAS 83 (1991) p. 321.<\/p>\n<p style=\"text-align: justify;\"><strong>[252]<\/strong> Cf. Congr. per il Clero ed altre, Istr., <em>Ecclesiae de mysterio<\/em>, Disposizioni pratiche, art. 8 \u00a7 2: AAS 89 (1997) p. 872.<\/p>\n<p style=\"text-align: justify;\"><strong>[253]<\/strong> Cf. Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 32: AAS 95 (2003) p. 455.<\/p>\n<p style=\"text-align: justify;\"><strong>[254]<\/strong><em> Codice di Diritto Canonico<\/em>, can. 900 \u00a7 1.<\/p>\n<p style=\"text-align: justify;\"><strong>[255]<\/strong> Cf. <em>ibidem<\/em>, can. 910 \u00a7 1; cf. anche Giovanni Paolo II, Lett., <em>Dominicae Cenae<\/em>, n. 11: AAS 72 (1980) p. 142; Congr. per il Clero ed altre, Istr., <em>Ecclesiae de mysterio<\/em>, Disposizioni pratiche, art. 8 \u00a7 1: AAS 89 (1997) pp. 870-871.<\/p>\n<p style=\"text-align: justify;\"><strong>[256]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>, can. 230 \u00a7 3.<\/p>\n<p style=\"text-align: justify;\"><strong>[257]<\/strong> Cf. S. Congr. per la Disc. dei Sacram., Istr., <em>Immensae caritatis<\/em>, proemio: AAS 65 (1973) p. 264; Paolo VI, Motu proprio, <em>Ministeria quaedam<\/em>, 15 agosto 1972: AAS 64 (1972) p. 532; Missale Romanum, Appendix III: Ritus ad deputandum ministrum sacrae Communionis ad actum distribuendae, p. 1253; Congr. per il Clero ed altre, Istr., <em>Ecclesiae de mysterio<\/em>, Disposizioni pratiche, art. 8 \u00a7 1: AAS 89 (1997) p. 871.<\/p>\n<p style=\"text-align: justify;\"><strong>[258]<\/strong> Cf. S. Congr. per i Sacram. e per il Culto Div., Istr.,\u00a0<em>Inaestimabile donum<\/em>,<em>\u00a0<\/em>n. 10: AAS 72 (1980) p. 336; cf. Pont. Comm. per l\u2019Interpretazione Autentica del Codice di Diritto Canonico, Responsio ad propositum dubium, 11 luglio 1984: AAS 76 (1984) p. 746.<\/p>\n<p style=\"text-align: justify;\"><strong>[259]<\/strong> Cf. S. Congr. per la Disc. dei Sacram., Istr., <em>Immensae caritatis<\/em>, n. 1: AAS 65 (1973) pp. 264-271, qui pp. 265-266; Pont. Comm. per l\u2019Interpr. autent. del Codice di Diritto Canonico, Responsio ad propositum dubium, 1 giugno 1988: AAS 80 (1988) p. 1373; Congr. per il Clero ed altre, Istr., <em>Ecclesiae de mysterio<\/em>, Disposizioni pratiche, art. 8 \u00a7 2: AAS 89 (1997) p. 871.<\/p>\n<p style=\"text-align: justify;\"><strong>[260]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>, can. 767 \u00a7 1.<\/p>\n<p style=\"text-align: justify;\"><strong>[261]<\/strong> Cf. <em>ibidem<\/em>, can. 766.<\/p>\n<p style=\"text-align: justify;\"><strong>[262]<\/strong> Cf. Congr. per il Clero ed altre, Istr., <em>Ecclesiae de mysterio<\/em>, Disposizioni pratiche, art. 2 \u00a7\u00a7 3-4: AAS 89 (1997) p. 865.<\/p>\n<p style=\"text-align: justify;\"><strong>[263]<\/strong> Cf. Giovanni Paolo II, Ep. Ap., <em>Dies Domini<\/em>, specialmente nn. 31-51: AAS 90 (1998) pp. 713-766, qui pp. 731-746; Giovanni Paolo II, Lett. Ap., <em>Novo Millennio ineunte<\/em>, 6 gennaio 2001, nn. 35-36: AAS 93 (2001) pp. 290-292; Giovanni Paolo II, Lett. Enc.,<em>Ecclesia de Eucharistia<\/em>, n. 41: AAS 95 (2003) pp. 460-461.<\/p>\n<p style=\"text-align: justify;\"><strong>[264]<\/strong> Conc. Ecum. Vat. II, Decr. sul ministero e la vita dei sacerdoti, <em>Presbyterorum ordinis<\/em>, n. 6; cf. Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, nn. 22, 33: AAS 95 (2003) pp. 448, 455-456.<\/p>\n<p style=\"text-align: justify;\"><strong>[265]<\/strong> Cf. S. Congr. dei Riti, Istr., <em>Eucharisticum mysterium<\/em>, n. 26: AAS 59 (1967) pp. 555-556; Congr. per il Culto Divino, Direttorio per le celebrazioni domenicali in assenza del sacerdote, <em>Christi Ecclesia<\/em>, 2 giugno 1988, nn. 5 e 25: <em>Notitiae<\/em> 24 (1988) pp. 366-378, qui pp. 367, 372.<\/p>\n<p style=\"text-align: justify;\"><strong>[266]<\/strong> Cf. Congr. per il Culto Divino, Direttorio per le celebrazioni domenicali in assenza del sacerdote, <em>Christi Ecclesia<\/em>, 2 giugno 1988, n. 18: <em>Notitiae<\/em> 24 (1988) pp. 366-378, qui p. 370.<\/p>\n<p style=\"text-align: justify;\"><strong>[267]<\/strong> Cf. Giovanni Paolo II, Lett., <em>Dominicae Cenae<\/em>, n. 2: AAS 72 (1980) p. 116.<\/p>\n<p style=\"text-align: justify;\"><strong>[268]<\/strong> Cf. Giovanni Paolo II, Lett. Ap., <em>Dies Domini<\/em>, n. 49: AAS 90 (1998) p. 744; Lett. Enc.,<em>Ecclesia de Eucharistia<\/em>, n. 41: AAS 95 (2003) pp. 460-461; <em>Codice di Diritto Canonico<\/em>, cann. 1246-1247.<\/p>\n<p style=\"text-align: justify;\"><strong>[269]<\/strong><em> Codice di Diritto Canonico<\/em>, can. 1248 \u00a7 2; cf. Congr. per il Culto Divino, Direttorio per le celebrazioni domenicali in assenza del sacerdote, <em>Christi Ecclesia<\/em>, 2 giugno 1988, nn. 1-2: <em>Notitiae<\/em> 24 (1988) pp. 366-378, qui p. 366.<\/p>\n<p style=\"text-align: justify;\"><strong>[270]<\/strong> Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 33: AAS 95 (2003) pp. 455-456.<\/p>\n<p style=\"text-align: justify;\"><strong>[271]<\/strong> Cf. Congr. per il Culto Divino, Direttorio per le celebrazioni domenicali in assenza del sacerdote, <em>Christi Ecclesia<\/em>, 2 giugno 1988, n. 22: <em>Notitiae<\/em> 24 (1988) pp. 366-378, qui p. 371.<\/p>\n<p style=\"text-align: justify;\"><strong>[272]<\/strong>Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 30: AAS 95 (2003) pp. 453-454; cf. anche Pont. Cons. per la Promoz. dell\u2019Unit\u00e0 dei Cristiani, Direttorio per l\u2019applicazione dei principi e norme sull\u2019ecumenismo, <em>La recherche de l\u2019unit\u00e9<\/em>, n. 115: AAS 85 (1993) p. 1085.<\/p>\n<p style=\"text-align: justify;\"><strong>[273]<\/strong> Cf. Pont. Cons. per la Promoz. dell\u2019Unit\u00e0 dei Cristiani, Direttorio per l\u2019applicazione dei principi e norme sull\u2019ecumenismo, <em>La recherche de l\u2019unit\u00e9<\/em>, n. 101: AAS 85 (1993) pp. 1081-1082.<\/p>\n<p style=\"text-align: justify;\"><strong>[274]<\/strong><em> Codice di Diritto Canonico<\/em>,can. 292; cf. Pont. Cons. per l\u2019Interpr. dei Testi Legislativi, Dichiarazione sulla retta interpretazione del can. 1335, seconda parte, C.I.C., 15 maggio 1997, n. 3: AAS 90 (1998) p. 64.<\/p>\n<p style=\"text-align: justify;\"><strong>[275]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>, cann. 976; 986 \u00a7 2.<\/p>\n<p style=\"text-align: justify;\"><strong>[276]<\/strong> Cf. Pont. Cons. per l\u2019Interpr. dei Testi Legislativi, Dichiarazione sulla retta interpretazione del can. 1335, seconda parte, C.I.C., 15 maggio 1997, nn. 1-2: AAS 90 (1998) pp. 63-64.<\/p>\n<p style=\"text-align: justify;\"><strong>[277]<\/strong> Per ci\u00f2 che riguarda i sacerdoti che hanno ottenuto la dispensa dal celibato, cf. S. Congr. per la Dottrina della Fede, Norme sulla dispensa dal celibato sacerdotale, <em>Normae substantiales<\/em>, 14 ottobre 1980, art. 5; cf. anche Congr. per il Clero ed altre, Istr., <em>Ecclesiae de mysterio<\/em>, Disposizioni pratiche, art. 3 \u00a7 5: AAS 89 (1997) p. 865.<\/p>\n<p style=\"text-align: justify;\"><strong>[278]<\/strong> S. Tommaso d\u2019Aquino, <em>Summa Theol.<\/em>, II, 2, q. 93, a. 1.<\/p>\n<p style=\"text-align: justify;\"><strong>[279]<\/strong> Cf. Giovanni Paolo II, Lett. Ap., <em>Vicesimus quintus annus<\/em>, n. 15: AAS 81 (1989) p. 911; cf. anche Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, nn. 15-19.<\/p>\n<p style=\"text-align: justify;\"><strong>[280]<\/strong> Cf. Giovanni Paolo II, Motu proprio, <em>Sacramentorum sanctitatis tutela<\/em>, 30 aprile 2001: AAS 93 (2001) pp. 737-739; Congr. per la Dottrina della Fede, Lett. ai Vescovi della Chiesa Cattolica e agli altri Ordinari e Gerarchi interessati: sui delitti pi\u00f9 gravi riservati alla stessa Congregazione per la Dottrina della Fede: AAS 93 (2001) p. 786.<\/p>\n<p style=\"text-align: justify;\"><strong>[281]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>, can. 1367; Pont. Cons. per l\u2019Interpr. dei Testi Legislativi, Responsio ad propositum dubium, 3 luglio 1999: AAS 91 (1999) p. 918; Congr. per la Dottrina della Fede, Lett. ai Vescovi della Chiesa Cattolica e agli altri Ordinari e Gerarchi interessati: sui delitti pi\u00f9 gravi riservati alla stessa Congregazione per la Dottrina della Fede: AAS 93 (2001) p. 786.<\/p>\n<p style=\"text-align: justify;\"><strong>[282]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>, can. 1378 \u00a7 2 n. 1 et 1379; Congr. per la Dottrina della Fede, Lett. ai Vescovi della Chiesa Cattolica e agli altri Ordinari e Gerarchi interessati: sui delitti pi\u00f9 gravi riservati alla stessa Congregazione per la Dottrina della Fede: AAS 93 (2001) p. 786.<\/p>\n<p style=\"text-align: justify;\"><strong>[283]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>, can. 908 et 1365; Congr. per la Dottrina della Fede, Lett. ai Vescovi della Chiesa Cattolica e agli altri Ordinari e Gerarchi interessati: sui delitti pi\u00f9 gravi riservati alla stessa Congregazione per la Dottrina della Fede: AAS 93 (2001) p. 786.<\/p>\n<p style=\"text-align: justify;\"><strong>[284]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>, can. 927; Congr. per la Dottrina della Fede, Lett. ai Vescovi della Chiesa Cattolica e agli altri Ordinari e Gerarchi interessati: sui delitti pi\u00f9 gravi riservati alla stessa Congregazione per la Dottrina della Fede: AAS 93 (2001) p. 786.<\/p>\n<p style=\"text-align: justify;\"><strong>[285]<\/strong><em> Codice di Diritto Canonico<\/em>,can. 387.<\/p>\n<p style=\"text-align: justify;\"><strong>[286]<\/strong><em> Ibidem<\/em>, can. 838 \u00a7 4.<\/p>\n<p style=\"text-align: justify;\"><strong>[287]<\/strong><em> Ibidem<\/em>, can. 392.<\/p>\n<p style=\"text-align: justify;\"><strong>[288]<\/strong> Giovanni Paolo II, Cost. Ap., <em>Pastor bonus<\/em>, art. 52: AAS 80 (1988) p. 874.<\/p>\n<p style=\"text-align: justify;\"><strong>[289]<\/strong> Cf. <em>ibidem<\/em>, n. 63: AAS 80 (1988) p. 876.<\/p>\n<p style=\"text-align: justify;\"><strong>[290]<\/strong> Cf. <em>Codice di Diritto Canonico<\/em>, can. 1417 \u00a7 1.<\/p>\n<p style=\"text-align: justify;\"><strong>[291]<\/strong> Giovanni Paolo II, Lett. Enc., <em>Ecclesia de Eucharistia<\/em>, n. 24: AAS 95 (2003) p. 449.<\/p>\n<p style=\"text-align: justify;\"><strong>[292]<\/strong><em> Ibidem<\/em>, nn. 53-58: AAS 95 (2003) pp. 469-472.<\/p>\n<p style=\"text-align: justify;\"><strong>[293]<\/strong> Cf. Conc. Ecum. Vat. II, Cost. sulla Sacra Liturgia, <em>Sacrosanctum Concilium<\/em>, n. 14; cf. anche nn. 11, 41 e 48.<\/p>\n<p style=\"text-align: justify;\"><strong>[294]<\/strong> Cf. S. Tommaso d\u2019Aquino, <em>Summa Theol.<\/em>, III, q. 64, a. 9 ad primum.<\/p>\n<p style=\"text-align: justify;\"><strong>[295]<\/strong> Cf. Missale Romanum, Institutio Generalis, n. 24.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CONGREGAZIONE PER IL CULTO DIVINO E LA DISCIPLINA DEI SACRAMENTI\u00a0 ISTRUZIONE Redemptionis sacramentum su alcune cose che si devono osservare ed evitare circa la Santissima Eucaristia INDICE _______________________<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/redemptionis-sacramentum\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":26994,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,115],"tags":[1606,1094],"class_list":["post-26993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-liturgia","tag-abusi-liturgici","tag-s-messa","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Redemptionis sacramentum - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/redemptionis-sacramentum\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Redemptionis sacramentum - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/redemptionis-sacramentum\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-14T22:00:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-09T08:21:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/10\/S.Messa_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"280\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"104 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/redemptionis-sacramentum\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/redemptionis-sacramentum\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Redemptionis sacramentum\",\"datePublished\":\"2015-10-14T22:00:55+00:00\",\"dateModified\":\"2019-04-09T08:21:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/redemptionis-sacramentum\\\/\"},\"wordCount\":20875,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/redemptionis-sacramentum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/S.Messa_.jpg\",\"keywords\":[\"abusi liturgici\",\"S Messa\"],\"articleSection\":[\"Chiesa\",\"Liturgia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/redemptionis-sacramentum\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/redemptionis-sacramentum\\\/\",\"name\":\"Redemptionis sacramentum - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/redemptionis-sacramentum\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/redemptionis-sacramentum\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/S.Messa_.jpg\",\"datePublished\":\"2015-10-14T22:00:55+00:00\",\"dateModified\":\"2019-04-09T08:21:19+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/redemptionis-sacramentum\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/redemptionis-sacramentum\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/redemptionis-sacramentum\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/S.Messa_.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/S.Messa_.jpg\",\"width\":280,\"height\":180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/redemptionis-sacramentum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Redemptionis sacramentum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Redemptionis sacramentum - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/redemptionis-sacramentum\/","og_locale":"it_IT","og_type":"article","og_title":"Redemptionis sacramentum - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/redemptionis-sacramentum\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2015-10-14T22:00:55+00:00","article_modified_time":"2019-04-09T08:21:19+00:00","og_image":[{"width":280,"height":180,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/10\/S.Messa_.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"104 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/redemptionis-sacramentum\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/redemptionis-sacramentum\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Redemptionis sacramentum","datePublished":"2015-10-14T22:00:55+00:00","dateModified":"2019-04-09T08:21:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/redemptionis-sacramentum\/"},"wordCount":20875,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/redemptionis-sacramentum\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/10\/S.Messa_.jpg","keywords":["abusi liturgici","S Messa"],"articleSection":["Chiesa","Liturgia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/redemptionis-sacramentum\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/redemptionis-sacramentum\/","name":"Redemptionis sacramentum - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/redemptionis-sacramentum\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/redemptionis-sacramentum\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/10\/S.Messa_.jpg","datePublished":"2015-10-14T22:00:55+00:00","dateModified":"2019-04-09T08:21:19+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/redemptionis-sacramentum\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/redemptionis-sacramentum\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/redemptionis-sacramentum\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/10\/S.Messa_.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/10\/S.Messa_.jpg","width":280,"height":180},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/redemptionis-sacramentum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Redemptionis sacramentum"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/26993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=26993"}],"version-history":[{"count":7,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/26993\/revisions"}],"predecessor-version":[{"id":42704,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/26993\/revisions\/42704"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/26994"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=26993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=26993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=26993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}