{"id":2674,"date":"2009-02-27T12:53:09","date_gmt":"2009-02-27T11:53:09","guid":{"rendered":""},"modified":"2015-01-28T09:01:17","modified_gmt":"2015-01-28T08:01:17","slug":"una-costituzione-senza-dio","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-costituzione-senza-dio\/","title":{"rendered":"Una Costituzione senza Dio"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/02\/costituz.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-17895\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/02\/costituz.jpg\" alt=\"costituz\" width=\"178\" height=\"200\" \/><\/a>Il Timone<\/strong> n.76 settembre-ottobre 2008<\/div>\n<p style=\"text-align: justify;\"><em>La Carta del 1948 compie sessant&#8217;anni. Fu il prodotto del compromesso fra cultura cattolica, partiti marxisti e forze laiche. E porta con s\u00e9 una colpa originale: non parla di Dio<\/em><\/p>\n<p style=\"text-align: justify;\"><em>La Costituzione della Repubblica italiana compie 60 anni. Era il primo gennaio del 1948 quando il testo fondamentale del nostro ordinamento entrava formalmente in vigore. La Costituzione era stata approvata pochi giorni prima, il 22 dicembre del &#8217;47, con una maggioranza schiacciante, che sfiorava l&#8217;unanimit\u00e0: 453 i voti favorevoli tra i membri dell&#8217;Assemblea costituente, soltanto 62 i contrari. Un risultato sorprendente, se si considera quale fosse la composizione di quell&#8217;organismo, eletto dagli italiani il 2 giugno del 1946.<\/em><\/p>\n<div><!--more--><\/div>\n<p style=\"text-align: justify;\"><strong>Un compromesso storico<\/strong><\/p>\n<p style=\"text-align: justify;\">Nella Costituente, 207 seggi erano andati alla Democrazia cristiana (35,2%), 115 seggi al Partito socialista di unit\u00e0 proletaria (20,7%) e 104 al Partito comunista italiano (19,9%). Seguivano liberali e demolaburisti con 41 seggi, il Frante dell&#8217;Uomo qualunque con 30 rappresentanti, i Repubblicani con 23 seggi, i Monarchici con 16 seggi, il Partito d&#8217;Azione con 7. Si pu\u00f2 subito notare che comunisti e socialisti insieme contavano su un numero di voti superiore a quello del partito di maggioranza relativa, la Dc. L&#8217;influsso della componente marxista e materialista sarebbe quindi stato determinante per la stesura della carta costituzionale.<\/p>\n<p style=\"text-align: justify;\">Non solo: dopo la caduta del regime guidato da Benito Mussolini, il 25 luglio 1943, i cosiddetti partiti antifascisti avevano inaugurato una stagione di stretta collaborazione, dando vita a una serie di governi composti da democristiani, comunisti, socialisti, liberali e azionisti.<\/p>\n<p style=\"text-align: justify;\">Era pur vero che il rapporto fra social-comunisti e il resto dei partiti si era poi progressivamente deteriorato. Ma nell&#8217;Assemblea costituente fu chiaro fin dall&#8217;inizio che si sarebbe lavorato alla stesura di un testo di compromesso, in grado di mettere d&#8217;accordo anime cos\u00ec diverse.<\/p>\n<p style=\"text-align: justify;\">Paimiro Togliatti descrisse in questi termini il lavoro della Costituente: \u00abAbbiamo cercato di arrivare ad una unit\u00e0, cio\u00e8 di individuare quale poteva essere il terreno comune sul quale potevano confluire correnti ideologiche e politiche diverse\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Una Costituzione senza Dio<\/strong><\/p>\n<p style=\"text-align: justify;\">Le parole di Togliatti fotografano con molta onest\u00e0 il risultato fissato sulla Carta nel testo che ancora oggi \u00e8 alla base della Repubblica italiana. La mediazione fra cattolici e marxisti produsse una prima vittima illustre fin dalle prime righe: nella Costituzione italiana non c&#8217;\u00e8 alcuna traccia di Dio. Il deputato democristiano Giorgio La Pira, prendendo la parola alla vigilia del voto finale, il 22 dicembre del 1947, propose di far precedere agli articoli gi\u00e0 votati un breve preambolo, in cui si facesse esplicito riferimento a Dio come ispiratore della nuova Costituzione.<\/p>\n<p style=\"text-align: justify;\">La proposta non piacque ai laici &#8211; anche se Giuseppe Saragat si dichiar\u00f2 favorevole &#8211; e suscit\u00f2 perplessit\u00e0 nella stessa Democrazia cristiana perch\u00e9, come riferisce uno storico cattolico, \u00abil nome di Dio rischiava di essere un ulteriore elemento di divisione e di vanificare il vastissimo accordo che andava profilandosi\u00bb. Alla fine, lo stesso La Pira fu indotto suo malgrado a ritirare la proposta.<\/p>\n<p style=\"text-align: justify;\">Si dir\u00e0 che quel richiamo a un Dio generico non avrebbe modificato le sorti del nostro Paese. Pu\u00f2 darsi. Ma \u00e8 pur vero che si tratt\u00f2 di un segnale politico e culturale molto forte, anche all&#8217;interno dello stesso mondo cattolico: mentre da una parte Pio XII riteneva giustamente prioritario &#8220;ricristianizzare l&#8217;Italia&#8221;, la dirigenza democristiana riteneva che la sua missione storica consistesse nel laicizzare e democratizzare il Paese, peri agganciarlo alla modernit\u00e0.<\/p>\n<p style=\"text-align: justify;\">II risultato \u00e8 una Costituzione repubblicana materialista e apertamente atea, che sul tema della religione e del rapporto fra l&#8217;uomo e Dio consuma uno strappo radicale rispetto al precedente Statuto Albertino, promulgato nel 1848.<\/p>\n<p style=\"text-align: justify;\"><strong>Il lavoro come valore supremo<\/strong><\/p>\n<p style=\"text-align: justify;\">L&#8217;esito paradossale della &#8220;abolizione costituzionale di Dio&#8221; \u00e8 che la Carta si apre all&#8217;articolo 1 con una infelicissima formulazione, che rimanda vagamente ai Paesi del blocco sovietico e al Capitale di Marx: \u00abL&#8217;Italia \u00e8 una Repubblica democratica, fondata sul lavoro\u00bb. Dove si coglie immediatamente tutto peso dell&#8217;antropologia social-comunista, I che pone addirittura al vertice dell&#8217;architettura statuale il lavoro umano, inteso come &#8220;forza lavoro&#8221;. E dove si nota l&#8217;elevazione a I valore assoluto di due concetti &#8211; repubblica e democrazia &#8211; che sono invece ambivalenti, ambigui, e relativi ai contenuti che intendono promuovere. Ci sono cio\u00e8 democrazie buone e democrazie cattive.<\/p>\n<p style=\"text-align: justify;\">A queste critiche si pu\u00f2 obiettare che la Carta del 1948 contiene in grande quantit\u00e0 principi e valori di diretta derivazione cristiana. Effettivamente, il contributo della cultura cattolica in molti snodi della Costituzione \u00e8 ancora oggi del tutto evidente. Basti citare, ad esempio, il fatto che i diritti inviolabili dell&#8217;uomo sono &#8220;riconosciuti&#8221; dalla Repubblica (articolo 2) con una implicita allusione al fatto che questi diritti preesistono allo Stato e hanno un fondamento meta-giuridico, e che quindi non sono inventati o creati dal legislatore.<\/p>\n<p style=\"text-align: justify;\">Oppure si pensi all&#8217;articolo 29, dove la famiglia \u00e8 definita come \u00absociet\u00e0 naturale fondata sul matrimonio\u00bb, e dove &#8220;l&#8217;unit\u00e0 familiare&#8221; \u00e8 riconosciuta come preminente sui pur legittimi interessi dei coniugi. Articoli di evidente impronta giusnaturalistica, che tuttavia manifestano il loro tallone d&#8217;Achille proprio nella mancanza di una fondazione metafisica.<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 infatti chiaro &#8211; n\u00e9 la Carta si sforza di spiegarlo &#8211; quali siano le radici degli spesso evocati &#8220;valori costituzionali&#8221;. L&#8217;assenza di ogni riferimento al Creatore autorizza a pensare che tutte le norme, anche le supreme e fondative dell&#8217;ordinamento, siano soltanto il prodotto della volont\u00e0 arbitraria degli uomini, che si proclamano &#8220;autolegislatori&#8221; e fonte ultima ed esclusiva del diritto vigente. Per cui i contenuti della Costituzione vengono relativizzati e sottomessi al mutevole capriccio delle mode e delle generazioni che si susseguono nel tempo.<\/p>\n<p style=\"text-align: justify;\">Dire infatti &#8211; come fa pomposamente l&#8217;articolo 1 &#8211; che \u00abla sovranit\u00e0 appartiene al popolo\u00bb, e dirlo senza evocare la divinit\u00e0, significa riaffermare prometeicamente che non esiste alcuna autorit\u00e0 alla quale l&#8217;uomo deve rendere conto. Significa, insomma, trasformare il principio di maggioranza in un assoluto etico e giuridico.<\/p>\n<p style=\"text-align: justify;\"><strong>La Costituzione come Moloc intoccabile<\/strong><\/p>\n<p style=\"text-align: justify;\">Non vogliamo certo negare i molti contenuti positivi che la Costituzione del 1948 ha consegnato alla nostra cultura giuridica. Valori e modelli gi\u00e0 presenti nella poderosa e insuperata tradizione romanistica, affinati dalla giurisprudenza classica italiana, e solennizzati in numerosi articoli della nostra Carta costituzionale. Tuttavia, la storia della repubblica \u00e8 costellata di svolte legislative che hanno rivelato la debolezza sostanziale della nostra Costituzione. Pensiamo alla legalizzazione del divorzio, vulnus gravissimo alla natura intrinseca del matrimonio; o all&#8217;approvazione della legge sull&#8217;aborto, che contrasta proprio con l&#8217;articolo 2 della Costituzione.<\/p>\n<p style=\"text-align: justify;\">Queste leggi ingiuste, approvate con la &#8220;benedizione&#8221; della Corte Costituzione, confermano l&#8217;esistenza di una radice malata nell&#8217;intero impianto costituzionale, una sorta di debolezza congenita che consentir\u00e0, purtroppo, ulteriori derive nei prossimi anni. Ad esempio sul terreno dell&#8217;eutanasia e delle cosiddette coppie di fatto. Ragioni pi\u00f9 che valide per abbandonare una certa visione idolatrica della Costituzione, diffusa anche in alcuni settori del mondo cattolico italiano. Quasi che la Costituzione del &#8217;48 sia una sorta di appendice alle tavole della legge che Mos\u00e8 ricevette da Dio sul monte Sinai.<\/p>\n<p style=\"text-align: justify;\">Si tratta, molto pi\u00f9 prosaicamente, di una legge fatta da uomini, mortali e fallibili. Molti dei quali, per giunta, affascinati da ideologie false e bugiarde.<\/p>\n<p style=\"text-align: justify;\"><strong>Bibliografia<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Tommaso D&#8217;Aquino<\/strong>, <em>La politica dei pr\u00ecncipi cristiani<\/em>, Edizioni Cantagalli, 1997.<\/p>\n<p style=\"text-align: justify;\"><strong>Roberto De Mattei<\/strong>, <em>Il centro che ci port\u00f2 a sinistra<\/em>, Edizioni Fiducia, 1994.<\/p>\n<p style=\"text-align: justify;\"><strong>Thomas S. Eliot<\/strong>, <em>L&#8217;idea di una societ\u00e0 cristiana<\/em>, Gribaudt,<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Timone n.76 settembre-ottobre 2008 La Carta del 1948 compie sessant&#8217;anni. Fu il prodotto del compromesso fra cultura cattolica, partiti marxisti e forze laiche. E porta con s\u00e9 una colpa originale: non parla di Dio La Costituzione della Repubblica italiana compie 60 anni. Era il primo gennaio del 1948 quando il testo fondamentale del nostro &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-costituzione-senza-dio\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":17895,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,96],"tags":[1525],"class_list":["post-2674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica-nazionale","category-storia-italiana","tag-costituzione-italiana","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Una Costituzione senza Dio - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-costituzione-senza-dio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una Costituzione senza Dio - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-costituzione-senza-dio\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-02-27T11:53:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-01-28T08:01:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/02\/costituz.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"212\" \/>\n\t<meta property=\"og:image:height\" content=\"238\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-costituzione-senza-dio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-costituzione-senza-dio\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Una Costituzione senza Dio\",\"datePublished\":\"2009-02-27T11:53:09+00:00\",\"dateModified\":\"2015-01-28T08:01:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-costituzione-senza-dio\\\/\"},\"wordCount\":1197,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-costituzione-senza-dio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/costituz.jpg\",\"keywords\":[\"costituzione italiana\"],\"articleSection\":[\"Politica nazionale\",\"Storia italiana\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-costituzione-senza-dio\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-costituzione-senza-dio\\\/\",\"name\":\"Una Costituzione senza Dio - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-costituzione-senza-dio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-costituzione-senza-dio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/costituz.jpg\",\"datePublished\":\"2009-02-27T11:53:09+00:00\",\"dateModified\":\"2015-01-28T08:01:17+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-costituzione-senza-dio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-costituzione-senza-dio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-costituzione-senza-dio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/costituz.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/costituz.jpg\",\"width\":212,\"height\":238},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/una-costituzione-senza-dio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una Costituzione senza Dio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una Costituzione senza Dio - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-costituzione-senza-dio\/","og_locale":"it_IT","og_type":"article","og_title":"Una Costituzione senza Dio - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-costituzione-senza-dio\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-02-27T11:53:09+00:00","article_modified_time":"2015-01-28T08:01:17+00:00","og_image":[{"width":212,"height":238,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/02\/costituz.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-costituzione-senza-dio\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-costituzione-senza-dio\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Una Costituzione senza Dio","datePublished":"2009-02-27T11:53:09+00:00","dateModified":"2015-01-28T08:01:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-costituzione-senza-dio\/"},"wordCount":1197,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-costituzione-senza-dio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/02\/costituz.jpg","keywords":["costituzione italiana"],"articleSection":["Politica nazionale","Storia italiana"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-costituzione-senza-dio\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-costituzione-senza-dio\/","name":"Una Costituzione senza Dio - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-costituzione-senza-dio\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-costituzione-senza-dio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/02\/costituz.jpg","datePublished":"2009-02-27T11:53:09+00:00","dateModified":"2015-01-28T08:01:17+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-costituzione-senza-dio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-costituzione-senza-dio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-costituzione-senza-dio\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/02\/costituz.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/02\/costituz.jpg","width":212,"height":238},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/una-costituzione-senza-dio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Una Costituzione senza Dio"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2674"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2674\/revisions"}],"predecessor-version":[{"id":17896,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2674\/revisions\/17896"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/17895"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}