{"id":2658,"date":"2009-02-26T13:02:46","date_gmt":"2009-02-26T12:02:46","guid":{"rendered":""},"modified":"2015-01-26T20:00:38","modified_gmt":"2015-01-26T19:00:38","slug":"i-gesuiti-tra-gli-indiani-del-west","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-gesuiti-tra-gli-indiani-del-west\/","title":{"rendered":"I gesuiti tra gli indiani del West"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/02\/gesuiti-nel-west.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-17775\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/02\/gesuiti-nel-west.png\" alt=\"gesuiti nel west\" width=\"169\" height=\"250\" \/><\/a>Studi Cattolici<\/strong> n.567 maggio 2008<\/div>\n<p style=\"text-align: center;\"><em>L&#8217;epopea dei missionari cattolici nelle terre selvagge del Nord America<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Paolo Poponessi<\/strong><\/p>\n<p style=\"text-align: justify;\">Quando si pensa alla corsa al West, ovvero alla colonizzazione degli sterminati territori dell&#8217;Ovest degli Stati Uniti nell&#8217;Ottocento, compare l&#8217;immagine tradizionale evocata perlopi\u00f9 con toni epici dalla cinematografia americana che ha come protagonisti i coloni bianchi, i cavalleggeri dell&#8217;esercito, i cercatori d&#8217;oro, banditi e avventurieri fronteggiati da sceriffi coraggiosi.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\"><\/div>\n<p style=\"text-align: justify;\">In realt\u00e0 la corsa al West fu qualche cosa di pi\u00f9 complesso della visione spesso oleografica che ne \u00e8 stata proposta, con tanti aspetti e vicende che meriterebbero di essere indagati e maggiormente conosciuti. Ad andare a Ovest non erano solo cercatori d&#8217;oro, allevatori o coloni in cerca di terre fertili da coltivare, ma anche missionari cristiani preoccupati della evangelizzazione di quelle terre. In particolare \u00e8 assai suggestiva la vicenda che vide protagonisti i cattolici con l&#8217;azione missionaria dei gesuiti che si svilupp\u00f2 a partire dal 1840 nel Nord Ovest degli Stati Uniti con la Missione gesuita delle Montagne Rocciose in un&#8217;area sterminata oggi compresa entro i confini degli Stati dell&#8217;Oregon, Idaho, Washington e Montana (1).<\/p>\n<p style=\"text-align: justify;\">La presenza della Compagnia di Ges\u00f9 contribu\u00ec a propagare il cattolicesimo sia tra i bianchi (agli inizi della missione erano comunque pochissimi) sia tra i nativi. Flatheads, Pend d&#8217;Oreilles, Crow, Cheyenne, Sioux, Nasi Forati, Piedi Neri, Coeur d&#8217;Alenes, Kalispel, Cree, Gros Ventres, Assiniboines, Spokane, Cayuse, Yakima, furono le tante trib\u00f9 indiane tra le quali la Compagnia di Ges\u00f9 organizz\u00f2 l&#8217;opera di evangelizzazione.<\/p>\n<p style=\"text-align: justify;\">La Missione delle Montagne Rocciose in effetti fu un tentativo che non impropriamente si pu\u00f2 accostare all&#8217;esperienza fatta dagli stessi gesuiti a partire dai primi del Seicento con le riduzioni paraguaiane tra gli indios sudamericani; non va dimenticato che il gesuita belga padre Pierre Jean De Smet, iniziatore della missione tra gli indiani del Nord Ovest, aveva tra le sue letture di riferimento Il Cristianesimo felice del Muratori, storia della missione gesuita in Paraguay.<\/p>\n<p style=\"text-align: justify;\">Nel Nord Ovest americano i missionari di sant&#8217;Ignazio tentarono un esperimento che, attraverso una convivenza con gli indiani capace di accogliere anche elementi della loro identit\u00e0 di popolo, si tradusse per i nativi in un incontro pacifico con il cattolicesimo, senza la violenza e la sopraffazione che quasi sempre gli indiani subirono nel loro rapporto con i bianchi.<\/p>\n<p style=\"text-align: justify;\"><strong>Una missione chiesta dagli indiani<\/strong><\/p>\n<p style=\"text-align: justify;\">L&#8217;inizio della missione avvenne davvero in modo inconsueto, visto che la presenza dei gesuiti fu espressamente richiesta dalle stesse trib\u00f9 indiane. Tutto cominci\u00f2 tra i Flatheads del Montana nordoccidentale, tra i quali si era insediato, attorno al 1816, un gruppo di indiani irochesi convertiti al cristianesimo che assunse il ruolo di promotore della diffusione della fede cristiana, facendone conoscere le basi elementari e presentandola come ci\u00f2 che poteva costituire un grande beneficio per la trib\u00f9, perch\u00e9 avrebbe indicato la strada della salvezza e dell&#8217;immortalit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Gli Irochesi sostenevano anche la necessit\u00e0 di chiedere la presenza, quali guide spirituali, dei gesuiti, gli \u00ababiti neri\u00bb. Questa prima elementare predicazione trov\u00f2 fertile terreno tra i Flatheads e anche la proposta di chiamare missionari gesuiti ebbe ottima accoglienza, poich\u00e9 si armonizzava con una tradizionale profezia venata di messianismo diffusa da tempo tra gli indiani, che indicava nella venuta di uomini vestiti di nero la salvezza per la trib\u00f9.<\/p>\n<p style=\"text-align: justify;\">Era quindi evidente che la proposta irochese di chiamare i gesuiti aveva dato un&#8217;identit\u00e0 ai misteriosi \u00ababiti neri\u00bb della profezia, probabile eco del passaggio avvenuto molti anni prima di qualche missionario gesuita nel Nord Ovest. Dopo una serie di tentativi falliti di instaurare un contatto con i missionari cattolici, finalmente, nell&#8217;estate del 1839, una delegazione indiana raggiunse Saint Louis, nel Missouri, e ottenne finalmente dal vescovo, l&#8217;italiano Giuseppe Rosati, l&#8217;assenso a fronte della richiesta della trib\u00f9.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec, fu incaricato per un primo contatto padre De Smet, che gi\u00e0 in precedenza era andato in missione presso la trib\u00f9 dei Pota-watomies: non a caso un gesuita, visto che l&#8217;assemblea plenaria dei vescovi degli Usa aveva deliberato nel 1837 a Baltimora di affidare la cura spirituale degli indiani alla Compagnia di Ges\u00f9.<\/p>\n<p style=\"text-align: justify;\">Dopo un primo viaggio esplorativo che conferm\u00f2 che vi erano le condizioni per stabilire la missione, nell&#8217;aprile del 1841 De Smet ripartiva con entusiasmo alla volta del Nord Ovest alla guida della prima pattuglia missionaria, e nello stesso anno nasceva la prima storica missione cattolica nel Montana, St. Mary, fondata sul luogo ove era stata sepolta una ragazzina indiana di tredici anni di nome Mary, battezzata dagli Irochesi, che in punto di morte aveva predetto la costruzione della missione e l&#8217;arrivo dei gesuiti, esortando gli indiani a seguire i loro insegnamenti.<\/p>\n<p style=\"text-align: justify;\">Nel 1844 fu fondata un&#8217;altra storica missione, quella di St. Ignatius (nel tempo spostata pi\u00f9 volte fino a trovare la sede definitiva nel 1854), che divenne un&#8217;importante base per l&#8217;attivit\u00e0 missionaria e sede di una tipografia che avvi\u00f2 una produzione editoriale di testi nelle varie lingue indiane.<\/p>\n<p style=\"text-align: justify;\">L&#8217;attivit\u00e0 dei gesuiti sin dagli inizi non si limit\u00f2 ai Flatheads, ma si allarg\u00f2 subito alle altre trib\u00f9 del Nord Ovest, mostrando gi\u00e0 in quei primi anni un forte dinamismo nonostante la vastit\u00e0 del territorio, la sua natura selvaggia e accidentata, e un clima poco accogliente.La vita delle prime missioni era estremamente dura, si viveva in condizioni di fortuna, senza i comfort abituali della societ\u00e0 civilizzata, spesso con limitate risorse alimentari, lontano dagli avamposti della civilt\u00e0.<\/p>\n<p style=\"text-align: justify;\">All&#8217;inizio essere missionari tra gli indiani voleva dire percorrere enormi distanze per seguirli nei loro spostamenti, comprese le lunghe campagne di caccia al bisonte, o viaggiare per lungo tempo su percorsi accidentati per raggiungere gli insediamenti delle trib\u00f9 pi\u00f9 isolate.<\/p>\n<p style=\"text-align: justify;\">Se \u00e8 vero che padre Pierre Jean De Smet fu il coraggioso e generoso pioniere dell&#8217;apostolato tra gli indiani del Nord Ovest, tocc\u00f2 per\u00f2 ad alcuni suoi successori, che ebbero l&#8217;incarico di superiori della Missione delle Montagne Rocciose, sviluppare grandemente l&#8217;attivit\u00e0 missionaria.<\/p>\n<p style=\"text-align: justify;\">I primi anni dopo il 1840 avevano visto un notevole dinamismo della missione, ma la fine degli anni &#8217;40 e i successivi anni &#8217;50 videro l&#8217;insorgere di difficolt\u00e0 che frenarono l&#8217;opera dei gesuiti, l\u2019impasse termin\u00f2 quando, nel 1858, vi fu la separazione della Missione delle Montagne Rocciose da quella della California, con la conseguente nomina di due distinti superiori, mentre entrambe erano state affidate gi\u00e0 dal 1854 alla cura della Provincia Torinese della Compagnia di Ges\u00f9.<\/p>\n<p style=\"text-align: justify;\">Tale assetto si sarebbe conservato fino al 1909, quando la Missione delle Montagne Rocciose sarebbe stata accorpata alla Missione Californiana, chiudendo cos\u00ec circa cinquant&#8217;anni di legami diretti con la Provincia Torinese. Il primo superiore della Missione delle Montagne Rocciose fu l&#8217;italiano Nicola Congiato, e va sottolineato che, indubbiamente, la ripresa di dinamicit\u00e0 missionaria coincise proprio con l&#8217;arrivo nel Nord Ovest di un consistente flusso di gesuiti italiani; in questo nuovo inizio della missione tra gli indiani risalta il ruolo e la figura del piemontese padre Giuseppe Giorda, personalit\u00e0 di grande rilievo e capacit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Per ben due volte, dal 1862 al 1866 e dal 1869 al 1877, Giorda fu massimo responsabile della Missione; fu poi con un altro italiano, padre Giuseppe Cataldo, superiore dal 1877 al 1893, che l&#8217;opera missionaria raggiunse il suo massimo sviluppo.<\/p>\n<p style=\"text-align: justify;\"><strong>Religiosi europei, chiave del successo<\/strong><\/p>\n<p style=\"text-align: justify;\">L&#8217;azione tra gli indiani produsse risultati considerevoli; la Chiesa cattolica nel 1873 sosteneva di avere nei tenitori del Nord Ovest verso il Pacifico pi\u00f9 di centomila fedeli tra gli indiani, a fronte dei circa quindicimila che facevano riferimento alle varie confessioni protestanti. Nell&#8217;area del Montana, dove verso il 1890 erano censiti circa diecimila indiani, quelli cattolici erano il settanta per cento.<\/p>\n<p style=\"text-align: justify;\">Interessanti sono i dati relativi all&#8217;attivit\u00e0 scolastica, particolarmente importante nell&#8217;ambito della Missione, che aiutano a comprendere meglio l&#8217;ampiezza del lavoro svolto dai gesuiti e la risposta degli indiani all&#8217;azione evangelizzatrice; infatti le statistiche relative alla frequenza dei giovani indiani alle scuole delle missioni nel Montana descrivono un fenomeno di tutto rispetto.<\/p>\n<p style=\"text-align: justify;\">Alla missione di St. Ignatius nel 1864 c&#8217;erano quattrocento scolari; a St. Peter, presso i Piedi Neri, gli studenti erano 200, mentre a St. Labr\u00e8, presso i Cheyenne, c&#8217;erano nel 1884 quaranta allievi. La missione di St. Paul tra gli Assiniboines e i Gros Ventres ospitava centoquarantacinque allievi nel 1886; quella di St. Xavier presso i Crow, nel periodo 1886\/1887 ne aveva centoventi, e analogo numero di allievi era presente nella missione di Holy Family, tra i Piedi Neri.<\/p>\n<p style=\"text-align: justify;\">Va per\u00f2 precisato che il successo della predicazione dei gesuiti non fu uniforme; ebbe maggior fortuna tra i Flatheads, i Pend D&#8217;Oreilles, i Kootenais, i Coeur d&#8217;Alenes, mentre il cattolicesimo si diffuse pi\u00f9 lentamente e con maggiori difficolt\u00e0 fra trib\u00f9 come i Piedi Neri, i Gros Ventres, gli Assiniboines, i Crow.<\/p>\n<p style=\"text-align: justify;\">Una delle ragioni dell&#8217;efficacia delle attivit\u00e0 missionarie tra gli indiani \u00e8 probabilmente da ricercare nell&#8217;impegno, nello zelo e nel sacrificio di gesuiti di origine europea, un carattere europeo della Missione rafforzato con la presa in carico della responsabilit\u00e0 dell&#8217;attivit\u00e0 da parte della Provincia Torinese dei gesuiti che invi\u00f2 ben 158 missionari.<\/p>\n<p style=\"text-align: justify;\">Il fatto che i missionari non fossero nati in America potrebbe avere contribuito a vincere le diffidenze e le resistenze dei nativi, che considerarono sempre i gesuiti \u00abaltro\u00bb rispetto ai bianchi americani che invadevano le loro terre e li privavano delle risorse per mantenere un&#8217;esistenza libera e indipendente. Nella sostanza gli \u00ababiti neri\u00bb erano per gli indiani portatori di una fede religiosa pronta a convivere pacificamente, e non erano visti come strumenti di un piano di sottomissione forzata.<\/p>\n<p style=\"text-align: justify;\">Va sottolineato poi che, durante i momenti di conflitto tra bianchi e indiani, i gesuiti svolsero iniziative di mediazione tra le parti, mantenendo una neutralit\u00e0 che non imped\u00ec loro di assumere iniziative volte a cercare di limitare le rappresaglie e i duri comportamenti dei militari americani verso le trib\u00f9, ben conoscendo l&#8217;origine di torti e vessazioni subite dagli indiani e le relative colpe dei bianchi.<\/p>\n<p style=\"text-align: justify;\">Anche per questo, spesso i gesuiti furono considerati con sospetto dalle autorit\u00e0 americane, mentre ebbero confermata la stima e l&#8217;amicizia delle trib\u00f9; eloquente, in tal senso, capo Giuseppe, guida dei Nasi Forati in una disperata resistenza contro l&#8217;esercito americano nel 1877, che cos\u00ec definiva il superiore della Missione dei gesuiti: \u00abPadre Cataldo \u00e8 mio amico ed \u00e8 un uomo buono. La mia gente gli vuole bene\u00bb.<\/p>\n<p style=\"text-align: justify;\">Altro elemento che facilit\u00f2 la relazione tra missionari e nativi fu la padronanza degli idiomi delle trib\u00f9, che fu un tratto comune a tutti missionari della Compagnia di Ges\u00f9, una condizione indispensabile per operare nel Nord Ovest; la padronanza delle lingue tribali serviva per un contatto senza mediazioni, secondo un metodo assai apprezzato dai nativi.<\/p>\n<p style=\"text-align: justify;\">La conoscenza delle lingue indiane si tradusse in una ricca attivit\u00e0 di studi di linguistica prodotti da un folto gruppo di missionari che venne poi diffusa attraverso l&#8217;attivit\u00e0 editoriale avviata nel Nord Ovest da parte degli stessi gesuiti, originalissimo e importante frutto della Missione nelle Montagne Rocciose (2).<\/p>\n<p style=\"text-align: justify;\">Ulteriore elemento che probabilmente contribu\u00ec alla penetrazione del cattolicesimo tra le trib\u00f9 fu la forte presenza di gesuiti di origine italiana in seno alla Missione delle Montagne Rocciose. Secondo un consolidato orientamento della storiografia americana, furono proprio gli italiani che proposero una fede cattolica filtrata dalla sensibilit\u00e0 latina e mediterranea, capace di affascinare gli indiani.<\/p>\n<p style=\"text-align: justify;\">In maniera sorprendente la spiritualit\u00e0 della tradizione cattolica italiana sarebbe stato il terreno di incontro con gli indiani, incoraggiando le relazioni e la convivenza. D&#8217;altra parte gioc\u00f2 a favore degli sforzi dei gesuiti anche un&#8217;altra loro capacit\u00e0, che appartiene al patrimonio di cultura e di esperienza pi\u00f9 affascinante del cattolicesimo: proporre una fede cattolica in grado di assorbire e utilizzare segni e strumenti della cultura dei nativi a loro famigliari (il canto, alcuni elementi della natura, l&#8217;attenzione a riti e simboli), in grado quindi di far percepire la nuova fede non estranea o legata a modelli culturali e di vita troppo lontani.<\/p>\n<p style=\"text-align: justify;\"><strong>Tempi duri per i gesuiti<\/strong><\/p>\n<p style=\"text-align: justify;\">II declino della Missione nel Nord Ovest fu un fatto graduale e determinato da una serie di fattori, e non da un&#8217;unica causa. Come gi\u00e0 evidenziato, lo slancio della missione era merito dei gesuiti di origine europea, con particolare riguardo a quelli italiani; l&#8217;organico della missione nelle Montagne Rocciose fu fortemente incrementato durante l&#8217;Ottocento da gesuiti che si trasferivano dall&#8217;Europa per sfuggire all&#8217;ondata di ostilit\u00e0 e persecuzione scatenata dall&#8217;ideologia liberale, che identificava nella religione cattolica, nel Papa e nei suoi difensori (in primis i gesuiti) i principali pilastri di un vecchio ordine sociale, politico e anche economico da abbattere.<\/p>\n<p style=\"text-align: justify;\">Caso emblematico fu l&#8217;Italia, dove il processo di unificazione nel suo progredire manifest\u00f2 un carattere anticattolico mantenutosi forte anche gli inizi della vita dello Stato unitario; furono anni nei quali l&#8217;emigrazione dei gesuiti divenne un flusso consistente che and\u00f2 a rinvigorire e rilanciare la Missione delle Montagne Rocciose.<\/p>\n<p style=\"text-align: justify;\">Quando per\u00f2, negli ultimi decenni del XIX secolo, la situazione italiana divenne, almeno in parte, meno dura e aspra per la Chiesa cattolica, l&#8217;emigrazione gesuita dall&#8217;Italia verso il Nord Ovest diminu\u00ec, fino a estinguersi. Cos\u00ec, gradualmente ma inesorabilmente, cominciarono ad assottigliarsi le fila di questa corposa componente italiana della Compagnia di Ges\u00f9 in questi tenitori.<\/p>\n<p style=\"text-align: justify;\">Probabilmente anche il rapporto non sempre facile tra gesuiti e Stato americano contribu\u00ec al tramonto di questa esperienza missionaria; gi\u00e0 attorno al 1870 la legislazione varata sotto la presidenza Grant, con un&#8217;arbitraria ripartizione delle trib\u00f9 in sfere di influenza tra le varie confessioni cristiane, cre\u00f2 problemi alla libert\u00e0 di manovra dei gesuiti.<\/p>\n<p style=\"text-align: justify;\">Successivamente la campagna di laicizzazione dell&#8217;insegnamento scolastico, autorevolmente sostenuta a livello politico-governativo e di opinione pubblica, fu un altro elemento di difficolt\u00e0 per l&#8217;attivit\u00e0 missionaria. Va poi anche rilevato che l&#8217;orientamento governativo circa l&#8217;obbligatoriet\u00e0 dell&#8217;utilizzo della lingua inglese anche nelle scuole dei gesuiti per gli indiani, oltre a contribuire al declino dell&#8217;uso delle lingue tribali cre\u00f2 ulteriori problemi a gesuiti, in gran parte italiani, che sistematicamente privilegiavano l&#8217;uso delle lingue indiane, che conoscevano assai meglio di quella inglese.<\/p>\n<p style=\"text-align: justify;\">Un colpo decisivo alla Missione fu portato, per\u00f2, a partire dagli ultimi anni dell&#8217;Ottocento, dallo sgretolamento del sistema delle riserve, ultima precaria barriera a difesa dell&#8217;autonoma identit\u00e0 indiana; la crisi del sistema tribale, la dispersione dei singoli nativi in un territorio con i bianchi ormai in maggioranza, la \u00abamericanizzazione\u00bb degli indiani, rendevano difficile la sopravvivenza della vecchia struttura e della sperimentata metodologia della Missione delle Montagne Rocciose.<\/p>\n<p style=\"text-align: justify;\">Il Nord Ovest \u00abcivilizzato\u00bb di fine Ottocento non attirava pi\u00f9 come sessant&#8217;anni prima i gesuiti, che iniziarono a essere affascinati da nuove terre di missione; era il caso della gelida Alaska, dove ancora vivevano trib\u00f9 di nativi in un ambiente e in condizioni di vita molto simili al Nord Ovest selvaggio dei primi decenni del XIX secolo, quando padre De Smet aveva dato inizio a una straordinaria e avventurosa epopea missionaria.<\/p>\n<p style=\"text-align: justify;\"><strong>Note<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>1)<\/strong> Vi sono numerosi lavori editi in Usa che descrivono la storia dei gesuiti nel Nord Ovest; fondamentali tra questi L. B. Palladino, Indian and White in the Northwest, Wickersham Publishing Company, Lancaster 1922; W. P. Schoenberg, Paths to the Norhtwest, Loyola University Press, Chicago 1982; G Me Kevitt, Brokers of Culture, Stanford University Press, Stanford 2007.<\/p>\n<p style=\"text-align: justify;\"><strong>2)<\/strong> Sulla produzione editoriale, da parte dei gesuiti, di testi in varie lingue tribali, si veda W. P. Schoenberg, Jesuit Mission Presses, Ye Galleon Press, Fairfield 1994.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Studi Cattolici n.567 maggio 2008 L&#8217;epopea dei missionari cattolici nelle terre selvagge del Nord America di Paolo Poponessi Quando si pensa alla corsa al West, ovvero alla colonizzazione degli sterminati territori dell&#8217;Ovest degli Stati Uniti nell&#8217;Ottocento, compare l&#8217;immagine tradizionale evocata perlopi\u00f9 con toni epici dalla cinematografia americana che ha come protagonisti i coloni bianchi, i &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-gesuiti-tra-gli-indiani-del-west\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":17775,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,76],"tags":[555,562],"class_list":["post-2658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-stati-uniti","tag-gesuiti","tag-missioni","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I gesuiti tra gli indiani del West - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-gesuiti-tra-gli-indiani-del-west\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I gesuiti tra gli indiani del West - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-gesuiti-tra-gli-indiani-del-west\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2009-02-26T12:02:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-01-26T19:00:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/02\/gesuiti-nel-west.png\" \/>\n\t<meta property=\"og:image:width\" content=\"185\" \/>\n\t<meta property=\"og:image:height\" content=\"273\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-gesuiti-tra-gli-indiani-del-west\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-gesuiti-tra-gli-indiani-del-west\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"I gesuiti tra gli indiani del West\",\"datePublished\":\"2009-02-26T12:02:46+00:00\",\"dateModified\":\"2015-01-26T19:00:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-gesuiti-tra-gli-indiani-del-west\\\/\"},\"wordCount\":2542,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-gesuiti-tra-gli-indiani-del-west\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/gesuiti-nel-west.png\",\"keywords\":[\"gesuiti\",\"missioni\"],\"articleSection\":[\"Chiesa\",\"Stati Uniti\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-gesuiti-tra-gli-indiani-del-west\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-gesuiti-tra-gli-indiani-del-west\\\/\",\"name\":\"I gesuiti tra gli indiani del West - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-gesuiti-tra-gli-indiani-del-west\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-gesuiti-tra-gli-indiani-del-west\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/gesuiti-nel-west.png\",\"datePublished\":\"2009-02-26T12:02:46+00:00\",\"dateModified\":\"2015-01-26T19:00:38+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-gesuiti-tra-gli-indiani-del-west\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-gesuiti-tra-gli-indiani-del-west\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-gesuiti-tra-gli-indiani-del-west\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/gesuiti-nel-west.png\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2009\\\/02\\\/gesuiti-nel-west.png\",\"width\":185,\"height\":273},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-gesuiti-tra-gli-indiani-del-west\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I gesuiti tra gli indiani del West\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I gesuiti tra gli indiani del West - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-gesuiti-tra-gli-indiani-del-west\/","og_locale":"it_IT","og_type":"article","og_title":"I gesuiti tra gli indiani del West - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-gesuiti-tra-gli-indiani-del-west\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2009-02-26T12:02:46+00:00","article_modified_time":"2015-01-26T19:00:38+00:00","og_image":[{"width":185,"height":273,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/02\/gesuiti-nel-west.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"12 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-gesuiti-tra-gli-indiani-del-west\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-gesuiti-tra-gli-indiani-del-west\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"I gesuiti tra gli indiani del West","datePublished":"2009-02-26T12:02:46+00:00","dateModified":"2015-01-26T19:00:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-gesuiti-tra-gli-indiani-del-west\/"},"wordCount":2542,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-gesuiti-tra-gli-indiani-del-west\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/02\/gesuiti-nel-west.png","keywords":["gesuiti","missioni"],"articleSection":["Chiesa","Stati Uniti"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-gesuiti-tra-gli-indiani-del-west\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-gesuiti-tra-gli-indiani-del-west\/","name":"I gesuiti tra gli indiani del West - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-gesuiti-tra-gli-indiani-del-west\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-gesuiti-tra-gli-indiani-del-west\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/02\/gesuiti-nel-west.png","datePublished":"2009-02-26T12:02:46+00:00","dateModified":"2015-01-26T19:00:38+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-gesuiti-tra-gli-indiani-del-west\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-gesuiti-tra-gli-indiani-del-west\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-gesuiti-tra-gli-indiani-del-west\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/02\/gesuiti-nel-west.png","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2009\/02\/gesuiti-nel-west.png","width":185,"height":273},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-gesuiti-tra-gli-indiani-del-west\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"I gesuiti tra gli indiani del West"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2658"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2658\/revisions"}],"predecessor-version":[{"id":17776,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2658\/revisions\/17776"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/17775"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}