{"id":26495,"date":"2015-07-16T00:00:10","date_gmt":"2015-07-15T22:00:10","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=26495"},"modified":"2015-07-09T11:01:00","modified_gmt":"2015-07-09T09:01:00","slug":"omosessualita-suicidio-e-malattie-mentali","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/omosessualita-suicidio-e-malattie-mentali\/","title":{"rendered":"Omosessualit\u00e0, suicidio e malattie mentali"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/07\/gay.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-26496 size-medium\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/07\/gay-300x127.jpg\" alt=\"gay\" width=\"300\" height=\"127\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/07\/gay-300x127.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/07\/gay.jpg 344w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Tradizione Famiglia e Propriet\u00e0<\/strong> n.65 giugno 2015<\/p>\n<p style=\"text-align: justify;\"><em>\u00c8 risaputo che il tasso di suicidi e di malattie mentali fra gli omosessuali \u00e8 molto pi\u00f9 elevato che tra gli eterosessuali. Ci\u00f2 \u00e8 dovuto alla pressione sociale &#8220;omofobica&#8221;, oppure allo stesso stile di vita omosessuale?<\/em><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">In un recente convegno, Massimo Gandolfini, noto neuroscienziato e primario di neurochirurgia alla fondazione Poliambulanza di Brescia, ha criticato chi attribuisce all&#8217;omofobia l&#8217;alto tasso di suicidi e di disturbi mentali delle persone omosessuali, mostrando invece che essi permangono anche nelle societ\u00e0 cosiddette &#8220;gay-friendly&#8221;. Immediata la reazione delle lobby LGBT. Su &#8220;L&#8217;Espresso&#8221;, per esempio, il giornalista e militante omosessualista Simone Alliva ha subito accusato Gandolf\u00ecni di voler imporre &#8220;cure e correzioni&#8221;.<\/p>\n<p style=\"text-align: justify;\">Come al solito, le lobby LGBT si stanno mettendo contro la scienza. Infatti, l&#8217;alto tasso di suicidi e di disturbi psico-fisici tra persone omosessuali \u00e8 purtroppo un dato di fatto, confermato da numerosi studi scientifici. Prendiamo, per esempio, l&#8217;ampio studio condotto nel 2008 da un team di psicologi e psichiatri britannici, basato su pi\u00f9 di 13mila casi: \u00ab<em>A systematic review of mental disorder, suicide, and deliberate self harm in lesbian, gay and bisexual people<\/em>\u00bb. Ecco alcune delle conclusioni:<\/p>\n<p style=\"text-align: justify;\">&#8220;<em>Le persone LGB hanno un rischio sostanzialmente maggiore di soffrire disordini mentali, ideazione suicida, abuso di sostanze e autolesionismo rispetto alla popolazione eterosessuale. (&#8230;) Le persone lesbiche, gay e bisessuali (LGB) spesso sviluppano un senso di colpa sulla propria sessualit\u00e0. A ci\u00f2 si aggiungono i rischi del loro particolare stile di vita, come l&#8217;abuso di alcool e di sostanze, il rischio di contrarre malattie infettive e tendenze suicide. Abbiamo anche riscontrato un alto indice di autolesionismo e di auto-avvelenamento. L&#8217;autolesionismo nella comunit\u00e0 LGB \u00e8 una delle principali cause di ammissione ai Pronto Soccorso negli ospedali della Gran Bretagna<\/em> &#8221; (1).<\/p>\n<p style=\"text-align: justify;\">Non diverse sono le conclusioni di uno studio pubblicato nel 2011 negli Stati Uniti, e basato su numerose ricerche internazionali: &#8220;<em>Gli studi negli Stati Uniti e all\u2019estero forniscono forte evidenza dell\u2019elevato indice di tentativi di suicidio fra le persone LGBT. (&#8230;) Dall\u2019inizio degli anni Novanta, tutte le ricerche condotte fra i giovani americani, che comprendono anche l&#8217;identificazione dell&#8217;orientamento sessuale, hanno riscontrato negli omosessuali indici di tentativi di suicidi sette volte pi\u00f9 elevato rispetto ai giovani che si dichiarano eterosessuali<\/em>&#8221; (2).<\/p>\n<p style=\"text-align: justify;\">Basato sui dati del sistema di sanit\u00e0 pubblica e privata della Citt\u00e0 di New York, uno studio ufficiale pervenne a simili conclusioni: &#8220;<em>Alcuni gruppi della Citt\u00e0 sono a rischio notevolmente pi\u00f9 elevato di suicidio e di autolesionismo, specialmente le lesbiche, gay e bisessuali. Questi gruppi riportano anche un indice notevolmente superiore di problemi mentali, fisici e sociali<\/em> &#8221; (3).<\/p>\n<p style=\"text-align: justify;\">Le lobby LGBT non contestano questi dati (come potrebbero?), ma attribuiscono l&#8217;alto tasso di suicidi e di autolesionismo all&#8217;omofobia, cio\u00e8 alla pressione sociale e psicologica. Questo \u00e8 unilaterale e fuorviante.<\/p>\n<p style=\"text-align: justify;\">Secondo il dott. Gandolf\u00ecni, perfino nei Paesi pi\u00f9 dichiaratamente tolleranti non si assiste ad alcuna diminuzione o sparizione degli alti tassi di disturbi nella comunit\u00e0 omosessuale. I problemi sono dovuti a cause endogene, cio\u00e8 legate in qualche modo alla tendenza omosessuale stessa o allo stile di vita omosessuale. Perfino molti omosessuali riconoscono che il problema sia dovuto, in realt\u00e0, al loro stile di vita, come ha ben spiegato, ad esempio, Simon Fanshawe, importante scrittore omosessuale e intellettuale inglese.<\/p>\n<p style=\"text-align: justify;\">Da parte sua, Luis Pabon, ex militante omosessualista, ha fatto discutere annunciando: \u00ab<em>Non voglio pi\u00f9 essere omosessuale. Sono approdato nella comunit\u00e0 omosessuale alla ricerca di amore, intimit\u00e0 e fratellanza. Ci\u00f2 che ho trovato \u00e8 sospetto, infedelt\u00e0, solitudine e mancanza di unione. In questa comunit\u00e0, c &#8216;\u00e8 talmente tanto disgusto di se stessi che si incontrano continuamente uomini a pezzi, autodistruttivi, che sanno solo ferire, che sono crudeli e vendicativi gli uni contro gli altri\u00bb; si sperimenta \u00abuna immoralit\u00e0 diabolica che ti porta alla distruzione quotidiana. Non ne vale la pena, non pi\u00f9. Ho scelto di dissociarmi da uno stile di vita al di fuori della morale e della bont\u00e0. Vivere la vita omosessuale \u00e8 come infatuarsi di un cattivo ragazzo, di cui all&#8217;inizio desiderate spasmodicamente l&#8217;attenzione e l&#8217;amore, ma che alla fine vi fa ribrezzo. Io non ci sto pi\u00f9<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Matthew Todd, drammaturgo e redattore della rivista omosessuale inglese &#8220;Attitude&#8221;, ha definito &#8220;il problema dei problemi&#8221; il preoccupante aumento dei tassi di malattie mentali e problemi di dipendenza tra gli uomini omosessuali, spiegando: \u00ab<em>C&#8217;\u00e8 questo luogo comune che passiamo tanto tempo a fare festa, ma in realt\u00e0 noi lo sappiamo bene e le ricerche ora lo dimostrano: c&#8217;\u00e8 un inferno di omosessuali infelici, un alto numero di depressi, ansiosi e con istinti suicidi, che abusano di droghe e alcol e che soffrono di dipendenza sessuale, tassi molto pi\u00f9 elevati di comportamenti auto-distruttivi. La vita omosessuale \u00e8 incredibilmente sessualizzata. I ragazzi entrano in questo mondo dove c &#8216;\u00e8 un sacco di alcol e un sacco di droga, non c &#8216;\u00e8 nulla di sano, dolce o rilassato<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Come accennato sopra, numerosi studi sostengono questo.<\/p>\n<p style=\"text-align: justify;\">Una ricerca su &#8220;Archives of General Psychiatry&#8221;, ad esempio, ha concluso: \u00ab<em>Mentre vi \u00e8 un crescente consenso sul fatto che i giovani omosessuali abbiano un aumentato rischio di comportamenti suicidi e problemi di salute mentale, i processi che portano a questa associazione rimangono poco chiari. Sebbene tali risultati siano talvolta interpretati come conseguenze di atteggiamenti omofobici e pregiudizi sociali, sono possibili anche spiegazioni alternative. Queste includono: (1) la possibilit\u00e0 di una casualit\u00e0 reversibile: i giovani inclini a disturbi psichiatrici sono pi\u00f9 inclini a sperimentare attrazione omosessuale; (2) la possibilit\u00e0 che le scelte di vita fatte dai giovani omosessuali li mettano a maggior rischio di eventi avversi e aumentati rischi di problemi di salute mentale<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Altri studi hanno rilevato che la maggior parte dei tentativi di suicidio sono dovuti a problemi derivanti da una relazione omosessuale (rottura del rapporto, litigi), tanto che il &#8220;British Journal of Psychiatry&#8221; ha sostenuto: \u00ab<em>Pu\u00f2 essere che il pregiudizio della societ\u00e0 contro gli omosessuali porti ad una maggiore angoscia. Tuttavia, la psicologia omosessuale pu\u00f2 anche portare ad assumere stili di vita che rendono queste persone pi\u00f9 vulnerabili al disturbo psicologico<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">In un&#8217;indagine su &#8220;Archives of General Psychiatry&#8221;, condotta sui disturbi psicofisici di oltre 7mila cittadini olandesi, \u00e8 stato riconosciuto un altissimo tasso di problematiche tra le persone omosessuali, nonostante l&#8217;Olanda sia in cima alle graduatorie per assenza di omofobia. La stessa ricerca, replicata qualche anno pi\u00f9 tardi, evidenzia di nuovo come l&#8217;omosessualit\u00e0 sia significativamente correlata con il suicidio e con i disturbi mentali, riconoscendo ancora una volta che \u00ab<em>persino in un paese con un clima relativamente tollerante nei confronti dell&#8217;omosessualit\u00e0, gli uomini omosessuali sono esposti ad un rischio suicida molto pi\u00f9 elevato rispetto agli uomini eterosessuali<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Una recente ricerca condotta in Danimarca, paese anch&#8217;esso massimamente tollerante verso l&#8217;omosessualit\u00e0, ha rilevato che nel corso dei primi dodici anni di legalizzazione delle unioni omosessuali (1990-2001) per gli uomini omosessuali legalmente sposati, il tasso di suicidio \u00e8 stato otto volte maggiore di quello degli uomini che hanno una unione eterosessuale, e il doppio rispetto a quello degli uomini single.<\/p>\n<p style=\"text-align: justify;\">Nello stesso Paese, un&#8217;importante ricerca, condotta su 6,5 milioni di danesi tra il 1982 e il 2011, ha evidenziato come il suicidio tra uomini conviventi con un altro uomo sia quattro volte maggiore rispetto a quello degli uomini sposati con una donna. Lo stesso accade in altri &#8220;paradisi&#8221;, come Norvegia e Svezia.<\/p>\n<p style=\"text-align: justify;\">Come \u00e8 stato scritto in una ricerca pubblicata sul &#8220;Journal of Human Sexuality&#8221; nel 2010: \u00ab<em>Le persone con attrazione per lo stesso sesso (SSA) hanno una variet\u00e0 deplorevolmente elevata di problematiche di salute mentale, e ci sono prove che questo sia dovuto alla pressione sociale molto meno di quanto comunemente si supponga<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Bisognerebbe quindi includere nelle cause la possibilit\u00e0 di una causa endogena, come ha fatto il dott. Gandolfini. Potrebbe dipendere dallo stile vita omosessuale, oppure dall&#8217;inclinazione stessa. Ogni persona che assume un comportamento omosessuale, infatti, vive permanentemente un contrasto e una contraddizione tra il dato biologico e fisiologico del proprio corpo &#8211; le cui diverse parti sono permanentemente e oggettivamente predisposte a completarsi mediante l&#8217;incontro con il corpo di una persona dalla sessualit\u00e0 complementare ed opposta &#8211; e il dato psicologico. Il conflitto interno tra corpo e psicologia non \u00e8 senza esiti, e questo disordine potrebbe purtroppo trasformarsi in un disagio, provocando disturbi e altre conseguenze.<\/p>\n<p style=\"text-align: justify;\">(Basato su un articolo pubblicato sul sito dell&#8217;Unione Cristiani Cattolici Razionali &#8211; UCCR, 25 aprile 2015. Con autorizzazione.)<\/p>\n<p style=\"text-align: justify;\"><strong>Note<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>1)<\/strong> Michael King et al., <em>A systematic review of mental disorder, suicide, and deliberate self harm in lesbian, gay and bisexual people<\/em>, in &#8220;Bio Medical Center, Psychiatry&#8221;, 18 agosto 2008.<\/p>\n<p style=\"text-align: justify;\"><strong>2)<\/strong> Ann P. Haas et al., <em>Suicide and Suicide Risk in Lesbian, Gay, Bisexual, and Transgender Populations: Review and Recommendations<\/em>, in &#8220;Journal of Homosexuality&#8221;, gennaio 2011.<\/p>\n<p style=\"text-align: justify;\"><strong>3)<\/strong> New York City Department of Health and Mental Hygiene, <em>Suicide and Self-inflicted Injuries in New York City<\/em>, in &#8220;NYC Vital Signs&#8221;, febbraio 2012, volume 11, No. 1.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tradizione Famiglia e Propriet\u00e0 n.65 giugno 2015 \u00c8 risaputo che il tasso di suicidi e di malattie mentali fra gli omosessuali \u00e8 molto pi\u00f9 elevato che tra gli eterosessuali. Ci\u00f2 \u00e8 dovuto alla pressione sociale &#8220;omofobica&#8221;, oppure allo stesso stile di vita omosessuale?<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/omosessualita-suicidio-e-malattie-mentali\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":26496,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[916],"class_list":["post-26495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-omosessualit","tag-ideologia-gay","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Omosessualit\u00e0, suicidio e malattie mentali - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/omosessualita-suicidio-e-malattie-mentali\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Omosessualit\u00e0, suicidio e malattie mentali - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/omosessualita-suicidio-e-malattie-mentali\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-15T22:00:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/07\/gay.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"344\" \/>\n\t<meta property=\"og:image:height\" content=\"146\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/omosessualita-suicidio-e-malattie-mentali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/omosessualita-suicidio-e-malattie-mentali\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Omosessualit\u00e0, suicidio e malattie mentali\",\"datePublished\":\"2015-07-15T22:00:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/omosessualita-suicidio-e-malattie-mentali\\\/\"},\"wordCount\":1452,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/omosessualita-suicidio-e-malattie-mentali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/gay.jpg\",\"keywords\":[\"ideologia gay\"],\"articleSection\":[\"Omosessualit&agrave;\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/omosessualita-suicidio-e-malattie-mentali\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/omosessualita-suicidio-e-malattie-mentali\\\/\",\"name\":\"Omosessualit\u00e0, suicidio e malattie mentali - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/omosessualita-suicidio-e-malattie-mentali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/omosessualita-suicidio-e-malattie-mentali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/gay.jpg\",\"datePublished\":\"2015-07-15T22:00:10+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/omosessualita-suicidio-e-malattie-mentali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/omosessualita-suicidio-e-malattie-mentali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/omosessualita-suicidio-e-malattie-mentali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/gay.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/07\\\/gay.jpg\",\"width\":344,\"height\":146},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/omosessualita-suicidio-e-malattie-mentali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Omosessualit\u00e0, suicidio e malattie mentali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Omosessualit\u00e0, suicidio e malattie mentali - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/omosessualita-suicidio-e-malattie-mentali\/","og_locale":"it_IT","og_type":"article","og_title":"Omosessualit\u00e0, suicidio e malattie mentali - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/omosessualita-suicidio-e-malattie-mentali\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2015-07-15T22:00:10+00:00","og_image":[{"width":344,"height":146,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/07\/gay.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/omosessualita-suicidio-e-malattie-mentali\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/omosessualita-suicidio-e-malattie-mentali\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Omosessualit\u00e0, suicidio e malattie mentali","datePublished":"2015-07-15T22:00:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/omosessualita-suicidio-e-malattie-mentali\/"},"wordCount":1452,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/omosessualita-suicidio-e-malattie-mentali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/07\/gay.jpg","keywords":["ideologia gay"],"articleSection":["Omosessualit&agrave;"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/omosessualita-suicidio-e-malattie-mentali\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/omosessualita-suicidio-e-malattie-mentali\/","name":"Omosessualit\u00e0, suicidio e malattie mentali - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/omosessualita-suicidio-e-malattie-mentali\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/omosessualita-suicidio-e-malattie-mentali\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/07\/gay.jpg","datePublished":"2015-07-15T22:00:10+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/omosessualita-suicidio-e-malattie-mentali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/omosessualita-suicidio-e-malattie-mentali\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/omosessualita-suicidio-e-malattie-mentali\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/07\/gay.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/07\/gay.jpg","width":344,"height":146},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/omosessualita-suicidio-e-malattie-mentali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Omosessualit\u00e0, suicidio e malattie mentali"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/26495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=26495"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/26495\/revisions"}],"predecessor-version":[{"id":26497,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/26495\/revisions\/26497"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/26496"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=26495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=26495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=26495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}