{"id":2540,"date":"2007-03-22T00:00:00","date_gmt":"2007-03-21T23:00:00","guid":{"rendered":""},"modified":"2015-11-13T13:53:22","modified_gmt":"2015-11-13T12:53:22","slug":"in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\/","title":{"rendered":"In Russia il vecchio partito comunista resiste agli assalti di Putin"},"content":{"rendered":"<div style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/03\/elezioni-Russia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-27752 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/03\/elezioni-Russia.jpg\" alt=\"elezioni Russia\" width=\"208\" height=\"156\" \/><\/a>Il <strong>Sole 24 Ore<\/strong> 13 marzo 2007<\/div>\n<p style=\"text-align: center;\">di <strong>Piero Sinatti<\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0Le elezioni regionali svoltesi domenica hanno interessato 31 milioni di elettori. Si dovevano rinnovare le assemblee legislative di 14 soggetti della Federazione russa (su 87). La partecipazione \u00e8 stata bassa, come previsto. Poco pi\u00f9 del 39% degli elettori ha partecipato al voto (contro il 36,5% del voto regionale del 2006). La maggioranza degli elettori si \u00e8 disinteressata di un voto che almeno in teoria dovrebbe influenzare le decisioni pi\u00f9 importanti di quelle assemblee, tra cui le spese sociali e la scelta del governatore sulla rosa dei candidati presidenziali.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">La bassissima affluenza, prevista, riflette lo scetticismo e la sfiducia di gran parte della popolazione nei confronti dei parlamenti e dei governi locali. Contro questo dato, il gruppo dirigente si \u00e8 premunito, per il voto di dicembre, eliminando la percentuale minima dei votanti necessaria per dare validit\u00e0 al voto.<\/div>\n<p style=\"text-align: justify;\">Ma il dato pi\u00f9 atteso, al di l\u00e0 dell\u2019affluenza, era il risultato ottenuto dal nuovo partito, Russia Giusta (RG). Creata lo scorso ottobre dal presidente della Camera alta Sergej Mironov (un concittadino e prot\u00e9g\u00e9 di Putin), grazie a un\u2019operazione di ingegneria politica sostenuta dal Kremlino, RG ha superato gli sbarramenti e ottenuto i mandati in tutte le 14 regioni. Un successo, per un neo-concorrente. Tuttavia aspirava al secondo posto in tutte le 14 regioni. Lo ha ottenuto, invece, solo in cinque regioni, tra cui San Pietroburgo e Dagestan. Ed ha vinto solo nella regione meridionale di Stavropol\u2019.<\/p>\n<p style=\"text-align: justify;\">Nelle altre otto ha ottenuto solo il terzo o quarto posto, anche con percentuale a una cifra. RG (chiamato anche il \u201cPartito del Potere n. 2\u201d per il patrocinio di Putin) non \u00e8 riuscito, per ora, nel compito assegnatogli dal Kremlino: quello di ridurre ulteriormente la consistenza elettorale del Partito comunista di Gennadij Zjuganov, sottraendogli voti.<\/p>\n<p style=\"text-align: justify;\">Il PC, infatti, nonostante gli scarsi finanziamenti ricevuti per la campagna elettorale in confronto a quasi tutti gli altri partiti in lizza e la sua esclusione pressoch\u00e9 totale dalle TV (dove l\u2019hanno fatta da protagonisti Russia Unita e RG), si \u00e8 confermato il secondo partito in sette regioni e il terzo in altrettante. In sostanza, risulta ancora il secondo partito russo. Con una percentuale superiore a quella ottenuta alle politiche di quattro anni fa (il risultato pi\u00f9 basso della sua storia).<\/p>\n<p style=\"text-align: justify;\">Nonostante gli slogan e il programma di sinistra sbandierati da Mironov, RG non \u00e8 riuscito a prenderne il posto. Il fatto \u00e8 che se da una parte RG si \u00e8 presentata come una sorta di partito d\u2019opposizione, il suo leader Mironov, dirigendo da cinque anni la Camera Alta, non ha mai preso le distanze da Putin e dal \u201cPartito del Potere n. 1\u201d, Russia Unita (RU). E proprio RU, nonostante l\u2019apparizione spesso aggressiva del suo concorrente presidenziale \u201cdi sinistra\u201d, ha vinto in 13 regioni su 14, superando in alcune di esse il 50% dei suffragi.<\/p>\n<p style=\"text-align: justify;\">RU \u00e8 il partito dei governatori, dell\u2019apparato amministrativo a tutti i livelli, delle oligarchie economiche, delle \u201cstrutture della forza\u201d (ministero degli interni, della difesa, FSB). \u00c8 stata finora lo strumento legislativo di Putin. RU ha vinto anche a San Pietroburgo, dove il partito di Mironov (secondo solo a RU per i finanziamenti ricevuti) godeva del sostegno di uno dei maggiori gruppi immobiliari e di costruzioni russi e aveva svolto la pi\u00f9 aggressiva campagna elettorale nei confronti di comunisti e RU. Ha ottenuto mandati in tutte le 14 regioni, anche il Partito (sedicente) liberal democratico (LDPR), fondato e diretto dal demagogo nazional-populista Vladimir Zhirinovskij. \u00c8 il \u201cpartito del potere\u201d di riserva: si autodefinisce d\u2019opposizione, ma dall\u2019epoca di Eltsin a ora ha sempre votato a favore delle fondamentali decisioni del Kremlino. Tuttavia, il consenso attorno ad esso si restringe.<\/p>\n<p style=\"text-align: justify;\">Allora, se le elezioni di domenica sono state una prova generale di quelle di dicembre, sono questi tre i partiti destinati a rientrare nella Duma: RU, comunisti e zhirinovskiani. Con loro, vi entrer\u00e0 RG. Un risultato comunque notevole, per un partito con pochi mesi di vita (ma con mezzi e accessi mediatici pi\u00f9 che abbondanti). Per il momento appare ancora lontano il bipartitismo che gli architetti del Kremlino (come il maggior consigliere di Putin, Vladislav Surkov), vorrebbero far camminare sulle due gambe rappresentate dai \u201cpartiti del potere\u201d, RU e RG, sbarazzandosi finalmente dell\u2019opposizione comunista.<\/p>\n<p style=\"text-align: justify;\">Ma il PCFR, unico reale partito d\u2019opposizione sociale e politica (ben pi\u00f9 anti-occidentale di Putin in politica estera), dispone ancora di uno zoccolo duro nel Paese. Non sono solo le vecchie generazioni a votarlo. Infine, nettamente sconfitti appaiono i due partiti di orientamento liberale e \u201cfilo-occidentale\u201d, che dovrebbero rappresentare i nuovi strati borghesi economicamente attivi, l\u2019intelligentsija non radicale. Jabloko, non ammesso alle elezioni nella sua roccaforte di San Pietroburgo con vari pretesti e bandito dalla TV pi\u00f9 dei comunisti, non ha superato le percentuali di sbarramento in nessuna delle 14 regioni. Ala di sinistra dei liberali, Jabloko sembra vicino all\u2019esaurimento della sua parabola politica, nonostante il prestigio intellettuale e la dignit\u00e0 morale del suo leader, Grigorij Javlinskij.<\/p>\n<p style=\"text-align: justify;\">Ha superato invece gli sbarramenti (per lo pi\u00f9 al 7%) l\u2019ala di destra dei liberali &#8211; l\u2019SPS (Unione delle Forze di Destra), il partito dei riformatori (impopolarissimi) degli anni Novanta. Ma solo in cinque regioni (tra cui San Pietroburgo). SPS e Jabloko scontano la mancata unificazione elettorale, oltre che la loro poco numerosa base sociale. Per cercare di sopravvivere e tornare nella Duma (da cui nel 2003 furono esclusi) dovrebbero accordarsi per presentarsi uniti al voto. \u00c8 improbabile che lo facciano. D\u2019altra parte, non sarebbe facile per loro superare lo sbarramento fissato al 7% (due per cento in pi\u00f9 che alle elezioni del 2003).<\/p>\n<p style=\"text-align: justify;\">Se i risultati di domenica si confermeranno a dicembre, la Duma sar\u00e0 rappresentata dai quattro partiti che in varia misura hanno superato la prova dell\u201911 marzo. Anche se Russia Giusta potr\u00e0 accelerare e vincere posizioni nel rush finale del prossimo autunno. I santi in Paradiso non le mancano<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Sole 24 Ore 13 marzo 2007 di Piero Sinatti \u00a0Le elezioni regionali svoltesi domenica hanno interessato 31 milioni di elettori. Si dovevano rinnovare le assemblee legislative di 14 soggetti della Federazione russa (su 87). La partecipazione \u00e8 stata bassa, come previsto. Poco pi\u00f9 del 39% degli elettori ha partecipato al voto (contro il 36,5% &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":27752,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108,116],"tags":[1462],"class_list":["post-2540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-paesi-e-continenti","category-russia","tag-comunisti","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>In Russia il vecchio partito comunista resiste agli assalti di Putin - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"In Russia il vecchio partito comunista resiste agli assalti di Putin - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2007-03-21T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-13T12:53:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/03\/elezioni-Russia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"208\" \/>\n\t<meta property=\"og:image:height\" content=\"156\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"In Russia il vecchio partito comunista resiste agli assalti di Putin\",\"datePublished\":\"2007-03-21T23:00:00+00:00\",\"dateModified\":\"2015-11-13T12:53:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\\\/\"},\"wordCount\":969,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2007\\\/03\\\/elezioni-Russia.jpg\",\"keywords\":[\"comunisti\"],\"articleSection\":[\"Paesi e continenti\",\"Russia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\\\/\",\"name\":\"In Russia il vecchio partito comunista resiste agli assalti di Putin - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2007\\\/03\\\/elezioni-Russia.jpg\",\"datePublished\":\"2007-03-21T23:00:00+00:00\",\"dateModified\":\"2015-11-13T12:53:22+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2007\\\/03\\\/elezioni-Russia.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2007\\\/03\\\/elezioni-Russia.jpg\",\"width\":208,\"height\":156},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"In Russia il vecchio partito comunista resiste agli assalti di Putin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"In Russia il vecchio partito comunista resiste agli assalti di Putin - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\/","og_locale":"it_IT","og_type":"article","og_title":"In Russia il vecchio partito comunista resiste agli assalti di Putin - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2007-03-21T23:00:00+00:00","article_modified_time":"2015-11-13T12:53:22+00:00","og_image":[{"width":208,"height":156,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/03\/elezioni-Russia.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"In Russia il vecchio partito comunista resiste agli assalti di Putin","datePublished":"2007-03-21T23:00:00+00:00","dateModified":"2015-11-13T12:53:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\/"},"wordCount":969,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/03\/elezioni-Russia.jpg","keywords":["comunisti"],"articleSection":["Paesi e continenti","Russia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\/","name":"In Russia il vecchio partito comunista resiste agli assalti di Putin - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/03\/elezioni-Russia.jpg","datePublished":"2007-03-21T23:00:00+00:00","dateModified":"2015-11-13T12:53:22+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/03\/elezioni-Russia.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/03\/elezioni-Russia.jpg","width":208,"height":156},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/in-russia-il-vecchio-partito-comunista-resiste-agli-assalti-di-putin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"In Russia il vecchio partito comunista resiste agli assalti di Putin"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2540"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2540\/revisions"}],"predecessor-version":[{"id":27753,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2540\/revisions\/27753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/27752"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}