{"id":24960,"date":"2015-05-28T00:00:37","date_gmt":"2015-05-27T22:00:37","guid":{"rendered":"http:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=24960"},"modified":"2015-05-22T12:15:58","modified_gmt":"2015-05-22T10:15:58","slug":"da-hollywood-a-dio","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-hollywood-a-dio\/","title":{"rendered":"Da Hollywood a Dio"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/05\/Michael_Lonsdale.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-24961\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/05\/Michael_Lonsdale.jpg\" alt=\"Michael_Lonsdale\" width=\"140\" height=\"200\" \/><\/a>Tracce<\/strong> \u2013 Litterae Communionis n. 4 aprile 2015<\/p>\n<p style=\"text-align: justify;\"><em>Dal volto celebre sul grande schermo a quello nascosto di un uomo innamorato di del Vangelo. Dopo aver vestito i panni del monaco di Tibhirine, Michael Londsdale racconta (in anteprima) la sua \u00abdolce\u00bb conversione<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Carlo Dignola<\/strong><\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">\u00abCi sono cose molto belle nell\u2019Upanishad, ci sono buddhisti meravigliosi, ind\u00f9 impressionanti per la saggezza, maestri sufi&#8230; Ho provato grande felicit\u00e0 nel leggere Lao-Tse e Confucio. L&#8217;uomo non cessa di cercare. Ma quello che di pi\u00f9 vero ho letto durante la mia vita \u00e8 il Vangelo. La parola di Ges\u00f9 \u00e8 la pi\u00f9 giusta, quella che suscita pi\u00f9 vita\u00bb.<\/p>\n<p style=\"text-align: justify;\">Michael Lonsdale, 83 anni, \u00e8 un attore francese dal curriculum impressionante: ha recitato in circa 150 film, comprese grandi produzioni hollywoodiane come Munich di Steven Spielberg e Moonraker, della serie di James Bond. Ha lavorato per registi come Orson Welles, Truffaut, Malie, Godard, De Oliveira, Ivory, Bunuel, Olmi ( <em>Il <\/em>villaggio di cartone). L&#8217;ultimo suo successo \u00e8 del 2010, Uomini di Dio, un film che racconta la storia dei monaci di Tibhirine trucidati nel 1996 da un gruppo islamico armato, in Algeria. Lonsdale \u00e8 in tv dagli anni Cinquanta, ed \u00e8 un grande attore di teatro: ha recitato Sofocle e la Bibbia, Shake<em>speare e Proust, Samuel Beckett e Camus, Ionesco e Pavese&#8230;<\/em><\/p>\n<p style=\"text-align: justify;\">Ora ha scritto un piccolo libro sulla sua vita, che esce tradotto in italiano da Lorenzo Fazzini per l&#8217;Editrice missionaria italiana. Si intitola <em>Dare un volto all&#8217;amore. La mia fede da Spielberg a Tibhirine<\/em>, e non parla dei successi professionali, ma del suo rapporto con Dio. \u00c8 un uomo che al cristianesimo si \u00e8 avvicinato per lunghe tappe; Ges\u00f9 lo ha preso \u00abdolcemente\u00bb, come dice lui a Tracce. \u00abMio padre era un inglese protestante, mia madre una francese cattolica, ma in chiesa non si andava. I miei, cosa rara a quel tempo, avevano deciso di non battezzarmi. Mamma per\u00f2 amava molto Ges\u00f9: \u00e8 stata la prima persona a parlarmi di Lui\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>La ricerca<\/strong>. Quando Michael aveva 7 anni, la famiglia si trasfer\u00ec a Rabat, in Marocco. Mi pare che il primo libro religioso che ha letto sia stato il Corano, giusto? \u00ab\u00c8 vero. A 15 anni sono diventato amico di un musulmano, un antiquario di F\u00e8s\u00bb, racconta: \u00abMi parlava di Dio, nei caff\u00e8 della citt\u00e0, alla sera. Ero affascinato. Non sono mai diventato musulmano, per\u00f2\u00bb. Non si \u00e8 convertito sui libri. Sono stati certi incontri a cambiare la sua vita. Questa autobiografia \u00e8 soprattutto un elenco di nomi, di luoghi, di momenti, di facce che sono diventate decisive per lui: \u00abPer me Ges\u00f9 \u00e8 un uomo concreto, in carne e ossa\u00bb.<\/p>\n<p style=\"text-align: justify;\">E come se ne \u00e8 accorto? \u00abStavo cercando qualcosa e l&#8217;ho trovato in un domenicano meraviglioso, padre Raymond R\u00e9gamey. L&#8217;ho conosciuto dopo essere rientrato a Parigi. Lo andai ad ascoltare perch\u00e9 spiegava i rapporti tra l&#8217;arte e la fede con grande passione. Presi un appuntamento al convento di Saint-Jacques. &#8220;Tu cosa cerchi?&#8221;, mi chiese. &#8220;Non so. Cerco qualcosa di vero, di buono, di grande&#8230;&#8221;. &#8220;Forse quello che stai cercando \u00e8 Dio, semplicemente&#8221;, mi ha risposto\u00bb.<\/p>\n<p style=\"text-align: justify;\">La persona che ha cambiato davvero la sua vita, per\u00f2, non \u00e8 un religioso, ma una donna, cieca: Denise Robert. \u00abEra una persona deliziosa: sempre sorridente, gioiosa, luminosa. Abbiamo passato interi pomeriggi insieme, parlavamo di tutto. Padre R\u00e9gamey non sempre lo capivo, usava parole che io non sapevo neppure cosa significassero. Denise, invece, mi ha aiutato molto a diventare cristiano. A lei piaceva camminare per Parigi, conosceva bene la citt\u00e0. Mi portava nel Santuario della Medaglia Miracolosa in Rue du Bac. Ridevamo molto e intanto mi spiegava il Vangelo, mi ha detto tutto di Ges\u00f9\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>Un uomo felice.<\/strong> A 22 anni Michael decide di farsi battezzare, proprio al Convento di Saint-Jacques. Madrina, naturalmente, Denise: \u00abQuel giorno io piangevo, piangevo!\u00bb, ricorda. Non era un luogo qualunque quello, negli anni Cinquanta e Sessanta era una sede intellettuale importante in Francia: \u00abL\u00ec ho incontrato grandi teologi, preti straordinari come Marie-Dominique Chenu, Yves Congar\u00bb.<\/p>\n<p style=\"text-align: justify;\">Un&#8217;altra svolta negli anni Ottanta, con la morte, in pochi mesi, della madre (\u00ab\u00e8 stata molto malata per tanti anni, ma perderla \u00e8 stato duro\u00bb), di Denise e di altre persone care. Cosa le accadde in quei giorni? \u00abNon avevo pi\u00f9 voglia di vivere, non vedevo pi\u00f9 nessuno, non sentivo pi\u00f9 nulla\u00bb. \u00c8 allora che Lonsdale incontra il movimento del Rinnovamento carismatico e si avvicina alla Comunit\u00e0 dell&#8217;Emmanuele. Perch\u00e9? \u00abVado regolarmente a Paray-le-Monial, mi piace questo luogo e la sua bella chiesa romanica. Ho trovato con gioia dei cristiani accoglienti, aperti, calorosi. E l\u00ec ho conosciuto anche padre Dominique Rey, che oggi \u00e8 Vescovo di Tolone. \u00c8 diventato un mio grande amico: mi ha aiutato molto\u00bb.<\/p>\n<p style=\"text-align: justify;\">Negli ultimi anni, Lonsdale come attore ha voluto dedicarsi \u00absolo a opere di tipo spirituale. Questo ormai non \u00e8 pi\u00f9 un lavoro, ma il mio modo di rispondere alla chiamata di Cristo\u00bb. Si \u00e8 calato nei panni di preti, monaci, cardinali; \u00e8 stato il Rettore della Grande moschea di Parigi, l&#8217;arcangelo Gabriele&#8230; \u00abMa ho interpretato anche ruoli di cattivi, ad esempio il diavolo nei <em>Fratelli Karamazov<\/em>\u00bb.<\/p>\n<p style=\"text-align: justify;\">Mi pare, per\u00f2, che lei abbia portato in scena soprattutto dei cristiani &#8220;normali&#8221;, come il curato di campagna di Bernanos, Teresa di Lisieux, Madeleine Delbr\u00e8l&#8230; Perch\u00e9? \u00abSono persone che hanno qualcosa da dire al mondo di oggi, che attende una speranza. Ho recitato anche <em>I fioretti<\/em> di san Francesco d&#8217;Assisi, il mio santo preferito. E ho incontrato diverse volte Guy Gilbert, che raccoglie i ragazzi per strada\u00bb. L&#8217;impressione \u00e8 che le piacciano i cristiani semplici e diretti, che abbia un&#8217;idea pi\u00f9 &#8220;affettiva&#8221; che intellettuale della fede, non \u00e8 cos\u00ec? \u00abS\u00ec\u00bb, risponde sorridendo: \u00abE infatti credo che sia straordinario questo nuovo Papa, Francesco. Sta cambiando le cose a Roma.<\/p>\n<p style=\"text-align: justify;\">Questa sua attenzione per i poveri \u00e8 meravigliosa\u00bb. Il suo punto d&#8217;arrivo, per\u00f2, \u00e8 stato indossare il saio di <em>fr\u00e9re<\/em> Luc, in <em>Uomini di Dio<\/em> \u00abUna figura cos\u00ec essenziale, cos\u00ec vera, cos\u00ec vicina alla santit\u00e0. E poi per me \u00e8 l&#8217;immagine di un uomo felice: l&#8217;amore del prossimo rende felici\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>La profezia di P\u00e9guy<\/strong><strong><em>.<\/em><\/strong> Ora Lonsdale ha trovato una nuova figura di cristiano che lo affascina molto: \u00abCharles P\u00e9guy. Con un altro attore leggiamo sue pagine in teatro. \u00c8 un uomo bellissimo, vedo che la gente \u00e8 molto interessata a lui. Ed \u00e8 straordinario che quello che P\u00e9guy disse cinquantanni fa si stia avverando proprio ora, \u00e8 stato una sorta di profeta. Anche in lui trovo decisiva la questione della speranza&#8230; Quando usciamo dalle messe, la domenica, la fede dovrebbe vedersi sul nostro volto, invece siamo spesso troppo timorosi\u00bb.<\/p>\n<p style=\"text-align: justify;\">Lei scrive che dentro l&#8217;uomo di oggi \u00abqualcosa si \u00e8 rotto\u00bb: cosa intende dire? \u00abVede bene quello che sta succedendo in Francia, o in Libia, con il terrorismo. Sono sconvolto. Quando ero giovane ho vissuto in mezzo ai musulmani in Marocco; ho avuto dei grandi amici, ma non erano assolutamente dei fanatici. I veri musulmani sono scioccati dagli attentati del 7 gennaio e dall&#8217;Isis. Non c&#8217;\u00e8 scritto nel Corano che bisogna andare in giro a uccidere la gente in quel modo. I terroristi sono gente fanatica. \u00c8 un momento molto difficile\u00bb. Ma il male c&#8217;\u00e8 sempre stato&#8230; \u00abCerto. Ma \u00e8 venuto il momento in cui, come cristiani, dobbiamo tornare al nostro compito\u00bb. E qual \u00e8? \u00abDiffondere l&#8217;umanit\u00e0\u00bb.<\/p>\n<p style=\"text-align: center;\"><strong>CHI E&#8217;<\/strong><\/p>\n<p style=\"text-align: justify;\"><em><strong>Michael Lonsdale<\/strong><\/em><em> \u00e8 nato a Parigi, il 24 maggio 1931, da madre francese e padre inglese. Dal 1939 al &#8217;47 ha vissuto in Marocco. Nella sua carriera ha recitato, tra gli altri, per Spielberg, Truffaut, Malie, Bufiuel, Olmi. L&#8217;interpretazione in <\/em><em>Uomini di Dio<\/em><em> gli \u00e8 valsa il premio come miglior attore non protagonista ai C\u00e9sar2011.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>\u00a0<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tracce \u2013 Litterae Communionis n. 4 aprile 2015 Dal volto celebre sul grande schermo a quello nascosto di un uomo innamorato di del Vangelo. Dopo aver vestito i panni del monaco di Tibhirine, Michael Londsdale racconta (in anteprima) la sua \u00abdolce\u00bb conversione di Carlo Dignola<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-hollywood-a-dio\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":24961,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[259,2151],"class_list":["post-24960","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-personaggi","tag-conversioni","tag-michael-lonsdale","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Da Hollywood a Dio - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-hollywood-a-dio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Da Hollywood a Dio - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-hollywood-a-dio\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2015-05-27T22:00:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/05\/Michael_Lonsdale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"188\" \/>\n\t<meta property=\"og:image:height\" content=\"268\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-hollywood-a-dio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-hollywood-a-dio\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Da Hollywood a Dio\",\"datePublished\":\"2015-05-27T22:00:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-hollywood-a-dio\\\/\"},\"wordCount\":1244,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-hollywood-a-dio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Michael_Lonsdale.jpg\",\"keywords\":[\"conversioni\",\"Michael Lonsdale\"],\"articleSection\":[\"Personaggi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-hollywood-a-dio\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-hollywood-a-dio\\\/\",\"name\":\"Da Hollywood a Dio - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-hollywood-a-dio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-hollywood-a-dio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Michael_Lonsdale.jpg\",\"datePublished\":\"2015-05-27T22:00:37+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-hollywood-a-dio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-hollywood-a-dio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-hollywood-a-dio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Michael_Lonsdale.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2015\\\/05\\\/Michael_Lonsdale.jpg\",\"width\":188,\"height\":268},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/da-hollywood-a-dio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Da Hollywood a Dio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Da Hollywood a Dio - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-hollywood-a-dio\/","og_locale":"it_IT","og_type":"article","og_title":"Da Hollywood a Dio - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-hollywood-a-dio\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2015-05-27T22:00:37+00:00","og_image":[{"width":188,"height":268,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/05\/Michael_Lonsdale.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-hollywood-a-dio\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-hollywood-a-dio\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Da Hollywood a Dio","datePublished":"2015-05-27T22:00:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-hollywood-a-dio\/"},"wordCount":1244,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-hollywood-a-dio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/05\/Michael_Lonsdale.jpg","keywords":["conversioni","Michael Lonsdale"],"articleSection":["Personaggi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-hollywood-a-dio\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-hollywood-a-dio\/","name":"Da Hollywood a Dio - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-hollywood-a-dio\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-hollywood-a-dio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/05\/Michael_Lonsdale.jpg","datePublished":"2015-05-27T22:00:37+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-hollywood-a-dio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-hollywood-a-dio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-hollywood-a-dio\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/05\/Michael_Lonsdale.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2015\/05\/Michael_Lonsdale.jpg","width":188,"height":268},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/da-hollywood-a-dio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Da Hollywood a Dio"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/24960","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=24960"}],"version-history":[{"count":1,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/24960\/revisions"}],"predecessor-version":[{"id":24962,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/24960\/revisions\/24962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/24961"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=24960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=24960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=24960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}