{"id":2465,"date":"2007-02-01T12:49:17","date_gmt":"2007-02-01T11:49:17","guid":{"rendered":""},"modified":"2016-04-22T11:39:29","modified_gmt":"2016-04-22T09:39:29","slug":"la-politica-figlia-dellesperienza-la-storia-politica-sperimentale","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\/","title":{"rendered":"La politica, figlia dell&#8217;esperienza; la storia, politica sperimentale"},"content":{"rendered":"<div style=\"text-align: center;\" align=\"center\"><strong><a href=\"http:\/\/www.totustuus.biz\/users\/pvalori\/index.html\" target=\"_blank\">http:\/\/www.totustuus.biz\/users\/pvalori\/index.html<\/a><\/strong><\/div>\n<div style=\"text-align: center;\" align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-33351\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/02\/De-Maistre.jpg\" alt=\"De Maistre\" width=\"203\" height=\"200\" \/><\/div>\n<p style=\"text-align: center;\">Conte<strong> Joseph De Maistre <\/strong>(1753-1821)<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\"><strong>PREFAZIONE<\/strong><\/div>\n<p style=\"text-align: justify;\">La politica, che forse \u00e8 la pi\u00f9 spinosa delle scienze, per la difficolt\u00e0, sempre risorgente, di discernere ci\u00f2 che vi \u00e8 di stabile o di mutevole nei suoi elementi, presenta un fenomeno singolare e capace di far tremare ogni uomo saggio chiamato all&#8217;amministrazione dello Stato: il fatto cio\u00e8 che tutto ci\u00f2 che il buonsenso intravede sulle prime in questa scienza, come verit\u00e0 evidente, si rivela quasi sempre, quando l&#8217;esperienza ha parlato, non soltanto falso, ma funesto.<\/p>\n<p style=\"text-align: justify;\">A cominciare dalle basi: se non si fosse mai sentito parlare di governi e gli uomini fossero chiamati a deliberare, per esempio, sulla monarchia ereditaria o elettiva, verrebbe giustamente considerato un insensato chi scegliesse la prima. Gli argomenti contro di essa si presentano infatti cosi naturalmente alla ragione, che \u00e8 inutile ricordarli.<\/p>\n<p style=\"text-align: justify;\">E tuttavia la storia, che \u00e8 la politica sperimentale, dimostra che la monarchia ereditaria \u00e8 la forma di governo pi\u00f9 stabile, pi\u00f9 felice, pi\u00f9 connaturale all&#8217;uomo; e che la monarchia elettiva \u00e8, al contrario, la peggiore specie di governo conosciuta.<\/p>\n<p style=\"text-align: justify;\">In materia di popolazione, di commercio, di leggi coercitive e di mille altri argomenti importanti, vediamo quasi sempre la teoria pi\u00f9 plausibile contraddetta e annullata dall&#8217;esperienza.<\/p>\n<p style=\"text-align: justify;\">Citiamo qualche esempio.<\/p>\n<p style=\"text-align: justify;\">Come fare per rendere uno Stato potente?<\/p>\n<p style=\"text-align: justify;\">&#8220;<em>Bisogna incoraggiare innanzitutto, con ogni mezzo possibile, l&#8217;aumento della popolazione<\/em>&#8220;.<\/p>\n<p style=\"text-align: justify;\">Al contrario, sappiamo che ogni legge tendente a incoraggiare direttamente l&#8217;aumento della popolazione, a prescindere da considerazioni di altro genere, \u00e8 nociva. \u00c8 invece necessario cercare di stabilire nello Stato una certa forza morale che tenda a far diminuire il numero dei matrimoni e a renderli meno precoci. La prevalenza delle nascite sulle morti, stabilita dalle statistiche, non prova ordinariamente che il numero dei miserabili, ecc., ecc. Gli economisti francesi avevano abbozzato la dimostrazione di queste verit\u00e0; il bel lavoro di Malthus \u00e8 venuto a completarla. (1)<\/p>\n<p style=\"text-align: justify;\">Come fare per prevenire la fame e la carestia?<\/p>\n<p style=\"text-align: justify;\">&#8220;<em>Niente di pi\u00f9 semplice: si deve proibire l&#8217;esportazione di cereali<\/em>&#8220;.<\/p>\n<p style=\"text-align: justify;\">Al contrario \u00e8 necessario accordare un premio a chi li esporta. L&#8217;autorevole esempio dell&#8217;Inghilterra ci ha costretto a ingoiare questo paradosso.<\/p>\n<p style=\"text-align: justify;\">Come fare per sostenere il cambio a favore di un certo paese?<\/p>\n<p style=\"text-align: justify;\"><em>&#8220;Bisogna senz&#8217;altro impedire l&#8217;uscita della valuta e vigilare quindi, attraverso severe leggi coercitive, che lo Stato non comperi pi\u00f9 di quanto vende<\/em>&#8220;.<\/p>\n<p style=\"text-align: justify;\">Al contrario, tali mezzi non sono mai stati impiegati senza portare come conseguenza l&#8217;abbassamento del cambio o comunque, il che \u00e8 lo stesso, l&#8217;aumento del debito della nazione; cosi come non si potr\u00e0 mai imboccare una strada opposta senza farlo salire, ossia senza provare visibilmente che il credito della nazione \u00e8 aumentato, ecc., ecc.<\/p>\n<p style=\"text-align: justify;\">Ma questo genere d\u00ec considerazioni si ripropone di continuo soprattutto in ci\u00f2 che la politica ha di pi\u00f9 essenziale e fondamentale, e cio\u00e8 nella stessa costituzione degli imperi. Sento dire che i filosofi tedeschi hanno inventato il termine di meta-politica per porlo, in rapporto a politica, nella stessa relazione che c&#8217;\u00e8 tra metafisica e fisica. Mi sembra che questa nuova espressione sia molto ben trovata, per esprimere la metafisica della politica; infatti ce n&#8217;\u00e8 una, e questa scienza merita tutta l&#8217;attenzione degli osservatori.<\/p>\n<p style=\"text-align: justify;\">Uno scrittore anonimo, che si occupava molto di questo genere di speculazioni e che cercava di esplorare le fondamenta nascoste dell&#8217;edificio sociale, si credeva in diritto, circa vent&#8217;anni fa, di proporre, come altrettanti assiomi incontestabili, le proposizioni seguenti, diametralmente opposte alle teorie del tempo:<\/p>\n<p style=\"text-align: justify;\"><strong>1.<\/strong> Nessuna costituzione \u00e8 frutto di una deliberazione: i diritti dei popoli non sono mai scritti, o lo sono solo come semplici dichiarazioni di diritti anteriori non scritti.<\/p>\n<p style=\"text-align: justify;\"><strong>2.<\/strong> L&#8217;azione umana, in questi casi, \u00e8 talmente limitata che gli stessi uomini che agiscono sono solo delle circostanze.<\/p>\n<p style=\"text-align: justify;\"><strong>3.<\/strong> I diritti dei popoli, propriamente detti, derivano quasi sempre dalla concessione dei sovrani, e possono essere allora verificati storicamente; ma i diritti del sovrano e dell&#8217;aristocrazia non hanno n\u00e9 data n\u00e9 autori conosciuti.<\/p>\n<p style=\"text-align: justify;\"><strong>4.<\/strong> Queste stesse concessioni sono sempre state precedute da uno stato di cose, indipendente dalla volont\u00e0 del sovrano, che le ha rese necessarie.<\/p>\n<p style=\"text-align: justify;\"><strong>5<\/strong>. Sebbene le leggi scritte non siano mai altro che dichiarazioni di diritti anteriori, non tutti questi diritti possono per\u00f2 essere scritti.<\/p>\n<p style=\"text-align: justify;\"><strong>6.<\/strong> Pi\u00f9 si scrive, pi\u00f9 l&#8217;istituzione \u00e8 debole.<\/p>\n<p style=\"text-align: justify;\"><strong>7<\/strong>. Pu\u00f2 darsi la libert\u00e0 solo una nazione che gi\u00e0 la possiede; (2) l&#8217;influenza umana non si estende infatti oltre lo sviluppo dei diritti esistenti.<\/p>\n<p style=\"text-align: justify;\"><strong>8<\/strong>. I legislatori propriamente detti sono uomini straordinari che forse non appartengono che al mondo antico e alla giovinezza delle nazioni.<\/p>\n<p style=\"text-align: justify;\"><strong>9.\u00a0<\/strong>Questi legislatori, anche con la loro meravigliosa potenza, non hanno mai fatto altro che raccogliere elementi preesistenti, e hanno sempre agito in nome della divinit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>10<\/strong>. La libert\u00e0, in un certo senso, \u00e8 un dono dei re; perch\u00e9 quasi tutte le nazioni libere furono costituite da re. (3)<\/p>\n<p style=\"text-align: justify;\"><strong>11.<\/strong>Non vi fu mai nazione libera che non avesse nella sua costituzione naturale germi di libert\u00e0 tanto antichi quanto essa, e nessuna nazione tent\u00f2 mai efficacemente di sviluppare, attraverso le sue leggi fondamentali scritte, diritti diversi da quelli che erano presenti nella sua costituzione naturale.<\/p>\n<p style=\"text-align: justify;\"><strong>12.<\/strong> Una qualsiasi assemblea di uomini non pu\u00f2 costituire una nazione. Una impresa del genere merita anzi di ottenere un posto tra gli atti di follia pi\u00f9 memorabili. (4)<\/p>\n<p style=\"text-align: justify;\">Non sembra che dal 1796, data della prima edizione del libro citato, (5) sia accaduto nel mondo qualcosa che abbia potuto indurre l&#8217;autore a ricredersi sulla sua teoria. Crediamo, anzi, che in questo momento possa essere utile svilupparla pienamente e seguirla in tutte le sue conseguenze, di cui una delle pi\u00f9 importanti \u00e8 senza dubbio quella che si trova enunciata in questi termini nel capitolo decimo della stessa opera:<\/p>\n<p style=\"text-align: justify;\">L&#8217;uomo non pu\u00f2 creare sovrani. &#8220;<em>Al massimo pu\u00f2 servire di strumento per spossessare un sovrano e abbandonare i suoi Stati a un altro sovrano gi\u00e0 principe&#8230; Del resto non \u00e8 mai esistita una famiglia sovrana cui si possa attribuire un&#8217;origine plebea. Se si manifestasse un tale fenomeno, segnerebbe una nuova epoca del mondo<\/em>&#8220;. (6)<\/p>\n<p style=\"text-align: justify;\">Si pu\u00f2 meditare su questa tesi, ratificata recentemente in maniera cosi solenne dalla censura divina. Ma non si pu\u00f2 sapere se l&#8217;ignorante leggerezza del nostro tempo non arriver\u00e0, a dire, seriamente, che &#8220;<em>se lo avesse voluto, sarebbe ancora al suo posto<\/em>&#8221; ; come del resto va ripetendo da due secoli che &#8220;<em>se Richard Cromwell avesse avuto il genio di suo padre, avrebbe reso stabile il protettorato nella sua famiglia<\/em>&#8221; ; il che equivale a dire: &#8220;<em>Se quella famiglia non avesse cessato di regnare, regnerebbe ancora<\/em>&#8220;.<\/p>\n<p style=\"text-align: justify;\">\u00c8 scritto: sono io che creo i RE (Prov 8, 15). Non \u00e8 affatto una frase da pulpito ne una metafora da predicatore; \u00e8 la verit\u00e0 letterale, semplice e palpabile. \u00c8 una legge del mondo politico. Dio fa i re, letteralmente. Egli prepara le stirpi regali; le matura entro una nube che nasconde la loro origine. Esse appaiono poi coronate di gloria e di onore; si stabiliscono; ed ecco il maggiore segno della loro legittimit\u00e0. Si fanno avanti come da s\u00e9, senza violenza da una parte e senza visibile deliberazione dall&#8217;altra: \u00e8 una specie di tranquillit\u00e0 magnifica, che non \u00e8 agevole esprimere. Legittima usurpazione mi sembrerebbe (se non fosse forse troppo audace) l&#8217;espressione propria per caratterizzare questi tipi di origine che il tempo si affretta a consacrare.<\/p>\n<p style=\"text-align: justify;\">Non ci si lasci dunque per nulla abbagliare dalle pi\u00f9 belle apparenze umane. Chi ne riun\u00ec infatti in misura maggiore di quello straordinario personaggio della cui caduta tutta l&#8217;Europa riecheggia ancora? Si vide mai una sovranit\u00e0 apparentemente pi\u00f9 consolidata, una maggiore riunione di mezzi, un uomo pi\u00f9 potente, pi\u00f9 attivo, pi\u00f9 temibile? Per lungo tempo lo vedemmo calpestare venti nazioni, mute e agghiacciate dal terrore; la sua potenza infine aveva gettato certe radici che potevano far disperare la speranza.<\/p>\n<p style=\"text-align: justify;\">Eppure ora \u00e8 caduto, e cosi in basso che la piet\u00e0 che lo contempla indietreggia, per paura di esserne toccata. Si pu\u00f2 qui osservare d&#8217;altronde, di passaggio, che, per una ragione un po&#8217; diversa, \u00e8 divenuto altrettanto difficile parlare di quest&#8217;uomo e dell&#8217;augusto rivale che ne ha liberato il mondo.<\/p>\n<p style=\"text-align: justify;\">L&#8217;uno sfugge all&#8217;insulto, l&#8217;altro alla lode. (7) Ma torniamo al nostro argomento. In un&#8217;opera conosciuta solo da un piccolo numero di persone a San Pietroburgo, l&#8217;autore scriveva nel 1810: &#8220;<em>Quando in una rivoluzione, due partiti si scontrano, se da un lato si vedono cadere vittime preziose, si pu\u00f2 scommettere che questo partito, malgrado ogni apparenza contraria, finir\u00e0 per vincere<\/em>&#8220;.<\/p>\n<p style=\"text-align: justify;\">Anche in questo caso si tratta di un&#8217;asserzione la cui verit\u00e0 \u00e8 stata recentemente dimostrata nella maniera pi\u00f9 mirabile e imprevista. L&#8217;ordine morale, come l&#8217;ordine fisico, ha le sue leggi, e la ricerca di queste leggi menta di occupare le meditazioni di un vero filosofo.<\/p>\n<p style=\"text-align: justify;\">Dopo un intero secolo di futilit\u00e0 criminali, \u00e8 giunto il momento di ricordarci chi siamo e di far risalire ogni scienza alla sua fonte. Questo \u00e8 il motivo che ha spinto l&#8217;autore di quest&#8217;opuscolo a permettergli di evadere dalla timida cartella che lo tratteneva da cinque anni. Ne conserviamo dunque la data e lo riproduciamo tale e quale fu scritto a quell&#8217;epoca. L&#8217;amicizia ha causato questa pubblicazione e sar\u00e0 forse tanto peggio per l&#8217;autore, giacch\u00e9 quella cara signora, in certe occasioni, \u00e8 altrettanto cieca del fratello.<\/p>\n<p style=\"text-align: justify;\">Comunque sia, lo spirito che ha dettato l&#8217;opera gode di un privilegio noto: pu\u00f2 certamente ingannarsi talvolta su punti indifferenti; pu\u00f2 esagerare o tenere un linguaggio troppo alto; pu\u00f2 offendere la lingua o il gusto, e in questo caso, tanto meglio per i maligni, se per caso ce ne sono; ma gli rester\u00e0 sempre la pi\u00f9 fondata speranza di non offendere nessuno, perch\u00e9 ama tutti; e inoltre la perfetta certezza di interessare una classe di uomini assai numerosa e stimabile, senza poter mai nuocere a uno solo: questa fede rende assolutamente tranquillo l&#8217;autore.<\/p>\n<p style=\"text-align: justify;\">S.Pietroburgo, maggio 1814<\/p>\n<p style=\"text-align: justify;\"><strong>Note a prefazione:<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>(1)<\/strong> Pu\u00f2 sorprendere il richiamo di de Maistre a Thomas Robert Malthus (1766-1834) che nel suo An Essay on the Principle of Population (1798) sostenne la tesi dell&#8217;esito catastrofico del crescente squilibrio tra la progressione geometrica dell&#8217;aumento della popolazione e la progressione aritmetica della produzione dei mezzi di sussistenza. Le teorie del Malthus, ampiamente riprese nell&#8217;Ottocento (pu\u00f2 essere interessante ricordare che la societ\u00e0 malthusiana di Londra fu fondata nel 1877 da Carlo Bradlaugh e dalla teosofa Annie Besant) e riproposte oggi in forma pi\u00f9 sofisticata dalla Fao e dal Club di Roma si sono dimostrate scientificamente inconsistenti (per una loro recente confutazione cfr. Colin Clark, <em>Il mito dell&#8217;esplosione demografica<\/em>, Ares, Milano 1974); tuttavia \u00e8 da ricordare che i mezzi preventivi suggeriti dal Malthus per frenare la crescita demografica escludono le pratiche anticoncenzionali, su cui i neomalthusismi fonderanno le loro teorie, e consistono nel ritardo dei matrimoni, nella volontaria rinuncia al matrimonio da parte dei tarati, e soprattutto nell&#8217;astinenza prematrimoniale e coniugale; \u00e8 in questa chiave di elogio della castit\u00e0 e della continenza sessuale che de Maistre lesse evidentemente l&#8217;opera, senza poterne prevedere le successive deformazioni (N.d.T.).<\/p>\n<div>\n<div align=\"justify\">\n<div><strong>(2)<\/strong> Machiavelli \u00e8 chiamato qui come testimone: &#8220;<em>Uno popolo, uso a vivere sotto uno principe, se per qualche accidente diventa libero, con difficolt\u00e0 mantiene la libert\u00e0<\/em>&#8221; (Discorsi sopra la prima Deca di Tito Livio, libro I, cap. XVI).<\/div>\n<div><strong>(3)<\/strong> Questo principio deve essere preso in grande considerazione nelle monarchie moderne. Poich\u00e9 tutte le legittime e sante franchigie di questo genere devono derivare dal sovrano, tutto ci\u00f2 che gli \u00e8 strappato con la forza \u00e8 colpito da anatema. &#8220;<em>Scrivere una legge &#8211; diceva molto bene Demostene &#8211; non \u00e8 nulla: \u00e8 IL FAR VOLERE che \u00e8 tutto<\/em>&#8221; (Olynth. III). Ma se questo \u00e8 vero di un sovrano riguardo al popolo, che cosa diremmo di una nazione, cio\u00e8, per usare i termini pi\u00f9 dolci, di un pugno di accesi dottrinari che proponessero una costituzione a un legittimo sovrano come si propone una capitolazione a un generale assediato? Tutto questo sarebbe indecente, assurdo, e, soprattutto, nullo.<\/div>\n<div><strong>(4)<\/strong> Citiamo nuovamente Machiavelli: &#8221; \u00c8 necessario che uno solo sia quello che dia il modo, e dalla cui mente dependa qualunque simile ordinazione &#8221; (Discorsi sopra la prima Deca di Tito Livio, libro I, cap. IX).<\/div>\n<div><strong>(5)<\/strong> Consid\u00e9rations sur la France, cap. VI.<\/div>\n<div><strong>(6)<\/strong> Ibidem, cap. X, \u00a7 3.<\/div>\n<div><strong>(7)<\/strong> L&#8217;augusto rivale di Napoleone cui de Maistre si riferisce \u00e8 Alessandro I<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>http:\/\/www.totustuus.biz\/users\/pvalori\/index.html Conte Joseph De Maistre (1753-1821)<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":33351,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53,54],"tags":[852],"class_list":["post-2465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-rivoluzione-e-controrivoluzione","tag-joseph-de-maistre","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La politica, figlia dell&#039;esperienza; la storia, politica sperimentale - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La politica, figlia dell&#039;esperienza; la storia, politica sperimentale - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2007-02-01T11:49:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-22T09:39:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/02\/De-Maistre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"226\" \/>\n\t<meta property=\"og:image:height\" content=\"223\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La politica, figlia dell&#8217;esperienza; la storia, politica sperimentale\",\"datePublished\":\"2007-02-01T11:49:17+00:00\",\"dateModified\":\"2016-04-22T09:39:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\\\/\"},\"wordCount\":2013,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2007\\\/02\\\/De-Maistre.jpg\",\"keywords\":[\"Joseph de Maistre\"],\"articleSection\":[\"Politica\",\"Rivoluzione e controrivoluzione\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\\\/\",\"name\":\"La politica, figlia dell'esperienza; la storia, politica sperimentale - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2007\\\/02\\\/De-Maistre.jpg\",\"datePublished\":\"2007-02-01T11:49:17+00:00\",\"dateModified\":\"2016-04-22T09:39:29+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2007\\\/02\\\/De-Maistre.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2007\\\/02\\\/De-Maistre.jpg\",\"width\":226,\"height\":223},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La politica, figlia dell&#8217;esperienza; la storia, politica sperimentale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La politica, figlia dell'esperienza; la storia, politica sperimentale - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\/","og_locale":"it_IT","og_type":"article","og_title":"La politica, figlia dell'esperienza; la storia, politica sperimentale - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2007-02-01T11:49:17+00:00","article_modified_time":"2016-04-22T09:39:29+00:00","og_image":[{"width":226,"height":223,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/02\/De-Maistre.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"10 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La politica, figlia dell&#8217;esperienza; la storia, politica sperimentale","datePublished":"2007-02-01T11:49:17+00:00","dateModified":"2016-04-22T09:39:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\/"},"wordCount":2013,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/02\/De-Maistre.jpg","keywords":["Joseph de Maistre"],"articleSection":["Politica","Rivoluzione e controrivoluzione"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\/","name":"La politica, figlia dell'esperienza; la storia, politica sperimentale - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/02\/De-Maistre.jpg","datePublished":"2007-02-01T11:49:17+00:00","dateModified":"2016-04-22T09:39:29+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/02\/De-Maistre.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2007\/02\/De-Maistre.jpg","width":226,"height":223},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-politica-figlia-dellesperienza-la-storia-politica-sperimentale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La politica, figlia dell&#8217;esperienza; la storia, politica sperimentale"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2465"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2465\/revisions"}],"predecessor-version":[{"id":33353,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2465\/revisions\/33353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/33351"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}