{"id":2408,"date":"2006-12-21T00:00:00","date_gmt":"2006-12-20T23:00:00","guid":{"rendered":""},"modified":"2016-01-04T18:54:07","modified_gmt":"2016-01-04T17:54:07","slug":"giovanna-fai-il-presepe","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovanna-fai-il-presepe\/","title":{"rendered":"Giovanna, fai il presepe"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/12\/presepe.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-29203\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/12\/presepe.jpg\" alt=\"presepe\" width=\"250\" height=\"187\" \/><\/a>Il Foglio<\/strong>, sabato 9 dicembre 2006<\/div>\n<p style=\"text-align: justify;\"><em>L\u00b4albero lascialo perdere. Ricordati piuttosto che senza quel bambino e quella mangiatoia saresti ancora un\u00b4acciuga<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Camillo Langone<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Carissima Giovanna,<\/div>\n<p style=\"text-align: justify;\">mi raccomando, l\u00b4albero no. Tempo fa scrissi un romanzo, vabb\u00e8 non voglio esagerare, era un racconto lungo, intitolato &#8220;La battaglia del vino rosso contro il vino bianco&#8221;. Non so nemmeno che fine abbia \u00a0fatto, tanto mi piaceva, l\u00b4avr\u00f2 perso o buttato. Per\u00f2 mi ricordo perfettamente che il protagonista combatteva un\u00b4altra guerra privata oltre a quella contro lo Chardonnay: girava con gli amici la Toscana per segare abeti. Quelle conifere spelacchiate che vengono piantate nei giardini delle villette al posto di alberi pi\u00f9 adatti al paesaggio e al clima della collina centroitaliana: cipressi, aceri, querce&#8230;<\/p>\n<p style=\"text-align: justify;\">Quel mio eroe inedito non era soltanto un cultore della filologia arborea, non era solo uno squisito conservatore che fra Arezzo e Siena pretendeva di vedere le stesse piante che videro e dipinsero Leonardo e Lorrain. Era anche un amante del presepe. Sapeva che gli abeti sono piantati nei giardini delle villette da uomini malvagi con l\u00b4intenzione di trasformarli a dicembre in alberi di Natale.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec come la moneta cattiva scaccia quella buona, l\u00b4albero scaccia il presepe. Ci pu\u00f2 essere una fase di compresenza ma l\u00b4esito finale \u00e8 questo. Sotto gli abeti non cresce niente, gli aghi caduti rendono acido e inospitale il terreno, sotto l\u00b4albero di Natale muore il Natale che discende dal latino e significa &#8220;della nascita&#8221;. Nascita di chi, di che cosa, se manca il presepe e quindi il Bambino? O se il nesso non \u00e8 evidente come spesso accade?<\/p>\n<p style=\"text-align: justify;\">Se ad esempio all\u00b4albero manca la stella cometa, segnale indicatore della nativit\u00e0? Resta un albero, solo un albero, a rappresentare s\u00e9 stesso e al limite la natura con i suoi cicli di vita e di morte (soprattutto di morte visto che la stragrande maggioranza degli alberi di Natale \u00e8 costituita da abeti agonizzanti, estirpati con violenza, amputati delle radici e destinati a seccare in breve tempo, compresi quelli ambientalisti pubblicizzati da Ikea, la multinazionale anticristiana che vende mobili tristi e abeti morenti, per\u00f2 ecologici perch\u00e9 si possono riconsegnare dopo le feste affinch\u00e9 vengano trasformati in truciolato, sai l\u00b4abete com\u00b4\u00e8 contento).<\/p>\n<p style=\"text-align: justify;\">L\u00b4albero tende all\u00b4astratto mentre il presepe \u00e8 figurativo, ma queste cose non devo spiegarle a te che di mestiere fai la &#8220;libera curatrice&#8221;, come mi hai spiegato, curatrice di mostre saltuaria almeno fino a quando non riuscirai a farti assumere, te lo auguro di cuore, in uno dei nuovi musei napoletani di arte contemporanea (quello comunale a Chiaia, quello regionale in centro&#8230;) per diventare finalmente curatrice senza aggettivi, senza quella parolina che sembra messa l\u00ec per beffare le lavoratrici precarie: &#8220;libera&#8221;.<\/p>\n<p style=\"text-align: justify;\">L\u00b4albero \u00e8 minimalista, pu\u00f2 essere stilizzato e ridotto a segno grafico, a triangolo verde o anche rosso. E come dice James Hillman, che sar\u00e0 pure uno psicanalista ma qualcosa capisce, &#8220;l\u00b4anima \u00e8 costretta a scappare dal minimalismo.&#8221; Prova tu a stilizzare un presepe. Impossibile perch\u00e9 \u00e8 impossibile stilizzare la vita, che sguscia e prolifera e prende sempre nuove forme.<\/p>\n<p style=\"text-align: justify;\">L\u00b4albero \u00e8 sostenuto dalla pubblicit\u00e0, dai film, dai centri commerciali, \u00e8 accettato da molte religioni e da tutte le irreligioni. Mentre il presepe appartiene solo alla vera religione, quella fondata da Ges\u00f9 Cristo alle sorgenti del Giordano, \u00a0sulle alture del Golan, e che attraverso l\u00b4imposizione delle mani si \u00e8 trasmessa per duemila anni senza \u00a0interruzioni da Pietro fino a Benedetto e che da Benedetto si trasmetter\u00e0 ad altri uomini fin quando ci saranno uomini perch\u00e9 &#8220;io sono con voi tutti i giorni, fino alla fine del mondo&#8221;.<\/p>\n<p style=\"text-align: justify;\">Il Bambino Divino non poteva apparire fra i protestanti, quei musilunghi che non ne amano la Madre, tantomeno fra i maomettani per i quali Dio \u00e8 \u00a0lontanissimo, impenetrabile e di certo non pu\u00f2 essere tenuto in braccio e allattato. Poteva apparire ed \u00e8 apparso in Italia, in un paese di montagna al centro esatto della penisola, a met\u00e0 strada fra nord e sud, fra Adriatico e Tirreno, ovvero a Greccio, diocesi di Rieti. Ad accoglierlo non poteva che essere l\u00b4<em>alter Christus<\/em>, il secondo Cristo, San Francesco, che nella notte del Santo Natale 1223 allest\u00ec il primo presepe. Non a caso era un presepe vivente. Vivo e brulicante.<\/p>\n<p style=\"text-align: justify;\">Francesco, innamorato della Creazione, non si sarebbe mai sognato di festeggiare una nascita segando un albero. Animato dallo Spirito infuse entusiasmo in tutto il paese che si trasform\u00f2 in una nuova Betlemme: &#8220;Uomini e donne con la gioia nel cuore facevano a gara nel preparare ceri e fiaccole per rischiarare quella notte fatidica, in cui si accese la Stella che illumin\u00f2 tutti i giorni e tutti gli anni.<\/p>\n<p style=\"text-align: justify;\">Alcuni preparano la mangiatoia, altri recano il fieno, altri ancora pensano al bue e all\u00b4asinello&#8221;. La moglie del signore di Greccio fece con le sue mani il simulacro del Bambino. Gli araldi annunciarono la notizia. I frati accompagnarono Francesco, gi\u00e0 circonfuso di santit\u00e0. Arriv\u00f2 anche l\u00b4attesa benedizione del Papa, che autorizzava a dire messa davanti a una stalla, su un altare portatile, situazione insolita che poteva sembrare indecorosa. (Il primo presepe vivente non fu una manifestazione folcloristica, fu una messa solenne).<\/p>\n<p style=\"text-align: justify;\">Da quella notte meravigliosa il Dio-Bambino \u00e8 entrato nelle case, e non solo per i suoi coetanei. E\u00b4 un suicidio dell\u00b4anima metterlo fuori dalla porta solo perch\u00e9 siamo diventati grandi. E\u00b4 come dire che siamo diventati vecchi, insensibili, quasi morti, incapaci di provare alcunch\u00e9. Tu mi dici che il presepe non lo vorresti fare pi\u00f9 ma che alla fine ti convinci quando ti vengono a trovare i nipotini: &#8220;Mi intenerisco e lo faccio con loro: cuore di\u00a0 zia!&#8221;. Benissimo.<\/p>\n<p style=\"text-align: justify;\">Ma oltre che per i bambini vorrei che lo facessi per il Bambino. E per te, e per gli altri. San Francesco quella notte non aveva in mente il catechismo per l\u00b4infanzia, si rivolgeva all\u00b4intera comunit\u00e0 e anche a s\u00e9 stesso. &#8220;Pi\u00f9 che rievocare l\u00b4episodio egli voleva rivivere il mistero&#8221; \u00e8 stato detto. Questo dev\u00b4essere anche il nostro atteggiamento.<\/p>\n<p style=\"text-align: justify;\">Non dobbiamo riprodurre meccanicamente una tradizione, dobbiamo sentire il bisogno di vedere nascere il Bambino sotto i nostri occhi, fra le nostre mani, la Santa Notte che sta per arrivare. Ho trovato un brano di Francesco Mastriani, romanziere ottocentesco prolificassimo (107 romanzi, beato lui! come faceva?), che descrive il rito cos\u00ec come si svolgeva a Napoli all\u00b4epoca sua: &#8220;Uomini, donne, e ragazzi provvisti di ceri, fanno in processione il giro della casa, scendono talvolta nel cortile, visitano gli altri quartieri del palazzo, e si riducono al presepe, dove genuflessi e cantando l\u00b4inno ambrosiano, da qualcuno della famiglia (spesso un ragazzo) viene collocato sulla paglia il celeste Pargoletto&#8221;.<\/p>\n<p style=\"text-align: justify;\">Era il tempo felice in cui Napoli andava famosa nel mondo per la devozione e i mandolini: citt\u00e0 da cartolina, dissero in seguito come fosse una colpa, come se il pino di Posillipo e il sangue di san Gennaro ostacolassero le belle migliorie che avevano in mente, centri direzionali, acciaierie, scampie.<\/p>\n<p style=\"text-align: justify;\">Una processione tipo quella di Mastriani la faccio anch\u00b4io, anche se in tono minore, senza coinvolgere i vicini di casa. E senza cantare l\u00b4inno ambrosiano che c\u00b4entra con Milano solo perch\u00e9 composto da sant\u00b4Ambrogio. E\u00b4 un canto gregoriano chiamato anche &#8220;Veni Redemptor gentium&#8221;, dalle prime parole, che in questo preciso istante sto scaricando con eMule, miracoloso e forse birichino programmino che in questi ultimi tempi mi ha riempito il computer di musica.<\/p>\n<p style=\"text-align: justify;\">Fra pochi minuti lo potr\u00f2 ascoltare e da quel momento la mia lettera avr\u00e0 questa colonna sonora. Noi di solito cantiamo qualcosa di pi\u00f9 facile, in italiano, &#8220;Tu scendi dalle stelle&#8221;. Mi sembra l\u00b4accompagnamento ideale in quanto l\u00b4autore, sant\u00b4Alfonso Maria de\u00b4 Liguori, \u00e8 napoletano e settecentesco come lo stile di tanti presepi casalinghi.<\/p>\n<p style=\"text-align: justify;\">Cantiamo solo la prima parte. &#8220;Tu scendi dalle stelle, \/ o Re del cielo, \/ e vieni in una grotta al freddo e al gelo&#8221;, e qui mi vengono i brividi. &#8220;O Bambino mio divino, \/ io ti vedo qui a tremar \/ o Dio beato \/ ah quanto ti cost\u00f2 l\u00b4averci amato!&#8221;, e a questo punto mi scendono le lacrime. Dovrebbe capirlo chiunque quanto stoni in un momento simile l\u00b4abete agonizzante, la distrazione che apportano le sue lucine.<\/p>\n<p style=\"text-align: justify;\">Lo dice Ges\u00f9: &#8220;Non potete servire a Dio e a Mammona&#8221;. L\u00b4albero \u00e8 mammonico, \u00e8 stato piazzato nel tempio famigliare dai mercanti e da l\u00ec bisogna scacciarlo prima che il suo neopaganesimo per poveri di spirito faccia guai ulteriori. Gli abeti lass\u00f9 sulle montagne, per la gioia degli scoiattoli, e il presepe quaggi\u00f9 per la gioia degli uomini a cui facilita almeno quattro delle sette opere di misericordia spirituale che la chiesa esorta caldamente a compiere. &#8220;Perdonare le offese&#8221;: il Natale ci rinnova liberandoci da quella zavorra che sono i propositi di vendetta.<\/p>\n<p style=\"text-align: justify;\">&#8220;Consolare gli afflitti&#8221;: invitare ad esempio le persone sole a condividere con noi i riti di festa. &#8220;Consigliare i dubbiosi&#8221; e &#8220;Insegnare agli ignoranti&#8221;: il presepe \u00e8 un formidabile catechismo visivo. Gli angeli evocano l\u00b4esistenza di una sfera superiore, di un mondo oltre il mondo.<\/p>\n<p style=\"text-align: justify;\">L\u00b4asino e il bue sembrano volerci parlare e dirci che la natura non \u00e8 necessariamente ferina, mortifera come per i pagani, ma pu\u00f2 essere addomesticata e resa amica. Dal volto della Madonna si capisce che tutto quello che conta \u00e8 amare ed essere amati.<\/p>\n<p style=\"text-align: justify;\">I Re Magi, che provenendo da paesi lontani vanno messi davanti alla mangiatoia solo all\u00b4Epifania, evidenziano che Ges\u00f9 \u00e8 nato per tutti i popoli: gli europei di Gasparre, gli africani di Baldassarre, gli asiatici di Melchiorre. In pratica i Re Magi mostrano che Ges\u00f9 nasce ebreo ma che dopo pochi giorni diventa cattolico, cio\u00e8 universale.<\/p>\n<p style=\"text-align: justify;\">In un libro di Bukowski, e che c\u00b4entra Bukowski potrai dire ma Bukowski c\u00b4entra sempre perch\u00e9 \u00e8 una vena d\u00b4oro, il suo fango pullula di pepite, ho scovato due definizioni perfette e meno male che l\u00b4alcol danneggia le cellule cerebrali: &#8220;Un intellettuale \u00e8 un uomo che dice una cosa semplice in maniera difficile, un artista un uomo che dice una cosa difficile in maniera semplice.&#8221; Ecco, san Francesco era un grandissimo artista perch\u00e9 capace di tradurre nella lingua della commozione una montagna di noiosi libri teologici. Senza nemmeno averli letti. Lui stesso si definiva &#8220;ignorante e illetterato&#8221; e probabilmente nulla sapeva di iconoclastia, che \u00e8 una versione antica, quindi ancora religiosa, di minimalismo. A loro volta iconoclastia e minimalismo sono due forme di nichilismo.<\/p>\n<p style=\"text-align: justify;\">Quando mi hai detto che stavi organizzando una mostra a Castel dell\u00b4Ovo ho tremato, temevo fossero installazioni, specchi rotti, mucchi di sabbia, e a quel punto non so che fine avrebbe fatto la nostra amicizia. Poi mi \u00e8 arrivato il catalogo e ho tirato un sospiro di sollievo: erano quadri e sulle tele c\u00b4erano perfino delle figure. La questione delle immagini \u00e8 troppo importante per essere abbandonata nelle mani dei critici d\u00b4arte che sono, lasciamelo dire, in completa balia di Mammona.<\/p>\n<p style=\"text-align: justify;\">La affront\u00f2 Ratzinger quand\u00b4era ancora cardinale: &#8220;L\u00b4iconoclasmo come una negazione dell\u00b4incarnazione, come la somma di tutte le eresie. Incarnazione significa anzitutto che Dio, l\u00b4invisibile, entra nello spazio del visibile, perch\u00e9 noi, che siamo legati al materiale, possiamo riconoscerlo&#8221;.<\/p>\n<p style=\"text-align: justify;\">San Francesco inventando il presepe schiacci\u00f2 l\u00b4iconoclastia per secoli cos\u00ec come la Madonna fece scrocchiare la testa del serpente nel quadro di Caravaggio e nel film di Gibson, Dio ce lo conservi. Ora che il nichilismo torna a masticare vittime, che Botta, Fuksas e Meier sono assoldati da preti pi\u00f9 disgraziati di loro per cancellare ogni segno visibile di Cristo a cominciare dalla Croce, il presepe \u00e8 pi\u00f9 importante che mai.<\/p>\n<p style=\"text-align: justify;\">Con la sua attenzione per tutte le cose, anche le pi\u00f9 minute. Ti ricordi cosa disse il proprietario della Terrazza Calabritto quando ci port\u00f2 il conto? Io mangiai bene e bevetti meglio ma la cena si \u00e8 fissata nella mia memoria per quella sua parola: &#8220;Attenzione&#8221;. Ci avvis\u00f2 dello sconto con incredibile garbo,\u00a0 senza la solita laidezza del ristoratore ruffiano, dicendo: &#8220;Ho avuto un\u00b4attenzione&#8221;.<\/p>\n<p style=\"text-align: justify;\">Il presepe, in particolare quello napoletano, \u00e8 fondato sull\u00b4attenzione. Attenzione verso tutto: uomini, animali, cose. Attraverso la cura del particolare il presepista d\u00e0 valore a\u00a0 ogni singolo infinitesimale elemento. &#8220;La salvezza del piccolo&#8221; l\u00b4ha definita il filosofo Giorgio Agamben. Tutto viene attentamente considerato affinch\u00e9 tutto venga salvato. &#8220;Perfino i capelli del vostro capo sono tutti contati&#8221;: certi presepi sembrano l\u00b4illustrazione di queste parole di Ges\u00f9 riportate da Matteo. Mi si chiarisce una frase di don Giussani: &#8220;Dentro il Mistero anche l\u00b4acciuga mangiata dal tonno trova la sua redenzione&#8221;. Ho visto un milione di presepi e nemmeno quelli pi\u00f9 ingombranti prevedevano tonni e acciughe eppure ora capisco, siamo tutti acciughe e la stella del presepe ci indica la direzione da prendere per non finire in salamoia.<\/p>\n<p style=\"text-align: justify;\">Adesso non \u00e8 che ti dico di correre a San Gregorio Armeno per fare incetta di pastori e pecorelle, fra l\u00b4altro se c\u00b4\u00e8 qualcuno a cui San Gregorio Armeno piace non sono io ma sei tu: &#8220;Una folla bellissima, almeno l\u00ec non c\u00b4erano gli scugnizzi che ti tirano i petardi addosso, perch\u00e9 senn\u00f2 i pastorai non venderebbero quindi sono loro stessi a cacciarli&#8221;. Io preferisco via Tribunali dove c\u00b4\u00e8 meno folla e pi\u00f9 bellezza ovvero La Scarabattola.<\/p>\n<p style=\"text-align: justify;\">Vorrei comprare da quei sommi artigiani un presepe in campana di vetro, un presepe a sviluppo verticale con la Sacra Famiglia o poco pi\u00f9, soluzione perfetta per l\u00b4esteta pigro che sono: nessun bisogno di cercare il muschio, di ritagliar le stelle, di ricomprare ogni anno le pecorelle smarrite&#8230; Un presepe monoblocco che non richieda interventi, a parte l\u00b4estrazione della campana dallo sgabuzzino ogni 8 dicembre.<\/p>\n<p style=\"text-align: justify;\">Ma forse come dicevi tu, alludendo alla gioia dei nipotini quando cominciano a trafficarci, la magia del presepe \u00e8 fatta anche di allestimento. Alzo le mani: ognuno scelga il presepe pi\u00f9 confacente, piccolo o grande, fisso o mobile, napoletano o leccese o bolognese o peruviano, l\u00b4importante \u00e8 che si faccia.<\/p>\n<p style=\"text-align: justify;\">San Gregorio Armeno o Tribunali o soffitta col baule degli avi, attingi dove ti pare ma sbrigati, non aspettare che i nipoti ti preghino di farlo, e non frapporre pi\u00f9 scuse fra te e il Bambino, non dire che per il presepe ci vuole la famiglia altrimenti che senso ha, ci vuole l\u00b4armonia altrimenti che senso ha, ci vuole chiss\u00e0 quale fede vigorosa altrimenti che senso ha. Non \u00e8 la tua condizione a dare un senso al presepe, \u00e8 il presepe che d\u00e0 un senso alla tua condizione. Qualunque essa sia.<\/p>\n<p style=\"text-align: justify;\">Che Ges\u00f9 Bambino ti benedica sempre.<\/p>\n<p style=\"text-align: justify;\">Camillo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Foglio, sabato 9 dicembre 2006 L\u00b4albero lascialo perdere. Ricordati piuttosto che senza quel bambino e quella mangiatoia saresti ancora un\u00b4acciuga di Camillo Langone<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovanna-fai-il-presepe\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":29203,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[1063],"class_list":["post-2408","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-e-tradizioni","tag-presepe","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Giovanna, fai il presepe - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovanna-fai-il-presepe\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Giovanna, fai il presepe - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovanna-fai-il-presepe\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2006-12-20T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-01-04T17:54:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/12\/presepe.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovanna-fai-il-presepe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovanna-fai-il-presepe\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Giovanna, fai il presepe\",\"datePublished\":\"2006-12-20T23:00:00+00:00\",\"dateModified\":\"2016-01-04T17:54:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovanna-fai-il-presepe\\\/\"},\"wordCount\":2399,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovanna-fai-il-presepe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/12\\\/presepe.jpg\",\"keywords\":[\"presepe\"],\"articleSection\":[\"Cultura e tradizioni\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovanna-fai-il-presepe\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovanna-fai-il-presepe\\\/\",\"name\":\"Giovanna, fai il presepe - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovanna-fai-il-presepe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovanna-fai-il-presepe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/12\\\/presepe.jpg\",\"datePublished\":\"2006-12-20T23:00:00+00:00\",\"dateModified\":\"2016-01-04T17:54:07+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovanna-fai-il-presepe\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovanna-fai-il-presepe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovanna-fai-il-presepe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/12\\\/presepe.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/12\\\/presepe.jpg\",\"width\":259,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/giovanna-fai-il-presepe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Giovanna, fai il presepe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Giovanna, fai il presepe - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovanna-fai-il-presepe\/","og_locale":"it_IT","og_type":"article","og_title":"Giovanna, fai il presepe - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovanna-fai-il-presepe\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2006-12-20T23:00:00+00:00","article_modified_time":"2016-01-04T17:54:07+00:00","og_image":[{"width":259,"height":194,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/12\/presepe.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"12 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovanna-fai-il-presepe\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovanna-fai-il-presepe\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Giovanna, fai il presepe","datePublished":"2006-12-20T23:00:00+00:00","dateModified":"2016-01-04T17:54:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovanna-fai-il-presepe\/"},"wordCount":2399,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovanna-fai-il-presepe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/12\/presepe.jpg","keywords":["presepe"],"articleSection":["Cultura e tradizioni"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovanna-fai-il-presepe\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovanna-fai-il-presepe\/","name":"Giovanna, fai il presepe - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovanna-fai-il-presepe\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovanna-fai-il-presepe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/12\/presepe.jpg","datePublished":"2006-12-20T23:00:00+00:00","dateModified":"2016-01-04T17:54:07+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovanna-fai-il-presepe\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovanna-fai-il-presepe\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovanna-fai-il-presepe\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/12\/presepe.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/12\/presepe.jpg","width":259,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/giovanna-fai-il-presepe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Giovanna, fai il presepe"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2408"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2408\/revisions"}],"predecessor-version":[{"id":29204,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2408\/revisions\/29204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/29203"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2408"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2408"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}