{"id":2303,"date":"2006-11-02T00:00:00","date_gmt":"2006-11-01T23:00:00","guid":{"rendered":""},"modified":"2015-01-12T13:17:30","modified_gmt":"2015-01-12T12:17:30","slug":"ragazze-spericolate-e-anticonformiste","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ragazze-spericolate-e-anticonformiste\/","title":{"rendered":"Ragazze spericolate e anticonformiste"},"content":{"rendered":"<div style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/clausura.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-16623 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/clausura.jpg\" alt=\"clausura\" width=\"240\" height=\"192\" \/><\/a>Tratto dalla newsletter <strong>Lo Straniero <\/strong><\/div>\n<p style=\"text-align: justify;\"><strong>Ragazze spericolate e anticonformiste: il fascino della clausura, l\u2019avventura di Dio, l\u2019abbraccio forte e dolce di Gesu\u2019<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>Come difendersi dall\u2019assedio del nulla, dalla noia, dall\u2019insoddisfazione, dal male e dalla stupida televisione? Come ritrovare il gusto della vita? Ascoltate il cuore e aprite gli occhi&#8230; stupitevi!<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Antonio Socci<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">I mass media trasformano ogni piccola scemenza in una tendenza, ogni stravaganza finto-trasgressiva in una moda, ogni sgallettata che appare in tv in un \u201cevento\u201d da immortalare. Ma non si sono accorti di un fenomeno che \u2013 questo s\u00ec \u2013 \u00e8 l\u2019unico veramente trasgressivo e anticonfomista: l\u2019aumento delle giovani ragazze che scelgono la clausura. Anche la televisione \u2013 dovendo riempire ore del palinsesto per propagare le \u201ceroiche\u201d gesta dell\u2019Isola dei famosi, cos\u00ec da rincoglionire il pubblico sotto tonnellate di Nulla \u2013 sta alla larga da questo eroismo autentico e da questo sorprendente amore.<\/div>\n<p style=\"text-align: justify;\">I dati sono semplici. Fra il 2004 e il 2005, in Italia, sono aumentate di 300 unit\u00e0 le vocazioni claustrali. Trecento giovani ragazze italiane, spesso laureate, del tutto normali, figlie del loro tempo (discoteche comprese), che si sono \u201cinnamorate\u201d cos\u00ec e hanno lasciato tutto, proprio tutto, scegliendo le quattro mura di una clausura e una vita di totale povert\u00e0, silenzio e preghiera, per questo Amore.<\/p>\n<p style=\"text-align: justify;\">Complessivamente le professe solenni sono 6.672 (anche i monasteri sono passati da 524 a 533). Ed \u00e8 una fioritura non solo italiana. Sempre nel periodo 2004-2005 le claustrali nel mondo sono aumentate di 1.147 unit\u00e0, arrivando a 47. 626 (a cui vanno aggiunte 8.107 ragazze in periodo di formazione). Curiosamente sono le laicissime Spagna e Francia che, con l\u2019Italia, hanno il maggior numero di vocazioni di questo tipo.<\/p>\n<p style=\"text-align: justify;\">Queste stupende avventuriere innamorate, sono figlie di una generazione che non conosce pi\u00f9 la carezza di Dio, la compagnia forte e dolce dell\u2019Eterno. Facevano parte di una generazione consumata dal desiderio di qualcosa a cui non sa dare un nome, del senso della vita che non sa trovare. Vengono in mente le antiche parole del profeta biblico Amos: \u201cEcco stanno per venire dei giorni\/ nei quali mander\u00f2 la mia fame sopra la terra:\/ non una fame di pane, non una sete d\u2019acqua,\/ ma fame e sete di udire la Parola di Dio.\/ Ed essi andranno errando da un mare all\u2019altro,\/ e dal Settentrione all\u2019Oriente;\/ ed andranno qua e l\u00e0 cercando la parola di Dio\/ e non la troveranno.\/ In quei giorni saranno sfiniti per la sete\/ le fanciulle e i giovani\u201d (VIII, 11-13).<\/p>\n<p style=\"text-align: justify;\">Ma c\u2019\u00e8 chi ha la fortuna di trovare. Anzi di essere trovato. Come ha detto ad una cronista di Avvenire suor Maria Eliana del Carmelo di Carpineto Romano: \u201cnon pensavo al Signore, ma Lui, nel suo amore, ha pensato a me e si \u00e8 fatto presente\u201d. Racconta: \u201cnon ho mai pensato di farmi suora. Tanto meno monaca di clausura. Sono nata a Rimini e ho vissuto per 19 anni a Cattolica, perci\u00f2 non mancava il modo di divertirsi\u201d. Alla maniera di tutti: \u201cla mia vita era come quella di tanti giovani: mare, discoteca, uscite con gli amici\u2026\u201d. Poi \u00e8 arrivato il grande amore: \u201cMi sono sentita amata da Lui e questo amore mi ha toccato il cuore\u201d.<\/p>\n<p style=\"text-align: justify;\">Mi \u00e8 capitato di visitare un monastero di clausura umbro, di clarisse. Ne sono uscito abbagliato. Ho parlato con quattro suore: due erano sull\u2019ottantina, stavano l\u00ec dentro da 50 anni. Ma io non ho mai conosciuto persone pi\u00f9 ilari, vitali, dolci, piene perfino di buonumore. Poi ho parlato con due nuove clarisse: sui 25-26 anni. Ero stupito dai loro volti e dai loro occhi. Avrei voluto avere una telecamera per fare loro un primo piano stretto mentre parlavano.<\/p>\n<p style=\"text-align: justify;\">Vi assicuro che chiunque rimarrebbe colpito. Non era solo la consueta bellezza di due giovani donne. Era, la loro, una bellezza speciale, piena di luce, perch\u00e9 soprattutto erano felici. Parlando con semplicit\u00e0 delle cose normali della loro vita trasmettevano dolcezza e bont\u00e0. Loro che avevano rinunciato a tutto, anche alla loro giovinezza e vivevano totalmente povere dietro quella grata, mi sembravano possedere tutto. Soprattutto la pace che noi non conosciamo. Pur portando davanti al trono di Dio, ogni ora, tutti i dolori e le sofferenze del mondo che affluiscono fra queste mura.<\/p>\n<p style=\"text-align: justify;\">E\u2019 il fascino di questa ricchezza, di questa Bellezza sconosciuta a tutti noi che viviamo nel mondo, che sta dietro il successo del film \u201cIl grande silenzio\u201d. Non si ha la sensazione di persone che abbiano perduto qualcosa o rinunciato a qualcosa, ma piuttosto di donne e uomini che possiedono ci\u00f2 che noi affannosamente cerchiamo e la cui mancanza ci sfianca e ci addolora. Il vero deserto, quello dove si muore di sete, \u00e8 nei nostri cuori sazi e disperati e non certo in quei chiostri silenziosi, simili piuttosto a oasi verdi e fresche. Ci\u00f2 che il mondo chiama \u201cfelicit\u00e0\u201d \u00e8 dissipazione che lascia solo la cenere di un fuoco troppo fatuo. L\u2019insoddisfazione perenne accompagna gli umani. Da sempre. Ci\u00f2 che dappertutto \u00e8 ricerca agitata e nervosa l\u00ec, in quei chiostri, \u00e8 gioia dell\u2019abbandono. Ci\u00f2 che dovunque \u00e8 convulsa corsa al possesso del nulla l\u00ec \u00e8 godimento di Dio, l\u2019Eterno per cui siamo fatti.<\/p>\n<p style=\"text-align: justify;\">E\u2019 letteralmente una cosa dell\u2019altro mondo. Un altro mondo dentro il nostro mondo. Dove la verginit\u00e0 significa amore totale e trasfigurazione della propria stessa carne, \u201cdivinizzazione\u201d, come dicono i padri della Chiesa orientale che sanno ben riconoscere l\u2019aureola nel volto luminoso degli uomini di Dio. Il cardinal Ruini, concludendo il convegno di Verona, ha sottolineato questo \u201cboom\u201d delle vocazioni alla clausura, ma forse anche la Chiesa dovrebbe rifletterci. Perch\u00e9 gli istituti religiosi in genere hanno crisi di vocazioni mentre la clausura attrae? Non sar\u00e0 che troppo spesso i religiosi sono stati trasformati in assistenti sociali o attivisti? Non sar\u00e0 che il \u201cfare\u201d prevale sul \u201cmendicare\u201d e sull\u2019adorazione amorosa? Non sar\u00e0 che in troppi ordini religiosi \u2013 per dire \u2013 i superiori hanno sostituito il Buon Samaritano che guarisce (che \u00e8 Cristo) con psicologi e psicanalisti?<\/p>\n<p style=\"text-align: justify;\">Si potrebbe imparare qualcosa da questo fatto se si ascoltasse finalmente il Papa. Nelle sue parole pronunciate a Verona c\u2019\u00e8 tutto. C\u2019\u00e8 innanzitutto la passione per Ges\u00f9 Cristo. Che \u00e8 tutto. E che basta alla vita. S. Agostino, che aveva vissuto una giovinezza dissipata (in un modo simile alla nostra epoca erotomane e intellettualistica), ha descritto meglio di chiunque altro questo innamoramento di Cristo, la Bellezza fatta carne: \u201cTardi ti ho amato, o Bellezza sempre antica e sempre nuova, tardi ti ho amato! Ed ecco tu eri dentro di me e io ero fuori e l\u00e0 ti cercavo ed io nella mia deformit\u00e0 mi gettavo sulle cose ben fatte che tu avevi creato. Tu eri con me ed io non ero con te. Quelle bellezze esteriori mi tenevano lontano da te e tuttavia se esse non fossero state in te non sarebbero affatto esistite. Tu mi hai chiamato e hai squarciato la mia sordit\u00e0; tu hai brillato su di me e hai dissipato la mia cecit\u00e0. Tu hai emanato la tua fragranza e io ho sentito il tuo profumo e ora ti bramo. Ho gustato e ora ho fame e sete. Tu mi hai toccato e io bramo la tua pace\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tratto dalla newsletter Lo Straniero Ragazze spericolate e anticonformiste: il fascino della clausura, l\u2019avventura di Dio, l\u2019abbraccio forte e dolce di Gesu\u2019 Come difendersi dall\u2019assedio del nulla, dalla noia, dall\u2019insoddisfazione, dal male e dalla stupida televisione? Come ritrovare il gusto della vita? Ascoltate il cuore e aprite gli occhi&#8230; stupitevi! di Antonio Socci<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ragazze-spericolate-e-anticonformiste\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":16623,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[1369],"class_list":["post-2303","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","tag-clausura","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ragazze spericolate e anticonformiste - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ragazze-spericolate-e-anticonformiste\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ragazze spericolate e anticonformiste - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ragazze-spericolate-e-anticonformiste\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2006-11-01T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-01-12T12:17:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/clausura.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"192\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ragazze-spericolate-e-anticonformiste\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ragazze-spericolate-e-anticonformiste\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Ragazze spericolate e anticonformiste\",\"datePublished\":\"2006-11-01T23:00:00+00:00\",\"dateModified\":\"2015-01-12T12:17:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ragazze-spericolate-e-anticonformiste\\\/\"},\"wordCount\":1181,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ragazze-spericolate-e-anticonformiste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/11\\\/clausura.jpg\",\"keywords\":[\"clausura\"],\"articleSection\":[\"Chiesa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ragazze-spericolate-e-anticonformiste\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ragazze-spericolate-e-anticonformiste\\\/\",\"name\":\"Ragazze spericolate e anticonformiste - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ragazze-spericolate-e-anticonformiste\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ragazze-spericolate-e-anticonformiste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/11\\\/clausura.jpg\",\"datePublished\":\"2006-11-01T23:00:00+00:00\",\"dateModified\":\"2015-01-12T12:17:30+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ragazze-spericolate-e-anticonformiste\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ragazze-spericolate-e-anticonformiste\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ragazze-spericolate-e-anticonformiste\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/11\\\/clausura.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/11\\\/clausura.jpg\",\"width\":240,\"height\":192},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ragazze-spericolate-e-anticonformiste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ragazze spericolate e anticonformiste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ragazze spericolate e anticonformiste - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ragazze-spericolate-e-anticonformiste\/","og_locale":"it_IT","og_type":"article","og_title":"Ragazze spericolate e anticonformiste - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ragazze-spericolate-e-anticonformiste\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2006-11-01T23:00:00+00:00","article_modified_time":"2015-01-12T12:17:30+00:00","og_image":[{"width":240,"height":192,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/clausura.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ragazze-spericolate-e-anticonformiste\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ragazze-spericolate-e-anticonformiste\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Ragazze spericolate e anticonformiste","datePublished":"2006-11-01T23:00:00+00:00","dateModified":"2015-01-12T12:17:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ragazze-spericolate-e-anticonformiste\/"},"wordCount":1181,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ragazze-spericolate-e-anticonformiste\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/clausura.jpg","keywords":["clausura"],"articleSection":["Chiesa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ragazze-spericolate-e-anticonformiste\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ragazze-spericolate-e-anticonformiste\/","name":"Ragazze spericolate e anticonformiste - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ragazze-spericolate-e-anticonformiste\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ragazze-spericolate-e-anticonformiste\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/clausura.jpg","datePublished":"2006-11-01T23:00:00+00:00","dateModified":"2015-01-12T12:17:30+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ragazze-spericolate-e-anticonformiste\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ragazze-spericolate-e-anticonformiste\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ragazze-spericolate-e-anticonformiste\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/clausura.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/clausura.jpg","width":240,"height":192},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ragazze-spericolate-e-anticonformiste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Ragazze spericolate e anticonformiste"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2303"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2303\/revisions"}],"predecessor-version":[{"id":16625,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2303\/revisions\/16625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/16623"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2303"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2303"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}