{"id":2299,"date":"2006-11-02T00:00:00","date_gmt":"2006-11-01T23:00:00","guid":{"rendered":""},"modified":"2015-01-14T10:49:09","modified_gmt":"2015-01-14T09:49:09","slug":"liturgia-e-poveri-tesori-della-chiesa","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/liturgia-e-poveri-tesori-della-chiesa\/","title":{"rendered":"&laquo;Liturgia e poveri, tesori della Chiesa&raquo;"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/Malcom-Ranjith.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-16770\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/Malcom-Ranjith.jpg\" alt=\"Malcom Ranjith\" width=\"133\" height=\"200\" \/><\/a>30 Giorni<\/strong> n.9 settembre 2006<\/div>\n<p style=\"text-align: justify;\"><em>Intervista con l\u2019arcivescovo <strong>Malcolm Ranjith<\/strong> scelto da papa Benedetto XVI come segretario della Congregazione per il culto divino e la disciplina dei sacramenti<\/em><\/p>\n<p style=\"text-align: center;\">intervista di <strong>Gianni Cardinale<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">L\u2019arcivescovo Albert Malcolm Ranjith Patabendige Don, 59 anni da compiere a met\u00e0 novembre, originario dello Sri Lanka, \u00e8 stato nominato segretario della Congregazione per il culto divino e la disciplina dei sacramenti il 10 dicembre dello scorso anno. Benedetto XVI lo ha richiamato in Curia per quella che \u00e8 stata la seconda nomina di rilievo del suo pontificato, dopo quella di William Joseph Levada a prefetto della Congregazione per la dottrina della fede. Insieme al neoinsediato cardinale segretario di Stato Tarcisio Bertone, monsignor Ranjith fa parte quindi della cerchia degli stretti collaboratori della Curia romana, personalmente scelta da papa Ratzinger.\u00a0 <em>30Giorni <\/em>gli ha chiesto di approfondire alcuni aspetti della sua biografia.<\/div>\n<p style=\"text-align: justify;\"><strong>Eccellenza, come \u00e8 nata la sua vocazione? <\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Albert Malcolm Ranjith Patabendige Don: <\/strong>Sono nato in una famiglia di buoni cattolici. La nostra era una parrocchia in cui si viveva con gioia la sana e buona tradizione della Chiesa, dove la messa quotidiana era una pratica diffusa tra molti semplici fedeli. Era retta da un bravo missionario francese, un oblato di Maria immacolata, padre Jean Habestroh, che ha dato tutto per Ges\u00f9 e per la Sua Chiesa. Un vero modello di dedizione. E cos\u00ec, all\u2019interno di questa intensa vita di fede nella famiglia e nella parrocchia, la chiamata a dedicarmi pienamente al servizio del Signore \u00e8 nata fin da piccolo ed \u00e8 maturata, quando facevo il chierichetto, quasi in modo naturale.<\/p>\n<p style=\"text-align: justify;\"><strong>Dove ha studiato?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith: <\/strong>In una scuola dei Fratelli delle scuole cristiane di La Salle, scuole di ottima qualit\u00e0 e dove la vita devozionale era molto intensa. Ogni giorno recitavamo il Rosario, ed eravamo quasi tutti membri della Legio Mariae. Sono stato fortunato, perch\u00e9 in queste scuole sono cresciuto non solo nelle conoscenze scientifiche e nella formazione culturale, ma anche nella vita spirituale. E i fratelli di La Salle erano guide esemplari.<\/p>\n<p style=\"text-align: justify;\"><strong>Lei ha frequentato il seminario maggiore nazionale di Kandy dal 1966 al 1970\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith: <\/strong>Avevo diciott\u2019anni quando sono entrato. Mio padre in un primo tempo non era molto contento, perch\u00e9 ero il primogenito e unico figlio maschio. Ma poi, grazie soprattutto a mia madre, i miei genitori si sono messi d\u2019accordo nel darmi il permesso di entrare in seminario. Dopo gli studi filosofici e un periodo di tempo passato fuori seminario, il primo e unico cardinale che ha avuto lo Sri Lanka, Thomas Benjamin Cooray, mi ha mandato a Roma, al Collegio di Propaganda Fide, per completare gli studi teologici.<\/p>\n<p style=\"text-align: justify;\"><strong>E a Roma \u00e8 stato ordinato sacerdote.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith: <\/strong>S\u00ec, il 29 giugno 1975. Eravamo pi\u00f9 di 350 diaconi ordinati da Paolo VI in occasione dell\u2019Anno Santo. Successivamente ho frequentato il Pontificio Istituto Biblico dove, dopo quattro anni, ho conseguito la licenza in Sacra Scrittura. Durante questi anni ho avuto la fortuna anche di poter seguire un corso di otto mesi all\u2019Universit\u00e0 ebraica di Gerusalemme, dove dagli insegnanti rabbini ho potuto ricevere un grande senso di amore verso la Parola di Dio. La Terra Santa \u00e8 piena di Dio e del Suo amore verso l\u2019umanit\u00e0, un amore che in quei luoghi si pu\u00f2 quasi toccare con mano. La mia vocazione sacerdotale, quindi si arricchiva di nuove forze spirituali ogni giorno che respiravo quell\u2019aria.<\/p>\n<p style=\"text-align: justify;\"><strong>Chi sono stati i suoi maestri?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith:<\/strong> Ero studente dell\u2019allora padre Carlo Maria Martini, intelligente e capace: ci insegnava il Vangelo di san Luca e la critica testuale. Un mio docente era anche un altro gesuita oggi cardinale, padre Albert Vanhoye. Con lui come relatore, nel 1978 ho scritto la mia tesina per la licenza in Sacra Scrittura sulla Lettera agli ebrei. All\u2019Urbaniana mi \u00e8 rimasta impressa la figura di padre Carlo Molari: presentava la dottrina dogmatica in una chiave diversa, per\u00f2 interessante, che suscitava dibattito e ci apriva gli occhi per gustare il vero valore della teologia. C\u2019erano anche molti altri bravi insegnanti. Mi ricordo di monsignor Stefano Virgulin e del padre comboniano Pietro Chiocchetta: insegnavano non in modo libresco, ma con una fede intensa in Ges\u00f9.<\/p>\n<p style=\"text-align: justify;\"><strong>Finiti gli studi, nel 1978 \u00e8 tornato in patria.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith: <\/strong>Ho fatto il viceparroco in una zona poco sviluppata, in un villaggio di pescatori, tutti cattolici. E l\u00ec ho cominciato a scoprire il collegamento della teologia alla vita quotidiana dei fedeli attraverso il grande veicolo della liturgia. Chi celebra e prega intensamente viene aiutato a mettere in pratica ci\u00f2 che celebra. Poi sono stato parroco sempre in altri villaggi di pescatori. Erano molto poveri ma avevano una grande fede. E proprio attraverso il contatto con queste realt\u00e0 ho scoperto la necessit\u00e0 che la Chiesa si occupi anche della giustizia sociale. Fin da allora l\u2019amore per la liturgia e l\u2019amore per i poveri, due veri e propri tesori della Chiesa, si potrebbe dire, sono stati la bussola della mia vita di sacerdote. Anche se all\u2019epoca non avrei mai pensato di diventare un giorno addirittura segretario della Congregazione per il culto divino\u2026<\/p>\n<p style=\"text-align: justify;\"><strong>Come ha aiutato queste popolazioni?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith:<\/strong> Ho sfruttato le conoscenze che avevo coltivato a Roma e in Germania. Ho chiamato i miei vecchi amici e, grazie a Dio, gli aiuti sono arrivati. \u00c8 grazie anche a questa attivit\u00e0 che, nel 1983, sono diventato direttore nazionale delle Pontificie opere missionarie. Incarico che ho ricoperto per dieci anni. E in questa veste ho partecipato a molti incontri con gli altri direttori delle Pontificie opere missionarie sparse per tutto il mondo. Proprio queste riunioni mi hanno aiutato ad avere una visione veramente cattolica, universale della Chiesa.<\/p>\n<p style=\"text-align: justify;\"><strong>Nel 1991 lei \u00e8 stato nominato vescovo ausiliare di Colombo. Come ha vissuto questa prima esperienza episcopale?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith:<\/strong> Da vescovo ausiliare ho potuto allargare la mia presenza a tutta la diocesi e collaborare cos\u00ec con il mio vescovo ordinario. Ho potuto scoprire inoltre come il popolo cristiano voglia sentire vicino i propri pastori dai quali si attendono una vita che rifletta quella del supremo pastore, Ges\u00f9. Durante questo periodo, su richiesta dell\u2019episcopato, ho coordinato con il governo e la Santa Sede la preparazione del viaggio di papa Giovanni Paolo II nello Sri Lanka avvenuto nel gennaio 1995. \u00c8 stata una grande esperienza anche questa. Era commovente vedere i nostri semplici fedeli che si stringevano attorno al Papa con un grande senso di affetto.<\/p>\n<p style=\"text-align: justify;\"><strong>Era la prima volta che un papa toccava il suolo dello Sri Lanka?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith:<\/strong> No, trent\u2019anni prima, nel dicembre 1970, Paolo VI, di ritorno a Roma dall\u2019Australia, fece una sosta a Colombo, dove celebr\u00f2 una messa nell\u2019aeroporto. All\u2019epoca ero un giovane seminarista e ricordo ancora la gioia con cui i cattolici, ma non solo, si raccolsero attorno alla figura del primo papa che metteva piede nella nostra isola.<\/p>\n<p style=\"text-align: justify;\"><strong>Alla fine del 1995 lei viene chiamato a guidare la nuova diocesi di Ratnapura, dove \u00e8 rimasto fino al 2001.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith:<\/strong> Mi hanno chiesto di occuparmi di una diocesi nuova, appena costituita, situata all\u2019interno del Paese. E ho accettato. Sono stati cinque anni molto felici, nonostante i problemi che sempre ci sono, soprattutto quando si deve costruire un\u2019intera struttura diocesana. Ho imparato a stare vicino al clero \u2013 che a Ratnapura era un po\u2019 diviso al suo interno \u2013 e ai fedeli, la maggioranza dei quali erano e sono molto poveri. Non si trattava pi\u00f9 di pescatori ma di coltivatori delle piantagioni di t\u00e8.<\/p>\n<p style=\"text-align: justify;\"><strong>Quanti erano i cattolici a Ratnapura?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith:<\/strong> Solo il due per cento. Ma col resto della popolazione, nella stragrande maggioranza buddista, i rapporti erano ottimi. Quando sono entrato in diocesi come vescovo, sono andato a visitare tutti i templi buddisti della citt\u00e0 e incontrare i monaci. Dal primo giorno abbiamo creato un organismo di dialogo e di cooperazione in quei campi, come in quello sociale, dove questo \u00e8 possibile. Con alcuni di questi monaci \u00e8 nata un\u2019amicizia molto forte. A loro, a volte, abbiamo chiesto consigli e suggerimenti quando costruivamo nuove chiese.<\/p>\n<p style=\"text-align: justify;\"><strong>Eppure, proprio negli ultimi tempi, nello Sri Lanka si sono discusse delle leggi per impedire la conversione da una religione a un\u2019altra\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith:<\/strong> Si tratta di una questione discussa a livello nazionale e dovuta all\u2019annosa guerra tra la minoranza tamil, perlopi\u00f9 induista, e la maggioranza cingalese, perlopi\u00f9 buddista, e dovuta anche alle attivit\u00e0 poco corrette di alcune sette cristiane fondamentaliste. La maggioranza cingalese-buddista ha paura che le minoranze, quella tamil-induista ma anche le comunit\u00e0 cristiane che si trovano sia tra i tamil che tra i cingalesi, vogliano conquistare una posizione dominante nella societ\u00e0, e allora reagisce e cerca di controllarle, creando talvolta in esse un senso di oppressione. Questo a livello generale. Ma quando ero vescovo a Ratnapura, l\u00ec la situazione era tranquilla anche perch\u00e9 era fuori dalle zone pi\u00f9 calde del conflitto, che sono quelle nordorientali del Paese.<\/p>\n<p style=\"text-align: justify;\"><strong>Nel 2000 viene pubblicata la dichiarazione <em>Dominus Iesus<\/em><em>, <\/em>sull\u2019unicit\u00e0 salvifica di Ges\u00f9. Ha creato dei problemi nel dialogo con il buddismo?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith: <\/strong>A dire il vero, un primo problema era nato nel 1994, quando Giovanni Paolo II pubblic\u00f2 il libro-intervista con Vittorio Messori intitolato Varcare la soglia della speranza, in cui c\u2019erano delle frasi sul buddismo che suscitarono reazioni. Ma quelli che diedero ampia diffusione a queste affermazioni erano stranieri provenienti dall\u2019estero. Furono loro a dare grande risalto sui giornali dello Sri Lanka alla notizia che il Papa in questo libro aveva attaccato il buddismo. Erano articoli che infiammavano le tensioni, anche se molti non avevano neanche letto il libro del Papa. Ma un monaco buddista, che io conoscevo, scrisse sul principale giornale di lingua inglese dello Sri Lanka, il Daily News, un articolo in cui difendeva il Santo Padre.<\/p>\n<p style=\"text-align: justify;\">Questo monaco scrisse che, secondo le indicazioni di Buddha, tutti gli insegnamenti andavano sottoposti a critica, anche i suoi. E quindi il Papa aveva tutto il diritto di dire quello che secondo lui era negativo della religione buddista. Paradossalmente furono pi\u00f9 alcuni teologi cattolici a criticare il Papa che non gli stessi buddisti. Pi\u00f9 o meno lo stesso \u00e8 avvenuto con la Dominus Iesus: gli attacchi maggiori sono venuti dai teologi cattolici e non tanto dagli altri. Spesso in queste cose ci si lascia guidare dalle proprie emozioni pi\u00f9 che da un\u2019analisi dei fatti. E cos\u00ec si creano delle situazioni antipatiche e inutili.<\/p>\n<p style=\"text-align: justify;\"><strong>Comunque durante la visita di Giovanni Paolo II in Sri Lanka del gennaio 1995 i leader buddisti non parteciparono all\u2019incontro col Papa\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith:<\/strong> I leader no, ma moltissimi fedeli buddisti vi parteciparono con gioia. Devo specificare che l\u2019altare principale sul quale il Papa celebr\u00f2 la santa messa, nella spianata di Galle Face, era stato disegnato e costruito da un monaco buddista, nostro amico, che cos\u00ec rifiut\u00f2 di essere strumentalizzato dagli altri.<\/p>\n<p style=\"text-align: justify;\"><strong>Torniamo all\u2019attualit\u00e0. Come valuta il tentativo di introdurre leggi anticonversione nel suo Paese?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith:<\/strong> Innanzitutto noi cristiani diciamo chiaramente alla maggioranza buddista che non \u00e8 nostro desiderio sovvertire le tradizioni religiose e culturali in cui si riconosce la maggioranza del popolo dello Sri Lanka. E poi, anche se una legge di questo tipo verr\u00e0 approvata, le conseguenze potranno non essere tutte negative. Vorr\u00e0 dire che il Signore vuole mettere alla prova la nostra fede e con il Suo aiuto non dubito che la fede del nostro popolo cristiano si rafforzer\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>Il 1\u00b0 ottobre 2001 viene pubblicata la sua nomina a segretario aggiunto di Propaganda Fide. Come ricorda questa chiamata a Roma?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith:<\/strong> Nel 1995, oltre che vescovo di Ratnapura ero diventato anche segretario generale della Conferenza episcopale e presidente della Commissione episcopale per la giustizia e la pace. Insieme al vicepresidente di questa Commissione, il vescovo di Mannar Joseph Rayappu, di etnia tamil, ho lavorato molto per portare il governo di Colombo e le Tigri tamil al tavolo dei negoziati che hanno condotto al cessate il fuoco, infranto, ahim\u00e9, proprio questa estate. Ricordo che con monsignor Rayappu riuscimmo a portare 26 monaci buddisti nella zona controllata dai tamil per cercare di rompere l\u2019ostilit\u00e0 che animava sia i buddisti che i tamil l\u2019uno verso l\u2019altro a causa delle atrocit\u00e0 commesse da entrambi nel passato.<\/p>\n<p style=\"text-align: justify;\">L\u2019incontro tra i due gruppi fu un\u2019esperienza molto felice. Proprio quando ero molto impegnato in queste iniziative di pace, mi chiam\u00f2 il nunzio apostolico che mi annunciava la decisione del Papa di nominarmi segretario aggiunto a Propaganda Fide e chiedeva se aderivo a questa richiesta. Di fronte al desiderio del Papa ho detto s\u00ec. Cos\u00ec sono arrivato a Roma per svolgere la mia missione nella Congregazione posta sotto la guida del cardinale Crescenzio Sepe.<\/p>\n<p style=\"text-align: justify;\"><strong>Dove \u00e8 rimasto per circa due anni.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith: <\/strong>\u00c8 stato un periodo molto interessante. Per me si \u00e8 trattato un po\u2019 come di una continuazione del lavoro che avevo gi\u00e0 svolto in qualit\u00e0 di direttore delle Pontificie opere missionarie in Sri Lanka. Quasi due anni in cui ho cercato di essere il pi\u00f9 possibile autentico, leale e sincero nel mio lavoro. Ho tentato di valorizzare al massimo il ruolo dei direttori nazionali delle Pontificie opere missionarie nelle varie Chiese locali, e di salvaguardare la trasparenza assoluta in tutte le delicate questioni finanziarie che riguardano queste opere.<\/p>\n<p style=\"text-align: justify;\"><strong>Il 29 aprile 2004 viene resa nota la sua nomina a nunzio apostolico in Indonesia e Timor Est.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith:<\/strong> Dopo un periodo di riflessione mi \u00e8 stato chiesto di diventare nunzio apostolico. Ho accettato con grande interesse. Anche se si trattava per me di un\u2019esperienza nuova, in un campo che per me era ancora misterioso. Da vescovo avevo collaborato con la nunziatura di Colombo, ma non avevo avuto la formazione speciale che hanno i nunzi. Direi che \u00e8 stata un\u2019esperienza molto ricca e ho cercato di essere vicino a quella Chiesa e ai suoi pastori e manifestare cos\u00ec la vicinanza del Santo Padre a loro.<\/p>\n<p style=\"text-align: justify;\"><strong>Proprio durante la sua permanenza a Jakarta c\u2019\u00e8 stato il terribile tsunami che ha sconvolto il Sud Est asiatico. Come ha vissuto quella esperienza?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith: <\/strong>In quei giorni si trovava da me un mio carissimo amico, l\u2019arcivescovo di Vienna il cardinale Christoph Sch\u00f6nborn. Appresa la tragedia, abbiamo abbandonato il programma che avevamo gi\u00e0 stabilito per lui e siamo andati a Banda Aceh. \u00c8 stato un viaggio estremamente difficoltoso, ma siamo riusciti ad arrivare e a visitare le zone colpite. \u00c8 stato uno spettacolo terribile: morte e distruzione dappertutto. Abbiamo trascorso due giorni da missionari, abbiamo dormito in alloggi di fortuna senza acqua corrente e senza luce. Ma siamo stati contenti di poter essere vicini alla piccola comunit\u00e0 cattolica di Banda Aceh e anche dell\u2019isola di Nias.<\/p>\n<p style=\"text-align: justify;\">La voce del cardinale Sch\u00f6nborn che da quella zona raccontava alle radiotelevisioni europee la sua esperienza \u00e8 stata anche determinante nella solidariet\u00e0 che abbiamo ricevuto da ogni parte del mondo. Successivamente attraverso la rete delle Caritas e l\u2019aiuto della Santa Sede siamo riusciti a stabilire un programma di aiuti solido per quelle popolazioni. La Caritas indonesiana era inattiva e cos\u00ec con l\u2019aiuto del cardinale arcivescovo di Jakarta e della Caritas internationalis siamo riusciti a riattivare questo organismo ecclesiale e a stabilire progetti di aiuto per la ricostruzione di quelle zone. Ricordo che abbiamo partecipato a riunioni interminabili ma importanti grazie alle quali abbiamo potuto dare il nostro contributo come Chiesa cattolica per le popolazioni colpite da questa immane tragedia.<\/p>\n<p style=\"text-align: justify;\"><strong>Poco prima della sua nomina a nunzio, L\u2019Osservatore Romano del 26-27 aprile 2004 ospit\u00f2 un suo articolo di commento alla istruzione Redemptionis Sacramentum \u00absu alcune cose che si devono osservare ed evitare circa la Santissima Eucaristia\u00bb, pubblicata poco tempo prima a cura della Congregazione per il culto divino d\u2019intesa con la Congregazione per la dottrina della fede\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith:<\/strong> L\u2019articolo lo scrissi su richiesta del prefetto della Congregazione per il culto divino, il cardinale Francis Arinze. Avevo trovato la Redemptionis Sacramentum assai utile e necessaria, e perci\u00f2 sono stato ben contento di commentarla.<\/p>\n<p style=\"text-align: justify;\"><strong>Fu un articolo per cos\u00ec dire profetico, visto l\u2019incarico da lei oggi ricoperto\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith: <\/strong>Non lo so. Per\u00f2 come ho gi\u00e0 detto, mi sono sempre interessato della liturgia soprattutto nei suoi risvolti pastorali, e ho sempre cercato di leggere e documentarmi su questi aspetti. E ricordo che quando mi capitava di incontrare l\u2019allora cardinale Ratzinger, spesso nei nostri colloqui si finiva per parlare di liturgia.<\/p>\n<p style=\"text-align: justify;\"><strong>Come ha conosciuto il cardinale Joseph Ratzinger?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith:<\/strong> Per una questione riguardante lo Sri Lanka, quella del teologo Tissa Balasuriya, il quale aveva scritto un libro, Mary and human liberation, in cui veniva fatta un\u2019analisi teologica difficilmente compatibile con la dottrina cattolica. Allora ero un giovane vescovo appena nominato, mi sono interessato a questo libro e ho coordinato una commissione episcopale appositamente creata per studiare questo testo. Nel 1994, alla fine dei lavori di questa commissione, la Conferenza episcopale emise un comunicato in cui si avvisavano i fedeli che il libro non rispecchiava la dottrina della Chiesa.<\/p>\n<p style=\"text-align: justify;\">Questo comunicato scaten\u00f2 una campagna stampa mondiale contro di noi e in favore di padre Balasuriya. La controversia fu talmente forte che anche Roma cominci\u00f2 a indagare. E cos\u00ec venni richiamato nell\u2019Urbe per spiegare quello che stava succedendo al Papa e al prefetto della Congregazione per la dottrina della fede, il cardinale Ratzinger. Le affermazioni di padre Balasuriya erano talmente gravi che nel gennaio 1997 vennero formalmente condannate dalla Congregazione e lui stesso, non avendole ritirate, venne colpito dalla scomunica latae sententiae. Scomunica che rientr\u00f2 l\u2019anno successivo, dopo una solenne dichiarazione pubblica dello stesso padre Balasuriya.<\/p>\n<p style=\"text-align: justify;\"><strong>Fu quindi in questo contesto che cominci\u00f2 la sua frequentazione con il cardinale Ratzinger\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith: <\/strong>S\u00ec, l\u2019ho incontrato diverse volte e in quelle occasioni avevo modo di illustrare a lui le mie impressioni e le mie preoccupazioni di vescovo specialmente riguardo alla questione del dialogo interreligioso e anche alle questioni liturgiche. Quando poi sono stato chiamato a Propaganda Fide, ho avuto modo di incontrare il cardinale Ratzinger pi\u00f9 di frequente, anche durante le ordinarie del dicastero di cui anche lui faceva parte. Cos\u00ec, oltre a essere un avido lettore dei suoi libri, ho imparato ad apprezzarne personalmente anche le sue doti umane. In lui ho visto sempre un grande teologo e nelle sue parole non un pedante, ma essenzialmente una persona vicina al Signore.<\/p>\n<p style=\"text-align: justify;\"><strong>A Jakarta quindi \u00e8 stato poco meno di due anni. Il 10 dicembre 2005 \u00e8 stata pubblicata la nomina a segretario del Culto divino. Si aspettava questa nuova chiamata a Roma?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith:<\/strong> Ricordo che Benedetto XVI mi chiam\u00f2 in udienza a Castel Gandolfo durante l\u2019estate del 2005, era met\u00e0 settembre, e mi chiese se volevo accettare la nomina a segretario della Congregazione per il culto divino. Ho detto di s\u00ec. Ho sempre avuto un interesse per la liturgia, che ho sempre considerato la chiave del rapporto tra fede e vita, perch\u00e9 come viene celebrata la liturgia cos\u00ec viene vissuta la fede cristiana. La liturgia da un lato esteriorizza la fede, dall\u2019altro la alimenta. Poter dare su questo punto, che sta molto a cuore a papa Benedetto, il mio pur modesto contributo mi ha riempito il cuore di gioia.<\/p>\n<p style=\"text-align: justify;\"><strong>Eccellenza, la sua prima uscita pubblica da segretario della Congregazione per il culto divino \u00e8 stata una conferenza tenuta in occasione della presentazione del libro di Uwe Michael Lang, oratoriano di origini tedesche residente a Londra, Rivolti al Signore. L\u2019orientamento nella preghiera liturgica (Cantagalli, Siena 2006, pp. 150, euro 14,90), avvenuta il 27 aprile presso l\u2019Istituto patristico Augustinianum di Roma. Il volume, edito in tedesco nel 2003, contiene una prefazione dell\u2019allora cardinale Joseph Ratzinger, pubblicata per la prima volta in italiano sul numero di marzo 2004 di 30Giorni. Cosa l\u2019ha colpita di pi\u00f9 di questo libro?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith:<\/strong> Avevo gi\u00e0 letto questo libro e la bellissima prefazione dell\u2019allora cardinale Ratzinger. Cos\u00ec quando ho ricevuto l\u2019invito, ho subito accettato. Perch\u00e9 \u00e8 stata l\u2019occasione per far nascere un dibattito molto positivo nella Chiesa. Si parla tanto di partecipazione dei fedeli alla liturgia. Ma i fedeli partecipano di pi\u00f9 se il sacerdote celebra versus populum o se celebra verso l\u2019altare? Non \u00e8 detto infatti che questa partecipazione sia pi\u00f9 attiva se il prete celebra verso il popolo; pu\u00f2 darsi che in questo caso il popolo si distragga.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec \u00e8 vera partecipazione quando al segno della pace in chiesa si crea una grande confusione, con dei sacerdoti che a volte vanno a dare il loro saluto fino alle ultime file? Si tratta della actuosa participatio, auspicata dal Concilio Vaticano II, o semplicemente di una grande distrazione che non aiuta per nulla a seguire con devozione il momento successivo della messa \u2013 a parte il fatto che a volte ci si dimentica pure di declamare l\u2019Agnus Dei\u2026 Ripeto, il libro di padre Lang \u00e8 stato ed \u00e8 un\u2019utilissima provocazione, a cominciare dall\u2019introduzione in cui il cardinale Ratzinger ricorda che il Concilio non ha mai chiesto di abolire il latino n\u00e9 di rivoluzionare la direzione della preghiera liturgica\u2026<\/p>\n<p style=\"text-align: justify;\"><strong>Una sua intervista alla Croix del 26 giugno, intitolata La riforma liturgica del Vaticano II non \u00e8 mai decollata, ha fatto molto rumore. Pu\u00f2 spiegare meglio i suoi giudizi sulla riforma liturgica attuata dopo il Concilio Vaticano II?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith:<\/strong> Queste parole sono state messe fuori contesto. Non \u00e8 che valuti negativamente tutto quello che \u00e8 avvenuto dopo il Concilio. Ho detto invece che il risultato atteso dalla riforma liturgica non si \u00e8 manifestato. Ci si domanda se la vita liturgica, la partecipazione dei fedeli alle sacre funzioni, sia pi\u00f9 alta e migliore oggi rispetto a quella presente negli anni Cinquanta. Si \u00e8 criticato il fatto che prima del Concilio i fedeli non partecipavano veramente alla messa, ma assistevano passivamente o facevano delle devozioni personali. Ma oggi davvero i fedeli partecipano in modo spiritualmente pi\u00f9 elevato e personale? \u00c8 davvero successo che tanti che erano fuori della Chiesa con le nuove liturgie si siano messi in fila per entrare nelle nostre chiese? O non \u00e8 successo invece che molti se ne sono andati via e che le chiese si sono svuotate? Di quale riforma allora si parla?<\/p>\n<p style=\"text-align: justify;\"><strong>Colpa della secolarizzazione\u2026<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith:<\/strong> Certamente, ma tale situazione \u00e8 anche frutto del modo con cui \u00e8 stata trattata o, meglio, bistrattata la liturgia\u2026 In pratica, secondo me, le sacrosante aspettative del Concilio di una liturgia meglio compresa e quindi spiritualmente pi\u00f9 feconda, sono state ancora disattese. E quindi c\u2019\u00e8 ancora molto da fare, affinch\u00e9 le chiese si riempiano di nuovi fedeli che durante le sacre liturgie si sentano veramente toccati dalla grazia del Signore. In un mondo secolarizzato, invece di cercare di elevare i cuori verso la grandezza del Signore, si \u00e8 cercato, piuttosto, credo, di abbassare i misteri divini a un livello banale.<\/p>\n<p style=\"text-align: justify;\"><strong>Quando \u00e8 stato nominato segretario al Culto divino, \u00e8 stato scritto che lei avrebbe ottimi rapporti col mondo lefebvriano. Corrisponde al vero?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith: <\/strong>Non ho conosciuto monsignor Marcel Lefebvre per motivi anagrafici, perch\u00e9 lui \u00e8 di un\u2019altra epoca. Ma certamente ho avuto qualche contatto con alcuni dei suoi seguaci. Ma non sono un appassionato dei lefebvriani. Sfortunatamente non sono ancora rientrati nella piena comunione con la Santa Sede, ma quello che loro qualche volta dicono sulla liturgia lo dicono a ragion veduta. E perci\u00f2 loro sono un pungolo che ci deve far riflettere su quello che stiamo facendo. Questo non vuol dire che posso essere definito come un aderente o un amico dei lefebvriani. Io condivido alcuni punti dei cosiddetti no global riguardo alla giustizia sociale, ma questo non vuol dire che sono un loro aderente\u2026 D\u2019altra parte la messa tridentina non \u00e8 propriet\u00e0 privata dei lefebvriani. Essa \u00e8 un tesoro della Chiesa e di noi tutti. Come il Papa ha detto alla Curia Romana l\u2019anno scorso, il Concilio Vaticano II non \u00e8 un momento di rottura, ma di rinnovamento nella continuit\u00e0. Non si butta via il passato, ma si cresce su di esso.<\/p>\n<p style=\"text-align: justify;\"><strong>Questo vuol dire che la messa cosiddetta di san Pio V in realt\u00e0 non \u00e8 stata mai abolita?<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Ranjith:<\/strong> Il fatto che la Santa Sede abbia recentemente approvato l\u2019istituzione, a Bordeaux, di una societ\u00e0 di vita apostolica di diritto pontificio caratterizzata dal fatto di usare esclusivamente i libri liturgici preconciliari [si tratta dell\u2019Istituto del Buon Pastore in cui si sono raccolti alcuni fuoriusciti \u201clefebvriani\u201d, ndr], sta a significare in modo inequivocabile che la messa di san Pio V non pu\u00f2 essere considerata come abolita dal nuovo messale cosiddetto di Paolo VI.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>30 Giorni n.9 settembre 2006 Intervista con l\u2019arcivescovo Malcolm Ranjith scelto da papa Benedetto XVI come segretario della Congregazione per il culto divino e la disciplina dei sacramenti intervista di Gianni Cardinale<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/liturgia-e-poveri-tesori-della-chiesa\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":16770,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,115,18],"tags":[1379],"class_list":["post-2299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-liturgia","category-personaggi","tag-card-malcom-ranjith","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&laquo;Liturgia e poveri, tesori della Chiesa&raquo; - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/liturgia-e-poveri-tesori-della-chiesa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&laquo;Liturgia e poveri, tesori della Chiesa&raquo; - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/liturgia-e-poveri-tesori-della-chiesa\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2006-11-01T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-01-14T09:49:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/Malcom-Ranjith.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"176\" \/>\n\t<meta property=\"og:image:height\" content=\"264\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/liturgia-e-poveri-tesori-della-chiesa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/liturgia-e-poveri-tesori-della-chiesa\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"&laquo;Liturgia e poveri, tesori della Chiesa&raquo;\",\"datePublished\":\"2006-11-01T23:00:00+00:00\",\"dateModified\":\"2015-01-14T09:49:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/liturgia-e-poveri-tesori-della-chiesa\\\/\"},\"wordCount\":3987,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/liturgia-e-poveri-tesori-della-chiesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/11\\\/Malcom-Ranjith.jpg\",\"keywords\":[\"card. Malcom Ranjith\"],\"articleSection\":[\"Chiesa\",\"Liturgia\",\"Personaggi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/liturgia-e-poveri-tesori-della-chiesa\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/liturgia-e-poveri-tesori-della-chiesa\\\/\",\"name\":\"&laquo;Liturgia e poveri, tesori della Chiesa&raquo; - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/liturgia-e-poveri-tesori-della-chiesa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/liturgia-e-poveri-tesori-della-chiesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/11\\\/Malcom-Ranjith.jpg\",\"datePublished\":\"2006-11-01T23:00:00+00:00\",\"dateModified\":\"2015-01-14T09:49:09+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/liturgia-e-poveri-tesori-della-chiesa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/liturgia-e-poveri-tesori-della-chiesa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/liturgia-e-poveri-tesori-della-chiesa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/11\\\/Malcom-Ranjith.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/11\\\/Malcom-Ranjith.jpg\",\"width\":176,\"height\":264},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/liturgia-e-poveri-tesori-della-chiesa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&laquo;Liturgia e poveri, tesori della Chiesa&raquo;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"&laquo;Liturgia e poveri, tesori della Chiesa&raquo; - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/liturgia-e-poveri-tesori-della-chiesa\/","og_locale":"it_IT","og_type":"article","og_title":"&laquo;Liturgia e poveri, tesori della Chiesa&raquo; - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/liturgia-e-poveri-tesori-della-chiesa\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2006-11-01T23:00:00+00:00","article_modified_time":"2015-01-14T09:49:09+00:00","og_image":[{"width":176,"height":264,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/Malcom-Ranjith.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"20 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/liturgia-e-poveri-tesori-della-chiesa\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/liturgia-e-poveri-tesori-della-chiesa\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"&laquo;Liturgia e poveri, tesori della Chiesa&raquo;","datePublished":"2006-11-01T23:00:00+00:00","dateModified":"2015-01-14T09:49:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/liturgia-e-poveri-tesori-della-chiesa\/"},"wordCount":3987,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/liturgia-e-poveri-tesori-della-chiesa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/Malcom-Ranjith.jpg","keywords":["card. Malcom Ranjith"],"articleSection":["Chiesa","Liturgia","Personaggi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/liturgia-e-poveri-tesori-della-chiesa\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/liturgia-e-poveri-tesori-della-chiesa\/","name":"&laquo;Liturgia e poveri, tesori della Chiesa&raquo; - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/liturgia-e-poveri-tesori-della-chiesa\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/liturgia-e-poveri-tesori-della-chiesa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/Malcom-Ranjith.jpg","datePublished":"2006-11-01T23:00:00+00:00","dateModified":"2015-01-14T09:49:09+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/liturgia-e-poveri-tesori-della-chiesa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/liturgia-e-poveri-tesori-della-chiesa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/liturgia-e-poveri-tesori-della-chiesa\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/Malcom-Ranjith.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/11\/Malcom-Ranjith.jpg","width":176,"height":264},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/liturgia-e-poveri-tesori-della-chiesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"&laquo;Liturgia e poveri, tesori della Chiesa&raquo;"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2299"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2299\/revisions"}],"predecessor-version":[{"id":16771,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2299\/revisions\/16771"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/16770"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}