{"id":2279,"date":"2006-10-18T12:32:38","date_gmt":"2006-10-18T10:32:38","guid":{"rendered":""},"modified":"2016-07-05T10:11:06","modified_gmt":"2016-07-05T08:11:06","slug":"perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\/","title":{"rendered":"Perch&eacute; non si pu&ograve; non dirsi cristiani anche senza esserlo."},"content":{"rendered":"<div style=\"text-align: center;\">\n<div id=\"attachment_35641\" style=\"width: 200px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-35641\" class=\"wp-image-35641\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Tettamanzi.jpg\" alt=\"Tettamanzi\" width=\"200\" height=\"200\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Tettamanzi.jpg 225w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Tettamanzi-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><p id=\"caption-attachment-35641\" class=\"wp-caption-text\">Card. Dionigi Tettamanzi<\/p><\/div>\n<p><strong>Il Foglio<\/strong>, mercoled\u00ec 18 ottobre 2006<\/div>\n<p style=\"text-align: center;\">Lettera di un ateo devoto a S.E.R. Dionigi cardinale Tettamanzi.<\/p>\n<p style=\"text-align: justify;\"><strong>Perch\u00e9 non si pu\u00f2 non dirsi cristiani anche senza esserlo.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Misera l\u2019alternativa tra un cristianesimo muto e uno impostore<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Eminenza reverendissima, Dionigi cardinale Tettamanzi, arcivescovo di Milano, da molto tempo una parte della chiesa impegna le proprie energie a polemizzare, ammonire, mettere in guardia i fedeli da un pericolo: ci sono dei laici, si dice, e perfino degli atei, che invece di convertirsi e condurre una vita cristiana nelle parrocchie, svolgendo la funzione propria del laicato cattolico secondo gli insegnamenti del Concilio Vaticano II e nel quadro della dottrina sociale della chiesa, tirano in ballo Dio e abusano del nome di Cristo Ges\u00f9 per scopi poco chiari, presumibilmente politici nel senso pi\u00f9 deteriore e partigiano del termine, contraddicendo ogni ottimismo, ogni speranza, ogni senso della differenza cristiana che \u00e8 fatta di spirito di accoglienza, di fraterno dialogo tra le religioni, di amore e di pace fra tutti gli uomini di buona volont\u00e0. Nella sua prolusione a Verona, Ella ha \u00a0riassunto questo monito nell\u2019affermazione, paurosamente tautologica e dunque vuota di senso nonostante la santa attribuzione antiochena, che \u00e8 \u201cmeglio essere cristiani senza dirlo che proclamarsi cristiani senza esserlo\u201d.<\/div>\n<p style=\"text-align: justify;\">Se l\u2019alternativa fosse tra un cristianesimo muto e un cristianesimo impostore, lei avrebbe ragione nello scegliere l\u2019umilt\u00e0 privata della vita cristiana che perde la parola e rifiuta la cultura, ma il Suo encomiabile ottimismo antropologico, la Sua convinzione che la dimensione della crisi contemporanea vada superata con atti e iniziative di buona volont\u00e0 nel solco di una dottrina conciliare impermeabile alla storia in cammino, e a volte anche in corsa con la perdita di senso, si darebbe la classica zappa sui piedi. Ci sarebbe poco da stare allegri.<\/p>\n<p style=\"text-align: justify;\">Dirsi cristiani senza esserlo, eminenza, \u00e8 la parafrasi di un saggio celebre di un filosofo napoletano del secolo scorso, il laico e liberale Benedetto Croce, che le consiglio di rileggersi. Vedr\u00e0 che l\u00ec non c\u2019\u00e8 impostura, ma una base interessante per il dialogo tra fede e ragione che, senza escludere e anzi per inverare il progetto di carit\u00e0 che \u00e8 il succo del cristianesimo, \u00e8 oggetto della cura premurosa e appassionata di Roma da oltre un quarto di secolo. Un dialogo al quale si sono appellate la \u201cVeritatis splendor\u201d, la \u201cFides et ratio\u201d di Giovanni Paolo II e l\u2019intera opera teologica e pastorale di Joseph Ratzinger e di Benedetto XVI, che come Ella sa bene sono la stessa persona.<\/p>\n<p style=\"text-align: justify;\">Anche il presidente della Conferenza episcopale italiana, il cardinal Ruini, ha manifestato un sereno e distaccato interesse, pi\u00f9 volte, per le convergenze possibili, in materia di ragione laica inclusiva del ruolo pubblico della fede, in materia di criteri etici non negoziabili, con quelle tendenze \u201cculturali\u201d che nel mondo occidentale e particolarmente in America e in Italia (ma la Francia sta prendendo anch\u2019essa lo slancio) si vanno affermando con modalit\u00e0 e a stadi di sviluppo diversi.<\/p>\n<p style=\"text-align: justify;\">Se il Suo discorso contro l\u2019impostura pseudocristiana riguardasse politici maldestri, come il presidente del Senato nella scorsa legislatura, che hanno invocato l\u2019amicizia degli ecclesiastici, e perfino del Papa, a scudo protettivo per beghe di cortile politico in quel di Lucca, si abbia tutta la nostra comprensione, ma \u00e8 un <em>de minimis<\/em> che ci farebbe soltanto perdere tempo.<\/p>\n<p style=\"text-align: justify;\">Se invece nelle Sue parole si riverberasse una scelta favorevole al cattolicesimo cosiddetto democratico, quello che con un linguaggio durissimo censurava ieri un ex presidente della Repubblica noto per i suoi fervori e furori e malumori di credente e di fedele e di cattolico liberale ribelle, allora si tratterebbe di una scelta politico ecclesiastica legittima in favore del partito dei cattolici adulti, ed \u00e8 inutile mascherarla da protezione della genuinit\u00e0 della fede contro le intromissioni della politica. In ogni caso, per quanto conti, noi nel nostro piccolo non c\u2019entriamo un bel nulla con queste fobie, imposture e mascheramenti.<\/p>\n<p style=\"text-align: justify;\">Noi cosiddetti \u201catei devoti\u201d, cio\u00e8 credenti e non credenti che non possono non dirsi cristiani e si sono autorifilati un nomignolo falso e provocatorio, conduciamo un limpido discorso pubblico, fatto di ascolto e di parola \u00a0modesta ma viva, mai di rassegnazione e di autocensura, il cui scopo non \u00e8 quello di essere legittimati dai preti o legittimare il ruolo pubblico della religione come elemento di un\u2019agenda di bassa cucina politica.<\/p>\n<p style=\"text-align: justify;\">Non facciamo corridoio, non chiediamo udienza, siamo aperti al dialogo o al rigetto polemico nella chiesa e delle chiese neosecolariste e postsecolariste con equivalente serenit\u00e0 e autonomia di spirito. Ci sembr\u00f2 interessante la \u201cDominus Iesus\u201d, e la pubblicammo perch\u00e9 se ne discutesse. Ci sembr\u00f2 importante il Mea culpa giubilare, e ne parlammo liberamente.<\/p>\n<p style=\"text-align: justify;\">Amammo Giovanni Paolo II, e dicemmo il nostro amore che si nutriva di mille ragioni, comprese quelle legate alla libert\u00e0 politica nel mondo e alla riaffermazione non dogmatica, ma corporale e perfino atletica, dell\u2019identit\u00e0 ebraico-cristiana in occidente. Ci stimolano le esperienze del laicato movimentista, quelle di alta pedagogia e modernissime di un don Giussani, ma anche quelle orientalistiche di un Sant\u2019Egidio o i carismi febbricitanti che parlano di un\u2019apostasia dell\u2019Europa da combattere (neocatecumenali).<\/p>\n<p style=\"text-align: justify;\">Ci appassiona l\u2019elaborazione culturale e dottrinale di quello che consideriamo uno dei maggiori pensatori cristiani a cavallo del secolo, Joseph Ratzinger, che abbiamo salutato con un applauso amabile dopo la sua elezione al soglio petrino, di cui eravamo intimamente certi.<\/p>\n<p style=\"text-align: justify;\">Ma ci piace anche discutere con i suoi critici, ammiriamo la cocciutaggine conciliare della scuola di Bologna, l\u2019erudizione in fatto di storia cristiana dei suoi maestri e allievi, spaziamo liberamente e criticamente dove ci porta la testa, se non il cuore. Inoltre, e questo Ella dovrebbe saperlo bene, vista la Sua formazione di bioeticista cattolico, abbiamo a cuore la battaglia non contro la legge sull\u2019aborto, ma contro la banalizzazione culturale dell\u2019aborto, la sua trasformazione in diritto liberale, e contro una concezione creatrice, nel senso tecno-scientista del termine, anzich\u00e9 creaturale dell\u2019esistenza umana contemporanea.<\/p>\n<p style=\"text-align: justify;\">Abbiamo poi, e mal ce ne incolse per via degli interessati travisamenti politici conseguenti, difeso il diritto di un cattolico a fare il commissario europeo con le sue idee, una volta stabilito il confine tra morale e legge nell\u2019esercizio delle sue funzioni pubbliche.<\/p>\n<p style=\"text-align: justify;\">E abbiamo avviato con un po\u2019 d\u2019anticipo polemiche sapide sullo zapaterismo, sul mondo incantato e perduto di un poeta come Almod\u00f3var, quel cervantino senza Cervantes che ha dato il suggello estetico necessario al progetto di scristianizzazione totale della famiglia e del matrimonio, fino alla derubricazione zapaterista dei nomi di moglie, marito, padre e madre, sostituiti da coniuge A e B e progenitore A o progenitore B.<\/p>\n<p style=\"text-align: justify;\">Infine, non ci piace la torsione dello spirito pubblico europeo in direzione della Mecca, non perch\u00e9 siamo insensibili al fascino spirituale dell\u2019islam o banalmente impauriti dallo straniero, ma perch\u00e9 pensiamo che integrazione e composizione degli scontri in atto tra faglie di civilt\u00e0 debbano realizzarsi, per cos\u00ec dire, senza vincitori n\u00e9 vinti. E se proprio un vincitore avesse da esserci, vincitrice ha da essere quella civilt\u00e0 che incorpora, secondo la lezione di Regensburg, ebraismo, grecit\u00e0 e cristianesimo in un concetto di persona e di diritto compatibile con una societ\u00e0 aperta.<\/p>\n<p style=\"text-align: justify;\">Con osservanza, e nella speranza che il Suo alto monito, sincero nelle intenzioni e nelle paure, sia accolto criticamente, come occasione di riflessione, dai laici e sacerdoti riuniti in Verona.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Foglio, mercoled\u00ec 18 ottobre 2006 Lettera di un ateo devoto a S.E.R. Dionigi cardinale Tettamanzi. Perch\u00e9 non si pu\u00f2 non dirsi cristiani anche senza esserlo. Misera l\u2019alternativa tra un cristianesimo muto e uno impostore<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":35641,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[1373],"class_list":["post-2279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","tag-laici","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Perch&eacute; non si pu&ograve; non dirsi cristiani anche senza esserlo. - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perch&eacute; non si pu&ograve; non dirsi cristiani anche senza esserlo. - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2006-10-18T10:32:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-05T08:11:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Tettamanzi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"225\" \/>\n\t<meta property=\"og:image:height\" content=\"225\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Perch&eacute; non si pu&ograve; non dirsi cristiani anche senza esserlo.\",\"datePublished\":\"2006-10-18T10:32:38+00:00\",\"dateModified\":\"2016-07-05T08:11:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\\\/\"},\"wordCount\":1233,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/10\\\/Tettamanzi.jpg\",\"keywords\":[\"Laici\"],\"articleSection\":[\"Chiesa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\\\/\",\"name\":\"Perch&eacute; non si pu&ograve; non dirsi cristiani anche senza esserlo. - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/10\\\/Tettamanzi.jpg\",\"datePublished\":\"2006-10-18T10:32:38+00:00\",\"dateModified\":\"2016-07-05T08:11:06+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/10\\\/Tettamanzi.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/10\\\/Tettamanzi.jpg\",\"width\":225,\"height\":225},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perch&eacute; non si pu&ograve; non dirsi cristiani anche senza esserlo.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perch&eacute; non si pu&ograve; non dirsi cristiani anche senza esserlo. - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\/","og_locale":"it_IT","og_type":"article","og_title":"Perch&eacute; non si pu&ograve; non dirsi cristiani anche senza esserlo. - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2006-10-18T10:32:38+00:00","article_modified_time":"2016-07-05T08:11:06+00:00","og_image":[{"width":225,"height":225,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Tettamanzi.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Perch&eacute; non si pu&ograve; non dirsi cristiani anche senza esserlo.","datePublished":"2006-10-18T10:32:38+00:00","dateModified":"2016-07-05T08:11:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\/"},"wordCount":1233,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Tettamanzi.jpg","keywords":["Laici"],"articleSection":["Chiesa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\/","name":"Perch&eacute; non si pu&ograve; non dirsi cristiani anche senza esserlo. - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Tettamanzi.jpg","datePublished":"2006-10-18T10:32:38+00:00","dateModified":"2016-07-05T08:11:06+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Tettamanzi.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Tettamanzi.jpg","width":225,"height":225},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/perch-non-si-pu-non-dirsi-cristiani-anche-senza-esserlo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Perch&eacute; non si pu&ograve; non dirsi cristiani anche senza esserlo."}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2279"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2279\/revisions"}],"predecessor-version":[{"id":35642,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2279\/revisions\/35642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/35641"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}