{"id":2275,"date":"2006-10-14T00:00:00","date_gmt":"2006-10-13T22:00:00","guid":{"rendered":""},"modified":"2015-01-13T09:04:15","modified_gmt":"2015-01-13T08:04:15","slug":"un-voto-sbagliato","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-voto-sbagliato\/","title":{"rendered":"Un voto sbagliato"},"content":{"rendered":"<div style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/urna-elett.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-16657\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/urna-elett.jpg\" alt=\"urna elett\" width=\"250\" height=\"169\" \/><\/a>da <strong>il Timone<\/strong> n. 53, maggio 2006<\/div>\n<p style=\"text-align: justify;\"><em>C\u2019\u00e8 un errore dottrinale nel cattolicesimo che boccia un politico perch\u00e9 ne conosce le miserie personali. Ci\u00f2 che conta sono le leggi e\u00a0il loro influsso sui costumi della societ\u00e0. Ecco alcuni falsi criteri assolutamente da evitare<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Mario Palmaro<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">I cattolici sanno per chi votare? La domanda, Un po\u2019 brutale, ritorna pi\u00f9 insistente all\u2019indomani delle elezioni politiche 2006. Anche questa volta, infatti, \u00e8 apparso chiaro che fra quanti si dichiarano cattolici \u2014 praticanti o meno \u2014 esistono divergenze clamorose quando si tratta di tradurre le proprie convinzioni in una scelta di voto.<\/div>\n<p style=\"text-align: justify;\">Intendiamoci: esiste un legittimo \u201cpluralismo\u201d politico che orienta una persona, tanto per intenderci, pi\u00f9 a sinistra o pi\u00f9 a destra. Questa diversit\u00e0 \u00e9 di per se lecita. Ma diventa scandalosa quando essa ignora \u2014 colpevolmente o dolosamente \u2014 alcuni nodi morali che rendono oggettivamente sbagliata una certa opzione. In altre parole: dalla fede in Cristo non discende immediatamente la collocazione politica di un uomo: ci mancherebbe altro.<\/p>\n<p style=\"text-align: justify;\">Ma ci\u00f2 che invece \u00e8 assolutamente inaccettabile \u00e8 il fatto che si proceda al voto, ci si \u201cschieri\u201d politicamente parlando, senza aver utilizzato quei criteri che sono indispensabili per operare secondo verit\u00e0 e retta coscienza. Se un muratore deve costruire una casa, \u00e8 libero di usare la sua arte senza limitazioni ingiustificate. Ma per tirare su un muro che sia diritto, deve usare quello strumento che chiamiamo livella, o \u201cbolla\u201d: se decide di fame a meno, il muro sar\u00e0 irrimediabilmente storto.<\/p>\n<p style=\"text-align: justify;\">La Chiesa ha messo in mano agli elettori un metro di giudizio molto chiaro, lasciando a ognuno il compito di usarlo. Il Papa e i vescovi hanno stilato una stringente gerarchia dei valori, nella quale essere contro l\u2019aborto o essere contro ii buco d\u2019ozono non ha lo stesso peso. A questo punto, osservando la condotta dei partiti negli ultimi cinque anni e cercando di decifrare i loro programmi, sarebbe stato piuttosto semplice desumere il da farsi.<\/p>\n<p style=\"text-align: justify;\">Invece \u2014 per una serie di ragioni che sono un misto di ignoranza, buona fede, cattivi consigli di alcuni parroci, orgoglio, malafede, superficialit\u00e0, mancanza di amore per la Chiesa e i suoi pastori, \u201ccattolicesimo fai da te\u201d, schizofrenia tra fede e principi morali \u2014 \u00e8\u00a0accaduto che fette importanti del mondo cattolico abbiano preferito fare a meno della famosa livella del muratore. Con il risultato che la casa della politica sar\u00e0, inevitabilmente, storta.<\/p>\n<p style=\"text-align: justify;\">Talvolta si pu\u00f2 giungere meglio a vedere la verit\u00e0 a partire dagli errori, come ci ha insegnato quel grande Papa che fu il beato Pio IX. Proviamo allora a indicare i principali \u201cfalsi criteri\u201d che hanno guidato alcuni cattolici in queste elezioni. Sperando che l\u2019errore serva come monito per il futuro.<\/p>\n<p style=\"text-align: justify;\"><strong>La moralit\u00e0 del candidato<\/strong><\/p>\n<p style=\"text-align: justify;\">Non pochi cattolici sinceri e praticanti hanno messo in cima ai criteri di giudizio quello che potremmo chiamare lo \u201cstato di vita\u201d del leader politico. Non sveliamo un segreto se ricordiamo che i quattro protagonisti dell\u2019alleanza di centro destra vivono situazioni familiari irregolari, mentre il capo del centro sinistra \u00e8 felicemente sposato con la stessa donna da sempre. Se dicessimo che questo \u00e8 un fatto di poco conto dal punto di vista umano e morale, sbaglieremmo di grosso. Conosciamo bene infatti i danni devastanti che il divorzio provoca ogni giorno nella nostra societ\u00e0.<\/p>\n<p style=\"text-align: justify;\">Ma c\u2019e un errore, oseremmo dire dottrinale, nel cattolicesimo che boccia un politico perch\u00e9 ne conosce le miserie personali: l\u2019errore che confonde il piano del peccato \u2014 di cui ognuno risponder\u00e0 a suo tempo al Padre Eterno \u2014 con ii terreno del programmi politici che quella stessa persona vuole (o dice di) voler realizzare. Tanto \u00e8 vero che si assiste a questo ribaltamento: gli uomini politici additati ad esempio perch\u00e8 non hanno divorziato, sono poi favorevoli in linea di principio al divorzio e agiscono in partiti e alleanze che non si sognerebbero mai di mettere in discussione questo \u201cdiritto civile\u201d.<\/p>\n<p style=\"text-align: justify;\">Ora, ci\u00f2 che conta in un politico sono le leggi e le scelte di governo che vorr\u00e0 adottare. Per intenderci: \u00e8 la stessa differenza che passa tra un sacerdote o un Papa peccatore, e la fedelt\u00e0 di questo stesso prete o Papa alla dottrina. Nella storia, ci\u00f2 che ha fatto la grandezza del papato non \u00e8 (sempre) stata la santit\u00e0 dei suoi protagonisti, ma la capacit\u00e0 di ogni successore di Pietro di custodire la retta dottrina.<\/p>\n<p style=\"text-align: justify;\">Un capo di governo non \u00e8 che debba custodire verit\u00e0 di fede, ma ha un ruolo analogico: deve operare per il bene comune, cio\u00e8 per la preservazione (o il recupero, ove il danno sia gi\u00e0 stato consumato) della legge naturale. Per paradosso: un politico divorziato che fosse contrario alla legge sul divorzio, \u00e8 di gran lunga assai preferibile a un bravo marito che per\u00f2 non creda affatto nella indissolubilit\u00e0 del matrimonio. Ricordo sempre il caso esemplare di un politico controverso come Giorgio Almirante: nonostante avesse un tornaconto personale alla legalizzazione del divorzio, guid\u00f2 il suo partito su una linea di ferma opposizione alla legge voluta dal socialista Loris Fortuna per sfasciare il matrimonio indissolubile.<\/p>\n<p style=\"text-align: justify;\">La storia della cristianit\u00e0 ha conosciuto molti re che non brillarono per la loro dirittura morale: ma ci\u00f2 che li ha resi grandi e \u201cprovvidenziali\u201d \u00e8 l\u2019insieme dei loro atti di governo. Dunque, l\u2019elettore non deve chiedersi: chi \u00e8 il candidato pi\u00f9 santo? Anche perch\u00e9 vorrei proprio sapere come pensa di poterlo stabilire. E poi: che cosa me ne faccio di un politico che fa la comunione tutte le mattine, e poi firma una legge che legalizza l\u2019uccisione dei bambini non nati, e non ammette l\u2019errore? Di pi\u00f9: se uno \u00e8 regolarmente sposato, ma \u00e8 favorevole al divorzio, all\u2019aborto, alle unioni gay, in che maniera pu\u00f2 essere proposto come modello di santit\u00e0?<\/p>\n<p style=\"text-align: justify;\"><strong>La simpatia del candidato<\/strong><\/p>\n<p style=\"text-align: justify;\">Che un elettore secolarizzato e superficiale possa scegliere in base alla faccia, ai modi, al linguaggio, al censo del candidato, \u00e8 cosa piuttosto ovvia: quando la politica si fa competizione da bar, \u00e8 normale che ne accetti tutte le regole. Ma \u00e8 invece stupefacente constatare quanti cattolici abbiano affidato il loro voto al volubile elemento della simpatia\/antipatia. Anche qui fa capolino una vera e propria mancanza di visione cattolica. Gli uomini passano, e fra qualche anno i personaggi che oggi occupano le prime pagine dei giornali saranno dimenticati, ritenuti degni al massimo di una targa in qualche via della citt\u00e0 o di un convegno commemorativo.<\/p>\n<p style=\"text-align: justify;\">Siamo cenere e la scena di questo mondo passa. Ci\u00f2 che invece rischia di rimanere sono le leggi, e i cambiamenti culturali che queste impongono. Fra qualche anno Marco Pannella non ci sar\u00e0 pi\u00f9. Ma il carico di morte e di devastazione che la sua azione politica ha portato segner\u00e0 a lungo non solo la nostra vita, ma quella delle future generazioni. Tanto pi\u00f9 che oggi proprio Pannella ha contribuito al risultato di quel gigantesco partito radicale di massa che \u00e8 la coalizione di centrosinistra.<\/p>\n<p style=\"text-align: justify;\"><strong>L\u2019attenzione per i poveri<\/strong><\/p>\n<p style=\"text-align: justify;\">Una fetta significativa del mondo cattolico \u00e8 letteralmente incantata dalla famosa\u00a0\u201copzione preferenziale per i poveri\u201d. Attempate dame di san Vincenzo e generosi preti impegnati nella Caritas votano a occhi chiusi i candidati \u201cattenti\u201d agli extracomunitari e ai senza tetto. Fatte salve alcune precisazioni dottrinali che qui non possiamo sviluppare, c\u2019\u00e8 da restare allibiti di fronte all\u2019incapacit\u00e0 di questi fratelli nella fede nel riconoscere chi sono i poveri di cui oggi dovremmo primariamente preoccuparci: i bambini cui \u00e8 impedito di nascere; ma anche i figli di coppie divorziate per i quali le forze politiche emergenti preparano divorzi ancora pi\u00f9 rapidi; adolescenti confusi che saranno costretti a vedere una societ\u00e0 in cui uomini si \u201csposano\u201d con uomini e donne con donne; coppie monoreddito che saranno penalizzate perch\u00e9 la donna vuole fare la madre a tempo pieno; anziani, malati e handicappati avviati all\u2019eutanasia. Senza dimenticarsi del pi\u00f9 povero dei poveri: ogni uomo che non ha incontrato Cristo, e che certo avr\u00e0 sempre meno possibilit\u00e0 di incontrarlo in una societ\u00e0 secolarizzata e anticattolica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>da il Timone n. 53, maggio 2006 C\u2019\u00e8 un errore dottrinale nel cattolicesimo che boccia un politico perch\u00e9 ne conosce le miserie personali. Ci\u00f2 che conta sono le leggi e\u00a0il loro influsso sui costumi della societ\u00e0. Ecco alcuni falsi criteri assolutamente da evitare di Mario Palmaro<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-voto-sbagliato\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":16657,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[1323],"class_list":["post-2275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dottrina-sociale","tag-voto-cattolico","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un voto sbagliato - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-voto-sbagliato\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un voto sbagliato - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-voto-sbagliato\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2006-10-13T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-01-13T08:04:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/urna-elett.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"273\" \/>\n\t<meta property=\"og:image:height\" content=\"185\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-voto-sbagliato\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-voto-sbagliato\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Un voto sbagliato\",\"datePublished\":\"2006-10-13T22:00:00+00:00\",\"dateModified\":\"2015-01-13T08:04:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-voto-sbagliato\\\/\"},\"wordCount\":1300,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-voto-sbagliato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/10\\\/urna-elett.jpg\",\"keywords\":[\"voto cattolico\"],\"articleSection\":[\"Dottrina sociale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-voto-sbagliato\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-voto-sbagliato\\\/\",\"name\":\"Un voto sbagliato - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-voto-sbagliato\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-voto-sbagliato\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/10\\\/urna-elett.jpg\",\"datePublished\":\"2006-10-13T22:00:00+00:00\",\"dateModified\":\"2015-01-13T08:04:15+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-voto-sbagliato\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-voto-sbagliato\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-voto-sbagliato\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/10\\\/urna-elett.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/10\\\/urna-elett.jpg\",\"width\":273,\"height\":185},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/un-voto-sbagliato\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un voto sbagliato\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un voto sbagliato - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-voto-sbagliato\/","og_locale":"it_IT","og_type":"article","og_title":"Un voto sbagliato - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-voto-sbagliato\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2006-10-13T22:00:00+00:00","article_modified_time":"2015-01-13T08:04:15+00:00","og_image":[{"width":273,"height":185,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/urna-elett.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-voto-sbagliato\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-voto-sbagliato\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Un voto sbagliato","datePublished":"2006-10-13T22:00:00+00:00","dateModified":"2015-01-13T08:04:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-voto-sbagliato\/"},"wordCount":1300,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-voto-sbagliato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/urna-elett.jpg","keywords":["voto cattolico"],"articleSection":["Dottrina sociale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-voto-sbagliato\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-voto-sbagliato\/","name":"Un voto sbagliato - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-voto-sbagliato\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-voto-sbagliato\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/urna-elett.jpg","datePublished":"2006-10-13T22:00:00+00:00","dateModified":"2015-01-13T08:04:15+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-voto-sbagliato\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-voto-sbagliato\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-voto-sbagliato\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/urna-elett.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/urna-elett.jpg","width":273,"height":185},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/un-voto-sbagliato\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Un voto sbagliato"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2275"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2275\/revisions"}],"predecessor-version":[{"id":16658,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2275\/revisions\/16658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/16657"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}