{"id":2258,"date":"2006-10-09T10:03:58","date_gmt":"2006-10-09T08:03:58","guid":{"rendered":""},"modified":"2016-03-29T10:13:02","modified_gmt":"2016-03-29T08:13:02","slug":"la-resistenza-e-i-miti-da-sfatare","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-resistenza-e-i-miti-da-sfatare\/","title":{"rendered":"La resistenza e i miti da sfatare"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-32262\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Pansa_cover.jpg\" alt=\"Pansa_cover\" width=\"130\" height=\"200\" \/>corriere.it<\/strong> del 4 ottobre 2006<\/div>\n<p style=\"text-align: justify;\"><em>In un nuovo libro Giampaolo Pansa continua a smentire i tanti luoghi comuni, se non vere e proprie menzogne, sulla Resistenza che non fu &#8220;guerra di popolo&#8221; ma vera e propria guerra civile egemonizzata da una sinistra non meno sanguinaria delle squadracce fasciste\u00a0<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Ernesto Galli Della Loggia<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Un libro \u00abvergognoso, non revisionista ma falsario\u00bb, \u00abuna vergognosa operazione opportunista\u00bb, \u00ablibro vergognoso di un voltagabbana\u00bb, \u00abuna cinica operazione editoriale\u00bb: sono solo quattro (rispettivamente di Aldo Aniasi, di Giorgio Bocca, di Liberazione e di Sandro Curzi) delle decine e decine di definizioni ingiuriose piovute sulla testa di Giampaolo Pansa quando pubblic\u00f2 pochi anni fa <em><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=1301\" target=\"_blank\"><em><strong>Il sangue dei vinti.<\/strong><\/em><\/a><\/strong><\/em><\/div>\n<p style=\"text-align: justify;\">Che cosa gli rimproverava la sinistra pi\u00f9 conservatrice e aggressiva, quella, come lui la chiama, degli \u00abuomini di marmo\u00bb? Semplicemente di aver rotto il tab\u00f9 delle migliaia di fascisti (o presunti tali, o addirittura, in pi\u00f9 di un caso, di antifascisti perfino) brutalmente fatti fuori dai partigiani all&#8217;indomani del 25 aprile.<\/p>\n<p style=\"text-align: justify;\">Di avere smascherato cio\u00e8 La Grande Bugia, \u00abil racconto per met\u00e0 falso (&#8230;) dilagato anno dopo anno in centinaia di libri, per migliaia e migliaia di pagine\u00bb, e diventato \u00abun&#8217;immensa tomba destinata a seppellire per sempre la verit\u00e0 della guerra civile italiana: quella stessa <strong><em>Grande Bugia<\/em><\/strong> che d\u00e0 il titolo al libro che Pansa ha appena mandato in libreria (Sperling &amp; Kupfer editori, pp. 469, e 18).<\/p>\n<p style=\"text-align: justify;\">Si tratta in un certo senso del completamento del Sangue dei vinti. Sia perch\u00e9 aggiunge nuovo materiale (nuovo perlomeno per il grande pubblico) sui delitti efferati che dopo la Liberazione insanguinarono per mesi alcune zone del Paese, tra l&#8217;altro con molte vittime svanite nel nulla non essendosene mai pi\u00f9 trovati i corpi (nella sola provincia di Reggio Emilia la cifra oscilla intorno ai 130-140!); sia perch\u00e9 in queste pagine Pansa cerca di spiegare le ragioni a suo avviso di quella mattanza, e insieme il perch\u00e9 della furibonda volont\u00e0 di mantenere in piedi ancora oggi la menzogna di cui sopra.<\/p>\n<p style=\"text-align: justify;\">Sulle ragioni della mattanza il nostro autore non ha dubbi. Si tratt\u00f2 di \u00abun&#8217;operazione pianificata messa in atto da veri e propri squadroni della morte\u00bb. Non si pu\u00f2 attribuire alcun valore, insomma, alla spiegazione \/ giustificazione avanzata mille volte da quando la verit\u00e0 ha cominciato a farsi strada e che a un dipresso suona cos\u00ec: \u00abChe c&#8217;\u00e8 da scandalizzarsi? Si sa, le guerre civili mica possono finire d&#8217;un tratto. Esse si lasciano sempre dietro una scia di odi che dura a lungo\u00bb. Gi\u00e0, ma come spiegare allora \u2014 se lo \u00e8 chiesto per primo Paolo Mieli \u2014 il fatto che a questa, chiamiamola cos\u00ec, vischiosit\u00e0 della guerra fossero sensibili solo i partigiani comunisti? Non risulta neppure un caso, infatti, di un commando azionista, socialista o cattolico, che settimane e settimane dopo la fine delle ostilit\u00e0 si sia recato a casa di qualcuno o lo abbia aspettato dietro una siepe, lasciandolo stecchito o facendone scomparire per sempre anche il cadavere. Ripeto, neppure un caso: come mai?<\/p>\n<p style=\"text-align: justify;\">Invece tutti i casi che conosciamo riguardano assassini commessi da uomini delle formazioni comuniste ai danni di persone che seppure avevano talvolta, ma solo talvolta, degli insignificanti trascorsi fascisti, si segnalavano soprattutto per rappresentare posizioni politiche o di classe potenzialmente ostili a quelle rappresentate allora dal Partito comunista.<\/p>\n<p style=\"text-align: justify;\">A cominciare da esponenti anticomunisti dello stesso mondo partigiano, come il popolarissimo comandante della divisione Cichero, Aldo Gastaldi, detto Bisogno, ventiquattrenne ex sottotenente del Genio, che nella primavera del &#8217;45, ci racconta Pansa, protesta sempre pi\u00f9 duramente contro l&#8217;egemonia del Pci nelle file delle bande nonch\u00e9 la sua strumentalizzazione della Resistenza (\u00abUn giorno \u2014 scrive \u2014 dovremo vergognarci di essere scesi a Genova alla loro testa\u00bb), e alla fine trova la morte in un \u00abinverosimile incidente stradale\u00bb subito dopo la Liberazione.<\/p>\n<p style=\"text-align: justify;\">Del tutto ragionevolmente a parere di chi scrive, Pansa \u00e8 convinto che i delitti riferibili ai membri delle formazioni comuniste non fossero per nulla casuali, bens\u00ec che dietro di essi vi fosse un disegno pi\u00f9 o meno compiuto e consapevole di conquista del potere; perlomeno che un tale disegno vi fosse in settori significativi del partito, specie nel Nord, i quali non intendevano affatto la Resistenza come una guerra contro nazisti e fascisti, ma soprattutto come una guerra di classe destinata a sfociare in un regime socialista di tipo sovietico.<\/p>\n<p style=\"text-align: justify;\">Dunque, l&#8217;immagine della Resistenza dominata dalla dimensione antifascista e combaciante sostanzialmente con essa \u00e8 la prima delle \u00ableggende da sfatare\u00bb che secondo l&#8217;autore costituiscono a loro volta la \u00abGrande Bugia\u00bb che la sinistra ha finito per far credere al Paese.<\/p>\n<p style=\"text-align: justify;\">Le altre quattro sono: che la repubblica di Sal\u00f2 non abbia avuto una consistente e convinta base di massa; di converso che la Resistenza sia stata davvero una \u00ablotta di popolo\u00bb con i contadini in particolare tutti schierati con i partigiani; che non ci sia stata \u2014 come invece c&#8217;\u00e8 stata, e come! \u2014 una vasta \u00abzona grigia\u00bb di attendisti, e infine \u00e8 pure un&#8217;assoluta leggenda, secondo Pansa, quella che continua a chiamarsi \u00abl&#8217;unit\u00e0 politica della Resistenza\u00bb.<\/p>\n<p style=\"text-align: justify;\">La quale fu invece attraversata da rivalit\u00e0 e contrapposizioni anche feroci: \u00abTutti diffidavano di tutti, leggiamo, i comunisti volevano imporre la loro supremazia. E quasi sempre ci riuscivano. Gli altri si difendevano con durezza. Il braccio di ferro \u00e8 stato continuo, senza pause. E spesso si \u00e8 lasciato alle spalle dei morti. Ossia partigiani uccisi da partigiani\u00bb.<\/p>\n<p style=\"text-align: justify;\">Pur essendo sempre stato e continuando ad essere un uomo di sinistra, Pansa non esita a definire l&#8217;antifascismo della vulgata storica alimentata dalla sinistra con le leggende ora dette una \u00abideologia proterva\u00bb. Ideologia che per mantenersi in vita \u00e8 ricorsa sempre pi\u00f9 spesso negli ultimi anni ad uno strumento in particolare (di cui il nostro autore ha fatto le spese come pochi altri): l&#8217;accusa di \u00abrevisionismo\u00bb, \u00abun&#8217;arma contundente\u00bb usata senza scrupolo contro chiunque rifiutasse di credere alla \u00abGrande Bugia\u00bb.<\/p>\n<p style=\"text-align: justify;\">Ma perch\u00e9, ci si pu\u00f2 chiedere, la sinistra si \u00e8 trovata costretta a dover \u00abcampare di antifascismo\u00bb, come scrive icasticamente Pansa: dell&#8217;antifascismo di una vulgata cos\u00ec bugiarda? a puntare su una costruzione ideologico- retorica cos\u00ec priva di basi reali? La sua risposta \u00e8 che ci\u00f2 \u00e8 dipeso in parte dall&#8217;arroganza della sinistra stessa, congenitamente incapace di riconoscere i propri torti, ma soprattutto dal suo rifiuto di tenere nel minimo conto le ragioni degli \u00abaltri\u00bb, dei fascisti, e dunque dalla conseguente necessit\u00e0 di operare una costante manipolazione \/ negazione dei fatti al fine di nascondere la verit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Personalmente spingerei lo sguardo pi\u00f9 lontano. Sono convinto, infatti, che l&#8217;origine prima della vulgata resistenzial-antifascista sia stato (oltre l&#8217;ovvia necessit\u00e0 di nascondere lo sporco sotto il tappeto) il tante volte sottolineato bisogno del Partito comunista di trovare una legittimazione nella nascente democrazia italiana che la sua natura totalitaria gli negava.<\/p>\n<p style=\"text-align: justify;\">Grazie all&#8217;egemonia culturale questo orientamento ha fondato un vero e proprio luogo comune, un topos storiografico, a cui hanno supinamente acceduto tanti altri, che oggi tuttavia, credo, viene difeso con aggressivit\u00e0 smisurata per una ragione diversa da quella originaria.<\/p>\n<p style=\"text-align: justify;\">In realt\u00e0 l&#8217;antirevisionismo odierno, infatti, rappresenta un momento essenziale della battaglia della sinistra per continuare a pensare se stessa come detentrice del monopolio del Bene. Ma solo se trova ogni volta qualcuno da dipingere come portabandiera del male, la sinistra, nata storicamente all&#8217;insegna di un forte rapporto con esigenze di tipo etico, continua a poter nutrire la sua illusoria certezza di essere buona o comunque migliore in modo sostanziale dei propri avversari.<\/p>\n<p style=\"text-align: justify;\">Cattivo \u00e8 ovviamente chiunque non condivida il suo pensiero medio, i suoi pregiudizi e i suoi tab\u00f9, e siccome il fascismo \u00e8 altrettanto ovviamente il prototipo del male, ecco perch\u00e9 \u2014 specie in anni in cui lo sgretolamento ideologico ha reso sempre pi\u00f9 scarsi i nemici reperibili sul mercato interno (con la fortunata eccezione di Berlusconi) \u2014 ecco perch\u00e9 i \u00abrevisionisti\u00bb vengono automaticamente qualificati come \u00abfascisti\u00bb pi\u00f9 o meno mascherati, comunque dei poco di buono in qualche modo collusi con il potere cattivo.<\/p>\n<p style=\"text-align: justify;\">Anche cos\u00ec, anche con questi metodi, si \u00e8 costruita quell&#8217;egemonia il cui successo consolidatosi negli anni spiega perch\u00e9 \u2014 come scrive Pansa, che l&#8217;ha imparato a proprie spese \u2014 nello scontro polemico \u00e8 sempre meglio avere per nemica la destra piuttosto che la sinistra (&#8230;) La destra ha poche armi, pochi giornali, poche case editrici. Pochi clan intellettuali che contano. (&#8230;) La sinistra, invece, possiede tutto ci\u00f2 che manca alla destra: una capacit\u00e0 di fuoco capace di stroncare chiunque\u00bb. Soprattutto, nella guerra per la memoria del Paese essa ha dalla sua la stragrande maggioranza della storiografia accademica. La quale, non per nulla, a suo tempo \u00e8 scesa massicciamente in campo contro Il sangue dei vinti e il suo autore. Ricorrendo alle pi\u00f9 svariate motivazioni: da quella pregna di boria professorale che i libri di Pansa \u00abnon sono libri di uno storico\u00bb (Angelo D&#8217;Orsi: come se contasse questo e non gi\u00e0 la verit\u00e0 delle cose dette), a quella di fornire \u00abbenzina per nuove molotov contro l&#8217;antifascismo e la Resistenza\u00bb (sempre D&#8217;Orsi), a quella di scrivere al solo scopo di \u00absuscitare orrore e ripugnanza\u00bb (Giovanni De Luna), all&#8217;accusa di avere indebitamente alimentato \u00abil piagnisteo sul sangue dei vinti\u00bb (Sergio Luzzatto).<\/p>\n<p style=\"text-align: justify;\">La sinistra di tradizione comunista o che in essa \u00e8 confluita cerca insomma di difendere a tutti i costi l&#8217;idea che il binomio antifascista- Resistenza (ivi inclusa l&#8217;analisi storica di entrambi) debba essere una sorta di suo appannaggio personale in quanto parte della sua specifica identit\u00e0 e \u2014 essa vorrebbe far credere \u2014 solo della sua.<\/p>\n<p style=\"text-align: justify;\">Ma per fortuna non \u00e8 cos\u00ec. In quanto espressione e impegno per la libert\u00e0, antifascismo e Resistenza sono conseguenza naturale di ogni fede democratica e non sopportano n\u00e9 pudori n\u00e9 clericalismi ideologici di alcun tipo. Contribuisce davvero a rafforzare quella fede perci\u00f2 non chi si straccia le vesti sui suoi supposti dogmi, ma quelle personalit\u00e0 libere, come \u00e8 appunto Giampaolo Pansa: un giornalista, s\u00ec un semplice giornalista (e sono sicuro che a lui piace essere definito solo cos\u00ec), che tuttavia, per restituire agli Italiani la verit\u00e0 sul loro passato ha fatto molto, molto di pi\u00f9 di tanti storici di professione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>corriere.it del 4 ottobre 2006 In un nuovo libro Giampaolo Pansa continua a smentire i tanti luoghi comuni, se non vere e proprie menzogne, sulla Resistenza che non fu &#8220;guerra di popolo&#8221; ma vera e propria guerra civile egemonizzata da una sinistra non meno sanguinaria delle squadracce fasciste\u00a0 di Ernesto Galli Della Loggia<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-resistenza-e-i-miti-da-sfatare\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":32262,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17,100,96],"tags":[1231],"class_list":["post-2258","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-libri","category-resistenza","category-storia-italiana","tag-sinistre","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La resistenza e i miti da sfatare - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-resistenza-e-i-miti-da-sfatare\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La resistenza e i miti da sfatare - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-resistenza-e-i-miti-da-sfatare\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2006-10-09T08:03:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-03-29T08:13:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Pansa_cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"181\" \/>\n\t<meta property=\"og:image:height\" content=\"278\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-resistenza-e-i-miti-da-sfatare\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-resistenza-e-i-miti-da-sfatare\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La resistenza e i miti da sfatare\",\"datePublished\":\"2006-10-09T08:03:58+00:00\",\"dateModified\":\"2016-03-29T08:13:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-resistenza-e-i-miti-da-sfatare\\\/\"},\"wordCount\":1654,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-resistenza-e-i-miti-da-sfatare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/10\\\/Pansa_cover.jpg\",\"keywords\":[\"sinistre\"],\"articleSection\":[\"Libri\",\"Resistenza\",\"Storia italiana\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-resistenza-e-i-miti-da-sfatare\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-resistenza-e-i-miti-da-sfatare\\\/\",\"name\":\"La resistenza e i miti da sfatare - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-resistenza-e-i-miti-da-sfatare\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-resistenza-e-i-miti-da-sfatare\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/10\\\/Pansa_cover.jpg\",\"datePublished\":\"2006-10-09T08:03:58+00:00\",\"dateModified\":\"2016-03-29T08:13:02+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-resistenza-e-i-miti-da-sfatare\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-resistenza-e-i-miti-da-sfatare\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-resistenza-e-i-miti-da-sfatare\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/10\\\/Pansa_cover.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/10\\\/Pansa_cover.jpg\",\"width\":181,\"height\":278},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-resistenza-e-i-miti-da-sfatare\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La resistenza e i miti da sfatare\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La resistenza e i miti da sfatare - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-resistenza-e-i-miti-da-sfatare\/","og_locale":"it_IT","og_type":"article","og_title":"La resistenza e i miti da sfatare - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-resistenza-e-i-miti-da-sfatare\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2006-10-09T08:03:58+00:00","article_modified_time":"2016-03-29T08:13:02+00:00","og_image":[{"width":181,"height":278,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Pansa_cover.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-resistenza-e-i-miti-da-sfatare\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-resistenza-e-i-miti-da-sfatare\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La resistenza e i miti da sfatare","datePublished":"2006-10-09T08:03:58+00:00","dateModified":"2016-03-29T08:13:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-resistenza-e-i-miti-da-sfatare\/"},"wordCount":1654,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-resistenza-e-i-miti-da-sfatare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Pansa_cover.jpg","keywords":["sinistre"],"articleSection":["Libri","Resistenza","Storia italiana"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-resistenza-e-i-miti-da-sfatare\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-resistenza-e-i-miti-da-sfatare\/","name":"La resistenza e i miti da sfatare - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-resistenza-e-i-miti-da-sfatare\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-resistenza-e-i-miti-da-sfatare\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Pansa_cover.jpg","datePublished":"2006-10-09T08:03:58+00:00","dateModified":"2016-03-29T08:13:02+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-resistenza-e-i-miti-da-sfatare\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-resistenza-e-i-miti-da-sfatare\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-resistenza-e-i-miti-da-sfatare\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Pansa_cover.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Pansa_cover.jpg","width":181,"height":278},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-resistenza-e-i-miti-da-sfatare\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La resistenza e i miti da sfatare"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2258"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2258\/revisions"}],"predecessor-version":[{"id":32263,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2258\/revisions\/32263"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/32262"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}