{"id":2244,"date":"2006-10-04T09:01:38","date_gmt":"2006-10-04T07:01:38","guid":{"rendered":""},"modified":"2016-06-13T13:11:58","modified_gmt":"2016-06-13T11:11:58","slug":"amare-il-mondo-appassionatamente","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/amare-il-mondo-appassionatamente\/","title":{"rendered":"Amare il mondo appassionatamente"},"content":{"rendered":"<div style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-34603\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Josemar\u00eda-Escriv\u00e0.jpg\" alt=\"Josemar\u00eda Escriv\u00e0\" width=\"250\" height=\"166\" \/>Testo dell&#8217;omelia pronunciata nel campus dell&#8217;Universit\u00e0 di Navarra, l&#8217;8 ottobre 1967<\/div>\n<p style=\"text-align: center;\">da <strong>San Josemar\u00eda Escriv\u00e0<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><em>Mons. Javier Echevarr\u00eda presentava cos\u00ec quest&#8217;omelia durante il XIII Simposio sulla Storia della Chiesa in Spagna e in America: \u201cAmare il mondo significa amarlo in Dio e per Dio. In questa determinazione si radica il messaggio di questo sacerdote santo. Un messaggio vecchio come il Vangelo e come il Vangelo nuovo. Nel mondo esistono molti uomini e donne, e il Maestro chiama tutti, senza eccezione. Li chiama a una vita di santit\u00e0, a una vita eterna\u201d.<\/em><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Avete or ora ascoltato la lettura solenne dei due brani della Sacra Scrittura corrispondenti alla Messa della domenica XXI dopo Pentecoste. Il fatto di aver ascoltato la parola di Dio vi colloca di gi\u00e0 nell&#8217;\u00e0mbito in cui vogliono situarsi le parole che ora vi rivolgo: parole di sacerdote, pronunciate di fronte a una grande famiglia di figli di Dio nella sua Santa Chiesa. Parole, quindi, che vogliono essere soprannaturali, e proclamare la grandezza di Dio e le sue misericordie verso gli uomini: parole che vi preparino a questa impressionante Eucaristia che oggi celebriamo nel &#8220;campus&#8221; dell&#8217;Universit\u00e0 di Navarra.<\/div>\n<p style=\"text-align: justify;\">Considerate un momento la circostanza cui accennavo. Celebriamo la Sacra Eucaristia, il sacrificio sacramentale del Corpo e del Sangue del Signore, il mistero di fede che riassume in s\u00e9 tutti i misteri del cristianesimo. Celebriamo, pertanto, l&#8217;azione pi\u00f9 sacra e trascendente che noi uomini possiamo realizzare, per grazia di Dio, in questa vita: unirci in comunione con il Corpo e il Sangue del Signore viene a essere per noi, in un certo senso, come scioglierci dai legami di terra e di tempo per trovarci di gi\u00e0 con Dio nel Cielo, l\u00e0 dove Cristo stesso asciugher\u00e0 le lacrime dei nostri occhi e dove non ci sar\u00e0 morte, n\u00e9 pianto, n\u00e9 gemiti di fatica, perch\u00e9 il mondo vecchio sar\u00e0 ormai passato [Cfr &#8220;Ap&#8221; 21, 4].<\/p>\n<p style=\"text-align: justify;\">Questa verit\u00e0 cos\u00ec consolante e profonda, questo significato escatologico dell&#8217;Eucaristia, come usano dire i teologi, potrebbe per\u00f2 essere frainteso: e lo \u00e8 stato ogni qual volta si \u00e8 voluto presentare la vita cristiana come qualcosa di esclusivamente \u00abspirituale\u00bb &#8211; spiritualista, voglio dire -, riservato a gente \u00abpura\u00bb, eccezionale, che non si mescola alle cose spregevoli di questo mondo, o tutt&#8217;al pi\u00f9 le tollera come una cosa a cui lo spirito \u00e8 necessariamente giustapposto, finch\u00e9 viviamo sulla terra.<\/p>\n<p style=\"text-align: justify;\">Quando si ha questa visione delle cose, il tempio diventa il luogo per antonomasia della vita cristiana; essere cristiano vuol dire allora andare nel tempio, partecipare alle cerimonie sacre, abbarbicarsi a una sociologia ecclesiastica, in una specie di \u00abmondo\u00bb a parte, che si spaccia per l&#8217;anticamera del Cielo, mentre il mondo comune va per la sua strada. La dottrina del cristianesimo, la vita della grazia, passerebbero, dunque, appena sfiorando l&#8217;agitato procedere della storia umana, senza entrare in contatto con esso.<\/p>\n<p style=\"text-align: justify;\">In questa mattina di ottobre, nel momento in cui ci disponiamo a addentrarci nel memoriale della Pasqua del Signore, rispondiamo con un semplice \u00abno\u00bb a questa visione distorta del cristianesimo. Pensate un momento alla cornice della nostra Eucaristia, della nostra Azione di Grazie: ci troviamo in un tempio singolare; si potrebbe dire che la navata \u00e8 il &#8220;campus&#8221; universitario, la pala d&#8217;altare \u00e8 la biblioteca dell&#8217;Universit\u00e0; attorno ci sono le gru per la costruzione dei nuovi edifici; e, sopra di noi, il cielo di Navarra&#8230;<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 forse vero che questo sguardo a ci\u00f2 che abbiamo intorno vi conferma &#8211; con un&#8217;immagine viva e indimenticabile &#8211; che \u00e8 la vita ordinaria il vero &#8220;luogo&#8221; della vostra esistenza cristiana? Figli miei, l\u00ec dove sono gli uomini vostri fratelli, l\u00ec dove sono le vostre aspirazioni, il vostro lavoro, l\u00ec dove si riversa il vostro amore, quello \u00e8 il posto del vostro quotidiano incontro con Cristo. \u00c8 in mezzo alle cose pi\u00f9 materiali della terra che ci dobbiamo santificare, servendo Dio e tutti gli uomini.<\/p>\n<p style=\"text-align: justify;\">Ho insegnato incessantemente, con parole della Sacra Scrittura, che il mondo non \u00e8 cattivo: perch\u00e9 \u00e8 uscito dalle mani di Dio, perch\u00e9 \u00e8 creatura sua, perch\u00e9 Jahv\u00e8 lo guard\u00f2 e vide che era buono [Cfr &#8220;Gn&#8221; 1, 7 ss]. Siamo noi uomini a renderlo cattivo e brutto, con i nostri peccati e le nostre infedelt\u00e0. Siatene pur certi, figli miei: qualsiasi specie di evasione dalle realt\u00e0 oneste di tutti i giorni significa per voi, uomini e donne del mondo, il contrario della volont\u00e0 di Dio.<\/p>\n<p style=\"text-align: justify;\">Dovete invece comprendere adesso &#8211; con una luce tutta nuova &#8211; che Dio vi chiama per servirlo &#8220;nei&#8221; compiti e &#8220;attraverso&#8221; i compiti civili, materiali, temporali della vita umana: in un laboratorio, nella sala operatoria di un ospedale, in caserma, dalla cattedra di un&#8217;universit\u00e0, in fabbrica, in officina, sui campi, nel focolare domestico e in tutto lo sconfinato panorama del lavoro, Dio ci aspetta ogni giorno. Sappiatelo bene: c&#8217;\u00e8 &#8220;un qualcosa&#8221; di santo, di divino, nascosto nelle situazioni pi\u00f9 comuni, qualcosa che tocca a ognuno di voi scoprire.<\/p>\n<p style=\"text-align: justify;\">A quegli universitari e a quegli operai che mi seguivano verso gli anni Trenta, io solevo dire che dovevano saper &#8220;materializzare&#8221; la vita spirituale. Volevo allontanarli in questo modo dalla tentazione &#8211; cos\u00ec frequente allora, e anche oggi &#8211; di condurre una specie di doppia vita: da una parte, la vita interiore, la vita di relazione con Dio; dall&#8217;altra, come una cosa diversa e separata, la vita familiare, professionale e sociale, fatta tutta di piccole realt\u00e0 terrene<\/p>\n<p style=\"text-align: justify;\">No, figli miei! Non ci pu\u00f2 essere una doppia vita, non possiamo essere come degli schizofrenici, se vogliamo essere cristiani: vi \u00e8 una sola vita, fatta di carne e di spirito, ed \u00e8 questa che dev&#8217;essere &#8211; nell&#8217;anima e nel corpo &#8211; santa e piena di Dio: questo Dio invisibile lo troviamo nelle cose pi\u00f9 visibili e materiali.<\/p>\n<p style=\"text-align: justify;\">Non vi \u00e8 altra strada, figli miei: o sappiamo trovare il Signore nella nostra vita ordinaria, o non lo troveremo mai. Per questo vi posso dire che la nostra epoca ha bisogno di restituire alla materia e alle situazioni che sembrano pi\u00f9 comuni il loro nobile senso originario, metterle al servizio del Regno di Dio, spiritualizzarle, facendone mezzo e occasione del nostro incontro continuo con Ges\u00f9 Cristo.<\/p>\n<p style=\"text-align: justify;\">Il senso cristiano autentico &#8211; che professa la risurrezione della carne &#8211; si \u00e8 sempre opposto, come \u00e8 logico, alla &#8220;disincarnazione&#8221;, senza tema di essere tacciato di materialismo. \u00c8 consentito, pertanto, parlare di un &#8220;materialismo cristiano&#8221;, che si oppone audacemente ai materialismi chiusi allo spirito.<\/p>\n<p style=\"text-align: justify;\">Che cosa sono i Sacramenti &#8211; orme dell&#8217;Incarnazione del Verbo, come dissero gli antichi &#8211; se non la manifestazione pi\u00f9 evidente di questa strada che Dio ha scelto per santificarci e condurci al Cielo? Non vedete che ogni Sacramento \u00e8 l&#8217;amore di Dio, con tutta la sua forza creatrice e redentrice, che si dona a noi servendosi di mezzi materiali? Che cos&#8217;\u00e8 questa Eucaristia &#8211; ormai imminente &#8211; se non il Corpo e il Sangue adorabili del nostro Redentore, che si offre a noi attraverso l&#8217;umile materia di questo mondo &#8211; vino e pane -, attraverso gli \u00abelementi della natura, coltivati dall&#8217;uomo\u00bb [Cfr &#8220;Gaudium et spes&#8221;, 38], come l&#8217;ultimo Concilio ecumenico ha voluto ricordare?<\/p>\n<p style=\"text-align: justify;\">Si comprende bene, figli miei, perch\u00e9 l&#8217;Apostolo poteva scrivere: \u00abTutte le cose sono vostre, voi siete di Cristo e Cristo \u00e8 di Dio\u00bb [1 &#8220;Cor&#8221; 3, 22-23]. Si tratta di un moto ascensionale che lo Spirito Santo, diffuso nei nostri cuori, vuole provocare nel mondo: dalla terra, fino alla gloria del Signore. E perch\u00e9 non ci fosse dubbio che in questo moto si includeva pure ci\u00f2 che sembra pi\u00f9 prosaico, san Paolo scriveva anche: \u00abSia che mangiate, sia che beviate, fate tutto per la gloria di Dio\u00bb [1 &#8220;Cor&#8221; 10, 31].<\/p>\n<p style=\"text-align: justify;\">Questa dottrina della Sacra Scrittura, che si trova, come sapete, nel cuore stesso della spiritualit\u00e0 dell&#8217;Opus Dei, vi deve spingere a realizzare il vostro lavoro con perfezione, ad amare Dio e gli uomini facendo con amore le piccole cose della vostra giornata abituale, scoprendo quel &#8220;qualcosa di divino&#8221; che \u00e8 nascosto nei particolari. Vengono a pennello, a questo proposito, i versi del poeta di Castiglia: \u00abPian pianino, con bella grafia: \/ ch\u00e9 fare le cose bene \/ vale pi\u00f9 che farle\u00bb [\u00ab&#8221;Despacito, y buena letra: \/ El hacer las cosas bien \/ Importa m\u00e1s que el hacerlas&#8221;\u00bb A. MACHADO, &#8220;Poes\u00edas completas&#8221;, 161 (&#8220;Proverbios y cantares&#8221;, XXIV), Espasa &#8211; Calpe, Madrid 1940].<\/p>\n<p style=\"text-align: justify;\">Vi assicuro, figli miei, che quando un cristiano compie con amore le attivit\u00e0 quotidiane meno trascendenti, in esse trabocca la trascendenza di Dio. Per questo vi ho ripetuto, con ostinata insistenza, che la vocazione cristiana consiste nel trasformare in endecasillabi la prosa quotidiana. Il cielo e la terra, figli miei, sembra che si uniscano laggi\u00f9, sulla linea dell&#8217;orizzonte. E invece no, \u00e8 nei vostri cuori che si fondono davvero, quando vivete santamente la vita ordinaria&#8230;<\/p>\n<p style=\"text-align: justify;\">Vivere santamente la vita ordinaria, vi ho detto. E con questa parole mi riferisco a tutto il programma del vostro agire cristiano. Mettete dunque da parte i sogni, i falsi idealismi, le fantasticherie, tutto quell&#8217;atteggiamento che sono solito chiamare \u00abmistica del magari\u00bb &#8211; magari non mi fossi sposato, magari non avessi questa professione, magari avessi pi\u00f9 salute, magari fossi giovane, magari fossi vecchio!&#8230; -, e attenetevi piuttosto, con sobriet\u00e0, alla realt\u00e0 pi\u00f9 materiale e immediata, perch\u00e9 \u00e8 proprio l\u00ec che si trova il Signore: \u00abGuardate le mie mani e i miei piedi\u00bb, dice Ges\u00f9 risuscitato, \u00absono proprio io! Toccatemi e guardate; un fantasma non ha carne e ossa come vedete che ho io\u00bb [&#8220;Lc&#8221; 24, 39].<\/p>\n<p style=\"text-align: justify;\">Sono molti gli aspetti dell&#8217;ambiente secolare in cui vi muovete che vengono a essere illuminati partendo da queste verit\u00e0. Pensate, per esempio, alla vostra azione di cittadini nella vita civile. Un uomo consapevole che il mondo &#8211; e non solo il tempio &#8211; \u00e8 il luogo del suo incontro con Cristo, ama questo mondo, si sforza di raggiungere una buona preparazione intellettuale e professionale, e va formando &#8211; in piena libert\u00e0 &#8211; il proprio criterio sui problemi dell&#8217;ambiente in cui opera; e di conseguenza prende le sue decisioni che, essendo decisioni di un cristiano, sono anche frutto di una riflessione personale, umilmente intesa a cogliere la Volont\u00e0 di Dio in questi particolari piccoli e grandi della vita.<\/p>\n<p style=\"text-align: justify;\">Ma a questo cristiano non viene mai in mente di credere o di dire che lui scende dal tempio al mondo per rappresentare la Chiesa, e che le sue scelte sono le &#8220;soluzioni cattoliche&#8221; di quei problemi. Questo non va, figli miei! Un atteggiamento del genere sarebbe clericalismo, &#8220;cattolicesimo ufficiale&#8221; o come volete chiamarlo. In ogni caso, vuol dire violentare la natura delle cose. Dovete diffondere dappertutto una vera &#8220;mentalit\u00e0 laicale&#8221;, che deve condurre a tre conclusioni:<\/p>\n<p style=\"text-align: justify;\">&#8211; a essere sufficientemente onesti da addossarsi personalmente il peso delle proprie responsabilit\u00e0;<\/p>\n<p style=\"text-align: justify;\">&#8211; a essere sufficientemente cristiani da rispettare i fratelli nella fede che propongono &#8211; nelle materie opinabili &#8211; soluzioni diverse da quelle che sostiene ciascuno di noi;<\/p>\n<p style=\"text-align: justify;\">&#8211; a essere sufficientemente cattolici da non servirsi della Chiesa, nostra Madre, immischiandola in partigianerie umane<\/p>\n<p style=\"text-align: justify;\">\u00c8 evidente che, in questo terreno, come in tutti, voi non potreste realizzare questo programma di vivere santamente la vita ordinaria, se non fruiste di tutta la libert\u00e0 che vi viene riconosciuta sia dalla Chiesa che dalla vostra dignit\u00e0 di uomini e di donne creati a immagine di Dio. La libert\u00e0 personale \u00e8 essenziale nella vita cristiana. Ma non dimenticate, figli miei, che io parlo sempre di una libert\u00e0 responsabile.<\/p>\n<p style=\"text-align: justify;\">Interpretate quindi le mie parole per quello che sono: un appello all&#8217;esercizio &#8211; tutti i giorni! e non solo nelle situazioni di emergenza &#8211; dei vostri diritti; e all&#8217;esemplare compimento dei vostri doveri di cittadini &#8211; nella vita politica, nella vita economica, nella vita universitaria, nella vita professionale &#8211; addossandovi coraggiosamente tutte le conseguenze delle vostre libere decisioni, assumendo la responsabilit\u00e0 dell&#8217;indipendenza personale che vi spetta. E questa cristiana &#8220;mentalit\u00e0 laicale&#8221; vi consentir\u00e0 di evitare ogni intolleranza e ogni fanatismo, ossia &#8211; per dirlo in modo positivo &#8211; vi far\u00e0 convivere in pace con tutti i vostri concittadini e favorire anche la convivenza nei diversi ordini della vita sociale.<\/p>\n<p style=\"text-align: justify;\">So che non c&#8217;\u00e8 bisogno che vi ricordi quello che sto ripetendo da tanti anni. Questa dottrina di libert\u00e0 civile, di convivenza e di comprensione, \u00e8 un elemento di primissimo piano nel messaggio che l&#8217;Opus Dei diffonde. C&#8217;\u00e8 bisogno che ribadisca ancora una volta che gli uomini e le donne che vogliono servire Cristo Ges\u00f9 nell&#8217;Opera di Dio sono semplicemente dei &#8220;cittadini uguali agli altri&#8221; che si sforzano di vivere con responsabilit\u00e0 seria &#8211; fino alle ultime conclusioni &#8211; la loro vocazione cristiana?<\/p>\n<p style=\"text-align: justify;\">Non c&#8217;\u00e8 nulla che distingua i miei figli dagli altri membri della societ\u00e0 civile. Invece non hanno nulla in comune con i membri delle congregazioni religiose, salvo la fede. Io amo i religiosi e venero e ammiro le loro clausure, le loro attivit\u00e0 apostoliche, la loro separazione dal mondo &#8211; il &#8220;contemptus mundi&#8221; &#8211; che sono &#8220;altri &#8220;segni di santit\u00e0 nella Chiesa. Ma il Signore non mi ha dato una vocazione religiosa, e il desiderarla per me sarebbe un disordine. Nessuna autorit\u00e0 sulla terra mi potr\u00e0 obbligare a essere un religioso, come nessuna autorit\u00e0 pu\u00f2 costringermi a contrarre matrimonio. Sono un sacerdote secolare: un sacerdote di Cristo Ges\u00f9 che ama appassionatamente il mondo.<\/p>\n<p style=\"text-align: justify;\">Coloro che &#8211; assieme a me, povero peccatore &#8211; hanno seguito Ges\u00f9 Cristo, sono: una piccola percentuale di sacerdoti, che hanno esercitato in precedenza una professione o un mestiere laicale; un gran numero di sacerdoti secolari di molte diocesi del mondo &#8211; che in tal modo rinsaldano la loro obbedienza e il loro amore ai rispettivi vescovi, e l&#8217;efficacia del loro lavoro diocesano -, sempre con le braccia aperte in croce per fare in modo che tutte le anime trovino posto nel loro cuore, e che stanno come me nel bel mezzo della strada, nel mondo, e lo amano; e la grande folla di uomini e di donne &#8211; di nazioni diverse, di lingue diverse, di razze diverse &#8211; che vivono del loro lavoro professionale, sposati la maggior parte, celibi parecchi altri, che partecipano assieme ai loro concittadini al grave compito di rendere pi\u00f9 umana e pi\u00f9 giusta la societ\u00e0 temporale; nella nobile lotta degli impegni quotidiani, con personale responsabilit\u00e0 &#8211; ripeto -, assaporando assieme agli altri uomini, gomito a gomito, successi e insuccessi, sforzandosi di compiere i loro doveri e di esercitare i loro diritti sociali e civili.<\/p>\n<p style=\"text-align: justify;\">E tutto questo con naturalezza, come un qualsiasi cristiano consapevole, senza mentalit\u00e0 di gente eletta, fusi nella massa dei loro colleghi, mentre si impegnano a scoprire gli splendori divini riverberati nelle realt\u00e0 pi\u00f9 banali<\/p>\n<p style=\"text-align: justify;\">Anche le opere che l&#8217;Opus Dei promuove come istituzione hanno caratteristiche eminentemente secolari: non sono opere ecclesiastiche. Non sono rivestite di nessuna rappresentanza ufficiale della sacra Gerarchia della Chiesa. Sono opere di promozione umana, culturale, sociale, realizzate da cittadini che si impegnano a illuminarle con le luci del Vangelo e a riscaldarle con l&#8217;amore di Cristo. Un dato vi aiuter\u00e0 a comprenderlo: l&#8217;Opus Dei non ha n\u00e9 avr\u00e0 mai come missione, per esempio, quella di dirigere dei seminari diocesani, nei quali i vescovi, \u00abistituiti dallo Spirito Santo\u00bb [Cfr &#8220;At&#8221; 20, 28], preparano i futuri sacerdoti.<\/p>\n<p style=\"text-align: justify;\">L&#8217;Opus Dei promuove invece centri di qualificazione per operai, di formazione professionale per contadini, di istruzione elementare, media e universitaria, e tante e cos\u00ec diverse attivit\u00e0 ancora, in tutto il mondo, perch\u00e9 il suo slancio apostolico &#8211; come ebbi a scrivere molti anni or sono &#8211; \u00e8 un mare senza sponde. Ma perch\u00e9 dilungarmi su questo argomento, quando la vostra stessa presenza qui \u00e8 pi\u00f9 eloquente di un lungo discorso?<\/p>\n<p style=\"text-align: justify;\">Voi, Amici dell&#8217;Universit\u00e0 di Navarra, siete parte di un popolo che \u00e8 consapevole di essere impegnato nel progresso della societ\u00e0 cui appartiene. Il vostro cordiale incoraggiamento, la vostra preghiera, il vostro sacrificio e i vostri contributi non scorrono attraverso i canali del confessionalismo cattolico; nel dare la vostra cooperazione, voi siete una chiara testimonianza di retta coscienza civica, sollecita del bene comune temporale; e date prova che una universit\u00e0 pu\u00f2 scaturire dalle energie del popolo ed essere sostenuta dal popolo.<\/p>\n<p style=\"text-align: justify;\">Una volta ancora, in questa occasione, desidero manifestare la mia riconoscenza per la collaborazione che prestano alla nostra Universit\u00e0 la mia nobilissima citt\u00e0 di Pamplona, la grande e forte regione navarrese, gli amici provenienti da ogni parte della Spagna e infine &#8211; lo dico con particolare commozione &#8211; i non spagnoli e anche i non cattolici e i non cristiani che hanno compreso, e ne danno prova con i fatti, l&#8217;intenzione e lo spirito di questa impresa.<\/p>\n<p style=\"text-align: justify;\">Tutti hanno contribuito a far s\u00ec che l&#8217;Universit\u00e0 sia un faro, sempre pi\u00f9 luminoso, di libert\u00e0 civile, di preparazione intellettuale, di emulazione professionale, e un fattore di stimolo per tutta l&#8217;istruzione universitaria. Il vostro generoso sacrificio \u00e8 il supporto di quest&#8217;opera universale, tutta tesa allo sviluppo delle scienze umane, alla promozione sociale, alla pedagogia della fede.<\/p>\n<p style=\"text-align: justify;\">Ci\u00f2 che vi ho appena detto \u00e8 stato ben compreso dal popolo di Navarra, che riconosce pure nella sua Universit\u00e0 quel fattore di promozione economica per la regione, e soprattutto di promozione sociale, che ha consentito a tanti dei suoi figli un accesso alle professioni intellettuali altrimenti arduo se non addirittura impossibile. \u00c8 stato indubbiamente l&#8217;aver capito il ruolo dell&#8217;Universit\u00e0 nella vita stessa della regione a spingere la Navarra ad appoggiarla fin dagli inizi: appoggio destinato senz&#8217;altro a diventare ogni giorno pi\u00f9 vasto ed entusiasta.<\/p>\n<p style=\"text-align: justify;\">Io continuo a nutrire la speranza che arriver\u00e0 il momento &#8211; perch\u00e9 risponde a criteri di giustizia e alla realt\u00e0 vigente in tante nazioni &#8211; in cui lo Stato spagnolo contribuir\u00e0, per quanto lo concerne, ad alleggerire l&#8217;onere di un&#8217;attivit\u00e0 che non persegue alcun genere di profitto privato, ma \u00e8 invece totalmente votata al servizio della societ\u00e0 e a operare efficacemente per la prosperit\u00e0 attuale e futura della nazione.<\/p>\n<p style=\"text-align: justify;\">E adesso, figlie e figli miei, permettetemi di soffermarmi su di un altro aspetto &#8211; particolarmente toccante &#8211; della vita di tutti i giorni. Mi riferisco all&#8217;amore umano, l&#8217;amore autentico e puro fra un uomo e una donna, il fidanzamento, il matrimonio. Mi preme di dire una volta ancora che questo santo amore umano non \u00e8 qualcosa di semplicemente consentito o tollerato, accanto alle vere attivit\u00e0 dello spirito, come potrebbe sottintendersi in quei falsi spiritualismi cui alludevo dianzi. Sono quarant&#8217;anni che sto predicando a viva voce e per scritto tutto il contrario, e finalmente cominciano a comprenderlo quelli che non lo capivano.<\/p>\n<p style=\"text-align: justify;\">L&#8217;amore che conduce al matrimonio e alla famiglia pu\u00f2 essere anch&#8217;esso un cammino divino, vocazionale, meraviglioso, una strada per la completa dedicazione al nostro Dio. Fate le cose con perfezione, vi ricordavo, mettete amore nelle piccole attivit\u00e0 della giornata, scoprite &#8211; insisto ancora &#8211; quel &#8220;qualcosa di divino&#8221; nascosto nei particolari: tutta questa dottrina ha speciale applicazione nello spazio vitale in cui si muove l&#8217;amore umano.<\/p>\n<p style=\"text-align: justify;\">Lo sapete bene, professori, alunni e tutti voi che dedicate la vostra opera all&#8217;Universit\u00e0 di Navarra: io ho affidato i vostri affetti pi\u00f9 cari a Santa Maria, Madre del Bell&#8217;Amore. L&#8217;edicola con la sua statua, l&#8217;avete qui: l&#8217;abbiamo costruita con devozione, in mezzo al &#8220;campus&#8221; universitario, perch\u00e9 accolga le vostre preghiere e l&#8217;offerta di questo meraviglioso e puro amore, che Lei benedice.<\/p>\n<p style=\"text-align: justify;\">\u00abNon sapete che il vostro corpo \u00e8 tempio dello Spirito Santo che avete ricevuto da Dio, e che non appartenete quindi a voi stessi?\u00bb [1 &#8220;Cor&#8221; 6, 19]. Quante volte, davanti alla statua della Vergine Santa, Madre del Bell&#8217;Amore, voi risponderete con un&#8217;affermazione gioiosa a questa domanda dell&#8217;Apostolo! S\u00ec &#8211; direte -, lo sappiamo, Vergine Madre di Dio, e col tuo efficace aiuto vogliamo anche viverlo.<\/p>\n<p style=\"text-align: justify;\">La preghiera contemplativa sgorgher\u00e0 dal vostro cuore ogni volta che mediterete questa grandiosa verit\u00e0: una cosa cos\u00ec materiale come il mio corpo \u00e8 stata prescelta dallo Spirito Santo per stabilirvi la sua dimora&#8230;, io non appartengo pi\u00f9 a me stesso&#8230;, il mio corpo e la mia anima &#8211; tutt&#8217;intero il mio essere &#8211; sono di Dio&#8230; E questa preghiera sar\u00e0 feconda di risultati pratici, derivanti dalla grande conseguenza che lo stesso Apostolo suggerisce: \u00abGlorificate Dio nel vostro corpo\u00bb [1 &#8220;Cor&#8221; 6, 20].<\/p>\n<p style=\"text-align: justify;\">D&#8217;altra parte, non potete ignorare che soltanto fra quelli che comprendono e valutano in tutta la loro profondit\u00e0 le considerazioni che abbiamo fatto sull&#8217;amore umano pu\u00f2 sorgere la comprensione ineffabile di cui parla Ges\u00f9 [Cfr &#8220;Mt &#8220;19, 2], quella che \u00e8 dono squisitamente divino e spinge a dare per intero il corpo e l&#8217;anima al Signore, offrendogli il cuore indiviso, senza la mediazione dell&#8217;amore terreno.<\/p>\n<p style=\"text-align: justify;\">Ormai devo concludere, figli miei. Vi dicevo all&#8217;inizio che le mie parole volevano annunciarvi qualcosa della grandezza e della misericordia di Dio. Ritengo di averlo fatto dicendovi di vivere santamente la vita ordinaria: perch\u00e9 una vita santa nel mezzo della realt\u00e0 temporale &#8211; una vita senza risonanza, semplice, verace &#8211; non \u00e8 forse oggi la manifestazione pi\u00f9 commovente delle &#8220;magnalia Dei&#8221; [&#8220;Sir &#8220;18, 4], delle mirabili prove di misericordia che Dio ci ha dato sempre, e che sempre continua a darci per salvare il mondo?<\/p>\n<p style=\"text-align: justify;\">Adesso vi chiedo, con le parole del salmista, di unirvi alla mia preghiera e alla mia lode: \u00ab&#8221;Magnificate Dominum mecum, et extollamus nomen eius simul&#8221;\u00bb [&#8220;Sal &#8220;33, 4]; magnificate con me il Signore, ed esaltiamo tutti assieme il suo nome. In altri termini, figli miei, viviamo di fede.<\/p>\n<p style=\"text-align: justify;\">Prendiamo lo scudo della fede, l&#8217;elmo della salvezza, e la spada dello Spirito che \u00e8 la Parola di Dio. Cos\u00ec ci sprona l&#8217;apostolo san Paolo nell&#8217;epistola agli Efesini [Cfr &#8220;Ef&#8221; 6, 2 ss], di cui un momento fa veniva data lettura liturgica.<\/p>\n<p style=\"text-align: justify;\">Fede, una virt\u00f9 di cui tanto abbiamo bisogno noi cristiani, e in modo tutto speciale in questo \u00abanno della Fede\u00bb promulgato dal nostro amatissimo Santo Padre, il papa Paolo VI: perch\u00e9 senza fede viene a mancare la base stessa per la santificazione della vita di tutti i giorni.<\/p>\n<p style=\"text-align: justify;\">Fede viva in questo momento, perch\u00e9 ci accostiamo al \u00ab&#8221;mysterium fidei&#8221;\u00bb [1 &#8220;Tm&#8221; 3, 9], la Sacra Eucaristia; perch\u00e9 stiamo per prendere parte a questa Pasqua del Signore che riassume e realizza le misericordie di Dio verso gli uomini.<\/p>\n<p style=\"text-align: justify;\">Fede, figli miei, per professare che fra pochi istanti, su quest&#8217;ara, si rinnover\u00e0 \u00abl&#8217;opera della nostra redenzione\u00bb [Preghiera sulle offerte nella Messa della domenica IX dopo Pentecoste]. Fede, per assaporare il &#8220;Credo&#8221; e avvertire intorno a questo altare e in questa Assemblea la presenza di Cristo, che ci rende \u00ab&#8221;cor unum et anima una&#8221;\u00bb [&#8220;At&#8221; 4, 32], un solo cuore e una sola anima; e ci fa diventare famiglia, Chiesa, una, santa, cattolica, apostolica e romana, che per noi \u00e8 come dire universale<\/p>\n<p style=\"text-align: justify;\">Fede, infine, figlie e figli carissimi, per dimostrare al mondo che queste non sono cerimonie e parole, ma realt\u00e0 divina, offrendo agli uomini la testimonianza di una vita ordinaria santificata nel nome del Padre e del Figlio e dello Spirito Santo e di Santa Maria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Testo dell&#8217;omelia pronunciata nel campus dell&#8217;Universit\u00e0 di Navarra, l&#8217;8 ottobre 1967 da San Josemar\u00eda Escriv\u00e0. Mons. Javier Echevarr\u00eda presentava cos\u00ec quest&#8217;omelia durante il XIII Simposio sulla Storia della Chiesa in Spagna e in America: \u201cAmare il mondo significa amarlo in Dio e per Dio. In questa determinazione si radica il messaggio di questo sacerdote santo. &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/amare-il-mondo-appassionatamente\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":34603,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[1249],"class_list":["post-2244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","tag-josemaria-escriva-de-balaguer","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Amare il mondo appassionatamente - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/amare-il-mondo-appassionatamente\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Amare il mondo appassionatamente - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/amare-il-mondo-appassionatamente\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2006-10-04T07:01:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-13T11:11:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Josemar\u00eda-Escriv\u00e0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"19 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/amare-il-mondo-appassionatamente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/amare-il-mondo-appassionatamente\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Amare il mondo appassionatamente\",\"datePublished\":\"2006-10-04T07:01:38+00:00\",\"dateModified\":\"2016-06-13T11:11:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/amare-il-mondo-appassionatamente\\\/\"},\"wordCount\":3782,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/amare-il-mondo-appassionatamente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/10\\\/Josemar\u00eda-Escriv\u00e0.jpg\",\"keywords\":[\"Josemar\u00eda Escriv\u00e1 de Balaguer\"],\"articleSection\":[\"Chiesa\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/amare-il-mondo-appassionatamente\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/amare-il-mondo-appassionatamente\\\/\",\"name\":\"Amare il mondo appassionatamente - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/amare-il-mondo-appassionatamente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/amare-il-mondo-appassionatamente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/10\\\/Josemar\u00eda-Escriv\u00e0.jpg\",\"datePublished\":\"2006-10-04T07:01:38+00:00\",\"dateModified\":\"2016-06-13T11:11:58+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/amare-il-mondo-appassionatamente\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/amare-il-mondo-appassionatamente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/amare-il-mondo-appassionatamente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/10\\\/Josemar\u00eda-Escriv\u00e0.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/10\\\/Josemar\u00eda-Escriv\u00e0.jpg\",\"width\":275,\"height\":183},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/amare-il-mondo-appassionatamente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Amare il mondo appassionatamente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Amare il mondo appassionatamente - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/amare-il-mondo-appassionatamente\/","og_locale":"it_IT","og_type":"article","og_title":"Amare il mondo appassionatamente - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/amare-il-mondo-appassionatamente\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2006-10-04T07:01:38+00:00","article_modified_time":"2016-06-13T11:11:58+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Josemar\u00eda-Escriv\u00e0.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"19 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/amare-il-mondo-appassionatamente\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/amare-il-mondo-appassionatamente\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Amare il mondo appassionatamente","datePublished":"2006-10-04T07:01:38+00:00","dateModified":"2016-06-13T11:11:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/amare-il-mondo-appassionatamente\/"},"wordCount":3782,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/amare-il-mondo-appassionatamente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Josemar\u00eda-Escriv\u00e0.jpg","keywords":["Josemar\u00eda Escriv\u00e1 de Balaguer"],"articleSection":["Chiesa"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/amare-il-mondo-appassionatamente\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/amare-il-mondo-appassionatamente\/","name":"Amare il mondo appassionatamente - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/amare-il-mondo-appassionatamente\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/amare-il-mondo-appassionatamente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Josemar\u00eda-Escriv\u00e0.jpg","datePublished":"2006-10-04T07:01:38+00:00","dateModified":"2016-06-13T11:11:58+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/amare-il-mondo-appassionatamente\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/amare-il-mondo-appassionatamente\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/amare-il-mondo-appassionatamente\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Josemar\u00eda-Escriv\u00e0.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/10\/Josemar\u00eda-Escriv\u00e0.jpg","width":275,"height":183},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/amare-il-mondo-appassionatamente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Amare il mondo appassionatamente"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2244"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2244\/revisions"}],"predecessor-version":[{"id":34604,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2244\/revisions\/34604"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/34603"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}