{"id":2230,"date":"2006-09-21T09:47:50","date_gmt":"2006-09-21T07:47:50","guid":{"rendered":""},"modified":"2015-12-02T15:51:41","modified_gmt":"2015-12-02T14:51:41","slug":"e-la-bibbia-del-giornalismo-liberal-divent-il-corano","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\/","title":{"rendered":"E la Bibbia del giornalismo liberal divent&ograve; il Corano"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/09\/MewYork-Times.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-28516\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/09\/MewYork-Times.jpg\" alt=\"MewYork Times\" width=\"250\" height=\"172\" \/><\/a>Il Foglio<\/strong> 18 settembre 2006<\/div>\n<p style=\"text-align: center;\"><strong>Giuliano Ferrara<\/strong><\/p>\n<p style=\"text-align: justify;\">La Bibbia o il Corano del giornalismo li\u00adberal e politicamente corretto, il <em>New York Times<\/em>, ha scritto sabato nella rubrica dei suoi editoriali, una sequenza di enor\u00admit\u00e0, che ricalcano alla lettera le aggres\u00adsioni islamiche a Benedetto XVI dopo il suo discorso di Regensburg.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Pericolose enormit\u00e0, che dimostrano la chiusura del cerchio magico dentro il quale si collocano ormai il correttismo politico occidentale e l&#8217;islamismo politico della ummah maomet\u00adtana. C&#8217;\u00e8 da sperare che di fronte a questo manifesto dell&#8217;intolleranza verso di s\u00e9, ver\u00adso la propria cultura, verso i propri sacri principi di libert\u00e0 del pensiero, si muova\u00adno, non in difesa del Papa, che non ne ha bisogno, ma in difesa di se stessi, gli intel\u00adlettuali e i politici europei che conoscono la differenza tra tolleranza e intolleranza, e predicano stucchevolmente tolleranza e dialogo a noi estremisti dello scontro di ci\u00advilt\u00e0, cosiddetti.<\/p>\n<p style=\"text-align: justify;\">La prima enormit\u00e0: \u00abIl Papa ha insulta\u00adto i musulmani, citando una descrizione dell&#8217;islam, risalente al XIV secolo, come cattivo e disumano\u00bb.<\/p>\n<p style=\"text-align: justify;\">La seconda enormit\u00e0: \u00abI leader musul\u00admani di tutto il mondo hanno denunciato nelle parole del Papa una visione falsa e ispirata al pregiudizio dell&#8217;islam. Per mol\u00adti musulmani la guerra santa o jihad \u00e8 una lotta spirituale e non un appello alla vio\u00adlenza. Ed essi denunciano il suo perverti\u00admento da parte degli estremisti che usano il jihad per giustificare assassinio e terro\u00adrismo\u00bb.<\/p>\n<p style=\"text-align: justify;\">La terza enormit\u00e0: \u00abNon \u00e8 la prima volta che il Papa fomenta la discordia tra cri\u00adstiani e musulmani. Nel 2004, quando era ancora il capo dei teologi del Vaticano, parl\u00f2 contro l&#8217;ingresso della Turchia nell&#8217;Unione europea, perch\u00e9 la Turchia, in quanto paese musulmano, era stata &#8220;in permanente contrasto con l&#8217;Europa&#8221;\u00bb.<\/p>\n<p style=\"text-align: justify;\">La quarta e finale enormit\u00e0: \u00abIl mondo ascolta con attenzione le parole di ogni Papa. \u00c8 tragico e pericoloso quando esse alimentano la discordia, per scelta delibe\u00adrata o per negligenza. Il Papa deve offrire con parole persuasive le sue scuse, dimo\u00adstrando che le parole possono anche gua\u00adrire le piaghe\u00bb.<\/p>\n<p style=\"text-align: justify;\">Quando diciamo che il correttismo poli\u00adtico ricalca alla lettera l&#8217;islamismo politi\u00adco (e lo diciamo da tempo, ma non avevamo mai avuto una dimostrazione tanto persua\u00adsiva delle nostre ragioni), parliamo sul se\u00adrio. Nell&#8217;editoriale del NYT non esiste un punto di vista culturale occidentale, figlio . della nostra cultura laica, del nostro modo filosofico e politico di intendere il dialogo o la disputa in materie di fede e di ragione.<\/p>\n<p style=\"text-align: justify;\">Non ci si pone nemmeno il problema se le parole di un Papa che parla di religione, di filosofia, di cultura e di civilt\u00e0 politiche debbano essere discusse civilmente, contrastate laicamente, anzich\u00e9 dannate e messe in croce con gesti e linguaggi da ta\u00adgliatori di teste, da emittenti di fatwa che parlano contro l&#8217;infedele a nome sia della comunit\u00e0, sia del clero islamico, sia degli stati islamici (dall&#8217;universit\u00e0 cairota Al Azhar al Parlamento del Pakistan, fino ai gruppi jihadisti della provincia irachena di Anbar dove i guerriglieri sunniti minac\u00adciano, mediante avviso in moschea, di ster\u00adminare i cristiani se il Papa cattolico non dovesse scusarsi).<\/p>\n<p style=\"text-align: justify;\">Quel testo del New York Times quasi in\u00adcredibile a occhi e orecchie liberali, ma\u00adnifesto involontario della trasformazione del liberalismo in ideologia carceraria della libert\u00e0 in nome del rispetto della di\u00adversit\u00e0, retrodata la cultura dei giornalisti che lo sottoscrivono ai secoli in cui l&#8217;islam si chiuse a riccio, interruppe ogni possibi\u00adlit\u00e0 di discussione e analisi e interpreta\u00adzione del testo coranico e della precetti\u00adstica legale o sharia. E un editoriale scrit\u00adto a Cordoba nel XII secolo dai censori della filosofia araba.<\/p>\n<p style=\"text-align: justify;\">\u00c8 un testo che mo\u00adstra in modo compiuto che l&#8217;ultima onda\u00adta del secolarismo e del laicismo occiden\u00adtale ha condotto, per paura, per vilt\u00e0, per dabbenaggine, per ignoranza, al regresso verso l&#8217;irrazionalismo e il nichilismo oscu\u00adrantista, naturalmente mascherato da ar\u00adgomenti multiculturalisti e dal mito del dialogo inter-religioso senza premesse e senza conseguenze, dialogo in s\u00e9, cio\u00e8 re\u00adsa relativista all&#8217;inesistenza della verit\u00e0, all&#8217;impossibilit\u00e0 della ricerca della verit\u00e0 come matrice del dialogo.<\/p>\n<p style=\"text-align: justify;\">L&#8217;editoriale accetta che il Papa abbia in\u00adsultato l&#8217;islam per avere criticato una par\u00adte dottrinale importante del corpus cora\u00adnico e della prassi islamica della conqui\u00adsta e del califfato (prima enormit\u00e0). La cri\u00adtica teologica diventa un caso politico e si trasforma in un insulto solo in un mondo in cui regna l&#8217;intolleranza. O no?<\/p>\n<p style=\"text-align: justify;\">L&#8217;editoriale sposa la protesta dei leader musulmani di tutto il mondo e abbraccia senza alcun dubbio la loro versione di ci\u00f2 che \u00e8 e di ci\u00f2 che non \u00e8 guerra santa jiha\u00addista, con l&#8217;effetto involontariamente tra\u00adgicomico di cancellare oltre alla storia e alla teologia, di cui gli editorialisti del NYT non sono tenuti a sapere, i fatti.<\/p>\n<p style=\"text-align: justify;\">Parliamo di quel che \u00e8 sotto gli occhi del\u00adl&#8217;occidente e dell&#8217;oriente, cio\u00e8 appunto il risveglio jiha\u00addista che ha portato per esempio diciannove bravi musulmani a di\u00adrigere un paio di aerei di linea sulle torri che facevano ombra sul Downtown Manhattan, dove quel giornale si pubblica, e migliaia di altri a uccidere cristiani ed ebrei (e molti musulmani) in nome di Dio clemente e misericordioso.<\/p>\n<p style=\"text-align: justify;\">L&#8217;editoriale trova censurabile che un teo\u00adlogo abbia ricordato nel 2004 una certa ini\u00admicizia storica tra la Turchia e l&#8217;Europa, cio\u00e8 la verit\u00e0 della storia, quella verit\u00e0 che gli accademici liberal amici dei giornalisti liberal vorranno forse riscrivere in qualche cattedra di Lepanto studies, dopo avere gi\u00e0 abbondantemente dannato le crociate co\u00adme culmine dell&#8217;incivilt\u00e0 occidentale.<\/p>\n<p style=\"text-align: justify;\">Infine le scuse. Anche qui, ricalco alla lettera degli argomenti delle cattedre islamiche di ogni tipo, dal terrorista al primo ministro di Hamas, dallo sceicco Al Tantawi al Parlamento Pakistano al porta\u00advoce della religione islamica di Stato in Turchia. Roba forte, fortissima, roba da pazzi. Le scuse per aver pensato e per aver detto. Per aver esercitato la libert\u00e0 di predicare la virt\u00f9 del Logos, di una ragione che comprende la fede e di una fede che si esprime anche attraverso la ragione in uno statuto di vera analogia tra l\u2019umano e il di vino.<\/p>\n<p style=\"text-align: justify;\">Eccoli, i laicisti dell&#8217;autocritica papale su suggerimento intollerante e su decreto delle autorit\u00e0 politico-religiose dell&#8217;islam &#8220;moderato&#8221;. Eccoli, gli immemori! Gli occidentali squinternati verso i quali vorremmo si volgessero le attenzioni di persone serie come i Rusconi, come le Mancina, come i Cacciari, come i Finkielkraut, come i Gluksmann e pi\u00f9 in generale le attenzioni critiche di un&#8217;intelligenza ormai introvabile nei media, nelle universit\u00e0, nelle elite europee.<\/p>\n<p style=\"text-align: justify;\">Ci resta solo il popolo, e i venti milioni di copie vendute dalla Fallaci. Ma \u00e8 ancora poco. I Vogliamo il resto. Vogliamo un piccolo esercizio di ragione laica in difesa del Papa cattolico aggredito e ricattato dalle richieste intolleranti di scuse multiculturali, che vengano dai mullah, dal laicissimo Ahmadinejad o dal Corano del giornalismo liberal, poco importa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Foglio 18 settembre 2006 Giuliano Ferrara La Bibbia o il Corano del giornalismo li\u00adberal e politicamente corretto, il New York Times, ha scritto sabato nella rubrica dei suoi editoriali, una sequenza di enor\u00admit\u00e0, che ricalcano alla lettera le aggres\u00adsioni islamiche a Benedetto XVI dopo il suo discorso di Regensburg.<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":28516,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[110,16,103],"tags":[161],"class_list":["post-2230","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-benedetto-xvi","category-islam","category-laicismo","tag-islam-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>E la Bibbia del giornalismo liberal divent&ograve; il Corano - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"E la Bibbia del giornalismo liberal divent&ograve; il Corano - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2006-09-21T07:47:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-12-02T14:51:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/09\/MewYork-Times.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"271\" \/>\n\t<meta property=\"og:image:height\" content=\"186\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"E la Bibbia del giornalismo liberal divent&ograve; il Corano\",\"datePublished\":\"2006-09-21T07:47:50+00:00\",\"dateModified\":\"2015-12-02T14:51:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\\\/\"},\"wordCount\":1172,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/09\\\/MewYork-Times.jpg\",\"keywords\":[\"islam\"],\"articleSection\":[\"Benedetto XVI\",\"Islam\",\"Laicismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\\\/\",\"name\":\"E la Bibbia del giornalismo liberal divent&ograve; il Corano - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/09\\\/MewYork-Times.jpg\",\"datePublished\":\"2006-09-21T07:47:50+00:00\",\"dateModified\":\"2015-12-02T14:51:41+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/09\\\/MewYork-Times.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/09\\\/MewYork-Times.jpg\",\"width\":271,\"height\":186},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E la Bibbia del giornalismo liberal divent&ograve; il Corano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"E la Bibbia del giornalismo liberal divent&ograve; il Corano - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\/","og_locale":"it_IT","og_type":"article","og_title":"E la Bibbia del giornalismo liberal divent&ograve; il Corano - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2006-09-21T07:47:50+00:00","article_modified_time":"2015-12-02T14:51:41+00:00","og_image":[{"width":271,"height":186,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/09\/MewYork-Times.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"E la Bibbia del giornalismo liberal divent&ograve; il Corano","datePublished":"2006-09-21T07:47:50+00:00","dateModified":"2015-12-02T14:51:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\/"},"wordCount":1172,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/09\/MewYork-Times.jpg","keywords":["islam"],"articleSection":["Benedetto XVI","Islam","Laicismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\/","name":"E la Bibbia del giornalismo liberal divent&ograve; il Corano - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/09\/MewYork-Times.jpg","datePublished":"2006-09-21T07:47:50+00:00","dateModified":"2015-12-02T14:51:41+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/09\/MewYork-Times.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/09\/MewYork-Times.jpg","width":271,"height":186},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/e-la-bibbia-del-giornalismo-liberal-divent-il-corano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"E la Bibbia del giornalismo liberal divent&ograve; il Corano"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2230"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2230\/revisions"}],"predecessor-version":[{"id":28517,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2230\/revisions\/28517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/28516"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}