{"id":2162,"date":"2006-07-28T10:49:21","date_gmt":"2006-07-28T08:49:21","guid":{"rendered":""},"modified":"2015-01-03T19:34:16","modified_gmt":"2015-01-03T18:34:16","slug":"tempo-di-autogestione","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tempo-di-autogestione\/","title":{"rendered":"Tempo di autogestione"},"content":{"rendered":"<div style=\"text-align: center;\">tratto da <strong>Tempi<\/strong>, anno X, 9.12.2004, n. 50, p. 30.<\/div>\n<p style=\"text-align: center;\">di <strong>Alfonso Indelicato<\/strong><\/p>\n<p style=\"text-align: justify;\">Quest&#8217;anno nella mia scuola l&#8217;autogestione pare che inizier\u00e0 il 13 dicembre. Di solito funziona cos\u00ec. Nei giorni immediatamente precedenti i ragazzi del collettivo si mettono d&#8217;accordo con quelli eletti nel ConsDist per decidere di che parlare. Poi stabiliscono in quali aule si tratter\u00e0 di questa cosa, in quale di quella.<\/p>\n<p style=\"text-align: justify;\"><!--more--><\/p>\n<p style=\"text-align: justify;\">Preparano le etichette, le appiccicano sulle porte: &#8220;aula musica&#8221;, &#8220;aula tossicodipendenze&#8221;, &#8220;aula occulto&#8221;, &#8220;aula sesso&#8221;. Scelgono i membri del servizio d&#8217;ordine (di solito gli elementi pi\u00f9 maneschi e meno affidabili, stagionati primini di diciott&#8217;anni incazzosi e dallo sguardo torvo) e gli mettono al braccio un pezzo di stoffa che fa la divisa. Poi tutto incomincia.<\/p>\n<p style=\"text-align: justify;\">Il primo giorno vi \u00e8 effettivamente una certa organizzazione: gli improvvisati vigilantes girano per i corridoi e ricacciano a spintoni nelle aule tutti quelli che incontrano in giro, di fumo ne circola poco, non si registrano casi di coma etilico. Nelle aule improvvisati oratori tengono banco, nel gruppo musicale si suona e si balla, nel gruppo dell&#8217;occulto chiss\u00e0 che caspita fanno, in quello del sesso lasciamo perdere.<\/p>\n<p style=\"text-align: justify;\">Il secondo giorno c&#8217;\u00e8 gi\u00e0 qualche sbavatura: nelle aule i lavori languono (tranne, presumo, nell'&#8221;aula sesso&#8221;) e il numero dei deambulanti nei corridoi \u00e8 aumentato. Ragazzi e ragazze si slinguano per le scale, intrecciati come anaconda gli uni alle altre. Scoppiano le prime risse fra servizio d&#8217;ordine e anarchici individualisti che si fanno in giro i *** loro: prime ecchimosi e prime (leggere) tumefazioni. Il terzo giorno si tenta ancora di tenere la disciplina, ma il caos tracima ormai da tutte le parti&#8230;<\/p>\n<p style=\"text-align: justify;\">Dal quarto giorno in poi, \u00e8 il pandemonio pi\u00f9 totale. Oltre agli spacciatori interni &#8211; quelli che si sono iscritti a scuola per portare avanti il loro commercio sotto la protezione della legge (parlo dello &#8220;Statuto delle studentesse e degli studenti&#8221;) &#8211; arrivano quelli da fuori, perch\u00e9 nel raggio di dieci chilometri si \u00e8 saputo che l&#8217;Istituto professionale *** \u00e8 in autogestione.<\/p>\n<p style=\"text-align: justify;\">Ci sono un mucchio di clienti abituali da raggiungere, ma c&#8217;\u00e8 anche un nuovo mercato da creare&#8230; decine e decine di primini, che non si sono mai nemmeno fatti una canna, innocenti, vergini, ***, con un bel mucchietto di soldi in tasca, che aspettano solo di essere svezzati&#8230;<\/p>\n<p style=\"text-align: justify;\">Ne becchi qualcuno nei cessi, dico dei pusher, e gli fai: \u00abE tu chi sei? Non sei di questa scuola\u00bb. Quello ti risponde: \u00abE tu che *** vuoi?\u00bb, e ti guarda fermo e provocatorio ancora con le pasticche in mano. Ora tu potresti, con la forza dei tuoi cinquant&#8217;anni ancora intatti, spaccargli gli incisivi con un diretto ben assestato. Ma ci pensi, poi, il casino?<\/p>\n<p style=\"text-align: justify;\">Ci pensi ai magistrati democratici, ai sociologi umanisti, agli psicologi basagliani? Ai colleghi della Commissione Salute? Ci pensi ai preti buonisti? Perdono! Perdono! Ma ha fatto scoppiare il cervello a quante persone! Emb\u00e8? Chi sei tu per giudicare? Lo hai perdonato? Di&#8217;, lo hai perdonato? Noo? Ma che *** di cristiano sei? E le mamme, le mamme! \u00abFiglio, figlio mio, cos\u00ec buono, generoso, mai dato grattacapi, anzi, portava i soldi a casa, me l&#8217;ha rovinato, chillo fetente&#8230;\u00bb. Per carit\u00e0 ragazzi! Fate, fate pure, accomodatevi&#8230;<\/p>\n<p style=\"text-align: justify;\">I giorni passano. Le aule diventano stalle, i corridoi sterquilini, le rampe delle scale lupanari&#8230; Intanto la maggior parte degli insegnanti se ne sta rintanata in aula professori a leggere Repubblica o imboscata da qualche altra parte. Capita che un gruppo di ragazzi stufi dell&#8217;andazzo rintraccia uno dei suoi prof e gli chiede di fare lezione (\u00abAbbiamo trovato un&#8217;aula libera!\u00bb, gli bisbigliano all&#8217;orecchio con fare da cospiratori).<\/p>\n<p style=\"text-align: justify;\">Allora il prof solleva stancamente gli occhi da Repubblica, li spalanca, fa sussiegoso la boccuccia a cul di gallina e dice: \u00abMa perch\u00e9? State vivendo un&#8217;esperienza formativa, no?\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>tratto da Tempi, anno X, 9.12.2004, n. 50, p. 30. di Alfonso Indelicato Quest&#8217;anno nella mia scuola l&#8217;autogestione pare che inizier\u00e0 il 13 dicembre. Di solito funziona cos\u00ec. Nei giorni immediatamente precedenti i ragazzi del collettivo si mettono d&#8217;accordo con quelli eletti nel ConsDist per decidere di che parlare. Poi stabiliscono in quali aule si &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tempo-di-autogestione\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[233],"class_list":["post-2162","post","type-post","status-publish","format-standard","hentry","category-scuola-ed-educazione","tag-scuola","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tempo di autogestione - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tempo-di-autogestione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tempo di autogestione - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tempo-di-autogestione\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2006-07-28T08:49:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-01-03T18:34:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"163\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tempo-di-autogestione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tempo-di-autogestione\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Tempo di autogestione\",\"datePublished\":\"2006-07-28T08:49:21+00:00\",\"dateModified\":\"2015-01-03T18:34:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tempo-di-autogestione\\\/\"},\"wordCount\":626,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"keywords\":[\"scuola\"],\"articleSection\":[\"Scuola ed educazione\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tempo-di-autogestione\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tempo-di-autogestione\\\/\",\"name\":\"Tempo di autogestione - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"datePublished\":\"2006-07-28T08:49:21+00:00\",\"dateModified\":\"2015-01-03T18:34:16+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tempo-di-autogestione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tempo-di-autogestione\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/tempo-di-autogestione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tempo di autogestione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tempo di autogestione - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tempo-di-autogestione\/","og_locale":"it_IT","og_type":"article","og_title":"Tempo di autogestione - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tempo-di-autogestione\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2006-07-28T08:49:21+00:00","article_modified_time":"2015-01-03T18:34:16+00:00","og_image":[{"width":600,"height":163,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna.gif","type":"image\/gif"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tempo-di-autogestione\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tempo-di-autogestione\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Tempo di autogestione","datePublished":"2006-07-28T08:49:21+00:00","dateModified":"2015-01-03T18:34:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tempo-di-autogestione\/"},"wordCount":626,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"keywords":["scuola"],"articleSection":["Scuola ed educazione"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tempo-di-autogestione\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tempo-di-autogestione\/","name":"Tempo di autogestione - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"datePublished":"2006-07-28T08:49:21+00:00","dateModified":"2015-01-03T18:34:16+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tempo-di-autogestione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tempo-di-autogestione\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/tempo-di-autogestione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Tempo di autogestione"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2162"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2162\/revisions"}],"predecessor-version":[{"id":16173,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2162\/revisions\/16173"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}