{"id":2058,"date":"2006-06-01T00:00:00","date_gmt":"2006-05-31T22:00:00","guid":{"rendered":""},"modified":"2016-04-27T12:22:36","modified_gmt":"2016-04-27T10:22:36","slug":"la-scienza-magra","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-scienza-magra\/","title":{"rendered":"La scienza magra"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-33510 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/06\/crisi.jpg\" alt=\"crisi\" width=\"200\" height=\"199\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/06\/crisi.jpg 200w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/06\/crisi-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/>Avvenire<\/strong>, 7 maggio 2006<\/div>\n<p style=\"text-align: justify;\"><em>\u00abCi siamo limitati in questa analisi ai decenni della crisi delle scienze e quindi a quei fatti che hanno caratterizzato il clima dell\u2019inizio del novecento. Poich\u00e9 da l\u00ec comincia il grande declino che oggi,nel terzo millennio, appare in tutta la sua drammaticit\u00e0, fino a fare del presente un tempo dominato dalla stupidit\u00e0, da un\u2019involuzione che sembra apocalittica non tanto per ordine di un dio stanco, ma di un uomo che si \u00e8 perso, senza riferimenti e senza pi\u00f9 princ\u00ecpi.<\/em><\/p>\n<p style=\"text-align: center;\"><strong>Vittorino Andreoli<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\"><strong>1 <\/strong>Il percorso della scienza vale anche per la filosofia: la crisi del kantismo \u00e8 il segnale che anche l\u2019ultima fortezza si rompe.<\/div>\n<p style=\"text-align: justify;\"><strong>2<\/strong> Il mistero non \u00e8 pi\u00f9 un primitivismo che aspetta di essere superato dalla civilt\u00e0 della ragione, come sognava Vico.<\/p>\n<p>3 Freud fa una operazione elegantemente disperata, quella di dare un senso all\u2019ignoto e di razionalizzare l\u2019empirico.<\/p>\n<p><strong>4<\/strong> Si staglia un pericolo mortale non solo per il singolo, ma per una intera societ\u00e0 e forse per un\u2019intera civilt\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>SCIENZA E TECNOLOGIA<\/strong>. Non \u00e8 facile dar compiutezza a un viaggio nella scienza, anche se limitato allo scenario in auge tra la fine dell\u2019Ottocento e il primo decennio del Novecento: una fase in cui nel giro di pochi anni cambia il clima, e una scienza definita fino a quel momento &#8220;classica&#8221;, nel senso di un sapere elevato su basi indiscutibili e sicure, ritenute quindi perenni, si sovverte ed entra in crisi.<\/p>\n<p style=\"text-align: justify;\">\u00c8 importante rilevare questo aspetto, perch\u00e9 la scienza molto difficilmente la si coglie nell\u2019insieme. Abitualmente ci si sofferma sul particolare risultato colto da una disciplina, e su questo ci si ferma, considerando il resto come pura elucubrazione che non interessa gli scienziati. Una meta-scienza, che si gioca in un \u00e0mbito non lontano dalla filosofia e che dagli scienziati viene percepita come una congettura, mero gioco di parole in un percorso della mente, mentre l\u2019\u00e0mbito proprio della scienza \u00e8 il particolare.<\/p>\n<p style=\"text-align: justify;\">Uno degli esempi pi\u00f9 significativi di tale discrepanza, la diversa sensazione cio\u00e8 tra l\u2019analisi di un dato e l\u2019insieme dei dati scientifici, lo si trova indubbiamente nella figura quasi eroica dello scienziato Albert Einstein e nella sua scoperta per eccellenza, la relativit\u00e0. Indubbiamente il risultato da lui raggiunto \u00e8 straordinario, poich\u00e9 scopre una visione che nel campo della fisica scombina, e in parte sostituisce, la precedente, ma che in s\u00e9 appartiene a quelle scoperte che sanno di crisi, crisi dei princ\u00ecpi in generale: come se ci si venisse a trovare in un mondo diverso, e alle precedenti certezze dovesse subentrare solo una sorta di relativismo aperto.<\/p>\n<p style=\"text-align: justify;\">Sono affascinato dall\u2019\u00e8ra di Einstein, che considero uno dei pi\u00f9 grandi fisici della storia. Questi ha contribuito a mutare non solo il campo degli studi cui si era applicato, ma la stessa percezione del mondo e dell\u2019uomo nel mondo, e ad abbattere certezze che almeno da tre secoli \u2013 dai tempi di Newton \u2013 apparivano consolidate. La scienza non \u00e8 pi\u00f9 un forziere di certezze e verit\u00e0, che anzi, proprio a partire dalla crisi scoppiata a cavallo tra Ottocento e Novecento, appaiono termini superficiali, da abbandonare.<\/p>\n<p style=\"text-align: justify;\">Si pu\u00f2 legittimamente affermare che l\u2019azione condotta in quei decenni a riguardo della scienza classica \u00e8 pi\u00f9 &#8220;<em>destruens<\/em>&#8221; che non caratterizzata da una fase costruttiva nuova, seppur non vi sia dubbio che per ricostruire bisogna prima demolire. Ma se la distruzione si \u00e8 snodata nell\u2019arco di qualche decennio, \u00e8 comprensibile che una nuova visione del mondo non ci sia ancora, e quindi che un secolo non sia stato ancora sufficiente per ricostruirla.<\/p>\n<p style=\"text-align: justify;\">Guardando alla storia si ha l\u2019impressione che esistano climi culturali tra loro in successione: a quelli di grande costruzione ne subentrano altri di incertezza e di scompaginamento.<\/p>\n<p style=\"text-align: justify;\">Nel Rinascimento tutto era come fiorito, e infatti si assist\u00e9 a una grande innovazione nelle arti e nelle lettere, mentre la scienza \u2013 quella di Bacone e Galilei \u2013, non ancora nata, era forse in preparazione.<\/p>\n<p style=\"text-align: justify;\">Poi ci sono fasi che sembrano di distruzione, e persino di vuoto, in cui \u00e8 difficile reperire qualche cosa, qualche dimensione degna almeno di essere ricordata. Il che vale puntualmente per il periodo storico al quale ci stiamo dedicando, all\u2019insegna di una distruttivit\u00e0 che impressiona e che vediamo specchiarsi persino nella pittura, in particolare nell\u2019espressionismo tedesco, come nel senso di precariet\u00e0 e di minaccia che aveva il volto della guerra. Si aggiunga la situazione di crisi che colpisce anche l\u2019economia degli Stati Uniti nel 1929; come dire, pure il versante della sicurezza materiale e dello sviluppo vede la recessione, con la gente che muore letteralmente di fame e l\u2019alcolismo che si fa endemico.<\/p>\n<p style=\"text-align: justify;\">\u00c8 la scienza che genera una tecnologia straordinaria s\u00ec, ma anche apportatrice di morte. Durante il primo conflitto mondiale si avverte l\u2019orrore dei caccia bombardieri, e le micidiali armi per la distruzione del nemico singolo e di massa. I treni diventano mezzi di collegamento che facilitano lo spostamento degli eserciti d\u2019occupazione.<\/p>\n<p style=\"text-align: justify;\">Per chi volesse vedere poi nel secondo conflitto mondiale la prosecuzione del primo, ecco che il dramma della scienza applicata alla guerra diventa ancor pi\u00f9 tragico, poich\u00e9 dalla fisica delle particelle si arriva alla bomba atomica, strumento che solo a Hiroshima e Nagasaki annienta due intere citt\u00e0, lasciando ai sopravvissuti i codici di morte addosso, per passarli alle generazione successive a causa delle mutazioni genetiche sub\u00ecte.<\/p>\n<p style=\"text-align: justify;\">Un dramma, questo, in cui si collocano \u2013 a segno di un malessere diffuso \u2013 le storie emblematiche di due fisici \u2013 Ettore Majorana e Robert J. Oppenheimer \u2013 che di fronte alla bomba atomica entrano in crisi. Majorana scompare, forse in un monastero, o forse suicida nelle acque del Mediterraneo, mentre Oppenheimer (responsabile delle ricerche a Los Alamos) \u00e8 processato con l\u2019accusa di avere trasmesso informazioni sulla &#8220;bomba&#8221; all\u2019Unione Sovietica di Stalin, e finir\u00e0 per pentirsi dei sui stessi studi.<\/p>\n<p style=\"text-align: justify;\">Si giunge all\u2019inquinamento atmosferico, passando per i danni prodotti dalla ricerca, di cui la talidomide \u00e8 un esempio lampante nel campo della medicina e della farmacologica. Assieme a molte vittorie scientifiche nei singoli settori e a indubitabili vantaggi in vari campi, \u00e8 difficile non aver presenti anche i disastri. Si fa pressante ed endemica la paura per il rischio del nucleare. Basterebbe citare Cernobyl, ma anche la diossina della nostra Seveso, e poi guardare alle tante guerre &#8220;minori&#8221;, a cominciare dal Vietnam, e alla tecnologia nucleare che si \u00e8 sviluppata all\u2019ombra dello scudo spaziale.<\/p>\n<p style=\"text-align: justify;\">A partire da quel primo decennio del Novecento, insomma, si pu\u00f2 individuare una serie continua di catastrofi e procedere a un elenco senza fine dei rischi di morte legati alla scienza, rischi che insidiano il singolo ma anche le masse. Con la tecnologia infatti, la scienza passa dal bacino ristretto degli scienziati a quello assai pi\u00f9 ampio delle popolazioni, che magari non percepiscono la profondit\u00e0 e la specializzazione delle singole ricerche, ma ne avvertono il senso generale e il pericolo per la loro vita.<\/p>\n<p style=\"text-align: justify;\">E qui non si possono non ricordare i problemi legati non solo alla biologia ma anche alla tecnologia sugli embrioni, e quindi agli strumenti per impedire che si origini la vita oppure per interromperla mentre si sviluppa. Comunque la si consideri, si tratta di una dimensione che crea angoscia, e suscita gli interrogativi pi\u00f9 radicali.<\/p>\n<p style=\"text-align: justify;\">Non si pu\u00f2 pi\u00f9 dire insomma che la scienza trovi riparo nel segreto dei laboratori, anche perch\u00e9, diventando essa molto costosa, ha bisogno di grandi supporti e diventa materiale di promozione da parte di chi amministra la societ\u00e0, da coloro cio\u00e8 che devono rendere conto ai cittadini di come il denaro pubblico viene speso. Cos\u00ec, da disciplina che produce certezze, la scienza diventa una via per conoscere i dubbi, fino alla teorizzazione che essa non pu\u00f2 produrre altro che dubbi. Ogni risultato infatti \u00e8 parziale e in pi\u00f9 falsificabile, cio\u00e8 contiene almeno un\u2019apor\u00eca che necessita di correzione. Ciascun dato perci\u00f2 non pu\u00f2 che essere transitorio e parziale.<\/p>\n<p style=\"text-align: justify;\">In altre parole, la scienza appare come una modalit\u00e0 faticosa per ricercare la verit\u00e0, senza incontrarla poi mai, anzi sbagliando per il solo pensiero di riuscire a scoprirla. La scienza apporta, semmai, correzioni a errori, mentre per\u00f2 ne veicola altri: &#8220;verit\u00e0&#8221; storiche transeunti.<\/p>\n<p style=\"text-align: justify;\">Se si osserva bene quanto \u00e8 avvenuto nella fisica di Werner Heisenberg, di Paul Dirac e di Albert Einstein, non si pu\u00f2 certo negare che essa abbia compiuto grandi progressi, ma semplicemente perch\u00e9 aveva tanto da distruggere.\u00a0 Uno scenario che dal Seicento in poi si era solo allargato, al pari di una delle nostre metropoli in espansione continua, come ad esempio Tokyo che ha raggiunto i 26 milioni di abitanti.<\/p>\n<p style=\"text-align: justify;\">Quando ci si chiede perch\u00e9 la ricerca sia oggi cos\u00ec poco sostenuta non si tiene mai conto che \u00e8 diminuita fortemente la fiducia in essa, che non ha pi\u00f9 fascino, essendo anzi percepita come un affare pericoloso e foriero di disgrazie. A questo riguardo, basta considerare l\u2019atteggiamento generalmente adottato nei confronti degli organismi geneticamente modificati, a partire dalle culture agricole.<\/p>\n<p style=\"text-align: justify;\">Ebbene, si tratta di scoperte che la gente non accetta, anche quando gli scienziati si fanno garanti della sicurezza alimentare, e anche in presenza di un\u2019indubbia convenienza a livello di prezzo. Ormai c\u2019\u00e8 paura per ogni innovazione. E trovo che sia difficile convincere il mondo a sostenere una ricerca che fa paura: alcuni eventi drammatici sono ancora assai vivi nella memoria, e per molte famiglie o nazioni ne perdura la realt\u00e0.<\/p>\n<p style=\"text-align: justify;\">Se si pensa al concetto di natura contrapposta a tecnologia e ai sistemi che chiamiamo biologici, si pu\u00f2 senz\u2019altro intravedere questa paura, in parte almeno inconsapevole. La natura non \u00e8 infatti un &#8220;<em>hortus conclausus<\/em>&#8220;, come a suo tempo pensava anche Aristotele, ma un mondo che si \u00e8 fortemente modificato: non solo rispetto all\u2019antico ma anche in confronto a pochi secoli fa.<\/p>\n<p style=\"text-align: justify;\">Un mondo modificato anche da una tecnologia capace di interventi acuti, ben diversi da quelli di cui sono capaci anche scoiattoli e uccelli, animali capaci di apprendere operazioni nuove rispetto al passato. Domina questo scenario un preciso ideale di natura, insieme all\u2019idea che la ricerca e la tecnologia non debbano intaccare la natura medesima, quasi fosse una statua, qualcosa che l\u2019uomo deve rispettare e trattenersi dal rovinare.<\/p>\n<p style=\"text-align: justify;\">\u00c8 di certo possibile far danni, ma non \u00e8 lecito inventare una natura che non esiste e porre in relazione con essa l\u2019uomo come se fosse un soggetto estraneo, che la rovina sadicamente, alla stregua di un d\u00e9mone. Una simile mentalit\u00e0 frena la ricerca e si esprime in un atteggiamento anti-scientifico, magari sostenuto da chi al tempo stesso chiede di sovvenzionare la ricerca. La scienza che doveva soppiantare la filosofia si fa dunque debole, esile, persino malata.<\/p>\n<p style=\"text-align: justify;\"><strong>FILOSOFIA.<\/strong> A questo proposito per\u00f2 non si pu\u00f2 certo dire che la debolezza della scienza abbia incrementato il potere della filosofia. Se ci soffermiamo infatti sugli anni della crisi, a cavallo tra Otto e Novecento, possiamo renderci conto che in realt\u00e0 anche la filosofia si \u00e8 indebolita, sino a diventare filosofia della crisi. Basterebbe citare la fenomenologia, corrente che si forma attorno a Edmund Husserl proprio a partire dai primi anni del Novecento, ma che si allarga a Karl Jaspers e a Ludwig Binswanger. Una visione che si lega all\u2019esperienza, all\u2019essere qui e ora, e quindi alla vita. A conferma di ci\u00f2 basterebbe citare il titolo quanto mai espressivo di un\u2019opera fondamentale di Husserl, \u00abLa crisi delle scienze europee e la fenomenologia trascendentale\u00bb.<\/p>\n<p style=\"text-align: justify;\">Da questa corrente filosofica promana un fascino capace persino di sedurre. Non pu\u00f2 tuttavia sfuggire il senso di crisi che essa trasmette poich\u00e9 rinvia ogni fondamento all\u2019esperienza vissuta, e quindi alla relazione che proprio perch\u00e9 singolare \u00e8 irripetibile. Cos\u00ec per\u00f2 viene a mancare di ogni sostegno obbiettivo, almeno nel senso che questo termine aveva nella filosofia di Kant, e che arrivava a includere l\u2019universale.<\/p>\n<p style=\"text-align: justify;\">Giunti a questo punto non c\u2019\u00e8 dubbio alcuno che il cammino sin qui percorso per la scienza potrebbe essere ripetuto per la filosofia. La crisi del kantismo infatti \u00e8 il segnale che anche l\u2019ultima fortezza si incrina, se non crolla addirittura. Viene meno una costruzione del pensiero, una conoscenza del mondo che dava certezza ed esibiva persino verit\u00e0, al punto che molti avevano pensato che non si potesse andare oltre Kant, quasi che le sue opere costituissero le colonne d\u2019Ercole del sapere umano. A questo panorama bisogna naturalmente aggiungere le filosofie esistenzialistiche e quelle che si sono radicate nell\u2019empirismo pi\u00f9 estremo.<\/p>\n<p style=\"text-align: justify;\"><strong>SACRO.<\/strong> \u00c8 inevitabile che la debolezza della scienza e della filosofia induca ad avvicinarsi al sacro e alle religioni, che sembrano fornire una risposta immediata e totale, sen za dubbi e senza parzialit\u00e0: \u00e8 la risposta della fede, un \u00ab<em>credo quia absurdum<\/em>\u00bb, un percorso breve tra il bisogno e la sua risposta. Del resto, perch\u00e9 contrapporre fede e scienza quando \u00e8 fede anche l\u2019accettazione di assiomi, di postulati, di ipotesi di ricerca che nulla hanno a che vedere con il metodo rigido e razionale, e tanto meno con la sperimentazione?<\/p>\n<p style=\"text-align: justify;\">La fede in un Dio si aggancia all\u2019autonomia e concretezza di ciascuno e propone quei comportamenti che, al di l\u00e0 del significato specifico che ogni religione vi attribuisce, servono ad allontanare la paura, a controllare l\u2019angoscia del vivere che si accentua poich\u00e9 la vita si lega a una specie di filo di ragno che sembra sempre sul punto di rompersi.<\/p>\n<p style=\"text-align: justify;\">Il problema si allontana sempre pi\u00f9 dalla scienza &#8220;pura&#8221; e si lega ai miti, alla magia e persino alla metamorfosi, tanto che si scoprono sostanze che sembrano produrla rapidamente.\u00a0 Si ritorna al misticismo delle droghe, che hanno avuto una lunga storia presso i popoli primitivi e che adesso entrano nelle societ\u00e0 avanzate colte dalla paura. Ai princ\u00ecpi della logica scientifica e alle categorie della filosofia si sostituiscono gli empirismi pratici, la visione di mondi senza un futuro che nessuno garantisce e che si fa misterioso. Il mistero per\u00f2 non \u00e8 pi\u00f9 un primitivismo che aspetta di essere superato dalla civilt\u00e0 della ragione, come sognava Giambattista Vico, ma una dimensione sopravvissuta alla scienza, che nel frattempo \u00e8 morta.<\/p>\n<p style=\"text-align: justify;\"><strong>INCONSCIO E PSICOLOGIE.<\/strong> Dilaga l\u2019inconscio, e questo sembra persino un paradosso se solo pensiamo al nome con cui s\u2019impone questa dimensione nascosta in ciascuno ma capace di guidare lungo percorsi comportamentali che non hanno scelta e non si attivano sulla base di una logica razionale. Per secoli sul comportamento dell\u2019uomo avevano dominato il capire e il volere, nella convinzione che con la ragione si potesse discernere il bene e separarlo dal male, e che poi con la volont\u00e0 si riuscisse a scegliere il primo e rinunciare al secondo.<\/p>\n<p style=\"text-align: justify;\">Su questi parametri si dipingeva l\u2019uomo libero, in grado di capire il mondo che la scienza svelava sempre pi\u00f9 nei suoi veri connotati come premessa per intessere una vita pi\u00f9 opportuna e giusta. Su questi stessi parametri si fondava la pedagogia: sviluppando la ragione e poi rinforzando la volont\u00e0 l\u2019uomo poteva assurgere alla sua dignit\u00e0 e servire la verit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Nella seconda met\u00e0 dell\u2019Ottocento si comincia a parlare di inconscio, ancor prima della sua proposta organica da parte di Sigmund Freud. L\u2019intento \u00e8 di sostenere che il comportamento non sia riducibile al capire e al volere poich\u00e9 nell\u2019uomo agiscono forze oscure collocate oltre la coscienza, delle quali pertanto non c\u2019\u00e8 consapevolezza. Se cos\u00ec \u00e8, significa che si tratta di forze non comprensibili \u2013 almeno razionalmente \u2013 e non dominabili con la volont\u00e0, poich\u00e9 sfuggono persino alla loro identificazione (e senza identificazione non si pu\u00f2 esercitare alcuna scelta).<\/p>\n<p style=\"text-align: justify;\">Ci\u00f2 che di oscuro si agita dentro l\u2019uomo veniva gi\u00e0 anticipato dalle correnti romantiche: ma si trattava di ombre che si coglievano in qualche figura, ad esempio in tutti i grandi personaggi dell\u2019arte usciti da uno &#8220;Sturm und Drang&#8221;, da una sorta di tempesta emotiva. Un simile aspetto s\u2019imponeva con realizzazioni che, per quanto estranee al senso dettato dalla ragione, si proponevano come prodotti dell\u2019uomo, sue creature. Ora invece l\u2019inconscio s\u2019intravede in tutti gli uomini come qualcosa di strutturale.<\/p>\n<p style=\"text-align: justify;\">C\u2019\u00e8 come la certezza d\u2019un incerto, la presenza di uno sconosciuto che pu\u00f2 giungere persino a dominare, un demone che pu\u00f2 possedere l\u2019uomo senza che egli possa fare nulla. Si mettono in gioco, cos\u00ec, la libert\u00e0 e la responsabilit\u00e0. \u00c8 di questo periodo la dichiarazione che l\u2019uomo pu\u00f2 compiere gesti senza la capacit\u00e0 di capire e di volere ci\u00f2 che fa. In queste condizioni egli non pu\u00f2 essere ritenuto responsabile dell\u2019azione e del danno che consegue a quel comportamento.<\/p>\n<p style=\"text-align: justify;\">Ma se l\u2019inconscio \u2013 e dunque quell\u2019ombra di cui si diceva poc\u2019anzi \u2013 \u00e8 presente in tutti, e se addirittura esiste un inconscio non solo individuale ma collettivo, come sostiene Carl Gustav Jung, allora non \u00e8 forse l\u2019intera specie a trasformarsi in un\u2019entit\u00e0 governata non da ragione e da volont\u00e0 ma dall\u2019inconscio collettivo che vuole qualcosa che la coscienza ignora? E se lo ignora, come dominarlo? E come educare al controllo di ci\u00f2 che \u00e8 sconosciuto?<\/p>\n<p style=\"text-align: justify;\">Freud tenter\u00e0 di dare un volto comprensibile a questo mostro sconosciuto che ci possiede, e lo far\u00e0 proprio per non entrare nel dominio della religione rimanendo invece nell\u2019\u00e0mbito della medicina e persino della scienza, poich\u00e9 questa era la sua provenienza. Ma questo mostro rimane sempre nelle vesti di un limite, di qualcosa che sfugge, anche se lo psicoanalista lo pu\u00f2 rincorrere con la sua tecnica. Freud compie un\u2019operazione elegantemente disperata: dare un senso all\u2019ignoto, tentare di razionalizzare l\u2019empirico e il misterioso.<\/p>\n<p style=\"text-align: justify;\">D\u2019altra parte, ci si potrebbe chiedere: che senso ha avuto \u2013 e ancora ha \u2013 domandare uno statuto scientifico alla psicoanalisi, se la scienza nelle forme pi\u00f9 pure della matematica e della fisica possiede un\u2019apor\u00eca che non la libera dall\u2019irrazionale e non le permette di giungere a conclusioni di verit\u00e0 e di certezza? Non vogliamo entrare in questo tema specifico ma limitarci alla scoperta di una dimensione dell\u2019uomo che mette in crisi la concezione classica di un\u2019entit\u00e0 che di misterioso non dovrebbe aver nulla.<\/p>\n<p style=\"text-align: justify;\">Uomo. L\u2019uomo \u00e8 un grande sconosciuto, un mistero, nonostante tanta ricerca e tanto &#8220;progresso&#8221;. Lo stesso criterio di progresso a un certo punto viene anzi posto in discussione. A metterlo in crisi \u2013 si dice \u2013 sono i calcoli sulla valutazione delle risorse alimentari ed energetiche del pianeta che non sarebbero in grado di soddisfare un numero giudicato gi\u00e0 troppo alto di viventi. Il Club di Roma, coordinato da Aurelio Peccei, comincia a preconizzare la fine del pianeta per effetto di un consumo che lo devitalizzerebbe. Un\u2019anali si che evidenzia soprattutto i limiti dello sviluppo (si vedano, oltre ai rapporti dell\u2019istituzione, anche Aurelio Peccei, \u00abQuale futuro?\u00bb, Biblioteca dell\u2019Est, Mondadori 1974, e \u00abLa qualit\u00e0 umana\u00bb, Biblioteca dell\u2019Est, Mondadori 1976).<\/p>\n<p style=\"text-align: justify;\">Si aggiunge un\u2019altra dimensione che sembra persino ridicola: l\u2019uomo deve fare i conti con i rifiuti che egli stesso produce e che potrebbero seppellirlo. Un consumo che, cos\u00ec descritto, sa di idiozia, poich\u00e9 non \u00e8 segnale di benessere ma di una sorta di dipendenza che produce allo stesso tempo la morte del pianeta e dell\u2019uomo. Ma l\u2019uomo \u00e8 anche spaventato: non crede pi\u00f9 alla scienza, e di fronte a ogni suo risultato si domanda cosa veramente nasconda e se essa non sia invece uno strumento di potere, un\u2019arma cio\u00e8 che i potenti usano contro i poveri o i pi\u00f9 deboli. Con il nazismo la tecnologia delle armi di distruzione mostra la crudelt\u00e0 non solo dell\u2019uomo ma di un\u2019intera nazione: che \u00e8 la pi\u00f9 forte, e si mostra come la pi\u00f9 crudele.<\/p>\n<p style=\"text-align: justify;\">La scienza come terrore e paura finisce per trovarsi collocata nel cielo assieme agli d\u00e8i e alle potenze numinose da cui nascono le correnti apocalittiche.<\/p>\n<p style=\"text-align: justify;\">Nella cruda descrizione fatta dal Grande Inquisitore nei Fratelli Karamazov di Dostoevskij \u2013 siamo nel 1880 \u2013 costui afferma che l\u2019uomo ha bisogno di un pezzo di pane e di un padrone cui delegare la propria libert\u00e0 e ubbidire. Questo romanzo \u00e8 un richiamo straordinario al problema del male che ormai si fa dominante e non sembra risolvibile, almeno non dalla scienza. \u00c8 un male che coesiste con l\u2019uomo, come sua parte costitutiva, un male cui si lega un dolore ineliminabile e tremendo.<\/p>\n<p style=\"text-align: justify;\">La scienza dunque non domina pi\u00f9 lo scenario dell\u2019uomo: lo affianca piena di dubbi, di limiti, di apor\u00ece, senza pi\u00f9 princ\u00ecpi, o almeno senza quelli della certezza e della verit\u00e0, sostituiti dai princ\u00ecpi dell\u2019impotenza e del relativismo che la detronizzano. \u00c8 come se si fosse colto il limite intrinseco al procedere stesso della conoscenza, per cui si misura il mondo con la mente dell\u2019uomo che \u00e8 ignota, o almeno sfugge nella sua completezza e persino nella sua funzionalit\u00e0. \u00c8 come misurare una distanza senza conoscere l\u2019unit\u00e0 di misura che la determina, quasi che il &#8220;metro&#8221; fosse un pressappoco, un\u2019entit\u00e0 sconosciuta per misurare ci\u00f2 che \u00e8 indeterminato.<\/p>\n<p style=\"text-align: justify;\">\u00c8 il problema della mente dell\u2019uomo, che si pone questioni e non sa darsi risposte se non vaghe e mai prive di un dubbio: un dubbio che sar\u00e0 diverso da quello originario ma che si trascina solo cambiando maschera, non concedendo mai alcuna certezza. In taluni momenti l\u2019uomo ha cercato di convincersi e di credere in s\u00e9, nelle proprie forze, in altri invece ha sentito forte il senso del limite. Nel primo caso si rifugiava nella certezza di trovare la verit\u00e0, nel secondo camminava pi\u00f9 lentamente sapendo che tanto la verit\u00e0 non avrebbe mai potuto trovarla.<\/p>\n<p style=\"text-align: justify;\">La storia si \u00e8 sviluppata tra questi due poli: una vera maniaco-depressione del genere umano in rapporto al significato del mondo e al senso stesso dell\u2019uomo. Talvolta si \u00e8 pensato di dimenticare la parola &#8220;verit\u00e0&#8221;, scordando anche che nasceva dall\u2019interno stesso dell\u2019uomo e che quindi si trattava di una passione interiore che, se anche perde d\u2019intensit\u00e0, non pu\u00f2 annullare la propria forza. La verit\u00e0, dunque, vista come un bisogno.<\/p>\n<p style=\"text-align: justify;\">C\u2019\u00e8 stato un tempo in cui si \u00e8 avuta fede nella ragione, nel suo potere assoluto di discernere tra vero e falso, tra buono e cattivo.\u00a0 Una ragione destinata a sovrastare quel sentimento che \u00e8 invece il marchio dell\u2019individuo, della sua irripetibilit\u00e0. La ragione vista come universale, fondamento oggettivo, assoluto. Poi si scopre che la ragione risente delle emozioni, e che persino nel cervello le strutture che regolano la ragione sono embricate con quelle dell\u2019affettivit\u00e0, e che pertanto una separazione \u00e8 solo utopica.<\/p>\n<p style=\"text-align: justify;\">Si scopre che il cervello non \u00e8 nemmeno meccanico, ma una sua parte \u2013 il cervello plastico \u2013 si struttura e si modifica in rapporto alle esperienze e quindi in base alle rela zioni che il singolo stabilisce con altri esseri umani. Dunque il cervello cambia, si storicizza e finisce per stampare dentro la sua materia, nella carne, esperienze che quel singolo ha fatto e poteva non fare. Quindi il tempo e l\u2019esperienza strutturano lo stesso organo che dovrebbe scientificamente &#8220;misurare&#8221; il mondo dentro cui l\u2019uomo \u00e8 calato.<\/p>\n<p style=\"text-align: justify;\">Epicrisi. Ci siamo limitati in questa analisi ai decenni della crisi delle scienze e quindi a quei fatti che hanno caratterizzato il clima scientifico dell\u2019inizio del Novecento, poich\u00e9 da qui comincia il grande declino che oggi, nel terzo millennio, appare in tutta la sua drammaticit\u00e0 fino a fare del tempo presente un tempo dominato dalla stupidit\u00e0, da una involuzione che sembra apocalittica non tanto per ordine di un Dio stanco ma di un uomo che si \u00e8 perso, senza pi\u00f9 riferimenti e senza pi\u00f9 princ\u00ecpi. Il percorso, che in parte abbiamo alle spalle, \u00e8 dunque quello di analizzare gli anni del cambiamento per poi passare al presente che descriveremo nella vita e nei comportamenti che si sono fatti cronaca.<\/p>\n<p style=\"text-align: justify;\">Ma non abbiamo fretta. Vogliamo trattenerci sulla caduta dei princ\u00ecpi, mantenere l\u2019attenzione costantemente e quasi ossessivamente su di essi, sulle categorie: poich\u00e9, oltre che prestare attenzione a un itinerario che stiamo tracciando, vogliamo che dentro ciascuno si attivi una percezione dei princ\u00ecpi perduti, la consapevolezza di che cosa \u00e8 accaduto, anche se nessuno lo ha mostrato in maniera chiara e con l\u2019impegno che un tale segnale di pericolo mortale avrebbe meritato non solo per il singolo ma per un\u2019intera societ\u00e0, e forse per una civilt\u00e0. Che le civilt\u00e0 finiscano, del resto, non \u00e8 un delirio di qualche profeta di sventura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avvenire, 7 maggio 2006 \u00abCi siamo limitati in questa analisi ai decenni della crisi delle scienze e quindi a quei fatti che hanno caratterizzato il clima dell\u2019inizio del novecento. Poich\u00e9 da l\u00ec comincia il grande declino che oggi,nel terzo millennio, appare in tutta la sua drammaticit\u00e0, fino a fare del presente un tempo dominato dalla &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-scienza-magra\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":33510,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[261],"class_list":["post-2058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-scienza","tag-scienza-2","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La scienza magra - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-scienza-magra\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La scienza magra - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-scienza-magra\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2006-05-31T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-27T10:22:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/06\/crisi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"200\" \/>\n\t<meta property=\"og:image:height\" content=\"199\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"20 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-scienza-magra\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-scienza-magra\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"La scienza magra\",\"datePublished\":\"2006-05-31T22:00:00+00:00\",\"dateModified\":\"2016-04-27T10:22:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-scienza-magra\\\/\"},\"wordCount\":3988,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-scienza-magra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/06\\\/crisi.jpg\",\"keywords\":[\"scienza\"],\"articleSection\":[\"Scienza\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-scienza-magra\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-scienza-magra\\\/\",\"name\":\"La scienza magra - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-scienza-magra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-scienza-magra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/06\\\/crisi.jpg\",\"datePublished\":\"2006-05-31T22:00:00+00:00\",\"dateModified\":\"2016-04-27T10:22:36+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-scienza-magra\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-scienza-magra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-scienza-magra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/06\\\/crisi.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/06\\\/crisi.jpg\",\"width\":200,\"height\":199},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/la-scienza-magra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La scienza magra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La scienza magra - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-scienza-magra\/","og_locale":"it_IT","og_type":"article","og_title":"La scienza magra - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-scienza-magra\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2006-05-31T22:00:00+00:00","article_modified_time":"2016-04-27T10:22:36+00:00","og_image":[{"width":200,"height":199,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/06\/crisi.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"20 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-scienza-magra\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-scienza-magra\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"La scienza magra","datePublished":"2006-05-31T22:00:00+00:00","dateModified":"2016-04-27T10:22:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-scienza-magra\/"},"wordCount":3988,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-scienza-magra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/06\/crisi.jpg","keywords":["scienza"],"articleSection":["Scienza"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-scienza-magra\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-scienza-magra\/","name":"La scienza magra - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-scienza-magra\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-scienza-magra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/06\/crisi.jpg","datePublished":"2006-05-31T22:00:00+00:00","dateModified":"2016-04-27T10:22:36+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-scienza-magra\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-scienza-magra\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-scienza-magra\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/06\/crisi.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/06\/crisi.jpg","width":200,"height":199},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/la-scienza-magra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"La scienza magra"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2058"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2058\/revisions"}],"predecessor-version":[{"id":33511,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2058\/revisions\/33511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/33510"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}