{"id":2049,"date":"2006-05-25T00:00:00","date_gmt":"2006-05-24T22:00:00","guid":{"rendered":""},"modified":"2016-04-27T17:19:59","modified_gmt":"2016-04-27T15:19:59","slug":"a-qualcuno-non-piace-lo-sviluppo","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-qualcuno-non-piace-lo-sviluppo\/","title":{"rendered":"A qualcuno non piace lo sviluppo"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-33595\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/05\/decrescita.png\" alt=\"decrescita\" width=\"250\" height=\"165\" \/>Il Timone<\/strong> n.52 aprile 2006<\/div>\n<p style=\"text-align: center;\">di <strong>Riccardo Cascioli<\/strong><\/p>\n<p style=\"text-align: justify;\">Una strana moda da qualche tempo attraversa i media cattolici: la condanna dello sviluppo. Non di un certo tipo di sviluppo, identificabile magari con il liberismo pi\u00f9 estremo; no, \u00e8 proprio la condanna dello sviluppo in s\u00e9. Basta vedere la frequenza con cui compare sulle pagine di tanti media cattolici il pensiero di certi economisti, quali Serge Latouche, Wolfgang Sachs\u00a0 e Susan Gorge, o eco-catastrofisti come Lester Brown e Mathis Wackernagel, il teorico dell\u2019 \u201cimpronta ecologica\u201d.<\/p>\n<p style=\"text-align: justify;\">Per averne un\u2019idea basterebbe dare un\u2019occhiata al catalogo della EMI, la principale casa editrice missionaria: i titoli che teorizzano la fine dello sviluppo o \u201cla decrescita\u201d economica sono innumerevoli.<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Allo stesso modo questo \u00e8 l\u2019unico pensiero che viene proposto dall\u2019associazione ambientalista cristiana, <a href=\"http:\/\/www.greenaccord.it\/\" target=\"_blank\">Greenaccord<\/a> che recentemente ha pubblicato un volume su \u201cEconomia e ambiente\u201d in cui raccoglie una serie di saggi scritti dagli autori succitati o comunque sulla stessa linea.<\/div>\n<p style=\"text-align: justify;\">Il caso Greenaccord \u00e8 interessante perch\u00e9 questa associazione gi\u00e0 da tempo organizza incontri internazionali dedicati ai giornalisti cattolici allo scopo di formarli su temi ambientali, e a questi congressi partecipano anche personalit\u00e0 ecclesiali di rilievo Ci\u00f2 che stupisce non \u00e8 tanto il pensiero anti-sviluppo: in fondo non \u00e8 nuovo e non \u00e8 altro che la solita analisi marxista che per\u00f2 deve fare i conti con il crollo e il fallimento dei regimi comunisti.<\/p>\n<p style=\"text-align: justify;\">Si ripropone cos\u00ec la solita equazione \u201csviluppo uguale neocolonialismo\u201d oppure l\u2019altrettanto nota \u201csviluppo uguale pochi sempre pi\u00f9 ricchi e molti sempre pi\u00f9 poveri\u201d. Quindi, come sostiene Latouche in Come sopravvivere allo sviluppo (Bollati Boringhieri, 2005), \u201clo sviluppo \u00e8 la fonte del male\u201d e \u201cmacchina per affamare i popoli\u201d.<\/p>\n<p style=\"text-align: justify;\">La ricetta, secondo Latouche, consiste dunque nell\u2019abolizione \u201cdella propriet\u00e0 privata dei mezzi di produzione e dell\u2019accumulazione illimitata del capitale\u201d. State pensando all\u2019Unione Sovietica e alla Cina? State tranquilli, dice Latouche, quello \u00e8 un esperimento fallito, fondamentalmente perch\u00e9 l\u2019economia era ancora il centro della riflessione.<\/p>\n<p style=\"text-align: justify;\">Latouche chiama ad andare oltre, \u201cbisogna uscire dall\u2019economia\u201d, puntare alla \u201cdecrescita conviviale\u201d, perch\u00e9 \u201cla costruzione di una societ\u00e0 meno ingiusta si tradurrebbe nel recupero della convivialit\u00e0 e di un consumo pi\u00f9 limitato quantitativamente e pi\u00f9 esigente qualitativamente\u201d. In estrema sintesi, sostiene Latouche, basterebbe essere tutti pi\u00f9 poveri per evitare la miseria di tanti; cos\u00ec saremmo anche pi\u00f9 felici, perch\u00e9 i beni che ci fanno felici non sono i prodotti da consumare.<\/p>\n<p style=\"text-align: justify;\">A parte la banale considerazione che se non \u00e8 la ricchezza a farci felici non si capisce perch\u00e9 dovrebbe esserlo la povert\u00e0, appare evidente che per poter sostenere queste tesi \u00e8 necessario negare buona parte della realt\u00e0 e inventarsene una di sana pianta: ad esempio, come \u00e8 possibile far partire la storia dello sviluppo dalla Rivoluzione industriale?<\/p>\n<p style=\"text-align: justify;\">Non c\u2019\u00e8 dubbio che da l\u00ec in poi vi sia stata una accelerazione improvvisa, ma i millenni precedenti? Il passaggio dalla preistoria alla storia, dal nomadismo all\u2019agricoltura e su su per i secoli passando dalla tecnologia medievale, le grandi scoperte scientifiche, l\u2019esplorazione dei \u201cnuovi mondi\u201d? Come si pu\u00f2 negare che sia inscritto nell\u2019uomo un desiderio di andare oltre, di migliorare la propria situazione, di rispondere a nuovi bisogni?<\/p>\n<p style=\"text-align: justify;\">E ancora, i dati dimostrano che non \u00e8 lo sviluppo ad affamare: tra il 1900 e il 1998 il Pil (Prodotto interno lordo) globale, cio\u00e8 la ricchezza disponibile, \u00e8 aumentata da 20 a 40 volte contro un aumento della popolazione che \u00e8 stato di 4 volte; ma anche nei Paesi pi\u00f9 poveri la situazione \u00e8 migliorata: in media ogni abitante dei Paesi in via di sviluppo assume 2.700 calorie al giorno contro le 1.900 del 1960, e nel corso degli anni \u201990 il numero dei poveri assoluti (cio\u00e8 le persone che vivono con meno di 1 dollaro al giorno) nel mondo \u00e8 diminuito di 125 milioni di unit\u00e0, mentre in percentuale \u00e8 sceso dal 29 al 23% della popolazione dei Paesi in via di sviluppo, che nel frattempo \u00e8 aumentata di 600 milioni di unit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Insomma, rispetto a 50-100 anni fa oggi c\u2019\u00e8 meno miseria, anche se si pu\u00f2 e si deve fare molto di pi\u00f9 per colmare le gravi disuguaglianze esistenti, ma \u00e8 proprio qui il punto: per i pensatori come Latouche la soluzione non sta nello sviluppo di tutti, ma nella povert\u00e0 diffusa; non una eguaglianza al rialzo, ma al ribasso. Cos\u00ec salvaguarderemo anche l\u2019ambiente e la Terra che i nostri tassi di crescita stanno minacciando.<\/p>\n<p style=\"text-align: justify;\">Dicevamo prima: queste tesi in fondo non ci stupiscono molto. Ci\u00f2 che \u00e8 invece sorprendente \u00e8 l\u2019entusiasmo che con cui sono accolte e rilanciate in ambienti cattolici di rilievo, perch\u00e9 in fondo il pensiero che ne sta alla radice \u00e8 profondamente anti-cattolico. Il tanto vituperato concetto di sviluppo \u00e8 infatti figlio del cristianesimo che, fondato sulla tradizione ebraica, introduce una concezione completamente nuova della storia, lineare, ovvero con un punto di partenza e un punto di arrivo.<\/p>\n<p style=\"text-align: justify;\">La storia si svolge cio\u00e8 dalla Creazione fino al ritorno di Cristo e l\u2019uomo \u2013 immagine e somiglianza di Dio e vertice del Creato &#8211; \u00e8 chiamato a modellare la realt\u00e0 della \u201cGerusalemme terrena\u201d per renderla a somiglianza della \u201cGerusalemme celeste\u201d. L\u2019idea di progresso, di sviluppo, ha qui la sua radice. Non un fatto meramente economico, ma certamente anche economico. Perch\u00e9 il cristianesimo porta una concezione positiva della realt\u00e0 \u2013 che \u00e8 segno di Dio \u2013 e l\u2019economia \u00e8 parte di questa realt\u00e0.<\/p>\n<p style=\"text-align: justify;\">Ci\u00f2 che distingue il bene dal male \u00e8 dunque l\u2019agire \u2013 o meno &#8211; in funzione del Regno di Dio. Per questo nei documenti ecclesiali si parla spesso di \u201csviluppo integrale\u201d \u2013 che riguarda tutta la persona e alla cui base c\u2019\u00e8 la libert\u00e0 religiosa &#8211; e di \u201csviluppo solidale\u201d, per indicare l\u2019intima unit\u00e0 del genere umano che nasce dalla consapevolezza di avere un unico Padre. La visione lineare della storia \u00e8 una specificit\u00e0 del cristianesimo, che non troviamo n\u00e9 nelle religioni orientali (concezione circolare, l\u2019eterno ritorno) n\u00e9 in quelle animiste (dove l\u2019uomo \u00e8 elemento del cosmo e \u201cschiavo\u201d del passato).<\/p>\n<p style=\"text-align: justify;\">Ed \u00e8 proprio per questo che da secoli l\u2019Occidente \u2013 formatosi sul cristianesimo \u2013 guida il processo di sviluppo mondiale. In un Occidente che per\u00f2 ha perso la memoria e la coscienza delle proprie radici, eliminare il concetto di sviluppo equivarrebbe a dare l\u2019ultima spallata alla millenaria civilt\u00e0 cristiana, cancellarne ogni traccia visibile. Che a questo vogliano contribuire entusiasti anche dei cattolici lascia indubbiamente esterrefatti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Timone n.52 aprile 2006 di Riccardo Cascioli Una strana moda da qualche tempo attraversa i media cattolici: la condanna dello sviluppo. Non di un certo tipo di sviluppo, identificabile magari con il liberismo pi\u00f9 estremo; no, \u00e8 proprio la condanna dello sviluppo in s\u00e9. Basta vedere la frequenza con cui compare sulle pagine di &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-qualcuno-non-piace-lo-sviluppo\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":33595,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13,112],"tags":[1281],"class_list":["post-2049","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economia","category-terzomondialismo","tag-decrescita","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A qualcuno non piace lo sviluppo - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-qualcuno-non-piace-lo-sviluppo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A qualcuno non piace lo sviluppo - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-qualcuno-non-piace-lo-sviluppo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2006-05-24T22:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-27T15:19:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/05\/decrescita.png\" \/>\n\t<meta property=\"og:image:width\" content=\"276\" \/>\n\t<meta property=\"og:image:height\" content=\"182\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-qualcuno-non-piace-lo-sviluppo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-qualcuno-non-piace-lo-sviluppo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"A qualcuno non piace lo sviluppo\",\"datePublished\":\"2006-05-24T22:00:00+00:00\",\"dateModified\":\"2016-04-27T15:19:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-qualcuno-non-piace-lo-sviluppo\\\/\"},\"wordCount\":1025,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-qualcuno-non-piace-lo-sviluppo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/05\\\/decrescita.png\",\"keywords\":[\"decrescita\"],\"articleSection\":[\"Economia\",\"Terzomondialismo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-qualcuno-non-piace-lo-sviluppo\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-qualcuno-non-piace-lo-sviluppo\\\/\",\"name\":\"A qualcuno non piace lo sviluppo - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-qualcuno-non-piace-lo-sviluppo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-qualcuno-non-piace-lo-sviluppo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/05\\\/decrescita.png\",\"datePublished\":\"2006-05-24T22:00:00+00:00\",\"dateModified\":\"2016-04-27T15:19:59+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-qualcuno-non-piace-lo-sviluppo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-qualcuno-non-piace-lo-sviluppo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-qualcuno-non-piace-lo-sviluppo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/05\\\/decrescita.png\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/05\\\/decrescita.png\",\"width\":276,\"height\":182},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/a-qualcuno-non-piace-lo-sviluppo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A qualcuno non piace lo sviluppo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A qualcuno non piace lo sviluppo - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-qualcuno-non-piace-lo-sviluppo\/","og_locale":"it_IT","og_type":"article","og_title":"A qualcuno non piace lo sviluppo - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-qualcuno-non-piace-lo-sviluppo\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2006-05-24T22:00:00+00:00","article_modified_time":"2016-04-27T15:19:59+00:00","og_image":[{"width":276,"height":182,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/05\/decrescita.png","type":"image\/png"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-qualcuno-non-piace-lo-sviluppo\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-qualcuno-non-piace-lo-sviluppo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"A qualcuno non piace lo sviluppo","datePublished":"2006-05-24T22:00:00+00:00","dateModified":"2016-04-27T15:19:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-qualcuno-non-piace-lo-sviluppo\/"},"wordCount":1025,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-qualcuno-non-piace-lo-sviluppo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/05\/decrescita.png","keywords":["decrescita"],"articleSection":["Economia","Terzomondialismo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-qualcuno-non-piace-lo-sviluppo\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-qualcuno-non-piace-lo-sviluppo\/","name":"A qualcuno non piace lo sviluppo - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-qualcuno-non-piace-lo-sviluppo\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-qualcuno-non-piace-lo-sviluppo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/05\/decrescita.png","datePublished":"2006-05-24T22:00:00+00:00","dateModified":"2016-04-27T15:19:59+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-qualcuno-non-piace-lo-sviluppo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-qualcuno-non-piace-lo-sviluppo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-qualcuno-non-piace-lo-sviluppo\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/05\/decrescita.png","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/05\/decrescita.png","width":276,"height":182},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/a-qualcuno-non-piace-lo-sviluppo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"A qualcuno non piace lo sviluppo"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=2049"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2049\/revisions"}],"predecessor-version":[{"id":33596,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/2049\/revisions\/33596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/33595"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=2049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=2049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=2049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}