{"id":1921,"date":"2006-03-10T00:00:00","date_gmt":"2006-03-09T23:00:00","guid":{"rendered":""},"modified":"2016-05-09T12:45:40","modified_gmt":"2016-05-09T10:45:40","slug":"i-campioni-dellovvio-ovvero-la-malvagit-del-banale","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\/","title":{"rendered":"I campioni dell&#8217;ovvio, ovvero la malvagit&agrave; del banale"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-34019 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/03\/comizio.jpg\" alt=\"comizio\" width=\"271\" height=\"186\" \/>Vita e Pensiero<\/strong> n.1<\/div>\n<div style=\"text-align: center;\">gennaio-febbraio 2006<\/div>\n<p><em>L&#8217;editorialista ipertrofico e l&#8217;intellettuale salottiero sono il paradigma di una cultura di tendenza che non ha pi\u00f9 il problema della verit\u00e0 e produce, se non falsit\u00e0, certamente un bel numero di pagine perlomeno opinabili.<\/em><\/p>\n<p style=\"text-align: center;\">di <strong>Roberto Presilla<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">In un <em>pamphlet <\/em>assai stimolante intitolato <em>On Bullshit,<\/em> Harry G. Frankfurt si propone di offrire \u00abun&#8217;analisi filosofica provvisoria ed esplorativa\u00bb (p, 11) di quelle che potremmo chiamare <em>sciocchezze<\/em>, scegliendo il sinonimo che lo stesso Frankfurt considera come \u00abpi\u00f9 educato\u00bb.<\/div>\n<p style=\"text-align: justify;\">Per orientarci nel <em>mare magnum<\/em> delle sciocchezze, abbiamo bisogno di un&#8217;analisi della struttura del concetto. Prendendo le mosse dall&#8217;argomentazione proposta a suo tempo da Max Black (cfr. p. 15), Frankfurt sottolinea come le sciocchezze siano \u00abfalse rappresentazioni ingannevoli\u00bb, ossia rappresentazioni <em>deliberatamente<\/em> ingannevoli, che per\u00f2 non giungono alla menzogna. In effetti, si pu\u00f2 dire qualcosa di ingannevole senza dire menzogne: per esempio, si pu\u00f2 controbattere a un&#8217;obiezione con una risposta irrilevante, in modo da ingannare l&#8217;interlocutore sull&#8217;argomento in questione.<\/p>\n<p style=\"text-align: justify;\">La menzogna, per esser tale, deve essere un&#8217;asserzione falsa detta intenzionalmente, con lo scopo di ingannare proprio sul contenuto dell&#8217;asserzione. Nel dire sciocchezze, per\u00f2, normalmente non si arriva a questo: si cerca di ingannare su se stessi, piuttosto che su come stanno le cose.<\/p>\n<p style=\"text-align: justify;\">Il politico americano che, in occasione della festa del 4 luglio, pronunci un discorso pomposo sulla \u00abnostra grande e benedetta nazione, i cui Padri Fondatori, guidati da Dio, crearono un nuovo inizio per l&#8217;umanit\u00e0\u00bb (p.14), fornisce un ottimo esempio: il suo scopo non \u00e8 tanto diffondere credenze sui Padri Pellegrini, quanto accreditarsi come patriota. Non gli importa che cosa gli elettori pensano dei Padri Pellegrini: gli importa che cosa pensano di lui, e ricorre quindi a un espediente retorico per fare la figura del patriota.<\/p>\n<p style=\"text-align: justify;\">La definizione di Black &#8211; le sciocchezze come rappresentazioni deliberatamente ingannevoli circa chi le pronuncia &#8211; evoca facili corrispondenze nella vita di tutti i giorni. Frankfurt ritiene, tuttavia, che essa vada migliorata, sia sul versante del rapporto con la verit\u00e0 sia su quello dell&#8217;ingannevole rappresentazione di se stessi.<\/p>\n<p style=\"text-align: justify;\">Non c&#8217;\u00e8 legame tra la verit\u00e0 e le sciocchezze, che si caratterizzano essenzialmente per la loro \u00abindifferenza per come stanno davvero le cose\u00bb (p. 38). Il che non significa che siano false: l&#8217;essenza delle sciocchezze \u00abnon sta nell&#8217;essere <em>false<\/em>, ma nell&#8217;essere <em>finte<\/em>\u00bb (p. 46, corsivo originale) o anche fasulle. Questo conduce Frankfurt a spiegare perch\u00e9 le sciocchezze siano, rispetto alle bugie, a un tempo preferibili per chi le proferisce e perniciose per chi le ascolta.<\/p>\n<p style=\"text-align: justify;\">Dire una bugia costringe a sottostare alle leggi della verit\u00e0: perch\u00e9 la bugia sia efficace, il mentitore deve tener conto di quella che ritiene essere la verit\u00e0. Le sciocchezze, invece, consentono un approccio &#8220;artistico&#8221;, \u00abcon maggiori opportunit\u00e0 per l&#8217;improvvisazione, le note di colore e la fantasia\u00bb (p. 51): disinteressandosi della verit\u00e0, si pu\u00f2 &#8211; per cos\u00ec dire &#8211; raccontar balle a ruota libera.<\/p>\n<p style=\"text-align: justify;\">In una parola, la falsa rappresentazione offerta dalle sciocchezze non riguarda n\u00e9 le cose n\u00e9 quello che il parlante crede rispetto ad esse: essa riguarda piuttosto ci\u00f2 che il parlante sta facendo. Mentre il bugiardo vuole \u00aballontanarci da una corretta percezione della realt\u00e0\u00bb, chi ci racconta sciocchezze non vuole che sappiamo che \u00abla sua intenzione non \u00e8 n\u00e9 di riferire la verit\u00e0 n\u00e9 di nasconderla\u00bb (pp. 52-53).<\/p>\n<p style=\"text-align: justify;\">Sia la persona sincera che il bugiardo tengono conto della verit\u00e0, ma chi racconta sciocchezze se ne disinteressa: \u00absceglie [le cose da dire], o le inventa, perch\u00e9 si adattino ai suoi scopi\u00bb (p. 54). In tal modo, chi racconta sciocchezze causa un pericoloso indebolimento della nostra capacit\u00e0 di badare a come stanno le cose, in un modo pi\u00f9 sottile e pervasivo della menzogna, in quanto diffonde scetticismo sull&#8217;idea di verit\u00e0: mentre chi mente vuole che si creda alla <em>sua<\/em> verit\u00e0, chi racconta sciocchezze ritiene che il problema della verit\u00e0 sia in qualche modo secondario.<\/p>\n<p style=\"text-align: justify;\">\u00c8 chiaro come le nostre democrazie siano luoghi assai adatti al proliferare delle sciocchezze, \u00abche sono inevitabili ogni volta che le circostanze obbligano qualcuno a parlare senza sapere di cosa sta parlando\u00bb (p. 59). Cos\u00ec politici ed elettori sono costretti entrambi a prendere posizione su questioni rispetto alle quali sono incompetenti, confermando <em>a fortiori<\/em> l&#8217;aforisma &#8211; attribuito a G.B. Shaw &#8211; secondo il quale la democrazia sostituisce l&#8217;elezione da parte dei molti incompetenti alla nomina compiuta dai pochi corrotti.<\/p>\n<p style=\"text-align: justify;\">Ma il luogo privilegiato per l&#8217;accumulo delle sciocchezze \u00e8 il sistema del consumo e della comunicazione di massa: basta pensare ai numerosi messaggi alla clientela inviati da quanti offrono servizi, nel settore privato e pubblico. &#8220;Stiamo lavorando per voi&#8221;, &#8220;ci scusiamo per gli inconvenienti&#8221;: frasi talmente ubique che la seconda viene scherzosamente qualificata da Douglas Adams come il \u00abMessaggio Finale di Dio alla Sua Creazione\u00bb.<\/p>\n<p style=\"text-align: justify;\">Un&#8217;analisi cos\u00ec provocatoria non poteva passare inosservata, anche tra coloro che, secondo Frankfurt, sono tra i principali produttori di sciocchezze e, se qualcuno si \u00e8 accorto che il testo \u00e8 vecchio di vent&#8217;anni, il giudizio del \u00abCorriere della Sera\u00bb &#8211; \u00abil caso editoriale dell&#8217;anno\u00bb &#8211; viene riportato, con intento probabilmente autoironico, sulla fascetta del volume.<\/p>\n<p style=\"text-align: justify;\">Buona parte dei recensori, tra quelli americani e italiani, ha applicato l&#8217;analisi del filosofo americano ai rispettivi <em>leaders<\/em> politici o ai programmi tv. Bersagli appropriati, anche se un po&#8217; ovvi: quello che sembra mancare \u00e8, invece, un&#8217;applicazione al livello &#8220;culturale&#8221;. Anche se i recensori hanno pensato alla politica e alla tv, sembra strano che i produttori di sciocchezze si concentrino nei palazzi governativi e nelle redazioni, lasciando libere le case editrici di pubblicare solo opere di autentico spessore. Vediamo quindi se qualche volume pu\u00f2 essere osservato con la lente di Frankfurt.<\/p>\n<p style=\"text-align: justify;\">L&#8217;impresa richiede un po&#8217; di cautela, al fine di non incrementare, per quanto possibile, il numero delle sciocchezze in circolazione. Il criterio comunque sembra ovvio: cercare tra quanti scrivono pi\u00f9 spesso e di argomenti disparati, combinazione che offre un ricco <em>humus<\/em> per le sciocchezze. Potremmo anzi immaginare alcuni tipi ideali: per esempio, l&#8217;editorialista ipertrofico, che condensa in ampi volumi gli articoli di giornale che potrebbe scrivere, oppure l&#8217;intellettuale salottiero, che affida ai libri brillanti intuizioni da sfruttare durante le conversazioni.<\/p>\n<p style=\"text-align: justify;\">Un esempio del primo tipo \u00e8, probabilmente, Jeremy Rifkin, presidente della Foundation on Economie Trends di Washington. Negli ultimi dieci anni l&#8217;economista americano ha prodotto almeno sei volumi, che spaziano dai nuovi scenari del lavoro (<em>La fine del lavoro<\/em>), dell&#8217;energia (<em>Economia all&#8217;idrogeno<\/em>) e dell&#8217;ambiente (<em>Ecocidio<\/em>), dell\u2019Ict (<em>L&#8217;era dell&#8217;accesso<\/em>) e delle biotecnologie (<em>Il secolo biotech<\/em>), fino a raggiungere le nuove prospettive dell&#8217;Europa (<em>Il sogno europeo<\/em>).<\/p>\n<p style=\"text-align: justify;\">Sembra esserci spazio per applicare Frankfurt, Il che non significa impegnarsi in una particolareggiata confutazione delle copiose affermazioni di Rifkin; dopo tutto, abbiamo detto che le sciocchezze non sono necessariamente false, ma cercano di mascherare quello che l&#8217;autore sta facendo. Per far questo, l&#8217;autore si serve di quello che trova: nel nostro caso, oltre trecento pagine a volume, dense di fatti, molti dei quali interessanti e illuminanti.<\/p>\n<p style=\"text-align: justify;\">Il punto debole sembra essere nella storia che si pu\u00f2 ricavare da questi volumi e che appare straordinariamente coerente: in estrema sintesi, abbiamo da una parte la modernit\u00e0, caratterizzata dall&#8217;economia industriale, dallo sfruttamento dell&#8217;ambiente &#8211; soprattutto dal punto di vista energetico -, dalla propriet\u00e0 privata, dagli Stati-nazione assoluti e dalla cultura della verit\u00e0 scientifica.<\/p>\n<p style=\"text-align: justify;\">Dall&#8217;altra c&#8217;\u00e8 la postmodernit\u00e0 della <em>new economy <\/em>delle reti, basate sull&#8217;inclusivit\u00e0 dei partners in rete piuttosto che sull&#8217;esclusione degli avversari, dell&#8217;energia pulita e sostenibile dell&#8217;idrogeno, delle biotecnologie, del superamento degli Stati-nazione e della cultura postmoderna in cui la scienza \u00e8 uno dei mille racconti. Il tutto condensato, finalmente, in una bella contrapposizione tra il sogno americano, caratterizzato in senso inequivocabilmente <em>neocon<\/em>, e il sogno europeo, questo invece indubbiamente postmoderno: l&#8217;uno centrato sull&#8217;ottimismo del <em>self-made man <\/em>ma superato dagli eventi, l&#8217;altro imbevuto del cinismo di chi le ha viste tutte ma tuttavia capace di cogliere l&#8217;evoluzione della storia.<\/p>\n<p style=\"text-align: justify;\">Una favola raccontata tanto di frequente, e da cos\u00ec tanti cantastorie, da risultare banale, anche se la versione di Rifkin \u00e8 molto pi\u00f9 documentata, lucida, consapevole di altre.<\/p>\n<p style=\"text-align: justify;\">I rimandi tra i volumi permettono di verificare come questa favola guidi la narrazione di Rifkin sia a un livello generale, nell&#8217;architettura delle singole opere, sia nella miriade di ricostruzioni e considerazioni &#8220;storiche&#8221;, il che lo porta a disseminare qua e l\u00e0 luoghi comuni e inesattezze. Giusto per fare un esempio, nel cap. 1 de <em>Il sogno europeo<\/em> il sogno americano viene caratterizzato come un sogno veteroeuropeo, legato a un momento storico ormai sorpassato.<\/p>\n<p style=\"text-align: justify;\">Lo dimostrano le connotazioni profondamente religiose della cultura americana, mentre l&#8217;Europa si \u00e8 lasciata alle spalle l&#8217;et\u00e0 moderna e la religione: \u00abla parte pi\u00f9 laica della popolazione europea [&#8230;] da tempo si \u00e8 lasciata alle spalle l&#8217;idea di un Dio personale\u00bb (p. 21). \u00c8 probabile che lo stesso si possa dire della parte pi\u00f9 laica della popolazione di qualsiasi luogo, Stati Uniti compresi.<\/p>\n<p style=\"text-align: justify;\">Oppure, pi\u00f9 avanti: \u00abil ponte levatoio, il fossato, la torre di guardia sono i simboli architettonici della concezione europea dello spazio\u00bb (p. 92), basata sul concetto di comunit\u00e0 chiusa nella quale l&#8217;individuo trova sicurezza. Di fronte a tanta semplicit\u00e0, che senso ha ricordare piazze, chiese, viali, conventi, ville e altri simboli che nei secoli hanno contribuito a definire molteplici concezioni europee dello spazio?<\/p>\n<p style=\"text-align: justify;\">Gli esempi pi\u00f9 generali sono decisamente suggestivi: si va dai vezzi giornalistici veri e propri, come l&#8217;uso ricorrente della formula &#8220;il Vaticano&#8221; per parlare della Chiesa cattolica &#8211; anche di quella del IX secolo -, alla struttura stessa delle opere, che partono da ampie ricognizioni storiche, scientifiche, economiche e politiche per chiudere con le considerazioni sull&#8217;importanza della scelta di fronte a noi, che coinvolge il nostro essere uomini e le nostre relazioni.<\/p>\n<p style=\"text-align: justify;\">Il lettore ci perdoner\u00e0 se riproduciamo le ultimissime righe di quattro volumi, cominciando con <em>L&#8217;era dell&#8217;accesso<\/em>: \u00abl&#8217;era dell&#8217;accesso costringer\u00e0 ciascuno di noi a porsi delle domande fondamentali su come rimodellare le relazioni tra gli esseri umani. [&#8230;] La risposta a queste domande determiner\u00e0, nel XXI secolo, la natura della societ\u00e0 che creeremo per noi e per le generazioni a venire\u00bb (p. 353).<\/p>\n<p style=\"text-align: justify;\">Da <em>Economia all&#8217;idrogeno<\/em>: \u00absono rari, nella storia, i momenti in cui una generazione di uomini ha a disposizione un nuovo strumento grazie al quale riorganizzare le relazioni reciproche e la struttura nella quale si realizzano. Quello che stiamo vivendo \u00e8 uno di quei momenti. [&#8230; L&#8217;idrogeno \u00e8 una promessa per il futuro dell&#8217;umanit\u00e0 sulla terra. Dipender\u00e0 da noi se questa promessa\u00bb sar\u00e0 utilizzata bene o male (p. 310).<\/p>\n<p style=\"text-align: justify;\">Ne <em>Il secolo biotech<\/em> leggiamo che \u00abla rivoluzione della biotecnologia ci obbligher\u00e0 a riconsiderare [&#8230;] i nostri valori pi\u00f9 profondi e ci costringer\u00e0 a porci di nuovo [&#8230;] la domanda fondamentale sul significato e Io scopo dell&#8217;esistenza. E questo potrebbe rappresentare il risultato pi\u00f9 importante. Il resto dipende da noi\u00bb (p. 370).<\/p>\n<p style=\"text-align: justify;\">E, <em>dulcis in fundo<\/em>, da <em>II sogno, europeo<\/em>: \u00abquesti sono tempi tumultuosi [&#8230;] Il Sogno europeo \u00e8 un fascio di luce in un paesaggio sconvolto: ci indica la via verso una nuova era di inclusivit\u00e0, diversit\u00e0, qualit\u00e0 della vita, &#8220;gioco profondo&#8221;, sostenibilit\u00e0, diritti umani universali, diritti della natura e pace sulla terra. Gli americani sono soliti dire che per il Sogno americano vale la pena morire. Facciamo in modo che per il Sogno europeo valga la pena vivere\u00bb (p. 391).<\/p>\n<p style=\"text-align: justify;\">Una chiusa che condensa il programma chiaramente politico di Rifkin e che ci sentiamo di sottoscrivere, a patto che la nuova era comprenda la vittoria dell&#8217;Italia ai campionati mondiali di calcio, anche se questa manifestazione di cinismo conferma i peggiori luoghi comuni sugli europei.<\/p>\n<p style=\"text-align: justify;\">\u00c8 tempo di passare al nostro secondo tipo, l&#8217;intellettuale salottiero: il candidato migliore sembra essere Fernando Savater, professore di filosofia all&#8217;Universit\u00e0 di Madrid, autore di un numero imprecisato di libri, articoli ecc. La produzione \u00e8 talmente vasta che le sciocchezze non dovrebbero mancare; per la stessa ragione, per\u00f2, la ricerca \u00e8 ardua e pi\u00f9 difficile risulta il tentativo di ricavare un disegno coerente dietro ai capricci, agli aneddoti e alle opinioni che si susseguono tra le pagine.<\/p>\n<p style=\"text-align: justify;\">Per esempio, <em>Brevissime teorie<\/em> rappresenta una sorta di raccolta di <em>essais<\/em>, in cui Savater rif\u00e0 il verso a Montaigne e parla di tante cose disparate, attingendo con liberalit\u00e0 alla sua vena di scettico e disincantato osservatore del mondo. Nel penultimo capitolo, significativamente intitolato <em>Ideoclip<\/em>, l&#8217;autore raccoglie frammenti sconnessi, lunghi qualche riga, che, in tre pagine, danno l&#8217;idea di come sono strutturate le altre trecento.<\/p>\n<p style=\"text-align: justify;\">Si potrebbe avere l&#8217;impressione del caos, ma non \u00e8 cos\u00ec, come fa notare il testo riportato in quarta di copertina, che parla di \u00abuna trama ben precisa\u00bb. Per svelarla, si pu\u00f2 ricorrere a un testo pi\u00f9 recente, <em>Le domande della vita<\/em>: Savater lo qualifica come \u00abun invito o un proemio alla filosofia per qualunque profano\u00bb che sia interessato a quello che la filosofia oggi pu\u00f2 dirci, insomma un invito alla filosofia che \u00e8 \u00abinvito a filosofare\u00bb (pp. XI-XII).<\/p>\n<p style=\"text-align: justify;\">Il libro costituisce un&#8217;ampia rassegna di problemi, con riferimenti ai principali protagonisti della tradizione occidentale (con qualche assenza illustre). La trama del libro diventa di nuovo evidente alla fine, quando Savater tira le fila della sua sintesi filosofica in quattro punti: \u00ab<em>primo<\/em>, che non esiste la filosofia, ma esistono le filosofie e, soprattutto, il filosofare [&#8230;], <em>secondo<\/em>, [..,] che l&#8217;impegno di filosofare \u00e8 molto pi\u00f9 importante di ciascuno di coloro che [&#8230;] vi si sono dedicati [&#8230;], <em>terzo<\/em>, che perfino i filosofi migliori hanno detto notevoli idiozie e hanno commesso gravi errori [&#8230;], <em>quarto<\/em>, che riguardo a certe domande estremamente generali, imparare a domandare correttamente significa anche imparare a diffidare delle risposte troppo chiare\u00bb (pp. 234-235).<\/p>\n<p style=\"text-align: justify;\">Questi quattro punti sembrano un po&#8217; generici: si provi a sostituire alla coppia &#8220;filosofia-filosofare&#8221; altre coppie come &#8220;politica-far politica&#8221;, &#8220;sport-fare sport&#8221;, &#8220;maternit\u00e0-essere madre&#8221; o persino &#8220;vita-vivere&#8221;. Forse l&#8217;unico punto che ha una specificit\u00e0 filosofica \u00e8 il quarto, rispetto al quale le ultime pagine del volume rappresentano un commento quanto mai chiaro.<\/p>\n<p style=\"text-align: justify;\">In esse Savater definisce la mentalit\u00e0 religiosa come \u00ab<em>direttamente<\/em> opposta a quella filosofica\u00bb, in quanto per la mentalit\u00e0 religiosa una volta che si \u00e8 trovato in Dio il senso del mondo, \u00ab<em>ormai<\/em> \u00e8 legittimo smettere di interrogarsi\u00bb (p. 237, corsivi originali). Quindi \u00e8 la religione la risposta troppo chiara, di cui diffidare, a quelle domande estremamente generali che ogni uomo si fa. Ed \u00e8 una risposta dannosa perch\u00e9 interrompe il gioco del domandare, dell&#8217;indagare.<\/p>\n<p style=\"text-align: justify;\">Per precisare ulteriormente il quadro, spostiamoci verso <em>Il coraggio di scegliere<\/em>, una riflessione sulla libert\u00e0, che propone nella seconda parte di scegliere la verit\u00e0, il piacere, la politica, l&#8217;educazione civica, l&#8217;umanit\u00e0, il contingente.<\/p>\n<p style=\"text-align: justify;\">Il senso di queste scelte diventa di nuovo evidente nella parte finale, in cui Savater scaltramente identifica enfasi e banalit\u00e0: \u00abla banalit\u00e0 che si oppone all&#8217;assolutizzazione \u00e8 senza dubbio la cosa meno banale di tutte, quella che meglio conserva le proprie proporzioni.<\/p>\n<p style=\"text-align: justify;\">L&#8217;autentica banalit\u00e0 morbosa \u00e8 quella che rende necessario ci\u00f2 che \u00e8 contingente [&#8230;]. La banalit\u00e0 \u00e8 la necessit\u00e0 di mettere la lettera maiuscola a tutto ci\u00f2 che, senza di essa, nella sua effimera e commovente brevit\u00e0, dovrebbe suscitare ammirazione e rispetto da parte nostra\u00bb (pp. 147-148). Bisogna scegliere <em>le<\/em> verit\u00e0 o gli uomini, sempre al plurale e senza mai mettere le maiuscole.<\/p>\n<p style=\"text-align: justify;\">Il culmine dell&#8217;abilit\u00e0 salottiera (e la massima concentrazione di sciocchezze) si ha per\u00f2 ne <em>I dieci comandamenti<\/em> <em>nel ventunesimo secolo<\/em>, una revisione del testo biblico sulla base dei cambiamenti attuali (oggetto, tra l&#8217;altro, di una stroncatura solenne da parte di Giorgio Israel, su \u00abII foglio\u00bb del 28 giugno 2005). Gli argomenti si prestano a maestosi giochi di parole: per esempio, nel commentare il &#8220;non uccidere&#8221;, Dio viene qualificato come il \u00abgrande assassino universale\u00bb, che ci uccide tutti (p. 67).<\/p>\n<p style=\"text-align: justify;\">Il tono rimane scanzonato e i problemi vengono percorsi con l&#8217;ausilio di lunghe citazioni, per arrivare alle domande che devono in un certo senso sostituire gli ordini impartiti a suo tempo da Dio. In una paradossale conclusione, Savater sottolinea come l&#8217;immagine di Cristo sia infinitamente poetica per la sua sofferenza, ma \u00abdal punto di vista della legalit\u00e0, il dio vendicativo e crudele \u00e8 assai pi\u00f9 efficace, poich\u00e9 quello amorevole dice &#8220;amatevi gli uni gli altri, e non avrete bisogno di leggi&#8221; [&#8230;] ed \u00e8 vero, ma sfortunatamente noi non ci amiamo gli uni gli altri. Torniamo perci\u00f2 a un altro, pi\u00f9 incisivo comandamento: &#8220;Temetevi a vicenda e accettate le leggi&#8221;\u00bb (p. 141).<\/p>\n<p style=\"text-align: justify;\">Il paradosso \u00e8 per\u00f2 solo apparente: se si guarda bene, anche in questo caso la favola \u00e8 assai banale e fortemente coerente. L&#8217;uomo deve sfuggire i termini enfatici, quelli con la lettera maiuscola e al singolare, perch\u00e9 \u00e8 l&#8217;unico modo per vivere la sua pienezza, la sua gioia. Non ci pu\u00f2 accontentare di risposte troppo facili &#8211; quelle religiose -anche perch\u00e9 fanno smettere il gioco della ricerca; ma se tutto fosse ricercabile e sperimentabile allo stesso modo, si finirebbe per non avere argini a soprusi e violenza.<\/p>\n<p style=\"text-align: justify;\">La legalit\u00e0 diventa allora necessaria per garantire l&#8217;equilibrio e la convivenza, purch\u00e9 rispetti quelle regole che le permettono di non essere totalitaria, ossia la pluralit\u00e0 delle verit\u00e0, degli uomini, delle opinioni e dei costumi. L&#8217;unica cosa che non va limitata \u00e8 il gioco del conversare. Insomma, un&#8217;altra versione della favola postmoderna, meno nutrita di dati e di espressioni <em>high teck<\/em>, ma straordinariamente affine a quella di Rifkin.<\/p>\n<p style=\"text-align: justify;\">\u00c8 giunta l&#8217;ora di tornare al nostro Frankfurt e scendere a un livello pi\u00f9 profondo: che cosa sta dietro al proliferare delle sciocchezze? Quelle forme di scetticismo che invitano ad abbandonare l&#8217;ideale dell\u2019<em>esattezza<\/em> a favore di quello della <em>sincerit\u00e0<\/em>. Non possiamo sapere come stanno le cose, ma almeno possiamo sapere che cosa pensiamo: \u00abdato che non ha senso cercare di essere fedeli ai fatti, allora [l&#8217;individuo] dovr\u00e0 invece tentare di essere fedele a se stesso\u00bb (pp. 61-62). Ma questa seconda opzione non ha, alla luce delle nostre conoscenze, migliori probabilit\u00e0 di resistere alle obiezioni degli scettici. \u00abE, se questo \u00e8 vero, la sincerit\u00e0 \u00e8 in s\u00e9 una\u00bb sciocchezza (p. 62).<\/p>\n<p style=\"text-align: justify;\">I due nostri campioni dell&#8217;ovvio, l&#8217;editorialista ipertrofico e l&#8217;intellettuale salottiero, sono sicuramente sinceri riguardo a ci\u00f2 che pensano. La loro bella favola maschera un&#8217;operazione pi\u00f9 sottile, la cancellazione della differenza tra la favola e il discorso veritiero, da ridurre a una semplice variazione retorica, a una favola tra le altre. Non c&#8217;\u00e8 verit\u00e0 obiettiva, ci sono solo le opinioni: meglio allora scegliere quelle pi\u00f9 utili a un futuro migliore (Rifkin) e a una convivenza civile e gioiosa (Savater).<\/p>\n<p style=\"text-align: justify;\">E chi non vuole questi obiettivi? Di fronte ai problemi complessi e difficili, i cantastorie se la cavano con un po&#8217; di sciocchezze. E al crescere delle sciocchezze, diminuisce la nostra capacit\u00e0 di separare il vero dal falso e, quindi, la speranza di risolvere i problemi. \u00c8 questo il lato davvero umoristico e profondamente morale del discorso di Frankfurt, il Iato che ci svela quella che, con un ultimo funambolismo, potremmo chiamare la malvagit\u00e0 del banale.<\/p>\n<p style=\"text-align: justify;\">_________________<\/p>\n<p style=\"text-align: justify;\"><em><strong>Roberto Presilla<\/strong> \u00e8 professore incaricato di Logica presso la Lumsa di Roma. \u00c8 autore dei saggio <\/em>Olismo e significato<em> nel programma di ricerca di Michael Dummett (2000) e ha scritto la presentazione del volume collettaneo <\/em>L&#8217;uomo alla ricerca della verit\u00e0. Filosofia, scienza, teologia: prospettive per il terzo millennio<em> (2005).<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vita e Pensiero n.1 gennaio-febbraio 2006 L&#8217;editorialista ipertrofico e l&#8217;intellettuale salottiero sono il paradigma di una cultura di tendenza che non ha pi\u00f9 il problema della verit\u00e0 e produce, se non falsit\u00e0, certamente un bel numero di pagine perlomeno opinabili. di Roberto Presilla<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":34019,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[25],"tags":[1219],"class_list":["post-1921","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sguardo-sul-nostro-tempo","tag-sciocchezze","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>I campioni dell&#039;ovvio, ovvero la malvagit&agrave; del banale - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"I campioni dell&#039;ovvio, ovvero la malvagit&agrave; del banale - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2006-03-09T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-05-09T10:45:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/03\/comizio.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"271\" \/>\n\t<meta property=\"og:image:height\" content=\"186\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"I campioni dell&#8217;ovvio, ovvero la malvagit&agrave; del banale\",\"datePublished\":\"2006-03-09T23:00:00+00:00\",\"dateModified\":\"2016-05-09T10:45:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\\\/\"},\"wordCount\":3177,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/03\\\/comizio.jpg\",\"keywords\":[\"sciocchezze\"],\"articleSection\":[\"Sguardo sul nostro tempo\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\\\/\",\"name\":\"I campioni dell'ovvio, ovvero la malvagit&agrave; del banale - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/03\\\/comizio.jpg\",\"datePublished\":\"2006-03-09T23:00:00+00:00\",\"dateModified\":\"2016-05-09T10:45:40+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/03\\\/comizio.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/03\\\/comizio.jpg\",\"width\":271,\"height\":186},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"I campioni dell&#8217;ovvio, ovvero la malvagit&agrave; del banale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"I campioni dell'ovvio, ovvero la malvagit&agrave; del banale - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\/","og_locale":"it_IT","og_type":"article","og_title":"I campioni dell'ovvio, ovvero la malvagit&agrave; del banale - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2006-03-09T23:00:00+00:00","article_modified_time":"2016-05-09T10:45:40+00:00","og_image":[{"width":271,"height":186,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/03\/comizio.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"15 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"I campioni dell&#8217;ovvio, ovvero la malvagit&agrave; del banale","datePublished":"2006-03-09T23:00:00+00:00","dateModified":"2016-05-09T10:45:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\/"},"wordCount":3177,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/03\/comizio.jpg","keywords":["sciocchezze"],"articleSection":["Sguardo sul nostro tempo"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\/","name":"I campioni dell'ovvio, ovvero la malvagit&agrave; del banale - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/03\/comizio.jpg","datePublished":"2006-03-09T23:00:00+00:00","dateModified":"2016-05-09T10:45:40+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/03\/comizio.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/03\/comizio.jpg","width":271,"height":186},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/i-campioni-dellovvio-ovvero-la-malvagit-del-banale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"I campioni dell&#8217;ovvio, ovvero la malvagit&agrave; del banale"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1921","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1921"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1921\/revisions"}],"predecessor-version":[{"id":34020,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1921\/revisions\/34020"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/34019"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1921"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1921"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1921"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}