{"id":1823,"date":"2006-01-27T00:00:00","date_gmt":"2006-01-26T23:00:00","guid":{"rendered":""},"modified":"2016-06-15T15:42:50","modified_gmt":"2016-06-15T13:42:50","slug":"ai-confini-della-vita","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ai-confini-della-vita\/","title":{"rendered":"Ai confini della vita"},"content":{"rendered":"<div style=\"text-align: center;\">Conferenza che si \u00e8 svolta a Marina di Pisa l\u201911 marzo 2005<\/div>\n<div style=\"text-align: center;\">organizzata dalla Circoscrizione 1 e dal <strong>Centro Cattolico di Documentazione<\/strong><\/div>\n<div style=\"text-align: center;\"><\/div>\n<p style=\"text-align: center;\">Hanno partecipato:<\/p>\n<p style=\"text-align: center;\">prof. <strong>Antonio Boldrini<\/strong> <em>Direttore U.O. Neonatologia \u2013 Pisa<\/em><\/p>\n<p style=\"text-align: center;\">dott.sa <strong>Laura<\/strong> <strong>Guerrini <\/strong><em>U.O. Neonatologia \u2013 Pisa<\/em><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-34908\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/01\/rianimazione.jpg\" alt=\"rianimazione\" width=\"250\" height=\"159\" \/><\/p>\n<p style=\"text-align: center;\">&#8211; Trascrizione <strong>riveduta dai relatori<\/strong>\u00a0&#8211;<\/p>\n<div>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\"><strong>Antonio Boldrini: <\/strong><\/div>\n<\/div>\n<p style=\"text-align: justify;\">Dar\u00f2 un taglio pi\u00f9 pratico a questo argomento che riguarda il nostro mestiere che ci pone ai confini della vita, creandoci grossi problemi che non risolveremo stasera, ma dei quali discuteremo assieme a voi. Una cosa che volevo far presente \u00e8 che un obbiettivo primario dell\u2019Organizzazione Mondiale della Sanit\u00e0 \u00e8 quello di cercare di garantire il miglioramento qualitativo della vita della mamma e del bambino.<\/p>\n<p style=\"text-align: justify;\">Ma noi sappiamo anche com\u2019\u00e8 la situazione nazionale, attualmente, che cosa \u00e8 successo negli anni \u201960 quando vi erano circa 1 milione di nati all\u2019anno fino agli anni 2000 quando c\u2019\u00e8 stato il crollo di quasi il 50% della natalit\u00e0. Gli effetti di questo crollo li abbiamo visti tutti e specialmente gli insegnanti lo sanno bene.<\/p>\n<p style=\"text-align: justify;\">Questo ha fatto s\u00ec che il neonato sia diventato un bene ancora pi\u00f9 prezioso, lo \u00e8 sempre stato, ma ora \u00e8 preziosissimo, se si pu\u00f2 dire cos\u00ec. Questo ha comportato anche un\u2019aspettativa di vita e di qualit\u00e0 della vita stessa sensibilmente maggiore; pensiamo a certe frasi che si sentivano 50-60 anni fa: \u201csiete giovani, ne farete altri\u201d.<\/p>\n<p style=\"text-align: justify;\">Adesso si accentuano sempre pi\u00f9 le esigenze, per chi si appresta ad affrontare una gravidanza, ad avere delle garanzie. Ora \u00e8 altrettanto chiaro che da quando ci siamo posti il problema di cercare di capire meglio il neonato, questo ha portato non solo a considerare questo individuo un soggetto che non poteva essere pensato come un piccolo bambino; da anni, da circa un secolo, il bambino non era pi\u00f9 considerato un piccolo uomo, ma un\u2019entit\u00e0 a s\u00e9 degna di un\u2019attenzione particolare al punto che chi si occupa di questo individuo ne ha preso anche il nome di neonatologo.<\/p>\n<p style=\"text-align: justify;\">Tutta questa cultura ha portato poi anche alla traduzione in pratica di tecnologie particolarmente avanzate che hanno consentito sopravvivenze fino a qualche anno fa addirittura impensabili. Una nostra paziente, che adesso ha quasi 3 anni, nacque di 23 settimane, fino a qualche anno fa si considerava la possibilit\u00e0 di sopravvivenza non al di sotto delle 28 settimane, si parla di una bambina piccolissima le cui dimensioni superavano di poco quelle di un comune termometro. Questo \u00e8 l\u2019aspetto per noi gratificante, migliore, che, per\u00f2, ci deve far riflettere.<\/p>\n<p style=\"text-align: justify;\">Di fronte a queste situazioni splendide bisogna stare attenti ai trionfalismi, perch\u00e9 i trionfalismi si portano dietro quello che \u00e8 poi il rovescio della medaglia. Rovescio della medaglia rappresentato dal fatto che, di fronte a questi successi, si instaurano aspettative di vita tali per cui, accettare l\u2019eventuale fallimento come la morte o la sopravvivenza con gravi handicap e sequele neurologiche, diventa sempre pi\u00f9 difficile.<\/p>\n<p style=\"text-align: justify;\">Allora quando ci si presenta un neonato ai confini di quella che \u00e8 la nostra possibilit\u00e0 e anche la nostra conoscenza, \u00e8 chiaro che ci si pongono tante domande. Una delle domande che ci poniamo \u00e8 anche questa: \u00ab<em>se in tutti i casi l\u2019intervento medico rappresenti sempre il miglior interesse per questo paziente particolarissimo, per questo neonato\u00bb. <\/em>Ci possono essere tanti comportamenti, da quello pi\u00f9 classico dell\u2019eutanasia, all\u2019astensione completa dall\u2019assistenza (\u201c<em>guardo ma non intervengo<\/em>\u201d o addirittura \u201c<em>lasciamolo morire in pace<\/em>\u201d).<\/p>\n<p style=\"text-align: justify;\">Ci pu\u00f2 essere un altro modo di comportarsi che invece \u00e8 tipicamente \u201caggressivo\u201d: non si accetta in nessun modo la morte, la si affronta al punto tale da dimenticarsi che il paziente sta diventando un campo di battaglia, \u00e8 il classico accanimento terapeutico. Ma c\u2019\u00e8 anche un altro modo che pu\u00f2 essere quello di considerare la vita, sicuramente un bene supremo, ma non un valore assoluto per cui possiamo accettare la possibilit\u00e0, l\u2019inevitabilit\u00e0 della morte. Noi la traduciamo nell\u2019attivarci per una rianimazione, ma disponibili anche a interromperla. Cosa dice la legge. Noi viviamo in una nazione che ha le sue leggi, magari discutibili, ma che ci sono.<\/p>\n<p style=\"text-align: justify;\">Innanzitutto sappiamo che \u00e8 vietata l\u2019eutanasia dal codice penale e anche dal codice deontologico che riguarda noi sanitari. Codice che dice, a noi medici, che dobbiamo proseguire una terapia di sostegno vitale finch\u00e9 ritenuta ragionevolmente utile, cio\u00e8 fino a quando non sia accertata la perdita irreversibile di tutte le funzioni dell\u2019encefalo, quella che si chiama la morte cerebrale.<\/p>\n<p style=\"text-align: justify;\">Abbiamo accennato all\u2019accanimento diagnostico. Questo come si esprime: sempre secondo il codice deontologico si configura l\u2019accanimento diagnostico quando ci ostiniamo in trattamenti dai quali non si pu\u00f2 fondatamente attendere un beneficio per il paziente o un miglioramento della qualit\u00e0 della vita.<\/p>\n<p style=\"text-align: justify;\">Com\u2019\u00e8 che si pu\u00f2 realizzare nel nostro settore. In tanti modi, sicuramente quando io sono consapevole che l\u2019atto che sto per compiere \u00e8 di comprovata inefficacia. Oggi sempre di pi\u00f9, nel nostro settore, cerchiamo di orientarci verso le evidenze, le prove. Quando addirittura io col mio agire provoco una sofferenza a questo paziente, ancora maggiore di quella che poi \u00e8 una sua situazione gi\u00e0 grave.<\/p>\n<p style=\"text-align: justify;\">Quando voglio dare impressione di esagerata efficienza, o per compiacere le richieste pressanti dei parenti di far di tutto pur sapendo che non otterremo nessun risultato. Fortunatamente quest\u2019ultimo punto non si verifica pi\u00f9: quando si vogliono sperimentare terapie senza vantaggio alcuno per il paziente stesso all\u2019insaputa dei genitori. Da qualche anno ci vogliono le autorizzazioni e, soprattutto, ci vuole il consenso informato dei genitori.<\/p>\n<p style=\"text-align: justify;\">Per\u00f2 c\u2019\u00e8 da dire che allo stato attuale in Italia non c\u2019\u00e8 nessuna normativa che consenta di interrompere l\u2019assistenza a un neonato. Anche quando si configura la possibilit\u00e0 di una grave, gravissima compromissione della qualit\u00e0 della vita. Questo perch\u00e9 il Codice Penale tutela la vita, tutela la salute, ma demanda allo Stato di occuparsi della qualit\u00e0 della vita di un uomo.<\/p>\n<p style=\"text-align: justify;\">Quindi noi non possiamo interrompere niente; allora alla luce della realt\u00e0 legislativa nella quale ci troviamo, \u00e8 chiaro che quegli atteggiamenti che avevo richiamato, l\u2019eutanasia, l\u2019omissione di soccorso, l\u2019accanimento terapeutico, sicuramente non sono praticabili. \u00c8 giustificabile accettare l\u2019inevitabilit\u00e0, l\u2019ineluttabilit\u00e0 della morte? Come viene considerato il nascituro dal Codice Civile?<\/p>\n<p style=\"text-align: justify;\">Il Codice riconosce per il concepito alcuni diritti che per\u00f2 sono subordinati alla nascita. Praticamente il diritto civile considera la vita prenatale una speranza di vita reale, per\u00f2, alcuni diritti sono riconosciuti; ad es. quello di successione, non solo al nascituro, ma addirittura la nascituro non concepito. Di fatto pre acquisire la capacit\u00e0 giuridico occorre che questo signore sia nato e sia vivo, anche senza vitalit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Cos\u2019\u00e8 la vitalit\u00e0: \u00e8 la possibilit\u00e0 di sopravvivenza extrauterina. Ci sono dei grossi problemi ai quali ci troviamo di fronte quando, per esempio, siamo chiamati per una interruzione volontaria di gravidanza. La famosa legge 194 consente alla gestante, nei primi 90 giorni, di interrompere volontariamente la gravidanza quando questa comporti serio pericolo per la sua salute fisica o psichica.<\/p>\n<p style=\"text-align: justify;\">Ma l\u2019IVG \u00e8 concessa anche dopo i 90 giorni. \u00c8 concessa quando la gravidanza comporti grave pericolo per la vita della donna oppure quando siano accertati processi patologici o stati malformativi del nascituro che determinino grave pericolo per la salute fisica o psichica della donna.\u00a0 L\u2019art.7 della stessa legge recita che \u201c <em>quando sussiste la possibilit\u00e0 per il nascituro di una vita autonoma allora l\u2019IVG pu\u00f2 essere fatta nel caso della lettera A<\/em>\u201d, mentre se il feto \u00e8 malformato, ma ha possibilit\u00e0 di sopravvivenza, il medico \u00e8 tenuto ad adottare ogni misura idonea a salvaguardare la sua vita.<\/p>\n<p style=\"text-align: justify;\">Quindi \u00e8 evidente che questa legge sposta l\u2019equilibrio madre-feto nei primi 90 giorni a favore della madre, ma man mano che procede la gravidanza lo sposta a favore del nascituro, fino a imporre a noi di salvaguardare la sua vita quando vi sia possibilit\u00e0, sottolinea la legge, di vita autonoma.<\/p>\n<p style=\"text-align: justify;\">Questo ci introduce a un altro grosso problema, forse il punto focale, il concetto di vitalit\u00e0: quand\u2019\u00e8 che c\u2019\u00e8 questa possibilit\u00e0 di vita autonoma? Quali sono i limiti e se esistono dei dati oggettivi per definirla questa potenzialit\u00e0 di sopravvivenza. Dobbiamo dire che questo della vitalit\u00e0 \u00e8 un concetto tempo-luogo dipendente, molto condizionato da queste famose risorse umane e tecnologiche.<\/p>\n<p style=\"text-align: justify;\">Parliamoci chiaro, se Giorgia, che \u00e8 nata tre anni fa in un centro di terzo livello di terapia intensiva a 23 settimane e del peso di ca. 500 grammi, \u00e8 sopravvissuta, sarebbe sopravvissuta se fosse nata in un ospedale a Malindi in Kenya dove non ci sono risorse umane ma, soprattutto, non ci sono risorse tecnologiche disponibili? Non possiamo dire che a 23 settimane sopravvivono <em>tout-cour<\/em>, ma bisogna dire anche dove c\u2019\u00e8 la possibilit\u00e0 che questo avvenga. Diventa difficile, se non impossibile, la stessa definizione normativa, rigida e che possa avere una validit\u00e0 generale, del concetto di vitalit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Certamente ci sono dei fattori pesantemente condizionanti, uno lo abbiamo gi\u00e0 nominato, \u00e8 quello dell\u2019et\u00e0 gestazionale e poi la concomitanza della presenza di malformazioni. E allora cosa possiamo dire su questo problema che poi \u00e8 il problema: ci sono tante indicazioni in letteratura.<\/p>\n<p style=\"text-align: justify;\">I giapponesi hanno posto il loro limite di vitalit\u00e0 a 22 settimane completate, la stragrande maggioranza della letteratura americana e europea riporta nessuna possibilit\u00e0 di sopravvivenza al di sotto dei 154 giorni (qualche anno fa si parlava di 180), 22 settimane. Si d\u00e0 una possibilit\u00e0 per quelli che nascono tra la 21 e la 22ma settimana e 6 giorni (154-160 giorni); cominciano a comparire delle percentuali di sopravvivenza ad et\u00e0 gestazionali successive.<\/p>\n<p style=\"text-align: justify;\">Nel 1978 i \u201csacri testi\u201d che per noi medici sono quelli americani, ci dicevano che se nasceva un bambino sotto il chilo di peso era addirittura non etico cercare di farlo sopravvivere, di rianimarlo, perch\u00e9 quasi tutti morivano e se non morivano avrebbero avuto senz\u2019altro dei gravi handicap.<\/p>\n<p style=\"text-align: justify;\">Port Royale a Parigi, uno dei pi\u00f9 importanti centri europei di Neonatologia, non accettava bambini sotto il chilo. Se noi fossimo stati cos\u00ec rigidi una nostra cara amica che pesava 710 grammi nel 1978, e adesso \u00e8 una brava scrittrice, sarebbe rimasta sotto la mannaia di questo <em>cut off<\/em>. La mentalit\u00e0 latina \u00e8 molto meno rigida di quella anglosassone riguardo ai limiti entro i quali intervenire.<\/p>\n<p style=\"text-align: justify;\">Questi sono problemi enormi e allora permettetemi di citare una frase di Stan Lee, l\u2019ideatore dell\u2019Uomo Ragno, che fa dire al suo acerrimo nemico: \u00ab <em>\u2026 da un grande potere derivano grandi responsabilit\u00e0<\/em>\u00bb. Noi non abbiamo questo grande potere, ma sicuramente abbiamo grandi responsabilit\u00e0.<\/p>\n<p style=\"text-align: justify;\"><strong>Laura<\/strong> <strong>Guerrini:<\/strong><\/p>\n<p style=\"text-align: justify;\">Quello che vorrei proporvi \u00e8 il frutto di\u00a0 alcune riflessioni scaturite da questi anni di lavoro in un reparto di Terapia Intensiva Neonatale durante i quali ho sentito l\u2019esigenza di approfondire alcune tematiche. Il professor Boldrini ha terminato la sua relazione mettendo in evidenza come da un grande potere derivino grandi responsabilit\u00e0; bene, riprendendo questo passaggio finale credo che si possa dire che non esiste un neonatologo (spero) che si senta un supereroe ma ciascuno di noi \u00e8 sicuramente consapevole di dover affrontare dei superproblemi.<\/p>\n<p style=\"text-align: justify;\">Infatti, se andiamo a vedere quali sono le questioni di tipo etico con le quali ci dobbiamo confrontare nel nostro lavoro ci rendiamo conto che queste rappresentano veramente un fardello molto pesante da portare sulle spalle, fardello col quale ci dobbiamo raffrontare praticamente ogni giorno e che, a mio avviso, sono ulteriormente aggravate da nuove difficolt\u00e0.<\/p>\n<p style=\"text-align: justify;\">Queste nascono in parte dal progresso scientifico (e quindi dalla possibilit\u00e0 di far sopravvivere bambini di dimensioni fino a qualche anno fa impensabili), in parte anche dalla trasformazione degli ospedali in aziende, cosa che pu\u00f2 diventare un problema nel momento in cui si sviluppa una mentalit\u00e0 troppo manageriale con conseguenti calcoli economici a volte difficilmente compatibile con la tipologia dei nostri pazienti.<\/p>\n<p style=\"text-align: justify;\">Non va sottovalutato poi il fatto che \u00e8 cambiata anche la figura del medico e dalla vecchia concezione paternalista, nella quale era solamente il medico a decidere quale fosse il miglior atteggiamento terapeutico nei confronti del paziente, si \u00e8 passati a quella che viene definita come alleanza terapeutica nella quale deve essere dato ampio spazio alle richieste dei pazienti, chiedendo quindi ai medici di creare relazioni interpersonali significative.<\/p>\n<p style=\"text-align: justify;\">Nell\u2019ambito della Neonatologia tali relazioni assumono un carattere particolare perch\u00e9 oltre a doverci riferire al piccolo paziente, il neonato, dobbiamo comunicare\u00a0 anche con la famiglia, che in realt\u00e0 \u00e8 la prima referente per i neonati. Proprio dalla famiglia per\u00f2 possono nascere altre difficolt\u00e0 perch\u00e9 essa pu\u00f2 avere delle aspettative non adeguate, essendoci oggi un po\u2019 di confusione su cosa si pu\u00f2 chiedere alla medicina o su cosa ci si pu\u00f2 aspettare o non aspettare da essa e anche perch\u00e9 i genitori sono spesso in possesso di informazioni (ricavate da Internet o da riviste pi\u00f9 o meno specializzate)\u00a0 non sempre corrette.<\/p>\n<p style=\"text-align: justify;\">La societ\u00e0 inoltre aggiunge ulteriori ostacoli con la crescente mentalit\u00e0 di una \u201cmedicina dei desideri\u201d: oggi non solo si tende a pensare che tutto ci\u00f2 che uno desidera debba essere esaudito ma in pi\u00f9 i modelli da cui si derivano i desideri sono quelli della perfezione, del assoluto benessere psico-fisico e, purtroppo, non possiamo garantire per i nostri bambini l\u2019adeguamento a tali modelli.<\/p>\n<p style=\"text-align: justify;\">Non va poi sottovalutato l\u2019aspetto legale, ovvero la maggiore facilit\u00e0 con cui oggi si ricorre a pratiche legali nei confronti dei medici, perch\u00e9 questo pu\u00f2 causare una minore serenit\u00e0 nel lavoro. Se queste sono delle difficolt\u00e0 comuni a tutta la medicina, credo che la Neonatologia abbia una peculiarit\u00e0 che la rende una disciplina unica perch\u00e9 \u00e8 l\u2019unico reparto in cui ci troviamo ogni volta a dover convivere con i due confini della vita: la nascita e la morte e purtroppo anche nello stesso paziente. Questi due aspetti devono allora diventare un punto fondamentale della nostra riflessione.<\/p>\n<p style=\"text-align: justify;\">Mi sembra allora che possiamo partire da una domanda: nell\u2019epoca in cui viviamo, i cambiamenti significativi che si sono verificati nella medicina hanno come conseguenza anche un cambiamento della nostra vita?<\/p>\n<p style=\"text-align: justify;\">Per rispondere a questa domanda vorrei partire da una definizione della bioetica un po\u2019 diversa da quella che conosciamo e che presenta la bioetica come un\u2019attivit\u00e0 filosofica: \u201cLa bioetica \u00e8 la coscienza critica della societ\u00e0 tecnologica\u2026. Il termine \u201ccoscienza critica\u201d indica il livello di chiarificazione e di valutazione morale dello specifico contenuto pratico e teorico introdotto dalle tecnoscienze\u2026 la bioetica si configura come un\u2019attivit\u00e0 filosofica\u2026 poich\u00e9 le domande (oggetto formale) che investono le tecnoscienze (oggetto materiale) sono di natura filosofica e riguardano il significato della costruzione dell\u2019identit\u00e0 umana all\u2019interno della azione tecnologica\u201d(1).<\/p>\n<p style=\"text-align: justify;\">La bioetica cio\u00e8 non \u00e8 una valutazione delle azioni compiute ma deve essere una coscienza critica cio\u00e8 una filosofia che pone alle tecnoscienze le domande di senso legate alla figura di uomo che si vuole raggiungere in questa societ\u00e0 tecnologica.\u00a0 Questa definizione presenta, a mio avviso, una grande novit\u00e0: passa dal \u201ccome ci si deve comportare\u201d al \u201cperch\u00e9\u201d \u00e8 bene fare certe scelte.<\/p>\n<p style=\"text-align: justify;\">Il <em>come<\/em> comportarci \u00e8 un po\u2019 la filosofia della bioetica nordamericana: il principialismo<em>, <\/em>che di fatto nasce come\u00a0 una specie di manuale di istruzioni: di fronte a situazioni limite fornisce indicazioni su come poter agire in concreto. Chiedersi il <em>perch\u00e9<\/em> significa invece fare un\u2019attivit\u00e0 di tipo speculativo e credo che in medicina, soprattutto nel terreno dell\u2019emergenza qual \u00e8 quello in cui operiamo, sia fondamentale domandarsi come \u00e8 coinvolta la persona umana, perch\u00e9 le azioni che noi compiamo mettono proprio in evidenza l\u2019idea che abbiamo della persona, la dignit\u00e0 che le attribuiamo e il valore che ha per noi.<\/p>\n<p style=\"text-align: justify;\">Ma attenzione perch\u00e9 quando parliamo di persona non parliamo solo del paziente, a cui rivolgiamo le nostre attenzioni, ma anche di noi stessi (2). Infatti le persone coinvolte nel nostro lavoro sono varie: il neonato, la sua famiglia, gli operatori sanitari e, se \u00e8 sicuramente difficile conciliare i bisogni di tutti, diventa fondamentale interrogarci su qual \u00e8 la nostra visione dell\u2019uomo, sia esso il paziente, sia l\u2019operatore sanitario che con lui si deve confrontare. Vi propongo allora la visione dell\u2019uomo secondo il modello \u201cpersonalista\u201d nel quale la persona \u00e8 il punto di riferimento di tutto il nostro agire ed ogni individuo appartenente alla specie umana \u00e8 persona.<\/p>\n<p style=\"text-align: justify;\">Da questa premessa deriva che ci\u00f2 che costituisce il valore della persona \u00e8 semplicemente il fatto di esserci e non la capacit\u00e0 che pu\u00f2 avere di esprimere la sua umanit\u00e0, la quale in genere coincide con quella che viene definita la razionalit\u00e0.\u00a0 A mio avviso ci\u00f2 \u00e8 fondamentale, perch\u00e9 senza questo presupposto possiamo correre il rischio di dire \u201cuomo\u201d pensando in realt\u00e0 ad un corpo, il quale per\u00f2 pu\u00f2 evolvere o ammalarsi.<\/p>\n<p style=\"text-align: justify;\">Quello che rimane sempre invece \u00e8 l\u2019umanit\u00e0, anche quando pu\u00f2 essere difficile da percepire (e nei nostri pazienti ci dobbiamo confrontare non eccezionalmente con questo dato). Ribadisco allora che la vita \u00e8 un valore fondamentale ma non assoluto. Fondamentale perch\u00e9 rappresenta la base per poter godere degli altri valori ma non assoluto, poich\u00e9 assoluto \u00e8 il rispetto della persona.<\/p>\n<p style=\"text-align: justify;\">Si potrebbe allora introdurre un concetto un po\u2019 nuovo per la medicina: <em>la reciprocit\u00e0<\/em>, che non significa semplicemente \u201cNon fare agli altri ci\u00f2 che non vorresti fosse fatto a te\u201d, ma in maniera molto pi\u00f9 profonda palesa l\u2019assoluta uguaglianza fra io, operatore sanitario, e il mio paziente riconoscendo che non esiste una differenza di valore.<\/p>\n<p style=\"text-align: justify;\">Il medico allora cambia decisamente il suo ruolo; non \u00e8 pi\u00f9 un tecnico ma prima di tutto \u00e8 un uomo. Se \u00e8 vero che le macchine ci curano, sicuramente \u00e8 solo l\u2019uomo che pu\u00f2 prendersi cura di noi; allora avviene l\u2019evoluzione tipica della medicina contemporanea dal <em>preoccuparsi<\/em>, che vuol dire curare ma che pu\u00f2 sfociare nel fare semplicemente tutto il possibile, al <em>prendersi cura.<\/em><\/p>\n<p style=\"text-align: justify;\">In netto contrasto con la visione personalistica troviamo quella utilitaristica, in realt\u00e0 molto presente oggi. Secondo l\u2019utilitarismo ci\u00f2 che attribuisce dignit\u00e0 alla persona \u00e8 l\u2019autocoscienza e il desiderio, quindi \u2013 e queste sono parole di Singer che \u00e8 uno dei pensatori pi\u00f9 conosciuto di questo modello \u2013 vecchi, handicappati, neonati, anziani che non hanno reale autocoscienza non sono persone.<\/p>\n<p style=\"text-align: justify;\">Esistono allora esseri umani che non sono persone ed esseri non umani che lo sono. Sempre secondo Singer pu\u00f2 essere pi\u00f9 grave uccidere uno scimpanz\u00e9 piuttosto che un essere umano gravemente handicappato. Egli sottolinea ancora come una vita di sofferenze fisiche, non riscattata da qualsiasi forma di piacere e da un livello minimo di autocoscienza, non sia degna di essere vissuta.<\/p>\n<p style=\"text-align: justify;\">Appare chiaro allora come scegliere una visione di uomo piuttosto che un\u2019altra cambi radicalmente il modo col quale possiamo vivere la nostra professione.\u00a0 Dopo queste premesse vorrei passare ad alcune delle argomenti fondamentali, sempre partendo dal tema di questa sera: i confini della vita.\u00a0 Come ha gi\u00e0 accennato il professor Boldrini la vita \u00e8 tutelata dallo Stato e non \u00e8 un caso che proprio la legge 194 ribadisca questo concetto nel suo primo articolo (3).<\/p>\n<p style=\"text-align: justify;\">Il codice di deontologia medica (4) ci richiama al dovere di tutelare la salute, la vita e la salute psichica e anche la Convenzione dei diritti dell\u2019infanzia (5) ribadisce il concetto, mentre Jonas (1979) scrive in maniera poetica e a mio avviso molto bella che \u201cil neonato con il solo suo respiro rivolge inconfutabilmente un DEVI all\u2019ambiente circostante affinch\u00e9 si prenda cura di lui\u201d.<\/p>\n<p style=\"text-align: justify;\">Esistono poi molti altri documenti ma tra questi credo sia significativo quello del Comitato Nazionale di Bioetica (6), che affronta il problema della gravidanza e del parto da un punto di vista bioetico mettendo in evidenza come guardando questo momento dalla parte del nascituro c\u2019\u00e8 solo una risposta: il nascituro ha il diritto di nascere e c\u2019\u00e8 un dovere di aiutarlo per tutti coloro che sono in grado di farlo.<\/p>\n<p style=\"text-align: justify;\">Questo diritto di nascere, una volta raggiunta la capacit\u00e0 di vita autonoma, deve essere riconosciuto a chiunque, ritenendo improponibile una selezione tra esseri umani in base al loro grado di salute.<\/p>\n<p style=\"text-align: justify;\">Viene anche messo in evidenza come sia impossibile decidere della vita di un feto vitale se questo \u00e8 malformato e presumibilmente destinato ad una cattiva qualit\u00e0 della vita. Dando la priorit\u00e0 al diritto del nascituro alla vita, questo documento sottolinea come nel momento in cui si verifichino delle situazioni in cui l\u2019ambiente materno diventa ostile per il bambino \u00e8 consigliabile anticipare il momento della nascita.<\/p>\n<p style=\"text-align: justify;\">Esistono anche delle sentenze interessanti ed in particolare cito quella dell\u2019agosto 2004 (7), che mette in evidenza come non vi sia un diritto a non nascere se non si \u00e8 sani. Certo che non mi permetto di sminuire la drammaticit\u00e0 di certi eventi ma come medico mi interrogo sul ruolo che posso giocare in queste situazioni, cio\u00e8 quando devo comunicare il sospetto (o la certezza) di uno stato malformativo.<\/p>\n<p style=\"text-align: justify;\">A questo proposito vi propongo la riflessione del Comitato siciliano di bioetica:\u00a0 \u201cNella comunicazione della diagnosi il medico trasmette il suo vissuto nei confronti dell\u2019handicap. Se non ha una formazione umana tale da riconoscere il valore di ogni persona al di l\u00e0 della sua \u201cefficienza\u201d, trasmetter\u00e0 un senso di sconforto e di fallimento, la certezza di trovarsi davanti a una condizione di \u201csubumanit\u00e0\u201d improduttiva\u201d (8).<\/p>\n<p style=\"text-align: justify;\">Nella comunicazione quindi mettiamo in gioco il nostro vissuto e, ancora una volta, la visione che abbiamo dell\u2019uomo, del suo valore al di la della sua efficienza. Ho accennato prima al concetto di qualit\u00e0 della vita, di cui tanto sentiamo parlare, anche a sproposito, e che pu\u00f2 essere interpretato in maniera diversa. Il criterio utilitaristico porta addirittura a quantificare la qualit\u00e0 della vita con formule matematiche, stabilendo dei limiti al di sotto dei quali tale qualit\u00e0 non \u00e8 pi\u00f9 significativa e la vita non \u00e8 pi\u00f9 degna di essere vissuta.<\/p>\n<p style=\"text-align: justify;\">In genere i criteri che vengono chiamati in gioco sono la mancanza di autonomia, di coscienza e la presenza di dolore, ma oggi sempre pi\u00f9 si affacciano interrogativi di tipo economico: quanto costa alla societ\u00e0 far vivere questi bambini?<\/p>\n<p style=\"text-align: justify;\">Come gi\u00e0 messo in evidenza si tratta di domande che a noi sembrano un po\u2019 lontane ma se ci guardiamo intorno ci rendiamo conto che basta andare anche poco oltreconfine per constatare che si tratta di problemi reali e ben presto saremo obbligati ad affrontarli anche noi, in un contesto, quello della Neonatologia appunto, in cui la valutazione economica si scontra con la notevole incertezza diagnostica: difficilmente, specialmente nelle primissime fasi di vita dei nostri bambini, siamo in grado di poterci esprimere con una prognosi assolutamente certa (da cui chiaramente dipendono le \u201cconseguenze economiche\u201d della cura, o forse sarebbe meglio dire della <em>care<\/em>, di questi bambini).<\/p>\n<p style=\"text-align: justify;\">Se invece lo stesso concetto lo valutiamo secondo il modello personalista il neonato \u00e8 uomo e lo \u00e8 anche quando \u00e8 fatto di membra contorte, anche quando la sua espressione storica non avverr\u00e0 mai in maniera completa. Anzi, se fossimo tentati di attribuire l\u2019umanit\u00e0 in base alla relazionalit\u00e0, si potrebbe riflettere sul fatto che entrare in relazione non significa semplicemente avere una socialit\u00e0 ma significa comunque farsi riconoscere dall\u2019altro come una persona dotata di propria individualit\u00e0.<\/p>\n<p style=\"text-align: justify;\">Per assurdo, allora, proprio i bambini con handicap sono quelli che maggiormente richiedono l\u2019attenzione della societ\u00e0 e perci\u00f2 hanno un potenziale relazionale pi\u00f9 alto di altri (9). Inoltre se un criterio di civilt\u00e0 pu\u00f2 essere l\u2019amore per i sofferenti (10) \u00e8 chiaro che la societ\u00e0 deve farsi carico dell\u2019accoglienza e della protezione dei bambini sofferenti e, aspetto ugualmente molto importante, dell\u2019accoglienza della sofferenza dei genitori: questi problemi non devono diventare le preoccupazioni della singola famiglia ma devono \u201cricadere\u201d su tutta la societ\u00e0 che dovrebbe essere capace di farli propri. In contrasto con l\u2019aspetto della vita vi \u00e8 la morte.<\/p>\n<p style=\"text-align: justify;\">La morte di un paziente, ed a maggior ragione di uno dei nostri piccoli pazienti, \u00e8 sicuramente uno dei momenti peggiori nella nostra professione. Essa \u00e8 comunque una eventualit\u00e0 che rimane al di l\u00e0 del progresso tecnico e scientifico. E\u2019 sicuramente un dramma per la famiglia ma posso assicurare che \u00e8 sempre causa di sofferenza anche per il medico.<\/p>\n<p style=\"text-align: justify;\">Io sono convinta che nel momento in cui uno di noi si accorgesse di rimanere assolutamente indifferente ad un evento come la morte di un bambino dovrebbe valutare l\u2019eventualit\u00e0 di cambiare tipo di lavoro. E\u2019 chiaro che la nostra sofferenza non \u00e8 minimamente paragonabile al dramma della famiglia, per\u00f2 la morte \u00e8 ugualmente difficile da accettare e pu\u00f2 essere vissuta come un fallimento professionale.<\/p>\n<p style=\"text-align: justify;\">Credo che un passo da fare sia di riuscire a \u201cvivere la morte\u201d. Pu\u00f2 sembrare un\u2019espressione strana, per\u00f2 questo \u201cvivere\u201d significa il riuscire a non proiettare sui bambini le nostre angosce legate all\u2019esperienza della morte, perch\u00e9 solo cos\u00ec potremo conservare quella lucidit\u00e0 che ci consente di operare nel migliore dei modi e cio\u00e8 con il massimo rispetto per il piccolo paziente.<\/p>\n<p style=\"text-align: justify;\">Se si perde di vista questo elemento il rischio pu\u00f2 essere, da un lato, di banalizzare il morire riducendolo ad una statistica biologica, dall\u2019altro di drammatizzarlo\u00a0 lasciandolo nel non senso (11) Mi sembra molto bella l\u2019espressione, usata nella della Carta degli operatori sanitari (12) perch\u00e9 inserisce la morte nella vita, richiamando al fatto che anche nella morte abbiamo una responsabilit\u00e0 terapeutica importante: uguale a quella che dobbiamo esercitare in ogni altro momento del vivere umano.<\/p>\n<p style=\"text-align: justify;\">Se si riuscisse a vivere la morte anche il concetto della \u201csospensione delle cure\u201d assumerebbe secondo me un carattere diverso, pi\u00f9 facilmente conciliabile con la nostra professione.<\/p>\n<p style=\"text-align: justify;\">Si tratta di capire che quando la morte \u00e8 ormai inevitabile e non possiamo fare altro che prolungarla in maniera precaria e penosa allora \u00e8 lecito, in coscienza, rinunciare a proseguire nei trattamenti. Questo perch\u00e9 il dovere di salvare la vita non pu\u00f2 entrare in collisione con il dovere di rispettare la persona e rendersi conto che non c\u2019\u00e8 pi\u00f9 la possibilit\u00e0 di curare un paziente e che quindi pu\u00f2 essere lecito sospendere le cure, pu\u00f2 diventare addirittura un atto di umilt\u00e0.<\/p>\n<p style=\"text-align: justify;\">E\u2019 chiaramente un giudizio molto delicato, che non pu\u00f2 essere sostituito da dati statistici o da linee guida.\u00a0 Io sono molto scettica e critica sull\u2019imposizione di linee guida e protocolli perch\u00e9 nella nostra professione il grosso rischio, a mio avviso, \u00e8 che il nostro operato venga ingabbiato entro confini difficilmente conciliabili con la professione.<\/p>\n<p style=\"text-align: justify;\">Ribadisco inoltre che sospendere le cure non significa abbandonare le terapie, ma per quello che dicevo prima, significa riuscire a conservare un atteggiamento terapeutico anche laddove in realt\u00e0 abbiamo l\u2019impressione di non servire pi\u00f9 a nulla.<\/p>\n<p style=\"text-align: justify;\">Collegato a questo tema non posso non dire due parole riguardo all\u2019eutanasia per riflettere insieme su quanto \u00e8 successo in Olanda. Nell\u2019agosto 2004 \u00e8 stato approvato un protocollo che estende la possibilit\u00e0 di praticare l\u2019eutanasia ai bambini minori di dodici anni e anche ai neonati. In questo protocollo il ruolo decisionale \u00e8 esclusivamente del medico curante, che deve avere il parere favorevole di un medico referente; i genitori sono tenuti completamente fuori da tutto l\u2019iter decisionale.<\/p>\n<p style=\"text-align: justify;\">Ci\u00f2 che ha detto il dott. Verhagen (13) (il medico olandese promotore di questo protocollo) \u00e8 secondo me degno di riflessione. Dopo aver sottolineato il fatto che in Olanda gi\u00e0 da tempo veniva praticata l\u2019eutanasia sui bambini il medico afferma che ogni anno circa 800 bambini vengono liberati con la dolce morte dal dolore; di questi una ventina hanno una esistenza terribile e insopportabile. La domanda che mi \u00e8 affiorata spontanea dopo aver letto questa cosa \u00e8: \u201cE gli altri 780?\u201d. Se solo 20 su 800 avevano una simile esistenza, gli altri con quale criterio sono stati accompagnati alla morte?<\/p>\n<p style=\"text-align: justify;\">D\u2019altra parte se andiamo a vedere la legge olandese sull\u2019eutanasia, denominata \u201cControllo della Cessazione della Vita a richiesta e Assistenza al Suicidio\u201d (Aprile 2002),\u00a0 vediamo che \u00e8 molto particolare, perch\u00e9 c\u2019\u00e8 solo un articolo in cui \u00e8 specificato che la richiesta di morire deve essere spontanea e ponderata, le sofferenze devono essere insopportabili e senza speranza di miglioramento e viene richiesta la necessit\u00e0 di un consulente; viene anche specificata una diversit\u00e0 di comportamento in base all\u2019et\u00e0 del richiedente, dopodich\u00e9 ci sono ben altri 23 articoli che non parlano pi\u00f9 della persona che deve morire ma di quello che il medico deve fare per adempiere in maniera corretta alla legge.<\/p>\n<p style=\"text-align: justify;\">L\u2019impressione \u00e8 dunque che questa non sia tanto una legge a tutela della persona che chiede un procedimento del genere, quanto una legge a tutela del medico, in modo che sappia come comportarsi per evitare qualsiasi implicazione di tipo legale. In Italia, per quanto riguarda i bambini, si pu\u00f2 fare riferimento ad un documento molto recente (14) dove si mette in evidenza che non \u00e8 lecito, n\u00e9 a livello clinico n\u00e9 etico, qualsiasi intervento di tipo eutanasico e viene anche condannata l\u2019eutanasia a carico di bambini con handicap, proprio perch\u00e9 la qualit\u00e0 della vita non pu\u00f2 essere un criterio per decidere se un bambino deve sopravvivere o meno.<\/p>\n<p style=\"text-align: justify;\">Si sottolinea anche un aspetto che ritengo molto importante: un atteggiamento di tolleranza nei confronti di pratiche di questo tipo potrebbe limitare la ricerca nel campo della prevenzione e della cura ma anche attenuare il dovere di solidariet\u00e0 sociale verso i portatori di handicap. Questo \u00e8 un particolare sul quale credo che non si rifletta abbastanza e cio\u00e8 la ricaduta che le leggi hanno sul comportamento sociale. Non \u00e8 forse vero che oggi se una donna in gravidanza riceve una diagnosi di malformazione del feto e nonostante ci\u00f2 si rifiuta di abortire viene considerata una \u201cpersona incosciente ed asociale\u201d?<\/p>\n<p style=\"text-align: justify;\">Sono allora convinta che dovremmo riuscire ad essere artefici di una vera \u201ccultura della vita\u201d, capace cio\u00e8 di rispettare l\u2019altro nella sua umanit\u00e0. In questo contesto, resistere alla volont\u00e0 di una persona che vuole essere aiutata a morire non significa venire meno al rispetto alla sua autonomia quanto piuttosto mandarle il messaggio che la sua presenza per noi \u00e8 preziosa.<\/p>\n<p style=\"text-align: justify;\">E\u2019 chiaro che tutto ci\u00f2 non pu\u00f2 ricadere solo sulle singole famiglie, altrimenti si va incontro a fatti come quelli che ci\u00a0 mostrano le cronache (15), ma non credo neppure che sia un impegno da supereroi dei fumetti: dovrebbe essere un assunzione di responsabilit\u00e0 di tutti i cittadini, ovvero di tutte le persone che vogliono vivere nella societ\u00e0.<\/p>\n<p style=\"text-align: justify;\">Per quanto riguarda la nostra esperienza in questi anni sono stati veramente pochissimi i genitori che ci hanno chiesto di interrompere le cure. Quello che ci chiedono sempre, soprattutto quando siamo costretti a comunicare l\u2019inevitabilit\u00e0 della morte, \u00e8 che i loro bambini non soffrano.<\/p>\n<p style=\"text-align: justify;\">Ed a conferma di come questo sia un pensiero ricorrente nei genitori vi propongo la pagina di un libro (secondo me \u00e8 molto bello e da cui ho tratto numerosi spunti per un mia personale riflessione) scritto da una giornalista che ha vissuto in prima persona l\u2019esperienza della nascita di un bambino prematuro, il suo secondogenito; una esperienza che l\u2019autrice ha raffigurato come un vivere sulle \u201cmontagne russe\u201d per il continuo alternarsi di ansie, speranze, crolli che caratterizzano le degenze (nel caso specifico di circa tre mesi) in un reparto di Neonatologia.<\/p>\n<p style=\"text-align: justify;\">L\u2019autrice scrive: \u201c\u2026Nina compie trentuno giorni e siamo di nuovo sulle montagne russe. Si ricomincia con la flebo di antibiotico. Se la glicemia non scende, dovranno farle l\u2019insulina. &#8211;<em>la bambina ha una ricaduta legata ad una complicazione di tipo infettivo\u00a0 n.d.r.<\/em>&#8211; Le hanno infilato un ago nel braccio sinistro, ma Nina ha le vene sottili come un filo da rammendo, e la cannula \u00e8 uscita. Le \u00e8 venuta una flebite, proprio come la mia.<\/p>\n<p style=\"text-align: justify;\">Ha il polso gonfio e rosso. Che pena. Ora cercheranno una vena pi\u00f9 robusta. La bucheranno dappertutto, come hanno fatto gi\u00e0 altre volte. Non mi capacito di come un essere cos\u00ec piccolo riesca a sopportare tutto questo. Nina non si lamenta mai. Incassa iniezioni, esami, rimescolamenti, tubi in gola. Soltanto, da quando ha la febbre alta, le sono venute due occhiaie cos\u00ec.<\/p>\n<p style=\"text-align: justify;\">Sono scure e profonde. Ho l\u2019impressione che mi guardi e supplichi: adesso basta mamma. Lasciami andare. Non ce la faccio pi\u00f9 a lottare in questo modo. Vorrei risponderle: hai ragione, amore mio. Adesso basta. Invece non le permetto di andarsene. Non che mi illuda di possedere il controllo sulla vita e sulla morte di mia figlia. Semplicemente mi siedo accanto all\u2019incubatrice \u2013 non posso neppure toccarla in questi giorni -, la guardo e le ordino: \u00abResisti!\u00bb\u201d (16).<\/p>\n<p style=\"text-align: justify;\">E\u2019 una maniera molto bella e molto vera di rappresentare come i genitori vivono il rapporto con questi bambini. All\u2019inizio di questo mio intervento avevo raffigurato il neonatologo schiacciato dal peso di tutte le problematiche etiche,\u00a0 ma in realt\u00e0 quello che spero e credo \u00e8 che, ciascuno di noi, facendo un lavoro su s\u00e9 stesso, possa diventare un astronomo, in grado cio\u00e8 di scrutare il cielo dove le stelle sono comunque ancora le problematiche etiche che ho schematizzato all\u2019inizio (e che rimangono i problemi con i quali dobbiamo confrontarci e che non possiamo far finta non esistano) ma con uno strumento ben preciso e cio\u00e8 il cannocchiale che nel nostro caso ha una lente particolare e cio\u00e8 quella dell\u2019antropologia: con questa lente che ci consente di avere un\u2019idea del concetto di uomo, tutte le problematiche che abbiamo davanti diventano un po\u2019 pi\u00f9 chiare.<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 semplice, per\u00f2 la mia esperienza mi porta a dire che quando si conosce il mondo della neonatologia succede un po\u2019 quello che il poeta Marquetz dice accadere ad un babbo: \u201cHo imparato che quando un neonato stringe con il suo piccolo pugno, per la prima volta, il dito di suo padre, lo tiene stretto per sempre.\u201d (17)<\/p>\n<p style=\"text-align: justify;\">Anche noi, nel momento in cui entriamo in contatto con questo mondo, cos\u00ec affascinante e problematico, siamo un po\u2019 presi per mano da questi bambini. Concludo con un passo tratto dal libro (gi\u00e0 citato) pubblicato lo scorso anno, che raccoglie una indagine condotta a Milano in alcuni reparti di rianimazione.<\/p>\n<p style=\"text-align: justify;\">Anche se sono escluse le rianimazioni neonatali, il messaggio che emerge \u00e8, secondo me, oltre che molto bello, applicabile anche alla mia realt\u00e0: \u201cCon la vita e con la morte non si scherza. E ci sono argomenti che vanno trattati con estrema cautela, perch\u00e9 sono in gioco la sofferenza, il dolore, la speranza, la disperazione.[\u2026] E quando ci si trova all\u2019interno di situazioni di confine, anche se sono situazioni ricorrenti, nelle quali ogni scelta pu\u00f2 determinare il futuro della vita altrui, \u00e8 necessario, prima di tutto, comprendere.\u00a0Che cosa richiede da un punto di vista morale, l\u2019esercizio di un\u2019attivit\u00e0 cos\u00ec delicata e spesso anche cos\u00ec amara, com\u2019\u00e8 quella di un rianimatore? Non \u00e8 una domanda retorica! La professionalit\u00e0, la competenza, l\u2019abilit\u00e0, l\u2019esperienza, sono sufficienti a determinare un approccio alle singole situazioni che non lasci spazio al dubbio, o a ripensamenti, se non addirittura a pentimenti? Forse, ci\u00f2 che a volte viene a mancare \u00e8 il tempo e lo spazio per pensare\u201d (18).<\/p>\n<p style=\"text-align: justify;\">Io vi ringrazio per la pazienza, ma soprattutto per avermi obbligato a trovare lo spazio e il tempo per pensare su queste cose. Grazie.<\/p>\n<p style=\"text-align: justify;\"><strong>Note<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>1)<\/strong> A. Pessina, <em>Bioetica \u2013 L\u2019uomo sperimentale<\/em>, Milano 2000<\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 12px;\">2)<\/strong><span style=\"font-size: 12px;\"> cfr. <\/span><em style=\"font-size: 12px;\">Scelte di confine in Medicina<\/em><span style=\"font-size: 12px;\">\u201d a cura di A. Pessina , Milano 2004, 18: \u201cPrima di procedere alla discussione sul <\/span><em style=\"font-size: 12px;\"><span style=\"text-decoration: underline;\">che cosa fare<\/span><\/em><span style=\"font-size: 12px;\"> o sul <\/span><em style=\"font-size: 12px;\"><span style=\"text-decoration: underline;\">chi deve agire<\/span><\/em><span style=\"font-size: 12px;\"> nelle situazioni cliniche di confine, quando tutto \u00e8 sospeso tra la vita e la morte, \u00e8 necessario ritornare a pensare sul <\/span><strong style=\"font-size: 12px;\">chi \u00e8 l\u2019uomo<\/strong><span style=\"font-size: 12px;\">, sia quell\u2019uomo che ci si trova di fronte come paziente, sia quell\u2019uomo che, come agente morale, interviene su di lui, spesso con la mediazione di vari e complessi strumenti\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 12px;\">3)<\/strong><span style=\"font-size: 12px;\"> La Legge 194, la cui denominazione completa \u00e8 \u201cLegge per la tutela della maternit\u00e0 ed interruzione della gravidanza\u201d inizia proprio dicendo all\u2019Art. 1 che \u201cLo Stato tutela la vita umana dal suo inizio\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 12px;\">4)<\/strong><span style=\"font-size: 12px;\"> Infatti nel CODICE DI DEONTOLOGIA MEDICA (1998) all\u2019 Art. 3 troviamo: \u201cDovere del medico \u00e8 la tutela della vita, della salute fisica e psichica dell\u2019uomo e il sollievo dalla sofferenza nel rispetto della libert\u00e0 e della dignit\u00e0 della persona umana, senza discriminazioni di et\u00e0, di sesso, di razza, di religione, di nazionalit\u00e0, di condizione sociale, di ideologia, in tempo di pace come in tempo di guerra, quali che siano le condizioni istituzionali o sociali nelle quali opera.\u201d<\/span><\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 12px;\">5)<\/strong><span style=\"font-size: 12px;\"> Nell\u2019Art. 6 della \u201cConvenzione Internazionale sui diritti dell\u2019Infanzia\u201d proclamata dall\u2019ONU il 20 Novembre 1989 troviamo: \u201cGli Stati parti riconoscono che ogni fanciullo ha un diritto inerente alla vita. Gli Stati parti assicurano in tutta la misura possibile la sopravvivenza e lo sviluppo del fanciullo\u201d. (Art. 6)<\/span><\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 12px;\">6)<\/strong><span style=\"font-size: 12px;\"> CNB, <\/span><em style=\"font-size: 12px;\">La gravidanza e il parto sotto il profilo Bioetico<\/em><span style=\"font-size: 12px;\">, 1998<\/span><\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 12px;\">7)<\/strong><span style=\"font-size: 12px;\"> CORTE DI CASSAZIONE,<\/span><em style=\"font-size: 12px;\"> Sentenza n. 14488,<\/em><span style=\"font-size: 12px;\"> Agosto 2004: \u00a0\u201cSostenere che il concepito abbia un diritto a non nascere, sia pure in determinate situazioni di malformazioni, significa affermare l\u2019esistenza di un principio di eugenesi o di eutanasia prenatale, che \u00e8 in contrasto con i principi di solidariet\u00e0 dell\u2019articolo 2 della Costituzione\u201d.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 12px;\">8)<\/strong><span style=\"font-size: 12px;\"> S. Leone; M. Lo Giudice, <\/span><em style=\"font-size: 12px;\">Maxima debetur puero reverentia <\/em><span style=\"font-size: 12px;\">,\u00a0 ISB \u2013 Acireale 2002: 43<\/span><\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 12px;\">9)<\/strong> <em style=\"font-size: 12px;\">Ibid.<\/em><span style=\"font-size: 12px;\">: 48-49<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>10)<\/strong> Giovanni Paolo II, <em>Messaggio per la giornata Mondiale del Malato<\/em>, 1992.<\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 12px;\">11)<\/strong><span style=\"font-size: 12px;\"> cfr. <\/span><em style=\"font-size: 12px;\">Scelte di confine in Medicina<\/em><span style=\"font-size: 12px;\">\u201d a cura di A. Pessina , Milano 2004 : 14 ss<\/span><\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 12px;\">12)<\/strong><span style=\"font-size: 12px;\"> PONTIFICIO CONSIGLIO DELLA PASTORALE PER GLI OPERATORI SANITARI,<\/span><em style=\"font-size: 12px;\"> Carta degli operatori Sanitari<\/em><span style=\"font-size: 12px;\">, n\u00b0 116: \u201cIl morire appartiene alla vita come sua ultima fase. Va perci\u00f2 curato come suo momento. Interpella dunque la responsabilit\u00e0 terapeutica dell\u2019operatore sanitario come e non meno di ogni altro momento del vivere umano\u201d<\/span><\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 12px;\">13)<\/strong><span style=\"font-size: 12px;\"> \u201cGi\u00e0 adesso l\u2019eutanasia olandese \u00e8 applicata anche ai bambini. Ogni anno la dolce morte libera dai dolori circa 800 bambini olandesi. Di questi almeno una ventina hanno un\u2019esistenza talmente terribile, insopportabile, disperata da fare preferire la morte\u201d <\/span><em style=\"font-size: 12px;\">(ndr: questo \u00e8 quanto \u00e8 stato riportato da tutti i giornali)<\/em><\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 12px;\">14)<\/strong><span style=\"font-size: 12px;\"> COMITATO NAZIONALE DI BIOETICA, <\/span><em style=\"font-size: 12px;\">Mozione sull\u2019assistenza a neonati e a bambini afflitti da patologie o da handicap ad altissima gravit\u00e0 e sull\u2019eutanasia pediatrica<\/em><span style=\"font-size: 12px;\">, (28\/01\/2005): \u201cOgni intervento di carattere intenzionalmente eutanasico nei confronti dei minori non \u00e8 lecito n\u00e9 giuridicamente, n\u00e9 bioeticamente (\u2026). Merita una\u00a0 particolare ferma condanna l\u2019eutanasia a carico di bambini nati con handicap, anche particolarmente severi, dato che la compromissione della cosiddetta qualit\u00e0 della vita, non ne giustifica in alcun caso la soppressione (\u2026). Un diffuso atteggiamento di tolleranza nei confronti della soppressione di neonati con handicap,\u00a0 e ancora di pi\u00f9 la legalizzazione di tale prassi, oltre a costituire obiettivamente una pratica selettiva, potrebbe anche demotivare la ricerca nei confronti della prevenzione dell\u2019handicap medesimo e potrebbe attenuare il dovere di solidariet\u00e0 sociale verso i portatori di handicap e le loro famiglie\u201d (n. 5).<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>15)<\/strong> Si fa riferimento alla vicenda apparsa sui giornali nei giorni precedenti questo incontro relativa ad un collega medico che sapendo di avere un male incurabile ha ucciso il figlio gravemente disabile ed il cui accudimento era a totale suo carico.<\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 12px;\">16)<\/strong><span style=\"font-size: 12px;\"> A. Sartorio, <\/span><em style=\"font-size: 12px;\">L\u2019Arca di Nina<\/em><span style=\"font-size: 12px;\">, TEA, Milano 2003: 123.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 12px;\">17)<\/strong><span style=\"font-size: 12px;\"> G. Marquetz , <\/span><em style=\"font-size: 12px;\">Lettera di addio<\/em><\/p>\n<p style=\"text-align: justify;\"><strong>18)<\/strong> cfr. <em>Scelte di confine in Medicina<\/em>\u201d a cura di A. Pessina , Milano 2004: 8.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Conferenza che si \u00e8 svolta a Marina di Pisa l\u201911 marzo 2005 organizzata dalla Circoscrizione 1 e dal Centro Cattolico di Documentazione Hanno partecipato: prof. Antonio Boldrini Direttore U.O. Neonatologia \u2013 Pisa dott.sa Laura Guerrini U.O. Neonatologia \u2013 Pisa &#8211; Trascrizione riveduta dai relatori\u00a0&#8211;<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ai-confini-della-vita\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":34908,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[1201,1202],"class_list":["post-1823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bioetica","tag-concepito","tag-neonatologia","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ai confini della vita - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ai-confini-della-vita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ai confini della vita - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ai-confini-della-vita\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2006-01-26T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-15T13:42:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/01\/rianimazione.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"281\" \/>\n\t<meta property=\"og:image:height\" content=\"179\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"31 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ai-confini-della-vita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ai-confini-della-vita\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Ai confini della vita\",\"datePublished\":\"2006-01-26T23:00:00+00:00\",\"dateModified\":\"2016-06-15T13:42:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ai-confini-della-vita\\\/\"},\"wordCount\":6276,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ai-confini-della-vita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/01\\\/rianimazione.jpg\",\"keywords\":[\"concepito\",\"neonatologia\"],\"articleSection\":[\"Bioetica\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ai-confini-della-vita\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ai-confini-della-vita\\\/\",\"name\":\"Ai confini della vita - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ai-confini-della-vita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ai-confini-della-vita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/01\\\/rianimazione.jpg\",\"datePublished\":\"2006-01-26T23:00:00+00:00\",\"dateModified\":\"2016-06-15T13:42:50+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ai-confini-della-vita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ai-confini-della-vita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ai-confini-della-vita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/01\\\/rianimazione.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2006\\\/01\\\/rianimazione.jpg\",\"width\":281,\"height\":179},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/ai-confini-della-vita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ai confini della vita\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ai confini della vita - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ai-confini-della-vita\/","og_locale":"it_IT","og_type":"article","og_title":"Ai confini della vita - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ai-confini-della-vita\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2006-01-26T23:00:00+00:00","article_modified_time":"2016-06-15T13:42:50+00:00","og_image":[{"width":281,"height":179,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/01\/rianimazione.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"31 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ai-confini-della-vita\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ai-confini-della-vita\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Ai confini della vita","datePublished":"2006-01-26T23:00:00+00:00","dateModified":"2016-06-15T13:42:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ai-confini-della-vita\/"},"wordCount":6276,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ai-confini-della-vita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/01\/rianimazione.jpg","keywords":["concepito","neonatologia"],"articleSection":["Bioetica"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ai-confini-della-vita\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ai-confini-della-vita\/","name":"Ai confini della vita - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ai-confini-della-vita\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ai-confini-della-vita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/01\/rianimazione.jpg","datePublished":"2006-01-26T23:00:00+00:00","dateModified":"2016-06-15T13:42:50+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ai-confini-della-vita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ai-confini-della-vita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ai-confini-della-vita\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/01\/rianimazione.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2006\/01\/rianimazione.jpg","width":281,"height":179},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/ai-confini-della-vita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Ai confini della vita"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1823"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1823\/revisions"}],"predecessor-version":[{"id":34909,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1823\/revisions\/34909"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/34908"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}