{"id":1746,"date":"2005-12-16T00:00:00","date_gmt":"2005-12-15T23:00:00","guid":{"rendered":""},"modified":"2019-07-24T08:28:03","modified_gmt":"2019-07-24T06:28:03","slug":"lanno-in-cui-il-mondo-fin-diario-del-39-1","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanno-in-cui-il-mondo-fin-diario-del-39-1\/","title":{"rendered":"L&#8217;anno in cui il mondo fin\u00ec. Diario del &#8217;39 (1)"},"content":{"rendered":"<div style=\"text-align: center;\">Pubblicato su <strong>Il Sabato <\/strong>n.34 &#8211; 26\u00a0 agosto1989<strong><br \/>\n<\/strong><\/div>\n<p style=\"text-align: justify;\"><em>Cinquanta anni fa le truppe del F\u00fcrer invadevano la Polonia. Da quel giorno la guerra sar\u00e0 l\u2019unica realt\u00e0 di milioni uomini. Ma come e dove viene preparato il pi\u00f9 grande conflitto mai accaduto? La storia controcorrente del fatale 1939.<\/em><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/World-War.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-14762\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/World-War.jpg\" alt=\"World War\" width=\"140\" height=\"200\" \/><\/a><\/p>\n<p style=\"text-align: center;\">di<strong> Franco Bandini<a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/World-War.jpg\">\u00a0<\/a><\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: center;\"><strong>Il Sabato<\/strong> del 26 agosto 1989<\/div>\n<p style=\"text-align: center;\"><strong>UNDICI RINTOCCHI PER CHAMBERLAIN <\/strong><\/p>\n<p style=\"text-align: justify;\">Vecchio, legnoso e pallidissimo, sir Neville Chamberlain. primo ministro di Sua Maest\u00e0 britannica \u00e8 seduto al tavolo di lavoro in Downing Street numero 10. Sono le undici di domenica 3 settembre 1939, ed all&#8217;undicesimo tocco della campana del Big Ben scadr\u00e0 l&#8217;ultimatum inviato dall&#8217;Inghilterra ad Hitler due ore prima. Tutti sanno e temono che il Cancelliere non accetter\u00e0 di ritirare le sue truppe, che dal primo settembre all&#8217;alba stanno marciando velocemente nel cuore della Polonia, e tutti sanno che non esistono pi\u00f9 vie d&#8217;uscita.\u00a0In Hyde Park. uno dei consueti oratori improvvisati sta urlando: \u00abAbbiamo dato la nostra maledetta parola a quei maledetti polacchi, e che cosa stiamo maledettamente facendo per loro? Un maledetto niente\u00bb.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/Neville_Chamberlain.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-43730 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/Neville_Chamberlain.jpg\" alt=\"\" width=\"228\" height=\"221\" \/><\/a>Il giorno prima, nella stessa ultima frenetica notte, pochi uomini di buona volont\u00e0 han cercato di riannodare convulsamente i fragili fili della pace, ma le parole non hanno pi\u00f9 corso legale di fronte al sangue che scorre, all&#8217;urlo strozzato degli Stukas che bombardano Varsavia. Per questo, per questa straziante vacuit\u00e0 delle piccole azioni dei piccoli uomini schiacciati dalle forze immani del Fato, tutti sanno che la guerra sar\u00e0: nella stanza accanto allo studio del Premier, il presentatore della British broadcasting corporation ha gi\u00e0 apparecchiato i suoi microfoni su un tavolinetto, pronto per andare in onda con le dichiarazioni di Chamberlain, alle 11.15 precise.<\/p>\n<p style=\"text-align: justify;\">Per undici minuti il vituperato \u00abuomo di Monaco\u00bb, colui che col suo ombrello sottobraccio ha ceduto fronte ad Hitler l&#8217;anno precedente, rimane immobile, come pietrificato, poi si scuote e dice a bassa voce: \u00abAvvertite l&#8217;annunziatore la trasmissione \u00e8 posticipata\u00bb.<\/p>\n<p style=\"text-align: justify;\">Lentissimo, passa ancora un minuto. Passano negli occhi assorti di questo fragile eppur fortissimo amico della pace \u00abi cadaveri non ancor sepolti di una guerra non ancor combattuta\u00bb. Stanchissimo, si alza, puntellando le lunghe braccia al tavolo, si dirige ai microfoni, attende il breve annunzio di Alver Liddell, che lo presenta ai milioni di fedeli sudditi sparsi sui Sette Mari, sui cinque Continenti.<\/p>\n<p style=\"text-align: justify;\">\u00abQuesto\u00bb dice Chamberlain con voce velata \u00ab\u00e8 un triste giorno per tutti noi, e per nessuno \u00e8 cos\u00ec triste quanto per me\u00bb. Noi storici continentali, ben allenati a valutare e soppesare sulle bilance di precisione campi di battaglia e divisioni, linee fortificate ed assi di penetrazione, guerre di usura o di rapido corso, non abbiamo quasi alcuna possibilit\u00e0 di \u00absentire\u00bb la \u00abpersona\u00bb Inghilterra, e quindi di capire ed accettare che praticamente tutte le guerre da essa combattute negli ultimi quattro secoli abbiano avuto un carattere preventivo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/nazi-on-poland-line.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-14763 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/nazi-on-poland-line.jpg\" alt=\"nazi on poland line\" width=\"300\" height=\"235\" \/><\/a>Questo accade per il fatto che l&#8217;Inghilterra \u00e8 una potenza marittima, e noi no. Noi crediamo che possedere navi, disporre di una forte marina significhi anche esser potenze navali, ma non ci rendiamo mai conto che le navi sono l&#8217;aspetto terminale di un pensiero politico ben altrimenti importante, il volto visibile e palpabile di un&#8217;indole, di un costume, di un carattere profondo per il quale, a prima di tutto, il mare non \u00e8 un elemento di divisione tra le terre emerse, ma \u00abla larga strada di Dio\u00bb che permette di unirle.<\/p>\n<p style=\"text-align: justify;\">Tutto ci\u00f2 che minaccia questa larga strada mette in discussione le stesse possibilit\u00e0 di sopravvivenza dell&#8217;Inghilterra, e perci\u00f2 deve essere distrutto prima ancora che il pericolo da potenziale divenga attuale. Da parte inglese, la Prima guerra mondiale viene combattuta sullo spettro terrorizzante della Flotta d&#8217;Alto Mare di Tirpitz, e cio\u00e8 su di un dilemma per il quale non c&#8217;\u00e8 che una sola soluzione.<\/p>\n<p style=\"text-align: justify;\">Se la Flotta d&#8217;Alto Mare cresce oltre un limite molto preciso, moriremo: \u00abe l&#8217;unico modo per impedirle di crescere \u00e8 fare una guerra che ci permetta di distruggerla. Oppure, ma la differenza \u00e8 puramente verbale, accettare d\u00ec fare una guerra scoppiata per \u00abfutili motivi\u00bb, in modo tale da poterla distruggere.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec, non \u00e8 il 3 settembre 1939, n\u00e9 per il \u00abfutile motivo\u00bb del Corridoio Polacco che l&#8217;Inghilterra decide per la guerra, ma esattamente nel febbraio precedente, e per una ragione tanto terrorizzante quanto quella del 1914: la decisione di Hitler di porre mano alla costruzione rapida di una fortissima Marina da guerra, capace di recidere in Atlantico tutte le vene ed arterie di traffico che permettono alle isole britanniche di vivere e di prosperare sulle linfe di uno sterminato Impero.<\/p>\n<div id=\"attachment_14764\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/kiegsmarine.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-14764\" class=\"wp-image-14764 size-medium\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/kiegsmarine-300x164.jpg\" alt=\"kiegsmarine\" width=\"300\" height=\"164\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/kiegsmarine-300x164.jpg 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/kiegsmarine.jpg 303w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-14764\" class=\"wp-caption-text\">Il Panzerschiffe Admiral Graf Spee , Admiral Scheer e Deutschland seguiti da incrociatori.<\/p><\/div>\n<p style=\"text-align: justify;\">Quando a Londra arriva clandestinamente l&#8217;intero quadro del \u00abPiano Z\u00bb, approvato a Berlino nella stesura finale da pochissimi giorni, si ripresenta all&#8217;Ammiragliato l&#8217;identico dilemma: se questa nuova Flotta d&#8217;Alto Mare tedesca sar\u00e0 lasciata libera di crescere, entro il 1942 la Gran Bretagna avr\u00e0 perduto la stessa possibilit\u00e0 di combattere una guerra. Nel silenzio di una pace ingannevole si consumer\u00e0 una disfatta dalle proporzioni mondiali.<\/p>\n<p style=\"text-align: justify;\">Non fa meraviglia che al \u00abPiano Z\u00bb ed alle sue sconvolgenti implicazioni, gli storici continentali abbiano dedicato cos\u00ec poca attenzione, visto che gli stessi inglesi \u2014 con una scelta che \u00e8 parte integrante del pensiero navale \u2014 han fatto di tutto per farci girare gli occhi in tutt&#8217;altre direzioni. Ma ora \u00e8 venuto il momento, a cinquant&#8217;anni di distanza, di dire che il \u00abPiano Z\u00bb rappresent\u00f2 effettivamente per le sorti dell&#8217;Europa e del mondo qualcosa di assai\u00a0 pi\u00f9\u00a0 decisivo che non l&#8217;occupazione dell&#8217;Austria, o lo smembramento della Cecoslovacchia, o le preteso hitleriane in Polonia.<\/p>\n<p style=\"text-align: justify;\">Nessuno di questi clamorosi avvenimenti avrebbe mai indotto Ia la Gran Bretagna alla guerra, se non fosse stato per la certezza di non poter conservare la propria e gi\u00e0 precaria superiorit\u00e0 navale per pi\u00f9 di un anno o due.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/guerra_mondiale.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-43731 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/guerra_mondiale.jpg\" alt=\"\" width=\"193\" height=\"261\" \/><\/a>Il \u00abPiano Z\u00bb, difatti, consisteva non soltanto nella costruzione rapida di sei grandissime navi da battaglia armate coi pezzi da 406 millimetri, ma anche o soprattutto nei nuovi criteri del loro impiego: sarebbero state create speciali \u00abTask force\u00bb, ognuna con due navi da battaglia, una portaerei ed un paio di incrociatori pesanti, ed esse avrebbero operato in Atlantico contro il traffico mercantile britannico nei due sensi: bloccando le isole e con la privazione di viveri, materie prime ed energie, nel giro di pochissimi mesi.<\/p>\n<p style=\"text-align: justify;\">Nessuna concentrazione navale britannica e persino franco-britannica avrebbe potuto opporsi con successo ai Leviatani del mare progettati da Raeder, ed anzi, come d&#8217;ordinario succede nella sfera astratta e matematica del pensiero navale, non vi sarebbe stata neanche una guerra, perch\u00e9 non si combatte mai, quando la sconfitta \u00e8 l&#8217;unica possibile risultante di una fredda equazione.<\/p>\n<p style=\"text-align: justify;\">Sappiamo bene, oggi, quando e come la decisione inglese intervenne, perch\u00e9 l&#8217;11 febbraio 1939, provenendo da Berlino, varc\u00f2 la frontiera con l&#8217;Olanda quell\u2019ingegner Otto Kr\u00fcger che da vent&#8217;anni era la miglior spia tecnico-militare che il Secret service avesse mai avuto. Kr\u00fcger era specialista in brevetti elettro-meccanici, molti dei quali erano stati utilizzati dalla Flotta guglielmina nella Prima guerra mondiale, ma poi anche dagli inglesi, che nel 1919 lo avevano reclutato per un altro genere di informazioni.<\/p>\n<p style=\"text-align: justify;\">Otto Kr\u00fcger, istallato a Kiel nella posizione di consulente della Marina, era salito nella considerazione dello Stato Maggiore tedesco fino al punto di essere inserito nel Consiglio di amministrazione dei cantieri Blohm und Voss, ed in quello della Federazione delle industrie tedesche.<\/p>\n<div id=\"attachment_43732\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/guerra_mondiale.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-43732\" class=\"wp-image-43732 size-medium\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/guerra_mondiale-300x175.png\" alt=\"\" width=\"300\" height=\"175\" srcset=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/guerra_mondiale-300x175.png 300w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/guerra_mondiale-768x449.png 768w, https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/guerra_mondiale-1024x598.png 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-43732\" class=\"wp-caption-text\">Kriegsmarine, classe H<\/p><\/div>\n<p style=\"text-align: justify;\">Con queste entrature, fu uno dei pochissimi a conoscere nei dettagli la stesura finale del \u00abPiano Z\u00bb, e non gli fu per nulla difficile recapitare il tutto a Londra, salvo essere arrestato nella sua villa di Godesberg il 7 luglio 1939. Mor\u00ec suicida \u2014 o cos\u00ec si disse \u2014 in un campo di concentramento il 4 settembre dello stesso anno, ma prima dell&#8217;arresto aveva avuto ancora il tempo di trasmettere a Londra l&#8217;analisi dei materiali gi\u00e0 concentrati dall&#8217;industria tedesca sugli scali delle nuove navi da battaglia della classe \u00abH\u00bb.<\/p>\n<p style=\"text-align: justify;\">In questo modo, gli inglesi seppero cosa li aspettava il 12 o 13 del febbraio 1939, per cui non stupisce che il 17 del marzo successivo, abbandonando il vecchio atteggiamento conciliativo, lo stesso Neville Chamberlain si sia scagliato in un pubblico discorso a Birmingham contro la \u00absfida\u00bb tedesca; n\u00e9 che tra il 22 od il 30 gli altrettanto stupefatti polacchi si siano visti offrire e quasi imporre quella garanzia britannica contro l\u2019aggressione che\u00a0 dopo sei anni di guerra, si rivel\u00f2, come del resto era, soltanto carta straccia.<\/p>\n<p style=\"text-align: justify;\">E non \u00e8 senza significato che nei protocolli segreti del Patto si specificasse chiaramente che per aggressione si intendeva quella tedesca: ci\u00f2 permise all&#8217;Inghilterra, appena sei mesi dopo, di far finta che la Russia a sua volta non avesse aggredito la disgraziata Polonia, dal momento che, come si sa, la legge \u00e8 uguale per tutti, ma per alcuni pi\u00f9 uguale che per altri.<\/p>\n<p style=\"text-align: justify;\">Purtroppo, neppure per gli storici i pesi son gli stessi: se lo fossero, qualcuno si sarebbe forse chiesto se all&#8217;alba del 1939 Stalin non avrebbe dovuto e potuto esser considerato un perturbatore della quiete, ed un aggressore altrettanto pericoloso di Hitler. C&#8217;era un materiale abbondantissimo su cui rifletter\u00f2, ma fa parte della sconclusionata temperie del nostro tempo che esso sia stato ignorato allora tanto quanto lo \u00e8 oggi, con pochissime speranze di revisione.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/Urss_armata_rossa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-43733 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/Urss_armata_rossa.jpg\" alt=\"\" width=\"277\" height=\"182\" \/><\/a>In realt\u00e0, accanto ed anzi prima delle controreazioni britanniche che si sono appena descritte, occorre tener conto della linea di moto sovietica tra le due guerre: ma non di quella immaginaria e di comodo, bens\u00ec di quella reale, sepolta purtroppo sotto densi strati di opaca vernice propagandistica, secreta goccia a goccia negli ultimi decenni da un&#8217;agguerrita ed insonne falange di uomini della sinistra intellettuale, con un fenomeno globale che non ha alcun paragone nella storia quanto ad intensit\u00e0, durata e sostanziale disonest\u00e0; non magari per qualche singolo, perch\u00e9, come si sa, la madre del fanatico o dell&#8217;imbecille \u00e8 sempre incinta, ma certo per quei moltissimi divenuti ciechi e sordi per effetto di quella <em>left drift<\/em>, di quella deriva a sinistra che dal 1930 \u00e8 stata forse la caratteristica saliente e mortale del pensiero europeo, tutte le volte che esso s\u00ec \u00e8 applicato al \u00abmistero\u00bb sovietico.<\/p>\n<p style=\"text-align: justify;\">Che poi \u00e8 perfettamente penetrabile non appena si rinunzi a considerare la Russia come un tabernacolo, centro d\u00ec irraggiamento di un nuovo verbo, motore primo di una palingenesi liberatoria dell&#8217;umanit\u00e0.<\/p>\n<p style=\"text-align: justify;\">E si cominci a considerarla per quello che realmente essa \u00e8, o \u00e8 divenuta dopo un primo istantaneo lampo abbagliante, durato soltanto una frazione di secondo, e cio\u00e8 un Impero coloniale disteso su 22 milioni di chilometri quadrati, con problemi di crescita, difesa e sopravvivenza per nulla diversi da quelli che \u00e8 facile analizzare nella vita dei tre o quattro grandi imperi che conosciamo: ed in particolare del tutto identici, fino alla sovrapposizione, a quelli affrontati e risolti pi\u00f9 o meno bene da una lunga teoria di Zar.<\/p>\n<div id=\"attachment_14765\" style=\"width: 240px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/Brest-Litovsk.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-14765\" class=\"wp-image-14765\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/Brest-Litovsk.jpg\" alt=\"Brest-Litovsk\" width=\"240\" height=\"250\" \/><\/a><p id=\"caption-attachment-14765\" class=\"wp-caption-text\">Gli effetti sulla Russia del trattato Brest-Litovsk<\/p><\/div>\n<p style=\"text-align: justify;\">In altri termini, la \u00abpersona\u00bb Unione Sovietica non ha mutato carattere, n\u00e9 riflessi condizionati, per il semplice fatto di aver dato i natali a Lenin, ed aver portato in grembo la Rivoluzione d&#8217;Ottobre. Pensarla diversamente significa dimenticarsi che l&#8217;unica nazione veramente sconfitta nella Prima guerra mondiale non \u00e8 la Germania, ma la Russia, che a Brest Litowsky perde il pi\u00f9 ed il meglio delle sue terre occidentali, la Finlandia, le Repubbliche baltiche, la Carelia, tutta la Polonia, la Bessarabia, regioni di frontiera con la Turchia.<\/p>\n<p style=\"text-align: justify;\">Milioni di uomini e di donne passano otto altre bandiere, nascono nuovi Stati che sono potenziali nemici di domani, le linee di difesa arretrano di centinaia, qualche volta di un migliaio di chilometri, perch\u00e9 ne corrono quasi altrettanti tra i vecchi ed i nuovi confini lungo l&#8217;asse di Varsavia.<\/p>\n<p style=\"text-align: justify;\">L&#8217;imprevista vittoria alleata sui campi di battaglia francesi cauterizza, con Versailles, qualcuna di queste enormi ferite, ma non ripiana il danno globale: la Russia rimane un Impero, per\u00f2 gravemente pregiudicalo dalla sconfitta, con problemi difensivi decuplicati e con una possibilit\u00e0 di sopravvivenza ridotta al minimo. In queste condizioni, la Russia non \u00e8, non pu\u00f2 e non vuole essere la &#8220;guardiana della pace\u201d, bench\u00e9 l&#8217;intera sua propaganda d&#8217;infiltrazione sia basata proprio su questa parola d&#8217;ordine.<\/p>\n<p style=\"text-align: justify;\">Essa tende invece alla rottura dell&#8217;equilibrio europeo, cos\u00ec come si \u00e8 precariamente realizzato nel Salone dell&#8217;Orologio di Versailles, e per arrivarci utilizza una vastissima gamma di strumenti: riarma segretamente la Germania di Weimar, favorisce l&#8217;ascesa di Hitler al potere, sovvenziona attraverso i singoli partiti comunisti \u00abfratelli\u00bb la nascita di quei Fronti Popolari che tanto faranno per disintegrare dall&#8217;interno le possibilit\u00e0 militari soprattutto francesi.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/06\/Stalin_Hitler.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-37903 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2017\/06\/Stalin_Hitler.jpg\" alt=\"\" width=\"240\" height=\"210\" \/><\/a>Ed infine, attraverso un&#8217;analisi molto accurata dei pesi e contrappesi in azione nel complicato meccanismo europeo, sceglie amici e nemici coi quali e contro i quali condurre la tragica danza del Secondo conflitto mondiale. Si fa sempre finta di credere che questa scelta sia stata operata dalla Russia, e meglio sarebbe dire da Stalin, nel corso di quel febbrile agosto del 1939, durante il quale avvenne la rapidissima gestazione del Patto di non aggressione e di amicizia tra Hitler e Stalin.<\/p>\n<p style=\"text-align: justify;\">E si scarica una buona parte del peso morale di questo infausto connubio sulle lentezze, esitazioni e scarsa buona fede di inglesi e francesi, colpevoli di essersi giocati per insipienza l&#8217;indispensabile apporto russo al fronte comune contro Hitler: quasi che in politica avessero davvero corso le bizze e le ripicche.<\/p>\n<p style=\"text-align: justify;\">Sarebbe fin troppo facile dimostrare che Togliatti arriva a Parigi al principio del luglio 1939, col preciso compito d\u00ec \u00aborientare\u00bb i compagni del Pcf su quanto si sta preparando, e perci\u00f2 ben prima delle predette esitazioni e dubbi alleati. Come sarebbe facile far notare che nessuno dei \u00abcolpi del sabato\u00bb di Hitler trova reazione alcuna nella Russia sovietica, a parte alcune fole inventate al solo scopo di giustificare in qualche modo una passivit\u00e0 assai pi\u00f9 sospetta di quelle stesse inglesi e francesi.<\/p>\n<p style=\"text-align: justify;\">Sarebbe dunque facile, ma non porterebbe a quelle conclusioni che invece scendono limpidamente da un altro tipo di analisi, impostato su un genere di fattori molto diverso. In realt\u00e0, tutto comincia con la guerra di Spagna, primo micidiale colpo di clava al fragile equilibrio europeo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/Guerra_civile_spagna-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-41606 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2018\/11\/Guerra_civile_spagna-1.jpg\" alt=\"\" width=\"186\" height=\"271\" \/><\/a>Al \u00abFrente Popolar\u00bb succede la ribellione dei generali franchisti, ed a questa una stabilizzazione dei fronti che sbocca in una guerra civile sanguinosissima e di lunga durata. A tanto si arriva, quasi esclusivamente per il cospicuo sostegno alla Repubblica di armi moderne inviate dall&#8217;Unione Sovietica, e per la celere costituzione di Brigate Internazionali inquadrate da ufficiali sovietici.<\/p>\n<p style=\"text-align: justify;\">Questi decisivi aiuti procedono nel tempo quelli italiani e tedeschi, che assumono una dimensione un po&#8217; pi\u00f9 che modesta soltanto nel dicembre 1936, anche se \u00e8 giusto ricordare che i soldati di Franco riuscirono di fatto a traghettare dal Marocco in Andalusia grazie ad un piccolo numero di aerei da trasporto ceduti da Roma e da Berlino nelle prime giornate dello \u00abalzamiento\u00bb.<\/p>\n<p style=\"text-align: justify;\">Noi forse non sapremo mai quale fu, a proposito della Spagna, la vera linea di condotta sovietica, anche perch\u00e9 in realt\u00e0 ve ne furono due. Una interventista e strettamente solidale con i repubblicani spagnoli, e l&#8217;altra assai pi\u00f9 circospetta e tutto sommato indifferente alle loro sorti. Ed oggi conosciamo anche il perch\u00e9 di questo dualismo, il quale dipese sostanzialmente dal fatto che gi\u00e0 in quel momento Stalin stava perseguendo, contro il parere del Politburo e soprattutto dell&#8217;Armata Rossa, il suo piano di accordo con la Germania.<\/p>\n<p style=\"text-align: justify;\">Gi\u00e0 nel dicembre 1936 egli invia a Berlino il suo fidatissimo amico Kandelaki col compito di discutere un Trattato di commercio, come premessa a pi\u00f9 vaste intese successive. Una procedura identica sar\u00e0 seguita al principio del 1939, e porter\u00e0 al Patto dell&#8217;agosto.<\/p>\n<div id=\"attachment_14766\" style=\"width: 300px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/patto-Molotov-Ribbentrop.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-14766\" class=\"wp-image-14766\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/patto-Molotov-Ribbentrop.jpg\" alt=\"patto Molotov-Ribbentrop\" width=\"300\" height=\"190\" \/><\/a><p id=\"caption-attachment-14766\" class=\"wp-caption-text\">Firma del Patto Molotov-Ribbentrop<\/p><\/div>\n<p style=\"text-align: justify;\">Le ragioni per le quali Stalin sceglie Hitler e non le democrazie occidentali possono dispiacere e persino fare orrore ad un buon comunista, ma sono perfettamente accettabili in termini di politica reale. La Germania del 1937, rinata a nuova vita e gonfia di potenza espansiva, pu\u00f2 dirigersi ad est o ad ovest nella sua ricerca di spazi liberi, giusto o sbagliato che sia. Se si dirigesse ad est, le democrazie potrebbero starsene alla finestra, ben liete di veder cadere l&#8217;ultimo granatiere tedesco sull&#8217;ultimo soldato cosacco. Dunque, occorre deviarne le mire, farsela amica e capovolgere il gioco: cadano, i granatieri tedeschi, sull&#8217;ultimo francese o \u00abtommy\u00bb inglese.<\/p>\n<p style=\"text-align: justify;\">Nella Prima guerra, Francia ed Inghilterra han pagato con quasi tre milioni di morti: c&#8217;\u00e8 la speranza che nella Seconda il prezzo possa essere anche maggiore. La guerra di Spagna mette Stalin con le spalle al muro, perch\u00e9 i suoi uomini, il suo popolo, milioni di comunisti sparsi in tutto il mondo sono fermamente convinti che la missione dell&#8217;Unione Sovietica sia davvero quella di liberare i proletari del pianeta dalle loro catene, abbattendo il \u00abmarcio capitalismo\u00bb, maschera ultima del quale \u00e8 il bieco fascismo.<\/p>\n<p style=\"text-align: justify;\">Dopo vent&#8217;anni di predicazione ideologica, nella quale persino il socialismo ha potuto esser bollato come socialfascismo, non \u00e8 possibile andare a spiegare al popolo, ai comunisti di tutto il mondo, ai compagni del Politburo, che la Rivoluzione mondiale e una favola per bambini, che il capitalismo non sta morendo e che il pericolo fascista pu\u00f2 essere evitato soltanto deviandolo, perch\u00e9 il combatterlo segnerebbe molto probabilmente la perdita dell&#8217;Unione stessa. N\u00e9 Stalin. n\u00e9 alcuno al suo posto pu\u00f2 presentarsi alla tribuna del Presidium e dire questo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/06\/Urss_Nkvd.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-43275 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/06\/Urss_Nkvd.jpg\" alt=\"\" width=\"188\" height=\"268\" \/><\/a>La politica estera dell&#8217;Impero russo \u00e8 prigioniera dei suoi stessi miti, al punto che il suo timoniero non pu\u00f2 neppur pi\u00f9 invocare il \u00absacro egoismo\u00bb o la salute della Repubblica di romana memoria. L&#8217;unico spiraglio rimane la menzogna. Menzogna di sangue, ed annegata nel sangue, perch\u00e9 per poter mentire con qualche efficacia occorre liquidare non soltanto i pochi che potrebbero capire, ma anche coloro che li sostengono, che costituiscono la loro piattaforma di potere, politico o militare.<\/p>\n<p style=\"text-align: justify;\">Nascono da questa esigenza le grandi Purghe del 1937, nasce da qui la prima grossa ondata di diserzioni all&#8217;estero da parte di alti ed ancora integri funzionari della Polizia, della diplomazia e delle Forze Armate sovietiche. E nasce da qui il pi\u00f9 terribile di tutti gli atti di Stalin, quel processo segreto ai generali che spazza via, nel maggio 1937, l&#8217;intero Alto Comando, con Tuchacewsky alla testa, seguito da forse 35mila o 40mila ufficiali dal grado di maggiore in su.<\/p>\n<p style=\"text-align: justify;\">Una vasta moria che potrebbe essere giustificata, se si scarta la spiegazione che se ne \u00e8 data, soltanto dalla pazzia di Stalin: \u00e8 davvero commovente osservare come gli intellettuali della sinistra preferiscano ancora oggi trangugiare questa amarissima medicina, piuttosto che rassegnarsi all&#8217;idea di una Russia emersa banalmente come Impero dagli splendori di una rivoluzione fallita. In verit\u00e0, \u00e8 straordinariamente interessante constatare come dal 1937 in poi le linee di moto tedesche e sovietiche si accostino gradatamente, ma fatalmente.<\/p>\n<div id=\"attachment_43734\" style=\"width: 281px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/guerra_Spagna.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-43734\" class=\"wp-image-43734 size-full\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/guerra_Spagna.jpg\" alt=\"\" width=\"281\" height=\"179\" \/><\/a><p id=\"caption-attachment-43734\" class=\"wp-caption-text\">piloti della Legione Condor<\/p><\/div>\n<p style=\"text-align: justify;\">Dopo il maggio 1937, dopo gli \u00abincidenti di Palma\u00bb con i quali si arriva veramente ad un punto di non ritorno sulla strada della guerra, Stalin ed Hitler perdono qualsiasi interesse al conflitto di Spagna. Il secondo ne disimpegna completamene la Marina, e limita al massimo la partecipazione aeronautica: il primo blocca tutti gli aiuti diretti ed indiretti in armi e materiali, sostituendo ai fatti vaghe promesse, avvolte nel consueto linguaggio dell&#8217;oratoria populista.<\/p>\n<p style=\"text-align: justify;\">In compenso, Stalin ritira dalla Spagna l&#8217;intero gruppo dei consiglieri militari, diplomatici e della Polizia: vanno al muro quasi tutti, in una falcidia cos\u00ec radicale da richiedere una buona spiegazione, che nessuno ha tuttavia ancora data.<\/p>\n<p style=\"text-align: justify;\">Nel 1939 la stessa sorte toccher\u00e0 a migliaia di combattenti repubblicani di Spagna, fortunosamente approdati in Russia come alla Terra Promessa. Con loro, vengono spazzati via tutti i vecchi e provati quadri dei partiti comunisti europei, con l&#8217;unica eccezione di quello italiano, esule a Parigi: ma non \u00e8 un caso fortuito, perch\u00e9 i canali di comunicazione tra Russia ed Italia passano proprio di l\u00ec, e funzioneranno benissimo sino al 1945. Storia ancora non scritta, con qualche piccola speranza che un giorno lo sia, almeno in parte.<\/p>\n<p style=\"text-align: justify;\">Al principio del 1939, tutti coloro che non fanno parte della <em>left drift<\/em> sanno benissimo che il prossimo conflitto scoppier\u00e0 esattamente nel momento di un accordo tra dittatori. Lo sa e lo scrive da tempo Charles Maurras. inascoltato profeta della \u00abAction francaise\u00bb, lo sanno e lo sussurrano quei grandi esperti di politica estera che vivono o meglio vegetano nei campi di concentramento sovietici, e lo sanno, qualunque cosa se ne dica oggi sui testi di storia, anche gli inglesi, i quali non per caso forniscono alla Polonia una garanzia valida soltanto per un attacco tedesco, ma non sovietico.<\/p>\n<p style=\"text-align: justify;\">Ed infine, lo sanno tutte le Cancellerie europee, perch\u00e9 per gli attenti esperti della politica internazionale \u00e8 chiarissimo che la Russia, dopo un sonno apparente di quattro lustri, \u00e8 di nuovo in movimento.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/Finlandia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-43735 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/Finlandia.jpg\" alt=\"\" width=\"177\" height=\"285\" \/><\/a>Nel gennaio 1939, richiede alla Finlandia di poter occupare quattro isolette baltiche, il cui controllo farebbe perdere ad Helsinki ogni possibilit\u00e0 d\u00ec ricevere via mare aiuti dall&#8217;esterno, e subito dopo sguinzaglia una torma di agenti speciali in tutte le zone perdute vent&#8217;anni prima, dalla Carelia alla Bessarabia. Il 3 maggio Litvinov, l&#8217;uomo della conciliazione con l&#8217;Occidente, viene silurato, bruscamente, e deve cedere la sua poltrona a Molotov, il \u00abkammeny sad\u00bb. il \u00absedere di pietra\u00bb pi\u00f9 granitico dell&#8217;intera dirigenza sovietica.<\/p>\n<p style=\"text-align: justify;\">Litvinov ha una moglie inglese, figlia dello storico sir Sidney Low, interamente devota alla causa dell&#8217;amicizia anglo-russa. Quando il marito le osserva tristemente \u00abpenso che abbiano cambiato politica, Ivy\u00bb. essa esplode rabbiosa: \u00abE tutta colpa di quel pazzo di Chamberlain\u00bb. Giudizio che ancor oggi gode di grande favore, ma la cui persistenza dimostra soltanto la rotondit\u00e0 del successo intellettuale raggiunto sul piano mondiale dall&#8217;apparato della propaganda sovietica, quella visibile ed identifi-cabile, e quella sommersa, che passa attraverso innumeri canali, da quelli culturali a quelli di largo consumo, film, romanzi, televisione.<\/p>\n<p style=\"text-align: justify;\">Infatti, dovrebbe essere evidente, ma non lo \u00e8 affatto, almeno a questo presente stadio dello sviluppo della revisione critica del passato, che non si pu\u00f2 parlare di colpe e ragioni di questa o di quello, se prima non si affronta e non si colloca storicamente lo spinoso problema che la Germania pone a noi tutti almeno dal 1870.<\/p>\n<p style=\"text-align: justify;\">Il farlo partendo da Hitler, dalla inaccettabilit\u00e0 di Hitler e dei suoi metodi, significa voler ignorare che Hitler \u00e8 soltanto il punto terminale e davvero non accettabile delle potenti forze espansive delle genti tedesche, costrette in un territorio angusto, privo di difese naturali di un qualche valore sia ad est che ad ovest, ed assoggettate ai pesanti ricatti sulle materie prime e sui commerci che altri Paesi controllano.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/guerra_mondiale-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-43736 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/guerra_mondiale-1.jpg\" alt=\"\" width=\"277\" height=\"182\" \/><\/a>Significa anche voler ignorare che la Germania degli Hohenzollern, tanto preferibile a quella maniacale di Hitler, cerca di battere sulla fine del secolo le vie d\u00ec una ragionevole espansione commerciale e coloniale assolutamente priva di quei connotati aggressivi che oggi associamo automaticamente al carattere tedesco. Ed infine, significa voler dimenticare che questo desiderio di crescita urta quasi subito contro una coalizione di Stati fermamente decisi a non perdere il loro controllo sulla possibile evoluzione del problema europeo.<\/p>\n<p style=\"text-align: justify;\">Inghilterra e Russia zarista, entrambe potenze ad interessi sostanzialmente extraeuropei, hanno ragione, ma sul piano della Storia \u2014 possiamo dire purtroppo \u2014 le ragioni della conservazione non fanno necessariamente il torto delle forze tese ad una crescita naturale, ad una espansione che trova la sua giustificazione in se stessa.<\/p>\n<p style=\"text-align: justify;\">E questo equivale a dire, anche qui purtroppo, che l&#8217;unica domanda accettabile nelle crisi di questo tipo, \u00e8 se quelle determinate forze espansive abbiano o no dalla loro il consenso del futuro, siano o no l&#8217;origine di un qualcosa destinato a durare a lungo. Domanda che certo si posero Sanniti, Etruschi, Galli e Greci d&#8217;importazione, osservando preoccupati il sorgere di Roma, \u00abdal solco di Romolo, torva\u00bb.<\/p>\n<p style=\"text-align: justify;\">Svenate e praticamente messe fuori combattimento da un avversario durissimo, ricco di risorse intellettuali e morali, Francia ed Inghilterra contemplano subito dopo la Prima guerra mondiale un mondo in completa rovina, negli animi, nei corpi, nelle possibilit\u00e0. La Russia \u00e8 fuori combattimento, l&#8217;Impero austro-ungarico \u00e8 volato in minutissime schegge, la Francia \u00e8 rimasta una grande potenza soltanto negli articoli di giornale, e la stessa Inghilterra si trova a dover faro i tragici conti col suo milione d\u00ec morti, frutto avvelenato di quell&#8217;errore necessario che una potenza navale non dovrebbe mai commettere: ma che l&#8217;Inghilterra ha dovuto commettere, pagando di persona, perch\u00e9 quella funzione di controllo marittimo, che \u00e8 andata benissimo con Napoleone, nel 1914 si \u00e8 rivelata soltanto un arnese spuntato.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/Gran_Bretagna.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-43739 alignleft\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/Gran_Bretagna.jpg\" alt=\"\" width=\"175\" height=\"288\" \/><\/a>Nasce qui il tentativo inglese di comprendere la Germania, e di consentirle quell&#8217;espansione verso l&#8217;est che \u00e8 anche l&#8217;unica possibile nelle condizioni reali dell&#8217;Europa e del mondo nel 1933 e dintorni. Ma \u00e8 davvero possibile?<\/p>\n<p style=\"text-align: justify;\">Nei fatti non lo \u00e8 perch\u00e9, come dice chiaramente Hitler alla conferenza militare del novembre 1937, \u00abnon esistono terre senza padrone. Se le vogliamo, dovremo combattere\u00bb. Fa parte della tragedia d&#8217;Europa il comprendere nel suo seno troppe genti di fortissimo carattere, irriducibili e non disposte mai, anche a costo di guerre sanguinose, a barattare per una grigia sicurezza quello che \u00e8 o sembra il proprio destino.<\/p>\n<p style=\"text-align: justify;\">E poich\u00e9 questa tragedia alimenta le sue radici nell&#8217;anima profonda e nelle profonde pulsioni di queste genti, essa rimane potenzialmente intatta anche oggi, dopo due grandi guerre che hanno cambiato soltanto la forma del vulcano, ma non la natura del fuoco che vi arde dentro.<\/p>\n<p style=\"text-align: justify;\">Per lo storico, \u00e8 fonte d\u00ec una speciale meraviglia dover constatare oggi, a cinquant&#8217;anni dal secondo conflitto, ed a tre quarti di secolo dalla fine del primo, che le vie dell&#8217;accesso ad una posizione di predominio sono ora per la Germania assai pi\u00f9 sgombre di quanto non lo siano mai state nei decenni precedenti. Ed il fatto che siano state necessaria due guerre e cento milioni d\u00ec cadaveri per giungere a questo risultato, di certo non rallegra: n\u00e9 depone a favore della riposta saggezza degli uomini.<\/p>\n<p style=\"text-align: justify;\">Ma il lato peggiore di queste constatazioni persino banali \u00e8 che per due volte, due grandi volte, la guerra abbia funzionato come unico possibile crivello del sorgere e del decadere delle nazioni. Lezione che dobbiamo ritenere molto attentamente, poich\u00e9 dietro a tutte le sacrosante invocazioni di pace c\u2019\u00e8 sempre il grave errore di riferirsi ad un mondo immobile, con gerarchie stabilite <em>ab antiquo<\/em> e perci\u00f2 incapace di dire e dare parole nuove per la soluzione dei suoi vecchi problemi.<\/p>\n<p style=\"text-align: justify;\">In un angolo del quadro, ci siamo noi, gli italiani.<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/06\/fascisti.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-43384 alignright\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2019\/06\/fascisti.jpg\" alt=\"\" width=\"261\" height=\"193\" \/><\/a>Su questo buon popolo un po&#8217; frivolo, un po&#8217; ottimista e molto ignorante, il turbine del 1939 si abbatte all&#8217;improvviso, come un colpo di tuono nel meriggio estivo. Non c&#8217;\u00e8 una nuvola in ciclo e dunque non ci sar\u00e0 temporale. Allora l&#8217;allegro popolo esce di casa coi suoi leggeri vestiti da tempo bello, allegramente cianciando delle buone cose che si troveranno senza fatica sul cammino. L&#8217;ombrello \u00e8 rimasto a casa.<\/p>\n<p style=\"text-align: center;\">_______________________________<\/p>\n<p style=\"text-align: center;\"><strong>CRONOLOGIA<\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 12px;\">L&#8217;irresistibile ascesa di una guerra<\/span><\/p>\n<p style=\"text-align: justify;\"><strong>MARZO.<\/strong> Su pressione di Hitler la Slovacchia proclama l&#8217;indipendenza e si pone sotto la protezione del Terzo Reich.<\/p>\n<div align=\"justify\"><strong>15 MARZO<\/strong>. In violazione degli accordi di Monaco Hitler occupa la Cecoslovacchia.<br \/>\n<strong>19 MARZO<\/strong>. In Italia la Camera dei deputati viene sostituita dalla Camera dei Fasci.<br \/>\n<strong>21 MARZO<\/strong>. Hitler chiede alla Polonia la cessione di Danzica e del &#8220;corridoio polacco&#8221;. Varsavia rifiuta.<br \/>\n<strong>28 MARZO<\/strong>. In Spagna le truppe del generale Franco entrano a Madrid. Si conclude cos\u00ec la guerra civile iniziata tre anni prima, nel luglio del 1936.<br \/>\n<strong>31 MARZO<\/strong>. La Gran Bretagna abbandona la politica dell&#8217;<em>appeasement<\/em> e insieme alla Francia offre protezione alla Polonia contro ogni aggressione esterna.<br \/>\n<strong>APRILE<\/strong>. Hitler denuncia la convenzione navale anglo-tedesca del 1935 ed il patto tedesco-polacco del 1934.<br \/>\n<strong>APRILE.<\/strong> L&#8217;Italia occupa militarmente e si annette l&#8217;Albania.<br \/>\n<strong>MAGGIO<\/strong>. Germania e Italia stringono un&#8217;alleanza militare: il &#8220;Patto d&#8217;acciaio&#8221;.<br \/>\n<strong>AGOSTO<\/strong>. Ribbentrop e Molotov firmano il patto di non aggressione tra Russia e Germania.<br \/>\n<strong>1 SETTEMBRE<\/strong>. Inizia l&#8217;aggressione tedesca contro la Polonia.<br \/>\n<strong>3 SETTEMBRE<\/strong>. Gran Bretagna e Francia dichiarano guerra alla Germania.<br \/>\n<strong>17 SETTEMBRE.<\/strong> Le truppe dell&#8217;Unione Sovietica invadono la Polonia orientale.<br \/>\n<strong>27 SETTEMBRE<\/strong>. I tedeschi entrano dopo un&#8217;accanita battaglia, a Varsavia.<br \/>\n<strong>1 OTTOBRE.<\/strong> Cessata ogni resistenza, Germania ed Unione sovietica si spartiscono il territorio polacco.<\/div>\n<p>di <strong>Daniele Nardi<\/strong><\/p>\n<div>\n<div align=\"justify\">\n<div align=\"justify\">\n<div align=\"center\"><strong><br \/>\n(<a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?p=1747\">Vai alla seconda parte<\/a>)<\/strong><\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Pubblicato su Il Sabato n.34 &#8211; 26\u00a0 agosto1989 Cinquanta anni fa le truppe del F\u00fcrer invadevano la Polonia. Da quel giorno la guerra sar\u00e0 l\u2019unica realt\u00e0 di milioni uomini. Ma come e dove viene preparato il pi\u00f9 grande conflitto mai accaduto? La storia controcorrente del fatale 1939. di Franco Bandini\u00a0<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanno-in-cui-il-mondo-fin-diario-del-39-1\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":14762,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[90,24],"tags":[1140],"class_list":["post-1746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ii-guerra-mondiale","category-storia","tag-seconda-guerra-mondiale","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;anno in cui il mondo fin\u00ec. Diario del &#039;39 (1) - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanno-in-cui-il-mondo-fin-diario-del-39-1\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;anno in cui il mondo fin\u00ec. Diario del &#039;39 (1) - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanno-in-cui-il-mondo-fin-diario-del-39-1\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-12-15T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-24T06:28:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/World-War.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"176\" \/>\n\t<meta property=\"og:image:height\" content=\"251\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"23 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanno-in-cui-il-mondo-fin-diario-del-39-1\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanno-in-cui-il-mondo-fin-diario-del-39-1\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"L&#8217;anno in cui il mondo fin\u00ec. Diario del &#8217;39 (1)\",\"datePublished\":\"2005-12-15T23:00:00+00:00\",\"dateModified\":\"2019-07-24T06:28:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanno-in-cui-il-mondo-fin-diario-del-39-1\\\/\"},\"wordCount\":4676,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanno-in-cui-il-mondo-fin-diario-del-39-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/12\\\/World-War.jpg\",\"keywords\":[\"Seconda Guerra Mondiale\"],\"articleSection\":[\"II Guerra Mondiale\",\"Storia\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanno-in-cui-il-mondo-fin-diario-del-39-1\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanno-in-cui-il-mondo-fin-diario-del-39-1\\\/\",\"name\":\"L'anno in cui il mondo fin\u00ec. Diario del '39 (1) - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanno-in-cui-il-mondo-fin-diario-del-39-1\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanno-in-cui-il-mondo-fin-diario-del-39-1\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/12\\\/World-War.jpg\",\"datePublished\":\"2005-12-15T23:00:00+00:00\",\"dateModified\":\"2019-07-24T06:28:03+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanno-in-cui-il-mondo-fin-diario-del-39-1\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanno-in-cui-il-mondo-fin-diario-del-39-1\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanno-in-cui-il-mondo-fin-diario-del-39-1\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/12\\\/World-War.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/12\\\/World-War.jpg\",\"width\":176,\"height\":251},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/lanno-in-cui-il-mondo-fin-diario-del-39-1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;anno in cui il mondo fin\u00ec. Diario del &#8217;39 (1)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'anno in cui il mondo fin\u00ec. Diario del '39 (1) - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanno-in-cui-il-mondo-fin-diario-del-39-1\/","og_locale":"it_IT","og_type":"article","og_title":"L'anno in cui il mondo fin\u00ec. Diario del '39 (1) - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanno-in-cui-il-mondo-fin-diario-del-39-1\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-12-15T23:00:00+00:00","article_modified_time":"2019-07-24T06:28:03+00:00","og_image":[{"width":176,"height":251,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/World-War.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"23 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanno-in-cui-il-mondo-fin-diario-del-39-1\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanno-in-cui-il-mondo-fin-diario-del-39-1\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"L&#8217;anno in cui il mondo fin\u00ec. Diario del &#8217;39 (1)","datePublished":"2005-12-15T23:00:00+00:00","dateModified":"2019-07-24T06:28:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanno-in-cui-il-mondo-fin-diario-del-39-1\/"},"wordCount":4676,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanno-in-cui-il-mondo-fin-diario-del-39-1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/World-War.jpg","keywords":["Seconda Guerra Mondiale"],"articleSection":["II Guerra Mondiale","Storia"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanno-in-cui-il-mondo-fin-diario-del-39-1\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanno-in-cui-il-mondo-fin-diario-del-39-1\/","name":"L'anno in cui il mondo fin\u00ec. Diario del '39 (1) - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanno-in-cui-il-mondo-fin-diario-del-39-1\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanno-in-cui-il-mondo-fin-diario-del-39-1\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/World-War.jpg","datePublished":"2005-12-15T23:00:00+00:00","dateModified":"2019-07-24T06:28:03+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanno-in-cui-il-mondo-fin-diario-del-39-1\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanno-in-cui-il-mondo-fin-diario-del-39-1\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanno-in-cui-il-mondo-fin-diario-del-39-1\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/World-War.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/World-War.jpg","width":176,"height":251},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/lanno-in-cui-il-mondo-fin-diario-del-39-1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"L&#8217;anno in cui il mondo fin\u00ec. Diario del &#8217;39 (1)"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1746"}],"version-history":[{"count":8,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1746\/revisions"}],"predecessor-version":[{"id":43744,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1746\/revisions\/43744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/14762"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}