{"id":1733,"date":"2005-12-02T10:29:38","date_gmt":"2005-12-02T09:29:38","guid":{"rendered":""},"modified":"2016-06-15T15:18:59","modified_gmt":"2016-06-15T13:18:59","slug":"salvati-70-mila-bambini","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salvati-70-mila-bambini\/","title":{"rendered":"Salvati 70 mila bambini"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-34900\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/centro_aiuto_vita.jpg\" alt=\"centro_aiuto_vita\" width=\"240\" height=\"190\" \/>Il Giornale<\/strong> del 2 dicembre 2005<\/div>\n<p style=\"text-align: center;\">di <strong>Antonio Socci<\/strong><\/p>\n<p style=\"text-align: justify;\">Un miliardo di vite innocenti soppresse dall&#8217;aborto legalizzato nel mondo \u00e8 un orrore su cui riflettere o una statistica da liquidare con indifferenza facendo spallucce? E i 4 milioni e 200mila aborti realizzati legalmente negli ospedali italiani dall&#8217;introduzione della legge fino al primo febbraio 2004 sono un fatto di cui rallegrarsi o una dolorosa tragedia che ci spinge a fare qualcosa?<\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Le donne, che sono le prime vittime di questa situazione, sanno bene qual \u00e8 la risposta. Infatti non c&#8217;\u00e8 una sola donna che si sia convinta a rifiutare l&#8217;aborto e poi se ne sia pentita. Mentre tantissime fra coloro che hanno abortito si portano addosso per anni un immenso carico di sofferenza, di rimorso e anche traumi fisici pesantissimi, vere vittime, come i loro figli.<\/div>\n<p style=\"text-align: justify;\">Le donne dunque sanno bene, sulla propria pelle, che l&#8217;aborto \u00e8 un male e sarebbe meglio non trovarsi a viverlo. Nessuna ha mai detto che \u00e8 un bene. Per questo &#8211; che \u00e8 il \u00abvissuto\u00bb della donne &#8211; anche il cosiddetto fronte abortista ripete sempre, continuamente, che \u00abl&#8217;aborto \u00e8 un dramma\u00bb, che non c&#8217;\u00e8 nessun \u00abmovimento per la morte\u00bb e che nessuno \u00e8 \u00abper\u00bb l&#8217;aborto, ma solo \u00abper la libert\u00e0 di scelta\u00bb.<\/p>\n<p style=\"text-align: justify;\">Bene. La situazione nuova di oggi \u00e8 dovuta alla posizione veramente laica (al contrario di tanti laici giacobini), pragmatica dei cattolici e della Chiesa che dicono: vi prendiamo in parola, crediamo a ci\u00f2 che dichiarate, che cio\u00e8 non volete la morte, ma la vita; lasciamo stare dunque l&#8217;antica diatriba sulla legge 194 e insieme diamoci da fare per attuare quelle parti della legge 194, oggi largamente disattese, che &#8211; proprio perch\u00e9 l&#8217;aborto \u00e8 un dramma terribile &#8211; mettevano a disposizione delle donne in difficolt\u00e0 aiuti e sostegni, finalizzati a evitare quella tragedia.<\/p>\n<p style=\"text-align: justify;\">I cattolici hanno dalla loro parte uno straordinario argomento. Innanzitutto \u00e8 la stessa legge 194 che proclama di essere \u00aba tutela della maternit\u00e0\u00bb e che invita le strutture pubbliche a tendere una mano alle donne in difficolt\u00e0. Per questo appare totalmente anacronistica e insensata la polemica di un certo fronte laicista che ripete &#8211; un po&#8217; come un disco rotto &#8211; uno slogan di 25 anni fa: \u00abLa legge 194 non si tocca\u00bb.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec facendo non si rendono conto che i tempi sono cambiati: non c&#8217;\u00e8 nessuno che chiede di abolire quella legge, ma al contrario si chiede di attuarla veramente. Questo tipo di laici si trova con le spalle al muro perch\u00e9 non ha di fronte dei cattolici che fanno un&#8217;astratta crociata di principio, ma piuttosto un interlocutore che chiede loro di essere conseguenti con il loro principio per cui \u00abl&#8217;aborto \u00e8 un dramma\u00bb e nessuno \u00e8 \u00abper\u00bb l&#8217;aborto, ma solo \u00abper la libera scelta\u00bb.<\/p>\n<p style=\"text-align: justify;\">Se cos\u00ec stanno le cose &#8211; dicono i cattolici (e con loro sempre pi\u00f9 laici umanisti) &#8211; diamo seriamente la possibilit\u00e0 a tante donne in difficolt\u00e0 di scegliere davvero, evitiamo che si sentano in un vicolo cieco, obbligate all&#8217;aborto, diamo loro la possibilit\u00e0 di vincere quei problemi sotto i quali si sentono schiacciare fino a dover ricorrere all&#8217;aborto.<\/p>\n<p style=\"text-align: justify;\">\u00c8 il Movimento per la vita e lo splendido mondo di volontariato che ha attorno che veramente \u00e8 \u00abpro choice\u00bb, che cio\u00e8 vuole veramente che la donna scelga liberamente fra possibilit\u00e0 egualmente percorribili, senza essere sopraffatta da circostanze ostili e ricattata dalle difficolt\u00e0.<\/p>\n<p style=\"text-align: justify;\">Infatti l&#8217;esperienza insegna che se una donna non viene lasciata sola, se viene aiutata, sostenuta con aiuti concreti, anche di amore e di comprensione, tender\u00e0 a evitare l&#8217;aborto. Lo insegna proprio il lavoro eroico e silenzioso che migliaia di persone legate ai \u00abCentri di aiuto alla vita\u00bb e al Movimento per la vita hanno realizzato in questi tre decenni: in 27 anni di attivit\u00e0 pi\u00f9 di 70mila bambini (ripeto: settantamila) sono nati grazie all&#8217;aiuto che questa gente ha dato ad altrettante donne in sofferenza.<\/p>\n<p style=\"text-align: justify;\">Settantamila persone sotto i 30 anni oggi vivono fra noi (forse ignorandolo loro stessi) grazie a tanti volontari sconosciuti che alle loro madri hanno donato le proprie energie, il proprio amore, le proprie case. Spesso ricavandone sberleffi e disprezzo sui giornali dove cinici intellettuali o politici sprezzanti ironizzano, dal basso della propria indifferenza, su queste persone come se fossero \u00abmilitanti\u00bb ottusi o donne e uomini di serie B.<\/p>\n<p style=\"text-align: justify;\">Sono invece i silenziosi e invisibili eroi del nostro tempo. Sono i giusti &#8211; come diceva Solzenicyn &#8211; grazie ai quali il villaggio non si \u00e8 autodistrutto e vive ancora. Ma la loro &#8211; e quella della Chiesa &#8211; \u00e8 anche l&#8217;unica posizione veramente laica e \u00abpro choice\u00bb. Perch\u00e9 consegna al passato lo scontro sulla legge 194 e, chiedendo di attuarla per intero, tende la mano a tutti coloro che non sono \u00abper la morte\u00bb, chiedendo di unire le forze per evitare il male (la soppressione di una vita umana innocente) e fare il bene (aiutare concretamente donne e bambini).<\/p>\n<p style=\"text-align: justify;\">Naturalmente ci\u00f2 non significa che la 194 in s\u00e9 sia moralmente benemerita. Si cita questa legge come se, con la legalizzazione, avesse ridotto il numero degli aborti. Chi enuclea queste statistiche dovrebbe innanzitutto riconoscere le incredibili menzogne che furono propalate negli anni Settanta sul numero di aborti clandestini.<\/p>\n<p style=\"text-align: justify;\">E dovrebbe poi considerare nella statistica anche altri tipi di aborti non chirurgici. Ma soprattutto &#8211; se vogliamo fare un&#8217;analisi sociologica seria &#8211; dovrebbe rispondere alla seguente domanda: perch\u00e9 l&#8217;Italia \u00e8 l&#8217;unico fra i Paesi dell&#8217;Europa occidentale in cui, dopo l&#8217;introduzione di una legge abortista, si \u00e8 registrata una leggera flessione degli aborti legalmente praticati in tre decenni?<\/p>\n<p style=\"text-align: justify;\">C&#8217;\u00e8 chi risponde che lo si deve alla legge che legalizza l&#8217;aborto. \u00c8 un controsenso logico, ma prendiamolo per buono.<\/p>\n<p style=\"text-align: justify;\">Se fosse cos\u00ec lo stesso fenomeno si sarebbe dovuto verificare anche negli altri Paesi dell&#8217;Europa occidentale dopo l&#8217;introduzione di leggi abortiste. Invece l\u00ec \u00e8 accaduto il contrario. Allora come si spiega? L&#8217;ipotesi seria \u00e8 un&#8217;altra: perch\u00e9 in Italia, in questi tre decenni, \u00e8 cresciuta nell&#8217;opinione pubblica una forte convinzione che l&#8217;aborto sia un male, un dramma moralmente e umanamente devastante.<\/p>\n<p style=\"text-align: justify;\">Questo trend dell&#8217;opinione pubblica \u00e8 dimostrato clamorosamente sia dai periodici sondaggi dei giornali nel corso degli anni (ricordo quello clamoroso di Repubblica di un anno fa), sia dalle ricerche sociologiche (come \u00abLa sfida dei valori\u00bb di Loredana Sciolla). \u00c8 naturale pensare che sia stata la presenza della Chiesa a indurre gli italiani, nella loro coscienza, a maturare queste convinzioni che ci hanno portato molto lontano dall&#8217;indifferenza morale degli anni Settanta, come ha dimostrato clamorosamente il referendum sulla legge 40.<\/p>\n<p style=\"text-align: justify;\">La prova definitiva e incontestabile \u00e8 fornita dagli stessi che sbandierano questi dati. Se infatti loro stessi, per primi, esaltano come positivo il dato della diminuzione degli aborti (sia pure attribuendone il merito alla 194) significa che quello \u00e8 anche il loro giudizio di valore (meno aborti si fanno meglio \u00e8) e dunque che questo \u00e8 l&#8217;obiettivo a cui puntare, tutti insieme, volontariato e istituzioni, laici e cattolici.<\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 tutti sentiamo come drammaticamente vere le parole di Gandhi: \u00abMi sembra chiaro come la luce del giorno che l&#8217;aborto \u00e8 un crimine\u00bb. Di fronte al quale nessuno di noi pu\u00f2 sentirsi innocente e quindi indifferente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Giornale del 2 dicembre 2005 di Antonio Socci Un miliardo di vite innocenti soppresse dall&#8217;aborto legalizzato nel mondo \u00e8 un orrore su cui riflettere o una statistica da liquidare con indifferenza facendo spallucce? E i 4 milioni e 200mila aborti realizzati legalmente negli ospedali italiani dall&#8217;introduzione della legge fino al primo febbraio 2004 sono &hellip; <\/p>\n<p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salvati-70-mila-bambini\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":34900,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[2386],"class_list":["post-1733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aborto","tag-aborto","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Salvati 70 mila bambini - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salvati-70-mila-bambini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Salvati 70 mila bambini - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salvati-70-mila-bambini\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-12-02T09:29:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-15T13:18:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/centro_aiuto_vita.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"253\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salvati-70-mila-bambini\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salvati-70-mila-bambini\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Salvati 70 mila bambini\",\"datePublished\":\"2005-12-02T09:29:38+00:00\",\"dateModified\":\"2016-06-15T13:18:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salvati-70-mila-bambini\\\/\"},\"wordCount\":1169,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salvati-70-mila-bambini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/12\\\/centro_aiuto_vita.jpg\",\"keywords\":[\"Aborto\"],\"articleSection\":[\"Aborto\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salvati-70-mila-bambini\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salvati-70-mila-bambini\\\/\",\"name\":\"Salvati 70 mila bambini - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salvati-70-mila-bambini\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salvati-70-mila-bambini\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/12\\\/centro_aiuto_vita.jpg\",\"datePublished\":\"2005-12-02T09:29:38+00:00\",\"dateModified\":\"2016-06-15T13:18:59+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salvati-70-mila-bambini\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salvati-70-mila-bambini\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salvati-70-mila-bambini\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/12\\\/centro_aiuto_vita.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/12\\\/centro_aiuto_vita.jpg\",\"width\":253,\"height\":200,\"caption\":\"limitare la piaga dell'aborto con una proposta di legge popolare\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/salvati-70-mila-bambini\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Salvati 70 mila bambini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Salvati 70 mila bambini - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salvati-70-mila-bambini\/","og_locale":"it_IT","og_type":"article","og_title":"Salvati 70 mila bambini - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salvati-70-mila-bambini\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-12-02T09:29:38+00:00","article_modified_time":"2016-06-15T13:18:59+00:00","og_image":[{"width":253,"height":200,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/centro_aiuto_vita.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salvati-70-mila-bambini\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salvati-70-mila-bambini\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Salvati 70 mila bambini","datePublished":"2005-12-02T09:29:38+00:00","dateModified":"2016-06-15T13:18:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salvati-70-mila-bambini\/"},"wordCount":1169,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salvati-70-mila-bambini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/centro_aiuto_vita.jpg","keywords":["Aborto"],"articleSection":["Aborto"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salvati-70-mila-bambini\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salvati-70-mila-bambini\/","name":"Salvati 70 mila bambini - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salvati-70-mila-bambini\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salvati-70-mila-bambini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/centro_aiuto_vita.jpg","datePublished":"2005-12-02T09:29:38+00:00","dateModified":"2016-06-15T13:18:59+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salvati-70-mila-bambini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salvati-70-mila-bambini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salvati-70-mila-bambini\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/centro_aiuto_vita.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/12\/centro_aiuto_vita.jpg","width":253,"height":200,"caption":"limitare la piaga dell'aborto con una proposta di legge popolare"},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/salvati-70-mila-bambini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Salvati 70 mila bambini"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1733"}],"version-history":[{"count":4,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1733\/revisions"}],"predecessor-version":[{"id":34901,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1733\/revisions\/34901"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/34900"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}