{"id":1705,"date":"2005-11-19T00:00:00","date_gmt":"2005-11-18T23:00:00","guid":{"rendered":""},"modified":"2014-12-03T12:47:34","modified_gmt":"2014-12-03T11:47:34","slug":"fare-famiglia-servire-il-popolo","status":"publish","type":"post","link":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fare-famiglia-servire-il-popolo\/","title":{"rendered":"Fare Famiglia servire il popolo"},"content":{"rendered":"<div style=\"text-align: center;\"><strong><a href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Aldo-Brandirali.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-14755\" src=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Aldo-Brandirali.jpg\" alt=\"Aldo Brandirali\" width=\"250\" height=\"187\" \/><\/a>Tracce<\/strong>\u00a0 n.10 novembre 2005<\/div>\n<p style=\"text-align: justify;\"><em>Nel 1972 il \u201cmatrimonio comunista\u201d. Poi Aldo incontra don Giussani. Una rivoluzione che gli cambia la vita. Fino alla decisione di \u201crisposarsi\u201d in chiesa<\/em>.<\/p>\n<p style=\"text-align: center;\">di <strong>Luca Pesenti<\/strong><\/p>\n<p><!--more--><\/p>\n<div style=\"text-align: justify;\">Era il 9 aprile 1994, il giorno del compimento. Aldo e Teresa vivevano insieme da 22 anni, da quel lontano 1972 in cui entrambi gi\u00e0 sposati e divorziati, di fronte a 200 \u201ccompagni\u201d si erano promessi amore eterno, sposandosi simbolicamente con il rito del \u201cmatrimonio comunista\u201d. Lui, Aldo Brandirali, era il capo carismatico dell\u2019organizzazione maoista \u201cServire il popolo\u201d, tra le cui fila militava Teresa, 22 anni di amore e liti feroci, difficili e meravigliosi, nel travaglio di un cambiamento lungo a venire, segnato dall\u2019incontro con la grande Presenza.<\/div>\n<p style=\"text-align: justify;\">N\u00e9 il triste rito borghese del matrimonio civile, n\u00e9 quello cattolico in Chiesa e vestito bianco li convinceva. \u00abNon eravamo cristiani \u2013 spiega oggi Aldo \u2013 e dunque per coerenza\u00a0 rifiutavamo l\u2019idea. Ma il surrogato laico ci faceva se possibile ancora pi\u00f9 ribrezzo. Eppure avevamo bisogno di un rito, di giurarci fedelt\u00e0 di fronte al mondo, di vivere il nostro amore in nome di qualcosa d\u2019altro rispetto a noi.<\/p>\n<p style=\"text-align: justify;\">L\u2019esperienza di quei due divorzi ci aveva reso evidente come la sfida dell\u2019unit\u00e0 non c\u2019entrava col ritualismo: serviva altro. Questo qualcosa era l\u2019ideale comunista. Presagivamo a modo nostro che la durata del nostro amore non potesse essere messa nelle mani della nostra\u00a0 coerenza, ma affidata a una tensione per ci\u00f2 che fondava le nostre vite: l\u2019ideologia, appunto\u00bb.<\/p>\n<p style=\"text-align: justify;\"><strong>La ricerca del bello<\/strong><\/p>\n<p style=\"text-align: justify;\">Si erano sposati cos\u2019. Ma non bastava. Soprattutto, non bastava a Teresa, sempre alla ricerca di ragioni verificabili, mai tranquilla. Per questo comincia a trascinare Aldo verso ci\u00f2 che pi\u00f9 di ogni altra cosa al mondo riesce a commuovere l\u2019uomo: la bellezza. Fu l\u2019arte a svelare a Teresa che l\u2019ideologia non poteva bastare. \u00abEra l\u2019inizio della salvezza \u2013 ricorda oggi Aldo -, anche se per me fu evidente che nemmeno la soddisfazione estetica reggeva. Paradossalmente Teresa si era mossa per prima, ma ora ero io in debito d\u2019ossigeno, ero io a spingermi ancora pi\u00f9 in l\u00e0\u00bb.<\/p>\n<p style=\"text-align: justify;\">E qui comincia un\u2019altra storia. Una nuova vita che inizia nel 1982, dieci anni di matrimonio comunista, dieci anni difficili che hanno lasciato i segni, soprattutto sui due figli Marco (che Aldo ebbe con la prima moglie) e Luca, nato dall\u2019unione con Teresa. Aldo incontra don Giussani, comincia una nuova vita. Teresa osserva perplessa, non lo ostacola, non lo aiuta: semplicemente lo lascia fare. Anche se teme l\u2019ennesima infatuazione ideologica, una nuova fregatura del desiderio.<\/p>\n<p style=\"text-align: justify;\">Aldo si mescola con i ciellini, i suoi vecchi compagni cominciano a irriderlo, il piccolo luca, che frequenta le scuole del partito, soffre, non capisce. \u00abFu un momento terribile. Ma io iniziai a cambiare, e con me anche Teresa, nonostante la sua distanza dal mondo\u00a0 che iniziavo a conoscere. Eravamo ancora atei, eppure tutto cambiava. E Luca fu molto aiutato da questa novit\u00e0 che ci rendeva ogni giorno meno litigiosi, pi\u00f9 capaci di abbracciare i nostri limiti. Finalmente potevamo essere per lui un esempio\u00bb<\/p>\n<p style=\"text-align: justify;\"><strong>Proposta di libert\u00e0<\/strong><\/p>\n<p style=\"text-align: justify;\">Venne il compimento, in quel giorno del 1994 in cui sono diventati una cosa sola di fronte a Dio e al suo popolo. Si sposarono in chiesa, lui ormai convertito, lei ancora alla ricerca della risposta alla grande domanda che non l\u2019abbandona mai. Teresa accetta di sposarsi perch\u00e9 capisce che per Aldo \u00e8 questione di vita o di morte.<\/p>\n<p style=\"text-align: justify;\">Non fa la comunione ma accetta di stare di fronte al Mistero. Due mesi dopo, don Giussani invita Aldo a un incontro: \u00abPorta anche tua moglie\u00bb, gli dice. Teresa ci sta, incontra il prete di desio e gli dice: \u00abGuarda che io non mi sono mica convertita\u00bb. E lui, spiazzante: \u00abNon c\u2019\u00e8 problema, sentiti libera\u00bb. Dal giorno dopo Teresa inizia a frequentare la messa domenicale, perch\u00e9 \u00abdi fronte a una proposta di libert\u00e0 \u2013 ricorda ancora Aldo \u2013 ogni obiezione e preconcetto erano crollati in un istante\u00bb.<\/p>\n<p style=\"text-align: justify;\">E le liti veementi degli anni della convivenza? \u00abTutto finito. La contraddizione del nostro rapporto rimane, anzi forse si \u00e8 fatta pi\u00f9 forte. Ma c\u2019\u00e8 un punto in cui ci fermiamo, riconoscendo che c\u2019\u00e8 qualcosa che viene prima della contraddizione. Si litiga ma si supera tutto. Questo \u00e8 quello che inserisce Cristo quando ti sposa\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tracce\u00a0 n.10 novembre 2005 Nel 1972 il \u201cmatrimonio comunista\u201d. Poi Aldo incontra don Giussani. Una rivoluzione che gli cambia la vita. Fino alla decisione di \u201crisposarsi\u201d in chiesa. di Luca Pesenti<\/p><p><a class=\"more-link btn\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fare-famiglia-servire-il-popolo\/\">Continua a leggere<\/a><\/p>\n","protected":false},"author":6,"featured_media":14755,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,82,18],"tags":[1144,1145],"class_list":["post-1705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chiesa","category-comunismo-in-italia","category-personaggi","tag-aldo-brandirali","tag-servire-il-popolo","item-wrap"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fare Famiglia servire il popolo - Rassegna Stampa Cattolica<\/title>\n<meta name=\"description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fare-famiglia-servire-il-popolo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fare Famiglia servire il popolo - Rassegna Stampa Cattolica\" \/>\n<meta property=\"og:description\" content=\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fare-famiglia-servire-il-popolo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rassegna Stampa Cattolica\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rassegnastampacattolica\" \/>\n<meta property=\"article:published_time\" content=\"2005-11-18T23:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2014-12-03T11:47:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Aldo-Brandirali.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"259\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:site\" content=\"@rassegnastampa9\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fare-famiglia-servire-il-popolo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fare-famiglia-servire-il-popolo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\"},\"headline\":\"Fare Famiglia servire il popolo\",\"datePublished\":\"2005-11-18T23:00:00+00:00\",\"dateModified\":\"2014-12-03T11:47:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fare-famiglia-servire-il-popolo\\\/\"},\"wordCount\":713,\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fare-famiglia-servire-il-popolo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/11\\\/Aldo-Brandirali.jpg\",\"keywords\":[\"Aldo Brandirali\",\"Servire il popolo\"],\"articleSection\":[\"Chiesa\",\"Comunismo in Italia\",\"Personaggi\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fare-famiglia-servire-il-popolo\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fare-famiglia-servire-il-popolo\\\/\",\"name\":\"Fare Famiglia servire il popolo - Rassegna Stampa Cattolica\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fare-famiglia-servire-il-popolo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fare-famiglia-servire-il-popolo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/11\\\/Aldo-Brandirali.jpg\",\"datePublished\":\"2005-11-18T23:00:00+00:00\",\"dateModified\":\"2014-12-03T11:47:34+00:00\",\"description\":\"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fare-famiglia-servire-il-popolo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fare-famiglia-servire-il-popolo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fare-famiglia-servire-il-popolo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/11\\\/Aldo-Brandirali.jpg\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2005\\\/11\\\/Aldo-Brandirali.jpg\",\"width\":259,\"height\":194},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/fare-famiglia-servire-il-popolo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fare Famiglia servire il popolo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#website\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"name\":\"Rassegna Stampa Cattolica\",\"description\":\"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\"},\"alternateName\":\"Rass. Cattolica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#organization\",\"name\":\"Rassegna Stampa Cattolica\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"contentUrl\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/logo-rassegna1.gif\",\"width\":600,\"height\":163,\"caption\":\"Rassegna Stampa Cattolica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/rassegnastampacattolica\",\"https:\\\/\\\/x.com\\\/rassegnastampa9\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/#\\\/schema\\\/person\\\/08f319d2bd1a0904ad9e2bfb7b15e5c3\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"url\":\"https:\\\/\\\/www.rassegnastampa-totustuus.it\\\/cattolica\\\/author\\\/pietroelle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fare Famiglia servire il popolo - Rassegna Stampa Cattolica","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fare-famiglia-servire-il-popolo\/","og_locale":"it_IT","og_type":"article","og_title":"Fare Famiglia servire il popolo - Rassegna Stampa Cattolica","og_description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","og_url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fare-famiglia-servire-il-popolo\/","og_site_name":"Rassegna Stampa Cattolica","article_publisher":"https:\/\/www.facebook.com\/rassegnastampacattolica","article_published_time":"2005-11-18T23:00:00+00:00","article_modified_time":"2014-12-03T11:47:34+00:00","og_image":[{"width":259,"height":194,"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Aldo-Brandirali.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_creator":"@rassegnastampa9","twitter_site":"@rassegnastampa9","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fare-famiglia-servire-il-popolo\/#article","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fare-famiglia-servire-il-popolo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3"},"headline":"Fare Famiglia servire il popolo","datePublished":"2005-11-18T23:00:00+00:00","dateModified":"2014-12-03T11:47:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fare-famiglia-servire-il-popolo\/"},"wordCount":713,"publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fare-famiglia-servire-il-popolo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Aldo-Brandirali.jpg","keywords":["Aldo Brandirali","Servire il popolo"],"articleSection":["Chiesa","Comunismo in Italia","Personaggi"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fare-famiglia-servire-il-popolo\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fare-famiglia-servire-il-popolo\/","name":"Fare Famiglia servire il popolo - Rassegna Stampa Cattolica","isPartOf":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fare-famiglia-servire-il-popolo\/#primaryimage"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fare-famiglia-servire-il-popolo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Aldo-Brandirali.jpg","datePublished":"2005-11-18T23:00:00+00:00","dateModified":"2014-12-03T11:47:34+00:00","description":"Rassegna Stampa Cattolica - Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","breadcrumb":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fare-famiglia-servire-il-popolo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fare-famiglia-servire-il-popolo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fare-famiglia-servire-il-popolo\/#primaryimage","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Aldo-Brandirali.jpg","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2005\/11\/Aldo-Brandirali.jpg","width":259,"height":194},{"@type":"BreadcrumbList","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/fare-famiglia-servire-il-popolo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/"},{"@type":"ListItem","position":2,"name":"Fare Famiglia servire il popolo"}]},{"@type":"WebSite","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#website","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","name":"Rassegna Stampa Cattolica","description":"Per una cultura che nasce dalla Rivelazione cristiana in conformit\u00e0 alla tradizione e al Magistero della Chiesa in opposizione ad ogni relativismo e totalitarismo","publisher":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization"},"alternateName":"Rass. Cattolica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#organization","name":"Rassegna Stampa Cattolica","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/","url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","contentUrl":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-content\/uploads\/2014\/04\/logo-rassegna1.gif","width":600,"height":163,"caption":"Rassegna Stampa Cattolica"},"image":{"@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/rassegnastampacattolica","https:\/\/x.com\/rassegnastampa9"]},{"@type":"Person","@id":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/#\/schema\/person\/08f319d2bd1a0904ad9e2bfb7b15e5c3","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2fcdf27c78ea025fbdb44e914cc63c72249ffec9dc8aafd5c82b26240ef3f346?s=96&d=mm&r=g","caption":"Redazione"},"url":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/author\/pietroelle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/comments?post=1705"}],"version-history":[{"count":3,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1705\/revisions"}],"predecessor-version":[{"id":14756,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/posts\/1705\/revisions\/14756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media\/14755"}],"wp:attachment":[{"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/media?parent=1705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/categories?post=1705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rassegnastampa-totustuus.it\/cattolica\/wp-json\/wp\/v2\/tags?post=1705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}